{"id":52,"date":"2008-01-16T18:36:07","date_gmt":"2008-01-16T17:36:07","guid":{"rendered":"https:\/\/blogs.ua.es\/educacionfisica\/software-para-estadisticas-de-balonmano\/"},"modified":"2010-09-29T20:11:21","modified_gmt":"2010-09-29T19:11:21","slug":"software-para-estadisticas-de-balonmano","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/educacionfisica\/software-para-estadisticas-de-balonmano\/","title":{"rendered":"Software para estadisticas de balonmano"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.kinetical.com\/imgsports\/sports_backhan.jpg\" alt=\"https:\/\/blogs.ua.es\/educacionfisica software estadisticas balonmano \" \/><\/p>\n<p>Os presentamos una posible soluci\u00f3n para realizar anotaciones estad\u00edsticas  por medio de  una PDA. En el caso del balonmano en http:\/\/www.kinetical.com ofrecen un software de estadisticas de Balonmano. Su precio es variable y es mejor consultarlo en su web.<\/p>\n<p>Esta empresa adem\u00e1s tiene desarrollado esta herramienta para los siguientes deportes: Balonmano, Baloncesto y F\u00fatbol.<\/p>\n<p><a title=\"Pdf informativo\" href=\"http:\/\/www.kinetical.com\/deportes\/handball_comercial.pdf\">Descarga el pdf informativo<\/a> sobre este Sotware de estadisticas de balonmano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os presentamos una posible soluci\u00f3n para realizar anotaciones estad\u00edsticas por medio de una PDA. En el caso del balonmano en http:\/\/www.kinetical.com ofrecen un software de estadisticas de Balonmano. Su precio es variable y es mejor consultarlo en su web. Esta empresa adem\u00e1s tiene desarrollado esta herramienta para los siguientes deportes: Balonmano, Baloncesto y F\u00fatbol. Descarga [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,438],"tags":[],"class_list":["post-52","post","type-post","status-publish","format-standard","hentry","category-general","category-tecnologias-y-deporte"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"predecessor-version":[{"id":118,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts\/52\/revisions\/118"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}