{"id":306,"date":"2013-12-28T10:08:18","date_gmt":"2013-12-28T09:08:18","guid":{"rendered":"https:\/\/blogs.ua.es\/elx2\/?p=306"},"modified":"2013-12-28T11:59:28","modified_gmt":"2013-12-28T10:59:28","slug":"els-pares-de-la-parroquia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/elx2\/2013\/12\/28\/els-pares-de-la-parroquia\/","title":{"rendered":"Els pares de la parr\u00f2quia"},"content":{"rendered":"<p><a href=\"http:\/\/www.flickr.com\/photos\/111391982@N04\/11601616266\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-330\" alt=\"constructors 450\" src=\"https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/constructors-450-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/constructors-450-225x300.jpg 225w, https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/constructors-450.jpg 450w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>A aquest cartell situat a la barana de granit que hi ha a l\u2018exterior de la \u201cParr\u00f2quia de Sant Vicent Ferrer\u201d, constru\u00efda al barri d\u2019Altabix en 2008, podem veure els noms de l\u2019arquitecte, Diego Casta\u00f1o Belda, els arquitectes t\u00e8cnics, David Casta\u00f1o Belda i Esteban Hern\u00e1ndez Abad, el promotor, el bisbe d\u2019Oriola &#8211; Alacant, i el constructor, <i>Silmu, S.A. Grup Anara<\/i>.<\/p>\n<p>Aquesta foto fou presa al carrer Antonio Mora Fern\u00e1ndez, 03202, Altabix, Elx, Alacant, el dia 6 de desembre de 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A aquest cartell situat a la barana de granit que hi ha a l\u2018exterior de la \u201cParr\u00f2quia de Sant Vicent Ferrer\u201d, constru\u00efda al barri d\u2019Altabix en 2008, podem veure els noms de l\u2019arquitecte, Diego Casta\u00f1o Belda, els arquitectes t\u00e8cnics, David &hellip; <a href=\"https:\/\/blogs.ua.es\/elx2\/2013\/12\/28\/els-pares-de-la-parroquia\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3455,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[392115],"tags":[548651,620121,131703,620426],"class_list":["post-306","post","type-post","status-publish","format-standard","hentry","category-inscripcions-i-plaques-a-recints-religiosos","tag-altabix","tag-constructors","tag-parroquia","tag-sant-vicent"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/users\/3455"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":334,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/306\/revisions\/334"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}