{"id":380,"date":"2013-12-28T15:27:47","date_gmt":"2013-12-28T14:27:47","guid":{"rendered":"https:\/\/blogs.ua.es\/elx2\/?p=380"},"modified":"2013-12-28T15:27:47","modified_gmt":"2013-12-28T14:27:47","slug":"tienes-entrada-para-el-cielo","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/elx2\/2013\/12\/28\/tienes-entrada-para-el-cielo\/","title":{"rendered":"\u00bfTienes entrada para el cielo?"},"content":{"rendered":"<p><a href=\"http:\/\/www.flickr.com\/photos\/111391982@N04\/11447862003\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-381\" alt=\"bas\u00edlica17\" src=\"https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/bas\u00edlica17-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/bas\u00edlica17-300x225.jpg 300w, https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/bas\u00edlica17-399x300.jpg 399w, https:\/\/blogs.ua.es\/elx2\/files\/2013\/12\/bas\u00edlica17.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Esta placa est\u00e1 situada encima de una especie de urna en la Bas\u00edlica de Santa Mar\u00eda. En la placa pone &#8221;limosnas para misas en sufragio de las benditas almas del Purgatorio&#8221;, con letras de estilo antiguo y negras.<\/p>\n<p>Este cartel sirve para recaudar dinero para realizar misas para las almas del purgatorio. Es decir, personas que se han portado bien y no han sido bendecidos con el bautismo de la Iglesia, van all\u00ed, ni al cielo, ni al infierno,\u00a0tambi\u00e9n los reci\u00e9n nacidos que mueren antes de ser bautizados, seg\u00fan la\u00a0Iglesia\u00a0van a ese lugar. Finalmente da igual si has sido bueno o malo, en &#8221;la vida eterna&#8221; te vas a un lugar o a otro si perteneces o no a la Iglesia&#8230;<\/p>\n<p>Esta foto fue realizada el 10 de Diciembre del 2013, en la Bas\u00edlica de Santa Mar\u00eda de Elche, situada en el centro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta placa est\u00e1 situada encima de una especie de urna en la Bas\u00edlica de Santa Mar\u00eda. En la placa pone &#8221;limosnas para misas en sufragio de las benditas almas del Purgatorio&#8221;, con letras de estilo antiguo y negras. Este cartel &hellip; <a href=\"https:\/\/blogs.ua.es\/elx2\/2013\/12\/28\/tienes-entrada-para-el-cielo\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3447,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[392115],"tags":[632335,112161,632599,441035,632153],"class_list":["post-380","post","type-post","status-publish","format-standard","hentry","category-inscripcions-i-plaques-a-recints-religiosos","tag-almas","tag-basilica","tag-limosna","tag-misa","tag-purgatorio"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/users\/3447"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/comments?post=380"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/380\/revisions"}],"predecessor-version":[{"id":382,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/posts\/380\/revisions\/382"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/media?parent=380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/categories?post=380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/elx2\/wp-json\/wp\/v2\/tags?post=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}