{"id":1130,"date":"2014-10-14T14:02:13","date_gmt":"2014-10-14T14:02:13","guid":{"rendered":"https:\/\/blogs.ua.es\/faraonllorens\/?p=1130"},"modified":"2014-10-14T14:02:13","modified_gmt":"2014-10-14T14:02:13","slug":"abpgame-2014-2015-presentaciones-hito-0","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/faraonllorens\/2014\/10\/14\/abpgame-2014-2015-presentaciones-hito-0\/","title":{"rendered":"ABPgame+  2014-2015: presentaciones hito 0"},"content":{"rendered":"<p>Presentaciones Hito 0 (Presentaci\u00f3n Proyectos ABP)<br \/>\nIngenier\u00eda Multimedia, <a href=\"http:\/\/www.eps.ua.es\/ingenieria-multimedia\/videojuegos\/\" target=\"_blank\">Itinerario Creaci\u00f3n y Entretenimiento Digital<\/a> (videojuegos)<br \/>\nProyecto ABP<br \/>\nCurso 2014-2015<br \/>\nViernes 13 de Octubre de 2014<br \/>\nSal\u00f3n de Actos de la EPS I a partir de las 15:00 h.<\/p>\n<p>Los distintos grupos de ABP realizar\u00e1n una breve exposici\u00f3n del proyecto (10 minutos), que resuman el documento de informe previo o presupuesto que est\u00e1n elaborando.<\/p>\n<p>V\u00eddeo:<br \/>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentaciones Hito 0 (Presentaci\u00f3n Proyectos ABP) Ingenier\u00eda Multimedia, Itinerario Creaci\u00f3n y Entretenimiento Digital (videojuegos) Proyecto ABP Curso 2014-2015 Viernes 13 de Octubre de 2014 Sal\u00f3n de Actos de la EPS I a partir de las 15:00 h. Los distintos grupos de ABP realizar\u00e1n una breve exposici\u00f3n del proyecto (10 minutos), que resuman el documento de [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[412,204,669],"tags":[1544,563983,182],"class_list":["post-1130","post","type-post","status-publish","format-standard","hentry","category-actividades","category-innovacion-educativa","category-videojuegos","tag-aprendizaje","tag-aprendizaje-basado-en-proyectos","tag-universidad"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/comments?post=1130"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1130\/revisions"}],"predecessor-version":[{"id":1191,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1130\/revisions\/1191"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/media?parent=1130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/categories?post=1130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/tags?post=1130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}