{"id":1396,"date":"2015-05-31T22:50:55","date_gmt":"2015-05-31T22:50:55","guid":{"rendered":"https:\/\/blogs.ua.es\/faraonllorens\/?p=1396"},"modified":"2015-09-09T15:21:02","modified_gmt":"2015-09-09T15:21:02","slug":"publicado-revision-vol-8-num-2-2015","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/faraonllorens\/2015\/05\/31\/publicado-revision-vol-8-num-2-2015\/","title":{"rendered":"Publicado ReVisi\u00f3n, vol 8, num 2 (2015)"},"content":{"rendered":"<p>Acaba de salir el \u00faltimo n\u00famero (<a href=\"http:\/\/www.aenui.net\/ojs\/index.php?journal=revision&amp;page=issue&amp;op=view&amp;path%5B%5D=18\" target=\"_blank\">vol. 8 num. 2<\/a>) de <a href=\"http:\/\/www.aenui.net\/ReVision\" target=\"_blank\">ReVisi\u00f3n<\/a>, revista de <a href=\"http:\/\/www.aenui.net\" target=\"_blank\">AENUI<\/a> de <strong>Investigaci\u00f3n en Docencia Universitaria de la Inform\u00e1tica<\/strong>. Ya lo ten\u00e9is disponible en el quiosco habitual (<a href=\"http:\/\/www.aenui.net\/ReVision\" target=\"_blank\">http:\/\/www.aenui.net\/ReVision<\/a>).<\/p>\n<p>Este n\u00famero, adem\u00e1s de las columnas habituales, contiene la secci\u00f3n especial dedicada a los m\u00e1steres en Inform\u00e1tica. Tambi\u00e9n contiene la segunda parte del art\u00edculo de recepci\u00f3n del premio AENUI a la calidad e Innovaci\u00f3n Docente 2014 otorgado a Rosal\u00eda Pe\u00f1a.<\/p>\n<p>En este n\u00famero pod\u00e9is encontrar:<\/p>\n<ul>\n<li>La editorial de Joe Mir\u00f3, esta vez dedicada a los <strong>Cambios tecnol\u00f3gicos, cambios sociales, cambios docentes<\/strong>.<\/li>\n<li>Luis Fern\u00e1ndez hace una <strong>ReVisi\u00f3n del empleo y la profesi\u00f3n inform\u00e1tica: Competencias digitales (I)<\/strong>.<\/li>\n<li>La habitual columna Docencia 2.0 de JJ Merelo y Fernando Tricas, titulada &#8220;<strong>Un servidor en mi bolsillo trasero<\/strong>.<\/li>\n<li>La segunda parte de pasando de la innovaci\u00f3n a la publicaci\u00f3n de David L\u00f3pez, dedicada a <strong>Tiempos de un art\u00edculo y errores habituales<\/strong>.<\/li>\n<li>la columna de Fara\u00f3n Llorens, comentando que <strong>Dicen por ah\u00ed&#8230; que la nueva alfabetizaci\u00f3n pasa por la programaci\u00f3n<\/strong>.<\/li>\n<li>Miguel Valero en su colaboraci\u00f3n En el Aula responde a la pregunta <strong>\u00bfDesde d\u00f3nde se abre la puerta para que entre la calidad?<\/strong>.<\/li>\n<li>Y como ya hemos dicho el segundo art\u00edculo de Rosal\u00eda Pe\u00f1a titulado <strong>Python como primera aproximaci\u00f3n a la programaci\u00f3n<\/strong>.<\/li>\n<\/ul>\n<p>En la Secci\u00f3n Especial tenemos:<\/p>\n<ul>\n<li><strong>Introducci\u00f3n a la Secci\u00f3n Especial: La Problem\u00e1tica de los M\u00e1steres en Inform\u00e1tica<\/strong>, de Francisco Ruiz Gonz\u00e1lez.<\/li>\n<li><strong>El M\u00e1ster Universitario en Ingenier\u00eda Inform\u00e1tica en un contexto no presencial<\/strong>, de Robert Claris\u00f3, Maria Jes\u00fas Marco, Josep Maria Marco-Sim\u00f3, Josep Prieto y Daniel Riera.<\/li>\n<li><strong>Impartiendo el M\u00e1ster en Ingenier\u00eda Inform\u00e1tica bajo la doble modalidad Presencial-Semipresencial simult\u00e1neamente<\/strong>, de Isabel de Sivatte, David Vallejo, Carlos Gonz\u00e1lez y Eduardo Fern\u00e1ndez-Medina.<\/li>\n<li><strong>Dise\u00f1o, Implantaci\u00f3n y Desarrollo de un M\u00e1ster en Ingenier\u00eda Inform\u00e1tica<\/strong>, de Francisco Jos\u00e9 Su\u00e1rez Alonso, Pablo Javier Tuya Gonz\u00e1lez, Daniel Fernando Garc\u00eda Mart\u00ednez, Roberto Garc\u00eda Fern\u00e1ndez, Vicente Rodr\u00edguez Montequ\u00edn, Enrique Antonio De la Cal Mar\u00edn y Alfredo Santiago Alguero Garc\u00eda.<\/li>\n<li><strong>Metodolog\u00eda \u00e1gil en el dise\u00f1o e implantaci\u00f3n de un M\u00e1ster en Ingenier\u00eda Inform\u00e1tica<\/strong>, de Patricia Compa\u00f1, Virgilio Gilart, Fernando Llopis, Fara\u00f3n Llorens, Jose-Norberto Mazon, Andr\u00e9s Montoyo, Rosana Satorre y Mireia Sempere.<\/li>\n<li><strong>El M\u00e1ster en Ingenier\u00eda Inform\u00e1tica: Una oportunidad para la colaboraci\u00f3n de la Universidad con Empresas y Centros Tecnol\u00f3gicos<\/strong>, de Juan Carlos D\u00edaz Mart\u00edn, Luis Mariano del R\u00edo P\u00e9rez, Pablo Garc\u00eda Rodr\u00edguez y Juan Manuel Murillo Rodr\u00edguez.<\/li>\n<\/ul>\n<p>Como siempre, os pedimos que difund\u00e1is la revista: aconsejad art\u00edculos a vuestros compa\u00f1eros, difundidla en las redes sociales, poned enlaces a los articulos que m\u00e1s os han gustado&#8230;<\/p>\n<p>Y si ten\u00e9is algo que os gustar\u00eda publicar, sometedlo. La revista es con revisi\u00f3n por pares, est\u00e1 bien editada y es de acceso libre. Es una buena manera de difundir vuestro trabajo.<\/p>\n<p>Esperamos que el n\u00famero os guste.<\/p>\n<p>Merche Marqu\u00e9s, Joe Mir\u00f3 y Fara\u00f3n Llorens (editores)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acaba de salir el \u00faltimo n\u00famero (vol. 8 num. 2) de ReVisi\u00f3n, revista de AENUI de Investigaci\u00f3n en Docencia Universitaria de la Inform\u00e1tica. Ya lo ten\u00e9is disponible en el quiosco habitual (http:\/\/www.aenui.net\/ReVision). Este n\u00famero, adem\u00e1s de las columnas habituales, contiene la secci\u00f3n especial dedicada a los m\u00e1steres en Inform\u00e1tica. Tambi\u00e9n contiene la segunda parte del [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[204],"tags":[1544,432,223,30,182],"class_list":["post-1396","post","type-post","status-publish","format-standard","hentry","category-innovacion-educativa","tag-aprendizaje","tag-didactica","tag-docencia","tag-informatica","tag-universidad"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/comments?post=1396"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1396\/revisions"}],"predecessor-version":[{"id":1397,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/1396\/revisions\/1397"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/media?parent=1396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/categories?post=1396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/tags?post=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}