{"id":2781,"date":"2020-04-30T22:59:11","date_gmt":"2020-04-30T22:59:11","guid":{"rendered":"https:\/\/blogs.ua.es\/faraonllorens\/?p=2781"},"modified":"2020-05-05T10:00:25","modified_gmt":"2020-05-05T10:00:25","slug":"reflexion-para-una-docencia-postpandemia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/faraonllorens\/2020\/04\/30\/reflexion-para-una-docencia-postpandemia\/","title":{"rendered":"Reflexi\u00f3n para una docencia postpandemia"},"content":{"rendered":"<p><strong>Reflexi\u00f3n para una docencia postpandemia<\/strong><\/p>\n<p><em>Fara\u00f3n Llorens Largo<\/em><br \/>\n<a href=\"https:\/\/catedra-transformacion-digital.ua.es\" rel=\"noopener noreferrer\" target=\"_blank\">C\u00e1tedra Santander-UA de Transformaci\u00f3n Digital<\/a><br \/>\n<a href=\"http:\/\/www.ua.es\" target=\"_blank\" rel=\"noopener noreferrer\">Universidad de Alicante<\/a> <\/p>\n<p>Reflexi\u00f3n para una docencia postpandemia<br \/>\n#DocenciaVirtual #DocenciaOnline #eLearning<br \/>\nTras actuar de urgencia en la situaci\u00f3n actual, es momento de pensar en el <strong>curso 2020-2021 y siguientes<\/strong>.<br \/>\n@CatedraTD_UA, @UA_Universidad @CrueUniversidad @RedCLARA @infometared<br \/>\nAbro Hilo:<\/p>\n<p>[T01] \tNecesitamos dise\u00f1ar una <strong>docencia universitaria a prueba de coronavirus<\/strong> y la tecnolog\u00eda ser\u00e1 nuestra mejor aliada, pero \u2026 no nos pasemos de frenada.<\/p>\n<p>[T02] \tSi algo ha demostrado este confinamiento en casa, es que los humanos necesitamos contacto f\u00edsico. Esto es un <strong>valor diferencial de las universidades presenciales<\/strong>. \u00a1No lo perdamos de vista! Los campus universitarios, con todo su contexto, son un activo.<\/p>\n<p>[T03] \tEsta pandemia ha sido causada por un virus biol\u00f3gico, pero <strong>\u00bfla pr\u00f3xima pandemia ser\u00e1 a causa de un virus inform\u00e1tico?<\/strong><br \/>\nEn este confinamiento en casa nos han prohibido salir a la calle, pero <strong>\u00bfen el pr\u00f3ximo confinamiento nos prohibir\u00e1n salir a internet?<\/strong><\/p>\n<p>[T04] \tPasar de una dependencia de las aulas y la presencialidad a <strong>una dependencia de la tecnolog\u00eda<\/strong> tampoco es una opci\u00f3n inteligente para una universidad presencial. No sabemos lo que va a venir, ni por donde va a venir.<\/p>\n<p>[T05] \tSe habla de dise\u00f1ar el pr\u00f3ximo curso con dos alternativas: modalidad A (presencial) y modalidad B (online), por si acaso. Yo voy a dise\u00f1arla en modalidad AB que aproveche lo mejor de lo online y lo mejor de lo presencial, sin dependencia total de ninguna: \u00bf<strong>bivalente<\/strong>?<\/p>\n<p>[T06] \tVoy a tratar de hacer un <strong>dise\u00f1o docente tolerante a fallos<\/strong>, es decir que pueda continuar funcionando incluso cuando se produzca alg\u00fan fallo en el sistema.<\/p>\n<p>[T07] \tLa tolerancia a fallos se consigue no solo con los <strong>componentes<\/strong>, sino tambi\u00e9n por las <strong>reglas seg\u00fan las cuales interact\u00faan<\/strong>. Se puede lograr tambi\u00e9n <strong>anticipando las condiciones excepcionales<\/strong> (prevenci\u00f3n de fallos).<\/p>\n<p>[T08] \tLas estrategias m\u00e1s habituales para conseguir un sistema lo m\u00e1s tolerante a fallos posible son <strong>redundancia<\/strong>, <strong>replicaci\u00f3n<\/strong>, <strong>diversidad<\/strong> y <strong>autocorrecci\u00f3n<\/strong>. Intentar\u00e9 combinar estas cuatro estrategias en el dise\u00f1o de mis asignaturas para el pr\u00f3ximo curso.<\/p>\n<p>[T09] \tEn esencia, un \u00a1<strong>sistema flexible<\/strong>! Por tanto no es cuesti\u00f3n ahora de que las universidades hagan complicadas reglamentaciones, sino que permitan que los profesores dise\u00f1en sus asignaturas teniendo en cuenta sus especificidades. <\/p>\n<p>[T10] \tOs dejo la conferencia de clausura que di en octubre en el CINAIC 2019 titulada \u201c<strong>\u00bfC\u00f3mo pueden responder las universidades a los retos derivados de la transformaci\u00f3n digital? Modelos educativos flexibles<\/strong>\u201d <a href=\"https:\/\/blogs.ua.es\/faraonllorens\/2019\/10\/11\/modelos-educativos-flexibles-cinaic2019\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/blogs.ua.es\/faraonllorens\/2019\/10\/11\/modelos-educativos-flexibles-cinaic2019<\/a><\/p>\n<p>Cierro Hilo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reflexi\u00f3n para una docencia postpandemia Fara\u00f3n Llorens Largo C\u00e1tedra Santander-UA de Transformaci\u00f3n Digital Universidad de Alicante Reflexi\u00f3n para una docencia postpandemia #DocenciaVirtual #DocenciaOnline #eLearning Tras actuar de urgencia en la situaci\u00f3n actual, es momento de pensar en el curso 2020-2021 y siguientes. @CatedraTD_UA, @UA_Universidad @CrueUniversidad @RedCLARA @infometared Abro Hilo: [T01] Necesitamos dise\u00f1ar una docencia universitaria [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[412,564009,204,2325692],"tags":[1544,944,223,163204,564010,182],"class_list":["post-2781","post","type-post","status-publish","format-standard","hentry","category-actividades","category-catedratd_ua","category-innovacion-educativa","category-smart_learning","tag-aprendizaje","tag-blearning","tag-docencia","tag-educacion-abierta","tag-transformacion-digital","tag-universidad"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/2781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/comments?post=2781"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/2781\/revisions"}],"predecessor-version":[{"id":2783,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/2781\/revisions\/2783"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/media?parent=2781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/categories?post=2781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/tags?post=2781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}