{"id":3199,"date":"2021-05-06T21:39:30","date_gmt":"2021-05-06T21:39:30","guid":{"rendered":"https:\/\/blogs.ua.es\/faraonllorens\/?p=3199"},"modified":"2021-05-07T11:46:47","modified_gmt":"2021-05-07T11:46:47","slug":"madurez-digital-de-las-universidades","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/faraonllorens\/2021\/05\/06\/madurez-digital-de-las-universidades\/","title":{"rendered":"Madurez digital de las universidades"},"content":{"rendered":"<p><strong>Madurez digital de las universidades<\/strong><br \/>\nFara\u00f3n Llorens Largo<\/p>\n<p>Tema 2.5. <em>La Universidad Digital<\/em><br \/>\nResponsable: Carlos Delgado Kloos<br \/>\n(03\/05\/2021 y 06\/05\/2021) <\/p>\n<p>M\u00f3dulo 2. <em>Financiaci\u00f3n, personas y digitalizaci\u00f3n<\/em><br \/>\nCoordinadores: Juan Herna\u0301ndez Armenteros y Jose\u0301 Antonio Pe\u0301rez Garci\u0301a<\/p>\n<p><strong>Diploma de posgrado en pol\u00edtica y gesti\u00f3n universitarias<\/strong><br \/>\nDirecci\u00f3n: Manuel Parras Rosa<br \/>\n<a href=\"https:\/\/www.unia.es\" rel=\"noopener\" target=\"_blank\">UNIA<\/a>, <a href=\"https:\/\/www.ujaen.es\" rel=\"noopener\" target=\"_blank\">UJA<\/a> y <a href=\"https:\/\/www.crue.org\" rel=\"noopener\" target=\"_blank\">CRUE<\/a><br \/>\n<a href=\"https:\/\/www.ujaen.es\/estudios\/oferta-academica\/titulos-propios\/diplomas-de-postgrado\/diploma-de-posgrado-en-politica-y-gestion-universitarias\" rel=\"noopener\" target=\"_blank\">https:\/\/www.ujaen.es\/estudios\/oferta-academica\/titulos-propios\/diplomas-de-postgrado\/diploma-de-posgrado-en-politica-y-gestion-universitarias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madurez digital de las universidades Fara\u00f3n Llorens Largo Tema 2.5. La Universidad Digital Responsable: Carlos Delgado Kloos (03\/05\/2021 y 06\/05\/2021) M\u00f3dulo 2. Financiaci\u00f3n, personas y digitalizaci\u00f3n Coordinadores: Juan Herna\u0301ndez Armenteros y Jose\u0301 Antonio Pe\u0301rez Garci\u0301a Diploma de posgrado en pol\u00edtica y gesti\u00f3n universitarias Direcci\u00f3n: Manuel Parras Rosa UNIA, UJA y CRUE https:\/\/www.ujaen.es\/estudios\/oferta-academica\/titulos-propios\/diplomas-de-postgrado\/diploma-de-posgrado-en-politica-y-gestion-universitarias<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[412,564009,163436],"tags":[564008,229692,39,564010,182],"class_list":["post-3199","post","type-post","status-publish","format-standard","hentry","category-actividades","category-catedratd_ua","category-gobierno-de-las-ti","tag-cartera-estrategica-proyectos-ti","tag-cio","tag-tecnologia","tag-transformacion-digital","tag-universidad"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/3199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/comments?post=3199"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/3199\/revisions"}],"predecessor-version":[{"id":3200,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/posts\/3199\/revisions\/3200"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/media?parent=3199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/categories?post=3199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/faraonllorens\/wp-json\/wp\/v2\/tags?post=3199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}