{"id":8031,"date":"2025-09-09T07:43:41","date_gmt":"2025-09-09T06:43:41","guid":{"rendered":"https:\/\/blogs.ua.es\/fisicateleco\/?p=8031"},"modified":"2025-09-17T10:41:57","modified_gmt":"2025-09-17T09:41:57","slug":"8031","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/fisicateleco\/2025\/09\/09\/8031\/","title":{"rendered":"Comienza la asignatura &#8220;Ampliaci\u00f3n de F\u00edsica&#8221; del Grado en Ingenier\u00eda Rob\u00f3tica de la UA"},"content":{"rendered":"<h2 id=\"contenidos\" class=\"apartado\">Contenidos para el curso 2025-26<\/h2>\n<p><strong>Tema 1. Cinem\u00e1tica plana del s\u00f3lido r\u00edgido<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Traslaci\u00f3n. Movimiento plano. Rotaci\u00f3n alrededor de un eje fijo<\/li>\n<li>Movimiento plano general. Velocidades absoluta y relativa<\/li>\n<li>Centro instant\u00e1neo de rotaci\u00f3n en el movimiento plano<\/li>\n<li>Aceleraciones absoluta y relativa en el movimiento plano<\/li>\n<li>Movimiento plano relativo a ejes en rotaci\u00f3n. Aceleraci\u00f3n de Coriolis<\/li>\n<\/ul>\n<p><strong>Tema 2. Cinem\u00e1tica tridimensional del s\u00f3lido r\u00edgido<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Teorema de Euler. Rotaciones finitas e infinitesimales<\/li>\n<li>Rotaci\u00f3n en torno a un punto fijo<\/li>\n<li>Movimiento general de un s\u00f3lido r\u00edgido en el espacio<\/li>\n<li>Eje instant\u00e1neo de rotaci\u00f3n y m\u00ednimo deslizamiento<\/li>\n<li>Movimiento tridimensional relativo a ejes en rotaci\u00f3n<\/li>\n<li>Derivada respecto al tiempo de un vector con respecto a un sistema fijo o a un sistema trasladante-rotatorio<\/li>\n<\/ul>\n<p><strong>Tema 3. Geometr\u00eda de masas<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Centro de masas, centro de gravedad y centroide<\/li>\n<li>Momento de inercia<\/li>\n<li>Radio de giro<\/li>\n<li>Teoremas de Steiner para momentos de inercia<\/li>\n<li>Productos de inercia<\/li>\n<li>Momentos principales de inercia<\/li>\n<li>Momentos de inercia de superficies planas<\/li>\n<\/ul>\n<p><strong>Tema 4. Est\u00e1tica del s\u00f3lido r\u00edgido<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Condiciones de equilibrio<\/li>\n<li>Reacciones de enlace<\/li>\n<li>Resoluci\u00f3n de problemas. Diagrama del s\u00f3lido libre<\/li>\n<li>Fuerzas interiores en miembros estructurales<\/li>\n<\/ul>\n<p><strong>Tema 5. Din\u00e1mica plana del s\u00f3lido r\u00edgido<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Ecuaciones del movimiento plano de un s\u00f3lido r\u00edgido<\/li>\n<li>Traslaci\u00f3n, rotaci\u00f3n y movimiento plano general de un s\u00f3lido r\u00edgido<\/li>\n<li>Trabajo de fuerzas y pares que se ejercen sobre un s\u00f3lido r\u00edgido<\/li>\n<li>Energ\u00eda cin\u00e9tica de un s\u00f3lido r\u00edgido en movimiento plano<\/li>\n<li>Conservaci\u00f3n de la energ\u00eda<\/li>\n<li>Momento angular de un s\u00f3lido r\u00edgido en movimiento plano<\/li>\n<\/ul>\n<p><strong>Tema 6. Din\u00e1mica tridimensional del s\u00f3lido r\u00edgido<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Movimiento tridimensional de un s\u00f3lido r\u00edgido. Ecuaciones de Euler<\/li>\n<li>Momento angular en el movimiento tridimensional<\/li>\n<li>Principio del impulso y cantidad de movimiento<\/li>\n<li>Energ\u00eda cin\u00e9tica de un s\u00f3lido r\u00edgido en tres dimensiones<\/li>\n<li>Conservaci\u00f3n de la energ\u00eda<\/li>\n<li>Movimiento de un gir\u00f3scopo<\/li>\n<li>Movimiento sin par de torsi\u00f3n<\/li>\n<\/ul>\n<p><strong>Tema 7. Vibraciones mec\u00e1nicas<br \/>\n<\/strong><\/p>\n<ul>\n<li>Introducci\u00f3n<\/li>\n<li>Vibraciones libres no amortiguadas<\/li>\n<li>Vibraciones libres amortiguadas<\/li>\n<li>Vibraciones forzadas<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Contenidos para el curso 2025-26 Tema 1. Cinem\u00e1tica plana del s\u00f3lido r\u00edgido Introducci\u00f3n Traslaci\u00f3n. Movimiento plano. Rotaci\u00f3n alrededor de un eje fijo Movimiento plano general. Velocidades absoluta y relativa Centro instant\u00e1neo de rotaci\u00f3n en el movimiento plano Aceleraciones absoluta y &hellip; <a href=\"https:\/\/blogs.ua.es\/fisicateleco\/2025\/09\/09\/8031\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1239,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2230164,173824,2230165,4723,1366],"tags":[2230164,1671,2230165,6693],"class_list":["post-8031","post","type-post","status-publish","format-standard","hentry","category-ampliacion-de-fisica","category-asignatura","category-grado-en-ingenieria-robotica","category-materiales-docentes","category-temas","tag-ampliacion-de-fisica","tag-asignatura","tag-grado-en-ingenieria-robotica","tag-mecanica"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/posts\/8031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/users\/1239"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/comments?post=8031"}],"version-history":[{"count":7,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/posts\/8031\/revisions"}],"predecessor-version":[{"id":8344,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/posts\/8031\/revisions\/8344"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/media?parent=8031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/categories?post=8031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/fisicateleco\/wp-json\/wp\/v2\/tags?post=8031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}