{"id":38,"date":"2009-03-11T15:32:52","date_gmt":"2009-03-11T13:32:52","guid":{"rendered":"https:\/\/blogs.ua.es\/genetica\/?p=38"},"modified":"2009-03-18T19:54:04","modified_gmt":"2009-03-18T17:54:04","slug":"el-mito-de-anastasia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/genetica\/2009\/03\/11\/el-mito-de-anastasia\/","title":{"rendered":"El mito de Anastasia"},"content":{"rendered":"<figure id=\"attachment_39\" aria-describedby=\"caption-attachment-39\" style=\"width: 376px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blogs.ua.es\/genetica\/files\/2009\/03\/anastasia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39\" src=\"https:\/\/blogs.ua.es\/genetica\/files\/2009\/03\/anastasia-300x185.jpg\" alt=\"Las grandes duquesas de Rusia\" width=\"376\" height=\"231\" \/><\/a><figcaption id=\"caption-attachment-39\" class=\"wp-caption-text\">Las grandes duquesas de Rusia<\/figcaption><\/figure>\n<p>Tras el \u00e9xito de la revoluci\u00f3n bolchevique, el zar <strong>Nicol\u00e1s II<\/strong> de Rusia abdic\u00f3 en 1917. \u00c9l y su familia fueron conducidos a <strong>Ekaterinburgo<\/strong>, donde fueron mantenidos presos junto con algunos leales sirvientes. El 17 de julio de 1918 el zar, la zarina <strong>Alejandra<\/strong>, sus hijas<strong> Olga, Mar\u00eda, Anastasia y Tatiana<\/strong>, y su hijo <strong>Alejandro<\/strong> fueron ejecutados por un pelot\u00f3n de fusilamiento, bajo las \u00f3rdenes expresas de <strong>Lenin<\/strong>. Sus cuerpos fueron enterrados, junto con los de los criados, en una fosa com\u00fan, y olvidados durante decenios.<\/p>\n<p>Numerosas personas pretendieron ser los hijos del zar Nicol\u00e1s, supuestamente hu\u00eddos de su prisi\u00f3n y milagrosamente salvados del ej\u00e9rcito rojo. Tras la ca\u00edda del r\u00e9gimen sovi\u00e9tico, se procedi\u00f3 a buscar los cad\u00e1veres de la familia imperial rusa, con la intenci\u00f3n de desvelar de una vez por todas uno de los grandes misterios de la historia moderna europea: cu\u00e1l fue el destino de los Romanov.<\/p>\n<p>En 1991 se produjo en Ekaterinburgo el descubrimiento oficial de una fosa com\u00fan que conten\u00eda restos de nueve personas. Aparte de otras evidencias, al an\u00e1lisis de ADN fue una parte decisiva en el estalecimiento de la identidad de esas personas, en el que participan miembros actuales de la nobleza europea y famosos estafadores e impostores.<\/p>\n<p><a href=\"http:\/\/www.nature.com\/ng\/journal\/v6\/n2\/abs\/ng0294-130.html\">Un estudio<\/a> de una serie de <strong>polimorfismos cortos en t\u00e1ndem<\/strong> (STR) del ADN extra\u00eddo de los nueve esqueletos,\u00a0 estableci\u00f3 que dos de las personas eran los padres de los tres ni\u00f1os, mientras que los dos restantes no estaban emparentados biol\u00f3gicamente con ellos. Es decir, faltaban dos de los hijos del zar y de la zarina, confirm\u00e1ndose los testimonios que afirmaban que fueron enterrados separadamente. Alternativamente, tambi\u00e9n apoyaban la creencia de que Alejandro y Anastasia sobrevivieron a la masacre. Los restos no emparentados corresponder\u00edan a un sirviente y al m\u00e9dico imperial, <strong>Eugeny Botkin<\/strong>.<\/p>\n<p>Varios porlimorfismos del <strong>ADN mitocondrial<\/strong> de la zarina Alejandra coincid\u00eda con el de las ni\u00f1as, confirmando que era su madre, pero tambi\u00e9n con un pariente vivo, bis-sobrino de Alejandra, el pr\u00edncipe <strong>Felipe, duque de Edinburgo<\/strong> y esposo de Isabel II de Inglaterra. Las mitocondrias solo se heredan por v\u00eda materna, los hombres no aportan ADN mitocondrial a sus hijos, por lo que es necesario que el parentesco se establezco por v\u00eda materna o entre hermanas. La abuela materna del pr\u00edncipe, <strong>Victoria de Hesse y del Rhin<\/strong>, era hermana de Alejandra.<\/p>\n<p>El ADN mitocondrial de Nicol\u00e1s segundo tambi\u00e9n iba a dar una pista sobre su parentesco con algunos descendientes vivos de su abuela, <strong>Luisa de Hesse-Cassel<\/strong>. Pero adem\u00e1s guardaba una sorpresa: el ADN mitocondrial del zar presentana un fen\u00f3meno raro de <strong>heteroplasmia<\/strong>: exist\u00edan en sus mitocondrias dos secuencias diferentes de ADN, originadas posiblemente por mutaci\u00f3n. Ya que las mitocondrias no se separan tan precisamente como los cromosomas en la formaci\u00f3n de los gametos, es posible que esta heteroplasmia la presentaran tambi\u00e9n algunos de sus parientes. <a href=\"http:\/\/www.nature.com\/ng\/journal\/v12\/n4\/abs\/ng0496-417.html\">En 1996<\/a> se determin\u00f3 que el hermano del zar, <strong>Jorge Romanov<\/strong>, enterrado en la catedral de San Petersburgo, conten\u00eda la misma variante de heteroplasmia, perdida paulatinamente por segregaci\u00f3n en su pariente por v\u00eda materna a\u00fan viva, la condesa <strong>Xenia Cheremeteff-Sfiri<\/strong>, sobrina-nieta de Nicol\u00e1s II.<\/p>\n<p>La historia de los pr\u00edncipes perdidos ha llenado p\u00e1ginas y p\u00e1ginas de peri\u00f3dicos, creado literatura e incluso pel\u00edculas de cine. Tambi\u00e9n ha dado lugar a varios falsos pretendientes al trono. El caso m\u00e1s famoso fue el de <strong>Anna Anderson<\/strong>, que pretendi\u00f3 ser la princesa <strong>Anastasia<\/strong>. A pesar de que hubo testigos que afirmaban que toda la famila Romanov fue ejecutada, otros testimonios sembraron la duda sobre la posible fuga de Anastasia, que pudo haberse librado de la ejecuci\u00f3n protegida por su madre y hermanas. Anderson fue rescatada como herida de guerra durante el primer conficto mundial e ingresada en un hospital de Alemania con transtornos de memoria, donde anunci\u00f3 ser la gran duquesa Anastasia en 1921.<\/p>\n<p>Una serie de confusas entrevistas con personas que conocieron a Anastasia Romanov emitieron una serie de informes contradictorios e inconcluyentes. Anderson empez\u00f3 una larga batalla legal para el reconocimiento de sus derechos como heredera de los Romanov. No fue hasta 1970 cuando finalmente se determin\u00f3 judicialmente que no exist\u00edan pruebas concluyentes para afirmar que Anderson era Anastasia. Tras el descubrimiento de la tumba del zar en 1991, se comprob\u00f3 que el ADN de unas muestras de tejido de Anderson, que guardaba el <strong>hospital Martha Jefferson<\/strong> de Charlottesville (donde muri\u00f3 Anna Anderson en 1984), no coincid\u00eda en absoluto con el ADN rescatado ni con el del pr\u00edncipe Felipe. El fraude hab\u00eda sido definitivamente descubierto.<\/p>\n<p>La historia acaba en el a\u00f1o 2007, cuando unos arque\u00f3logos aficionados interesados en el esclarecimiento de las tumbas de los Romanov, descubre una segunda sepultura. <a href=\"http:\/\/www.plosone.org\/article\/info:doi\/10.1371\/journal.pone.0004838\">Recientemente en 2009<\/a>, se ha demostrado empleando polimorfismos STR, ADN mitocondrial y an\u00e1lisis del <strong>cromosoma Y<\/strong> que en esa tumba se hallaban los restos de la hija y el hijo de Nicol\u00e1s y Alejandra que faltaban.<\/p>\n<p>Debido a su edad muy similar, ha sido imposible diferenciar los restos de Mar\u00eda y Anastasia, pero indudablemente ambas fueron enterradas en Ekaterinburgo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el \u00e9xito de la revoluci\u00f3n bolchevique, el zar Nicol\u00e1s II de Rusia abdic\u00f3 en 1917. \u00c9l y su familia fueron conducidos a Ekaterinburgo, donde fueron mantenidos presos junto con algunos leales sirvientes. El 17 de julio de 1918 el zar, la zarina Alejandra, sus hijas Olga, Mar\u00eda, Anastasia y Tatiana, y su hijo Alejandro [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/posts\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/posts\/38\/revisions"}],"predecessor-version":[{"id":42,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/posts\/38\/revisions\/42"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/media?parent=38"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/categories?post=38"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/genetica\/wp-json\/wp\/v2\/tags?post=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}