{"id":135,"date":"2010-01-07T21:49:24","date_gmt":"2010-01-07T19:49:24","guid":{"rendered":"https:\/\/blogs.ua.es\/grancapitan\/?p=135"},"modified":"2010-01-09T12:37:27","modified_gmt":"2010-01-09T10:37:27","slug":"los-ingenieros-del-gran-capitan","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/grancapitan\/2010\/01\/07\/los-ingenieros-del-gran-capitan\/","title":{"rendered":"Los ingenieros del Gran Capit\u00e1n"},"content":{"rendered":"<p>El Gran Capit\u00e1n di\u00f3 mucha importancia a las tareas de preparaci\u00f3n de terreno, empleo de minas y paso de puentes. Emple\u00f3 soldados de infanter\u00eda en trabajos especializados de zapadores e inculc\u00f3 en todo el ej\u00e9rcito la importancia de la fortificaci\u00f3n.<\/p>\n<p>Respecto a la castrametaci\u00f3n adopt\u00f3 un sistema normalizado de campamento tipo adaptable a cualquier situaci\u00f3n y terreno. Respecto a l<strong><\/strong>a fortificaci\u00f3n, la emple\u00f3 para inutilizar las armas ofensivas enemigas y la acci\u00f3n de sus proyectiles. Emple\u00f3 minas <strong><\/strong>como una nueva t\u00e9cnica de combate para el asalto a las plazas fortificadas (los castillos de Castilnovo y Castel de Ovo). Por \u00faltimo, utiliz\u00f3 pontoneros<strong><\/strong> para el tendido improvisado de puentes (en la batalla de Garellano).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gran Capit\u00e1n di\u00f3 mucha importancia a las tareas de preparaci\u00f3n de terreno, empleo de minas y paso de puentes. Emple\u00f3 soldados de infanter\u00eda en trabajos especializados de zapadores e inculc\u00f3 en todo el ej\u00e9rcito la importancia de la fortificaci\u00f3n. Respecto a la castrametaci\u00f3n adopt\u00f3 un sistema normalizado de campamento tipo adaptable a cualquier situaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1321,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5729],"tags":[5960,3639],"class_list":["post-135","post","type-post","status-publish","format-standard","hentry","category-militar","tag-gran-capitan","tag-ingenieros"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/posts\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/users\/1321"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"predecessor-version":[{"id":148,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/posts\/135\/revisions\/148"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/grancapitan\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}