{"id":36,"date":"2013-12-16T10:18:27","date_gmt":"2013-12-16T10:18:27","guid":{"rendered":"https:\/\/blogs.ua.es\/historiacallosa\/?p=36"},"modified":"2013-12-16T10:18:27","modified_gmt":"2013-12-16T10:18:27","slug":"real-privilegio-de-1579","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/historiacallosa\/2013\/12\/16\/real-privilegio-de-1579\/","title":{"rendered":"Real Privilegio de 1579."},"content":{"rendered":"<p align=\"LEFT\"><span style=\"font-size: medium\">El ya citado privilegio del 4 de noviembre de 1579 que nombr\u00f3 a Callosa universidad independiente, es otorgado por su majestad debido a la prosperidad econ\u00f3mica y el aumento demogr\u00e1fico que sufre el Reino de Valencia a finales del siglo XVI. Adem\u00e1s la monarqu\u00eda hisp\u00e1nica estaba sumida en una pol\u00edtica exterior expansiva y de constantes disputas que desgastaban de forma constante a la corona de forma econ\u00f3mica y pol\u00edtica. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">Es en esta coyuntura cuando varias localidades comarcales ven la oportunidad de tener autonom\u00eda y gestionar sus intereses al margen de los centros urbanos de los que depend\u00edan. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">Para la segregaci\u00f3n de callosa hicieron falta 8,000 ducados que pagara a la corona, que salieron de impuestos especiales a\u00f1adidos a la poblaci\u00f3n, pero que sobretodo fueron asumidos por las \u00e9lites locales. Se pagaba no solo para ser independiente de los centros urbanos importantes, sino tambi\u00e9n para alcanzar un rango urbano mayor, lo que les proporcionaba la independencia que solicitaban en mayor o menor medida dependiendo del rango que adquiriese el lugar. Si mas tarde se quer\u00eda seguir ascendiendo de rangos dentro de la escala urbana era necesario un nuevo pago. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">Callosa fue la primera localidad que se independiza de Orihuela, pero m\u00e1s tarde otras localidades siguieron el ejemplo de Callosa debido a que la gesti\u00f3n de Orihuela era dudosamente beneficiosa para las localidades, ya que miraba mayormente por sus intereses. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">Callosa adem\u00e1s ser\u00e1 la primera localidad de la zona que alcance el rango de villa real tras el pago de 4,500 libras en 1638. Esto indica que la densidad demogr\u00e1fica de la comarca era lo suficientemente densa como para permitirse la creaci\u00f3n de nuevos enclaves independientes importantes. Adem\u00e1s hay que recalcar que no solo es necesario un alto volumen demogr\u00e1fico, sino una \u00e9lite acaudalada que pueda hacer frente a los pagos para independizarse y m\u00e1s tarde pagar los impuestos requeridos. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">No se tienen datos de todas las gestiones de Callosa ya que su archivo fue destruido a finales de la guerra civil espa\u00f1ola, pero se sabe que para lograra estos objetivos eran necesarios muchos tr\u00e1mites administrativos y judiciales para llevarse a cabo, adem\u00e1s que tras la independencia de Orihuela ser\u00edan los propios callosinos los que se encargasen de la administraci\u00f3n y gesti\u00f3n pol\u00edtica de su localidad, lo que produce a\u00fan mucho m\u00e1s volumen archiv\u00edstico. <\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">Al remitir Orihuela el memorial en 1579 se puede deducir que las intenciones separatistas de Callosa ya eran palpables a\u00f1os atr\u00e1s antes de que Felipe II concediese a la localidad el rango de universidad independiente con el real privilegio de 1579.<\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">El real privilegio de 1579 cuenta con cinco partes que se diferencian en los que encontramos una introducci\u00f3n en el cual llama la atenci\u00f3n de que el alguacil real(Joan Abell\u00e1) convoca a todos los habitantes de Callosa en la iglesia de de San Mart\u00edn bao pena de multa para aquellos que all\u00ed no se encontrasen, fue cuando todos estaban reunidos cuando se procedi\u00f3 a la lectura del real privilegio que les proporcionaba la independencia de Orihuela<\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: medium\">En los 34 art\u00edculos se explica como deben componerse los nuevos cargos p\u00fablicos de Callosa y les anuncian sus nuevos deberes y obligaciones, adem\u00e1s se insta a que Callosa y Orihuela mantengan unas relaciones cordiales pese a la fractura territorial.<\/span><\/p>\n<p align=\"LEFT\">\n<p align=\"LEFT\"><span style=\"font-size: large\">Navarro Hern\u00e1ndez, Antonio Jos\u00e9, Creaci\u00f3n y consolidaci\u00f3n del municipio de Callosa del Segura en tiempos de fueros, Alicante, Instituto alicantino de cultura Juan Gil-Albert, 2001, pp. 43-46.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ya citado privilegio del 4 de noviembre de 1579 que nombr\u00f3 a Callosa universidad independiente, es otorgado por su majestad debido a la prosperidad econ\u00f3mica y el aumento demogr\u00e1fico que sufre el Reino de Valencia a finales del siglo XVI. Adem\u00e1s la monarqu\u00eda hisp\u00e1nica estaba sumida en una pol\u00edtica exterior expansiva y de constantes [&hellip;]<\/p>\n","protected":false},"author":3135,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[457931,112179,266317,457927],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-politica","tag-457931","tag-callosa","tag-real-privilegio","tag-universidad-independiente"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/users\/3135"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"predecessor-version":[{"id":46,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/posts\/36\/revisions\/46"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiacallosa\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}