{"id":29,"date":"2014-01-14T17:54:35","date_gmt":"2014-01-14T17:54:35","guid":{"rendered":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/?p=29"},"modified":"2014-01-14T17:54:35","modified_gmt":"2014-01-14T17:54:35","slug":"siglo-xiv","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/2014\/01\/14\/siglo-xiv\/","title":{"rendered":"Siglo XIV"},"content":{"rendered":"<p>En la mitad del siglo XIV la zona valenciana estar\u00e1 sumida en una crisis general, agravada por la suma de una serie de calamidades (sequ\u00edas, inundaciones, crisis de subsistencias), lo que desembocar\u00e1 en un proceso de inestabilidad pol\u00edtica.<\/p>\n<p>Desde el propio reino habr\u00e1 una serie de enfrentamientos tanto end\u00f3genos como ex\u00f3genos. Como conflictos externos se asiste al enfrentamiento con Castilla, cuya guerra finalizar\u00e1 con la muerte de Pedro el Cruel en el a\u00f1o 1369, as\u00ed como la firma del tratado de Almaz\u00e1n (1375), renunciando la Corona de Arag\u00f3n a Murcia y de Castilla al Sur del reino.<\/p>\n<p>En cuanto al factor end\u00f3geno, el panorama resultante ser\u00e1 la necesidad de capital del monarca, por lo que realizar\u00e1 peticiones de donaciones y pr\u00e9stamos a las Cortes. Situaci\u00f3n que aprovechar\u00e1n las Cortes para recuperar parte del poder perdido anta\u00f1o.<\/p>\n<p>En el a\u00f1o 1360 tiene lugar la creaci\u00f3n de la Generalitat para controlar la labor de donaciones al rey. Pero dos a\u00f1os m\u00e1s tarde adquirir\u00e1 un nuevo al gestionar el impuesto de las generalitats, trat\u00e1ndose de un impuesto sobre producci\u00f3n y el comercio.<\/p>\n<p>Como finalizaci\u00f3n de este siglo XIV decir que la dentro de los territorios de la Corona de Arag\u00f3n, el reino de Valencia, y m\u00e1s concretamente su capital, se convierte en el nuevo centro financiero para la corona. Paralelamente se producen unos incrementos de la autonom\u00eda financiera de los municipios, as\u00ed como el de la deuda p\u00fablica. Todo ello en conclusi\u00f3n para satisfacer las necesidades econ\u00f3micas de la monarqu\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la mitad del siglo XIV la zona valenciana estar\u00e1 sumida en una crisis general, agravada por la suma de una serie de calamidades (sequ\u00edas, inundaciones, crisis de subsistencias), lo que desembocar\u00e1 en un proceso de inestabilidad pol\u00edtica. Desde el &hellip; <a href=\"https:\/\/blogs.ua.es\/historiamonfortedelcid\/2014\/01\/14\/siglo-xiv\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3175,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/users\/3175"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"predecessor-version":[{"id":30,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/posts\/29\/revisions\/30"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiamonfortedelcid\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}