{"id":94,"date":"2014-01-13T21:25:59","date_gmt":"2014-01-13T21:25:59","guid":{"rendered":"https:\/\/blogs.ua.es\/historiaorihuela\/?p=94"},"modified":"2014-01-14T21:57:25","modified_gmt":"2014-01-14T21:57:25","slug":"el-trigo-y-el-posito","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/historiaorihuela\/2014\/01\/13\/el-trigo-y-el-posito\/","title":{"rendered":"El trigo y el p\u00f3sito"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/historiaorihuela\/files\/2014\/01\/Trigo-y-p\u00f3sito.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-192\" alt=\"Trigo y p\u00f3sito\" src=\"https:\/\/blogs.ua.es\/historiaorihuela\/files\/2014\/01\/Trigo-y-p\u00f3sito-300x202.gif\" width=\"300\" height=\"202\" \/><\/a><\/p>\n<p>Durante la Edad Moderna <b>Orihuela<\/b> fue considerada el <b>granero del reino<\/b>, porque era capaz de producir el suficiente trigo como para proveer el mercado exterior y su consumo local. Sin embargo, no siempre fue capaz de producir la misma abundancia de cereal, concretamente durante el siglo XVII, que en general fue un siglo de decadencia en muchos sentidos. No obstante, su producci\u00f3n sigui\u00f3 siendo significativa.<\/p>\n<p>A pesar de la alta productividad, no se descart\u00f3 la idea de crear una c\u00e1mara municipal de trigo o <b><i>p\u00f3sito<\/i><\/b>. Estas c\u00e1maras, junto a las alh\u00f3ndigas y graneros, ayudaban a proteger y garantizar el consumo y producci\u00f3n del trigo ante las posibles amenazas a las que \u00e9ste estaba expuesto, como: las malas cosechas; la oscilaci\u00f3n de los precios; y la especulaci\u00f3n y pr\u00e1cticas de usura sobre el mercado. Adem\u00e1s el p\u00f3sito ten\u00eda como funci\u00f3n principal conceder pr\u00e9stamos de cereal en condiciones m\u00f3dicas a los vecinos que tuvieran necesidad de vender o comprar. El precio que fijaban las autoridades se basaba en el valor que en ese momento tuviera el trigo en el mercado.<\/p>\n<p>Por otra parte, a esta abundante productividad se le sumo la presi\u00f3n que los cosecheros ejerc\u00edan para conseguir asegurarse un mercado exterior. Ambas circunstancias llevaron a que en 1542 se le concediera a Orihuela el privilegio de exportar trigo a las afueras del reino de Valencia.<\/p>\n<p>Miriam T Mu\u00f1oz Rico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la Edad Moderna Orihuela fue considerada el granero del reino, porque era capaz de producir el suficiente trigo como para proveer el mercado exterior y su consumo local. Sin embargo, no siempre fue capaz de producir la misma abundancia de cereal, concretamente durante el siglo XVII, que en general fue un siglo de decadencia [&hellip;]<\/p>\n","protected":false},"author":1863,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[258],"tags":[170458,365793],"class_list":["post-94","post","type-post","status-publish","format-standard","hentry","category-economia","tag-economia-2","tag-posito"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/posts\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/users\/1863"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/posts\/94\/revisions"}],"predecessor-version":[{"id":197,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/posts\/94\/revisions\/197"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/categories?post=94"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/historiaorihuela\/wp-json\/wp\/v2\/tags?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}