{"id":78,"date":"2010-11-03T09:10:58","date_gmt":"2010-11-03T09:10:58","guid":{"rendered":"https:\/\/blogs.ua.es\/indumentariamoderna\/?p=78"},"modified":"2013-01-13T13:58:48","modified_gmt":"2013-01-13T13:58:48","slug":"prendas-de-vestir-hombres","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/indumentariamoderna\/2010\/11\/03\/prendas-de-vestir-hombres\/","title":{"rendered":"Hombres"},"content":{"rendered":"<h1>Trajes<\/h1>\n<p style=\"text-align: justify\">Las prendas masculinas principales eran el <strong><em><span style=\"color: #3366ff\">jub\u00f3n<\/span><\/em><\/strong>, las <em>calzas<\/em> y el <strong><em><span style=\"color: #3366ff\">sayo<\/span><\/em><\/strong>.<\/p>\n<ul>\n<li>\n<div style=\"text-align: justify\">El <em>jub\u00f3n<\/em> se vest\u00eda sobre la camisa y cubr\u00eda el cuerpo hasta la cintura. Las <strong><em><span style=\"color: #3366ff\">calzas<\/span><\/em><\/strong> se sujetaban al <em>jub\u00f3n<\/em> con unos cordones llamados <strong><em><span style=\"color: #3366ff\">agujetas<\/span><\/em><\/strong>. <span style=\"color: #ff0000\">(Ver figuras <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-2.jpg\">8, 9<\/a> y <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-18.jpg\">86<\/a>). <\/span>De un hombre vestido s\u00f3lo con <em>calzas<\/em> y <em>jub\u00f3n<\/em> se dec\u00eda que estaba desnudo. Para poder decir que estaba vestido era necesario que llevase otra prenda encima.<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">El traje con faldas que se vest\u00eda directamente sobre el <em>jub\u00f3n<\/em> era el <strong><em><span style=\"color: #3366ff\">sayo<\/span><\/em><\/strong>. <span style=\"color: #ff0000\">(Figuras <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-2.jpg\">5<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-8.jpg\">42<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-12.jpg\">59<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-24.jpg\">113<\/a> y <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-30.jpg\">145<\/a>). <\/span>En los primeros treinta a\u00f1os del siglo, aproximadamente, s\u00f3lo prescind\u00edan del <em>sayo<\/em> los soldados, los pajes, los mozos de espuelas y los muchachos muy j\u00f3venes. Despu\u00e9s, la moda de llevar sobre el jub\u00f3n una prenda corta que dejase las piernas totalmente al descubierto, hizo perder importancia al sayo, especialmente en el traje cortesano.<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">Las prendas cortas que pod\u00edan sustituir al sayo fueron el <strong><em><span style=\"color: #3366ff\">coleto<\/span><\/em><\/strong>, la <strong><em><span style=\"color: #3366ff\">cuera<\/span><\/em><\/strong>, la <em>ropeta<\/em> y la <strong><em><span style=\"color: #3366ff\">ropilla<\/span><\/em><\/strong>. El coleto era en un principio una especie de chaleco sin mangas, que apenas pasaba de la cintura <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-4.jpg\">19<\/a>, <span style=\"color: #ff0000\"><a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-9.jpg\">45<\/a><\/span><\/span><span style=\"color: #ff0000\">).<\/span> La <em>cuera<\/em> tuvo origen en el traje militar espa\u00f1ol poco antes del 1530. Ven\u00eda a ser un nuevo modelo de <em>coleto<\/em> m\u00e1s largo, cerrado, que pod\u00eda tener mangas cortas <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-21.jpg\">99<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-29.jpg\">143<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-32.jpg\">154<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-37.jpg\">175<\/a>).<\/span> Las voces <em>coleto<\/em> y <em>cuera<\/em> llegaron a confundirse. La <em>ropeta<\/em> y la <em>ropilla<\/em> eran prendas cortas con mangas que equival\u00edan en cierto modo a la chaqueta de nuestros d\u00edas (<span style=\"color: #ff0000\">figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-21.jpg\">100<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-32.jpg\">155<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-37.jpg\">176<\/a>).<\/span><\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">Sobre el <em>sayo<\/em>, o sobre las prendas cortas que lo sustitu\u00edan, vest\u00edan los hombres un sobretodo o <strong><em><span style=\"color: #3366ff\">ropa de cubrir<\/span><\/em><\/strong>. Estos eran fundamentalmente de dos tipos. Unos eran sobretodos con mangas, abiertos por delante, forrados de piel por lo general, que recib\u00edan sencillamente el nombre de <strong><em><span style=\"color: #3366ff\">ropas<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-3.jpg\">13<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-13.jpg\">64<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-16.jpg\">79<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-17.jpg\">80<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-36.jpg\">167<\/a>); <\/span>si estaban forrados con piel de cordero de llamaban <strong><em><span style=\"color: #3366ff\">zamarros<\/span><\/em><\/strong>. En los \u00faltimos a\u00f1os de la vida del emperador apareci\u00f3 el <strong><em><span style=\"color: #3366ff\">tudesco<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(<a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-37.jpg\">figs. 173, 174<\/a>).<\/span> Otros sobretodos pertenec\u00edan a la familia de la <strong><em><span style=\"color: #3366ff\">capa<\/span><\/em><\/strong> y sus variedades. En este grupo debemos incluir adem\u00e1s de la capa propiamente dicha <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-2.jpg\">6, 7<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-4.jpg\">16<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-6.jpg\">28<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-24.jpg\">117<\/a>),<\/span> el <strong><em><span style=\"color: #3366ff\">capuz<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-24.jpg\">114<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-28.jpg\">137<\/a>),<\/span> el <strong><em><span style=\"color: #3366ff\">tabardo<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(<a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-29.jpg\">fig. 141<\/a>)<\/span>, la <strong><em><span style=\"color: #3366ff\">bernia<\/span><\/em><\/strong> o manto grosero y el <strong><em><span style=\"color: #3366ff\">capote<\/span><\/em><\/strong> para la lluvia.<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">Artesanos y labradores usaron los <span style=\"color: #3366ff\"><strong><em>calzones<\/em><\/strong> <\/span><span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-44.jpg\">207<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-45.jpg\">215<\/a>), <\/span>los <strong><em><span style=\"color: #3366ff\">zarag\u00fcelles<\/span><\/em><\/strong> (<span style=\"color: #ff0000\"><a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-44.jpg\">figs. 206, 211<\/a><\/span>), el <strong><em><span style=\"color: #3366ff\">gab\u00e1n<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(<a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-43.jpg\">fig. 204<\/a>),<\/span> el <strong><em><span style=\"color: #3366ff\">paletoque<\/span><\/em><\/strong> <span style=\"color: #ff0000\">(<a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-29.jpg\">fig. 142<\/a>)<\/span> y el <strong><em><span style=\"color: #3366ff\">capotillo de dos haldas<\/span><\/em><\/strong> (<span style=\"color: #ff0000\"><a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-45.jpg\">figs. 213, 214<\/a><\/span>). Algunas de estas prendas proced\u00edan del traje de las clases altas, pero en el siglo XVI hab\u00edan pasado ya de moda en esas clases. Otras ten\u00edan varios siglos de antig\u00fcedad.<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">Prendas de identificaci\u00f3n insegura o problem\u00e1tica, por carecer de datos suficientes sobre ellas, eran la <span style=\"color: #3366ff\"><strong><em>escuba<\/em><\/strong> <\/span>y la <strong><em><span style=\"color: #3366ff\">chamarra<\/span><\/em><\/strong>. La <strong><em><span style=\"color: #3366ff\">casaca<\/span><\/em><\/strong> se puso de moda en los \u00faltimos a\u00f1os del reinado del emperador (<span style=\"color: #ff0000\"><a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-41.jpg\">fig. 194<\/a><\/span>).<\/div>\n<\/li>\n<\/ul>\n<h1>Tocados<\/h1>\n<p style=\"text-align: justify\">Los dos tocados masculinos principales eran la <span style=\"color: #3366ff\"><strong><em>gorra<\/em><\/strong>\u00a0 <\/span>el <strong><em><span style=\"color: #3366ff\">sombrero<\/span><\/em><\/strong>. La misi\u00f3n de la gorra era adornar, la del sombrero proteger.<\/p>\n<ul>\n<li>\n<div style=\"text-align: justify\">La <em>gorra<\/em> apareci\u00f3 en el tr\u00e1nsito del siglo XV al XVI como una variedad del <strong><em><span style=\"color: #3366ff\">bonete<\/span><\/em><\/strong>, en la forma de un tocado redondo y aplastado, con vueltas o alas dobladas. Despu\u00e9s tom\u00f3 formas muy variadas <span style=\"color: #ff0000\">(<a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-7.jpg\">l\u00e1mina 7<\/a><\/span>).<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<div style=\"text-align: justify\">El <em>sombrero<\/em> era de hechura mucha m\u00e1s sencilla, se usaba para viajar y caminar al aire libre, y pod\u00eda llevarse sobre una <em>gorra<\/em> <span style=\"color: #ff0000\">(figs, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-11.jpg\">53<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-16.jpg\">78<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-20.jpg\">97<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-41.jpg\">192<\/a>).<\/span><\/div>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Durante el prime tercio del siglo XVI era moda llevar el pelo recogido en una <span style=\"color: #3366ff\"><strong><em>cofia<\/em><\/strong> <\/span>o <strong><em><span style=\"color: #3366ff\">garvin<\/span><\/em><\/strong> bajo la gorra <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-2.jpg\">8<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-6.jpg\">27<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-7.jpg\">34<\/a>).<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\">\u00a0<\/span><\/p>\n<h1>Calzado<\/h1>\n<p style=\"text-align: justify\">En los textos encontramos numerosos nombres de calzados, pero resulta a veces dif\u00edcil establecer diferencias y hacer definiciones exactas. Es posible agruparlos en las siguientes categor\u00edas:<\/p>\n<ul>\n<li>\u00a0Calzados escotados o cerrados, con tal\u00f3n, que se pon\u00edan directamente sobre las calzas (<strong><em><span style=\"color: #3366ff\">zapatos, zapatillas<\/span><\/em><\/strong>).<\/li>\n<li>Calzados que se diferenciaban de los anteriores en que cubr\u00edan tambi\u00e9n parte de las pernas (<strong><em><span style=\"color: #3366ff\">estivales, botas<\/span><\/em><\/strong>). <span style=\"color: #ff0000\">(figs. <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-16.jpg\">78<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-30.jpg\">144<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-41.jpg\">194<\/a>).<\/span><\/li>\n<li>Calzados de cuero o badana, muy flexibles, que sol\u00edan llevarse con un segundo calzado encima (los <strong><em><span style=\"color: #3366ff\">borcegu\u00edes<\/span><\/em><\/strong>, flexibles y altos hasta las rodillas, y las <strong><em><span style=\"color: #3366ff\">servillas<\/span><\/em><\/strong>, que cubr\u00edan s\u00f3lo el pie).<\/li>\n<li>Calzados sin tal\u00f3n, que se llevaban con los borcegu\u00edes, servillas y otros (los <strong><em><span style=\"color: #3366ff\">alcorques<\/span><\/em><\/strong> y <strong><em><span style=\"color: #3366ff\">pantufos<\/span><\/em><\/strong>, ambos con suela de corcho; las <strong><em><span style=\"color: #3366ff\">chinelas<\/span><\/em><\/strong>, de suela delgada, y las <strong><em><span style=\"color: #3366ff\">galochas<\/span><\/em><\/strong> para protegerse del barro).<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><span style=\"color: #ff0000\">(V\u00e9anse las figuras <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-24.jpg\">114<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-28.jpg\">137<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-36.jpg\">169<\/a>, <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-39.jpg\">184<\/a>, y la <a href=\"https:\/\/blogs.ua.es\/indumentariamoderna\/files\/2013\/01\/lamina-42.jpg\">l\u00e1mina 42<\/a>).<\/span><\/p>\n<p style=\"text-align: justify\">Bajo las calzas se us\u00f3 una prenda equivalente a nuestros calcetines que recib\u00eda el nombre de <strong><em><span style=\"color: #3366ff\">escarpines<\/span><\/em><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trajes Las prendas masculinas principales eran el jub\u00f3n, las calzas y el sayo. El jub\u00f3n se vest\u00eda sobre la camisa y cubr\u00eda el cuerpo hasta la cintura. Las calzas se sujetaban al jub\u00f3n con unos cordones llamados agujetas. (Ver figuras 8, 9 y 86). De un hombre vestido s\u00f3lo con calzas y jub\u00f3n se dec\u00eda [&hellip;]<\/p>\n","protected":false},"author":1838,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18979],"tags":[],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","category-prendas-de-vestir"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/posts\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/users\/1838"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":15,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"predecessor-version":[{"id":80,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/posts\/78\/revisions\/80"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/indumentariamoderna\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}