{"id":82,"date":"2013-01-25T12:41:10","date_gmt":"2013-01-25T12:41:10","guid":{"rendered":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/?p=82"},"modified":"2013-01-27T19:01:26","modified_gmt":"2013-01-27T19:01:26","slug":"trayectoria-profesional","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/2013\/01\/25\/trayectoria-profesional\/","title":{"rendered":"Trayectoria profesional"},"content":{"rendered":"<p style=\"text-align: justify\">Archivo de la Universidad de Alicante. Fondo documental Josefina Ferr\u00e1ndiz Casares[20 de diciembre de 2012]Disponible en: JF 10 BIS, Escritos personales.<\/p>\n<p style=\"text-align: justify\">Josefina Ferr\u00e1ndiz Casares, maestra de la Escuela Aneja a la del Magisterio de Alicante. Desde que termin\u00f3 su carrera hasta que obtuvo plaza en propiedad desempe\u00f1\u00f3 interinamente las siguientes plazas: su primera escuela, una escuela rural mixta, en medio del campo de Elche, Daim\u00e9s, \u201c<em>y una se pregunta: \u00bfvendr\u00e1n ni\u00f1os aqu\u00ed?<\/em>\u201d. Tras esto se estableci\u00f3 en la Secci\u00f3n de p\u00e1rvulos en la Escuela Graduada, \u201c<em>Fr\u00edo y nieve los tres meses que estuve all\u00ed<\/em>\u201d. Obtuvo plaza en la secci\u00f3n graduada del grupo escolar de Elda, \u201c<em>Estuve dos cursos en aquella escuela. El primero en la sexta secci\u00f3n. Ni\u00f1as despejadas y listas, de car\u00e1cter agradable y vivo. [\u2026] Al curso siguiente pas\u00e9 a la primera secci\u00f3n. Entre aquellas peque\u00f1as hab\u00eda una anormal. Era buena y bonita. Lleg\u00f3 a quererme mucho y yo tambi\u00e9n a ella<\/em>\u201d. Despu\u00e9s ejerci\u00f3 durante once d\u00edas en la escuela unitaria, en la ermita de San Antonio. Durante esos a\u00f1os e incluso despu\u00e9s de tomar posesi\u00f3n en la Aneja, asisti\u00f3 como maestra a las colonias escolares en vacaciones organizadas por la Normal.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/files\/2013\/01\/img7671.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-84\" src=\"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/files\/2013\/01\/img7671-297x300.jpg\" alt=\"\" width=\"297\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/files\/2013\/01\/img7671-297x300.jpg 297w, https:\/\/blogs.ua.es\/josefinaferrandizcasares\/files\/2013\/01\/img7671.jpg 863w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><\/a><\/p>\n<p>Para finalizar, continu\u00f3 en la secci\u00f3n en la Escuela Aneja a la del Magisterio de Alicante, el d\u00eda 12 de noviembre de 1934, su primera escuela en propiedad, \u201c<em>De nuevo en la escuela de mi infancia<\/em>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Archivo de la Universidad de Alicante. Fondo documental Josefina Ferr\u00e1ndiz Casares[20 de diciembre de 2012]Disponible en: JF 10 BIS, Escritos personales. Josefina Ferr\u00e1ndiz Casares, maestra de la Escuela Aneja a la del Magisterio de Alicante. Desde que termin\u00f3 su carrera &hellip; <a href=\"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/2013\/01\/25\/trayectoria-profesional\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2961,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[482],"tags":[256,15,199431],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-biografia","tag-educacion","tag-formacion","tag-josefina-ferrandiz"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/users\/2961"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":87,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/posts\/82\/revisions\/87"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/josefinaferrandizcasares\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}