{"id":215308,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/librosprivilegiosalicante\/tag\/maria-luisa-cabanes-catala\/","name":"Mar\u00eda Luisa Cabanes Catal\u00e1","slug":"maria-luisa-cabanes-catala","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/librosprivilegiosalicante\/wp-json\/wp\/v2\/tags\/215308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/librosprivilegiosalicante\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/librosprivilegiosalicante\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/librosprivilegiosalicante\/wp-json\/wp\/v2\/posts?tags=215308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}