{"id":191,"date":"2012-03-07T14:50:25","date_gmt":"2012-03-07T14:50:25","guid":{"rendered":"https:\/\/blogs.ua.es\/losmayas\/?p=191"},"modified":"2012-03-07T14:51:04","modified_gmt":"2012-03-07T14:51:04","slug":"diseno-urbano-y-construcciones","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/losmayas\/2012\/03\/07\/diseno-urbano-y-construcciones\/","title":{"rendered":"Dise\u00f1o urbano y construcciones"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: small\">El dise\u00f1o urbano maya podr\u00eda describirse f\u00e1cilmente como la divisi\u00f3n del espacio en grandes monumentos y calzadas. En este caso, las plazas p\u00fablicas al aire libre eran los lugares de reuni\u00f3n para las personas, as\u00ed como el enfoque del dise\u00f1o urbano, mientras que el espacio interior era completamente secundario. S\u00f3lo en el Poscl\u00e1sico Tard\u00edo las grandes ciudades mayas se convirtieron en fortalezas que carec\u00edan, en su mayor parte, de las grandes y numerosas plazas del cl\u00e1sico.<\/span><\/span><\/span><\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/Chichen-Itza-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-192\" src=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/Chichen-Itza-5-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/templo-maya-de-chichen-itza-yucatan.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-194\" src=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/templo-maya-de-chichen-itza-yucatan-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: small\">Realizaron todo tipo de construcciones: palacios rectangulares y alargados, templos, juegos de pelota, calzadas (sacbeob) que un\u00edan las ciudades principales, fortificaciones, ba\u00f1os de vapor (temascal).<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #ff6600\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: small\">El principal espect\u00e1culo de los mayas era un juego de pelota, parecido al f\u00fatbol. Seg\u00fan algunos investigadores, los jugadores eran los prisioneros de guerra y se decapitaba a los que perd\u00edan. Pero en realidad era m\u00e1s que un simple juego. Era un ceremonial religioso que representaba el paso de los astros y el sol (representado por la pelota), que es fuente de vida.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600\"><span style=\"font-family: 'Times New Roman', serif\"><span style=\"font-size: small\"><a href=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/144223172_451838c6ba.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-195\" src=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/144223172_451838c6ba-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/carocalchichen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-196\" src=\"https:\/\/blogs.ua.es\/losmayas\/files\/2012\/03\/carocalchichen-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dise\u00f1o urbano maya podr\u00eda describirse f\u00e1cilmente como la divisi\u00f3n del espacio en grandes monumentos y calzadas. En este caso, las plazas p\u00fablicas al aire libre eran los lugares de reuni\u00f3n para las personas, as\u00ed como el enfoque del dise\u00f1o urbano, mientras que el espacio interior era completamente secundario. S\u00f3lo en el Poscl\u00e1sico Tard\u00edo las [&hellip;]<\/p>\n","protected":false},"author":2204,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4690],"tags":[],"class_list":["post-191","post","type-post","status-publish","format-standard","hentry","category-geografia"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/posts\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/users\/2204"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/posts\/191\/revisions"}],"predecessor-version":[{"id":201,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/posts\/191\/revisions\/201"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/categories?post=191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/losmayas\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}