{"id":83,"date":"2009-03-14T11:44:48","date_gmt":"2009-03-14T10:44:48","guid":{"rendered":"https:\/\/blogs.ua.es\/maquiavelo\/?p=83"},"modified":"2009-03-17T13:52:22","modified_gmt":"2009-03-17T12:52:22","slug":"la-mandragora","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/maquiavelo\/2009\/03\/14\/la-mandragora\/","title":{"rendered":"La Mandr\u00e1gora"},"content":{"rendered":"<p>Comedia en prosa de cinco actos, con pr\u00f3logo en verso, 1518-20, representada en Florencia y Roma.<\/p>\n<div>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Messer Nicia, tan rico como c\u00e1ndiddo, para tener un hijo, no duda en entregar a su mujer a los brazos del primer llegado, convencido de que este morir\u00e1 a causa de una poci\u00f3n de mandr\u00e1gora que ha bebido su esposa.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comedia en prosa de cinco actos, con pr\u00f3logo en verso, 1518-20, representada en Florencia y Roma. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Messer Nicia, tan rico como c\u00e1ndiddo, para tener un hijo, no duda en entregar a su mujer a los brazos del primer llegado, convencido de que este morir\u00e1 a causa de una poci\u00f3n de mandr\u00e1gora que ha bebido [&hellip;]<\/p>\n","protected":false},"author":1149,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[321],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","hentry","category-videos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/users\/1149"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":111,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/posts\/83\/revisions\/111"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/maquiavelo\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}