{"id":1432,"date":"2021-01-15T08:36:08","date_gmt":"2021-01-15T07:36:08","guid":{"rendered":"https:\/\/blogs.ua.es\/matesfacil\/?p=1432"},"modified":"2021-09-22T08:45:48","modified_gmt":"2021-09-22T07:45:48","slug":"distancia-entre-puntos-del-plano","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/matesfacil\/2021\/01\/15\/distancia-entre-puntos-del-plano\/","title":{"rendered":"Distancia entre puntos del plano"},"content":{"rendered":"<p>La distancia entre dos puntos <em>(a, b)<\/em> y <em>(x, y)<\/em> del plano se define como<\/p>\n<p><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\"><img decoding=\"async\" class=\"aligncenter\" title=\"formula para calcular la distancia entre dos puntos del plano real\" src=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/T4b.png\" alt=\"Explicamos c\u00f3mo calcular la distancia entre dos puntos de la recta, del plano y del espacio reales Con ejemplos, representaciones y problemas resueltos. Matem\u00e1ticas. ESO. \u00c1lgebra b\u00e1sica.\" \/><\/a><\/p>\n<p>Como la distancia es una ra\u00edz cuadrada, es siempre mayor o igual que 0.<\/p>\n<p><strong>Ejemplo 1: l<\/strong>a distancia entre los puntos (2, 2) y (2, 4) es 2:<\/p>\n<p align=\"center\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\"><img decoding=\"async\" title=\"calculamos la distancia entre los puntos (2, 2) y (2, 4), que es 2\" src=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/T5.png\" alt=\"Explicamos c\u00f3mo calcular la distancia entre dos puntos de la recta, del plano y del espacio reales Con ejemplos, representaciones y problemas resueltos. Matem\u00e1ticas. ESO. \u00c1lgebra b\u00e1sica.\" \/><\/a><\/p>\n<p>Representaci\u00f3n:<\/p>\n<p align=\"center\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\"><img decoding=\"async\" title=\"representaci\u00f3n de la distancia entre los puntos (2,2) y (2,4) del plano\" src=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/img1.png\" alt=\"Explicamos c\u00f3mo calcular la distancia entre dos puntos de la recta, del plano y del espacio reales Con ejemplos, representaciones y problemas resueltos. Matem\u00e1ticas. ESO. \u00c1lgebra b\u00e1sica.\" \/><\/a><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Ejemplo 2:<\/strong> la distancia entre los puntos (-2, 6) y (-5, 2) es 5:<\/p>\n<p align=\"center\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\"><img decoding=\"async\" title=\"calculamos la distancia entre los puntos (-2, 6) y (-5, 2), que es 5\" src=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/P3-1.png\" alt=\"Explicamos c\u00f3mo calcular la distancia entre dos puntos de la recta, del plano y del espacio reales Con ejemplos, representaciones y problemas resueltos. Matem\u00e1ticas. ESO. \u00c1lgebra b\u00e1sica.\" \/><\/a><\/p>\n<p>Representaci\u00f3n:<\/p>\n<p align=\"center\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\"><img decoding=\"async\" title=\"representaci\u00f3n de la distancia entre los puntos (-2,6) y (-5,2) del plano real\" src=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/P3g.png\" alt=\"Explicamos c\u00f3mo calcular la distancia entre dos puntos de la recta, del plano y del espacio reales Con ejemplos, representaciones y problemas resueltos. Matem\u00e1ticas. ESO. \u00c1lgebra b\u00e1sica.\" \/><\/a><\/p>\n<p style=\"text-align: left\" align=\"center\">M\u00e1s ejemplos y temas relacionados:<\/p>\n<ul>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/distancia-puntos\/distancia-puntos-formula-calcular-ejemplos-problemas-resueltos.html\">Distancia entre dos puntos<\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/equidistancia\/puntos-equidistantes-vertices-circunferencia-ejemplos-cuadrado-triangulo.html\">Puntos equidistantes<\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/recta-puntos\/recta-une-dos-puntos-alineados-ejemplos-problemas-resueltos.html\">Recta entre dos puntos<\/a><\/li>\n<li><a href=\"https:\/\/www.problemasyecuaciones.com\/trigonometria\/trigonometria-problemas-resueltos-seno-coseno-tangente-angulo-calcular-ejemplos.html\">Problemas de trigonometr\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/index.html\">Pol\u00edgonos<\/a><\/li>\n<li><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/area\/circulo\/calcular-area-perimetro-circunferencia-circulo-calculadora-problemas.html\">\u00c1rea del c\u00edrculo<\/a><\/li>\n<li><a href=\"https:\/\/www.problemasyecuaciones.com\/geometria2D\/area\/triangulo\/area-perimetro-triangulo-formula-Heron-semiperimetro-ejemplos-problemas-resueltos.html\">\u00c1rea del tri\u00e1ngulo<\/a><\/li>\n<li><a href=\"https:\/\/www.problemasyecuaciones.com\/Pitagoras\/problemas-resueltos-teorema-pitagoras-tringulo-rectangulo-secundaria.html\">Teorema de Pit\u00e1goras<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La distancia entre dos puntos (a, b) y (x, y) del plano se define como Como la distancia es una ra\u00edz cuadrada, es siempre mayor o igual que 0. Ejemplo 1: la distancia entre los puntos (2, 2) y (2, 4) es 2: Representaci\u00f3n: Ejemplo 2: la distancia entre los puntos (-2, 6) y (-5, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.ua.es\/matesfacil\/2021\/01\/15\/distancia-entre-puntos-del-plano\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Distancia entre puntos del plano&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4324,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2262,676],"tags":[685245,566385,486556,1743253],"class_list":["post-1432","post","type-post","status-publish","format-standard","hentry","category-geometria","category-sin-categoria","tag-distancia","tag-formula","tag-plano","tag-punto"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/posts\/1432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/users\/4324"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/comments?post=1432"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/posts\/1432\/revisions"}],"predecessor-version":[{"id":1439,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/posts\/1432\/revisions\/1439"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/media?parent=1432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/categories?post=1432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/matesfacil\/wp-json\/wp\/v2\/tags?post=1432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}