{"id":202786,"count":2,"description":"","link":"https:\/\/blogs.ua.es\/miguelhernandez\/category\/pelicula-documental\/","name":"pel\u00edcula\/ documental","slug":"pelicula-documental","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/miguelhernandez\/wp-json\/wp\/v2\/categories\/202786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/miguelhernandez\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.ua.es\/miguelhernandez\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/miguelhernandez\/wp-json\/wp\/v2\/posts?categories=202786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}