{"id":344,"date":"2009-01-07T01:45:51","date_gmt":"2009-01-07T00:45:51","guid":{"rendered":"https:\/\/blogs.ua.es\/miguelon\/?p=344"},"modified":"2009-01-07T02:42:40","modified_gmt":"2009-01-07T01:42:40","slug":"no-hay-forma-de-meter-twitter-en-este-blog","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/miguelon\/2009\/01\/no-hay-forma-de-meter-twitter-en-este-blog\/","title":{"rendered":"No hay forma de meter Twitter en este blog"},"content":{"rendered":"<p>El plugin de Twitter que la UA ha instalado s\u00f3lo me funciona para enviar un mensaje cuando he escrito un post. El resto de opciones no funcionan. Twitter me deja poner un objeto flash chulo, pero no hay manera de meterlo aqu\u00ed. En fin, qu\u00e9 le vamos a hacer, alg\u00fan d\u00eda solucionar\u00e1n esto.<\/p>\n<p>Editado: Os cuento todo lo que he probado (para que nadie repita).<\/p>\n<ol>\n<li>He estado usando el widget de Twitter instalado en el WordPress de la UA. S\u00ed que manda un mensaje a Twitter cuando escribo una entrada aqu\u00ed, pero no refleja en el widget mi estado actual.<\/li>\n<li>Bueno, pues como Twitter tiene una cosa que son los bagdes (justo para a\u00f1adir un objeto a tu blog), pues nada, a introducirlo. Tienen uno flash muy chulo (dejar\u00eda de usar Twitterrific), cojo el c\u00f3digo y lo meto en un widget de texto. No hay tu t\u00eda, parece que tienen activada alguna opci\u00f3n que filtra el HTML y me borra el c\u00f3digo proporcionado por Twitter. Busco con Google alguna opci\u00f3n para solucionarlo, pruebo algunas y nada. Bien, probar\u00e9 con la versi\u00f3n html del bagdet. Tampoco. Vaya tela.<\/li>\n<li>Bueno, como WordPress tiene un widget RSS, pues cojo la direcci\u00f3n RSS de mi Twitter y a funcionar. Vaya tela, tampoco funciona. Me dice que no encuentra ning\u00fan RSS en la direcci\u00f3n: <a href=\"http:\/\/twitter.com\/statuses\/friends_timeline\/16664655.rss\">http:\/\/twitter.com\/statuses\/friends_timeline\/16664655.rss<\/a> Espera, claro que me dice que no, como que ese RSS es privado. Simplemente sustituir friends por user y a funcionar. No queda tan bonito como el badget de Twitter, pero qu\u00e9 le vamos a hacer.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>El plugin de Twitter que la UA ha instalado s\u00f3lo me funciona para enviar un mensaje cuando he escrito un post. El resto de opciones no funcionan. Twitter me deja poner un objeto flash chulo, pero no hay manera de &hellip; <a href=\"https:\/\/blogs.ua.es\/miguelon\/2009\/01\/no-hay-forma-de-meter-twitter-en-este-blog\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":342,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[372],"tags":[4031],"class_list":["post-344","post","type-post","status-publish","format-standard","hentry","category-pensamientos","tag-twitter"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/posts\/344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/users\/342"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/comments?post=344"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/posts\/344\/revisions"}],"predecessor-version":[{"id":348,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/posts\/344\/revisions\/348"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/media?parent=344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/categories?post=344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/miguelon\/wp-json\/wp\/v2\/tags?post=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}