{"id":1151,"date":"2023-03-22T12:59:33","date_gmt":"2023-03-22T12:59:33","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=1151"},"modified":"2025-08-04T09:32:06","modified_gmt":"2025-08-04T09:32:06","slug":"milagros-pelegrin-banuls","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/03\/22\/milagros-pelegrin-banuls\/","title":{"rendered":"Milagros Pelegr\u00edn Ba\u00f1uls"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Milagros Pelegr\u00edn fue una militante ilicitana de Uni\u00f3n Republicana y presidenta de la Agrupaci\u00f3n de Mujeres Antifascistas de Elche, una o<\/span><span style=\"font-weight: 400\">rganizaci\u00f3n creada en 1936 e impulsada por el Partido Comunista, pero con participaci\u00f3n de mujeres de diferentes ideolog\u00edas de izquierda.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En Uni\u00f3n Republicana, consigui\u00f3 ser secretaria del partido en Elche, puesto desde el cual promovi\u00f3 la confecci\u00f3n de ropa para llevar a los combatientes en el frente durante la Guerra Civil. En relaci\u00f3n con ello, en septiembre de 1936, junto a otras militantes republicanas como Matilde Iborra y Antonia Castellano, parti\u00f3 a Madrid para proporcionar miles de prendas de abrigo al Batall\u00f3n Mart\u00ednez Barrio.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1153 aligncenter\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/PELEGRIN-BANULS-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/PELEGRIN-BANULS-210x300.jpg 210w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/PELEGRIN-BANULS-718x1024.jpg 718w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/PELEGRIN-BANULS-768x1095.jpg 768w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/PELEGRIN-BANULS.jpg 1039w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><em><span style=\"font-weight: 400\">Propaganda de Uni\u00f3n Republicana pidiendo participaci\u00f3n para el Batall\u00f3n Mart\u00ednez Barrio.<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400\">Tambi\u00e9n colabor\u00f3, desde el <\/span><span style=\"font-weight: 400\">22 de junio de 1938 hasta el 10 de agosto\u00a0del mismo a\u00f1o<\/span><span style=\"font-weight: 400\">, en el gobierno de Elche como consejera municipal de su ayuntamiento, en los departamentos de Plazas y Mercados y Beneficencia y Sanidad, cargo que compagin\u00f3 con el de cocinera en el Hospital Municipal de Elche. Quiso acceder al puesto de inspectora de enfermeras del hospital, pero no lo consigui\u00f3.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cuando la guerra acab\u00f3, Milagros Pelegr\u00edn permaneci\u00f3 presa durante un mes y aunque no lleg\u00f3 a ser castigada, desde ese momento y hasta su fallecimiento, dej\u00f3 de tener actuaci\u00f3n pol\u00edtica.\u00a0<\/span><\/p>\n<p><strong>Fuentes y bibliograf\u00eda:<\/strong><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Ors Montenegro, M. (2010). Pelegr\u00edn Ba\u00f1uls, Milagros. <\/span><i><span style=\"font-weight: 400\">Memoria Digital de Elche<\/span><\/i><span style=\"font-weight: 400\">. Universidad Miguel Hern\u00e1ndez (Elche). Disponible en:<\/span> <a href=\"https:\/\/www.elche.me\/biografia\/pelegrin-banuls-milagros\"><span style=\"font-weight: 400\">https:\/\/www.elche.me\/biografia\/pelegrin-banuls-milagros<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">Ors Montenegro, Miguel (2008).\u00a0<\/span><i><span style=\"font-weight: 400\">Elche, una ciudad en guerra, 1936-1939.\u00a0<\/span><\/i><span style=\"font-weight: 400\">Elche: Ali i Truc.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Pelegr\u00edn Ba\u00f1uls, Milagros. <\/span><i><span style=\"font-weight: 400\">Archivo represaliados en Alicante.<\/span><\/i><span style=\"font-weight: 400\"> Disponible en: https:\/\/apss.veu.ua.es\/archivo_represaliados\/records\/14618<\/span><\/li>\n<\/ul>\n<p><strong>Autor\u00eda:<\/strong> Desir\u00e9e Mart\u00ednez S\u00e1nchez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milagros Pelegr\u00edn fue una militante ilicitana de Uni\u00f3n Republicana y presidenta de la Agrupaci\u00f3n de Mujeres Antifascistas de Elche, una organizaci\u00f3n creada en 1936 e impulsada por el Partido Comunista, pero con participaci\u00f3n de mujeres de diferentes ideolog\u00edas de izquierda. En Uni\u00f3n Republicana, consigui\u00f3 ser secretaria del partido en Elche, puesto desde el cual promovi\u00f3 &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/03\/22\/milagros-pelegrin-banuls\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Milagros Pelegr\u00edn Ba\u00f1uls<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4555,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4337],"tags":[87595],"class_list":["post-1151","post","type-post","status-publish","format-standard","hentry","category-elx","tag-republicana"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4555"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":1984,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1151\/revisions\/1984"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}