{"id":1177,"date":"2023-03-22T13:44:19","date_gmt":"2023-03-22T13:44:19","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=1177"},"modified":"2025-08-04T09:27:18","modified_gmt":"2025-08-04T09:27:18","slug":"josefa-soriano-beltran","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/03\/22\/josefa-soriano-beltran\/","title":{"rendered":"Josefa Soriano Beltr\u00e1n"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1178 aligncenter\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN1-200x300.jpg\" alt=\"\" width=\"300\" height=\"450\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN1-200x300.jpg 200w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN1.jpg 632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><em><span style=\"font-weight: 400\">Fuente: Revista Festa 2014<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400\">Afiliada a la rama juvenil de la CNT, a las Juventudes Libertarias JLL y a la organizaci\u00f3n Mujeres Libres, Josefa Soriano Beltr\u00e1n fue la segunda mujer que ocup\u00f3 un cargo pol\u00edtico en el ayuntamiento de Petrer como consejera en el a\u00f1o 1938.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nacida en Yecla el a\u00f1o 1911, fruto del matrimonio entre Ram\u00f3n Soriano Alarc\u00f3n y \u00c1ngela Beltr\u00e1n de la Fuente, se traslad\u00f3 durante los a\u00f1os treinta a Petrer junto a su familia. Desde joven, comenz\u00f3 a trabajar como aparadora en una de las f\u00e1bricas m\u00e1s importantes del pueblo, Calzados Luvi.<\/span><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1179 aligncenter\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN2.jpg\" alt=\"\" width=\"499\" height=\"345\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN2.jpg 990w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN2-300x208.jpg 300w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN2-768x531.jpg 768w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><em><span style=\"font-weight: 400\">Secci\u00f3n de aparado de la f\u00e1brica Luvi en Petrer. Fuente: Petreraldia.com<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400\">Durante la Guerra Civil, Soriano fue elegida para formar parte del consejo de control de la f\u00e1brica en la que trabajaba y se afili\u00f3 a Mujeres Libres, asistiendo al Pleno Regional de Mujeres Libres en mayo de 1938 en Valencia, donde se trataron temas como la liberaci\u00f3n de la mujer, la educaci\u00f3n sexual, el aborto y el divorcio\u2026 Tambi\u00e9n, como integrante de las JJLL, particip\u00f3 activamente en la creaci\u00f3n de escuelas y bibliotecas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">El 9 de octubre de 1938 se convirti\u00f3 en la segunda mujer en ocupar el cargo de consejera municipal, solo antes ocupado por su hermana Mar\u00eda Soriano Beltr\u00e1n.<\/span><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1183\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN3-666x1024.jpg\" alt=\"\" width=\"325\" height=\"500\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN3-666x1024.jpg 666w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN3-195x300.jpg 195w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN3-768x1181.jpg 768w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/03\/JOSEFA-SORIANO-BELTRAN3.jpg 871w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><em><span style=\"font-weight: 400\">\u00a0Fuente: Revista Festa 2014<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400\">Con la guerra llegando a su fin y la inminente victoria del ej\u00e9rcito franquista, muchas personas comenzaron a huir al exilio. A finales de marzo de 1939 Josefa se encontraba en Valencia junto a su marido.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ambos llegaron a Alicante el 29 de marzo y esperaron la llegada de barcos que nunca se presentaron. Unos d\u00edas despu\u00e9s, Soriano fue detenida y llevada a un cine cines en Alicante que se habilit\u00f3 como c\u00e1rcel. Fue acusada de estar afiliada a la CNT y a las JJLL, ser consejera del ayuntamiento y formar parte del comit\u00e9 de la f\u00e1brica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por todo ello fue condenada a 12 a\u00f1os de prisi\u00f3n en el consejo de guerra de Elda el 20 de octubre de 1939. En 1943, a los 4 a\u00f1os, consigui\u00f3 salir de la c\u00e1rcel, pero fue condenada a destierro en Castell\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al acabar el destierro se traslad\u00f3 a vivir a Villena. All\u00ed, fue madre de tres hijos y se dedic\u00f3 al cuidado de su familia, sus padres y su casa, y no volvi\u00f3 a participar en pol\u00edtica durante el resto de su vida.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Josefa Soriano Beltr\u00e1n muri\u00f3 el 7 de agosto de 1997, con 86 a\u00f1os.<\/span><\/p>\n<p><strong>Fuentes y bibliograf\u00eda:\u00a0<\/strong><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Navarro Poveda, B. y Tendero Fern\u00e1ndez, F. (2014). &#8220;1938: Mar\u00eda y Josefa Soriano Beltr\u00e1n, dos mujeres para la historia de Petrer&#8221;. <\/span><i><span style=\"font-weight: 400\">Revista Festa<\/span><\/i><span style=\"font-weight: 400\">. Ayuntamiento de Petrer. Disponible e<\/span><span style=\"font-weight: 400\">n:<\/span><a href=\"https:\/\/www.valledeelda.com\/hemeroteca\/bibliopetrer\/5087-2014.html\"> <span style=\"font-weight: 400\">https:\/\/www.valledeelda.com\/hemeroteca\/bibliopetrer\/5087-2014.html<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">Soriano Beltr\u00e1n, Josefa. <\/span><i><span style=\"font-weight: 400\">Archivo represaliados en Alicante<\/span><\/i><span style=\"font-weight: 400\">. Disponible en:<\/span><a href=\"https:\/\/apps.veu.ua.es\/archivo_represaliados\/records\/10098\"> <span style=\"font-weight: 400\">https:\/\/apps.veu.ua.es\/archivo_represaliados\/records\/10098<\/span><\/a><\/li>\n<\/ul>\n<p><strong>Autor\u00eda:<\/strong> Desir\u00e9e Mart\u00ednez S\u00e1nchez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: Revista Festa 2014 Afiliada a la rama juvenil de la CNT, a las Juventudes Libertarias JLL y a la organizaci\u00f3n Mujeres Libres, Josefa Soriano Beltr\u00e1n fue la segunda mujer que ocup\u00f3 un cargo pol\u00edtico en el ayuntamiento de Petrer como consejera en el a\u00f1o 1938. Nacida en Yecla el a\u00f1o 1911, fruto del matrimonio &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/03\/22\/josefa-soriano-beltran\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Josefa Soriano Beltr\u00e1n<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4555,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3228],"tags":[374885,2369662],"class_list":["post-1177","post","type-post","status-publish","format-standard","hentry","category-petrer","tag-anarquista","tag-concejala"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4555"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"predecessor-version":[{"id":1980,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1177\/revisions\/1980"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}