{"id":1255,"date":"2023-04-23T09:50:29","date_gmt":"2023-04-23T09:50:29","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=1255"},"modified":"2025-08-04T09:14:24","modified_gmt":"2025-08-04T09:14:24","slug":"fete-federacion-espanola-de-trabajadores-de-la-ensenanza","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/04\/23\/fete-federacion-espanola-de-trabajadores-de-la-ensenanza\/","title":{"rendered":"FETE (Federaci\u00f3n Espa\u00f1ola de Trabajadores de la Ense\u00f1anza)"},"content":{"rendered":"<p>La Federaci\u00f3n Espa\u00f1ola de Trabajadores de la Ense\u00f1anza (FETE) fue la agrupaci\u00f3n de la Uni\u00f3n General de Trabajadores (UGT) de docentes.<\/p>\n<p>El asociacionismo de docentes en Espa\u00f1a fue creciendo en importancia a lo largo de los primeros treinta a\u00f1os del siglo XX, cuando la escuela pas\u00f3 a depender del Estado y el personal del magisterio se convirti\u00f3 en funcionario. Estas asociaciones buscaban un reformismo cultural y social, as\u00ed como planteaban reivindicaciones econ\u00f3micas y laborales del magisterio. Las primeras agrupaciones integraban generalmente s\u00f3lo a docentes de una localidad o partido judicial a causa de las p\u00e9simas condiciones laborales y econ\u00f3micas que soportaban maestras y maestros. A partir de 1912, se formaron la Asociaci\u00f3n General de Maestros (vinculada a la UGT en 1919), la Uni\u00f3n General de Maestros y la Liga de Maestros Rurales.<\/p>\n<p>En abril de 1931 se cre\u00f3 la FETE, a partir de la Asociaci\u00f3n General de Maestros. En ella se afiliaron no s\u00f3lo maestros y maestras socialistas sino tambi\u00e9n republicanos y republicanas de distintas corrientes. Durante la II Rep\u00fablica los sindicatos de docentes tuvieron unos objetivos administrativos y econ\u00f3micos comunes: la equiparaci\u00f3n salarial con otros funcionarios, organizar actividades para los docentes\u2026<\/p>\n<p>Desde el comienzo de la Guerra Civil, todo el profesorado tuvo que afiliarse a un sindicato para pasar la depuraci\u00f3n republicana y cobrar las n\u00f3minas. Tanto FETE como CNT colaboraron con el Ministerio de Instrucci\u00f3n P\u00fabica para elaborar el Plan de Estudios para la Escuela Primaria de 1937 y presionaron para conseguir una subida de salario a los docentes dada la carest\u00eda de los productos b\u00e1sicos. Tambi\u00e9n ambos sindicatos organizaron campa\u00f1as educativas en el frente y colonias escolares en la retaguardia.<\/p>\n<p>Por otra parte, a pesar de la guerra, continuaron algunas actividades de formaci\u00f3n permanente. Organizado por la FETE se celebr\u00f3 en Novelda, a primeros de junio de 1937, una Semana Pedag\u00f3gica y otra en Alcoy al mes siguiente.<\/p>\n<p>Las maestras de la provincia de Alicante no fueron muy proclives a la afiliaci\u00f3n sindical. Solo tenemos noticia de la integraci\u00f3n de 21 maestras en FETE, 14 en UGT, 4 en CNT y 2 estudiantes en la FUE. El n\u00famero de maestros afiliados era mayor, pero tampoco muy elevado: 79 en total, en su mayor\u00eda tambi\u00e9n a FETE.<\/p>\n<p>Las maestras con alguna responsabilidad en un sindicato eran escasas. Tuvieron cargos en FETE: Mar\u00eda Mart\u00ednez M\u00e1s, que fue vicepresidenta de FETE en Callosa D&#8217;Ensarri\u00e1 y Mar\u00eda Sell\u00e9s Berenguer, que fue fundadora del sindicato en Alicante. Por lo dicho anteriormente se deduce que ni siquiera dentro del magisterio las mujeres alcanzaron las mismas cotas de representaci\u00f3n ni de autoridad sindical durante la II Rep\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Autor\u00eda:<\/strong> Isabel Dom\u00e9nech Jim\u00e9nez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n Espa\u00f1ola de Trabajadores de la Ense\u00f1anza (FETE) fue la agrupaci\u00f3n de la Uni\u00f3n General de Trabajadores (UGT) de docentes. El asociacionismo de docentes en Espa\u00f1a fue creciendo en importancia a lo largo de los primeros treinta a\u00f1os del siglo XX, cuando la escuela pas\u00f3 a depender del Estado y el personal del magisterio &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/04\/23\/fete-federacion-espanola-de-trabajadores-de-la-ensenanza\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">FETE (Federaci\u00f3n Espa\u00f1ola de Trabajadores de la Ense\u00f1anza)<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4506,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[180,2369682],"tags":[182599,101521],"class_list":["post-1255","post","type-post","status-publish","format-standard","hentry","category-alicante","category-callosa-densarria","tag-sindicato","tag-socialista"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4506"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1255\/revisions"}],"predecessor-version":[{"id":1969,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1255\/revisions\/1969"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}