{"id":1362,"date":"2023-06-11T10:28:37","date_gmt":"2023-06-11T10:28:37","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=1362"},"modified":"2025-08-04T09:08:28","modified_gmt":"2025-08-04T09:08:28","slug":"luisa-garcia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/06\/11\/luisa-garcia\/","title":{"rendered":"Luisa Garc\u00eda"},"content":{"rendered":"<p>Luisa Garc\u00eda, vecina de Alcoy, perteneci\u00f3 a la Federaci\u00f3n Local de Juventudes Libertarias de Alicante, participando de manera activa en el movimiento anarquista durante la d\u00e9cada de 1930. Durante estos a\u00f1os, intervino en actos p\u00fablicos de esta organizaci\u00f3n, y dedic\u00f3 buena parte de su labor pol\u00edtica a la recopilaci\u00f3n de reivindicaciones feministas, en pro de la libertad de acci\u00f3n de las mujeres.<\/p>\n<p>Uno de los actos en los que la participaci\u00f3n de esta mujer dej\u00f3 huella en la prensa se relata en el diario <em>Vida nueva<\/em>, publicado por la CNT y la AIT -en el ejemplar del 17 de febrero de 1928-. El titular principal, \u2018Todo por la Guerra\u2019, se dedica en este n\u00famero al \u00a0Congreso de las Juventudes Libertarias, en cuya clausura (celebrada apenas 5 d\u00edas antes de la publicaci\u00f3n, el domingo) tom\u00f3 parte Luisa Garc\u00eda, que intervino como delegada. En el resumen de su discurso, se apunta el deseo de la autora por dedicar el congreso a los \u201c<em>hermanos ca\u00eddos en la lucha y a los compa\u00f1eros que trabajan por lograr una sociedad justa<\/em>\u201d, y la necesidad de incorporar a las mujeres al movimiento libertario.<\/p>\n<p>Junto a ello, Luisa Garc\u00eda se dedic\u00f3 a la publicaci\u00f3n de art\u00edculos de prensa en diarios de corte anarquista como <em>Tierra y Libertad<\/em> -editado en Barcelona-, en los que recogi\u00f3 reivindicaciones pol\u00edticas que compart\u00eda con otras mujeres obreras, relacionadas, por ejemplo, con la abolici\u00f3n de la pena de muerte. En el n\u00famero 169 de Agosto de 1934, se reproduce el art\u00edculo <em>\u00a1La mujer espa\u00f1ola debe levantarse contra la pena de muerte!<\/em>, en el que la autora hace una cr\u00edtica al gobierno de la Rep\u00fablica por consentir la continuidad de la pena de muerte, pr\u00e1ctica que condena por considerarla cruel e ineficaz para acabar con la delincuencia. En su lugar, Luisa Garc\u00eda apela a la educaci\u00f3n y la cultura como un derecho que debe estar al alcance de toda la poblaci\u00f3n, y a la garant\u00eda de las necesidades b\u00e1sicas de toda la sociedad como verdaderos m\u00e9todos efectivos para lograr este objetivo.<\/p>\n<p><em>\u201cLas mujeres proletarias de Espa\u00f1a juntan sus voces de protesta, (\u2026) y piden que tambi\u00e9n ahora se suprima la pena de muerte. Lo piden por ellas: lo piden por sus hijos, \u00a1por la humanidad!, y lo piden tambi\u00e9n por la honra de esta \u00e9poca que se llama civilizada.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1363 alignnone\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-1-147x300.png\" alt=\"\" width=\"241\" height=\"492\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-1-147x300.png 147w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-1.png 428w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1364 alignnone\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-2-185x300.png\" alt=\"\" width=\"295\" height=\"478\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-2-185x300.png 185w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-2.png 404w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1365 alignnone\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-3-210x300.png\" alt=\"\" width=\"277\" height=\"396\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-3-210x300.png 210w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-3.png 392w\" sizes=\"auto, (max-width: 277px) 100vw, 277px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1366 alignnone\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-4-181x300.png\" alt=\"\" width=\"265\" height=\"439\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-4-181x300.png 181w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2023\/06\/luisa-4.png 397w\" sizes=\"auto, (max-width: 265px) 100vw, 265px\" \/>:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuentes y bibliograf\u00eda:<\/strong><\/p>\n<ul>\n<li>Moreno Seco, M\u00f3nica: Mar\u00eda Nomded\u00e9u. <em>Diccionari Biogr\u00e0fic de Dones<\/em>. Biograf\u00eda n\u00ba 999. Xarxa Vives d\u2019universitats. 2010. Disponible en: <a href=\"https:\/\/dbd.vives.org\/bio.php\">https:\/\/dbd.vives.org\/bio.php<\/a>.<\/li>\n<li><em>Tierra y Libertad. Seminario Anarquista. <\/em>Barcelona. N\u00aa 169. Agosto, 1934.<\/li>\n<li><em>Vida nueva<\/em>. \u00d3rgano de la Federaci\u00f3n Local de Sindicatos \u00danicos de Tarrassa. N\u00ba 414. 17-II-1938.<\/li>\n<\/ul>\n<p><strong>Autor\u00eda<\/strong>: Mar\u00eda Jos\u00e9 G\u00f3mez Meg\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luisa Garc\u00eda, vecina de Alcoy, perteneci\u00f3 a la Federaci\u00f3n Local de Juventudes Libertarias de Alicante, participando de manera activa en el movimiento anarquista durante la d\u00e9cada de 1930. Durante estos a\u00f1os, intervino en actos p\u00fablicos de esta organizaci\u00f3n, y dedic\u00f3 buena parte de su labor pol\u00edtica a la recopilaci\u00f3n de reivindicaciones feministas, en pro de &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2023\/06\/11\/luisa-garcia\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Luisa Garc\u00eda<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4565,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3394],"tags":[374885],"class_list":["post-1362","post","type-post","status-publish","format-standard","hentry","category-alcoy","tag-anarquista"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4565"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=1362"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1362\/revisions"}],"predecessor-version":[{"id":1963,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1362\/revisions\/1963"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=1362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=1362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=1362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}