{"id":1884,"date":"2025-07-25T09:57:10","date_gmt":"2025-07-25T09:57:10","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=1884"},"modified":"2025-08-04T15:56:09","modified_gmt":"2025-08-04T15:56:09","slug":"rosa-garcia-vera","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2025\/07\/25\/rosa-garcia-vera\/","title":{"rendered":"Rosa Garc\u00eda Vera"},"content":{"rendered":"\n<p>Era maestra, con plaza en Daya Vieja desde 1930, y ocup\u00f3 el cargo de alcaldesa de la localidad en 1933.<\/p>\n\n\n\n<p>En esta poblaci\u00f3n, en enero de 1933 tom\u00f3 posesi\u00f3n una comisi\u00f3n gestora que sustituy\u00f3 al anterior ayuntamiento, en cumplimiento de la ley de 30 de diciembre de 1932 sobre el cese de concejales elegidos por el art\u00edculo 29 de la Ley Electoral. Como sucedi\u00f3 en otros lugares, esta circunstancia permiti\u00f3 el acceso de mujeres a puestos de responsabilidad municipal. Rosa Garc\u00eda Vera form\u00f3 parte de dicha comisi\u00f3n gestora y unos d\u00edas despu\u00e9s fue elegida \u201cAlcalde Presidente\u201d (sic). <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"336\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2025\/07\/Libro-actas-Daya-Vieja-31-enero-1933.jpg\" alt=\"\" class=\"wp-image-1885\" \/><figcaption class=\"wp-element-caption\">Fuente: Archivo de la Diputaci\u00f3n de Alicante, Libro de Actas del Ayuntamiento de Daya Vieja, 1930-1933<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ejerci\u00f3 como tal durante unos meses, en que el funcionamiento de la corporaci\u00f3n municipal atendi\u00f3 asuntos de tr\u00e1mite, aprobaci\u00f3n de presupuestos, padrones, pagos ordinarios, etc. Ocup\u00f3 el cargo hasta la sesi\u00f3n del 10 de mayo de 1933, en que tom\u00f3 posesi\u00f3n el nuevo ayuntamiento, elegido por elecci\u00f3n popular de 23 de abril de 1933.<\/p>\n\n\n\n<p>Despu\u00e9s de la Guerra Civil, aunque pas\u00f3 la depuraci\u00f3n, no se le imputaron cargos (Dom\u00e9nech Fern\u00e1ndez, 2016, p. 375).<\/p>\n\n\n\n<p><strong>Fuentes y bibliograf\u00eda:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Archivo de la Diputaci\u00f3n de Alicante, Libro de Actas del Ayuntamiento de Daya Vieja, 1930-1933.<\/li>\n\n\n\n<li>Dom\u00e9nech Fern\u00e1ndez, Isabel (2016). Las maestras de la Guerra Civil y el primer franquismo en la provincia de Alicante, tesis doctoral, Universidad de Alicante.<\/li>\n<\/ul>\n\n\n\n<p><strong>Autor\u00eda:<\/strong> M\u00f3nica Moreno Seco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era maestra, con plaza en Daya Vieja desde 1930, y ocup\u00f3 el cargo de alcaldesa de la localidad en 1933. En esta poblaci\u00f3n, en enero de 1933 tom\u00f3 posesi\u00f3n una comisi\u00f3n gestora que sustituy\u00f3 al anterior ayuntamiento, en cumplimiento de la ley de 30 de diciembre de 1932 sobre el cese de concejales elegidos por &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2025\/07\/25\/rosa-garcia-vera\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Rosa Garc\u00eda Vera<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4506,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2369704],"tags":[2369662,218118],"class_list":["post-1884","post","type-post","status-publish","format-standard","hentry","category-daya-vieja","tag-concejala","tag-maestra"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4506"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=1884"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1884\/revisions"}],"predecessor-version":[{"id":2094,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/1884\/revisions\/2094"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=1884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=1884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=1884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}