{"id":207,"date":"2022-02-21T15:56:44","date_gmt":"2022-02-21T15:56:44","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=207"},"modified":"2025-08-04T16:07:55","modified_gmt":"2025-08-04T16:07:55","slug":"agrupacion-de-mujeres-antifascistas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/02\/21\/agrupacion-de-mujeres-antifascistas\/","title":{"rendered":"Agrupaci\u00f3n de Mujeres Antifascistas"},"content":{"rendered":"<p>Ante el auge del fascismo en Europa, surgieron numerosas organizaciones antifascistas. El origen de la Agrupaci\u00f3n de Mujeres Antifascistas se remonta a iniciativas surgidas en 1934. En julio de ese a\u00f1o, se cre\u00f3 en Madrid <i>Mujeres contra la Guerra y el Fascismo<\/i>, compuesta por republicanas, socialistas y comunistas, quienes lideraron el movimiento. En Alicante, sin embargo, la coordinaci\u00f3n recay\u00f3 en la republicana Manolita Luque, elegida en septiembre del mismo a\u00f1o para para desarrollar esta organizaci\u00f3n (<i>El Luchador<\/i>, 12 de septiembre de 1934). En 1935 m\u00e1s de 500 mujeres alicantinas firmaron un breve manifiesto contra la guerra (<i>El Luchador<\/i>, 3 de octubre de 1935).<\/p>\n<p>A causa de la represi\u00f3n desencadenada tras los hechos de octubre de 1934, Mujeres contra la Guerra y el Fascismo adopt\u00f3 el nombre de <i>Pro Infancia Obrera<\/i>. Esta organizaci\u00f3n desarroll\u00f3 una actividad solidaria, ajustada a los ideales maternales de la feminidad del momento, pero que adquiri\u00f3 un abierto contenido pol\u00edtico: la acogida de ni\u00f1os y ni\u00f1as procedentes de Asturias cuyos progenitores hab\u00edan muerto o estaban en la c\u00e1rcel. Dirigida por Luque, Pro Infancia Obrera coordin\u00f3 la llegada de tres expediciones a Alicante, de 10, 40 y 116 ni\u00f1os y ni\u00f1as respectivamente, que eran recogidos en Madrid, acompa\u00f1ados hasta la capital alicantina y repartidos entre familias de acogida de toda la provincia (<i>El Luchador<\/i>, 3 y 5 de abril de 1935, 20 de junio de 1935 y 15 de enero de 1936).<\/p>\n<figure id=\"attachment_211\" aria-describedby=\"caption-attachment-211\" style=\"width: 295px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-211 \" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/Pro-Infancia.jpg\" alt=\"\" width=\"295\" height=\"651\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/Pro-Infancia.jpg 462w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/Pro-Infancia-136x300.jpg 136w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><figcaption id=\"caption-attachment-211\" class=\"wp-caption-text\">Diario de Alicante, 4-IV-1935<\/figcaption><\/figure>\n<p>La <i>Agrupaci\u00f3n de Mujeres<\/i> <i>Antifascistas<\/i>, heredera de las anteriores organizaciones, despleg\u00f3 una importante actividad durante la Guerra Civil.\u00a0 Con una composici\u00f3n ideol\u00f3gica plural, estuvo dirigida por las comunistas. En la ciudad de Alicante, apareci\u00f3 en Alicante en marzo de 1937 y estuvo coordinada por las comunistas Carmen Caama\u00f1o como secretaria general, Carlota Duarte como secretaria de Agitaci\u00f3n y Propaganda y Paquita S\u00e1nchez, secretaria de Cultura. Tambi\u00e9n hab\u00eda grupos de AMA en Alcoy, Jijona, Elche, Mon\u00f3var y Almorad\u00ed. Junto con otras organizaciones de mujeres, la AMA alicantina promovi\u00f3 un acto en homenaje a la URSS y coordin\u00f3 la tarea de las mujeres que se presentaron voluntarias para trabajar. El 3 de abril de 1937 convoc\u00f3 una manifestaci\u00f3n de mujeres pro-ayuda a Madrid y m\u00e1s adelante recogi\u00f3 fondos para Euskadi, organiz\u00f3 la entrega de materiales para enfermos de los hospitales, la confecci\u00f3n de prendas de abrigo o el reparto de juguetes a ni\u00f1os y ni\u00f1as. Adem\u00e1s, convoc\u00f3 un acto con ocasi\u00f3n del 8 de marzo de 1938.<\/p>\n<figure id=\"attachment_216\" aria-describedby=\"caption-attachment-216\" style=\"width: 333px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-216 size-full\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/AMA.png\" alt=\"\" width=\"333\" height=\"477\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/AMA.png 333w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/02\/AMA-209x300.png 209w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><figcaption id=\"caption-attachment-216\" class=\"wp-caption-text\">Nuestra Bandera, 18-XI-1937<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Fuentes y bibliograf\u00eda:\u00a0<\/strong><\/p>\n<ul>\n<li>Moreno Seco, M\u00f3nica (2021). \u201cManolita Luque Albal\u00e1. Ciudadana, republicana y feminista\u201d, en Helena Establier P\u00e9rez y M\u00f3nica Moreno Seco (eds.), Modernas, luchadoras y pioneras. Mujeres alicantinas de la Edad de Plata, Universidad de Alicante, Alicante, pp. 285-325.<\/li>\n<li>Moreno Seco, M\u00f3nica (2009). \u201cMujeres y Guerra Civil en el Pa\u00eds Valenciano\u201d, en Albert Girona y Javier Navarro (eds.), <i>Fa setanta anys. La Guerra Civil al Pa\u00eds Valenci\u00e0 (1936-1939)<\/i>, PUV, Valencia, 2009, pp. 153-168.<\/li>\n<li>Ram\u00edrez Pacheco, Silvia (1992). \u201cLas organizaciones de mujeres durante la Guerra Civil en Alicante (1936-1939), en Instituto de Cultura Juan Gil-Albert, <i>Ayudas a la investigaci\u00f3n, 1986-87<\/i>, vol. V, Alicante, 1992, pp. 111-123.<\/li>\n<li><em>El Luchador, <\/em>Alicante.<\/li>\n<li><em>Diario de Alicante<\/em>, Alicante.<\/li>\n<li><em>Nuestra Bandera<\/em>, Alicante.<\/li>\n<\/ul>\n<p><strong>Autor\u00eda:<\/strong> M\u00f3nica Moreno Seco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante el auge del fascismo en Europa, surgieron numerosas organizaciones antifascistas. El origen de la Agrupaci\u00f3n de Mujeres Antifascistas se remonta a iniciativas surgidas en 1934. En julio de ese a\u00f1o, se cre\u00f3 en Madrid Mujeres contra la Guerra y el Fascismo, compuesta por republicanas, socialistas y comunistas, quienes lideraron el movimiento. En Alicante, sin &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/02\/21\/agrupacion-de-mujeres-antifascistas\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Agrupaci\u00f3n de Mujeres Antifascistas<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4506,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3394,180,4337],"tags":[],"class_list":["post-207","post","type-post","status-publish","format-standard","hentry","category-alcoy","category-alicante","category-elx"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4506"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":9,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":2106,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/207\/revisions\/2106"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}