{"id":379,"date":"2022-03-05T16:33:43","date_gmt":"2022-03-05T16:33:43","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=379"},"modified":"2025-08-04T15:48:51","modified_gmt":"2025-08-04T15:48:51","slug":"maria-cambrils-sendra","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/03\/05\/maria-cambrils-sendra\/","title":{"rendered":"Maria Cambrils Sendra"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Mar\u00eda Cambrils Sendra naci\u00f3 en El Cabanyal (Valencia) en 1877 y falleci\u00f3 en Pego (Alicante) en 1939. Estuvo afiliada a las Agrupaciones Socialistas de Valencia y Pego. Escritora autodidacta, se convirti\u00f3 en una de las pocas mujeres colaboradoras en la prensa. Escribi\u00f3 art\u00edculos para <\/span><i><span style=\"font-weight: 400\">El Socialista <\/span><\/i><span style=\"font-weight: 400\">(Madrid), El Mundo Obrero (Alicante), <\/span><i><span style=\"font-weight: 400\">La Lucha de Clases <\/span><\/i><span style=\"font-weight: 400\">(Bilbao), <\/span><i><span style=\"font-weight: 400\">Solidaridad <\/span><\/i><span style=\"font-weight: 400\">(Vigo) o <\/span><i><span style=\"font-weight: 400\">El Obrero<\/span><\/i><span style=\"font-weight: 400\"> (Elche), entre otros, y trabaj\u00f3 como redactora en <\/span><i><span style=\"font-weight: 400\">Nueva Aurora<\/span><\/i><span style=\"font-weight: 400\"> (Valencia).\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-381 aligncenter\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/03\/Captura-de-pantalla-2022-03-05-172408-265x300.png\" alt=\"\" width=\"265\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/03\/Captura-de-pantalla-2022-03-05-172408-265x300.png 265w, https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/03\/Captura-de-pantalla-2022-03-05-172408.png 292w\" sizes=\"auto, (max-width: 265px) 100vw, 265px\" \/><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Mar\u00eda Cambrils y su obra Feminismo Socialista (1925)<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">Public\u00f3 en Valencia en 1925 una colecci\u00f3n de sus art\u00edculos, con el nombre de <\/span><i><span style=\"font-weight: 400\">Feminismo socialista<\/span><\/i><span style=\"font-weight: 400\">. Esta obra estaba dedicada al fundador del PSOE Pablo Iglesias, al cual le ten\u00eda mucha admiraci\u00f3n, refiri\u00e9ndose a \u00e9l como <\/span><i><span style=\"font-weight: 400\">\u2018venerable maestro\u2019, <\/span><\/i><span style=\"font-weight: 400\">y estaba prologado por la pol\u00edtica Clara Campoamor<\/span><i><span style=\"font-weight: 400\">. <\/span><\/i><span style=\"font-weight: 400\">Mar\u00eda y Clara no se conocieron nunca, pero exist\u00eda una<\/span> <span style=\"font-weight: 400\">red importante de comunicaci\u00f3n entre las mujeres feministas de la \u00e9poca, y, pese a no ser del mismo partido, se ten\u00edan admiraci\u00f3n la una a la otra.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-382 aligncenter\" src=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/files\/2022\/03\/Captura-de-pantalla-2022-03-05-172516.png\" alt=\"\" width=\"279\" height=\"274\" \/><\/p>\n<p style=\"text-align: center\"><em>&#8220;Feminismo socialista&#8221; por Maria Cambrils. Pr\u00f3logo de la se\u00f1orita Clara Campoamor. Doctora en derecho y abogada del colegio de Madrid&#8221;<\/em><\/p>\n<p><span style=\"font-weight: 400\">Desde la \u00f3ptica del socialismo, Mar\u00eda consider\u00f3 que para alcanzar la igualdad de clases era imprescindible la igualdad de g\u00e9neros; es decir, que no se pod\u00eda ser socialista sin ser feminista. Algunos autores la consideran como una adelantada a su tiempo, lleg\u00f3 incluso a denunciar en sus escritos la violencia dentro del matrimonio.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Enviud\u00f3 muy joven de Jos\u00e9 Mart\u00ednez Dols. M\u00e1s tarde entrar\u00eda dentro de un convento posiblemente, lo cual explicar\u00eda que a pesar de ser hija de una madre analfabeta y que fuera criada en un ambiente obrero de escasa instrucci\u00f3n, Maria pudiera adquirir una cultura importante. Ana Noguera Montagut la califica como una mujer <em>&#8216;dial\u00e9cticamente pol\u00e9mica&#8217;.<\/em> Y desde esa confrontaci\u00f3n, siempre desde el respeto y con un l\u00e9xico muy rico, pudo arrojar con sus escritos un poco de luz a las mujeres del primer tercio del siglo XX.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Comparti\u00f3 su vida con el tambi\u00e9n socialista Jos\u00e9 Alarc\u00f3n Herrero, primero en Valencia, y despu\u00e9s en Pego (Alicante) desde el verano de 1933, pueblo natal de la madre de Mar\u00eda. All\u00ed desarrollaron un papel importante en las reuniones de la Casa del Pueblo, siendo Jos\u00e9 Alarc\u00f3n su presidente. <\/span><span style=\"font-weight: 400\">Tras acabar la Guerra Civil, Jos\u00e9 Alarc\u00f3n fue aprisionado en el Reformatorio de Adultos de Alicante, y Mar\u00eda, muy enferma, se fue a vivir con unos familiares en el<\/span><i><span style=\"font-weight: 400\"> carrer Picadora,<\/span><\/i><span style=\"font-weight: 400\"> donde falleci\u00f3 en 1939, siendo la ubicaci\u00f3n de su enterramiento desconocida hasta la fecha. Jos\u00e9 Alarc\u00f3n fue fusilado en 1940.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">La periodista Rosa Solbes calific\u00f3 a Mar\u00eda Cambrils<\/span> <span style=\"font-weight: 400\">como <\/span><i><span style=\"font-weight: 400\">\u2018la famosa desconocida\u2019.<\/span><\/i><span style=\"font-weight: 400\"> Pese al \u00e9xito de su obra <em>Feminismo socialista<\/em>, Mar\u00eda Cambrils como persona fue durante muchas d\u00e9cadas una aut\u00e9ntica desconocida. <\/span><i><span style=\"font-weight: 400\">S<\/span><\/i><span style=\"font-weight: 400\">e lleg\u00f3 a pensar que incluso podr\u00eda haber sido un hombre quien escribi\u00f3 la obra. <\/span><span style=\"font-weight: 400\">Fue a partir de 1992 cuando la Asociaci\u00f3n Clara Campoamor de Bilbao reedit\u00f3 su obra y, especialmente a partir de 2015, cuando Rosa Solbes, Ana Aguado y J. Miquel Almela publicaron <\/span><i><span style=\"font-weight: 400\">\u201cMar\u00eda Cambrils: el despertar del feminismo socialista. Biograf\u00eda, textos y contextos\u201d , <\/span><\/i><span style=\"font-weight: 400\">cuando Mar\u00eda Cambrils por fin comenz\u00f3 a tener el lugar que le corresponde en la Historia.<\/span><\/p>\n<p><b>Fuentes y bibliograf\u00eda:<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Cambrils Sendra, Mar\u00eda. En:<\/span><i><span style=\"font-weight: 400\"> Fundaci\u00f3n Pablo Iglesias. <\/span><\/i><span style=\"font-weight: 400\">[en l\u00ednea] Consulta: 02 marzo 2022. Disponible en: <\/span><a href=\"https:\/\/fpabloiglesias.es\/entrada-db\/cambrils-sendra-maria\/\"><span style=\"font-weight: 400\">https:\/\/fpabloiglesias.es\/-db\/cambrils-sendra-maria\/<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">\u201cMaria Cambrils Sendra (1877-1939)\u201d. Serie documental \u2018Valentes\u2019 de \u00c0 punt. 20.07.2019. [en l\u00ednea] Consulta: 03 marzo 2022.\u00a0 Disponible en:\u00a0 <\/span><a href=\"https:\/\/www.apuntmedia.es\/programes\/valentes\/temporada-2\/28-07-2019-maria-cambrils-sendra-1877-1939_134_1392660.html\"><span style=\"font-weight: 400\">https:\/\/www.apuntmedia.es\/programes\/valentes\/temporada-2\/28-07-2019-maria-cambrils-sendra-1877-1939_134_1392660.html<\/span><\/a><\/li>\n<li><span style=\"font-weight: 400\">Mar\u00eda Cambrils Sendra. <\/span><i><span style=\"font-weight: 400\">Ateneu Cultural ciutat de Manises<\/span><\/i><span style=\"font-weight: 400\"> [en l\u00ednea] Consulta: 03 marzo 2022. Disponible en: <\/span><a href=\"https:\/\/ateneumanises.com\/es\/maria-cambrils-sendra\/\"><span style=\"font-weight: 400\">https:\/\/ateneumanises.com\/es\/maria-cambrils-sendra\/<\/span><\/a><\/li>\n<li>\u00a0Aguado, A., Almela, J. M., Solbes, R. (ed.) (2015). <em>Mar\u00eda Cambrils: El despertar del feminismo socialista. Biograf\u00eda, textos y contextos (1877-1939).<\/em> Universitat de Val\u00e8ncia.<\/li>\n<\/ul>\n<p><b>Autor\u00eda:<\/b><span style=\"font-weight: 400\"> \u00c1ngela P\u00e9rez Garc\u00eda\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Cambrils Sendra naci\u00f3 en El Cabanyal (Valencia) en 1877 y falleci\u00f3 en Pego (Alicante) en 1939. Estuvo afiliada a las Agrupaciones Socialistas de Valencia y Pego. Escritora autodidacta, se convirti\u00f3 en una de las pocas mujeres colaboradoras en la prensa. Escribi\u00f3 art\u00edculos para El Socialista (Madrid), El Mundo Obrero (Alicante), La Lucha de Clases &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/03\/05\/maria-cambrils-sendra\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Maria Cambrils Sendra<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4515,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7585],"tags":[2108178,72565,101521],"class_list":["post-379","post","type-post","status-publish","format-standard","hentry","category-pego","tag-escritora","tag-feminista","tag-socialista"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4515"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=379"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/379\/revisions"}],"predecessor-version":[{"id":2088,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/379\/revisions\/2088"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}