{"id":519,"date":"2022-03-26T17:56:46","date_gmt":"2022-03-26T17:56:46","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=519"},"modified":"2025-08-04T15:20:47","modified_gmt":"2025-08-04T15:20:47","slug":"marina-ivars-de-bergue","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/03\/26\/marina-ivars-de-bergue\/","title":{"rendered":"Marina Ivars de Bergu\u00e9"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Marina Ivars naci\u00f3 en Navarr\u00e9s (Valencia) el 29 de agosto de 1907. Perteneci\u00f3 a una familia perseguida por el franquismo: su madre Dolores de Bergu\u00e9 denunci\u00f3 en una carta que su familia hab\u00eda sido perseguida, siendo despojados de su casa y posteriormente encarcelados. Dolores de Bergu\u00e9 estuvo tres meses en prisi\u00f3n y su marido diez meses, falleciendo en abril de 1940. Seg\u00fan la madre de Marina Ivars en esa misma carta, su marido falleci\u00f3 <\/span><i><span style=\"font-weight: 400\">\u201ca consecuencia de la persecuci\u00f3n y fatigas sufridas en la c\u00e1rcel\u201d.\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">Durante la Guerra Civil, Marina Ivars se afili\u00f3 al PCE, llegando a ocupar el cargo de secretaria. Adem\u00e1s, fue vocal de Socorro Rojo Internacional (SRI) y\u00a0 perteneci\u00f3 a <\/span><a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/02\/21\/agrupacion-de-mujeres-antifascistas\/\">Mujeres Antifascistas.<\/a> Fue capturada en el puerto de Alicante cuando intentaba huir en los a\u00f1os finales de la guerra.<\/p>\n<p>Fue condenada por el Consejo de guerra a 12 a\u00f1os y un d\u00eda por auxilio a la rebeli\u00f3n, ideas izquierdistas y contraria a la Causa Nacional. Estuvo encarcelada en Barcelona, en el Reformatorio de Alicante y en la c\u00e1rcel de mujeres de Mon\u00f3var. En 1943 fue puesta en libertad condicional, pero fue desterrada a Madrid, donde trabaj\u00f3 como sastre. Fue indultada en 1947 y durante los siguientes a\u00f1os fue arrestada en varias ocasiones para cumplir ingresos inferiores a un mes; una de ellas por intentar sacar una carta clandestinamente.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Fuente<\/b><strong>:<\/strong><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Ivars de Bergu\u00e9, Marina. <\/span><i><span style=\"font-weight: 400\">Archivo represaliados en Alicante<\/span><\/i><span style=\"font-weight: 400\"> [en l\u00ednea] Consulta: 10 marzo 2022. Disponible en: <\/span><a href=\"https:\/\/apps.veu.ua.es\/archivo_represaliados\/records\/23024\"><span style=\"font-weight: 400\">https:\/\/apps.veu.ua.es\/archivo_represaliados\/\/23024<\/span><\/a><\/li>\n<\/ul>\n<p><b>Autor\u00eda: <\/b><span style=\"font-weight: 400\">\u00c1ngela P\u00e9rez Garc\u00eda<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marina Ivars naci\u00f3 en Navarr\u00e9s (Valencia) el 29 de agosto de 1907. Perteneci\u00f3 a una familia perseguida por el franquismo: su madre Dolores de Bergu\u00e9 denunci\u00f3 en una carta que su familia hab\u00eda sido perseguida, siendo despojados de su casa y posteriormente encarcelados. Dolores de Bergu\u00e9 estuvo tres meses en prisi\u00f3n y su marido diez &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/03\/26\/marina-ivars-de-bergue\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Marina Ivars de Bergu\u00e9<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4515,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7585],"tags":[127142],"class_list":["post-519","post","type-post","status-publish","format-standard","hentry","category-pego","tag-comunista"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4515"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/519\/revisions"}],"predecessor-version":[{"id":2068,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/519\/revisions\/2068"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}