{"id":642,"date":"2022-04-04T18:12:54","date_gmt":"2022-04-04T18:12:54","guid":{"rendered":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/?p=642"},"modified":"2025-08-04T11:16:16","modified_gmt":"2025-08-04T11:16:16","slug":"purificacion-solbes-oltra","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/04\/04\/purificacion-solbes-oltra\/","title":{"rendered":"Purificaci\u00f3n Solbes Oltra"},"content":{"rendered":"<p><span style=\"font-weight: 400\">A comienzos de 1926 se crea en la partida rural de Daim\u00e9s (Elche) una Escuela Nacional para ni\u00f1as, al mismo tiempo que en las partidas de La Hoya, Baya Alta, Baya Baja y Matola. En marzo de ese mismo a\u00f1o, Purificaci\u00f3n Solbes Oltra es nombrada como maestra interina en la Escuela Nacional de Daim\u00e9s, con un sueldo anual de 2.000 pesetas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Purificaci\u00f3n Solbes fue vecina de la localidad alicantina de Pego y maestra nacional y propietaria de la escuela graduada de dicha localidad desde 1935. Estuvo afiliada al PSOE (del que fue su vocal) y al sindicato de la UGT, adem\u00e1s de haber sido secretaria del Socorro Rojo Internacional (SRI).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Fue acusada de realizar propaganda socialista, as\u00ed como de poseer una \u201cp\u00e9sima moral y religiosa\u201d. Fue condenada por la Comisi\u00f3n Depuradora de la escuela a traslado forzoso a Mon\u00f3var (Alicante).<\/span><\/p>\n<p><b>Fuentes y bibliograf\u00eda<\/b><strong>:<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Domenech Jim\u00e9nez, Isabel (2016). <\/span><i><span style=\"font-weight: 400\">Las maestras de la Guerra Civil y el primer franquismo en la provincia de Alicante<\/span><\/i><span style=\"font-weight: 400\"> (tesis doctoral, Universidad de Alicante) Repositorio de la Universidad de Alicante (RUA) [en l\u00ednea] Consulta: 03 abril 2022. Disponible en: <\/span><a href=\"http:\/\/rua.ua.es\/dspace\/handle\/10045\/54766\"><span style=\"font-weight: 400\">http:\/\/rua.ua.es\/dspace\/handle\/10045\/54766<\/span><\/a><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">G\u00f3mez Mart\u00ednez, M. R. (2017). \u201c<\/span><i><span style=\"font-weight: 400\">Pobreza y salud p\u00fablica a trav\u00e9s de los discursos period\u00edsticos locales. Elche (1923-1930)\u201d<\/span><\/i><span style=\"font-weight: 400\"> (Tesis doctoral, Universidad de Alicante) [en l\u00ednea] Consulta: 03 abril 2022. Disponible en: <\/span><a href=\"http:\/\/rua.ua.es\/dspace\/handle\/10045\/82152\"><span style=\"font-weight: 400\">http:\/\/rua.ua.es\/dspace\/handle\/10045\/82152<\/span><\/a><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Solbes Oltra, Purificaci\u00f3n. En <\/span><i><span style=\"font-weight: 400\">Archivo represaliados de Alicante<\/span><\/i><span style=\"font-weight: 400\"> (en l\u00ednea) Consulta: 03 abril 2022. Disponible en: <\/span><a href=\"https:\/\/apps.veu.ua.es\/archivo_represaliados\/records\/23181\"><span style=\"font-weight: 400\">https:\/\/apps.veu.ua.es\/archivo_represaliados<\/span><\/a><\/li>\n<\/ul>\n<p><b>Autor\u00eda<\/b><span style=\"font-weight: 400\"><strong>:<\/strong> \u00c1ngela P\u00e9rez Garc\u00eda\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comienzos de 1926 se crea en la partida rural de Daim\u00e9s (Elche) una Escuela Nacional para ni\u00f1as, al mismo tiempo que en las partidas de La Hoya, Baya Alta, Baya Baja y Matola. En marzo de ese mismo a\u00f1o, Purificaci\u00f3n Solbes Oltra es nombrada como maestra interina en la Escuela Nacional de Daim\u00e9s, con &hellip; <a href=\"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/2022\/04\/04\/purificacion-solbes-oltra\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Purificaci\u00f3n Solbes Oltra<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4515,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4337,7585],"tags":[218118,101521],"class_list":["post-642","post","type-post","status-publish","format-standard","hentry","category-elx","category-pego","tag-maestra","tag-socialista"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/users\/4515"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"predecessor-version":[{"id":2058,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/posts\/642\/revisions\/2058"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/mujeresactivistasmodernas\/wp-json\/wp\/v2\/tags?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}