{"id":137,"date":"2012-12-08T16:02:29","date_gmt":"2012-12-08T16:02:29","guid":{"rendered":"https:\/\/blogs.ua.es\/nacionalismo\/?p=137"},"modified":"2012-12-08T16:13:18","modified_gmt":"2012-12-08T16:13:18","slug":"la-formacion-de-suecia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/nacionalismo\/2012\/12\/08\/la-formacion-de-suecia\/","title":{"rendered":"La formaci\u00f3n de Suecia"},"content":{"rendered":"<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/1\/10\/Stockholm_Bloodbath.jpg\" alt=\"\" width=\"377\" height=\"241\" \/>La pen\u00ednsula escandinava es un territorio muy poco poblado, de estructura econ\u00f3mica,\u00a0social\u00a0y pol\u00edtica muy sencilla, y de reciente y\u00a0superficial\u00a0cristianizaci\u00f3n. Desde\u00a0la Uni\u00f3n de Kalmar (1397), Noruega, Suecia y Dinamarca comparten un mismo\u00a0soberano\u00a0hasta principios del siglo XVI, pero se trata de una monarqu\u00eda muy d\u00e9bil:\u00a0sigue\u00a0siendo electiva y la nobleza goza de ampl\u00edsimas prerrogativas, y de una gran autonom\u00eda en Suecia y en Noruega.<\/p>\n<p style=\"text-align: justify\">Cristian II de Dinamarca (1513-1523) aspira a incrementar su poder y a controlar el comercio del B\u00e1ltico por los estrechos del Sund. Las ciudades costeras del Imperio alem\u00e1n, federadas en una <em>hansa<\/em> o liga comercial, no est\u00e1n dispuestas a tolerar algo que\u00a0supondr\u00eda\u00a0su ruina, y apoyan a cualquier brote de disidencia contra el rey. <strong>El brutal sometimiento de la nobleza sueca en 1520 (&lt;&lt;ba\u00f1o de sangre de Estocolmo&gt;&gt;) propicia una reacci\u00f3n nacional y el derrocamiento del monarca.<\/strong> En 1523, la nobleza sueca elige rey a uno de sus miembros, Gustavo Vasa, con lo que Suecia se separa de la Uni\u00f3n. Ese mismo a\u00f1o, la nobleza danesa aprovecha tambi\u00e9n la ocasi\u00f3n, derroca a Cristian II y corona a un noble alem\u00e1n como Federico I.<\/p>\n<p style=\"text-align: justify\">En ambos casos, los nuevos reyes de Suecia y de Dinamarca se\u00a0consolidan\u00a0en el trono gracias a la Reforma protestante. La secularizaci\u00f3n de los bienes\u00a0eclesi\u00e1sticos\u00a0permite a Gustavo I Vasa (1523-1560) comprar el apoyo de la nobleza, que sigue participando en el gobierno desde el Consejo de Estado. Vence adem\u00e1s la resistencia de los cat\u00f3licos, con el obispo de Uppsal al frente, y derrota a los daneses cuando pretenden recobrar el control de Suecia. Y, en 1544, obtiene el reconocimiento de la dieta\u00a0\u2212formada por nobles, eclesi\u00e1sticos, burgues\u00eda y campesinado\u2212\u00a0de que la corona ser\u00e1 hereditaria en su linaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pen\u00ednsula escandinava es un territorio muy poco poblado, de estructura econ\u00f3mica,\u00a0social\u00a0y pol\u00edtica muy sencilla, y de reciente y\u00a0superficial\u00a0cristianizaci\u00f3n. Desde\u00a0la Uni\u00f3n de Kalmar (1397), Noruega, Suecia y Dinamarca comparten un mismo\u00a0soberano\u00a0hasta principios del siglo XVI, pero se trata de una monarqu\u00eda muy d\u00e9bil:\u00a0sigue\u00a0siendo electiva y la nobleza goza de ampl\u00edsimas prerrogativas, y de una gran [&hellip;]<\/p>\n","protected":false},"author":1739,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2088],"tags":[170963,170961,1928,170964,5094,170962],"class_list":["post-137","post","type-post","status-publish","format-standard","hentry","category-religion","tag-cristian-ii","tag-gustavo-vasa","tag-nacionalismo","tag-stockholm-bloodbath","tag-suecia","tag-uppsala"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/posts\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/users\/1739"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":11,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"predecessor-version":[{"id":143,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/posts\/137\/revisions\/143"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/nacionalismo\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}