{"id":119,"date":"2010-04-22T19:45:09","date_gmt":"2010-04-22T19:45:09","guid":{"rendered":"https:\/\/blogs.ua.es\/niccolomachiavelli\/2010\/04\/22\/documental-maquiavelo\/"},"modified":"2010-06-02T08:25:56","modified_gmt":"2010-06-02T08:25:56","slug":"documental-maquiavelo","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/niccolomachiavelli\/2010\/04\/22\/documental-maquiavelo\/","title":{"rendered":"Documental &#8211; Maquiavelo"},"content":{"rendered":"<p>A continuaci\u00f3n a\u00f1ado una serie de enlaces de un documental de Discovery Channel\u00a0 sobre la  figura de <strong>Maquiavelo<\/strong> y su obra de <strong><em>El  Pr\u00edncipe<\/em><\/strong>. La duraci\u00f3n es aproximadamente de 50 minutos.<\/p>\n<p>En la parte final de esta entrada realizar\u00e9 una  cr\u00edtica personal sobre los aspectos que considero m\u00e1s destacables.<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=3WFbWKlkL0U<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=32hUWWEqWiM&#038;feature=related<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=iGJfBA_ypy8&#038;feature=related<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=uI38FEw57GE&#038;feature=related<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=FNiYBDPXoWc&#038;feature=relate<\/p>\n<p style=\"text-align: justify\"><strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Opini\u00f3n personal:<\/strong><\/p>\n<p style=\"text-align: justify\"><strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify\">El documental en s\u00ed del pensamiento de Maquiavelo, me parece algo surrealista y exagerado en su totalidad. Se intenta por parte de los productores una llamada de atenci\u00f3n al espectador con im\u00e1genes que realmente no est\u00e1n en el contexto de la \u00e9poca de Maquiavelo, como las de la Soluci\u00f3n final nazi.<\/p>\n<p style=\"text-align: justify\">Tambi\u00e9n, se realizan unos an\u00e1lisis desorbitados en el aspecto religioso, como los que hace Hanna. H. Gray sobre la cristiandad o no de Maquiavelo.<\/p>\n<p style=\"text-align: justify\">Entiendo que posiblemente est\u00e9 realizado (el documental) para dar una imagen general para la gente que no se haya le\u00eddo la obra, pero deja mucho que explicar y que entender.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s la utilizaci\u00f3n de\u00a0 Henry Kissinger, me parece aberrante, y con\u00a0 la utilizaci\u00f3n de este personaje ya podemos percibir desde que pie pol\u00edtico est\u00e1 realizado dicho documental \u2013 an\u00e1lisis. Bueno, aunque tambi\u00e9n podr\u00edamos pensar que la elecci\u00f3n de dicho personaje no es algo fortuito, porque \u00e9l mismo podr\u00eda encajar en el ideal m\u00e1s famoso de Maquiavelo:<em> El fin justifica los medios <\/em><em>.<\/em> Ya que coomo Secretario de Estado de EE.UU llev\u00f3 a cabo este tipo de ideal, con las m\u00faltiples violaciones de los Derechos Humanos e instigador de genocidios sistem\u00e1ticos de grupos pol\u00edticos.<\/p>\n<p style=\"text-align: justify\">Para terminar, decir que parece que la \u00fanica pol\u00edtica actual comparable con algunos ideales de Maquiavelo sea la de Estados Unidos, como podemos ver en la segunda parte del documental (minuto 8.34): &#8220;Tropas estadounidenses en misi\u00f3n humanitaria\u00b4\u00b4.<\/p>\n<p style=\"text-align: justify\">El documental es una americanada m\u00e1s, con la exaltaci\u00f3n de la patria estadounidense en todo momento,\u00a0 pero he decidido colgarlo para que cada uno de vosotros pod\u00e1is darle una visi\u00f3n y cr\u00edtica personal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n a\u00f1ado una serie de enlaces de un documental de Discovery Channel\u00a0 sobre la figura de Maquiavelo y su obra de El Pr\u00edncipe. La duraci\u00f3n es aproximadamente de 50 minutos. En la parte final de esta entrada realizar\u00e9 una cr\u00edtica personal sobre los aspectos que considero m\u00e1s destacables. http:\/\/www.youtube.com\/watch?v=3WFbWKlkL0U http:\/\/www.youtube.com\/watch?v=32hUWWEqWiM&#038;feature=related http:\/\/www.youtube.com\/watch?v=iGJfBA_ypy8&#038;feature=related http:\/\/www.youtube.com\/watch?v=uI38FEw57GE&#038;feature=related http:\/\/www.youtube.com\/watch?v=FNiYBDPXoWc&#038;feature=relate Opini\u00f3n [&hellip;]<\/p>\n","protected":false},"author":458,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6757,321],"tags":[],"class_list":["post-119","post","type-post","status-publish","format-standard","hentry","category-maquiavelo","category-videos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/users\/458"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":21,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"predecessor-version":[{"id":352,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/posts\/119\/revisions\/352"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/niccolomachiavelli\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}