{"id":22,"date":"2021-09-29T04:27:04","date_gmt":"2021-09-29T04:27:04","guid":{"rendered":"https:\/\/blogs.ua.es\/obispadoorihuela\/?page_id=22"},"modified":"2021-09-29T04:31:42","modified_gmt":"2021-09-29T04:31:42","slug":"09-la-defensa-de-la-ereccion-episcopal-de-1510","status":"publish","type":"page","link":"https:\/\/blogs.ua.es\/obispadoorihuela\/09-la-defensa-de-la-ereccion-episcopal-de-1510\/","title":{"rendered":"09. La defensa de la erecci\u00f3n episcopal de 1510"},"content":{"rendered":"<ol>\n<li><strong> El inicio de la recuperaci\u00f3n oriolana despu\u00e9s de la German\u00eda.<\/strong><\/li>\n<\/ol>\n<p>El 29 de septiembre de 1521, el marqu\u00e9s de los V\u00e9lez decidi\u00f3 dar por concluidas las rapi\u00f1as. Las tropel\u00edas cometidas por los hombres de D. Pedro Fajardo fueron de tal gravedad que han llevado a D. Ricardo Garc\u00eda C\u00e1rcel a afirmar que el Saco de Orihuela \u00abha pasado a la historia como una manifestaci\u00f3n ejemplar del salvajismo y de la barbarie humanas\u00bb<sup>1<\/sup>.<\/p>\n<p>Una vez finalizado, D. Pedro Maza, el Almirante de Arag\u00f3n y el marqu\u00e9s de los V\u00e9lez marcharon para reducir Alicante y otros pueblos de la comarca. Entonces, la ciudad de Orihuela qued\u00f3 en paz, y el 11 de octubre el <em>Consell<\/em> pudo reanudar t\u00edmidamente sus actividades<sup>2<\/sup>.<\/p>\n<p>En primer lugar, se encarg\u00f3 de tomar las medidas mas urgentes para mantener el orden y la calidad de vida en la ciudad. Siguiendo este criterio, los ediles realizaron una nueva insaculaci\u00f3n, pues durante el saqueo hab\u00edan desaparecido los sacos de los <em>redolins<\/em>, as\u00ed como diversos libros concejiles. Adem\u00e1s, tuvieron que preocuparse por llenar de trigo el granero municipal, que durante las altercaciones hab\u00eda sido vaciado por completo. Por ello, decidieron enviar comisarios a diversas localidades, y en Elda adquirieron una buena cantidad de grano. No obstante, antes de producirse la entrega del cereal, los vendedores incrementaron su precio y, de ese forma, Orihuela no pudo evitar verse inmersa en un nuevo pleito, que tuvo vistas en las ciudades del Bajo Segura y del Turia.<\/p>\n<p>Por otra parte, un nuevo peligro, si cabe, m\u00e1s temible que el propio Saco, se acerc\u00f3 a Orihuela. La peste se extendi\u00f3 por Elche, y las autoridades oriolanas tuvieron que tomar las estrictas medidas acostumbradas para que la epidemia no penetrase en la ciudad. Finalmente, la infecci\u00f3n no afect\u00f3 a los habitantes de la capital de la Gobernaci\u00f3n, pero s\u00ed dificult\u00f3 a sus oficiales la ya de por s\u00ed ardua tarea de conseguir los alimentos b\u00e1sicos que faltaban en ella<sup>3<\/sup>.<\/p>\n<p>Y el a\u00f1o acab\u00f3 a\u00fan peor, porque los corsarios berberiscos realizaron diversas incursiones por la Vega Baja, secuestrando a algunos trabajadores del campo, y llev\u00e1ndoselos a \u00c1frica para venderlos como esclavos o solicitar por ellos los correspondientes rescates. Por tal motivo, la huerta qued\u00f3 casi desierta<sup>4<\/sup>.<\/p>\n<p>Por \u00faltimo, sobre 1521 cabe se\u00f1alar que el 1 de diciembre falleci\u00f3 Le\u00f3n X, siendo sucedido en el solio pontificio por el cardenal de Tortosa, Adriano VI, el 9 de enero de 1522<sup>5<\/sup>.<\/p>\n<p>El nombramiento del nuevo papa fue acogido con satisfacci\u00f3n por las autoridades civiles y eclesi\u00e1sticas de Orihuela, puesto que el de Utrecht siempre se hab\u00eda mostrado receptivo hacia todas las peticiones que le hab\u00edan realizado cuando ocupaba el cargo de Inquisidor general de la Corona de Arag\u00f3n. Sin embargo, la ca\u00f3tica situaci\u00f3n que se viv\u00eda en la ciudad les impidi\u00f3 elevarle las protestas convenientes sobre la prestaci\u00f3n forzada del juramento de obediencia al cabildo de Cartagena y la il\u00edcita anulaci\u00f3n del obispado, que tuvieron lugar durante el Saco. Este hecho, sumado a su pronta muerte, acaecida el 14 de septiembre de ese mismo a\u00f1o, hicieron que nada pudiesen conseguir de este papa, que, sin duda, les habr\u00eda sido propicio<sup>6<\/sup>.<\/p>\n<p>Por otra parte, si nos fijamos en los acontecimientos m\u00e1s destacables que tuvieron lugar en dicho a\u00f1o 1522, hemos de hacer referencia a las principales consecuencias que se derivaron de la German\u00eda. La represi\u00f3n contra los rebeldes prosigui\u00f3. Se produjo una modificaci\u00f3n temporal del sistema de gobierno, siendo sustituido el tradicional m\u00e9todo insaculatorio por un sistema de nominaci\u00f3n de oficiales. Y hubo problemas con la percepci\u00f3n de los impuestos<sup>7<\/sup>.<\/p>\n<p>Ante el estado de destrucci\u00f3n y ruina en que hab\u00eda quedado la ciudad, el <em>Consell<\/em> busc\u00f3 el apoyo y el consejo de personajes ilustres y eminentes, entre los que cabe citar a D. Fernando de Loazes, quien actu\u00f3 durante alg\u00fan tiempo como asesor municipal.<\/p>\n<p>Al quedar la situaci\u00f3n de la ciudad m\u00e1s o menos normalizada, sus autoridades, pasando por alto las carencias econ\u00f3micas, decidieron enviar a dos embajadores a la corte real con el prop\u00f3sito de volver a ganar la confianza y el favor del emperador, y de hacerle algunas urgent\u00edsimas suplicaciones. De ese modo, a principios de noviembre, el referido Loazes y Lope Ferr\u00e1ndez de Mesa partieron en direcci\u00f3n a Valladolid, adonde arribaron mediado el citado mes.<\/p>\n<p>Gracias a la ayuda del duque de Alba, el d\u00eda 23 pudieron comparecer ante el monarca, y le rogaron que concediese el perd\u00f3n general para los habitantes de Orihuela por su participaci\u00f3n en la German\u00eda; que ordenase el restablecimiento del sistema insaculatorio de elecci\u00f3n de oficios municipales; que nombrase al asesor de la Gobernaci\u00f3n, pues Francisco Alavanya llevaba m\u00e1s siete a\u00f1os ejerciendo tal cargo sin cobrar estipendio alguno; que mandase al marqu\u00e9s de los V\u00e9lez que restituyese la artiller\u00eda y el pend\u00f3n de la ciudad, as\u00ed como los banderines de los nobles; que prohibiese a los murcianos que volviesen a desviar el curso del r\u00edo Segura para provocar inundaciones; y, por \u00faltimo, que siguiese el ejemplo de su abuelo, y se dignase a confirmar todos los privilegios, gracias e indultos concedidos por sus antecesores a Orihuela. Carlos I les pidi\u00f3 que le entregasen un memorial que recogiese todas estas peticiones. Y encomend\u00f3 su estudio al Consejo de Arag\u00f3n<sup>8<\/sup>.<\/p>\n<p>Pese a sus penurias monetarias, pronto los dos embajadores comenzaron a ver fructificar sus gestiones. El \u00faltimo d\u00eda de noviembre, el rey y su madre Juana, atendiendo al \u00faltimo de sus ruegos, firmaron un documento de suma trascendencia para el Pleito del Obispado. En \u00e9l, ratificaron y juraron respetar todas las gracias, inmunidades y franquicias de la ciudad de Orihuela. Con dicho acto, probablemente sin saberlo, el emperador se acababa de comprometer a observar el privilegio concedido por Alfonso el <em>Magn\u00e1nimo<\/em> en Gaeta el 11 de septiembre de 1437, y en adelante, habr\u00eda de procurar conseguir que prosperase el proyecto de creaci\u00f3n del obispado oriolano. Como veremos m\u00e1s adelante, al monarca le import\u00f3 bien poco este compromiso, y actu\u00f3 seg\u00fan sus sentimientos, convicciones e intereses<sup>9<\/sup>.<\/p>\n<p>Durante el mes de diciembre prosiguieron efectuando diligencias ante el Consejo de Arag\u00f3n y ante el propio rey, y consiguieron de Su Majestad que se comprometiese a decretar el perd\u00f3n general para el pueblo de Orihuela y su huerta por los sucesos de la German\u00eda, \u00ab<em>exceptats los capitans, alferis, sindichs e tretze e abolotadors<\/em>\u00bb<sup>10<\/sup>.<\/p>\n<p>A principios de 1523, los oficiales de la ciudad del Bajo Segura le escribieron a Fernando de Loazes que retornase pues ten\u00edan necesidad de que les asesorara en diferentes temas legales<sup>11<\/sup>.<\/p>\n<p>De ese modo, se qued\u00f3 Lope Ferr\u00e1ndez de Mesa como \u00fanico representante de los negocios oriolanos en la corte. Sus gestiones siguieron siendo tan efectivas como las que hab\u00eda realizado junto con Loazes. Y el 24 de enero consigui\u00f3 que Carlos I despachase una orden para el marqu\u00e9s de los V\u00e9lez conmin\u00e1ndole a restituirle al gobernador Maza la artiller\u00eda (\u00ab<em>una culebrina y un sacre y dos falconetes<\/em>\u00bb) y la bandera de la ciudad, y los banderines robados de las sepulturas de los caballeros<sup>12<\/sup>. Un mandato que no fue obedecido por D. Pedro Fajardo.<\/p>\n<p>Seis d\u00edas despu\u00e9s, se hizo p\u00fablica en Orihuela la noticia de que, por fin, el cauce alternativo del Segura hab\u00eda sido cerrado a instancia de algunos habitantes de Murcia, que ten\u00edan posesiones al otro lado de la frontera<sup>13<\/sup>.<\/p>\n<p>A principios de febrero, las autoridades de la ciudad decidieron retomar las diligencias relacionadas con el Pleito del Obispado, y escribieron a dos maestros en Teolog\u00eda, de la orden de Predicadores, que se hallaban en Valladolid, el ya conocido fr. Gaspar Esteve y fr. Juan Hurtado, para que interviniesen ante el monarca con el prop\u00f3sito de que Su Majestad se aviniese a encontrar una soluci\u00f3n pac\u00edfica, un \u00ab<em>asiento de concordia<\/em>\u00bb a las discordias habidas entre oriolanos y murcianos. No obstante, la actuaci\u00f3n de los dos frailes no signific\u00f3 ning\u00fan cambio en la cuesti\u00f3n del obispado, y la posesi\u00f3n dada a la clerec\u00eda murciana sigui\u00f3 teniendo vigor, pese a sus irregularidades<sup>14<\/sup>.<\/p>\n<p>El 8 de mayo de ese mismo a\u00f1o, Carlos I tom\u00f3 una decisi\u00f3n acerca de las reclamaciones de Orihuela en relaci\u00f3n con su sistema de gobierno y sentenci\u00f3 que \u00ab<em>los officios dessa ciudad se provean este anyo por nominacion de personas, y no por suerte o insaculacion<\/em>\u00bb<sup>15<\/sup>.<\/p>\n<p>Por otra parte, viendo que el asunto del obispado estaba totalmente aparcado, durante el mes de julio los mandatarios de la ciudad del Bajo Segura decidieron enviar a un nuevo s\u00edndico a la corte real. El elegido para tal misi\u00f3n fue Vicente Mart\u00ed. Sin embargo, pese a las actividades de tan insigne representante, durante el resto del a\u00f1o no se produjo ninguna novedad, y el cabildo de Cartagena y el provisor episcopal pudieron seguir detentando la autoridad en la di\u00f3cesis<sup>16<\/sup>. Adem\u00e1s, ante la nueva situaci\u00f3n, el vicario general Jaime de Soler decidi\u00f3 dejar de ejercer sus funciones, y comenz\u00f3 para Orihuela un largo per\u00edodo de desgobierno espiritual<sup>17<\/sup>.<\/p>\n<p>A comienzos de 1524, Carlos I decidi\u00f3 dirigirse a Valencia, y los mandatarios oriolanos volvieron a enviarle a Vicente Mart\u00ed, con la intenci\u00f3n de que tratase de convencer al monarca de que permitiese restaurar el sistema insaculatorio de \u00ab<em>extractio dels officis<\/em>\u00bb. Y plenamente conscientes de que era \u00ab<em>mester tenir bons padrins per a poder expedir los negocis<\/em>\u00bb, para facilitarle la misi\u00f3n le entregaron cartas de creencia y recomendaci\u00f3n para diferentes personalidades o instituciones, entre los que cabe destacar a D\u00aa. Germana de Foix -lugarteniente general del Reino de Valencia-, el vicecanciller Jimeno P\u00e9rez de Figuerola, el gobernador Maza, el doctor Dasio, micer Bas, micer Ros, D. Jer\u00f3nimo Vic, Maximiliano Transilvano, el doctor Salvador de Loazes, y, por \u00faltimo, el justicia y los jurados de la referida ciudad del Turia<sup>18<\/sup>.<\/p>\n<p>La embajada de Vicente Mart\u00ed no supuso ninguna modificaci\u00f3n relacionada con el regimiento de la ciudad, pero su estancia en Valencia s\u00ed fue provechosa desde el punto de vista del Pleito del Obispado. El 14 de febrero el s\u00edndico retorn\u00f3 a la ciudad del Bajo Segura. De inmediato, la asamblea municipal se reuni\u00f3, y Mart\u00ed dio relaci\u00f3n a los <em>consellers<\/em> de sus vanos intentos por recuperar el m\u00e9todo insaculatorio. No obstante, para menguar la desilusi\u00f3n generada por sus palabras, les entreg\u00f3 unas cuantas escrituras redactadas por \u00ab<em>solempnes doctors<\/em>\u00bb entre los que estaba micer Rubio -vicario general del arzobispado valentino-, que inclu\u00edan una serie de consejos que deb\u00edan seguir para realizar de un modo acertado las diligencias relacionadas con la referida cuesti\u00f3n episcopal. Y a continuaci\u00f3n, de acuerdo con dichas instrucciones, el citado organismo representativo dio poder al propio Mart\u00ed y a Fernando de Loazes para que pudiesen presentar protestas y disentimientos o interponer apelaciones ante cualquier notario o ante cualquier juez que tuviese competencia sobre la cuesti\u00f3n del obispado<sup>19<\/sup>.<\/p>\n<p>Y dos d\u00edas despu\u00e9s, siguiendo asimismo las recomendaciones de los doctores valencianos, el can\u00f3nigo Pedro Mart\u00ednez -procurador del cap\u00edtulo del Salvador- y los jurados Juan Sanz y Mart\u00edn P\u00e9rez presentaron ante el notario Francisco Olzina en la iglesia de las Santas Justa y Rufina una apelaci\u00f3n, declarando de parte de la Iglesia y la ciudad de Orihuela que sus habitantes estaban absolutamente exentos de la jurisdicci\u00f3n del cabildo de Cartagena, y que no aceptar\u00edan sus mandatos, ni ninguna de las letras citatorias o monitorias que sol\u00edan expedir el provisor del obispado y los jueces de su curia. Y le pidieron al citado notario que especificase en el auto p\u00fablico, que ten\u00edan la intenci\u00f3n de hacer llegar la apelaci\u00f3n hasta la Santa Sede<sup>20<\/sup>.<\/p>\n<p>\u00bfSobre qu\u00e9 bases fundamentaron los oriolanos la teor\u00eda de su exenci\u00f3n jurisdiccional respecto al provisor y el cabildo de la Catedral de Murcia, y su recurso a Roma? La aceptaci\u00f3n del breve revocatorio y de la autoridad eclesi\u00e1stica cartaginense, como sabemos, fue forzada por el marqu\u00e9s de los V\u00e9lez. Y no fue a todas luces irregular porque \u00e9ste obligase a las autoridades civiles y religiosas de Orihuela a prestar la obediencia, sino porque se extralimit\u00f3 en sus atribuciones. En virtud de los decretos reales de auxilio del brazo secular promulgados el 7 y el 10 de abril de 1520, y de las cl\u00e1usulas de los ejecutoriales apost\u00f3licos, el marqu\u00e9s -como representante de dicho poder civil- ten\u00eda facultad para confiscar los bienes muebles e inmuebles de los rebeldes, y para detenerlos y encarcelarlos hasta que quisiesen reconocer la superioridad cartaginense. Pero aprovechando su posici\u00f3n de fuerza, orden\u00f3 al clero y al pueblo de la ciudad que reconociesen la autoridad cartaginense amenaz\u00e1ndoles no s\u00f3lo con el embargo de bienes y la detenci\u00f3n y encarcelaci\u00f3n -penas para cuya imposici\u00f3n estaba habilitado-, sino tambi\u00e9n con el incendio de sus casas e, incluso, con la pena capital. Por este motivo, las autoridades civiles y eclesi\u00e1sticas de Orihuela apelaron ante la Santa Sede y, como comprobaremos algo m\u00e1s adelante, consiguieron hacer que los murcianos llegasen a dudar si la anulaci\u00f3n de la fundaci\u00f3n del obispado y la prestaci\u00f3n de obediencia al cardenal de Santo \u00c1ngel como obispo exclusivamente de Cartagena carec\u00edan de validez.<\/p>\n<p>Durante los meses siguientes, los ediles de la ciudad del Bajo Segura enviaron diferentes embajadas a D\u00aa. Germana de Foix, a fin de tratar de solucionar la cuesti\u00f3n de las elecciones de los oficios municipales, y para lograr de modo definitivo el perd\u00f3n general del pueblo por su participaci\u00f3n en la pasada German\u00eda. Sin embargo, la virreina desoy\u00f3 todas las suplicaciones, y plasm\u00f3 en la decadente realidad oriolana las \u00f3rdenes reales. De este modo, desech\u00f3 el sistema insaculatorio y realiz\u00f3 diferentes designaciones para cubrir los cargos gubernativos vacantes. Y fij\u00f3 una \u00ab<em>compositio dels populars, rebelles e ajermanats<\/em>\u00bb, una compensaci\u00f3n econ\u00f3mica de 5.000 ducados que habr\u00eda de servir para redimir los gastos causados por la revuelta<sup>21<\/sup>.<\/p>\n<ol start=\"2\">\n<li><strong> La problem\u00e1tica con la Inquisici\u00f3n del obispado de Cartagena y el primer breve revocatorio de Clemente VII.<\/strong><\/li>\n<\/ol>\n<p>El Pleito del Obispado volvi\u00f3 a cobrar protagonismo durante los meses de agosto y septiembre de 1524, y lo hizo de una manera ciertamente delicada: bajo la forma de un nuevo conflicto con la Inquisici\u00f3n.<\/p>\n<p>A principios del octavo mes, el licenciado Juan Y\u00e1\u00f1ez, inquisidor del obispado de Cartagena, estando en Elda, les envi\u00f3 al justicia y a los jurados de Orihuela una carta en la que les mostraba su intenci\u00f3n de ir en un futuro inmediato a la citada ciudad a ejercer el santo oficio. Y, ratificando tal prop\u00f3sito, les hizo notificar a los referidos oficiales y al lugarteniente del gobernador un mandato del emperador en el que claramente le ordenaba que se desplazase a la capital de la Gobernaci\u00f3n <em>ultra Sexonam<\/em> para realizar los procesos inquisitoriales que fuesen necesarios para mantener indemne la salud espiritual de sus habitantes.<\/p>\n<p>El <em>Consell<\/em> de la poblaci\u00f3n del Bajo Segura, con el fin de evitar que dicha inminente actuaci\u00f3n pudiese causar perjuicios a la ciudad, comision\u00f3 a los aludidos oficiales para que eligiesen a uno o m\u00e1s procuradores, y les otorgasen poder para interponer escrituras de protesta, disentimiento y apelaci\u00f3n contra todos los actos que hiciese Y\u00e1\u00f1ez en Orihuela como inquisidor del obispado de Cartagena, de modo que nadie pudiese arg\u00fcir que la aceptaci\u00f3n de sus actividades pudiese ser presentada como una prueba de la subordinaci\u00f3n oriolana a la Iglesia murciana. El justicia y los jurados solventaron el encargo de la asamblea municipal nombrando como s\u00edndicos diputados para tal labor a Andr\u00e9s Soler y a Jaime de Vilafranca.<\/p>\n<p>Sin embargo, pese al aviso-amenaza, Juan Y\u00e1\u00f1ez no se present\u00f3 en Orihuela en todo el mes de agosto, y Soler y Vilafranca no tuvieron que actuar<sup>22<\/sup>.<\/p>\n<p>El 2 de septiembre, el inquisidor volvi\u00f3 a escribir a las autoridades civiles de la ciudad del Bajo Segura una nueva misiva. En ella, les notific\u00f3 que ya estaba preparado para ir a Orihuela, con todos sus ministros, a ejercitar el santo oficio que ten\u00eda encomendado, y les pidi\u00f3 que les proporcionasen \u00ab<em>posades e altres coses necesaries<\/em>\u00bb<sup>23<\/sup>.<\/p>\n<p>Ante el nuevo comunicado, el <em>Consell<\/em> se reuni\u00f3 para debatir la cuesti\u00f3n, y como hab\u00eda sucedido el mes anterior, encarg\u00f3 al justicia y a los jurados que se ocupasen de responderle a Y\u00e1\u00f1ez, y de nombrar a uno o dos s\u00edndicos que fuesen a llevarle al licenciado la referida contestaci\u00f3n, y que tuviesen poder, adem\u00e1s, para presentarle protestas o apelaciones en nombre de la ciudad, en el caso de que persistiese en su intenci\u00f3n de menoscabar los intereses oriolanos en el Pleito del Obispado.<\/p>\n<p>Ese mismo d\u00eda, los aludidos oficiales sintetizaron en un bien trabado instrumento los planteamientos de Orihuela en torno al tema de la actuaci\u00f3n del inquisidor. En \u00e9l, le manifestaron que \u00ab<em>la voluntat y deliberacion desta ciudad siempre es estada y es de no ynpedir ne perturbar tan santo hoficio<\/em>\u00bb, que siempre hab\u00edan procurado que la Inquisici\u00f3n actuase en ella con total libertad, y que si el Santo Oficio llevaba mucho tiempo sin ejercer su purificadora misi\u00f3n en la ciudad del Bajo Segura, hab\u00eda sido \u00ab<em>por culpa de los de Murcia, que por sus pasiones no an dado lugar dello<\/em>\u00bb. Y a continuaci\u00f3n, le escribieron que estaban molestos por el hecho de que quisiese personarse en Orihuela para \u00ab<em>exercir el santo hoficio como enquisidor del hobispado de Cartagena y su partido, pretendiendo esta ciudad ser del hobispado de Cartagena<\/em>\u00bb, pues su objetivo fundamental al mantener el Pleito del Obispado, pese a los gastos y a las discordias, era que la Santa Sede reconociese la entidad independiente del obispado de Orihuela, lo que significaba que, por principio, ning\u00fan habitante de dicha ciudad pod\u00eda aceptar las \u00f3rdenes o las intervenciones de los oficiales o los inquisidores del obispado cartaginense.<\/p>\n<p>Acto seguido, le recordaron que en 1520 el difunto Adriano de Utrecht orden\u00f3 al licenciado Juan Ruiz de Salvatierra que mientras permaneciese irresoluto el pleito, los inquisidores de los obispados de Cartagena y Orihuela ejerciesen el santo oficio en esta \u00faltima ciudad con la intitulaci\u00f3n de inquisidores \u00ab<em>del reyno de Murcia y de la guovernacion de Oriuela<\/em>\u00bb, y que Salvatierra hab\u00eda aceptado el mandato del cardenal de Tortosa.<\/p>\n<p>Y continuaron explic\u00e1ndole a Y\u00e1\u00f1ez que si bien hab\u00eda sido nombrado inquisidor del obispado de Cartagena, ello no quer\u00eda decir que lo fuese tambi\u00e9n de la ciudad de Orihuela y su obispado, pues la di\u00f3cesis era \u00ab<em>exenta y separada del hobispado de Cartagena<\/em>\u00bb. Y que si el inquisidor general -que era D. Alonso Manrique, arzobispo de Sevilla- hab\u00eda incluido los territorios de la di\u00f3cesis de Orihuela en los de la de Cartagena hab\u00eda de deberse, sin duda, a que hab\u00eda dispuesto de informaci\u00f3n err\u00f3nea a la hora de tomar la decisi\u00f3n del nombramiento, pues de conocer los detalles del Pleito, al menos, no habr\u00eda despachado la provisi\u00f3n causando tan graves perjuicios a los intereses oriolanos.<\/p>\n<p>Por ello, finalmente, le informaron que ten\u00edan la intenci\u00f3n de enviar a un par de procuradores a la corte para que se entrevistasen con el emperador y con el reverend\u00edsimo prelado sevillano, a fin de exponerles el problema que hab\u00eda surgido. Y concluyeron suplic\u00e1ndole que, antes de cumplir las \u00f3rdenes reales, les hiciese la merced de consultar, asimismo, la cuesti\u00f3n con el propio Manrique, y que aplazase su intervenci\u00f3n hasta que se hiciesen p\u00fablicas las voluntades de Carlos I y del inquisidor general<sup>24<\/sup>.<\/p>\n<p>Una vez terminaron de redactar esta respuesta, el justicia y los jurados encomendaron su entrega a Jaime de Vilafranca y a Berenguer Manresa. No obstante, antes de que partiesen, les dieron tambi\u00e9n una apelaci\u00f3n, para que se la presentasen a Juan Y\u00e1\u00f1ez en el caso de que no aceptase la propuesta. Y con ambos documentos, los dos mensajeros salieron de Orihuela e iniciaron la b\u00fasqueda del inquisidor cartaginense por la geograf\u00eda de la Gobernaci\u00f3n<sup>25<\/sup>.<\/p>\n<p>Dos d\u00edas m\u00e1s tarde, el domingo 4 de septiembre, el <em>Consell<\/em> de la ciudad del Bajo Segura se reuni\u00f3 con el prop\u00f3sito de elegir a los procuradores que ten\u00edan que ir a presentar las alegaciones oriolanas ante Su Majestad y ante el inquisidor mayor. Intervino en primer lugar el justicia quien propuso que los mun\u00edcipes le comisionaran a \u00e9l mismo y a los jurados de la ciudad para que designasen a dos Electos que se encargasen de gestionar cuanto tuviese que ver con el Pleito del Obispado, con facultad delegada por el <em>Consell<\/em> incluso para nombrar s\u00edndicos.<\/p>\n<p>Los jurados manifestaron compartir el parecer del justicia. Pero un <em>conseller<\/em>, Juan Mart\u00ed, manifest\u00f3 una opini\u00f3n diferente. Propuso que fuese el <em>Consell<\/em> directamente quien se encargase de nombrar al procurador que hab\u00eda de ir a comparecer ante el monarca y el arzobispo de Sevilla para conseguir que ninguno de los dos permitiese que le fuese causado perjuicio alguno a la ciudad de Orihuela en la causa de la catedral, y que se le ofreciera a la persona elegida para tal misi\u00f3n el salario que se acostumbraba a dar para tales embajadas, esto es, 11 sueldos diarios. Y dijo que ser\u00eda conveniente que fuese un mismo s\u00edndico quien visitase primero al rey, y despu\u00e9s, conociendo su parecer, al inquisidor general. Al escuchar el parlamento de Juan Mart\u00ed, otros seis <em>consellers<\/em> decidieron mostrarle su apoyo. Los dem\u00e1s ediles, en cambio, se mostraron favorables a las tesis del justicia. No hubo finalmente acuerdo y se pospuso la decisi\u00f3n final para la pr\u00f3xima sesi\u00f3n de la asamblea municipal<sup>26<\/sup>.<\/p>\n<p>El d\u00eda siguiente, Vilafranca y Manresa hallaron, por fin, a Juan Y\u00e1\u00f1ez en la villa de Monforte del Cid y se entrevistaron con \u00e9l. Le comentaron los perjuicios que podr\u00edan derivarse para la ciudad de Orihuela en el caso de que se decidiese a ejercer el santo oficio en ella como \u00ab<em>inquisidor del bisbat de Cartagena<\/em>\u00bb. Y tras platicar un buen rato, proporcion\u00e1ndole m\u00faltiples razones, al no obtener \u00ab<em>cosa que fos en benefici<\/em>\u00bb de dicha ciudad, le leyeron la carta del justicia y los jurados, y viendo que no mudaba de opini\u00f3n, tuvieron que presentarle finalmente la escritura de disentimiento.<\/p>\n<p>Su reverencia respondi\u00f3 a la protesta por escrito, mediante un instrumento firmado por Rodrigo de Calahorra, notario del secreto del Santo Oficio de la Inquisici\u00f3n del obispado de Cartagena. En \u00e9l, Y\u00e1\u00f1ez declar\u00f3 que era \u00ab<em>jutge competent per a poder venir a esta ciutat a exercir lo dit sant ofici<\/em>\u00bb, deneg\u00f3 la apelaci\u00f3n, y les dio a los procuradores un plazo de tres d\u00edas para que le comunicaran las posadas en las que ten\u00edan que estar sus ministros y \u00e9l durante los d\u00edas que permaneciesen en Orihuela.<\/p>\n<p>El mi\u00e9rcoles 7, Vilafranca y Manresa mostraron a los oficiales la respuesta del inquisidor y todos los instrumentos relacionados con la cuesti\u00f3n, y \u00e9stos decidieron que el tema era de importancia suficiente como para que fuese tratado en el <em>Consell<\/em>, de modo que la medida a tomar fuese producto del acuerdo de todos los miembros del \u00f3rgano rector de la universidad oriolana.<\/p>\n<p>Por ello, congregados los <em>consellers<\/em>, el jueves 8, los oficiales entregaron la referida respuesta a Salvador de Loazes, uno de los escribanos de la asamblea, quien procedi\u00f3 a su lectura p\u00fablica. Una vez termin\u00f3 tal tarea, se suscitaron \u00ab<em>diversos vots y parers<\/em>\u00bb. No obstante, la discusi\u00f3n despareci\u00f3 casi de inmediato, pues poco despu\u00e9s, el mismo Loazes ley\u00f3 una carta de Carlos I en la que mandaba claramente a Y\u00e1\u00f1ez que fuese a Orihuela a ejercer el santo oficio. Al escuchar la voluntad del monarca, y sin que se clausurase la sesi\u00f3n, muchos <em>consellers<\/em> se marcharon de la sala, quedando en ella \u00ab<em>molt pochs<\/em>\u00bb. Y el justicia tom\u00f3 la palabra y puso de manifiesto su opini\u00f3n. Dijo que a \u00e9l le parec\u00eda lo m\u00e1s correcto escribir al licenciado que si quer\u00eda realmente ir a ejercer el santo oficio a Orihuela, se personase en ella cuando quisiese, pues \u00e9l le auxiliar\u00eda en la medida de sus posibilidades, \u00ab<em>e la entrada no li sera inpedida<\/em>\u00bb.<\/p>\n<p>Pero aunque hall\u00f3 apoyos a sus tesis, al no haber qu\u00f3rum, decidi\u00f3 posponer la decisi\u00f3n definitiva hasta el domingo 11, d\u00eda que ser\u00eda de nuevo convocado el <em>Consell<\/em>.<\/p>\n<p>El viernes 9, compareci\u00f3 ante el justicia y los jurados Juan Jim\u00e9nez, uno de los <em>consellers<\/em> que se hab\u00eda ausentado al conocer la c\u00e9dula real, para apoyar la propuesta del justicia. Jim\u00e9nez dijo que consideraba lo m\u00e1s apropiado que la ciudad escribiese a Y\u00e1\u00f1ez que viniese a Orihuela cuando quisiese, para no incumplir los mandatos de Su Majestad.<\/p>\n<p>Y ese mismo d\u00eda, el justicia decidi\u00f3 escribir, por medio del escribano Loazes, al licenciado Y\u00e1\u00f1ez su respuesta. Le dijo que, tras ser debatido el asunto en el <em>Consell<\/em> de la ciudad y haber habido diversidad de pareceres, tanto \u00e9l como otros <em>consellers<\/em> cre\u00edan conveniente que, sin perjudicar lo alegado en la anterior apelaci\u00f3n presentada por los representantes de la ciudad, y el Pleito pendiente del Obispado, se personase en Orihuela junto a los dem\u00e1s ministros del Santo Oficio, pues \u00e9l y los dem\u00e1s jurados y <em>consellers<\/em> le permitir\u00edan la entrada en Orihuela e intentar\u00edan favorecerle en su labor. No obstante, aunque no pudo asegurarle posada para todos sus ayudantes, el justicia s\u00ed le ofreci\u00f3 a Y\u00e1\u00f1ez su propia casa<sup>27<\/sup>.<\/p>\n<p>Y\u00e1\u00f1ez recibi\u00f3 la carta del justicia, y el 12 de septiembre contest\u00f3 al primero de los oficiales oriolanos. En su respuesta, le agradeci\u00f3 la delicadeza de haberle ofrecido su casa como residencia, y le comunic\u00f3 que cuando decidiera ir a Orihuela a ejercer el santo oficio, le avisar\u00eda<sup>28<\/sup>. No sabemos realmente el motivo que hizo desistir al licenciado de personarse en la ciudad del Bajo Segura. Probablemente pesasen en su decisi\u00f3n los malos tratos y las vejaciones que hab\u00edan sufrido sus antecesores en el cargo, cuando intentaron ejercer su misi\u00f3n como inquisidores del obispado cartaginense. Por ello, Y\u00e1\u00f1ez quiso proteger su integridad personal logrando una orden de intervenci\u00f3n en Orihuela del arzobispo de Sevilla.<\/p>\n<p>Por otra parte, la suspensi\u00f3n temporal de la intervenci\u00f3n de Y\u00e1\u00f1ez y la falta de acuerdo en el seno del <em>Consell<\/em>, aplazaron tambi\u00e9n el env\u00edo de los procuradores para comunicar la nueva problem\u00e1tica con el rey con el inquisidor general. Y no hubo ninguna novedad al respecto hasta principios de noviembre.<\/p>\n<p>No obstante, antes de hacer alusi\u00f3n a tales acontecimientos, hemos de decir que tras las apelaciones oriolanas contra la prestaci\u00f3n forzada de obediencia, los murcianos no se quedaron con los brazos cruzados. Inmediatamente, le suplicaron a Carlos I que rogase al nuevo papa Clemente VII que confirmase la revocaci\u00f3n de la fundaci\u00f3n del obispado de Orihuela, y que ordenase al clero y al pueblo de esta ciudad que volviesen a reconocer p\u00fablicamente y bajo juramento la superioridad y la autoridad del obispo y el cabildo de Cartagena, para que nadie pudiese albergar duda alguna sobre la situaci\u00f3n del obispado.<\/p>\n<p>El emperador atendi\u00f3 las demandas de los murcianos y, de modo conjunto con ellos, elev\u00f3 la referida petici\u00f3n al sumo pont\u00edfice, quien el 14 de octubre de ese a\u00f1o 1524 quiso satisfacer a los postulantes aprobando la expedici\u00f3n un breve.<\/p>\n<p>Con dicho rescripto, Clemente VII pretendi\u00f3 extirpar de ra\u00edz las controversias, discordias y esc\u00e1ndalos que hab\u00edan rodeado el Pleito desde la misma fundaci\u00f3n del obispado de Orihuela. El pont\u00edfice deseaba evitar que se produjesen nuevos enfrentamientos y, al mismo tiempo, auspiciar la paz y la tranquilidad entre las ciudades de Orihuela y Murcia, y lograr que no tuviesen que afrontar m\u00e1s gastos en cuestiones judiciales.<\/p>\n<p>Por ello, teniendo pleno conocimiento del tema, incluso de las \u00faltimas apelaciones interpuestas por la parte oriolana, extingui\u00f3 el mencionado litigio e impuso silencio perpetuo al cap\u00edtulo del Salvador, al clero y al pueblo de la ciudad del Bajo Segura, absolvi\u00e9ndolos, a su vez, de cualquier censura eclesi\u00e1stica que pudiese haber sido fulminada contra ellos. Y despu\u00e9s, revoc\u00f3 todos los documentos apost\u00f3licos que Julio II o Le\u00f3n X despacharon durante sus respectivos pontificados en beneficio de los intereses episcopales oriolanos, confirm\u00f3 la revocaci\u00f3n de la creaci\u00f3n del obispado, y decret\u00f3 la restituci\u00f3n al obispo y al cabildo de Cartagena de la antigua superioridad y jurisdicci\u00f3n espiritual y temporal que hab\u00edan tenido sobre el cap\u00edtulo del Salvador, el clero y el pueblo de Orihuela antes de las bulas institutorias de Julio II.<\/p>\n<p>Asimismo, nombr\u00f3 ejecutores del nuevo breve revocatorio a Jer\u00f3nimo de Thinutiis y al ministro del monasterio de la Merced de Murcia -fr. Fernando de Rojas-, y les encarg\u00f3 su publicaci\u00f3n solemne de modo que tras su ejecuci\u00f3n el obispo y el cabildo cartaginenses recuperasen plenamente su autoridad y jurisdicci\u00f3n, y tambi\u00e9n los dem\u00e1s derechos y rentas (que desde 1518 ten\u00edan secuestradas los mun\u00edcipes oriolanos). Y para que el cumplimiento de su decreto apost\u00f3lico se hiciese efectivo, el pont\u00edfice les dio poder para imponer a los contradictores las penas eclesi\u00e1sticas y pecuniarias indicadas en el breve revocatorio de Le\u00f3n X. Y en caso de necesidad los facult\u00f3 para acudir al auxilio del brazo secular, pues el tema de la revocaci\u00f3n de la erecci\u00f3n del obispado de Orihuela hab\u00eda de quedar zanjado por completo cuanto antes<sup>29<\/sup>.<\/p>\n<p>Una vez tuvieron en sus manos el rescripto, los procuradores murcianos, como hab\u00edan hecho en 1518, fueron a buscar a Jer\u00f3nimo de Thinutiis para que expidiese el mandato ejecutorial, y ello retras\u00f3 considerablemente la llegada del breve a Espa\u00f1a.<\/p>\n<p>No obstante, antes de que arribase a Espa\u00f1a, tuvo continuidad la pol\u00e9mica con el inquisidor Juan Y\u00e1\u00f1ez, como con anterioridad dejamos apuntado.<\/p>\n<p>El 6 de noviembre, las autoridades civiles de Orihuela recibieron dos cartas, una del inquisidor mayor fechada el 22 de octubre, en la que les mandaba que no perturbasen al referido licenciado en el ejercicio de su santo oficio, y otra de Y\u00e1\u00f1ez en la que les manifestaba que ten\u00eda la intenci\u00f3n inmediata de personarse en la ciudad con el fin anunciado por la misiva del arzobispo de Sevilla.<\/p>\n<p>De inmediato, fue convocado el <em>Consell<\/em> para tomar una decisi\u00f3n al respecto. Sin embargo, como hab\u00eda sucedido en anteriores ocasiones, no hubo unanimidad entre las opiniones de los miembros de la asamblea municipal. Algunos <em>consellers<\/em> (Juan Mart\u00ed, Juan Jim\u00e9nez, Gin\u00e9s Viudes, Alfonso Parera) afirmaron que deb\u00eda permit\u00edrsele la entrada en la ciudad para no desobedecer las \u00f3rdenes de Carlos I y de D. Alonso Manrique. No obstante, la mayor\u00eda estuvo de acuerdo en consultarles antes de dejar a Y\u00e1\u00f1ez que interviniese en Orihuela como inquisidor del obispado de Cartagena. Por ello, finalmente, el <em>Consell<\/em> comision\u00f3 a Jaime Masquefa -se\u00f1or de la Daya- y a Pedro Morrelles para que eligieran al embajador y le proporcionasen la documentaci\u00f3n necesaria. Y para pagar los gastos de la embajada, estableci\u00f3 una talla sobre los vecinos de Orihuela y de las poblaciones de su t\u00e9rmino<sup>30<\/sup>.<\/p>\n<p>Tres d\u00edas despu\u00e9s, el cap\u00edtulo del Salvador y los jurados de la ciudad presentaron una apelaci\u00f3n para la Santa Sede ante los reverendos fr. Juan Ordibel -vicario del monasterio de la Virgen Mar\u00eda, vulgarmente llamada del Socorro, de la orden de Predicadores-, fr. Juan Carmenso -prior del monasterio de San Agust\u00edn- y fr. Pedro Rocamora -comendador del monasterio de la Virgen Mar\u00eda de la Merced-, con la intenci\u00f3n de que ninguno de los actos que efectuase Y\u00e1\u00f1ez como inquisidor del obispado de Cartagena pudiese afectar al Pleito que manten\u00eda Orihuela con Murcia<sup>31<\/sup>.<\/p>\n<p>Y el d\u00eda siguiente, 10 de noviembre, fue convocada de nuevo la asamblea municipal con el fin de que los ediles decidiesen qu\u00e9 diligencias adicionales podr\u00edan realizarse para que la intervenci\u00f3n de Y\u00e1\u00f1ez no causase perjuicio alguno a la citada \u00ab<em>litis pendencia<\/em>\u00bb del Obispado.<\/p>\n<p>En primer lugar, intervinieron Jaime Masquefa y Pedro Morrelles, Electos por el <em>Consell<\/em> para encargarse personalmente de la preparaci\u00f3n de la embajada, para nombrar procurador de la ciudad de Orihuela a Vicente Mart\u00ed, y encomendarle la citada misi\u00f3n de consultar a Carlos I y al inquisidor general.<\/p>\n<p>A continuaci\u00f3n, el <em>Consell<\/em> confirm\u00f3 la nominaci\u00f3n, y dio comisi\u00f3n al justicia y a los jurados para que, junto a los aludidos Electos, fijasen el salario que hab\u00eda de percibir Mart\u00ed en concepto de dietas, poniendo como cantidad m\u00e1xima 15 sueldos diarios, y para que le proveyeran de diferentes escrituras y cartas de recomendaci\u00f3n.<\/p>\n<p>Y despu\u00e9s, la corporaci\u00f3n discuti\u00f3 los argumentos que Mart\u00ed habr\u00eda de presentar al monarca y al arzobispo de Sevilla<sup>32<\/sup>.<\/p>\n<p>Finalmente, hacia el 15 de noviembre, Juan Y\u00e1\u00f1ez decidi\u00f3 no dilatar m\u00e1s su empresa, entr\u00f3 en Orihuela, y se aposent\u00f3 en la casa del justicia en lo criminal. Los oficiales le ofrecieron su apoyo para que pudiese ejercer su santo oficio sin estorbos, aunque para ello le impusieron la condici\u00f3n de que actuase sin causar ning\u00fan perjuicio a la lite pendiente, esto es, intitul\u00e1ndose inquisidor del Reino de Murcia y la gobernaci\u00f3n de Orihuela. Y\u00e1\u00f1ez se neg\u00f3 rotundamente a aceptar tal t\u00edtulo, y persever\u00f3 en su intenci\u00f3n de intervenir en su condici\u00f3n de inquisidor del obispado de Cartagena. Entonces, los mun\u00edcipes le pidieron que les mostrase el poder del inquisidor general que le hab\u00eda facultado para presentarse en Orihuela para llevar a cabo las tareas inquisitoriales con tal intitulaci\u00f3n, pero Y\u00e1\u00f1ez, que estaba claramente en connivencia con el cabildo cartaginense, se neg\u00f3 a ense\u00f1arlo. Ello movi\u00f3 a las autoridades a presentarle ciertas escrituras e instrumentos de protesta y apelaci\u00f3n para evitar los perjuicios de su intervenci\u00f3n. Y la perseverancia de Y\u00e1\u00f1ez fue \u00ab<em>causa de alguns escandols entre el poble de aquesta ciutat<\/em>\u00bb que le impidi\u00f3 el ejercicio del santo oficio, y le forz\u00f3 a volverse a Murcia sin haber podido hacer efectivos sus prop\u00f3sitos<sup>33<\/sup>.<\/p>\n<p>A partir de este momento, el cabildo de Cartagena pod\u00eda contar con una nueva baza favorable a sus intereses: el clero y el pueblo de Orihuela hab\u00edan vuelto a desobedecer mandatos reales y eclesi\u00e1sticos, y por tal actitud no merec\u00edan ni deb\u00edan ser liberados de la tutela espiritual del obispo y el cabildo cartaginenses.<\/p>\n<ol start=\"3\">\n<li><strong> La embajada oriolana a Carlos I y al inquisidor general.<\/strong><\/li>\n<\/ol>\n<p>Tras los sucesos acaecidos a ra\u00edz del intento de intervenci\u00f3n del licenciado Y\u00e1\u00f1ez, las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura no tuvieron m\u00e1s remedio que confiar en que la inminente embajada al rey y al inquisidor general pudiese aclarar los motivos de la oposici\u00f3n a sus respectivas \u00f3rdenes. Por ello, decidieron nombrar a un nuevo s\u00edndico que, por su origen noble, contase con un mayor n\u00famero de contactos en la corte, y el elegido fue D. Juan Maza. La designaci\u00f3n no fue, desde luego, muy afortunada si consideramos que el nominado no hab\u00eda cosechado m\u00e1s que fracasos en las anteriores misiones que la corporaci\u00f3n municipal le hab\u00eda encomendado, y que durante el tiempo de auge de la German\u00eda, fue acusado de negligencia por los s\u00edndicos del pueblo, para escarnio p\u00fablico.<\/p>\n<ol start=\"34\">\n<li>Juan Maza, pasando por alto esta \u00faltima circunstancia, y queriendo servir a la ciudad del Bajo Segura, respondi\u00f3 a la propuesta diciendo que aceptar\u00eda el cargo si D. Pedro Maza estaba de acuerdo y se lo ped\u00eda. Por ello, el 16 de noviembre, el justicia y los jurados de Orihuela le escribieron al gobernador para que solicitase al procurador electo que aceptase el sindicato<sup>34<\/sup>.<\/li>\n<\/ol>\n<p>Sin embargo, D. Pedro se neg\u00f3 a que D. Juan dejara su servicio y le prohibi\u00f3 que se encargara de la labor que le hab\u00edan encomendado las autoridades oriolanas. \u00c9stas, al conocer la voluntad del gobernador, deliberaron de nuevo sobre la procura, y decidieron recurrir al que hab\u00edan designado en primer lugar: Vicente Mart\u00ed. Pero \u00e9ste, que s\u00ed destacaba por sus dotes negociadoras, sinti\u00e9ndose algo molesto por el anterior cambio de planes, se neg\u00f3 a aceptar la misi\u00f3n. Por ello, el 21 de noviembre los ediles volvieron a recurrir a D. Pedro Maza para que, desde su eminente posici\u00f3n, le pidiese a Mart\u00ed que aceptase realizar el viaje en representaci\u00f3n de los intereses de la ciudad<sup>35<\/sup>.<\/p>\n<p>No obstante, pese a la intervenci\u00f3n del gobernador, Mart\u00ed se mantuvo en sus trece y declin\u00f3 su procuraci\u00f3n. As\u00ed, el env\u00edo de la embajada fue retras\u00e1ndose hasta bien entrado el mes de diciembre.<\/p>\n<p>Mientras tanto, los murcianos no perd\u00edan el tiempo, y en Roma, el d\u00eda 6 del citado \u00faltimo mes del a\u00f1o, consiguieron que su viejo conocido Jer\u00f3nimo de Thinutiis les despachase el mandato ejecutorial del breve revocatorio de Clemente VII.<\/p>\n<p>En dicho instrumento, el juez diputado mand\u00f3 al cap\u00edtulo del Salvador, al clero y al pueblo de Orihuela que tras la presentaci\u00f3n del rescripto clementino y de su propio proceso, en un plazo de seis d\u00edas, jurasen obediencia al obispo y al cabildo de Cartagena, reconociesen su superioridad, y les permitiesen el ejercicio de la jurisdicci\u00f3n, sin oponer resistencia ni dificultades, de modo que la situaci\u00f3n en la di\u00f3cesis quedase seg\u00fan era antes de la dismembraci\u00f3n del obispado cartaginense decretada por Julio II. Tambi\u00e9n les orden\u00f3 que les restituyesen \u00edntegramente todas las rentas que les correspond\u00edan -incluidas las <em>Pilas<\/em>-, y que hab\u00edan tenido secuestradas desde 1518. Y que una vez ejecutado el breve revocatorio, no molestasen, inquietasen o perturbasen a los mencionados obispo y cabildo en la posesi\u00f3n de sus derechos.<\/p>\n<p>Asimismo, previendo la existencia de problemas, les advirti\u00f3 que en el caso de que se negasen a aceptar los designios apost\u00f3licos en el referido t\u00e9rmino de seis jornadas, ser\u00edan declarados culpables de desobediencia, y en adelante se les tendr\u00eda por contradictores, rebeldes y obstaculizadores. Y que como tales, volver\u00edan a caer sobre ellos las mismas censuras y penas eclesi\u00e1sticas y pecuniarias en las que incurrieron por oponerse a la ejecuci\u00f3n del breve revocatorio de Le\u00f3n X; y que, adem\u00e1s, por su parte, decretar\u00eda la suspensi\u00f3n <em>a divinis<\/em> sobre los cap\u00edtulos y colegios a los que estuviesen adscritos los delincuentes, y el entredicho sobre las iglesias, monasterios y capillas en los que ejerciesen sus oficios.<\/p>\n<p>Por otro lado, Thinutiis mand\u00f3 a las autoridades eclesi\u00e1sticas de la ciudad de Murcia y la di\u00f3cesis de Cartagena que, en calidad de jueces subdelegados, asistiesen al provisor y al cabildo en la ejecuci\u00f3n de los instrumentos. Y que si a pesar de las admoniciones, los oriolanos se negaban a obtemperar la voluntad apost\u00f3lica, procediesen a la imposici\u00f3n de las penas eclesi\u00e1sticas establecidas.<\/p>\n<p>La fulminaci\u00f3n de dichas censuras hab\u00eda de seguir un proceso temporal. Si pasados los seis d\u00edas fijados tras la notificaci\u00f3n los oriolanos no aceptaban el breve y el proceso, los subdelegados hab\u00edan de declarar p\u00fablicamente a los contradictores por excomulgados. A continuaci\u00f3n, si en las siguientes diez jornadas perseveraban en su negativa, les habr\u00edan de lanzar la maldici\u00f3n eterna. En tercer lugar, si transcurr\u00edan otros diez d\u00edas, y los desobedientes persist\u00edan pertinazmente en su oposici\u00f3n, los subejecutores tendr\u00edan que excomulgar a los familiares y a los sirvientes de los rebeldes. Posteriormente, habr\u00edan de fijar un nuevo plazo de diez d\u00edas para que acatasen las \u00f3rdenes apost\u00f3licas y, en caso contrario, tendr\u00edan que decretar el entredicho. Y, por \u00faltimo, si transcurridos otros diez d\u00edas, se ratificaban en su desobediencia, los subdelegados tendr\u00edan que acudir al auxilio del brazo secular para poner en ejecuci\u00f3n los mandatos pontificios, de modo que las autoridades civiles procediesen a la confiscaci\u00f3n de todos los bienes muebles e inmuebles de los contradictores, y despu\u00e9s a su detenci\u00f3n y encarcelaci\u00f3n hasta que se resignasen a reconocer la obediencia al obispo y el cabildo de Cartagena<sup>36<\/sup>.<\/p>\n<p>Por otra parte, volviendo a Orihuela, el 9 de diciembre los mun\u00edcipes desistieron de tratar de convencer a Vicente Mart\u00ed, y se decidieron a nombrar a un tercer s\u00edndico: el can\u00f3nigo del Salvador, Luis Mart\u00ednez, quien destacaba por su \u00ab<em>abilitat e bona sciencia<\/em>\u00bb<sup>37<\/sup>.<\/p>\n<p>Las instrucciones que le entregaron al nuevo procurador antes de su partida para la corte eran ciertamente amplias. Y tan \u00fatiles como le resultaron a \u00e9l en aquellos momentos, lo son ahora para nosotros a fin de ilustrar toda la problem\u00e1tica surgida en torno a las intervenciones inquisitoriales en Orihuela y, en particular, en relaci\u00f3n con la de Juan Y\u00e1\u00f1ez.<\/p>\n<p>En relaci\u00f3n con su comparecencia ante el inquisidor general, a quien hab\u00eda de ver antes que al rey, le ordenaron al sabio can\u00f3nigo, en primer lugar, que besase sus reverend\u00edsimas manos de parte del cap\u00edtulo del Salvador y de la ciudad de Orihuela, y que le diese una carta que para \u00e9l llevaba.<\/p>\n<p>En ella, los ediles le explicaban que estaba mal informado puesto que \u00ab<em>en esta ciudad son todos tan catolicos y fieles christianos que desean como la vida que los inquisidores husen de su oficio en esta ciudad, y no mande Dios que tengan pensamiento de perturbalo, antes desean favorecelle y acatalle<\/em>\u00bb. Y le dec\u00edan que consideraban un agravio que el licenciado Y\u00e1\u00f1ez hubiese querido actuar como \u00ab<em>inquisidor de Cartagena y governacion de Orihuela<\/em>\u00bb, sin hacer menci\u00f3n \u00ab<em>de nuestra iglesia Cathedral y diocesis de Orihuela<\/em>\u00bb, pues consintiendo que utilizase tal intitulaci\u00f3n, lo que hac\u00edan era \u00ab<em>destruir nuestra iglesia y nuestra justicia<\/em>\u00bb, m\u00e1xime cuando la creaci\u00f3n del obispado oriolano era objeto de litigio judicial en la Curia romana. Y en atenci\u00f3n a tales argumentos, le suplicaban que ordenase a los inquisidores cartaginenses que intervinieran en la ciudad del Bajo Segura con el t\u00edtulo propuesto por el <em>tunc<\/em> cardenal Adriano, pues de esa manera no perjudicaban a ninguna de las partes enfrentadas<sup>38<\/sup>.<\/p>\n<p>Tras la presentaci\u00f3n de la misiva, los mun\u00edcipes le indicaron a Mart\u00ednez que le hablase brevemente al metropolitano hispalense sobre la creaci\u00f3n del obispado de Orihuela, la toma de posesi\u00f3n del obispo Mateo, el nombramiento oficial de Jaime de Soler como vicario general del obispado, y las \u00ab<em>grandissimes diferencies<\/em>\u00bb suscitadas entre las ciudades de Orihuela y Murcia, \u00ab<em>de les quals se son tengudes batalles, mortes moltes gents, robos, cremades moltes cases, de hon esta tan inveterada la enemiga e mala voluntat entre aquelles<\/em>\u00bb, que pod\u00eda hablarse de que ambas poblaciones se ten\u00edan por \u00ab<em>enemichs capitals<\/em>\u00bb.<\/p>\n<p>Acto seguido, Luis Mart\u00ednez habr\u00eda de informar al inquisidor que desde que el cabildo de Cartagena y la ciudad de Murcia iniciaron las reclamaciones contra la fundaci\u00f3n del obispado, los inquisidores del obispado de Cartagena, queriendo perjudicar los intereses oriolanos en la lite, \u00ab<em>per plaure a los de Murcia<\/em>\u00bb, hab\u00edan querido ejercitar su santo oficio en la ciudad del Bajo Segura y la nueva di\u00f3cesis \u00ab<em>intitulantse inquisidors del bisbat de Cartagena<\/em>\u00bb, \u00ab<em>y no del bisbat de Oriola<\/em>\u00bb. Y que en virtud de tal titulaci\u00f3n, hab\u00edan actuado de diferentes maneras en perjuicio de los derechos y la justicia de Orihuela, esto es, llev\u00e1ndose a los presos a la ciudad de Murcia, \u00ab<em>fora del districte e teritori del bisbat de Oriola<\/em>\u00bb, para sentenciarlos all\u00ed ante la presencia del provisor general del obispado cartaginense, y no del vicario general de Orihuela, que era el juez ordinario que deb\u00eda asistir a los actos inquisitoriales; o citando en Murcia a los que hab\u00edan de prestar declaraci\u00f3n sin tener en consideraci\u00f3n que fuesen \u00ab<em>dones de honra, donzelles o persones malaltes<\/em>\u00bb, o importarles el hecho de que tuviesen lugar \u00ab<em>molts inconvenients e mal tractaments de les guardes e desmeros<\/em>\u00bb de Murcia, lleg\u00e1ndose a tal extremo que incluso un hombre llamado Luis Vives, tras ser convocado para prestar testimonio en la citada ciudad, fue esperado a la salida de ella por sus enemigos, quienes lo asesinaron.<\/p>\n<p>Tras esta exposici\u00f3n de agravios, Mart\u00ednez ten\u00eda que explicar que la ciudad de Orihuela se hab\u00eda visto forzada a quejarse en repetidas ocasiones tanto a Carlos I como a los inquisidores generales anteriores, sin la intenci\u00f3n de entorpecer la labor de los inquisidores, pero s\u00ed para evitar que tales actuaciones le supusiesen alg\u00fan perjuicio en el mencionado litigio.<\/p>\n<p>Despu\u00e9s, el s\u00edndico ten\u00eda que informar al arzobispo sevillano que sus predecesores hab\u00edan despachado \u00ab<em>moltes provisions acerca del dit negoci conformes a dret e justicia, repos e tranquilitat de les dos ciutats<\/em>\u00bb, y se las hab\u00eda de mostrar, incidiendo especialmente en la \u00faltima obtenida del cardenal de Tortosa, el difunto papa Adriano, quien -recordemos- orden\u00f3 al inquisidor Juan Ruiz de Salvatierra que cuando tuviese que ejercer el santo oficio en Orihuela o en los territorios de su di\u00f3cesis, lo hiciese como \u00ab<em>inquisidor del regne de Murcia y governacio de Oriola<\/em>\u00bb, de modo que no fuese causado perjuicio en el litigio que manten\u00edan ambas ciudades por la instituci\u00f3n del obispado oriolano. No obstante, Mart\u00ednez hab\u00eda de a\u00f1adir que pese a la orden del insigne inquisidor mayor, el licenciado Salvatierra, que adem\u00e1s era \u00ab<em>canonge de Cartagena<\/em>\u00bb, para complacer a los murcianos, nunca quiso ejercer sus obligaciones inquisitoriales en Orihuela para no llegar a intitularse como su superior hab\u00eda dispuesto. Y que s\u00ed hab\u00eda mandado en su lugar a otro inquisidor, el licenciado Juan Y\u00e1\u00f1ez, a Orihuela, pero de nuevo como \u00ab<em>inquisidor del bisbat de Cartagena<\/em>\u00bb.<\/p>\n<p>Tras estas informaciones, Mart\u00ednez hab\u00eda de darle buena cuenta al inquisidor mayor de la reciente actuaci\u00f3n de Y\u00e1\u00f1ez en la ciudad del Bajo Segura, y de los altercados motivados por ella.<\/p>\n<p>Luego, el can\u00f3nigo tendr\u00eda que explicarle a Alonso Manrique que el hecho de que los inquisidores fueran castellanos les supon\u00eda a los vecinos de Orihuela un \u00ab<em>grandissim dan<\/em>\u00bb, porque \u00ab<em>los castellans no entenen la lengua valenciana<\/em>\u00bb. Le ten\u00eda que se\u00f1alar que los inquisidores, en lugar de realizar los diferentes actos ante el vicario general de Orihuela, que era el juez ordinario, convocaban al provisor de Cartagena, que era \u00ab<em>natural de Burgos<\/em>\u00bb y no entend\u00eda ni una \u00ab<em>paraula valenciana, que es com si li parlaren en arabich<\/em>\u00bb. Y que las declaraciones de los testimonios hab\u00edan de ser recibidas por notarios que tampoco comprend\u00edan el valenciano. Y, por \u00faltimo, respecto a esta cuesti\u00f3n ling\u00fc\u00edstica, ten\u00eda que indicarle que los problemas se hab\u00edan manifestado en toda su tensi\u00f3n durante la visita del licenciado Y\u00e1\u00f1ez, quien, \u00ab<em>no entenent al advocat de la ciutat ni los scrits que li presentaven li mana que li parlas en castella<\/em>\u00bb, y Juan L\u00f3pez le respondi\u00f3 que \u00ab<em>no sabia parlar castella<\/em>\u00bb. Y si el inquisidor y los notarios no comprend\u00edan \u00ab<em>los scrits y parlar del advocat, menys entendran a les dones e persones simples que no tenen ni han tengut pratica en castella<\/em>\u00bb.<\/p>\n<p>A continuaci\u00f3n, los oficiales le indicaron a Mart\u00ednez que hab\u00eda de suplicar al inquisidor mayor que, despu\u00e9s de ver todos los instrumentos hechos ante Y\u00e1\u00f1ez, mandase dar soluci\u00f3n al conflicto, de modo que, sin afectar a la causa pendiente del Obispado, los inquisidores murcianos actuasen en Orihuela y su di\u00f3cesis como \u00ab<em>inquisidors del regne de Murcia y governacio de Oriola<\/em>\u00bb, y que ning\u00fan diocesano tuviese que ir a pleitear a la ciudad de Murcia, ni fuese sentenciado \u00ab<em>segons les leys e furs de Castella, sino segons los furs del regne de Valencia e ciutat e governacio de Oriola<\/em>\u00bb.<\/p>\n<p>Y en el caso de que el inquisidor general no quisiese atender las suplicaciones oriolanas, le indicaron a Mart\u00ednez que acudiese al doctor Artes, quien ten\u00eda pleno conocimiento de la problem\u00e1tica, para interponer apelaciones para el sumo pont\u00edfice. Y si no hallase en la corte al citado Artes, le mandaron que buscase a otro doctor, le mostrase los instrumentos relativos al tema, y presentase de igual forma la protesta, qued\u00e1ndose con una copia del citado documento<sup>39<\/sup>.<\/p>\n<p>Por otra parte, tambi\u00e9n le proporcionaron al s\u00edndico oriolano un buen n\u00famero de instrucciones por las que habr\u00eda de regirse cuando lograse comparecer ante Carlos I.<\/p>\n<p>En primer lugar, Mart\u00ednez hab\u00eda de besar protocolariamente las manos del rey, y entregarle la carta de creencia del cap\u00edtulo del Salvador, el justicia y los jurados de Orihuela que para \u00e9l llevaba<sup>40<\/sup>.<\/p>\n<p>Y tras la presentaci\u00f3n, el can\u00f3nigo tendr\u00eda que hacerle diversas suplicaciones. Le habr\u00eda de solicitar que volviese a otorgar a la ciudad el privilegio del regimiento, restableciendo en ella el sistema insaculatorio suspendido por la designaci\u00f3n de los oficios por D\u00aa. Germana de Foix. Despu\u00e9s, le ten\u00eda que pedir que ordenase al marqu\u00e9s de los V\u00e9lez que devolviese la artiller\u00eda y la bandera de la ciudad, as\u00ed como los banderines de los caballeros robados de las sepulturas ubicadas en las diferentes iglesias oriolanas. Hab\u00eda de suplicar la confirmaci\u00f3n del privilegio de la escriban\u00eda del <em>Consell<\/em> y el establecimiento del salario de micer Francisco Alavanya al frente de la asesor\u00eda de la Gobernaci\u00f3n.<\/p>\n<p>Sobre temas de cariz eclesi\u00e1stico, Luis Mart\u00ednez hab\u00eda de plantear la cuesti\u00f3n surgida con los inquisidores cartaginenses, y le ten\u00eda que solicitar al monarca que mandase al inquisidor mayor que tomase una decisi\u00f3n para cortar los perjuicios que se le hab\u00edan causado a la ciudad de Orihuela en relaci\u00f3n con el pleito pendiente del Obispado.<\/p>\n<p>Tambi\u00e9n le ten\u00eda que rogar que, \u00ab<em>per apartar de vexations, mals e dans<\/em>\u00bb a la ciudad de Orihuela, mandase escribir al santo padre para que diese una soluci\u00f3n judicial definitiva al contencioso suscitado a ra\u00edz de la creaci\u00f3n del obispado oriolano, citando a las partes para que expusiesen sus respectivas alegaciones.<\/p>\n<p>Y por \u00faltimo, sobre la cuesti\u00f3n del desbordamiento del r\u00edo Segura, Mart\u00ednez hab\u00eda de suplicarle al monarca que mandase al cabildo de Cartagena y a las autoridades civiles de la ciudad de Murcia, \u00ab<em>ab imposicio de grans penes<\/em>\u00bb, que no volviesen a amenazar a los vecinos de Orihuela y su t\u00e9rmino con la ruptura del \u00ab<em>quexer del riu<\/em>\u00bb para provocar inundaciones, con motivo del Pleito del Obispado<sup>41<\/sup>.<\/p>\n<p>Ese mismo d\u00eda 9 de diciembre, los oficiales de la ciudad del Bajo Segura le entregaron al procurador un buen n\u00famero de cartas de creencia y recomendaci\u00f3n para diferentes personalidades de la corte. Desde luego, Mart\u00ednez iba a contar con apoyos de cara a lograr traducir en logros las instrucciones que llevaba encomendadas. Los destinatarios de los citados escritos eran tres miembros de la familia Hurtado de Mendoza, D. Diego -conde de M\u00e9lito-, D. Rodrigo -marqu\u00e9s de Zenete- y su hija, la marquesa; el secretario real D. Hugo de Urries -se\u00f1or de Ayerve y comendador de Enguera-; D. Miguel May -canciller del Consejo de Arag\u00f3n-, y otros doctores de dicho organismo como Jacobo de Bononia o el abogado fiscal Felip de Ferreres; el doctor Franc\u00e9s de Artes; el marqu\u00e9s de Elche; el obispo de Segorbe; D. Juan Garc\u00eda, secretario real de la Inquisici\u00f3n; y, por \u00faltimo, el siempre atento duque de Alba<sup>42<\/sup>.<\/p>\n<p>Y a\u00fan antes de que partiese, le encargaron que pasase por la residencia del gobernador Maza, para solicitarle que le entregase nuevas cartas de recomendaci\u00f3n y para comentarle, asimismo, si quer\u00eda que le gestionase alg\u00fan asunto en la corte del emperador<sup>43<\/sup>.<\/p>\n<p>Y, por fin, despu\u00e9s de tantas dudas y tantos preparativos, el d\u00eda siguiente, 10 de diciembre de 1524, el can\u00f3nigo Luis Mart\u00ednez parti\u00f3 de Orihuela con poco m\u00e1s de 50 libras en concepto de adelanto por su salario<sup>44<\/sup>.<\/p>\n<ol start=\"4\">\n<li><strong> La tumultuosa intervenci\u00f3n del inquisidor Juan Y\u00e1\u00f1ez.<\/strong><\/li>\n<\/ol>\n<p>Tras la partida de Luis Mart\u00ednez para la corte, las autoridades civiles de Orihuela se preocuparon por obtener dinero con el que sufragar los gastos que la embajada iba a causar. No obstante, el maltrecho estado de las arcas municipales les forz\u00f3 a buscar alternativas que les permitiesen afrontarlos, pues aun descontando el tercio de dichos dispendios, que como hab\u00eda quedado acordado, correr\u00eda a cargo del cap\u00edtulo del Salvador, no ve\u00edan la forma de lograr todo el efectivo que iba a ser necesario. Por ello, decidieron solicitar ayuda econ\u00f3mica a los mandatarios de poblaciones vecinas como Catral o Callosa de Segura<sup>45<\/sup>.<\/p>\n<p>Por otra parte, con el inicio del a\u00f1o 1525, Juan Y\u00e1\u00f1ez pas\u00f3 de nuevo a la ofensiva. A\u00f1adiendo nuevos perjuicios a los que ya hab\u00eda causado a los intereses episcopales de Orihuela por su intervenci\u00f3n en ella, decidi\u00f3 ejercer el Santo Oficio desde la propia ciudad de Murcia. Y como inquisidor del obispado de Cartagena, el 2 de enero orden\u00f3 a tres vecinos de Orihuela, fr. Pedro Rocamora -comendador del monasterio de la Merced-, el jurado Pedro S\u00e1nchez y el notario Juan L\u00f3pez de Tuesta, bajo pena de excomuni\u00f3n y de 50 ducados de oro, que tres d\u00edas despu\u00e9s de la notificaci\u00f3n de su mandato, compareciesen ante \u00e9l para tratar algunas cuestiones relacionadas con la Inquisici\u00f3n<sup>46<\/sup>. Y encarg\u00f3 a su nuncio, Juan Lorenzo, que les presentase el monitorio.<\/p>\n<p>La orden de Y\u00e1\u00f1ez iba claramente en contra de los privilegios de Orihuela y de los fueros del Reino de Valencia, pues \u00e9stos establec\u00edan que los habitantes de la Gobernaci\u00f3n no hab\u00edan de ir a dirimir cuestiones judiciales fuera de dicha demarcaci\u00f3n territorial <em>ultra Sexonam<\/em>, ya fuera ante jueces seculares o ante jueces eclesi\u00e1sticos.<\/p>\n<p>Unos d\u00edas despu\u00e9s, Juan Lorenzo present\u00f3 el mandato a los tres oriolanos citados, y a ra\u00edz de este acto el conflicto con el inquisidor cartaginense volvi\u00f3 a adquirir una notoria fuerza. Rocamora, S\u00e1nchez y L\u00f3pez se negaron rotundamente a obedecerlo y, en lugar de desplazarse a Murcia, para comparecer ante Y\u00e1\u00f1ez, apelaron contra su orden. El licenciado deneg\u00f3 el recurso, y el 19 de enero volvi\u00f3 a despacharles otro monitorio similar al anterior, amenaz\u00e1ndoles con hacer efectiva la pena de excomuni\u00f3n y con imponerles una multa adicional de otros 50 ducados de oro. La tensi\u00f3n lleg\u00f3 entonces a tal extremo que la notificaci\u00f3n de la provisi\u00f3n se retras\u00f3 casi un mes<sup>47<\/sup>.<\/p>\n<p>Entretanto, a finales de enero, las autoridades civiles y eclesi\u00e1sticas de Orihuela consideraron la necesidad de enviar a Roma a alg\u00fan procurador para que presentase en la Curia una nueva apelaci\u00f3n contra la prestaci\u00f3n forzada de la obediencia al obispo y el cabildo de Cartagena, a fin de que su taciturnidad no fuese interpretada como una aceptaci\u00f3n impl\u00edcita de unos hechos tan irregularmente consumados. Por ello, escribieron al doctor Rubio, vicario general del arzobispado de Valencia, para que les preparase un \u00ab<em>acte de disentiment<\/em>\u00bb. El instrumento lleg\u00f3 a la ciudad del Bajo Segura a principios de febrero<sup>48<\/sup>.<\/p>\n<p>Sin embargo, antes de iniciar los tr\u00e1mites conducentes a su interposici\u00f3n, las referidas autoridades se toparon con un serio inconveniente: la pr\u00e1ctica inexistencia de fondos con los que poder sufragar la embajada a la capital del Orbe Cat\u00f3lico. Por ello, convocaron una reuni\u00f3n del <em>Consell<\/em> para el 5 de febrero, y en ella encontraron una soluci\u00f3n al problema. Encomendaron al grupo de los <em>Electos<\/em> la misi\u00f3n de pedir dinero prestado a las f\u00e1bricas de las iglesias de Orihuela y las poblaciones cercanas, y tambi\u00e9n a los particulares que, pese a la crisis devenida a ra\u00edz de la German\u00eda y su represi\u00f3n, pudiesen aportar alguna cantidad -por \u00ednfima que fuese- a la causa episcopal<sup>49<\/sup>.<\/p>\n<p>De inmediato, los comisionados comenzaron la b\u00fasqueda de prestamistas. Y tres d\u00edas despu\u00e9s, el justicia Pedro Morrelles, el se\u00f1or de Albatera -D. Ram\u00f3n de Rocafull- y Perot P\u00e9rez lograron que la f\u00e1brica de la iglesias del Salvador les proporcionase 100 ducados<sup>50<\/sup>. Sin embargo, poco despu\u00e9s, el reinicio de la pol\u00e9mica con el inquisidor Y\u00e1\u00f1ez les hizo aplazar dicha ocupaci\u00f3n, y tuvieron que centrar toda su atenci\u00f3n en la defensa de los intereses episcopales oriolanos contra los perjuicios que las actuaciones del licenciado iba a causar.<\/p>\n<p>Por otra parte, en Madrid, Luis Mart\u00ednez no consigui\u00f3 ninguna sentencia favorable del inquisidor general. Adem\u00e1s, Carlos I enferm\u00f3 el d\u00eda de Fin de A\u00f1o, y hasta el 10 de febrero no atendi\u00f3 ning\u00fan asunto. No obstante, el embajador oriolano no se qued\u00f3 parado. Habl\u00f3 uno a uno con los doctores del Consejo de Arag\u00f3n, y despu\u00e9s se dirigi\u00f3 a todos ellos conjuntamente para pedirles que recomendaran al monarca que escribiese a Clemente VII para que determinase el Pleito del Obispado \u00ab<em>por justicia<\/em>\u00bb.<\/p>\n<p>Los consejeros le mandaron que redactase un memorial breve porque quer\u00edan consultar el tema con el \u00ab<em>gran chanciller<\/em>\u00bb Gattinara. El can\u00f3nigo acat\u00f3 la orden de los doctores y, finalmente, se dio el visto bueno a la expedici\u00f3n de las cartas conforme a sus reclamaciones. Entonces, los se\u00f1ores del Consejo le entregaron las minutas al escribano de mandamiento Vaguer, quien se hab\u00eda de encargar de su redacci\u00f3n. Y aunque pronto las tuvo preparadas, el monarca no firm\u00f3 documentos intrascendentes a lo largo del mes de febrero, y su despacho tuvo que retrasarse hasta comienzos de marzo<sup>51<\/sup>.<\/p>\n<p>Volviendo a Orihuela, el 17 de febrero, el nuncio Lorenzo consigui\u00f3 presentar a Rocamora, S\u00e1nchez y L\u00f3pez el segundo proceso monitorio de Juan Y\u00e1\u00f1ez. Ninguno de los tres quisieron obedecerlo, de modo que incurrieron en las penas en \u00e9l se\u00f1aladas. Por ello, decidieron apelar de nuevo ante el inquisidor, y \u00e9ste les volvi\u00f3 a denegar el recurso.<\/p>\n<p>El d\u00eda siguiente -18-, una amplia representaci\u00f3n del clero y el pueblo de Orihuela solicit\u00f3 a fr. Juan Ordibel, fr. Juan Carmenso y fr. Nicasio Olivares el visto bueno para remitir a Roma la apelaci\u00f3n contra la prestaci\u00f3n forzada de la obediencia al obispo y al cabildo de Cartagena, que hab\u00eda preparado el doctor Rubio. Los tres venerables religiosos aprobaron la interposici\u00f3n, y el recurso fue mandado a Roma, sin que por ello fuese enviado all\u00ed ning\u00fan nuevo procurador<sup>52<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el procurador fiscal del Santo Oficio en el obispado de Cartagena, el bachiller Juan de Valera, le solicit\u00f3 a Juan Y\u00e1\u00f1ez que acusase a los tres reclamados por la Inquisici\u00f3n de rebeld\u00eda y que procediese a aplicarles las citadas penas. Accediendo a tal demanda, el d\u00eda 25 de ese mismo mes de febrero, el licenciado les despach\u00f3 otro mandato conmin\u00e1ndoles a pagar 100 ducados de oro -50 por cada una de las dos contumacias- a Pedro de Caviedes -receptor de los tributos inquisitoriales en dicho obispado- dentro de un plazo de nueve d\u00edas, que comenzar\u00edan a contarse a partir del momento en el que les fuese notificada su orden. Y, adem\u00e1s, antes de excomulgarlos, les dio tres d\u00edas para que compareciesen ante \u00e9l.<\/p>\n<p>Acto seguido, el nuncio Lorenzo se dirigi\u00f3 a Orihuela para presentarles la \u00faltima provisi\u00f3n inquisitorial, y cuando lo hizo, los afectados le reiteraron que no aceptar\u00edan ninguna disposici\u00f3n de Y\u00e1\u00f1ez mientras no fuese tomada en la ciudad del Bajo Segura y con la intitulaci\u00f3n de inquisidor del obispado de Orihuela. Por ello, poco despu\u00e9s fueron excomulgados<sup>53<\/sup>.<\/p>\n<p>Como apuntamos hace unas cuantas l\u00edneas, a principios de marzo, las gestiones de Luis Mart\u00ednez ante el Consejo de Arag\u00f3n y ante el emperador fructificaron. El d\u00eda 3 de dicho mes, Carlos I accedi\u00f3 a firmar una carta dirigida a Clemente VII en la que, en atenci\u00f3n a \u00ab<em>los scandalos y grandes gastos que se siguen de la dilacion<\/em>\u00bb, le suplicaba que determinase \u00ab<em>con toda presteza y brevedad<\/em>\u00bb el Pleito del Obispado, atendiendo \u00fanicamente a los criterios de la justicia y la equidad<sup>54<\/sup>. Y una semana despu\u00e9s, firm\u00f3 otra misiva dirigida a sus representantes en Roma, su \u00ab<em>vi\u00e7egerente<\/em>\u00bb, el duque de Sessa, y su \u00ab<em>embaxador<\/em>\u00bb, Juan Bartolom\u00e9 de Gattinara, pidi\u00e9ndoles que rogasen al pont\u00edfice que accediese a sus demandas en relaci\u00f3n con la cuesti\u00f3n \u00ab<em>de la erection de la Yglesia de Orihuela<\/em>\u00bb<sup>55<\/sup>.<\/p>\n<p>Mientras tanto, en Orihuela la tensi\u00f3n con Juan Y\u00e1\u00f1ez lleg\u00f3 a su punto culminante.<\/p>\n<p>El 3 de marzo Diego de Alarc\u00f3n, notario y escribano del secreto de la Santa Inquisici\u00f3n del obispado de Cartagena, por orden del pertinaz licenciado, public\u00f3 en la plaza de la ciudad del Bajo Segura una carta-mandato-admonici\u00f3n dirigida al justicia y a los jurados de la misma, a Luis Togores -lugarteniente del gobernador-, a micer Francisco Alavanya -asesor de Maza- y, en general, a toda la poblaci\u00f3n de Orihuela.<\/p>\n<p>En ella, Y\u00e1\u00f1ez les record\u00f3 todos los impedimentos que tanto las autoridades de la ciudad como sus vecinos hab\u00edan opuesto en contra de las actuaciones de los diferentes inquisidores cartaginenses desde 1518. Les concedi\u00f3 un plazo de nueve d\u00edas para que renunciasen a todas las apelaciones interpuestas con anterioridad, y, tambi\u00e9n, para que le dejasen entrar en la ciudad y le permitiesen ejercer en ella su santo oficio. Y les advirti\u00f3 que si transcurr\u00eda el t\u00e9rmino asignado y no cumpl\u00edan ambas condiciones, ser\u00edan acusados de promover la herej\u00eda y, en consecuencia, proceder\u00eda a su p\u00fablica excomuni\u00f3n.<\/p>\n<p>Dos d\u00edas despu\u00e9s, el justicia y los jurados municipales convocaron el <em>Consell<\/em>. En \u00e9l, los ediles decidieron enviar a Murcia a Vicente Mart\u00ed y al se\u00f1or de Cox, Juan Ruiz, con la intenci\u00f3n de que ambos le pidiesen a Y\u00e1\u00f1ez que firmase sus autos como inquisidor del Reino de Murcia y de la Gobernaci\u00f3n de Orihuela, de modo que su labor no tuviese ninguna incidencia sobre el Pleito del Obispado. Y como supon\u00edan que el inquisidor cartaginense se negar\u00eda a aceptar tal propuesta, puesto que lo que deseaba realmente era perjudicarles en la lite, indicaron a los dos s\u00edndicos que le rogasen que aplazase su intervenci\u00f3n en Orihuela hasta que el arzobispo de Sevilla diese un respuesta a la consulta que le hab\u00edan realizado, por medio del can\u00f3nigo Luis Mart\u00ednez, sobre los ejercicios inquisitoriales en la ciudad del Bajo Segura y en las dem\u00e1s localidades de su di\u00f3cesis<sup>56<\/sup>.<\/p>\n<p>El d\u00eda siguiente -6 de marzo-, los oficiales oriolanos se dedicaron a redactar el escrito que hab\u00edan de llevarle Mart\u00ed y Ruiz a Juan Y\u00e1\u00f1ez. En \u00e9l, le aclararon que la intenci\u00f3n de la ciudad no era ni hab\u00eda sido nunca \u00ab<em>impedir el dicho sancto oficio, ni procurar que los heretges no sean castigados<\/em>\u00bb, sino que, al contrario, lo que pretend\u00edan y siempre hab\u00edan deseado era la represi\u00f3n de la herej\u00eda. Le comunicaron que pod\u00eda personarse en Orihuela para ejercer el santo oficio cuando quisiera, pues no le opondr\u00edan \u00ab<em>contraste<\/em>\u00bb alguno. Y tras estas dos frases, fueron al grano. En primer lugar, le explicaron que si en alguna ocasi\u00f3n le hab\u00edan hecho \u00ab<em>algunos requerimientos<\/em>\u00bb, hab\u00eda sido con la intenci\u00f3n de suplicarle que no menoscabase sus derechos en el Pleito del Obispado. Y finalmente, le aclararon que si quer\u00eda intervenir, lo podr\u00eda hacer simplemente intitul\u00e1ndose seg\u00fan hab\u00eda mandado el cardenal Adriano en 1520<sup>57<\/sup>.<\/p>\n<p>El 7 de marzo, Vicente Mart\u00ed y Juan Ruiz, \u00ab<em>com a embaxadors dels magnifichs justicia e jurats e Consell, en nom de tota la universitat e particulars de aquella<\/em>\u00bb, comparecieron ante el licenciado, le presentaron la carta anteriormente descrita, le pidieron que ejercitase su oficio como inquisidor del Reino de Murcia y la Gobernaci\u00f3n de Orihuela, y le rogaron que, en caso contrario, aguardase hasta que se hiciese p\u00fablica la resoluci\u00f3n de D. Alonso Manrique<sup>58<\/sup>.<\/p>\n<p>Ese mismo d\u00eda, por la tarde, Y\u00e1\u00f1ez volvi\u00f3 dar audiencia a los procuradores oriolanos, y les respondi\u00f3 que ten\u00eda orden expresa del inquisidor general de ir a la ciudad rebelde, y de proceder all\u00ed contra los \u00ab<em>inpedidores<\/em>\u00bb. Y que el propio Carlos I hab\u00eda confirmado tal mandato del prelado hispalense. Y obviando por completo la posibilidad de actuar con la intitulaci\u00f3n que le hab\u00edan propuesto, les dijo que de ninguna manera pod\u00eda prorrogar el plazo otorgado \u00ab<em>por tiempo ni dia alguno<\/em>\u00bb, \u00ab<em>que no ay razon alguna que justa se pueda dezir<\/em>\u00bb. Les coment\u00f3 que su actuaci\u00f3n no les pod\u00eda causar ning\u00fan perjuicio en el Pleito del Obispado porque hac\u00eda uso del santo oficio como inquisidor apost\u00f3lico. Les se\u00f1al\u00f3 que el propio cardenal Adriano hab\u00eda revocado hac\u00eda ya tiempo la aludida provisi\u00f3n de 1520. Finaliz\u00f3 su discurso incidiendo en que ten\u00eda que mantener las disposiciones contenidas en su escritura admonitoria, y rechazando cualquier apelaci\u00f3n que pudieren haber interpuesto en contra de ella<sup>59<\/sup>. Y les mand\u00f3 que volviesen a comparecer ante \u00e9l el d\u00eda siguiente.<\/p>\n<p>El 8 de marzo, seg\u00fan les hab\u00eda ordenado, Mart\u00ed y Ruiz se presentaron ante Y\u00e1\u00f1ez, y \u00e9ste les dio una carta, que iba dirigida al justicia, los jurados y el <em>Consell<\/em> de Orihuela, en la que les anunciaba sucintamente su decisi\u00f3n con palabras aparentemente amables pero no carentes de un fino cinismo.<\/p>\n<p>En el escrito, el inquisidor cartaginense les dec\u00eda que querr\u00eda \u00ab<em>como la vida poder hazer<\/em>\u00bb lo que le mandaban, y que hab\u00eda sentido por ello \u00ab<em>harta congoxa<\/em>\u00bb. Se excusaba asever\u00e1ndoles que no hab\u00eda podido \u00ab<em>hazer mas de lo que veran por mi respuesta<\/em>\u00bb. Les suplicaba que le perdonasen y que reflexionasen sobre lo que iban a hacer al conocer su contestaci\u00f3n. Les aseguraba que su \u00ab<em>voluntad y deseo es mas de servir a vuestras mercedes general y particularmente, que no de pro\u00e7eder contra ellos<\/em>\u00bb; y a\u00f1ad\u00eda que, sin embargo, se deb\u00eda \u00ab<em>mas al servicio de Dios y a la obedien\u00e7ia de mis superiores que no a otra cosa<\/em>\u00bb. Y, por \u00faltimo, se desped\u00eda se\u00f1al\u00e1ndoles que los embajadores les proporcionar\u00edan m\u00e1s detalles acerca de su postura<sup>60<\/sup>.<\/p>\n<p>Ese mismo d\u00eda, los embajadores volvieron a Orihuela. De inmediato, buscaron al justicia y a los jurados, les comentaron las principales incidencias del encuentro con Y\u00e1\u00f1ez y les entregaron su carta. Ante las novedades, los oficiales decidieron convocar una reuni\u00f3n del <em>Consell<\/em> para el d\u00eda siguiente, jueves 9 de marzo.<\/p>\n<p>En ella, Ruiz y Mart\u00ed hicieron relaci\u00f3n de sus dos comparecencias ante el inquisidor, exponiendo, en resumen, que no hab\u00edan podido conseguir que el licenciado modificase sus intenciones sobre su pr\u00f3xima intervenci\u00f3n, y que sobre el sobreseimiento cautelar del monitorio, les hab\u00eda respondido que no ten\u00eda poder para conceder pr\u00f3rroga alguna. Despu\u00e9s, se procedi\u00f3 a la lectura p\u00fablica de su misiva. A continuaci\u00f3n, tras un apagado debate, los asistentes decidieron ceder a uno de los dos requerimientos de Y\u00e1\u00f1ez. Y se lo comunicaron por medio de una contrarrespuesta<sup>61<\/sup>.<\/p>\n<p>En ella, en primer lugar, le escribieron que no ten\u00edan constancia de que el cardenal Adriano hubiese revocado la esgrimida provisi\u00f3n de 1520. Le repitieron que no ten\u00edan intenci\u00f3n de \u00ab<em>impedir lo exercici del Sant Ofici, ni estorbar lo castich dels heretges<\/em>\u00bb, sino que solamente quer\u00edan suplicar que no les fuese causado perjuicio alguno en el archicitado Pleito del Obispado. Y \u00ab<em>per esser obedients a la Sancta Mare Sglesia, y per no encorer en les dites censuras y penes, les quals causaven e causen justum metum, per temor de aquelles<\/em>\u00bb, le comunicaron que renunciaban a todas las apelaciones interpuestas contra los inquisidores cartaginenses ante el Inquisidor general, y le aseguraron que podr\u00eda entrar libremente en Orihuela, y que podr\u00eda ejercer su oficio sin que le fuese opuesto \u00ab<em>empaig, contrast ni impediment algu<\/em>\u00bb, con la condici\u00f3n de que con sus actos no perjudicase en nada los derechos oriolanos en la lite pendiente con el cabildo de Cartagena y la ciudad de Murcia<sup>62<\/sup>.<\/p>\n<p>El 10 de marzo el <em>Consell<\/em> encarg\u00f3 de nuevo a Juan Ruiz y a Vicente Mart\u00ed que llevasen la contrarrespuesta a Juan Y\u00e1\u00f1ez<sup>63<\/sup>. Por otra parte, ese mismo d\u00eda, Carlos I, que estaba en Madrid, recibi\u00f3 noticias inmejorables procedentes de Italia. Sus generales Pescara, Leyva y Lannoy hab\u00edan derrotado a los franceses en Pav\u00eda, y hab\u00edan hecho prisionero al propio Francisco I. Y escribi\u00f3 a sus lugartenientes generales en las diferentes naciones -entre ellos, a D\u00aa. Germana de Foix- para participarles la victoria con \u00ab<em>consolacion y plazer<\/em>\u00bb, y para que extendiesen \u00ab<em>tan gloriosa nueva<\/em>\u00bb por todas las ciudades, villas y lugares de sus reinos<sup>64<\/sup>.<\/p>\n<p>El d\u00eda siguiente -11-, los dos s\u00edndicos le presentaron al inquisidor cartaginense la oferta de sus representados. Y\u00e1\u00f1ez se olvid\u00f3 de los altercados pasados y se mostr\u00f3 satisfecho por la actitud condescendiente de los oriolanos. Por ello, sigui\u00f3 en su t\u00f3nica de dirigir a las autoridades de la ciudad palabras amables. Por ejemplo, les escribi\u00f3 que deseaba que hiciesen caso a sus disposiciones \u00ab<em>mas por el bien y honrra dessa \u00e7iudad que por otro respecto alguno<\/em>\u00bb. O que deb\u00edan dar \u00ab<em>infinitas gra\u00e7ias y loores<\/em>\u00bb a Dios por haber encaminado tan favorablemente el negocio. Despu\u00e9s, les comunic\u00f3 que para no cometer falta por \u00ab<em>yngratitud ni indiligen\u00e7ia<\/em>\u00bb, y aunque en Murcia ten\u00eda \u00ab<em>asaz nego\u00e7ios y cosas en que entender<\/em>\u00bb, hab\u00eda decidido ir a Orihuela. Acto seguido, poniendo de manifiesto su buena disposici\u00f3n, afirm\u00f3 y prometi\u00f3 que no causar\u00eda ning\u00fan perjuicio a la lite pendiente del Obispado, aunque sin hacer alusi\u00f3n alguna a la cuesti\u00f3n de la intitulaci\u00f3n que adoptar\u00eda. Y, por \u00faltimo, les suplic\u00f3 que le buscasen un \u00ab<em>aposiento convenible<\/em>\u00bb para \u00e9l y para sus oficiales, y un lugar en el que ubicar \u00ab<em>la abdien\u00e7ia<\/em>\u00bb, y que le avisasen cuando tuviesen ambas localizaciones preparadas, para emprender el camino hacia la ciudad del Bajo Segura<sup>65<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s -el 13 de marzo- el se\u00f1or de Cox y Vicente Mart\u00ed dieron relaci\u00f3n a la asamblea municipal de la contestaci\u00f3n del inquisidor<sup>66<\/sup>. Y a continuaci\u00f3n, los mun\u00edcipes le escribieron de nuevo a Y\u00e1\u00f1ez agradeci\u00e9ndole \u00ab<em>la muncha honra y cortesia<\/em>\u00bb con que hab\u00eda tratado a los dos embajadores, y su afirmaci\u00f3n de que no perjudicar\u00eda los intereses oriolanos en el Pleito del Obispado. Y en cuanto a su aposento, le ofrecieron que residiese, junto con todos sus oficiales, en el monasterio de San Agust\u00edn, en dicha ciudad, \u00ab<em>por ser posada muy alegra<\/em>\u00bb. No obstante, le dijeron que necesitaban prepararlo, porque \u00ab<em>con las grandes aguas<\/em>\u00bb hab\u00eda sufrido desperfectos, y que cuando lo tuvieran adecentado, de inmediato, le avisar\u00edan<sup>67<\/sup>.<\/p>\n<p>Los trabajos de adecuaci\u00f3n del citado monasterio duraron apenas dos d\u00edas, y el 15 de marzo, el justicia y los jurados de Orihuela escribieron a Juan Y\u00e1\u00f1ez que la posada estaba preparada y que cuando lo desease pod\u00eda comenzar a ejercer el santo oficio<sup>68<\/sup>.<\/p>\n<p>El d\u00eda siguiente -16-, el inquisidor respondi\u00f3 a los oficiales agradeci\u00e9ndoles la diligencia que hab\u00edan puesto en aposentarle. Y les anunci\u00f3 que el d\u00eda siguiente, viernes 17, o \u00ab<em>al mas tardar<\/em>\u00bb, el s\u00e1bado 18 se presentar\u00eda en la ciudad del Bajo Segura<sup>69<\/sup>.<\/p>\n<p>A ciencia cierta, la documentaci\u00f3n consultada no nos permite conocer qu\u00e9 d\u00eda lleg\u00f3 a Orihuela Juan Y\u00e1\u00f1ez, ni cuanto tiempo permaneci\u00f3 en ella. Lo que s\u00ed que sabemos es que antes de que comenzase a ejercer su santo oficio, las autoridades de la ciudad le solicitaron que cumpliese lo que hab\u00eda prometido, esto es, que con su intervenci\u00f3n no causase ning\u00fan perjuicio a los intereses episcopales oriolanos. Sin embargo, ocurri\u00f3 lo previsible. Apoy\u00e1ndose en una orden del difunto cardenal Adriano, la cual se neg\u00f3 a ense\u00f1ar, el licenciado comenz\u00f3 a actuar invocando su t\u00edtulo de inquisidor del obispado de Cartagena, demostrando de esa manera que m\u00e1s que ejercer su santo oficio, lo que pretend\u00eda era lograr que los murcianos pudiesen utilizar la desobediencia oriolana a la Inquisici\u00f3n para desnivelar la balanza legal en el dilatado Pleito.<\/p>\n<p>Obviamente, los ediles se negaron a aceptar los mandatos de Y\u00e1\u00f1ez, le solicitaron en repetidas ocasiones que desistiese de sus lesivas intenciones, y volvieron a apelar ante el inquisidor mayor de Espa\u00f1a. No obstante, pese a las protestas, Y\u00e1\u00f1ez procedi\u00f3 contra algunos vecinos, por lo que el pueblo se alter\u00f3 y se produjeron algunos incidentes, que terminaron con la imposici\u00f3n de diferentes penas pecuniarias, con la excomuni\u00f3n de los habitantes de la ciudad, y con la detenci\u00f3n del justicia y los jurados, y su encarcelamiento en la ciudad de Murcia<sup>70<\/sup>.<\/p>\n<ol start=\"5\">\n<li><strong> Las Cortes frustradas de 1525.<\/strong><\/li>\n<\/ol>\n<p>En la corte real, las negociaciones del can\u00f3nigo Luis Mart\u00ednez segu\u00edan suponiendo logros. Tras conseguir de Carlos I la expedici\u00f3n de las cartas para Clemente VII y para sus embajadores en Roma, el procurador le inform\u00f3 al emperador sobre la cuesti\u00f3n de los desbordamientos provocados del r\u00edo Segura. Le explic\u00f3 que el cabildo de Cartagena hab\u00eda sufragado las obras de excavaci\u00f3n del \u00ab<em>riacho<\/em>\u00bb, y que en la d\u00e9cada anterior los can\u00f3nigos hab\u00edan mandado romper en repetidas ocasiones el \u00ab<em>quexer<\/em>\u00bb o \u00ab<em>portell<\/em>\u00bb que cerraba el nuevo cauce, propiciando terribles inundaciones en el distrito de Orihuela. Le refiri\u00f3 que no hac\u00eda mucho que, a solicitud de algunos vecinos de Murcia que ten\u00edan tierras en dicho t\u00e9rmino, hab\u00edan abandonado tal demencial pr\u00e1ctica. Y que, pese a ello, \u00ab<em>agora, a causa de las differencias e pleyto que esta entre la dicha ciudat de Murcia e Orihuela, amenazan cada dia de volver a romper el dicho quexer del rio, de lo qual redunda mucho danyo a la dicha cibdat de Orihuela<\/em>\u00bb. Y por ende, le suplic\u00f3 que ordenase a los murcianos que no volviesen a provocar \u00ab<em>las avenidas e aguaduchos<\/em>\u00bb.<\/p>\n<p>El asunto fue debatido en el Consejo de Castilla, y tanto sus doctores como el propio Carlos I decidieron enviar al juez de residencia de Murcia y Cartagena y a sus alcaldes un mandato en el que el monarca les conminaba a evitar la profusi\u00f3n de dichas amenazas, \u00ab<em>sin dar lugar a largas nin dilaciones de malicia<\/em>\u00bb, bajo la pena de 10.000 maraved\u00eds. La provisi\u00f3n fue expedida el 16 de marzo<sup>71<\/sup>.<\/p>\n<p>Hacia finales de ese mismo mes, los oficiales de Orihuela fueron liberados de su encierro y volvieron r\u00e1pidamente a la ciudad del Bajo Segura<sup>72<\/sup>. No obstante, su estancia en Murcia, si bien fue extremadamente onerosa, no result\u00f3 del todo improductiva. De una manera que desconocemos, consiguieron enterarse de una valios\u00edsima, aunque muy negativa noticia: la existencia del breve revocatorio de Clemente VII, expedido el 14 de octubre del a\u00f1o anterior, y del ejecutorial de Jer\u00f3nimo de Thinutiis.<\/p>\n<p>Por ello, no m\u00e1s pisaron el suelo de su ciudad, comenzaron a planear la adopci\u00f3n de nuevas medidas profil\u00e1cticas que les sirviesen para proteger y blindar sus derechos en el Pleito del Obispado.<\/p>\n<p>De esta manera, el 3 de abril, los oficiales se reunieron junto con la clerec\u00eda del Salvador en la sacrist\u00eda de dicha iglesia, y presentaron ante fr. Juan Ordibel, fr. Juan Carmenso y fr. Pedro Rocamora una apelaci\u00f3n para la Santa Sede en la que protestaron contra el modo de obtenci\u00f3n del rescripto clementino, del que adujeron que hab\u00eda sido obtenido con enga\u00f1os e informaciones falsas, y sin permitir previamente a los oriolanos que se defendiesen; y contra su contenido, pues el rescripto no censuraba los procedimientos utilizados en 1521 por los murcianos y los cartaginenses cuando consiguieron la anulaci\u00f3n forzada del obispado de Orihuela<sup>73<\/sup>.<\/p>\n<p>El d\u00eda siguiente, cinco de los miembros del grupo de los <em>Electos<\/em> -el justicia Pedro Morrelles, D. Ram\u00f3n de Rocafull, D. Jaime Masquefa, Vicente Mart\u00ed y Perot P\u00e9rez- consiguieron una considerable inyecci\u00f3n econ\u00f3mica para los fondos destinados a sufragar los gastos derivados del negocio de la Catedral. Recibieron a modo de pr\u00e9stamo 30 libras de la f\u00e1brica de la iglesia de Catral, y 50 ducados de oro de la de Santiago de Orihuela<sup>74<\/sup>.<\/p>\n<p>Posteriormente, los oficiales y los <em>Electos<\/em> tuvieron una gran idea para fortalecer los derechos episcopales oriolanos y para conferir un mayor peso espec\u00edfico a sus reclamaciones ante Carlos I y ante Clemente VII. As\u00ed, el 8 de abril, le encargaron al notario Bernardo Manresa, nombrado procurador del cap\u00edtulo, el clero y la ciudad de Orihuela y su di\u00f3cesis, que solicitase al lugarteniente del gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona, D. Luis Togores, que le permitiese realizar ante su supervisi\u00f3n un compendio informativo, con la intenci\u00f3n de que quedase constancia escrita en el futuro de la crueldad con que actuaron el marqu\u00e9s de los V\u00e9lez y sus hombres durante el Saco de 1521, y a fin de probar, asimismo, que la prestaci\u00f3n de obediencia al obispo y al cabildo de Cartagena fueron realizadas de un modo il\u00edcito e involuntario, por las coacciones del citado noble.<\/p>\n<p>Manresa cumpli\u00f3 satisfactoriamente con la misi\u00f3n encomendada. Convenci\u00f3 a Togores utilizando h\u00e1biles argumentos, como que era el momento adecuado para recabar dicha informaci\u00f3n porque algunas de las personas que vivieron tales acontecimientos eran \u00ab<em>velles<\/em>\u00bb y pod\u00edan morir. Y ese mismo d\u00eda 8 de abril comenz\u00f3 la recepci\u00f3n de testimonios con el suyo propio.<\/p>\n<p>Entrevist\u00f3 sucesivamente a otros 23 testigos de diferentes condiciones sociales. Interrog\u00f3 a hombres que hab\u00edan intervenido destacadamente los a\u00f1os anteriores en la administraci\u00f3n municipal como Juan Masquefa, Francisco P\u00e9rez Felipe, Francisco de Rocafull, Vicente Mart\u00ed, Bartolom\u00e9 Togores o Bartolom\u00e9 Cascant. A otros notarios como Luis Traver o Jaime Segarra. A cl\u00e9rigos seculares de la iglesia del Salvador como Gin\u00e9s Crietes, Pedro de la Mata, Pedro Santander o Gaspar Tafalla. A unos cuantos frailes mercedarios: Jaime Tom\u00e1s, Pedro Rocamora, Nicasio Olivares, Pedro G\u00f3mez y Juan Jaca. Y, finalmente, para dotar de una mayor rigurosidad a las informaciones, entrevist\u00f3 tambi\u00e9n a for\u00e1neos residentes en Orihuela como el cirujano vizca\u00edno Ochoa de Aleiturri o el jerezano Rodrigo Pollo.<\/p>\n<p>Manresa cerr\u00f3 la investigaci\u00f3n el 16 de mayo, d\u00eda en el que le entreg\u00f3 el proceso al lugarteniente Togores, y le solicit\u00f3 una copia aut\u00e9ntica de \u00e9l. Togores se la proporcion\u00f3, y las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura se la guardaron como oro en pa\u00f1o, con la intenci\u00f3n de utilizarla en sus futuras gestiones<sup>75<\/sup>.<\/p>\n<p>No obstante, hasta llegar a dicha fecha, a\u00fan sucedieron algunos acontecimientos dignos de ser rese\u00f1ados.<\/p>\n<p>El 18 de abril, el <em>Consell<\/em> se plante\u00f3 la necesidad de enviar un embajador a la Curia Romana para que tratase de conseguir de Clemente VII alguna bula que confirmase la leg\u00edtima fundaci\u00f3n del obispado, y anulase todos los rescriptos obtenidos il\u00edcitamente por los murcianos en contra de dicha instituci\u00f3n. No obstante, los <em>Electos<\/em> manifestaron a la corporaci\u00f3n municipal que hab\u00eda dinero para sufragar los gastos del viaje a la Ciudad Eterna, pero no para mantener al procurador que fuese electo durante el tiempo necesario para llevar a cabo las negociaciones, y mucho menos para pagar los costes de \u00e9stas, y de la expedici\u00f3n del anhelado rescripto<sup>76<\/sup>. Por ello, a los mun\u00edcipes no les qued\u00f3 m\u00e1s remedio que aplazar temporalmente el proyecto, y conformarse con las fruct\u00edferas actividades de Luis Mart\u00ednez en la corte del emperador, a quien le encargaron que explicase con sumo tacto al propio Carlos I y al arzobispo de Sevilla la postura de Orihuela en relaci\u00f3n con los incidentes acaecidos a ra\u00edz de la intervenci\u00f3n del inquisidor Juan Y\u00e1\u00f1ez<sup>77<\/sup>.<\/p>\n<p>El 26 de abril, el maltrecho estado de las arcas municipales se vio levemente aliviado por un nuevo aporte extraordinario. A instancia de los <em>Electos<\/em>, la f\u00e1brica de la iglesia de Callosa prest\u00f3 50 libras<sup>78<\/sup>. Y el 4 de mayo fue el fabriquero de la parroquial de Guardamar el que dio muestras de solidaridad al hacer llegar a las autoridades civiles oriolanas una suma de 30 libras<sup>79<\/sup>.<\/p>\n<p>Entrado el quinto mes de 1525, la coyuntura para la ciudad del Bajo Segura no era, desde luego, nada esperanzadora desde el punto de vista de sus intereses episcopales. La nueva revocaci\u00f3n del obispado hab\u00eda sido decretada por el sumo pont\u00edfice a suplicaci\u00f3n de Carlos I, y la \u00fanica manera que hab\u00eda para tratar de que no se hiciese efectiva era retrasar su ejecuci\u00f3n mediante la interposici\u00f3n de apelaciones, e intentar mientras tanto convencer al emperador para que le manifestase al papa su voluntad de mantener la vigencia de la disposici\u00f3n de Julio II. No obstante, por estas fechas, ello aparec\u00eda al entendimiento de los oriolanos casi como una utop\u00eda, puesto que el conflicto desatado con la Inquisici\u00f3n les hab\u00eda puesto en una situaci\u00f3n en la que nada pod\u00edan pedirle al monarca con una m\u00ednima expectativa de \u00e9xito. Adem\u00e1s, ni siquiera contaban con una representaci\u00f3n digna cerca de la Santa Sede, por lo que incluso la presentaci\u00f3n de protestas ante la Curia se ve\u00eda seriamente dificultada.<\/p>\n<p>Sin embargo, un hecho absolutamente ajeno a la cuesti\u00f3n del obispado vino a favorecer los intereses de Orihuela: la guerra con Francia.<\/p>\n<p>El 20 de mayo, Carlos I escribi\u00f3 una carta a D\u00aa. Germana de Foix, informando que necesitaba ayuda econ\u00f3mica para formar un nuevo ej\u00e9rcito con el que atacar a los franceses, y que, por ello, ten\u00eda previsto \u00ab<em>convocar Parlamento en esse Reyno<\/em>\u00bb, en Valencia, para el 10 de junio. Y con la misiva, le envi\u00f3 los anuncios de la convocatoria de las Cortes que hab\u00eda preparado para las autoridades municipales de las diferentes ciudades y villas que tendr\u00edan que participar en ellas, dentro del brazo real, a fin de que se los hiciese llegar en el menor tiempo posible<sup>80<\/sup>.<\/p>\n<p>La c\u00e9dula real lleg\u00f3 a Valencia el 26 de mayo, y D\u00aa. Germana remiti\u00f3 diligentemente las notificaciones<sup>81<\/sup>. La de Orihuela lleg\u00f3 a la ciudad antes del final del mes.<\/p>\n<p>La noticia de la inminente convocatoria elev\u00f3 considerablemente la moral de las autoridades oriolanas, pues la participaci\u00f3n en las Cortes siempre permit\u00eda elevar las s\u00faplicas al emperador con mayores posibilidades de \u00e9xito. Este factor, conjugado con la existencia puntual de cierta liquidez propiciada por los pr\u00e9stamos de las f\u00e1bricas y por la carga de algunos censales, hizo que el <em>Consell<\/em> se animase a nombrar al s\u00edndico que habr\u00eda de ir a Roma, y el 31 de mayo fue elegido para tan delicada misi\u00f3n el can\u00f3nigo del Salvador, D. Jaime G\u00f3mez Daroca<sup>82<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el 5 de junio, el organismo municipal procedi\u00f3 al nombramiento del procurador que habr\u00eda que representar a Orihuela en las Cortes, formando parte del brazo real. El electo fue el jurado Perot P\u00e9rez, a quien le fue conferido poder suficiente para defender los privilegios y las libertades de la ciudad, y para realizar las diligencias oportunas para que Carlos I atendiese las diferentes reclamaciones oriolanas, en especial, las concernientes al Pleito del Obispado<sup>83<\/sup>.<\/p>\n<p>Conociendo que Carlos I a\u00fan no hab\u00eda llegado a Valencia, y teniendo en cuenta tambi\u00e9n que los diferentes procuradores ten\u00edan de plazo para arribar a Valencia hasta el 21 de junio, pues no se les acusaba de contumacia hasta pasado un plazo de gracia de 12 d\u00edas, las autoridades de la ciudad dedicaron poco m\u00e1s de una semana en preparar la embajada de Perot P\u00e9rez, redact\u00e1ndole un complet\u00edsimo pliego de instrucciones y un par de cartas de creencia y recomendaci\u00f3n dirigidas a los jurados de Valencia y al cap\u00edtulo de la Metropolitana. Y el 14 de junio le entregaron toda la documentaci\u00f3n.<\/p>\n<p>Las \u00f3rdenes relacionadas con la causa del obispado eran muy claras. P\u00e9rez hab\u00eda de buscar el apoyo de Fernando de Loazes, de D\u00aa. Germana de Foix, de las autoridades municipales y eclesi\u00e1sticas valentinas, del gobernador Maza, y de otros caballeros principales \u00ab<em>affectats ad aquesta ciutat<\/em>\u00bb. Y en colaboraci\u00f3n con Lope Ferr\u00e1ndez de Mesa, \u00ab<em>sindich dels militars<\/em>\u00bb de Orihuela<sup>84<\/sup>, ten\u00eda que conseguir que los brazos real y militar le elevasen al Rey de Romanos una consistente suplicaci\u00f3n.<\/p>\n<p>En ella, le ten\u00eda que recordar que el 31 de noviembre de 1522 hab\u00eda jurado respetar los privilegios de la ciudad, y que entre ellos se hallaba el concedido por Alfonso V en Gaeta el 11 de septiembre de 1537, en el que promet\u00eda que tanto \u00e9l como sus sucesores tratar\u00edan de conseguir la creaci\u00f3n pontificia del obispado de Orihuela. Adem\u00e1s, P\u00e9rez le ten\u00eda que pedir que dejase de apoyar a los murcianos, pues, al parecer, tras enviar a Roma las cartas del 3 y el 10 de marzo de ese mismo 1525, hab\u00eda vuelto a escribir a Clemente VII que su voluntad era la revocaci\u00f3n del obispado. Y, finalmente, le hab\u00eda de rogar que le pidiese de nuevo al papa que revocase todos los rescriptos apost\u00f3licos posteriores a las bulas del 13 de mayo de 1510 que eran contrarios a la instituci\u00f3n de la mitra oriolana, y que la lite fuese sentenciada en el consistorio apost\u00f3lico, sin que mediase ning\u00fan tipo de presi\u00f3n, esto es, de modo que \u00fanicamente se tuviesen en cuenta los criterios de la equidad y la justicia<sup>85<\/sup>.<\/p>\n<p>El 16 de mayo el justicia y los jurados de Orihuela le entregaron a Perot P\u00e9rez algo de dinero para que pudiese hacer frente a los primeros gastos que se derivaran de la embajada<sup>86<\/sup>. Y poco despu\u00e9s, en compa\u00f1\u00eda de Lope Ferr\u00e1ndez de Mesa, parti\u00f3 para Valencia.<\/p>\n<p>Los dos procuradores llegaron a la ciudad del Turia justamente el d\u00eda 21, a las 9 de la ma\u00f1ana. Fueron a su posada, y descansaron hasta las 3 de la tarde. Despu\u00e9s, se dirigieron a la <em>Seu<\/em>, donde estaban reunidos los tres estamentos. All\u00ed presentaron sus sindicatos. Acto seguido, se dedicaron a repartir las cartas de creencia que llevaban de parte de la ciudad. Y los destinatarios le aseguraron a Orihuela su favor en las suplicaciones que hab\u00edan de presentar, destac\u00e1ndose especialmente por sus ofertas los doctores Dasio, Ros y Bas<sup>87<\/sup>.<\/p>\n<p>Las diligencias iban por buen camino cuando pocos d\u00edas despu\u00e9s lleg\u00f3 a manos de D\u00aa. Germana de Foix una provisi\u00f3n real datada en Toledo el 16 de junio, por la que Carlos I anunciaba el retraso de la fecha de la convocatoria del Parlamento hasta el 14 de julio, con el \u00ab<em>fin y determinacion de hallarse aqui personalmente<\/em>\u00bb, y ped\u00eda a las autoridades de las diferentes ciudades y villas del Reino que confiriesen a sus procuradores \u00ab<em>poder bastante para asistir en la dicha corte general y prestar el juramento de fidelidad<\/em>\u00bb. El monarca aclaraba que los s\u00edndicos habr\u00edan de personarse en la ciudad del Turia entre el citado 14 de julio y el d\u00eda 26 del mismo mes, dentro de \u00ab<em>los doze dias de las gracias<\/em>\u00bb, de modo que el 27 de julio tuviesen lugar la proposici\u00f3n real y el juramento de fidelidad, y despu\u00e9s tuviese tiempo suficiente para llegar a Monz\u00f3n antes del 15 de agosto, a fin de celebrar en la poblaci\u00f3n aragonesa \u00ab<em>la convocacion general<\/em>\u00bb<sup>88<\/sup>.<\/p>\n<p>La procuradora general del Reino comunic\u00f3 la nueva a los mun\u00edcipes de Orihuela mediante una misiva datada el 28 de junio<sup>89<\/sup>. Y el 5 de julio, el <em>Consell<\/em> de dicha ciudad le expidi\u00f3 a Perot P\u00e9rez un nuevo sindicato concedi\u00e9ndole las facultadas demandadas por Carlos I<sup>90<\/sup>.<\/p>\n<p>Sin embargo, de poco le sirvi\u00f3 al procurador porque el Parlamento del Reino de Valencia no lleg\u00f3 a celebrarse, y el juramento de fidelidad a Carlos I se retras\u00f3 hasta 1528<sup>91<\/sup>.<\/p>\n<ol start=\"6\">\n<li><strong> La intervenci\u00f3n de D. Pedro Maza en favor de Orihuela.<\/strong><\/li>\n<\/ol>\n<p>Perdida la ocasi\u00f3n de conseguir alguna provisi\u00f3n real provechosa en las frustradas Cortes, el <em>Consell<\/em> de Orihuela decidi\u00f3 dirigir sus esfuerzos hacia la corte real, en la que segu\u00eda el can\u00f3nigo Luis Mart\u00ednez, y hacia la Curia romana. En este sentido, el primero de agosto le dieron al tambi\u00e9n can\u00f3nigo Jaime G\u00f3mez Daroca -s\u00edndico electo el 31 de mayo- poder suficiente para que pudiese representar los intereses de la ciudad en Roma, y su marcha qued\u00f3 pendiente de la disponibilidad de dinero<sup>92<\/sup>.<\/p>\n<p>Y realmente era necesaria su presencia en la capital del Orbe Cat\u00f3lico, puesto que el 5 de agosto, y gracias a una suplicaci\u00f3n de Carlos I, los murcianos consiguieron de Clemente VII la expedici\u00f3n de un nuevo breve por el que el pont\u00edfice mand\u00f3 a tres eclesi\u00e1sticos -el arzobispo de Granada, el preceptor del monasterio de la Merced de Murcia, y el ministro del monasterio de la Trinidad de dicha ciudad- que facilitasen la publicaci\u00f3n del rescripto revocatorio del 14 de octubre del a\u00f1o anterior, a fin de que el obispo y el cabildo de Cartagena consiguiesen la misma jurisdicci\u00f3n y superioridad sobre Orihuela que ten\u00edan antes del pontificado de Julio II. Les orden\u00f3 que no permitiesen a nadie que molestase a los cartaginenses en la posesi\u00f3n de sus derechos, imponiendo a los infractores de sus mandatos apost\u00f3licos las penas eclesi\u00e1sticas y temporales se\u00f1aladas en escritos pontificios anteriores. Y por \u00faltimo, volvi\u00f3 a dar por concluidas y zanjadas todas las lites y apelaciones pendientes, relacionadas con el Pleito del Obispado, reimponiendo el silencio perpetuo a los oriolanos<sup>93<\/sup>.<\/p>\n<p>Tras obtener el breve, los murcianos acudieron al emperador suplic\u00e1ndole ayuda para que el cabildo de Cartagena pudiese proceder a la ejecuci\u00f3n de los mandatos pontificios sin esc\u00e1ndalos y de modo seguro, de modo que \u00e9stos entraran inmediatamente en vigor.<\/p>\n<p>Carlos I tuvo en consideraci\u00f3n los intentos fallidos de notificaci\u00f3n precedentes, y haciendo demostraci\u00f3n de su inconmutable voluntad de estar siempre conforme con las disposiciones tomadas por la Sede Apost\u00f3lica, el 25 del mismo mes de agosto le escribi\u00f3 una provisi\u00f3n a D. Pedro Maza de Lizana, gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona, mand\u00e1ndole, so pena de incurrir en su ira e indignaci\u00f3n regia y de pagar 2.000 florines de oro aragoneses, que marchase con los murcianos a Orihuela y, una vez estuviese all\u00ed, les asistiese y prestase auxilio tantas veces como fuese necesario hasta que pudiesen realizar la presentaci\u00f3n de las bulas papales, dando orden y remunerando convenientemente a alg\u00fan notario de la ciudad del Bajo Segura para que diese fe de todos los actos<sup>94<\/sup>.<\/p>\n<p>Tan pronto como recibi\u00f3 el gobernador Maza la orden real, le comunic\u00f3 a las autoridades civiles y eclesi\u00e1sticas de Orihuela las intenciones compartidas del cabildo de Cartagena, la ciudad de Murcia y el propio Carlos I.<\/p>\n<p>Sin embargo, una decisi\u00f3n previa de dichos mandatarios les impidi\u00f3 una pronta reacci\u00f3n. A principios del mes de septiembre le ordenaron al brillante can\u00f3nigo Luis Mart\u00ednez que regresase de la corte, y \u00e9ste arrib\u00f3 a la ciudad el d\u00eda 10, justo nueve meses despu\u00e9s de su partida<sup>95<\/sup>. Los <em>Electos<\/em> se arrepintieron de su decisi\u00f3n, pues la presencia de Mart\u00ednez cabe el monarca podr\u00eda haber resultado sumamente \u00fatil, teniendo en cuenta la dif\u00edcil situaci\u00f3n que se avecinaba.<\/p>\n<p>No obstante, buscaron con rapidez la mejor soluci\u00f3n. De inmediato, pensaron en volver a enviar al mismo can\u00f3nigo, pero se compadecieron de \u00e9l, y le permitieron descansar. Y tras algunas cavilaciones, finalmente, decidieron mandar a Toledo a un nuevo s\u00edndico, cuyo nombre no hemos logrado conocer, y del que s\u00ed sabemos que actu\u00f3 con la mayor diligencia, pues consigui\u00f3 comparecer ante el rey y pudo exponerle las argumentaciones de sus representados.<\/p>\n<p>El 15 de septiembre, las autoridades de la ciudad del Bajo Segura le entregaron al s\u00edndico Jaime G\u00f3mez Daroca 1.140 ducados de oro, y un buen pliego de documentos -cartas, instrumentos, procuras y memoriales-<sup>96<\/sup>. Y el d\u00eda siguiente inici\u00f3 el que ser\u00eda un largo y dilatado viaje a Roma, ya que el can\u00f3nigo del Salvador llevaba orden de esperar en Alicante hasta que finalizase la cuesti\u00f3n del intento de ejecuci\u00f3n de los rescriptos revocatorios por parte del cabildo de Cartagena<sup>97<\/sup>.<\/p>\n<p>Las gestiones del procurador an\u00f3nimo en la corte fueron absolutamente provechosas, de una manera ciertamente sorprendente<sup>98<\/sup>. El 23 de septiembre Carlos I le remiti\u00f3 al gobernador Maza una segunda misiva, en la que le comentaba que los oriolanos le acababan de informar que los murcianos hab\u00edan obtenido los referidos escritos pontificios de modo ilegal o poco claro, y en grave da\u00f1o y perjuicio de los derechos de su ciudad. Y que le hab\u00edan suplicado que no proveyese su ejecuci\u00f3n, por los referidos motivos, y porque de ella seguramente se seguir\u00edan muchas muertes y nuevas esc\u00e1ndalos entre ambas poblaciones, \u00ab<em>en deservicio de Dios y nuestro<\/em>\u00bb. Y como respuesta a tal ruego, el monarca le mand\u00f3 a D. Pedro Maza que asistiese a los cartaginenses en la presentaci\u00f3n de los documentos, que recibiese todas las protestas y apelaciones que quisiesen interponer las autoridades oriolanas tras la notificaci\u00f3n, y que en el caso de que las considerase justas y leg\u00edtimas, suspendiese la ejecuci\u00f3n de los rescriptos y remitiese la causa a la corte, para que fuese objeto de un nuevo estudio por parte de los doctores de los Consejos de Castilla y de Arag\u00f3n, y pudiese adoptar una resoluci\u00f3n definitiva<sup>99<\/sup>.<\/p>\n<p>A espaldas de las diligencias oriolanas, los murcianos prepararon la expedici\u00f3n ejecutoria. El 30 de septiembre, el provisor del obispado -el licenciado Sancho V\u00e9lez, inquisidor-, y el cabildo de Cartagena nombraron procuradores leg\u00edtimos a Mat\u00edas Coque -can\u00f3nigo de la Catedral de Murcia- y al caballero Rodrigo Puixmar\u00edn -regidor de dicha ciudad-, y les encargaron la misi\u00f3n de presentar al gobernador Maza la provisi\u00f3n real del 25 de agosto, y de solicitarle que tomase las medidas oportunas para que la disposici\u00f3n de Carlos I tuviese pleno cumplimiento<sup>100<\/sup>.<\/p>\n<p>Unos d\u00edas despu\u00e9s, el 3 de octubre, Coque y Puixmar\u00edn llegaron a la villa de Novelda, en la que resid\u00eda el gobernador, se presentaron ante \u00e9l, le presentaron su procura, y le requirieron que cumpliese las \u00f3rdenes reales recogidas en el referido primer mandato. Le pidieron que fuese con ellos a Orihuela, y que les ayudase y protegiese a la hora de presentar los breves de Clemente VII al cap\u00edtulo del Salvador y a las autoridades seglares de la ciudad. Y le instaron a obtemperar la voluntad real, record\u00e1ndole que en caso contrario incurrir\u00eda en las penas se\u00f1aladas por el propio Carlos I. Maza les respondi\u00f3 que obedecer\u00eda las \u00f3rdenes de Su Sacra Cesarea y Cat\u00f3lica Majestad con humilde reverencia, pero no hizo comentario alguno sobre la provisi\u00f3n del 23 de septiembre<sup>101<\/sup>.<\/p>\n<p>Los d\u00edas siguientes prepar\u00f3 su viaje a la capital de la Gobernaci\u00f3n. Y el 5 de octubre, poco antes de partir, compareci\u00f3 ante \u00e9l, y ante los dos s\u00edndicos cartaginenses, Gil G\u00f3mez, procurador de la Iglesia y la aludida ciudad de Orihuela<sup>102<\/sup>. G\u00f3mez le expuso a Maza que los murcianos consiguieron el despacho del mandato real ocultando la verdad y con argumentos falsos, y que todo redundaba en perjuicio de los fueros y privilegios de Orihuela, y, por extensi\u00f3n, del Reino de Valencia. Le dijo que si el emperador supiese que su orden estaba causando tan grave da\u00f1o a sus derechos, jam\u00e1s la habr\u00eda promulgado, y que tampoco permitir\u00eda que los breves pontificios fuesen ejecutados. Y, por \u00faltimo, le pidi\u00f3 que antes de que se realizase ning\u00fan acto, proporcionase a sus representados copias de los documentos apost\u00f3licos y reales, a fin de que pudiesen presentar las alegaciones con pleno conocimiento de la causa, sin que transcurriera el tiempo estipulado para tal acci\u00f3n legal hasta que los trasuntos les fueran entregados<sup>103<\/sup>.<\/p>\n<p>El gobernador admiti\u00f3 la petici\u00f3n de Gil G\u00f3mez y mand\u00f3 que le entregasen traslados de los instrumentos que portaban los procuradores murcianos<sup>104<\/sup>.<\/p>\n<p>Y a continuaci\u00f3n, D. Pedro Maza, siguiendo las \u00f3rdenes de Carlos I, march\u00f3 a la ciudad de Orihuela para asistir personalmente y otorgar su auxilio y favor a los citados s\u00edndicos cartaginenses a fin de que pudiesen presentar los rescriptos apost\u00f3licos<sup>105<\/sup>.<\/p>\n<p>Llegados a la ciudad del Bajo Segura, Coque y Puixmar\u00edn requirieron al gobernador que mandase reunir al cap\u00edtulo del Salvador y al <em>Consell<\/em> para poder realizar el acto de notificaci\u00f3n. Y Maza mand\u00f3 al notario Francisco Vilanova -escribano de la Corte de la Gobernaci\u00f3n- que comunicase a los miembros de ambas corporaciones que se congregasen en los lugares en los que sol\u00edan celebrar sus sesiones<sup>106<\/sup>.<\/p>\n<p>Vilanova busc\u00f3, en primer lugar, a los oficiales. Y transmiti\u00f3 la orden del gobernador al justicia Pedro Morrelles, y a los jurados Luis Alavanya, Juan Jim\u00e9nez, Perot P\u00e9rez y Bartolom\u00e9 Cascant. \u00c9stos le pidieron al notario que le comunicase de su parte a Maza que estaban dispuestos a reunir el <em>Consell<\/em> cuando se lo pidiera<sup>107<\/sup>.<\/p>\n<p>Seguidamente, Vilanova se dirigi\u00f3 hacia la Catedral para notificar la orden del gobernador a los capitulares, pero no hall\u00f3 all\u00ed a ninguno de los can\u00f3nigos, por lo que no le qued\u00f3 m\u00e1s remedio que presentarse ante Maza sin haber comunicado a los eclesi\u00e1sticos su mandato<sup>108<\/sup>.<\/p>\n<p>Poco despu\u00e9s, el s\u00edndico G\u00f3mez volvi\u00f3 a comparecer ante el gobernador, y le pidi\u00f3 que antes de ordenar la notificaci\u00f3n de los breves clementinos, permitiese a sus representados interponer una apelaci\u00f3n contra ellos, y que despu\u00e9s de comprobar la legitimidad de los argumentos aducidos, remitiese la causa de nuevo al emperador, sin tomar ninguna medida<sup>109<\/sup>.<\/p>\n<p>El gobernador acept\u00f3 la petici\u00f3n del procurador oriolano, y acto seguido, ante la sorpresa y la irritaci\u00f3n de Coque y Puixmar\u00edn, les mostr\u00f3 la provisi\u00f3n real del 23 de septiembre, y les ofreci\u00f3 una copia de ella. Los s\u00edndicos cartaginenses la aceptaron, y viendo seriamente comprometido el \u00e9xito de su misi\u00f3n, no supieron pedirle a Maza m\u00e1s que hiciese cumplir la orden del 25 de agosto. El gobernador les respondi\u00f3 que hab\u00eda sido invalidada por la otra, y que \u00fanicamente estaba obligado a obedecer esta \u00faltima<sup>110<\/sup>.<\/p>\n<p>Y entonces, Gil G\u00f3mez present\u00f3 un interesant\u00edsimo y conciso escrito de sus representados<sup>111<\/sup>. En \u00e9l, comenzaron explicando que el apoyo real a las pretensiones cartaginenses de conseguir la anulaci\u00f3n del obispado de Orihuela se deb\u00eda a una serie de factores concatenados: las repetidas importunaciones murcianas, el uso por sus procuradores de argumentos falsos, la consecuente falta de informaci\u00f3n correcta o verdadera sobre el estado preciso del Pleito del Obispado, y finalmente, la expedici\u00f3n de mandatos o ejecutoriales, por olvido o ignorancia, en claro menoscabo o detrimento de los privilegios concedidos a la ciudad de Orihuela o los fueros del Reino de Valencia, aunque sin intenci\u00f3n de causar da\u00f1o alguno a los regn\u00edcolas.<\/p>\n<p>Despu\u00e9s, argumentaron que los murcianos no pod\u00edan siquiera pretender la revocaci\u00f3n de la fundaci\u00f3n del obispado porque \u00e9sta no les causaba ning\u00fan perjuicio -al menos desde su punto de vista&#8230;-. Que tampoco era leg\u00edtimo que tratasen de conseguir rescriptos apost\u00f3licos encaminados a tal fin, en aquellos tiempos, pues el litigio estaba siendo sustanciado en los tribunales de la Curia romana, y no pod\u00eda adoptarse ninguna medida, no pod\u00eda haber ninguna novedad hasta que fuese sentenciado<sup>112<\/sup>. Y que a\u00fan era m\u00e1s il\u00edcito que fuese expedida cualquier bula o cualquier breve que pudiese causar alg\u00fan perjuicio, sin convocar previamente a la parte afectada y permitir a sus representantes el derecho a defender sus intereses.<\/p>\n<p>Y el suplicatorio conclu\u00eda con un valios\u00edsimo ap\u00e9ndice informativo, que daba un sumario repaso a todas las circunstancias hist\u00f3ricas que hab\u00edan contribuido a generar el inter\u00e9s de los vecinos de la ciudad del Bajo Segura por conseguir la creaci\u00f3n del obispado, y con el que los apelantes pretend\u00edan que Carlos I pudiese formarse una idea correcta de las leg\u00edtimas y justificadas causas que hab\u00edan llevado a Fernando el <em>Cat\u00f3lico<\/em> a promover la fundaci\u00f3n episcopal.<\/p>\n<p>El ap\u00e9ndice comenzaba remarcando la diversidad de los habitantes de las poblaciones de Orihuela y Murcia: \u00ab<em>los de Murcia parlen castella e los de Oriola valencia; los uns se nomenen castellans, los altres valencians; los uns son de la Corona Real de Castella, los altres de la Corona Real de Arag\u00f3, tots vasalls de S.M. empero regits e governats ab diverses leys, furs e privilegis, pratiques e costums; en la ciutat de Murcia esta lo port de Castella hon hi paguen los drets de moxariffat, aduanes e altres drets reales, los quals fan pagar als de Oriola entrant y exint en la dita ciutat de Murcia, y per lo semblant en Oriola esta la taula dels drets reals del Regne de Valencia per als que van a Murcia<\/em>\u00bb.<\/p>\n<p>Y prosegu\u00eda haciendo tambi\u00e9n especial incidencia en la existencia plurisecular de rivalidades locales, acentuadas por los respectivos sentimientos nacionalistas, y por la situaci\u00f3n cercana y fronteriza de ambas ciudades. El documento se\u00f1alaba que en tiempos de paz, entre murcianos y oriolanos siempre hab\u00eda habido enfrentamientos, discordias que hab\u00edan culminado en razias, cabalgadas, secuestros, matanzas e, incluso, en verdaderas batallas campales, porque -afirmaban- \u00ab<em>los de la ciutat de Murcia continuament an procurat e procuren de despoblar y anichilar aquesta ciutat, per no tenir en la frontera ciutat tant populosa com es Oriola<\/em>\u00bb. A\u00f1ad\u00eda que en tiempos de guerra entre los monarcas de Castilla y Arag\u00f3n, la \u00ab<em>enemistat capital<\/em>\u00bb se hab\u00eda manifestado haciendo, si cabe, m\u00e1s violentas las confrontaciones b\u00e9licas. Y comentaba que las rivalidades tambi\u00e9n hab\u00edan trascendido al \u00e1mbito religioso, poniendo como ejemplo el hecho de que la clerec\u00eda cartaginense consigui\u00f3 a finales del siglo XIV que los reyes castellanos vetasen la presencia de eclesi\u00e1sticos del Reino de Valencia en los beneficios de las iglesias murcianas, obligando a los oriolanos a suplicar a Mart\u00edn el <em>Humano<\/em> la concesi\u00f3n de un privilegio similar contra la intrusi\u00f3n de los religiosos murcianos.<\/p>\n<p>Tambi\u00e9n explicaban los oriolanos en el instrumento c\u00f3mo hab\u00edan evolucionado las relaciones con Murcia tras la uni\u00f3n de las Coronas por los Reyes Cat\u00f3licos. Dec\u00edan que a ra\u00edz de tal hito hist\u00f3rico, obviamente, cesaron las guerras entre las monarqu\u00edas, pero que las malas voluntades hab\u00edan persistido, \u00ab<em>raelades<\/em>\u00bb, enraizadas en los corazones de los habitantes de las dos ciudades. Y que los murcianos hab\u00edan hecho uso, o abuso, de las atribuciones espirituales del obispo, el provisor y del cabildo de Cartagena para perjudicar a sus vecinos oriolanos. Y recordaban las controversias suscitadas por los excesos de D. Juan Daza, durante su corto pontificado, o los m\u00faltiples agravios que sufr\u00edan los habitantes de la ciudad del Bajo Segura cada vez que ten\u00edan que desplazarse a Murcia con la necesidad de pleitear en los tribunales de la curia episcopal o de la Inquisici\u00f3n, y que en buena parte de las ocasiones les hac\u00edan preferir perder los casos por incomparecencia<sup>113<\/sup>.<\/p>\n<p>Y conclu\u00edan explicando que Fernando el <em>Cat\u00f3lico<\/em> conoc\u00eda bien la problem\u00e1tica, y que a fin de lograr la tranquilidad de sus reinos, y de observar los privilegios concedidos por sus antecesores, suplic\u00f3 a Julio II la creaci\u00f3n del obispado de Orihuela y su uni\u00f3n can\u00f3nica \u00ab<em>sub uno pastore<\/em>\u00bb con el de Cartagena. Y que despu\u00e9s de que el sumo pont\u00edfice procediese a la fundaci\u00f3n, los murcianos hab\u00edan apelado contra ella, y el Pleito a\u00fan segu\u00eda pendiente, a pesar de sus m\u00faltiples cambios y virajes.<\/p>\n<p>Por todo ello, Gil G\u00f3mez, en representaci\u00f3n del clero y el pueblo de Orihuela, le record\u00f3 a D. Pedro Maza que en el momento de su nombramiento como gobernador hab\u00eda jurado conservar los privilegios de la ciudad, y le pidi\u00f3 que no consintiese la ejecuci\u00f3n del breve revocatorio del 14 de octubre del a\u00f1o anterior, que siguiese los dictados reales manifestados en la orden del 23 de septiembre, y que le escribiese a Carlos I explic\u00e1ndole el estado verdadero de la causa, y reconociendo la justicia de las alegaciones oriolanas.<\/p>\n<p>El gobernador decidi\u00f3 guardar las formas y declin\u00f3 responder al s\u00edndico oriolano, por lo que \u00e9ste volvi\u00f3 a intervenir para quejarse de que hubiese tomado medidas para que los cartaginenses pudiesen publicar los breves de Clemente VII a las autoridades civiles y eclesi\u00e1sticas de la ciudad, arguyendo que sus representados hab\u00edan apelado contra la validez de los rescriptos por haber sido obtenidos de modo subrepticio, y no deb\u00edan ser notificados hasta que el recurso fuese sentenciado. Por ello, G\u00f3mez le requiri\u00f3 a Maza que echase marcha atr\u00e1s y consultase a Su Majestad antes de proceder a la ejecuci\u00f3n de la provisi\u00f3n real, y a la consiguiente presentaci\u00f3n de las bulas pontificias<sup>114<\/sup>.<\/p>\n<p>Ante la nueva petici\u00f3n oriolana, los procuradores murcianos reiteraron al gobernador su inter\u00e9s por que los reales mandatos fueran puestos en ejecuci\u00f3n y le solicitaron de nuevo que les permitiese publicar los breves<sup>115<\/sup>.<\/p>\n<ol>\n<li>Pedro Maza decidi\u00f3 no dar respuesta alguna a los requirentes, y los emplaz\u00f3 para el d\u00eda siguiente.<\/li>\n<\/ol>\n<p>El 6 de octubre, compareci\u00f3 ante \u00e9l un nuevo s\u00edndico de Orihuela, el notario Bernardo Manresa, quien le indic\u00f3 que Carlos I no deseaba en modo alguno que la ciudad del Bajo Segura fuese perjudicada en sus derechos. Y le dijo que no ten\u00eda ning\u00fan poder para forzar al cap\u00edtulo del Salvador a comparecer ante \u00e9l, pues no ten\u00eda ninguna jurisdicci\u00f3n sobre los citados eclesi\u00e1sticos. E incidiendo en esta \u00faltima afirmaci\u00f3n, le se\u00f1al\u00f3 que procediendo de tal manera hab\u00eda favorecido considerablemente a los murcianos<sup>116<\/sup>.<\/p>\n<p>Y seguidamente, fue Gil G\u00f3mez quien persever\u00f3 en las quejas<sup>117<\/sup>. Le pidi\u00f3 que antes de permitir la notificaci\u00f3n de los rescriptos, remitiese a las partes ante el emperador, para que \u00e9ste, conociendo la verdad de los hechos, remediara a la ciudad de Orihuela, y acallara a los murcianos. Y para intentar convencerle, le record\u00f3 las \u00faltimas manifestaciones de la malevolencia murciano-cartaginense:<\/p>\n<p>-Los desbordamientos del r\u00edo que, por las inundaciones en unas partes, y por la falta de riego en otras, hab\u00edan echado a perder las cosechas de trigo y de otros productos del campo, y hab\u00edan obligado a las autoridades municipales a recurrir a la importaci\u00f3n de trigo castellano para el abastecimiento de la ciudad, entrando en contradicci\u00f3n con el famoso dicho popular: \u00ab<em>ploga o no ploga forment hi ha en Oriola<\/em>\u00bb.<\/p>\n<p>-Y el ataque del marqu\u00e9s de los V\u00e9lez en la Navidad de 1518.<\/p>\n<p>Por fin, el s\u00e1bado 7 de octubre, D. Pedro Maza se pronunci\u00f3, y lo hizo, como era de prever, en favor de Orihuela. Tras una err\u00f3nea -o m\u00e1s bien, parcial- argumentaci\u00f3n, fundada en el hecho de que, desde su punto de vista, la verdadera intenci\u00f3n del emperador era que no se causara perjuicio a ninguna de las partes<sup>118<\/sup>, decidi\u00f3 impedir la notificaci\u00f3n de los breves revocatorios, y tras valorar la arduidad del pleito -tanto por la calidad de la causa como por la de los litigantes- y la s\u00f3lida apelaci\u00f3n oriolana -apoyada en la presentaci\u00f3n de un gran n\u00famero de documentos, bulas apost\u00f3licas y privilegios reales-, y prestar atenci\u00f3n a otras muchas razones -algunas tan aparentemente f\u00fatiles como el hecho de ser m\u00e1s decente otorgar que denegar-, remiti\u00f3 a ambas partes a Su Majestad y a sus Consejos de Castilla y Arag\u00f3n<sup>119<\/sup>.<\/p>\n<p>Acto seguido, incr\u00e9dulos, los procuradores murcianos volvieron a insistir al gobernador que cumpliese los mandatos reales. Pero todos sus intentos fueron vanos. D. Pedro Maza ya hab\u00eda tomado su decisi\u00f3n y se mostr\u00f3 inflexible<sup>120<\/sup>.<\/p>\n<p>Los d\u00edas siguientes, las autoridades oriolanas se afanaron por recopilar la documentaci\u00f3n necesaria para poder convencer a Carlos I de la legitimidad de sus aspiraciones episcopales. Tambi\u00e9n debatieron sobre la persona que ser\u00eda m\u00e1s adecuada para presentar las argumentaciones, y decidieron encargar tal tarea al doctor Mart\u00edn Ruiz de Mendoza, al cual le redactaron una cumplida procura. Por fin, el 25 de octubre, terminaron los preparativos, le entregaron a Ruiz el compendio alegatorio y una carta de creencia para el Consejo de Arag\u00f3n, y el embajador parti\u00f3 en direcci\u00f3n a la corte<sup>121<\/sup>.<\/p>\n<ol start=\"7\">\n<li><strong> Las represalias murcianas.<\/strong><\/li>\n<\/ol>\n<p>Las embajadas del can\u00f3nigo Jaime G\u00f3mez Daroca y del doctor Mart\u00edn Ruiz de Mendoza, en relaci\u00f3n con el Pleito del Obispado, volvieron a poner a las autoridades seculares de Orihuela en apuros econ\u00f3micos. Los gastos derivados de ambas, unidos a la importante cantidad de dinero que el <em>Consell<\/em> le adeudaba a Luis Mart\u00ednez por su larga estancia en la corte real, llevaron al citado organismo municipal a tomar una nueva medida, que no debi\u00f3 agradar mucho a la poblaci\u00f3n de la ciudad. El 1 de noviembre, los <em>consellers<\/em> aprobaron el incremento del precio de la carne, de 13 a 14 libras, a fin de que la libra impuesta fuese utilizada para sufragar los gastos de la causa episcopal. Dicha subida tendr\u00eda vigor, en principio, hasta finales del mes de octubre del a\u00f1o siguiente -1526-<sup>122<\/sup>.<\/p>\n<p>Vemos, pues, que cuando los mun\u00edcipes no ten\u00edan pecunias con las que afrontar los elevados dispendios derivados de la lite, buscaban r\u00e1pidamente los medios para obtenerlas. Con anterioridad tuvimos la oportunidad de comprobar otras soluciones al problema: la carga de censales y la petici\u00f3n de pr\u00e9stamos a particulares o a las propias f\u00e1bricas de las iglesias de las localidades de su t\u00e9rmino.<\/p>\n<p>Dos d\u00edas despu\u00e9s, decidieron utilizar el dinero del que pod\u00edan disponer para satisfacer la deuda que ten\u00edan con el mencionado can\u00f3nigo Luis Mart\u00ednez, por los nueve meses que hab\u00eda estado en la corte real, representando con eficiencia los intereses de la ciudad. Por ello, encargaron a Bartolom\u00e9 Cascant y a Vicente Mart\u00ed que revisasen las cuentas del antiguo procurador, para conocer a ciencia cierta la cuant\u00eda del d\u00e9bito<sup>123<\/sup>.<\/p>\n<p>El 5 de noviembre parti\u00f3, por fin, de Alicante el s\u00edndico Jaime G\u00f3mez Daroca en direcci\u00f3n hacia Roma<sup>124<\/sup>.<\/p>\n<p>Y el d\u00eda siguiente -6-, Bartolom\u00e9 Cascant le entreg\u00f3 a Luis Mart\u00ednez 110 libras, zanjando casi por completo la deuda municipal<sup>125<\/sup>.<\/p>\n<p>Ese mismo d\u00eda circul\u00f3 por la ciudad la noticia de que fr. Mart\u00edn de Molina, ministro del monasterio de la Sant\u00edsima Trinidad de Murcia, en calidad de ejecutor apost\u00f3lico, hab\u00eda publicado en Cartagena y Abanilla un proceso monitorio en el que mandaba al cap\u00edtulo del Salvador y al <em>Consell<\/em>, so pena de excomuni\u00f3n, que en un breve plazo de tiempo enviasen a sus procuradores a comparecer ante \u00e9l, al tiempo que acusaba a las citadas autoridades eclesi\u00e1sticas y seglares de rebeld\u00eda y contradicci\u00f3n de los mandatos apost\u00f3licos, por su negativa a aceptar la ejecuci\u00f3n de los breves de Clemente VII.<\/p>\n<p>Ante la promulgaci\u00f3n del edicto, el cap\u00edtulo y el <em>Consell<\/em> se pusieron de acuerdo para apelar contra \u00e9l y contra el propio ejecutor. De esta manera, decidieron nombrar procurador de las dos corporaciones a un mismo hombre, y el elegido fue el notario Andr\u00e9s Arnal, quien se habr\u00eda de encargar de presentar los recursos. Arnal fue designado s\u00edndico municipal para tal efecto el mismo 6 de noviembre<sup>126<\/sup>. Y dos d\u00edas despu\u00e9s -el 8-, los capitulares le hicieron una procura similar, convirti\u00e9ndole en su representante.<\/p>\n<p>El 9 de noviembre los mandatarios le pidieron a Arnal que hiciese efectiva la apelaci\u00f3n. No obstante, teniendo en cuenta que el acceso a fr. Mart\u00edn de Molina no era nada seguro, y que tanto su vida como la del notario Bernardo Manresa, que hab\u00eda de acompa\u00f1arle para dar fe escrita de la interposici\u00f3n de la protesta, corr\u00edan serio peligro si trataban de comparecer ante el ejecutor, le prepararon dos escritos de contenido similar. Uno -duplicado- que habr\u00eda de fijar en las puertas de los monasterios de San Francisco y de San Blas -el citado ministro viv\u00eda en este \u00faltimo establecimiento trinitario-, y que afortunadamente estaban situados fuera de los muros de la ciudad. Y otro que tendr\u00eda que presentar a varios religiosos de la ciudad, para asegurarse de que la apelaci\u00f3n fuese tramitada a la Santa Sede en el caso de que Molina denegase el recurso a \u00e9l presentado de tan peculiar manera.<\/p>\n<p>As\u00ed, Arnal y Manresa marcharon a Murcia, acompa\u00f1ados por dos testigos de Orihuela -Juan Litr\u00e1 y Juan Sanz-. Una vez llegaron al referido monasterio, el s\u00edndico le pidi\u00f3 al notario que procediese a la lectura de la apelaci\u00f3n, para que pudiese darla por notificada -aunque resulte, quiz\u00e1, algo absurdo-.<\/p>\n<p>En ella, las autoridades oriolanas le se\u00f1alaron, en primer lugar, a Molina que sus procuradores no pod\u00edan comparecer ante \u00e9l sin poner en peligro sus vidas, y que, por ello, le presentaban de esa forma la protesta. Despu\u00e9s, le comunicaron que hac\u00eda poco se hab\u00edan enterado de la existencia de su proceso monitorio, y que consideraban que ni dicho proceso ni las \u00f3rdenes en \u00e9l incluidas ten\u00edan validez alguna, puesto que el breve que le hab\u00eda de facultar para adoptar tales medidas carec\u00eda, asimismo, de validez por haber sido obtenido de modo subrepticio.<\/p>\n<p>Y tras esta explicaci\u00f3n, someti\u00e9ndose a la protecci\u00f3n del sumo pont\u00edfice, apelaron a la Santa Sede contra los breves revocatorios de Clemente II y contra todos los rescriptos apost\u00f3licos que perjudicasen los intereses episcopales oriolanos; contra la condici\u00f3n de ejecutor del propio Molina -por la aludida irregularidad del breve de comisi\u00f3n-, contra sus letras monitorias y sus mandatos, y contra todas las \u00f3rdenes y decretos que pudiese promulgar en el futuro en virtud de dicho escrito pontificio; y, finalmente, contra todos los agravios que hubiesen sufrido o les fuesen a ser causados en un futuro, por la causa de la fundaci\u00f3n del obispado.<\/p>\n<p>Adem\u00e1s, le solicitaron al ministro trinitario que no comenzase a contabilizar el tiempo establecido en el monitorio como plazo para la comparecencia hasta que la apelaci\u00f3n fuese sentenciada.<\/p>\n<p>Y, por \u00faltimo, le rogaron que admitiese el recurso y les diese la licencia, los ap\u00f3stolos reverenciales necesarios para tramitar la apelaci\u00f3n a la Curia romana.<\/p>\n<p>Tras la curiosa \u00abnotificaci\u00f3n\u00bb del contenido de la escritura, Arnal le requiri\u00f3 a Manresa que la fijase en las puertas del citado monasterio de San Blas, de modo que tanto fr. Mart\u00edn de Molina como el cabildo de Cartagena pudiesen tener noticia de su interposici\u00f3n. El notario satisfizo la petici\u00f3n del s\u00edndico, clav\u00f3 la protesta, y dio fe p\u00fablica de lo sucedido. Y despu\u00e9s, la expedici\u00f3n oriolana volvi\u00f3 a la ciudad del Bajo Segura<sup>127<\/sup>.<\/p>\n<p>Una vez all\u00ed, ese mismo d\u00eda 9, Andr\u00e9s Arnal compareci\u00f3 ante fr. Juan Ordibel y fr. Juan Carmenso. Les habl\u00f3 de las letras monitorias del ejecutor Molina. Les explic\u00f3 los perjuicios que les supon\u00edan a sus representados en relaci\u00f3n con el Pleito del Obispado. Les comunic\u00f3 que acababa de interponer un recurso ante el propio Molina, pero fij\u00e1ndolo en las puertas del monasterio en el que resid\u00eda por el peligro que conllevaba reconocer p\u00fablicamente en Murcia su condici\u00f3n de procurador de las autoridades de Orihuela. Y les present\u00f3 la segunda apelaci\u00f3n, cuyo tenor era pr\u00e1cticamente igual al de la primera.<\/p>\n<p>Y finalmente, les solicit\u00f3 que admitiesen el recurso, y que les concediesen al cap\u00edtulo del Salvador y al <em>Consell<\/em> de Orihuela los ap\u00f3stolos dimisorios o reverenciales para poder tramitarlo a la Santa Sede. Ordibel y Carmenso aceptaron la apelaci\u00f3n, pero aplazaron por unos d\u00edas la entrega de los ap\u00f3stolos, hasta confirmar que fr. Mart\u00edn de Molina, como era de prever, hab\u00eda denegado el recurso que Arnal le acababa de presentar<sup>128<\/sup>.<\/p>\n<p>Por otra parte, pocos d\u00edas despu\u00e9s de la boda de Carlos I con la Infanta D\u00aa. Isabel de Portugal<sup>129<\/sup>, el 13 de noviembre Mart\u00edn Ruiz de Mendoza present\u00f3 al Consejo de Arag\u00f3n el compendio legitimador de las aspiraciones episcopales oriolanas<sup>130<\/sup>.<\/p>\n<p>Y aunque la situaci\u00f3n en la corte comenzaba a ser favorable, en la ciudad del Bajo Segura volvieron a vivirse momentos de extrema tensi\u00f3n. Por aquellas, fechas, el ejecutor Molina deneg\u00f3 la apelaci\u00f3n presentada el 9 de noviembre, y una vez pasado el plazo fijado en su monitorio, decret\u00f3 la excomuni\u00f3n de todos los componentes del cap\u00edtulo del Salvador y del <em>Consell<\/em>. Pero lo realmente grave vino despu\u00e9s. Como represalia por no haber permitido la ejecuci\u00f3n de los breves de Clemente VII, el 18 de noviembre, los murcianos, instigados por el cabildo de Cartagena, volvieron a desbordar el r\u00edo Segura por el cauce artificial, causando da\u00f1os y p\u00e9rdidas de tal consideraci\u00f3n que ni siquiera los centenares de damnificados supieron valorar<sup>131<\/sup>.<\/p>\n<p>Entonces, las autoridades civiles y eclesi\u00e1sticas de la ciudad decidieron que el eminente Luis Mart\u00ednez, que se hallaba dentro del amplio conjunto de perjudicados, se desplazase a la corte para informar al emperador del suceso. Y decidieron interponer nuevas apelaciones.<\/p>\n<p>No obstante, en primer lugar, le pidieron al s\u00edndico Andr\u00e9s Arnal que volviese a solicitar a los reverendos Ordibel y Carmenso que les concediesen los ap\u00f3stolos necesarios para tramitar el recurso presentado el referido d\u00eda 9. El 24 de noviembre Arnal hizo la gesti\u00f3n, y los dos cl\u00e9rigos regulares no dudaron en entregarles la citada licencia<sup>132<\/sup>.<\/p>\n<p>Y el d\u00eda siguiente, el cap\u00edtulo del Salvador y el <em>Consell<\/em> le entregaron al procurador una nueva apelaci\u00f3n para la Santa Sede a fin de que la interpusiese ante los mismos frailes.<\/p>\n<p>En ella, protestaron contra la denegaci\u00f3n de la apelaci\u00f3n por parte del ejecutor, y contra la imposici\u00f3n de las excomuniones. Alegaron que se hallaban pendientes de resoluci\u00f3n en Roma dos cuestiones planteadas en el recurso aceptado del 9 de noviembre: la validez del breve de Clemente VII por su origen obrepticio y, por tal motivo, la legitimidad del nombramiento de fr. Mart\u00edn de Molina como su ejecutor. Explicaron que hasta que ambos puntos fuesen determinados en la Curia apost\u00f3lica, el ministro trinitario no pod\u00eda intervenir de ninguna manera, ni denegando apelaciones, ni imponiendo censuras eclesi\u00e1sticas o de cualquier otro tipo, y que si lo hac\u00eda, sus disposiciones, edictos o mandatos carecer\u00edan por completo de valor, y no habr\u00edan de ser obedecidos. Y para acabar, protestaron preventivamente contra los agravios que en el futuro Molina o cualquier otro ejecutor les pudiese causar.<\/p>\n<p>Tras mostrarles la escritura, Arnal solicit\u00f3 a Ordibel y Carmenso que la admitiesen, y que les concediese a sus representados la licencia para enviarla a Roma. Y los dos regulares le respondieron que le dar\u00edan su respuesta en dos d\u00edas, el 27 de noviembre<sup>133<\/sup>.<\/p>\n<p>El d\u00eda siguiente -26-, tres representantes de los damnificados por la riada, fr. Pedro Rocamora -quien, recordemos, era comendador del monasterio de la Merced-, Pedro Ferr\u00e1ndez de Mesa y Francisco Mons\u00ed de Casta\u00f1eda, comparecieron ante el <em>Consell<\/em> para informar a los ediles de los da\u00f1os causados por los murcianos, presentar una protesta contra su vand\u00e1lico comportamiento, pedir soluciones y reclamar justicia.<\/p>\n<p>Los referidos portavoces comentaron a los <em>consellers<\/em> que los capitulares de Cartagena, \u00ab<em>moguts de malictia<\/em>\u00bb, enviaron a \u00ab<em>molta gent de nit, a ora captada<\/em>\u00bb, y con su ayuda abrieron el \u00ab<em>portell<\/em>\u00bb y giraron el curso del r\u00edo, \u00ab<em>destroynt moltes vidues, pubils e miserables persones, e altres principals e persones de be<\/em>\u00bb, as\u00ed como \u00ab<em>la major part de la terra<\/em>\u00bb. Y tras manifestarles que, como \u00ab<em>bons fills de la patria<\/em>\u00bb, estaban \u00ab<em>pronptes e aparellats a perdre la vida e bens per defendre la catredal<\/em>\u00bb, y \u00ab<em>les libertats y honra de la terra<\/em>\u00bb, les pidieron que tomasen las medidas oportunas para que se remediase la da\u00f1ina situaci\u00f3n, \u00ab<em>per lo be e profit general<\/em>\u00bb, \u00ab<em>prenent exemple dels romans<\/em>\u00bb<sup>134<\/sup>, \u00ab<em>perque fentse de altra manera, los que voldran esser bons rebran dan e seran destroyts, y altres se riuran de ells<\/em>\u00bb, \u00ab<em>y en lo hospital los hauran de governar<\/em>\u00bb. Tambi\u00e9n les pidieron licencia \u00ab<em>per a poder fer arosos en ses eretats<\/em>\u00bb, puesto que el r\u00edo hab\u00eda ahogado los otros cereales cultivados. Y, por \u00faltimo, les solicitaron que el embajador Mart\u00ednez diese cumplida relaci\u00f3n de estos desmanes al emperador.<\/p>\n<p>Y el justicia, los jurados y los <em>consellers<\/em> accedieron a las demandas de los damnificados, y acordaron que tanto Jaime G\u00f3mez Daroca como el can\u00f3nigo Luis Mart\u00ednez suplicasen a Clemente VII y a Carlos I que pusiesen remedio a la lesiva situaci\u00f3n propiciada por el Pleito del Obispado<sup>135<\/sup>.<\/p>\n<p>El d\u00eda siguiente -27 de noviembre-, cumpliendo con la formalidad, Ordibel y Carmenso concedieron los ap\u00f3stolos reverenciales a la apelaci\u00f3n presentada dos d\u00edas antes, y las autoridades oriolanas la remitieron a Roma<sup>136<\/sup>.<\/p>\n<p>Y para que fr. Mart\u00edn de Molina no pudiese alegar ignorancia, dos d\u00edas despu\u00e9s, el pen\u00faltimo de noviembre, Andr\u00e9s Arnal volvi\u00f3 a desplazarse hasta el monasterio de San Blas, para notificar simb\u00f3licamente la \u00faltima apelaci\u00f3n y fijarla en las puertas de dicho edificio<sup>137<\/sup>.<\/p>\n<p>El d\u00eda siguiente -30-, el <em>Consell<\/em> volvi\u00f3 a reunirse para tratar la cuesti\u00f3n de la inundaci\u00f3n, y tom\u00f3 dos nuevas decisiones. Por una parte, concedi\u00f3 poder al justicia y a los jurados para que pudiesen tomar las medidas que estimasen oportunas para remediar los m\u00faltiples da\u00f1os causados, sin que tuviesen necesidad de consultar previamente a la citada asamblea municipal. Y por otra, cambiaron ligeramente de planes en relaci\u00f3n con la embajada de Luis Mart\u00ednez a la corte real. Decidieron que antes de marchar para Toledo, pasase por Valencia, le contase lo sucedido a D\u00aa. Germana de Foix, y le pidiese que mediase ante el emperador para que tuviese misericordia de los afectados y atendiese las s\u00faplicase oriolanas \u00ab<em>en benefici e repos<\/em>\u00bb de su ciudad<sup>138<\/sup>.<\/p>\n<p>El 2 de diciembre, las autoridades civiles de la ciudad le entregaron a Luis Mart\u00ednez las instrucciones que hab\u00eda de seguir en su comparecencia ante Carlos I. A continuaci\u00f3n, teniendo en cuenta su indudable inter\u00e9s, intentaremos reproducirlas con la mayor fidelidad posible al texto original.<\/p>\n<p>En primer lugar, a modo de recordatorio, el procurador, asistido por Mart\u00edn Ruiz de Mendoza, ten\u00eda que informarle al monarca de que, tras la erecci\u00f3n catedralicia de la iglesia del Salvador, \u00ab<em>per destrohir e despoblar<\/em>\u00bb Orihuela, \u00ab<em>ab la enemiga e mala volentat que ab antiquo sta raelada en los abitadors de la dita ciutat de Murcia, induhits del sperit maligne<\/em>\u00bb, rompieron el \u00ab<em>quexer<\/em>\u00bb del Segura \u00ab<em>a despesa de la ciutat e capitol de Cartagena, ab pales e altres instruments, e ab taladres feren un nou riu maior e mes fons, que no es lo alveo del dit riu<\/em>\u00bb, y por \u00e9l giraron el Segura \u00ab<em>en temps de ayguaduyts e avengudes de aygues de Castella<\/em>\u00bb, causando los \u00faltimos a\u00f1os grand\u00edsimos da\u00f1os en las tierras de cultivo de Orihuela, \u00ab<em>ofegant los blats<\/em>\u00bb, \u00ab<em>destrohint les vinyes e altres splets<\/em>\u00bb, e incluso llegando a matar a \u00ab<em>vidues, pubils e miserables persones<\/em>\u00bb. Tambi\u00e9n ten\u00eda que comentarle que, pese a que muchas veces los damnificados les hab\u00edan rogado a los murcianos que cerrasen el \u00ab<em>quexer<\/em>\u00bb, hasta que el provisor y el cabildo de Cartagena tomaron posesi\u00f3n de la iglesia del Salvador, il\u00edcitamente, \u00ab<em>per for\u00e7a de armes<\/em>\u00bb, \u00ab<em>jamay lo tancaren<\/em>\u00bb.<\/p>\n<p>Despu\u00e9s, Mart\u00ednez ten\u00eda que ponerle al corriente de los \u00faltimos acontecimientos acaecidos el 18 de noviembre. Hab\u00eda de contarle que, a ra\u00edz del fracaso cartaginense en la ejecuci\u00f3n de los breves de Clemente VII, \u00ab<em>los regidors de Murcia e capitulars del capitol de Cartagena<\/em>\u00bb, por \u00ab<em>la passio quels ha mogut e mou a voler fer dan a la dita ciutat<\/em>\u00bb de Orihuela, al ver llegar una avenida de agua, \u00ab<em>de nit, a ora captada<\/em>\u00bb, abrieron el \u00ab<em>portell<\/em>\u00bb, y utilizando diversos \u00ab<em>aparells<\/em>\u00bb giraron por completo el r\u00edo hacia las heredades de los oriolanos, \u00ab<em>destrohint los sembrats<\/em>\u00bb, \u00ab<em>mostrant tanta enemiga envers aquesta ciutat que jamay en temps de moros se intenpta, e en temps que les dites dos ciutats eren de diversos reys, stant en guerra uberta los reys de Arago e Castella, ab gents en lo camp, senyaladament lo Rey Don Pedro tenint cercada la ciutat de Oriola set anys ab tota sa crueldat, nos troba que tal manas fer com aquests han fet a causa del pleyt<\/em>\u00bb.<\/p>\n<p>Y a continuaci\u00f3n, tendr\u00eda que ponerle de manifiesto la actitud pacifista que en todo momento hab\u00edan mostrado el justicia y los jurados de la ciudad del Bajo Segura, puesto que, por una parte, evitaron una tragedia, si cabe, de mayores proporciones que la propiciada por la inundaci\u00f3n, ya que tanto \u00ab<em>los dapnificats com altres particulars stigueren moguts per anar a rompre lo malequo de Murcia e destrohir e avisar la dita ciutat<\/em>\u00bb, y los citados oficiales los detuvieron \u00ab<em>per no causar algunes revolucions en aquestes regnes<\/em>\u00bb<sup>139<\/sup>; y por otra, impidieron que se produjesen \u00ab<em>moltes morts e scandols<\/em>\u00bb, al prohibir a los oriolanos que fuesen a cerrar el \u00ab<em>portell<\/em>\u00bb.<\/p>\n<p>Y despu\u00e9s hab\u00eda de suplicarle al monarca \u00ab<em>ab totes ses forces<\/em>\u00bb y con \u00ab<em>grandissima diligencia<\/em>\u00bb que, para evitar que se agravasen las discordias entre ambas ciudades, \u00ab<em>en deservey de Sa Magestat<\/em>\u00bb, y que \u00e9stas degeneraran en enfrentamientos armados de mayor consideraci\u00f3n, mandase proveer los remedios que estimase m\u00e1s oportunos con la mayor brevedad. Y al respecto hab\u00eda de elevarle una propuesta triple:<\/p>\n<p>-Que ordenase a los murcianos que cerrasen el \u00ab<em>portell<\/em>\u00bb y no lo volviesen a abrir.<\/p>\n<p>-Que juzgase debidamente el delito cometido, teniendo en consideraci\u00f3n todas las p\u00e9rdidas humanas y materiales causadas.<\/p>\n<p>-Y que ya que el cabildo de Cartagena hab\u00eda financiado la mal\u00e9vola obra, mandase compensar los da\u00f1os producidos con las rentas eclesi\u00e1sticas que dicho organismo colegiado cartaginense percib\u00eda en la Gobernaci\u00f3n del Reino de Valencia m\u00e1s all\u00e1 de Jijona.<\/p>\n<p>Y, por \u00faltimo, los mun\u00edcipes le hicieron al can\u00f3nigo dos advertencias. <em>Ex una<\/em>, le indicaron que en el caso de que los murcianos arguyesen que desviaron el curso del r\u00edo para evitar que \u00ab<em>les cregudes<\/em>\u00bb llegasen a afectar a la ciudad, les replicase que Murcia estaba tres leguas por encima del \u00ab<em>riacho<\/em>\u00bb, y que, por tanto, dif\u00edcilmente pod\u00edan causarles perjuicios las avenidas.<\/p>\n<p>Y <em>ex alia<\/em>, si Carlos I decid\u00eda encomendar la investigaci\u00f3n del delito al corregidor de Murcia, le se\u00f1alaron que alegara que los oriolanos no podr\u00edan acceder a dicha ciudad sin que sus vidas corriesen un serio peligro, y que le suplicase a Su Majestad que cometiese el estudio del caso al referido corregidor y al gobernador de Orihuela, para que ambos determinasen la cuesti\u00f3n conjuntamente, contando con el consejo de sus asesores<sup>140<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s, el 4 de diciembre, le entregaron a Luis Mart\u00ednez otro pliego de documentos, conformado por diferentes cartas, instrumentos y c\u00e9dulas de cambio, para que cuando llegase a la corte se los enviase a Roma al can\u00f3nigo G\u00f3mez, y \u00e9ste pudiese incluir nuevos argumentos en sus alegaciones. Y el d\u00eda siguiente -martes 5- el procurador parti\u00f3 en direcci\u00f3n a Toledo<sup>141<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el 15 de ese mismo mes, las autoridades de la ciudad decidieron tramitar una nueva apelaci\u00f3n a la Santa Sede perseverando en sus protestas anteriores contra fr. Mart\u00edn de Molina, y para demostrar que interpondr\u00edan tantos recursos como fuesen necesarios a fin de preservar indemnes e intactos sus derechos episcopales<sup>142<\/sup>.<\/p>\n<p>Tres d\u00edas despu\u00e9s, el 18, el justicia y los jurados consideraron necesario reforzar la representaci\u00f3n oriolana en la corte real y decidieron nombrar a un nuevo procurador, con el fin de que asistiese al doctor Mart\u00edn Ruiz de Mendoza y al can\u00f3nigo Luis Mart\u00ednez en las negociaciones relacionadas con las inundaciones. El elegido fue otro de los damnificados, Nicol\u00e1s de Molins<sup>143<\/sup>, a quien el 23 de diciembre le entregaron un par de cartas de creencia dirigidas al can\u00f3nigo Mart\u00ednez y a Carlos I, y le ordenaron que se pusiese en camino para Toledo<sup>144<\/sup>.<\/p>\n<p>Mientras tanto, en la ciudad castellana las gestiones de los s\u00edndicos oriolanos surtieron efectos casi insospechados. Un d\u00eda antes de que partiese Molins, el emperador tom\u00f3 una resoluci\u00f3n al respecto de las alegaciones presentadas por Mart\u00edn Ruiz de Mendoza tras el intento cartaginense de ejecuci\u00f3n de los breves de Clemente VII. Por v\u00eda del Consejo de Arag\u00f3n, les envi\u00f3 una carta favorabil\u00edsima al justicia, los jurados y el <em>Consell<\/em> de Orihuela. En ella, les comunic\u00f3 que hab\u00edan actuado adecuadamente al consultarle sobre la legitimidad de los citados rescriptos. Les pidi\u00f3 que procediesen de la misma manera siempre que se suscitase alguna novedad concerniente al Pleito del Obispado, a menos que la orden procediese de su mano o de los doctores de los Consejos de Arag\u00f3n y de Castilla. Les declar\u00f3 que s\u00ed pretend\u00eda que la cuesti\u00f3n episcopal se resolviese de modo justo, y con la \u00ab<em>ygualdad devida<\/em>\u00bb. Y, por \u00faltimo, les mand\u00f3 que tratasen por todos los medios de evitar que se produjesen nuevos esc\u00e1ndalos<sup>145<\/sup>.<\/p>\n<p>La misiva debi\u00f3 llegar a la ciudad del Bajo Segura durante el per\u00edodo navide\u00f1o. Y con renovadas esperanzas comenz\u00f3 el a\u00f1o 1526.<\/p>\n<ol start=\"8\">\n<li><strong> Las negociaciones ante los Consejos de Castilla y Arag\u00f3n y el caso del Beato Mart\u00ed.<\/strong><\/li>\n<\/ol>\n<p>Antes de comenzar a relatar los acontecimientos relacionados con la cuesti\u00f3n del obispado que tuvieron lugar en 1526, hemos de destacar que la falta del <em>Contestador<\/em> correspondiente a este a\u00f1o en el Archivo Municipal de Orihuela nos ha supuesto graves inconvenientes, puesto que el resto de las fuentes documentales nos ofrecen muy poca informaci\u00f3n concerniente a tal per\u00edodo, y en las bibliogr\u00e1ficas no hay una sola menci\u00f3n a los sucesos que acaecieron en el transcurso de dicho lapso temporal. \u00danicamente podemos atisbar lo que sucedi\u00f3 gracias a unas cuantas referencias indirectas, insertas en documentos posteriores.<\/p>\n<p>Nada sabemos sobre las actividades de Luis Mart\u00ednez y Nicol\u00e1s de Molins en la corte real. No hemos podido conocer si sus gestiones sirvieron para que Carlos I prohibiese al cabildo de Cartagena y a las autoridades civiles de Murcia que volviesen a provocar inundaciones en Orihuela y su distrito<sup>146<\/sup>.<\/p>\n<p>Lo que s\u00ed podemos afirmar es que tras la decisi\u00f3n de D. Pedro Maza de remitir la causa al rey, \u00e9ste cit\u00f3 a las dos partes para que compareciesen ante \u00e9l en Sevilla. Acudieron el referido can\u00f3nigo Mart\u00ednez en representaci\u00f3n de Orihuela, y un murciano llamado Pacheco como s\u00edndico del cabildo cartaginense. Carlos I encarg\u00f3 el an\u00e1lisis de la cuesti\u00f3n a los doctores Ram y May del Consejo de Arag\u00f3n, y a Pollances y Vegara del de Castilla, y todos los procesos, escritos apost\u00f3licos y dem\u00e1s actos fueron puestos en poder de los respectivos secretarios Urries y Salmer\u00f3n. Tras ser estudiados los diferentes argumentos y no hallarse ninguna soluci\u00f3n que pudiese satisfacer a ambas partes, las negociaciones quedaron temporalmente suspendidas<sup>147<\/sup>.<\/p>\n<p>Posteriormente, el monarca volvi\u00f3 a convocar a los procuradores para que acudiesen a la corte, que se hallaba en Granada. Por Murcia, volvi\u00f3 a desplazarse Pacheco, y en representaci\u00f3n de Orihuela se presentaron Vicente Mart\u00ed y Lope Ferr\u00e1ndez de Mesa, quienes contaron con la ayuda del doctor Jer\u00f3nimo Soriano<sup>148<\/sup>.<\/p>\n<p>Por otra parte, Clemente VII, perplejo por el hecho de que sus rescriptos de 1524 y 1525 no hubiesen servido para apaciguar la situaci\u00f3n entre Orihuela y Murcia, y aturdido por las contradictorias informaciones que ten\u00eda sobre el Pleito del Obispado, le mand\u00f3 a su legado en Espa\u00f1a, el cardenal de los Santos Cosme y Dami\u00e1n, m\u00e1s conocido como Salviatis, que le preguntase personalmente al Rey de Romanos y Emperador electo cu\u00e1l era su voluntad acerca de la cuesti\u00f3n.<\/p>\n<p>De esta manera, Salviatis se person\u00f3 en Granada y entabl\u00f3 conversaciones con Carlos I. Tras su llegada, los s\u00edndicos oriolanos le informaron de los derechos episcopales de sus representados, y el cardenal se comprometi\u00f3 a apoyarles en la medida de sus posibilidades<sup>149<\/sup>. Sin embargo, no tuvo ninguna oportunidad para hacerlo puesto que el rey hispano, influenciado por las presiones de los castellanos, no dud\u00f3 al comentarle que lo que realmente deseaba era que el clero y el pueblo de la ciudad del Bajo Segura permaneciesen perpetuamente bajo la jurisdicci\u00f3n del cabildo y el obispo de Cartagena, pues cre\u00eda que \u00e9sa era la \u00fanica soluci\u00f3n v\u00e1lida para lograr la paz de sus s\u00fabditos. Por ello, el legado le escribi\u00f3 al pont\u00edfice comunic\u00e1ndole la firme voluntad real. Y el propio monarca le dirigi\u00f3 un despacho suplic\u00e1ndole que hiciese efectivas todas las censuras lanzadas contra los oriolanos, que les impusiese silencio perpetuo de nuevo, que extinguiese la lite y, en fin, que tomase cualquier otro remedio oportuno para conseguir el final de las discordias y la pacificaci\u00f3n de sus reinos. Y teniendo en cuenta la informaci\u00f3n de Salviatis y, sobre todo, los propios ruegos de Carlos I, a finales de a\u00f1o Clemente VII expidi\u00f3 un nuevo rescripto apost\u00f3lico cerrando las apelaciones indecisas, ordenando la plena ejecuci\u00f3n de los breves revocatorios de la creaci\u00f3n del obispado de Orihuela, dando validez al proceso promulgado por el ejecutor fr. Mart\u00edn de Molina tras la intervenci\u00f3n de D. Pedro Maza, y agravando las penas en las que habr\u00edan de incurrir los posibles rebeldes de los mandatos apost\u00f3licos<sup>150<\/sup>.<\/p>\n<p>Mientras tanto, en la corte real, las negociaciones prosiguieron y los diputados de ambos Consejos para tratar la cuesti\u00f3n comenzaron a elaborar un instrumento concordatario que, si bien inclu\u00eda alguna concesi\u00f3n para Orihuela, beneficiaba claramente los intereses murcianos<sup>151<\/sup>.<\/p>\n<p>En Roma, el s\u00edndico oriolano Jaime G\u00f3mez se vio con las manos completamente atadas y no pudo conseguir ni una sola provisi\u00f3n pontificia favorable, lo que molest\u00f3 considerablemente a las autoridades de la ciudad del Bajo Segura<sup>152<\/sup>.<\/p>\n<p>Tambi\u00e9n a finales de 1526, surgi\u00f3 un nuevo conflicto que alert\u00f3 a los oriolanos por cuanto pudo perjudicar gravemente sus aspiraciones episcopales: el caso del \u00ab<em>Beato Mart\u00ed<\/em>\u00bb. La discordia se origin\u00f3 a ra\u00edz de la posesi\u00f3n de una capellan\u00eda de la iglesia del Salvador que detentaba el can\u00f3nigo Luis Mart\u00ednez, y que era reclamada por fr. Andr\u00e9s Mart\u00ed.<\/p>\n<p>El \u00ab<em>Beato<\/em>\u00bb, que as\u00ed era llamado de forma ir\u00f3nica, era un fraile ciertamente particular. Figuraba como uno de los caballeros m\u00e1s destacados de la ciudad, y era doctor en Leyes. Tras comprar muchos bienes temporales y realengos, y acumular considerables deudas, decidi\u00f3 ingresar en la orden de San Francisco para acogerse al fuero eclesi\u00e1stico y evitar que la justicia laica pudiese ordenarle que pagase a sus acreedores. Adem\u00e1s, confiando en la inmunidad que le proporcionaba el h\u00e1bito franciscano, quiso librarse del abono de diferentes \u00ab<em>talles<\/em>\u00bb impuestas por la ciudad como la demandada para la campa\u00f1a contra los moros alzados en la Sierra de Espad\u00e1n. Y pese a su inclinaci\u00f3n clerical, sigui\u00f3 viviendo con su esposa y sus hijos.<\/p>\n<p>Mart\u00ed, viendo que el vicario general Jaime de Soler hab\u00eda dejado de actuar como tal tras la \u00ab<em>forsosa hobediensia<\/em>\u00bb prestada a los de Murcia, y que Mart\u00ednez iba a seguir disfrutando del beneficio mientras la cuesti\u00f3n permaneciese sin resolver, decidi\u00f3 acudir al provisor del obispado de Cartagena reconociendo de esa manera, impl\u00edcitamente, su autoridad, y sin tener en cuenta para nada \u00ab<em>lo dan y perjuhi y desonrra<\/em>\u00bb que estaba causando a la Iglesia y ciudad de Orihuela en el Pleito del Obispado. El oficial le despach\u00f3 un mandato citatorio dirigido a Luis Mart\u00ednez, en el que le ordenaba que compareciese ante \u00e9l para solucionar el litigio.<\/p>\n<p>Mart\u00ed le pidi\u00f3 a un notario que le presentase la \u00ab<em>lletra judicial<\/em>\u00bb al can\u00f3nigo, pero \u00e9ste le advirti\u00f3 que si lo hac\u00eda, ocasionar\u00eda un \u00ab<em>gran y evident perjuhi y mal<\/em>\u00bb, y que propiciar\u00eda la \u00ab<em>perdicio de la esglesia de Horihola<\/em>\u00bb. Y el letrado se neg\u00f3 a notificarle la orden citatoria.<\/p>\n<p>El justicia y los jurados se enteraron del intento del \u00ab<em>Beato<\/em>\u00bb y fueron a su casa a detenerlo. No lo encontraron pues ya hab\u00eda huido, aunque s\u00ed hallaron el lesivo instrumento cartaginense y lo requisaron.<\/p>\n<p>Poco despu\u00e9s, la noticia se extendi\u00f3 por la ciudad y todos sus habitantes, incluidos \u00ab<em>los parents de aquell<\/em>\u00bb, quedaron \u00ab<em>molt escandalisats<\/em>\u00bb. Muchos caballeros, encabezados por el se\u00f1or de Albatera, se reunieron y tomaron la decisi\u00f3n de \u00ab<em>ferli algun desastre en sa persona y casa<\/em>\u00bb. Al enterarse los oficiales de esas intenciones, para evitar que los incidentes pasaran a mayores y a fin de \u00ab<em>rellevarlo que no rebes dans<\/em>\u00bb, convocaron el <em>Consell<\/em>, y el organismo municipal, \u00ab<em>ab ver de tronpeta<\/em>\u00bb, lo desterr\u00f3 p\u00fablicamente de Orihuela y su distrito por t\u00e9rmino de dos a\u00f1os. Adem\u00e1s, lo condenaron a pagar todos los gastos que tuviese que hacer la ciudad para evitar que los documentos conseguidos por \u00e9l pudiesen perjudicar los derechos e intereses de la Catedral del Salvador en la lite pendiente del Obispado. Y so pena de 500 florines prohibieron a todos los habitantes de la ciudad y su distrito que lo acogiesen en sus casas y heredades. Solamente as\u00ed pudieron calmar los \u00e1nimos<sup>153<\/sup>.<\/p>\n<p>Fr. Andr\u00e9s Mart\u00ed -lejos de considerar \u00ab<em>lo benefici<\/em>\u00bb que se le hab\u00eda hecho teniendo en cuenta el castigo que merec\u00eda seg\u00fan las autoridades oriolanas- no se dio por vencido, y con el \u00ab<em>favor del spectable compte de Holiva<\/em>\u00bb interpuso una apelaci\u00f3n ante los virreyes del Reino de Valencia, el duque de Calabria -D. Fernando de Arag\u00f3n- y su mujer, D\u00aa. Germana de Foix<sup>154<\/sup>.<\/p>\n<p>Los lugartenientes generales aceptaron el bien recomendado recurso, y el 7 de enero de 1527 cometieron la sustanciaci\u00f3n y la determinaci\u00f3n de la causa al vicecanciller de su Consejo, el doctor Jimeno P\u00e9rez de Figuerola.<\/p>\n<p>Enterado Mart\u00ed del \u00e9xito de sus diligencias, le suplic\u00f3 al juez diputado que escribiese a las autoridades civiles de Orihuela para comunicarles su comisi\u00f3n para la resoluci\u00f3n de la apelaci\u00f3n. Y Figuerola atendi\u00f3 el ruego del afectado, y les despach\u00f3 a los citados ediles una misiva en la que les informaba que habr\u00edan de comparecer ante \u00e9l en la Real Audiencia o en su domicilio particular, dentro del plazo de los seis d\u00edas siguientes a la notificaci\u00f3n del escrito, para alegar cuanto quisieren en defensa de sus derechos<sup>155<\/sup>.<\/p>\n<p>Conocedoras de la presencia del Beato Mart\u00ed en Valencia y de sus intenciones -aunque no de la comisi\u00f3n al vicecanciller-, las autoridades civiles de la poblaci\u00f3n del Bajo Segura decidieron preparar dos embajadas con el fin de impedir que consiguiese alguna provisi\u00f3n que pudiese perjudicarles en el Pleito del Obispado. De esa manera, nombraron procuradores al notario Andr\u00e9s Arnal y al can\u00f3nigo Luis Mart\u00ednez, y les asignaron dos destinos diferentes. Al primero, la capital del reino. Y al segundo, la corte del emperador.<\/p>\n<p>El 8 de enero redactaron cuatro cartas de recomendaci\u00f3n y creencia para Arnal. Al gobernador Maza le dirigieron una misiva a fin de que le entregase a Arnal algunas cartas de favor para D\u00aa. Germana de Foix, para el doctor Francisco Ros -regente del Consejo del Reino de Valencia-, y para otros personajes destacados de la corte virreinal que pudiesen ayudarle en su cometido. Y le informaron que por no estar disponibles ni Salvador ni Fernando de Loazes, iban a utilizar como asesor a su abogado en la ciudad del Turia, micer Filibert, \u00ab<em>per esser persona de lletres y de bona fama<\/em>\u00bb<sup>156<\/sup>. Al doctor Filibert, le escribieron para solicitarle que aceptase dicho cargo<sup>157<\/sup>. En tercer lugar, se dirigieron al notario Lluch Riudaura para anunciarle la misi\u00f3n de Arnal y pedirle que le ayudase en las diferentes gestiones que tuviese que realizar<sup>158<\/sup>. Y, por \u00faltimo, al doctor Ros le pidieron que no permitiese que Mart\u00ed pudiese causar mayores perjuicios a la Iglesia y la ciudad de Orihuela, y a \u00ab<em>sa honrra, la qual es propia de tot lo regne y es deu preposar a qualsevol honrra e interes particular, majorment que sera engendrar en hesta ciutat grans desaventures<\/em>\u00bb. Y le suplicaron que favoreciese los intereses oriolanos, y que auxiliase al s\u00edndico Arnal<sup>159<\/sup>.<\/p>\n<p>Tres d\u00edas m\u00e1s tarde -el 11 de enero-, los oficiales les entregaron a los dos procuradores -Mart\u00ednez y Arnal- los documentos que inclu\u00edan las instrucciones que ambos hab\u00edan de seguir en sus respectivos destinos<sup>160<\/sup>. Y poco tiempo despu\u00e9s, partieron de Orihuela<sup>161<\/sup>.<\/p>\n<p>La citatoria del vicecanciller fue notificada el 16 de enero de 1527 a Francisco de Soler, uno de los jurados, y al justicia en lo criminal del a\u00f1o anterior, Bartolom\u00e9 Mons\u00ed de Casta\u00f1eda. Ambos respondieron que acatar\u00edan la orden del juez<sup>162<\/sup>.<\/p>\n<p>Sin embargo, la corporaci\u00f3n municipal consider\u00f3 innecesario que ambos fuesen personalmente a Valencia, y les inst\u00f3 a nombrar a un procurador para que los representase ante Figuerola. Eligieron a Lluch Riudaura, y el 19 de enero le enviaron la procura y un instrumento que recog\u00eda las instrucciones que el notario deb\u00eda seguir para defenderlos. En \u00e9l, le pusieron al corriente de todos los detalles de la situaci\u00f3n creada por Mart\u00ed, le pidieron que se encargase de la causa \u00ab<em>ab summa diligencia<\/em>\u00bb y \u00ab<em>ab totes ses forses<\/em>\u00bb, y le indicaron que en el caso de que los alegatos que presentase no bastasen para conseguir una resoluci\u00f3n favorable, le solicitase al vicecanciller y a los virreyes que cometiesen una investigaci\u00f3n <em>in situ<\/em> al gobernador Maza, pues en Orihuela f\u00e1cilmente podr\u00edan ofrecerle pruebas de las actividades sediciosas del fraile franciscano. Y, por \u00faltimo le aconsejaron que consultase la cuesti\u00f3n con el doctor Pedro Luis Sans -que hab\u00eda sido recomendado por Fernando de Loazes<sup>163<\/sup>.<\/p>\n<p>El mismo correo se llev\u00f3, asimismo, otras tres cartas. Una para el referido Sans, en la que le ped\u00edan que se pusiese en contacto con Riudaura. Otra para el doctor Ros, explic\u00e1ndole el estado de la cuesti\u00f3n tras la notificaci\u00f3n de la citatoria, y rog\u00e1ndole ayuda. Y la tercera para el propio vicecanciller Figuerola, a fin de que favoreciese los intereses oriolanos en la determinaci\u00f3n de la cuesti\u00f3n<sup>164<\/sup>.<\/p>\n<p>Pese a los esfuerzos de los procuradores Arnal y Riudaura y del abogado Filibert, la resoluci\u00f3n de la causa entablada por el Beato Mart\u00ed fue retras\u00e1ndose. A principios de febrero, Arnal escribi\u00f3 a las autoridades oriolanas reclamando como decisiva la presencia en Valencia del jurado Francisco de Soler, y pidi\u00e9ndoles que escribiesen a Luis Mart\u00ednez para que consiguiese una provisi\u00f3n real favorable.<\/p>\n<p>El d\u00eda 13 de ese mismo mes, los ediles escribieron al can\u00f3nigo enviado a la corte para transmitirle el ruego de Arnal y solicitarle que cuando consiguiese el mandato de Carlos I, lo remitiese sin demora, directamente, a Valencia. Redactaron la procura para Francisco de Soler. Le dieron dos cartas de creencia y recomendaci\u00f3n: una para D. Pedro Maza, y la segunda para otro personaje importante de la corte virreinal, D. Ram\u00f3n Boh\u00edl. Y, por \u00faltimo, le entregaron dos cartas dirigidas a Andr\u00e9s Arnal y al doctor Filibert, agradeci\u00e9ndoles sus servicios y la diligencia con la que estaban llevando el caso, y pidi\u00e9ndoles que siguiesen negociando de esa forma hasta que la causa llegase a su conclusi\u00f3n<sup>165<\/sup>.<\/p>\n<p>Unos d\u00edas despu\u00e9s, Soler parti\u00f3 de Orihuela, y lleg\u00f3 a la capital del Turia la noche del 18 de febrero. De inmediato, fue con Arnal a hablar con Riudaura. Y el d\u00eda siguiente, los tres platicaron con el doctor Filibert y llegaron a la conclusi\u00f3n de que la mejor manera para acabar con la lite era convenciendo al duque de Calabria de la justicia de sus representados. Por ello, decidieron buscar nuevos aliados que estuviesen pr\u00f3ximos al virrey. Se entrevistaron con D. Luis Carroz y D. Luis Lladr\u00f3, y ambos se avinieron a interceder por Orihuela ante D. Fernando de Arag\u00f3n<sup>166<\/sup>. Y gracias a la influencia de ambos caballeros y a la habilidad de los procuradores, el Beato Mart\u00ed perdi\u00f3 la causa y tuvo que cumplir las penas impuestas por la ciudad<sup>167<\/sup>.<\/p>\n<ol start=\"9\">\n<li><strong> Nuevos roces con la Inquisici\u00f3n cartaginense y la desfavorable concordia urdida en la corte.<\/strong><\/li>\n<\/ol>\n<p>Uno de los principales cometidos encargados al can\u00f3nigo Jaime G\u00f3mez Daroca en su embajada a Roma fue la obtenci\u00f3n en la Curia de un instrumento absolutorio de las censuras eclesi\u00e1sticas impuestas sobre el clero y el pueblo de Orihuela, a causa de su oposici\u00f3n a las actividades de la Inquisici\u00f3n cartaginense en la ciudad del Bajo Segura.<\/p>\n<p>Sin embargo, G\u00f3mez no consigui\u00f3 la expedici\u00f3n de la absoluci\u00f3n. Dos factores influyeron en ello de un modo particular: la propia ineptitud del s\u00edndico -manifiesta en el hecho de que no logr\u00f3 el despacho de una sola letra apost\u00f3lica-, y la nula receptividad de Clemente VII hacia sus peticiones -propiciada por la actitud promurciana o filocastellana de Carlos I-.<\/p>\n<p>De este modo, dos a\u00f1os despu\u00e9s del enfrentamiento con Juan Y\u00e1\u00f1ez, dichas penas a\u00fan permanec\u00edan vigentes. Y a principios de marzo de 1527, las autoridades oriolanas se vieron forzados a sopesar la posibilidad de que \u00e9stas, agravadas, siguiesen teniendo vigor durante mucho tiempo.<\/p>\n<p>Por tales fechas recibieron una misiva del inquisidor y provisor del obispado de Cartagena, el licenciado Sancho V\u00e9lez, en la que les notificaba su intenci\u00f3n de presentarse en la poblaci\u00f3n del Bajo Segura para ejercer el Santo Oficio. De inmediato, los jurados le contestaron que nadie se opondr\u00eda a su labor siempre y cuando no perjudicase los intereses de la ciudad y su Iglesia en el Pleito del Obispado. Y el 8 de marzo, el provisor-inquisidor les replic\u00f3 por escrito que no deseaba m\u00e1s que ejercer el Santo Oficio, y que no pensaba \u00ab<em>prejudicar en cosa alguna, direte ni yndirete, a essa yglesia como la \u00e7ibdad, en cosa alguna circa el su litigio con la yglesiade Cartagena<\/em>\u00bb. Y les pidi\u00f3 que le facilitasen su saludable tarea espiritual<sup>168<\/sup>. Y en otra carta separada, les anunci\u00f3 que les llevar\u00eda su misiva el alguacil Alonso G\u00f3mez de la Tonilla, quien, adem\u00e1s, les pedir\u00eda de su parte que preparasen las posadas y \u00ab<em>las otras cosas ne\u00e7esarias<\/em>\u00bb para su instalaci\u00f3n y la de todos sus oficiales<sup>169<\/sup>.<\/p>\n<p>El alguacil del Santo Oficio se person\u00f3 en Orihuela dos d\u00edas despu\u00e9s -el domingo 10 de marzo-, fue al Archivo de la Lonja y les entreg\u00f3 al justicia y a los jurados las dos cartas del licenciado V\u00e9lez. Por su contenido, los ediles comprobaron, aunque no sin recelo, que el provisor-inquisidor dec\u00eda no tener intenci\u00f3n de causarles perjuicios en la lite episcopal<sup>170<\/sup>.<\/p>\n<p>Y despu\u00e9s, G\u00f3mez de la Tonilla les present\u00f3 una c\u00e9dula real dada en Granada el 7 de diciembre del a\u00f1o anterior, que iba dirigida al gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona, al justicia y los jurados de Orihuela, y a las dem\u00e1s autoridades civiles de las otras localidades de la citada demarcaci\u00f3n territorial, en la que les ordenaba que ofreciesen de modo gratuito, \u00ab<em>sin dineros<\/em>\u00bb, a los inquisidores y a sus ministros y oficiales posadas \u00ab<em>que no sean mesones<\/em>\u00bb, las ropas que necesitasen, \u00ab<em>e todas las viandas e cosas que huvieren menester<\/em>\u00bb. Y les mandaba que no diesen origen a ning\u00fan altercado o esc\u00e1ndalo, ni tampoco a retrasos o dilaciones en la asignaci\u00f3n de las posadas, como hab\u00eda sucedido en ocasiones anteriores<sup>171<\/sup>.<\/p>\n<p>Los mun\u00edcipes le respondieron al alguacil que nunca se hab\u00edan negado a se\u00f1alar los lugares de acomodo de los inquisidores, pese a que no estaban obligados a hacerlo en virtud de los fueros y privilegios del Reino, y que el monarca hab\u00eda sido informado al respecto de un modo incorrecto. Y le contestaron que antes de darle una respuesta definitiva, habr\u00edan de debatir la cuesti\u00f3n en el <em>Consell<\/em>, lo que tendr\u00eda lugar el d\u00eda siguiente, lunes 11 de marzo.<\/p>\n<p>Tras la citada asamblea, los ediles le dieron a G\u00f3mez de la Tonilla su respuesta. De entrada, le hicieron saber que Orihuela siempre hab\u00eda honrado y servido a los inquisidores, y que nunca les hab\u00edan negado la posada. Y despu\u00e9s, reiterando la condici\u00f3n de que V\u00e9lez no causase detrimento alguno a la ciudad, a los fueros y privilegios del Reino, y al Pleito del Obispado, le comunicaron que \u00ab<em>per obeyr los manaments de Sa Magestat, y encara per exal\u00e7ament de la santa fe catolica, e per favorir lo Sant Ofici y per amor del dit senyor inquisidor<\/em>\u00bb, estaban dispuestos a acogerle, y que rogar\u00edan \u00ab<em>ab totes ses forces<\/em>\u00bb a las comunidades de religiosos y a otros particulares que lo alojasen en sus residencias. Y, por \u00faltimo, le dijeron al alguacil que le comentase a su superior que se personase en Orihuela cuando quisiese, pues ser\u00eda acogido y favorecido en todo lo posible para que pudiese ejercer su santo oficio<sup>172<\/sup>.<\/p>\n<p>V\u00e9lez se enter\u00f3 con satisfacci\u00f3n de la respuesta oriolana, y tres d\u00edas despu\u00e9s, el 14 de marzo, se present\u00f3 en la poblaci\u00f3n del Bajo Segura. Comenz\u00f3 su labor purificadora utilizando un nuevo t\u00edtulo mixto -eclesi\u00e1stico y civil-, el de \u00ab<em>inquisidor del bisbat de Cartagena y del partido de Orihuela<\/em>\u00bb, que obviaba la entidad propia del obispado encabezado por esta \u00faltima ciudad, y que perjudicaba, por consiguiente, sus derechos en el Pleito.<\/p>\n<p>De inmediato, tanto los mun\u00edcipes como los capitulares del Salvador se dieron cuenta de las intenciones poco escondidas del provisor, le reclamaron que cambiase dicha intitulaci\u00f3n por la recomendada por el cardenal Adriano en 1520, la ya manida de inquisidor \u00ab<em>del regne de Murcia y guovernacio de Oriola<\/em>\u00bb. A continuaci\u00f3n, en previsi\u00f3n de futuros problemas, le advirtieron que no se le ocurriese mandar a los vecinos de la ciudad que fuesen a Murcia a proseguir las causas del Santo Oficio. Y despu\u00e9s, le comunicaron que si cumpl\u00eda esas dos condiciones, le obedecer\u00edan \u00ab<em>com a catholichs christians<\/em>\u00bb. Y que si no lo hac\u00eda, le permitir\u00edan que ejerciese su santo oficio \u00ab<em>per temor de no incurir en algunes censures eclesiastiques<\/em>\u00bb, pero interponiendo alegaciones contra todos los actos que realizase, para que no fuesen perjudicados los derechos episcopales oriolanos, y nadie pudiese alegar que hab\u00edan aceptado pertenecer al obispado de Cartagena.<\/p>\n<p>El inquisidor les dijo que ya hab\u00eda anunciado que no quer\u00eda perjudicar en nada dichos intereses episcopales<sup>173<\/sup>. Y aunque no tenemos total certeza de ello, por la falta de documentaci\u00f3n, nos inclinamos a pensar que se avino a actuar seg\u00fan las indicaciones de las autoridades oriolanas<sup>174<\/sup>.<\/p>\n<p>Poco despu\u00e9s, a principios de abril, dichos mandatarios tuvieron que hacer frente a un nuevo e important\u00edsimo contratiempo: lleg\u00f3 a la ciudad la noticia de la existencia del breve despachado por Clemente VII a los murcianos a finales del a\u00f1o anterior. Ello moviliz\u00f3 de inmediato al cap\u00edtulo del Salvador y al <em>Consell<\/em> de forma que las dos instituciones decidieron apelar conjuntamente contra el rescripto. Prepararon una escritura de protesta y le encargaron a Andr\u00e9s Arnal -que hab\u00eda sido nombrado s\u00edndico de ambas corporaciones- que la presentase ante fr. Juan Carmenso y fr. Juan Ordibel con el prop\u00f3sito de lograr los ap\u00f3stolos necesarios para poder tramitarla a la Santa Sede, lo que hizo el notario el d\u00eda 3 del mencionado mes.<\/p>\n<p>Las autoridades oriolanas apelaron contra el breve arguyendo que hab\u00eda sido obtenido de modo ileg\u00edtimo y subrepticio. En primer lugar, porque en su tenor se especificaba que Carlos I le comunic\u00f3 al cardenal Salviatis que deseaba que el cap\u00edtulo del Salvador y la ciudad de Orihuela se sometiesen a la jurisdicci\u00f3n del obispo y el cabildo de Cartagena -lo que, al parecer, era cierto-, y que quer\u00eda que el papa no les diese siquiera la oportunidad de defenderse antes de proceder a la expedici\u00f3n del documento en el que hiciese efectivos sus deseos. Los oriolanos adujeron que esta referencia a la voluntad real no pod\u00eda ser cierta puesto que entonces carecer\u00eda de sentido que, tras la intervenci\u00f3n de D. Pedro Maza, Carlos I hubiese cometido el estudio del litigio a los Consejos de Castilla y de Arag\u00f3n, y que por esas fechas -algunos meses despu\u00e9s del despacho del rescripto pontificio-, los procuradores de ambas partes a\u00fan estuviesen presentando sus argumentaciones a los doctores diputados de ambos organismos para tratar de hallar una soluci\u00f3n al Pleito. Por ello, se quejaron de que el breve hab\u00eda sido logrado obrepticiamente, esto es, enga\u00f1ando al papa con falsas informaciones, y con la complicidad del propio Consejo de Castilla, que estaba completamente de parte de las aspiraciones murcianas. Tambi\u00e9n denunciaron que el documento cuestionado hab\u00eda sido obtenido de un modo ileg\u00edtimo, puesto que hab\u00eda obviado por completo los derechos legales de Orihuela, al impedir al can\u00f3nigo G\u00f3mez, el s\u00edndico enviado a Roma, que pudiese defender los intereses de sus representados.<\/p>\n<p>Por todo ello, el cap\u00edtulo del Salvador y los oficiales municipales apelaron contra la validez del breve solicitando la protecci\u00f3n de Clemente VII y de la Santa Sede. Y para proteger a\u00fan m\u00e1s sus derechos episcopales, a\u00f1adieron al instrumento de protesta una cl\u00e1usula extraordinaria en virtud de la cual, en el caso de que el papa perseverase en su negativa de no querer escuchar las alegaciones de Jaime G\u00f3mez, y tampoco quisiese admitir el recurso por estar mal informado y pesar sobre \u00e9l las influencias castellanas, apelaban para que no les fuese causado ning\u00fan da\u00f1o por tratar de proseguir las protestas.<\/p>\n<p>Una vez Arnal termin\u00f3 de dar lectura a la apelaci\u00f3n, solicit\u00f3 a los religiosos su asentimiento. Y Ordibel y Carmenso se mostraron dispuestos a que fuera tramitada a la Curia romana, y le concedieron los ap\u00f3stolos reverenciales<sup>175<\/sup>.<\/p>\n<p>Y con la interposici\u00f3n del nuevo recurso, los mandatarios oriolanos reafirmaron su posici\u00f3n de seguir neg\u00e1ndose a prestar la obediencia al cabildo cartaginense, y a reconocer su superioridad jurisdiccional.<\/p>\n<p>Unos diez d\u00edas despu\u00e9s, recibieron, v\u00eda Valencia, una carta del s\u00edndico Luis Mart\u00ednez, que reproduc\u00eda los puntos generales de la capitulaci\u00f3n que estaba siendo urdida, en detrimento de las aspiraciones episcopales de Orihuela, por los diputados de los Consejos de Castilla y Arag\u00f3n.<\/p>\n<p>El mayor poder castellano y la influencia del rey se reflejaban en la propuesta de concordia. \u00c9sta era claramente favorable a la parte murciana. Estipulaba que el cap\u00edtulo del Salvador y la ciudad de Orihuela dispondr\u00edan de \u00ab<em>un vicari natural de la ciutat e del regne<\/em>\u00bb, y que, como compensaci\u00f3n a dicha concesi\u00f3n, habr\u00edan de abandonar el Pleito del Obispado y aceptar la autoridad del obispo, el provisor y el cabildo de Cartagena<sup>176<\/sup>.<\/p>\n<p>Adem\u00e1s, Mart\u00ednez les comunic\u00f3 a sus representados que Carlos I ya hab\u00eda hecho p\u00fablica su voluntad de que los breves de Clemente VII fuesen puestos en vigor, y que estaba decidido a expedir en breve los mandatos ejecutoriales.<\/p>\n<p>Por consiguiente, a las autoridades de la ciudad del Bajo Segura se les plante\u00f3 un serio dilema: \u00bfQu\u00e9 ser\u00eda m\u00e1s conveniente, aceptar el nombramiento del nuevo vicario general, perdiendo por completo el obispado, o proseguir con las apelaciones arriesg\u00e1ndose a quedar sin vicario y absolutamente sometidos al poder murciano?<\/p>\n<p>Pues lo que a nuestro entendimiento podr\u00eda resultar una disyuntiva de dif\u00edcil resoluci\u00f3n, a los mandatarios oriolanos -tanto civiles como eclesi\u00e1sticos- no les cre\u00f3 ni la m\u00e1s m\u00ednima duda. Estaban absolutamente seguros de lo que quer\u00edan, al igual que sus antepasados y que todos sus antecesores en los cargos y prebendas que orgullosos ocupaban. Decidieron seguir aspirando a la instituci\u00f3n perpetua del obispado.<\/p>\n<p>Tras tomar tan importante decisi\u00f3n, el 16 de abril le escribieron a Luis Mart\u00ednez una carta para comunicarle su parecer sobre los \u00ab<em>capitols<\/em>\u00bb.<\/p>\n<p>En ella, le manifestaron su determinaci\u00f3n con palabras trascendentales: le participaron que estaban todos dispuestos a \u00ab<em>perdre la vida<\/em>\u00bb antes que \u00ab<em>la honra de la patria<\/em>\u00bb, y que \u00e9sta estribaba en lograr que el obispado se convirtiese en una realidad definitiva.<\/p>\n<p>Por ello, le mandaron que le elevase a Carlos I una serie de suplicaciones. El procurador le hab\u00eda de indicar que el \u00fanico juez que ten\u00eda competencia para resolver el Pleito era el papa, por ser la causa de cariz espiritual, y le ten\u00eda que implorar, por una parte, que suspendiese cautelarmente la ejecuci\u00f3n de los breves revocatorios, por ser subrepticios y perjudiciales a los derechos legales oriolanos, y, por otra, que le escribiese imparcialmente al pont\u00edfice para que resolviese la lite atendiendo exclusivamente a los t\u00e9rminos de la justicia, y no a favores ni a falsas informaciones. Las autoridades deseaban, por consiguiente, que el litigio fuese restituido \u00ab<em>al estament que estava ans que fos revocat sens avernos oyt<\/em>\u00bb, y que antes de que el papa tomase alguna decisi\u00f3n, les permitiese defender sus intereses.<\/p>\n<p>Adem\u00e1s, le ordenaron que se negase rotundamente a aceptar la capitulaci\u00f3n, y le se\u00f1alaron que dijese que no renunciar\u00edan al obispado ni siquiera aunque los cartaginenses les concediesen \u00ab<em>deu vicariats<\/em>\u00bb, y que no firmar\u00edan nada que fuese \u00ab<em>en perjuhi e vergonya de la ciutat<\/em>\u00bb, o en contra de sus privilegios reales. Y por si a alguien le quedaba alguna duda de su inquebrantable determinaci\u00f3n, le pidieron que manifestase que antes de consentir la anulaci\u00f3n, \u00ab<em>vendran quant tenen, y quant sos bens no bastasen, enpenyarien sos fills per sostenir lo pleyt<\/em>\u00bb. Adem\u00e1s, para defender las aspiraciones episcopales, le indicaron que argumentase que la fundaci\u00f3n del obispado no causaba ning\u00fan perjuicio ni al cabildo de Cartagena, ni a la ciudad de Murcia \u00ab<em>puix nols toquen en les rendes, ni es derogada la dignidad episcopal, y Murcia en aquest pleyt no es part<\/em>\u00bb, y que remarcase que la instituci\u00f3n serv\u00eda para honrar al obispo ya que tendr\u00eda bajo su gobierno \u00ab<em>dos sglesies catredals<\/em>\u00bb.<\/p>\n<p>Tambi\u00e9n le enviaron al can\u00f3nigo instrucciones para que supiese c\u00f3mo actuar en el caso de que Carlos I se dispusiese a expedir el mandato ejecutorial de los breves revocatorios. Siguiendo las recomendaciones formales del abogado Jer\u00f3nimo Soriano, le tendr\u00eda que decir al monarca que en la Curia romana hab\u00eda pendientes apelaciones contra dichos rescriptos, y que hasta su resoluci\u00f3n no podr\u00eda tomar ninguna decisi\u00f3n que pudiese modificar la situaci\u00f3n existente. Y en el caso de que persistiese en su intenci\u00f3n de despachar la citada provisi\u00f3n, habr\u00eda de apelar ante el papa contra ella, porque, seg\u00fan le indicaban, \u00ab<em>qui bes defen, bona merce espera<\/em>\u00bb.<\/p>\n<p>Y por \u00faltimo, le encargaron que le comentara al rey que ten\u00edan la intenci\u00f3n de presentar la remisi\u00f3n judicial de la causa a Roma como una petici\u00f3n por agravio en las pr\u00f3ximas Cortes de la Corona de Arag\u00f3n. Y le pidieron que le dijese que la p\u00e9rdida del obispado no s\u00f3lo perjudicar\u00eda a la ciudad de Orihuela, sino tambi\u00e9n al Reino de Valencia y la referida Corona, y que todos los representantes de los tres reinos les apoyar\u00edan en la reuni\u00f3n parlamentaria.<\/p>\n<p>La extensa carta conclu\u00eda con dos anuncios. Por un lado, le informaron de que ten\u00edan la intenci\u00f3n de solicitar consejos a algunos doctores de Valencia para saber qu\u00e9 deb\u00edan hacer en las diferentes situaciones que se pudiesen presentar. Y por otro, le avisaron de que hallar\u00eda en el env\u00edo postal un pliego de instrucciones para el embajador Jaime G\u00f3mez -que estaba parado en Roma-, y le pidieron que se lo hiciese llegar de un modo seguro<sup>177<\/sup>.<\/p>\n<p>Ese mismo d\u00eda 16 de abril, los capitulares del Salvador, y el justicia y los jurados, le escribieron, asimismo, una carta al m\u00e1ximo valedor del can\u00f3nigo Mart\u00ednez en la corte real, el obispo Jaime Cabrero. Le agradecieron su apoyo incondicional hacia la causa episcopal, y le pidieron que siguiese auxiliando al procurador en las duras negociaciones que se avecinaban<sup>178<\/sup>.<\/p>\n<p>Y dos d\u00edas despu\u00e9s, enviaron los escritos con el correo Jaime Siles.<\/p>\n<p>Durante la segunda mitad del mes de abril, los mandatarios oriolanos llegaron a la conclusi\u00f3n de que necesitaban ganar tiempo para que sus s\u00edndicos en las cortes real y pontificia tuviesen la posibilidad de realizar las gestiones oportunas para cumplir con los objetivos generales propuestos, esto es, la remisi\u00f3n de la causa a la Santa Sede, y la posterior confirmaci\u00f3n definitiva de la instituci\u00f3n del obispado. Entonces, se plantearon que no pod\u00edan permitir de ninguna forma que el duque de Calabria, una vez recibiese el ejecutorial real de los breves revocatorios, ayudase a los cartaginenses a ponerlos en vigor; y para evitarlo, decidieron enviar refuerzos a Valencia. El 30 de abril nombraron a un nuevo procurador, Lope Ferr\u00e1ndez de Mesa, y le encargaron que prestase atenci\u00f3n a cualquier movimiento sospechoso que pudiese acontecer en la corte virreinal, de modo que cuando los murcianos le presentasen al duque la aludida provisi\u00f3n real, siguiendo los consejos y recomendaciones de los doctores Riudaura y Filibert, interpusiese una apelaci\u00f3n contra ella, a fin de que el Lugarteniente General del Reino se viese obligado a consultar a Carlos I antes de hacerla efectiva. Adem\u00e1s, tambi\u00e9n le cometieron otra importante misi\u00f3n: que solicitase a algunos juristas valencianos, como Artes, Monfort, Ros, o los dos supracitados, que les remitiesen memoriales con los que poder fortalecer sus argumentaciones proepiscopales, e instrumentos con consejos que les ilustrasen sobre c\u00f3mo hab\u00edan de proceder si el rey persist\u00eda en su intenci\u00f3n de promover la ejecuci\u00f3n de los rescriptos revocatorios, o c\u00f3mo deb\u00edan actuar si \u00e9stos eran finalmente ejecutados. Y tras recibir 20 ducados, ese mismo d\u00eda 30, Lope Ferr\u00e1ndez de Mesa parti\u00f3 para Valencia<sup>179<\/sup>.<\/p>\n<p>Algunos d\u00edas despu\u00e9s, las autoridades oriolanas recibieron dos impresionantes argumentaciones del doctor Francisco Ros, y, de inmediato, las remitieron a la corte, para que pudiese utilizarlas Luis Mart\u00ednez<sup>180<\/sup>. \u00c9ste, a su vez, consigui\u00f3 que el doctor Jer\u00f3nimo Soriano tambi\u00e9n le proporcionase un par de memoriales muy bien fundamentados<sup>181<\/sup>. Y desde este momento, las diligencias del can\u00f3nigo, sustentadas en tan s\u00f3lida apoyatura y auspiciadas por el favor de los consejeros Ram y May, lograron ir variando progresivamente el signo de las negociaciones.<\/p>\n<p>El 8 de mayo regres\u00f3 a Orihuela el can\u00f3nigo Jaime G\u00f3mez, despu\u00e9s de pasar a\u00f1o y medio en Roma<sup>182<\/sup>. Y una semana despu\u00e9s, dio relaci\u00f3n de su larga embajada a los <em>Electos<\/em>. Y lo hizo muy r\u00e1pidamente puesto que en tanto tiempo como estuvo en la capital del Orbe Cat\u00f3lico no fue capaz de conseguir ni un solo rescripto apost\u00f3lico favorable a la causa oriolana. Ni siquiera la tan demandada absoluci\u00f3n de las censuras impuestas por los inquisidores cartaginenses. G\u00f3mez explic\u00f3 la falta absoluta de resultados diciendo que \u00ab<em>lo papa no volgue provehir per letres que lo emperador li fea<\/em>\u00bb, es decir, que Clemente VII no atendi\u00f3 los ruegos oriolanos por expresa indicaci\u00f3n de Carlos I. Entonces, los comisionados para el Pleito del Obispado, desconfiando de sus palabras, le pidieron pruebas de las instancias que hab\u00eda intentado introducir en la Curia, y el can\u00f3nigo no pudo presentar ning\u00fan documento pues afirm\u00f3 que los hab\u00eda dejado todos en la Ciudad Eterna, en poder de Mart\u00edn Ferr\u00e1ndez de Mesa, un oriolano, servidor del cardenal Fernes. Y ante el desencanto de los <em>Electos<\/em>, la reuni\u00f3n concluy\u00f3 cuando Jaime G\u00f3mez les pidi\u00f3 que hiciesen saber al <em>Consell<\/em> que le adeudaban una considerable cantidad de dinero por los servicios prestados<sup>183<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, toda la Monarqu\u00eda Hisp\u00e1nica vivi\u00f3 momentos extraordinariamente felices. A continuaci\u00f3n, reproducimos una escueta carta que el 21 de mayo envi\u00f3 Carlos I desde Valladolid, v\u00eda Valencia, a las autoridades civiles de Orihuela para anunciarles una important\u00edsima nueva<sup>184<\/sup>:<\/p>\n<p>\u00ab<em>El rey.<\/em><\/p>\n<p><em>Amados y fieles nuestros. Oy en este dia, la Serenissima Emperatriz, nuestra muy cara e muy amada muger, por gracia de Dios nuestro Senyor, ha parido hun hijo, y queda buena del parto. Es razon que lo sepays por vuestra consolacion, y para que deys gracias a Dios por la merced que en esto haze a nos y a todos nuestros Reynos y senyorios. Datum en Valladolid a XXI dias del mes de mayo del anyo MDXXVII.<\/em><\/p>\n<p><em>Yo el Rey.<\/em><\/p>\n<p><em>Urries Secretarius<\/em>\u00bb.<\/p>\n<p>Acababa de nacer el primog\u00e9nito real, el heredero universal del legado del emperador: el infante D. Felipe.<\/p>\n<p>La misiva lleg\u00f3 a Valencia, a manos del duque de Calabria, el 26 de mayo, y ese mismo d\u00eda D. Fernando de Arag\u00f3n la remiti\u00f3 a la ciudad del Bajo Segura, junto con otro escrito suyo que tambi\u00e9n nos permitimos la licencia de reproducir en honor del que con el paso del tiempo ser\u00eda llamado el <em>Rey Prudente<\/em><sup>185<\/sup>:<\/p>\n<p>\u00ab<em>El Rey, y por su Cesarea Catholica Magestad el duque don Fernando de Aragon, Lugartheniente general et caetera.<\/em><\/p>\n<p><em>Amados y fieles de Su Magestad. Por quanto Su Magestad, con sus cartas, nos ha mandado dar aviso de la merced que nuestro Senyror Dios nos ha fecho de dar salut a la Emperatriz, librandola del peligro del parto, que diz que fue rezio, dandole hijo primogenito, y juncto con esto ha mandado tambien por su carta daros dello aviso y noticia segun vereys por la dicha carta, la qual con esta os remitimos, rogamos vos por ende, affectuosamente, que en recibiendola deys por ello muchas gracias a nuestro Senyor y proveays y mandeys que se hagan todas las alegrias que fuere possible en esa ciudad. Y por quanto Su Magestad manda que no se pidan ni tomen albricias por esta nueva, os rogamos que no cureys de darlas en ninguna manera porque a Su Magestad y a nos seria molesto. Y porque como es razon, en esta ciudad se han de hazer grandes fiestas por alegria, os damos dello noticia por que si querreys venir a ellas que con vuestra presencia se augmenten las fiestas. Datum en la ciudad de Valencia a XXVI de mayo de MDXXVII.<\/em><\/p>\n<p><em>El duque de Calabria.<\/em><\/p>\n<p><em>Ludovicus Domingues<\/em>\u00bb.<\/p>\n<p>La buena nueva del feliz parto de Isabel de Portugal debi\u00f3 llegar a Orihuela el 27 o el 28 de mayo, y fue motivo para la organizaci\u00f3n de innumerables manifestaciones de alegr\u00eda y alborozo entre las que destacaron, a nivel civil, los \u00ab<em>jochs de canyes<\/em>\u00bb, en los que se corrieron \u00ab<em>bous molt braus<\/em>\u00bb, y en el \u00e1mbito eclesi\u00e1stico, una celebraci\u00f3n muy lujosa de \u00ab<em>la festa del Corpus<\/em>\u00bb<sup>186<\/sup>.<\/p>\n<ol start=\"10\">\n<li><strong> Las diligencias previas a las Cortes de 1528.<\/strong><\/li>\n<\/ol>\n<p>Las acertadas alegaciones del s\u00edndico Luis Mart\u00ednez y el decidido apoyo de los doctores Ram y May, del Consejo de Arag\u00f3n, tuvieron efectos insospechadamente beneficiosos para la causa episcopal oriolana. Por una parte, Carlos I aplaz\u00f3 el despacho del ejecutorial de los breves revocatorios. Y por otra, decidi\u00f3 no obligar a las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura a aceptar la lesiva capitulaci\u00f3n que hab\u00edan propuesto los consejeros castellanos Pollances y Vegara, y el procurador murciano Juan V\u00e1zquez.<\/p>\n<p>Transcurrido el mes de junio de 1527, la cuesti\u00f3n volvi\u00f3 a situarse en los t\u00e9rminos en que estaba cuando el monarca la cometi\u00f3 al estudio de los dos Consejos, a finales de 1525. Entonces, los mandatarios oriolanos se dieron por satisfechos y decidieron adoptar una t\u00e1ctica conservadora. Consideraron interesante que las negociaciones se ralentizasen hasta la convocatoria de las Cortes Generales de la Corona de Arag\u00f3n, para tratar de conseguir en ellas la ansiada remisi\u00f3n del litigio a la Santa Sede. Y en atenci\u00f3n a dichas l\u00edneas maestras actuaron.<\/p>\n<p>El 8 de julio les enviaron a los doctores Ram y May sendas cartas de agradecimiento reconoci\u00e9ndoles que hab\u00edan favorecido los intereses de Orihuela \u00ab<em>de tal manera que lo contrapes de Castella no ha bastat<\/em> [per] <em>a fer decantar la balan\u00e7a a la part de Murcia<\/em>\u00bb, ofreci\u00e9ndoles la gratitud perpetua de la ciudad e incluso sus \u00ab<em>persones e bens<\/em>\u00bb, y rog\u00e1ndoles que siguiesen auspiciando la causa episcopal<sup>187<\/sup>.<\/p>\n<p>Cinco d\u00edas m\u00e1s tarde, los mun\u00edcipes, que no ten\u00edan muchas ganas de tratar al can\u00f3nigo Jaime G\u00f3mez, tras muchas suplicaciones -m\u00e1s bien, importunaciones- suyas, se decidieron a revisar sus cuentas de la embajada a Roma. Y no llegaron a un entendimiento econ\u00f3mico con el ex-procurador<sup>188<\/sup>.<\/p>\n<p>Sin embargo, la relativa paz se vio turbada por un rumor. Al parecer, por esas fechas lleg\u00f3 a Murcia una carta de su s\u00edndico en la corte, Juan V\u00e1zquez, en la que les dec\u00eda a sus representados que Carlos I hab\u00eda aprobado la expedici\u00f3n del ejecutorial de los breves, y que pronto lo despachar\u00eda. Entonces, los capitulares de Cartagena y las autoridades de la ciudad de Murcia comenzaron a jactarse p\u00fablicamente del inminente logro, y la noticia lleg\u00f3 a Orihuela.<\/p>\n<p>De esa manera, el 18 de julio el cap\u00edtulo del Salvador y el justicia y los jurados volvieron a enviar varias cartas a la corte.<\/p>\n<p>En primer lugar, se dirigieron a Luis Mart\u00ednez, a quien le comentaron que estaban \u00ab<em>molt alegres<\/em>\u00bb de que la causa hubiese sido cometida de nuevo a los Consejos de Arag\u00f3n y Castilla, porque los doctores del primero, siendo \u00ab<em>tant justificats y savis<\/em>\u00bb, no permitir\u00edan que les fuesen causados nuevos perjuicios. Despu\u00e9s, le dieron cuenta de las \u00faltimas informaciones que hab\u00edan arribado a la ciudad. Y en ese sentido, le recalcaron que tratase de impedir la expedici\u00f3n del ejecutorial. Adem\u00e1s, le comunicaron que para prever dicha posibilidad, los doctores valencianos les hab\u00edan recomendado que tuviesen preparada una escritura de protesta y disentimiento contra el mandato real, en la que estuviesen muy bien fundamentadas sus aspiraciones episcopales, de modo que pudiesen presentarla en el caso de que el duque de Calabria recibiese el citado documento de auxilio del brazo secular. Y le explicaron que para prepararla, ten\u00edan necesidad de utilizar las argumentaciones de los doctores Soriano y Ros, que estaban en su poder, por lo que le pidieron que las enviase a Orihuela. Y, por \u00faltimo, le rogaron que fuese a besar las manos de micer Ram de parte del cap\u00edtulo y la ciudad, que le agradeciese sus continuos favores, y que le dijese que estaban dispuestos a servirle en lo que se le ofreciese<sup>189<\/sup>. Y le encargaron que, de paso, le diese a Felip de Ferreres, presidente del Consejo de Arag\u00f3n, una carta que para \u00e9l y los dem\u00e1s miembros de dicho organismo le remit\u00edan.<\/p>\n<p>En dicho escrito, las autoridades de la poblaci\u00f3n del Bajo Segura les manifestaron su asombro por la supuesta intenci\u00f3n real de despachar el ejecutorial. Y despu\u00e9s de recordarles que Orihuela era \u00ab<em>de la Corona de Arago, y es estada fidelissima, y per sa fidelitat es dotada de moltes gracies, libertats e privilegis<\/em>\u00bb, entre los que estaba el tantas veces se\u00f1alado de Alfonso V (en el que promet\u00eda que tanto \u00e9l como sus sucesores promover\u00edan la erecci\u00f3n del obispado), confiando en su \u00ab<em>molta virtut e consientia<\/em>\u00bb, les rogaron que se opusiesen a dicha expedici\u00f3n<sup>190<\/sup>.<\/p>\n<p>Las medidas protectoras de los capitulares y los ediles surtieron efecto y, finalmente, Carlos I no lleg\u00f3 a despachar el mandato ejecutorio. Durante los meses de agosto y septiembre, la situaci\u00f3n volvi\u00f3 a normalizarse, y las negociaciones en la corte real llegaron a un punto muerto, en espera de la resoluci\u00f3n pontificia de las apelaciones interpuestas por las autoridades oriolanas.<\/p>\n<p>En la ciudad del Bajo Segura, el 26 de septiembre los oficiales municipales volvieron a pedir consejo a los juristas de Valencia -en especial, a los doctores Rubio y Artes- para saber si deb\u00edan hacer alguna gesti\u00f3n en la Curia romana, pues a\u00fan segu\u00edan desconfiando de la ineptitud del \u00faltimo s\u00edndico, el can\u00f3nigo Jaime G\u00f3mez<sup>191<\/sup>. Obtuvieron una respuesta negativa, por lo que decidieron no innovar nada hasta la sentencia de los recursos.<\/p>\n<p>Ante el estado de la cuesti\u00f3n, le dieron licencia a Luis Mart\u00ednez para regresar de la corte, y el 10 de octubre entr\u00f3 en Orihuela<sup>192<\/sup>. Poco despu\u00e9s, el can\u00f3nigo les relat\u00f3 los \u00faltimos acontecimientos, y les coment\u00f3 que el doctor Jer\u00f3nimo Soriano le hab\u00eda pedido que les dijese que estaba dispuesto a encargarse de los negocios de la ciudad, en su ausencia. La propuesta agrad\u00f3 desde un primer momento tanto al cap\u00edtulo del Salvador como al <em>Consell<\/em> puesto que Soriano ten\u00eda fama de gran jurista, y desde 1526 hab\u00eda apoyado la causa episcopal. Sin embargo, antes de responderle, se tomaron un plazo para reflexionar. Entretanto, el 14 de octubre, para solaz de Luis Mart\u00ednez, dichos mandatarios le hicieron llegar 37 ducados, en retribuci\u00f3n de sus servicios<sup>193<\/sup>.<\/p>\n<p>Diez d\u00edas despu\u00e9s, el 24, acordaron expedir la procura del nuevo s\u00edndico en la corte real, Jer\u00f3nimo Soriano, a quien le concedieron poder para comparecer ante el emperador, ante sus Consejos, ante el Inquisidor general, y ante cualesquiera otros jueces seculares o eclesi\u00e1sticos, para tratar todas las cuestiones relacionadas con el Pleito del Obispado<sup>194<\/sup>. Y con mucha calma, esperaron hasta el 4 de noviembre para redactar la carta en la que le participaron su nombramiento. En ella, adem\u00e1s, le agradecieron los servicios que hasta entonces hab\u00eda prestado -haciendo menci\u00f3n especial a su actuaci\u00f3n en Granada-, as\u00ed como su ofrecimiento de llevar los negocios de la ciudad en la corte. Le asignaron un salario anual de 50 ducados. Le prometieron un incentivo de 20 ducados extraordinarios si consegu\u00eda que Carlos I remitiera la causa a la Santa Sede por v\u00eda de justicia. Y le anunciaron, por una parte, el env\u00edo de 24 ducados como adelanto de su sueldo, y, por otra, que el can\u00f3nigo Mart\u00ednez volver\u00eda a estar con \u00e9l tras las fiestas navide\u00f1as<sup>195<\/sup>. Y, por fin, el d\u00eda 20 del referido mes de noviembre le remitieron la procura, la carta y el dinero<sup>196<\/sup>.<\/p>\n<p>Soriano recibi\u00f3 el env\u00edo a finales de mes, y de inmediato escribi\u00f3 a las autoridades oriolanas para comunicarles la aceptaci\u00f3n del sindicato e informarles de que Carlos I hab\u00eda hecho p\u00fablica en la corte su intenci\u00f3n de ir en breve a la ciudad de Valencia.<\/p>\n<p>El a\u00f1o 1527 no termin\u00f3 de un modo tranquilo para los mun\u00edcipes puesto que el 27 de diciembre, el can\u00f3nigo Jaime G\u00f3mez volvi\u00f3 a comparecer ante el <em>Consell<\/em> para reclamar a sus componentes la satisfacci\u00f3n de las cantidades que a\u00fan le adeudaban por la embajada a Roma. En tono amenazante, les conmin\u00f3 a que le pagaran la deuda, advirti\u00e9ndoles que en el caso de que siguiesen neg\u00e1ndose a hacerlo, se ver\u00eda \u00ab<em>molt molest, constret e for\u00e7at<\/em>\u00bb a proceder contra ellos. Le respondieron que debatir\u00edan el asunto en la siguiente reuni\u00f3n municipal que fuese convocada, pero no lo hicieron, y G\u00f3mez decidi\u00f3 informar de su situaci\u00f3n a la autoridad inmediatamente superior, el gobernador D. Pedro Maza<sup>197<\/sup>.<\/p>\n<p>De modo similar, 1528 comenz\u00f3 en Orihuela con un buen susto que, finalmente, se qued\u00f3 en nada. De Murcia lleg\u00f3 el bulo de que sus procuradores cerca de la Santa Sede hab\u00edan conseguido un nuevo breve, muy favorable a su causa. Ello, conjugado con el env\u00edo de otro procurador a la corte real, alert\u00f3 al cap\u00edtulo del Salvador y a los oficiales municipales, y el 5 de enero se decidieron a escribir a su s\u00edndico Soriano, que estaba en la corte, en Burgos, para avisarle de las novedades, a fin de que tratase de confirmar la existencia del rescripto, y para que tuviese cuidado con los manejos de los procuradores murcianos ante los Consejos y ante el secretario de Estado Francisco de los Cobos<sup>198<\/sup>. Le indicaron, asimismo, que siguiese buscando el apoyo del doctor Ram y del escribano de registro Jimeno S\u00e1nchez del Vilar -persona muy pr\u00f3xima al citado consejero-, y que les avisase si consegu\u00eda conocer m\u00e1s datos sobre el inminente viaje del rey a la capital del Turia o sobre la pr\u00f3xima convocatoria de Cortes<sup>199<\/sup>. Tambi\u00e9n le escribieron una carta al aludido escribano S\u00e1nchez, agradeci\u00e9ndole sus favores y comprometi\u00e9ndose a premiarlos con algo m\u00e1s que cumplidos<sup>200<\/sup>.<\/p>\n<p>Una vez qued\u00f3 demostrada la inexistencia del nuevo breve apost\u00f3lico, la situaci\u00f3n de la cuesti\u00f3n del obispado volvi\u00f3 a normalizarse, y no se produjo ninguna novedad digna de ser destacada hasta la segunda mitad del mes de marzo.<\/p>\n<p>Ante la inminencia del viaje de Carlos I a Valencia -motivado por la necesidad de que los representantes del Reino le prestasen, por fin, juramento como rey-, y la proximidad de la convocatoria de Cortes, las autoridades oriolanas decidieron echar el resto enviando a la corte a tres procuradores de peso, Luis Mart\u00ednez, Lope Ferr\u00e1ndez de Mesa y Vicente Mart\u00ed, con la intenci\u00f3n de que le explicasen al monarca que, en relaci\u00f3n con el Pleito del Obispado, lo m\u00e1s razonable y justo era que la causa fuese sustanciada y determinada judicialmente en la Santa Sede. Pretend\u00edan con ello, al menos, poner en antecedentes al rey, de modo que tuviese pleno conocimiento del tema en el momento en el que el s\u00edndico que representase a la ciudad en la reuni\u00f3n parlamentaria le elevase dicha petici\u00f3n -la remisi\u00f3n a Roma- con el apoyo de los estamentos de los tres reinos de la Corona de Arag\u00f3n.<\/p>\n<p>Por ello, el 21 y el 23 de marzo las referidas autoridades les redactaron a los procuradores dos instrumentos en los que se recog\u00edan todas las instrucciones que habr\u00edan de seguir cuando llegasen a la corte. Adem\u00e1s de informar al monarca sobre la cuesti\u00f3n episcopal, Mart\u00ednez, Ferr\u00e1ndez y Mart\u00ed hab\u00edan de suplicar a Su Majestad que no causase ning\u00fan perjuicio a los privilegios y libertades de Orihuela. Adem\u00e1s, ten\u00edan que tratar con \u00e9l y con los se\u00f1ores del Consejo de Arag\u00f3n otros temas relacionados con los problemas de abastecimiento municipal de trigo, con el privilegio del regimiento de la ciudad, o con la posibilidad de nuevos roces con la Inquisici\u00f3n cartaginense. Tambi\u00e9n les encargaron que le pidiesen al doctor Soriano su opini\u00f3n sobre si Jaime de Soler podr\u00eda volver a ejercer como vicario general del obispado de Orihuela, sin temer las represalias murcianas<sup>201<\/sup>.<\/p>\n<p>Y para facilitar su labor les entregaron un buen n\u00famero de cartas de creencia y recomendaci\u00f3n, dirigidas a Carlos I<sup>202<\/sup>, al gran canciller Gattinara<sup>203<\/sup>, a diferentes miembros del Consejo de Arag\u00f3n (Miguel May, Juan Ram, Juan Jacobo de Bonomia, micer Ponciano y Felip de Ferreres)<sup>204<\/sup>, y a aliados como Jimeno S\u00e1nchez del Vilar<sup>205<\/sup>, y al procurador Jer\u00f3nimo Soriano<sup>206<\/sup>.<\/p>\n<p>A principios de abril, el grupo de los <em>Electos<\/em> comenz\u00f3 a preparar la intervenci\u00f3n oriolana en las inminentes Cortes de la Corona de Arag\u00f3n. Para ello, sus componentes decidieron contar con el asesoramiento del doctor Jer\u00f3nimo Soriano, de modo que el d\u00eda 13 del citado mes le escribieron una carta al procurador Luis Mart\u00ednez con la intenci\u00f3n de que le pidiese su cualificada opini\u00f3n sobre algunas cuestiones, esto es, sobre c\u00f3mo plantear la causa episcopal en el Parlamento a fin de que fuese aceptada como agravio, y sobre c\u00f3mo habr\u00eda de ser propuesto \u00e9ste para que fuese solucionado antes de la clausura de la referida reuni\u00f3n. Asimismo, le solicitaron que le comentase al aludido jurista que ten\u00edan el prop\u00f3sito de enviar a una persona de confianza por las villas y ciudades de realengo de los tres reinos para conseguir letras favorables a los intereses oriolanos de manera que el rey pudiese comprender que la cuesti\u00f3n del obispado \u00ab<em>no sols es pasio e interes de Oriola, mas dels regnes de Arago y principat de Catalunya<\/em>\u00bb. Y, por \u00faltimo, le encargaron al can\u00f3nigo que se enterase de dos datos de crucial inter\u00e9s: la fecha aproximada en la que Carlos I ten\u00eda previsto llegar a Valencia, y el lugar donde iban a celebrarse las Cortes<sup>207<\/sup>.<\/p>\n<p>No tuvieron las autoridades oriolanas que esperar a la respuesta de Mart\u00ednez para conocer esta \u00faltima informaci\u00f3n. Dos d\u00edas despu\u00e9s -el 15 de abril-, llegaron a sus manos una carta del virrey -fechada una semana antes-, y dos instrumentos del monarca, una c\u00e9dula real y una provisi\u00f3n, ambas datadas el 27 de marzo.<\/p>\n<p>En ellas, Carlos I, les explic\u00f3 que \u00ab<em>las grandes ocupa\u00e7iones que havemos tenido en tantos nego\u00e7ios que se nos han ofre\u00e7ido despues que venimos de la felice corona\u00e7ion del Sacratissimo Inperio no han dado lugar al desseo que tenemos de yr a essos Reynos<\/em>\u00bb. Les pidi\u00f3 que enviasen a Valencia a un procurador con poder suficiente para que el 4 de mayo le pudiese prestar juramento de fidelidad y obediencia en nombre de la ciudad. Les comunic\u00f3 que hab\u00eda convocado \u00ab<em>Corts generals de tots los tres regnes de la Corona de Arago en la vila de Mon\u00e7o<\/em>\u00bb para el 1 de junio, y les orden\u00f3 que mandasen tambi\u00e9n all\u00ed a un representante<sup>208<\/sup>.<\/p>\n<p>El duque de Calabria les coment\u00f3, adem\u00e1s, que \u00ab<em>a causa de la guerra uberta en que Sa Magestat esta ab los Reys de Francia, Inglaterra e sos confederats<\/em>\u00bb, el emperador s\u00f3lo podr\u00eda asistir personalmente a la \u00ab<em>proposicio<\/em>\u00bb, al discurso real, \u00ab<em>lo que per cert li desplau en estrem per quant sa real determinada voluntat era de asistir personalment a la conclusio de aquelles, per que ab mes conpliment e contentacio de tots se poguessen aquelles cloure<\/em>\u00bb, y les indic\u00f3 que, \u00ab<em>seguint vostra innata fidelitat e los continuus serveis que haveu prestat als Reys de immortal memoria<\/em>\u00bb, habr\u00edan de habilitarle por mediaci\u00f3n del s\u00edndico para que, en ausencia de Carlos I, fuera \u00e9l quien las clausurase. Y para ganarse su apoyo, D. Fernando de Arag\u00f3n les asever\u00f3 que, adem\u00e1s de \u00ab<em>confermar tots los privilegis, gracies e libertats<\/em>\u00bb, les har\u00eda \u00ab<em>altres e majors<\/em>\u00bb. Y concluy\u00f3 escribi\u00e9ndoles que le concediesen tal facultad habilitadora al procurador que se desplazase a las Cortes, de modo que pudiese ejercerla seg\u00fan mandaba el monarca, esto es, \u00ab<em>immediatament apres de ser feta la proposicio<\/em>\u00bb, \u00ab<em>sens posar greuges ne dilacio alguna<\/em>\u00bb<sup>209<\/sup>.<\/p>\n<p>Tras la recepci\u00f3n de los tres documentos, el 17 de abril el <em>Consell<\/em> design\u00f3 a algunos \u00ab<em>Elets<\/em>\u00bb (el justicia, los jurados, Andr\u00e9s de Soler, Juan Ruiz -se\u00f1or de Cox-, Juan Mart\u00ed, Jaime de Vilafranca, Blas Rausell, Perot P\u00e9rez y Juan de Mula) para que se encargasen de la organizaci\u00f3n de la doble embajada a Valencia y a las Cortes. Encomend\u00f3 a Perot P\u00e9rez la espec\u00edfica tarea de obtener tanto dinero como fuese necesario para sufragar sus costes, mediante la carga de censales. Y procedi\u00f3 al nombramiento como procurador de Jaime Despuig, la \u00ab<em>persona mes abil, sufficient y fiada<\/em>\u00bb<sup>210<\/sup>.<\/p>\n<p>Sin embargo, pese a los ruegos de las autoridades, el nominado no quiso aceptar la designaci\u00f3n concejil aduciendo que hab\u00eda de ir con D. Pedro Maza a visitar a Carlos I. Por ello, los mun\u00edcipes le escribieron al gobernador, rog\u00e1ndole que le mandase a Despuig que aceptase el sindicato, pues aun yendo como procurador de Orihuela, podr\u00eda servirle. Y le incidieron en el hecho de que \u00ab<em>en estes Corts nos hi va molt a causa del pleyt de la Sglesia Catedral<\/em>\u00bb, se\u00f1alando que necesitaban tener la mejor representaci\u00f3n, lo cual s\u00f3lo pod\u00eda suceder siendo Jaime Despuig el s\u00edndico de la ciudad<sup>211<\/sup>.<\/p>\n<p>Las instancias hechas ante Maza no sirvieron para nada. Despuig confirm\u00f3 su negativa, y las autoridades oriolanas se vieron obligadas a convocar de urgencia una nueva reuni\u00f3n del <em>Consell<\/em>, el 26 de abril, con el prop\u00f3sito de volver a elegir al s\u00edndico que habr\u00eda de ir a Valencia y a Monz\u00f3n. Y el nombramiento recay\u00f3 en la persona de Perot P\u00e9rez. Asimismo, tuvieron que cambiar la procura de la carga de censales, anteriormente encomendada al nuevo s\u00edndico, y encargaron tal tarea a Pedro Almod\u00f3var. Y tambi\u00e9n fue modificada la n\u00f3mina de <em>Electos<\/em>, pues a Perot P\u00e9rez lo sustituy\u00f3 en dicha comisi\u00f3n el propio Jaime Despuig<sup>212<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s, coincidiendo con la llegada a Orihuela de Vicente Mart\u00ed y Lope Ferr\u00e1ndez de Mesa, que habr\u00edan de acompa\u00f1ar a P\u00e9rez a Valencia y a Monz\u00f3n, los oficiales municipales le entregaron al s\u00edndico sus cartas credenciales. Le dieron una para el rey, en la que adem\u00e1s de presentarle como procurador, le suplicaban que \u00ab<em>les coses ques esguardaran al benefici e repos de aquesta vostra ciutat e conservacio de lurs privilegis mane tenir per comendades, y no done loch se fasen coses que sien en prejuhi dels privilegis e gracies a la dita ciutat atorgats<\/em>\u00bb<sup>213<\/sup>. Y otras dirigidas a diferentes componentes del Consejo de Arag\u00f3n, los doctores Ferreres, Ram, May, Ponciano y Bonomia en las que les informaban que P\u00e9rez, Mart\u00ed y Ferr\u00e1ndez iban a solicitar en las Cortes concesiones relacionadas con el Pleito del Obispado<sup>214<\/sup>.<\/p>\n<p>El \u00faltimo de abril, le entregaron otro escrito para Jer\u00f3nimo Soriano en el que le ped\u00edan que favoreciese a los tres oriolanos \u00ab<em>en lo ques sguarda la conservatio de nostres privilegis com en lo pleyt de nostra sglesia catredal<\/em>\u00bb. Y le remitieron la cantidad que les quedaba por entregarle -tras la primera paga- por haber actuado desde noviembre como procurador de Orihuela en la corte<sup>215<\/sup>.<\/p>\n<p>Ese mismo d\u00eda, los <em>Electos<\/em> le dieron a Perot P\u00e9rez las instrucciones que hab\u00eda de seguir a lo largo de su embajada. La estrategia dise\u00f1ada para presentar el agravio episcopal se fundamentaba en la violaci\u00f3n real del privilegio concedido por Alfonso V en Gaeta el 11 de septiembre de 1437 (en el que, como ya hemos repetido muchas veces, promet\u00eda que tanto \u00e9l como sus sucesores promover\u00edan la erecci\u00f3n del obispado).<\/p>\n<p>Los comisionados le mandaron al procurador que preparase junto con el abogado Soriano la escritura de suplicaci\u00f3n, utilizando el material que ten\u00eda el experto en leyes. Y que en ella, le pusiesen de manifiesto al rey, adem\u00e1s del citado argumento, que el 30 de noviembre de 1522 jur\u00f3 respetar los privilegios y libertades de la ciudad del Bajo Segura, y que \u00ab<em>per intercessio de los regnes de Castella<\/em>\u00bb, de las Cortes castellanas, los hab\u00eda infringido en relaci\u00f3n con la creaci\u00f3n del obispado, puesto que hab\u00eda escrito en repetidas ocasiones tanto a Le\u00f3n X como a Clemente VII para que la anulasen, sin permitir siquiera a los oriolanos el derecho de defensa legal. Tambi\u00e9n ten\u00edan que arg\u00fcir en el instrumento que hab\u00edan interpuesto diversas apelaciones ante Clemente VII, como \u00fanico juez verdaderamente competente para entender en la discordia, y que estaban pendientes de resoluci\u00f3n. Y le ten\u00edan que rogar, finalmente, que dejase de intervenir parcialmente en la causa y que la remitiese a la Santa Sede, de modo que fuese solucionada en la Curia por la v\u00eda estrictamente judicial, \u00ab<em>no obstant qualsevol letres en contrari fetes a suplicacio de Castella<\/em>\u00bb. Y para que la suplicaci\u00f3n tuviese un mayor peso, le ordenaron que consiguiera que la presentasen con \u00e9l todos los s\u00edndicos de las ciudades y villas reales que intervinieran en las Cortes.<\/p>\n<p>Perot P\u00e9rez tambi\u00e9n ten\u00eda que tratar ante el monarca otros asuntos de gran trascendencia para la vida de los habitantes de Orihuela. Sobre el r\u00edo Segura, \u00ab<em>lo qual acostuma de tenir grandissima multitut de aygues en temps de yvern, a causa dels ayguaduts o cregudes<\/em>\u00bb, y el \u00ab<em>riacho<\/em>\u00bb obrado por los murcianos tras la instituci\u00f3n del obispado, habr\u00eda de informar a Carlos I que los oriolanos no hab\u00edan querido adoptar ninguna medida, para evitar \u00ab<em>rebolutions en los regnes<\/em>\u00bb, y siguiendo los consejos de Soriano habr\u00eda de suplicarle que mandase cerrar el \u00ab<em>portell<\/em>\u00bb, y que ordenase a los murcianos que pagasen los da\u00f1os producidos o dispusiese alg\u00fan otro remedio para que los damnificados hallasen satisfacci\u00f3n a sus p\u00e9rdidas. Tambi\u00e9n tendr\u00eda que presentar otras peticiones relacionadas con el regimiento de la ciudad, algunos impuestos -como el general de la sal-, la provisi\u00f3n municipal de trigo, el privilegio de la escriban\u00eda del <em>Consell<\/em>, la devoluci\u00f3n por el marqu\u00e9s de los V\u00e9lez de la artiller\u00eda y la bandera de la ciudad, o la jurisdicci\u00f3n inquisitorial<sup>216<\/sup>.<\/p>\n<p>Con el tiempo justo, la ma\u00f1ana del 3 de mayo los tres embajadores oriolanos partieron en direcci\u00f3n a Valencia, donde Perot P\u00e9rez habr\u00eda de prestar, en nombre de la ciudad, el juramento de obediencia a Carlos I<sup>217<\/sup>.<\/p>\n<p>Ese mismo d\u00eda, el rey lleg\u00f3 a la ciudad del Turia. Y su entrada no pudo ser m\u00e1s tr\u00e1gica pues, a causa del peso del enorme gent\u00edo que esperaba el paso de la comitiva en el Puente del Real, la estructura se hundi\u00f3 y la cat\u00e1strofe provoc\u00f3 el fallecimiento de m\u00e1s de un millar de personas<sup>218<\/sup>.<\/p>\n<p>Tras el accidentado recibimiento, los representantes de las diferentes villas y ciudades le prestaron al monarca, por fin, una d\u00e9cada despu\u00e9s del inicio de su reinado, el juramento de fidelidad.<\/p>\n<p>Durante las tres semanas siguientes, en Valencia, los tres embajadores oriolanos, ayudados por D. Pedro Maza, se encargaron de entrevistarse y platicar con diferentes personajes destacados de la corte, y con los s\u00edndicos de los tres brazos del Reino, y lograron que se comprometiesen a apoyar la causa episcopal. Adem\u00e1s, pagaron al doctor Filibert para que les preparase algunas escrituras con la intenci\u00f3n de utilizarlas para presentar las suplicaciones relacionadas con la provisi\u00f3n municipal del \u00ab<em>forment<\/em>\u00bb y con el \u00ab<em>riacho<\/em>\u00bb. Y el 25 de mayo, escribieron dos cartas a los <em>Electos<\/em> para informarles de las gestiones realizadas, pedirles m\u00e1s dinero y dos traslados del privilegio de Alfonso V, y anunciarles su partida para la villa aragonesa de Monz\u00f3n<sup>219<\/sup>.<\/p>\n<ol start=\"11\">\n<li><strong> Las Cortes de Monz\u00f3n de 1528 y la remisi\u00f3n del Pleito del Obispado a la Santa Sede.<\/strong><\/li>\n<\/ol>\n<p>Las Cortes fueron inauguradas, cumpliendo las previsiones, el 1 de junio de 1528. En nuestra opini\u00f3n, el emperador escogi\u00f3 la opci\u00f3n de centralizar en Monz\u00f3n la reuni\u00f3n del Parlamento de los tres reinos para ganar tiempo, dispersar las fuerzas locales, y hallar una oposici\u00f3n menor a sus planes iniciales que radicaban en tomar el dinero y echar a correr.<\/p>\n<p>Desde un principio, Carlos I hab\u00eda anunciado sus prop\u00f3sitos de proceder a la lectura de la proposici\u00f3n real, conseguir el subsidio y habilitar al duque de Calabria para que se encargase de atender los agravios y clausurar las Cortes.<\/p>\n<p>As\u00ed, tras la inauguraci\u00f3n de las sesiones, el monarca trat\u00f3 de conseguir sus objetivos. Pese a la resistencia catalana, consigui\u00f3 que los diferentes s\u00edndicos de los estamentos habilitasen a su primo, D. Fernando de Arag\u00f3n. Y despu\u00e9s, a principios de julio, quiso conocer \u00ab<em>la quantitat del servey que se li tenia de fer<\/em>\u00bb antes de que los procuradores le presentasen los memoriales de \u00ab<em>greuges<\/em>\u00bb, generando por ello \u00ab<em>moltes altercacions, perque jamay se avia donat en Corts negunes lo servey fins a la conclusio de les Corts<\/em>\u00bb. A pesar de la inexistencia de precedentes, la voluntad real fue inquebrantable, y los brazos tuvieron que confirmarle que el servicio que le ofrecer\u00edan ser\u00eda de \u00ab<em>sent milia lliures<\/em>\u00bb, y que se lo dar\u00edan \u00ab<em>concloydes les Corts<\/em>\u00bb. Carlos I respondi\u00f3 que quer\u00eda el dinero m\u00e1s \u00ab<em>promptament<\/em>\u00bb, les pidi\u00f3 que tuviesen en cuenta la necesidad que ten\u00eda de \u00e9l, \u00ab<em>axi per lo fet del realme de Napols com per lo desafiu que lo rey de Fran\u00e7a li a fet<\/em>\u00bb, y ratific\u00f3 que hasta que le concediesen el servicio no proveer\u00eda \u00ab<em>en neguna cosa<\/em>\u00bb. Los asistentes al Parlamento le replicaron que \u00ab<em>jamay tal demanda se es feta per princep negu en negunes Corts<\/em>\u00bb y dudaron a la hora de contestar a las instancias reales ante la posibilidad de que el emperador se fuese sin celebrar finalmente la reuni\u00f3n estamental<sup>220<\/sup>.<\/p>\n<p>Los oriolanos no pudieron sino aceptar las \u00f3rdenes reales pues, de haberse negado, habr\u00edan comprometido por completo el futuro de las aspiraciones episcopales. \u00ab<em>De duobus malis minus est eligendus<\/em>\u00bb: \u00e9sta fue la consigna latina que decidieron seguir. De los dos males, eligieron el menor, y prefirieron satisfacer al monarca, puesto que como dec\u00eda el avezado Lope Ferr\u00e1ndez de Mesa: \u00ab<em>lo millor es mostrar tostems voler lo que Sa Magestat vol, y procurar que conegua que no se causa ques destorbe lo que cumple a son servey<\/em>\u00bb. Y realmente ten\u00eda claras las ideas ya que cre\u00eda que lo m\u00e1s beneficioso era, sin duda, \u00ab<em>procurar guanyar la voluntat de Sa Magestat, y del gran candeller, y de tots aquells que tenen cabuda ab Sa Magestat<\/em>\u00bb<sup>221<\/sup>.<\/p>\n<p>Por otra parte, durante esta primera fase de las Cortes, los tres embajadores oriolanos se enfrascaron en la labor de ganar el apoyo de todos los s\u00edndicos asistentes. Se dedicaron a ello \u00ab<em>de nit e de dia, per a poder portat la neguociacio al port que tots desijam<\/em>\u00bb. Hicieron \u00ab<em>totes aquelles diligenties que en lo mon se poden aver fet y procurat<\/em>\u00bb. Y consiguieron que todos los miembros de los brazos les confirmasen que suplicar\u00edan la remisi\u00f3n del Pleito del Obispado a Roma cuando se interpusiesen \u00ab<em>los primers memorials de greuges<\/em>\u00bb. Adem\u00e1s, presentaron una \u00ab<em>excellent suplicatio<\/em>\u00bb preparada por el doctor Soriano ante el Consejo de Arag\u00f3n, predisponiendo a\u00fan m\u00e1s a sus doctores. Y el \u00e9xito de todas las gestiones les llevaron al convencimiento de que finalmente conseguir\u00edan provisiones favorables, si no del rey, s\u00ed de su sustituto, el duque de Calabria. Tambi\u00e9n hicieron las diligencias precisas para que el resto de cuestiones que llevaban encomendadas fuesen solventadas<sup>222<\/sup>.<\/p>\n<p>El 4 de julio Carlos I se cans\u00f3 de esperar la respuesta de los estamentos y forz\u00f3 a los brazos a que accediesen a sus peticiones sobre el servicio<sup>223<\/sup>.<\/p>\n<p>Tres d\u00edas m\u00e1s tarde, los procuradores oriolanos presentaron al rey \u00ab<em>los memorials y suplications<\/em>\u00bb concernientes a la causa episcopal con el apoyo del resto de los asistentes a las Cortes. Y su estudio fue cometido a los doctores Juan Ram y Juan Jacobo de Bonomia<sup>224<\/sup>. \u00c9stos le recomendaron a Carlos I que lo m\u00e1s justo era remitir la causa a la determinaci\u00f3n de la Santa Sede, y el monarca, mediante un <em><u>acte de cort<\/u><\/em> -de cumplimiento ineludible y validez irrevocable-, acept\u00f3 el dictamen del Consejo de Arag\u00f3n y aprob\u00f3 la expedici\u00f3n de dos cartas, una dirigida a Clemente VII, y la otra para el embajador Miguel May. Ambas fueron redactadas el 15 de julio por Alonso de Soria en Zaragoza -aunque su dataci\u00f3n t\u00f3pica fue establecida en Monz\u00f3n, villa en la que su despacho fue aprobado-. Una vez terminadas, las firm\u00f3 el gran canciller Gattinara. Acto seguido, se las qued\u00f3 D. Hugo de Urries quien se las dio a su hijo Juan, y \u00e9ste se las llev\u00f3 a Carlos I a Calatayud, para que las firmase. Despu\u00e9s, fueron a parar a manos del escribano de mandamiento, Juan Vaguer, con quien Vicente Mart\u00ed acord\u00f3 que nada m\u00e1s llegase a Madrid, las registrase, sellase y cerrase, y se las entregase al correo que fuese mandado por las autoridades oriolanas a recogerlas, para tramitarlas cuanto antes a Roma<sup>225<\/sup>.<\/p>\n<p>Yendo al contenido de las cartas, Carlos I le escribi\u00f3 a May que \u00ab<em>los stamentos de nuestro Reyno de Valencia y la ciudad e Yglesia de Orihuela<\/em>\u00bb le hab\u00edan suplicado \u00ab<em>con mucha instancia<\/em>\u00bb en las Cortes que mandase escribir al \u00ab<em>muy Sancto Padre<\/em>\u00bb para que hiciese justicia en el Pleito del Obispado. Y atendiendo a los aludidos ruegos, le orden\u00f3 que le suplicase a Clemente VII que mandase que \u00ab<em>en la dicha causa se faga y ministre justicia recta ygualmente, por manera que a nenguna de las partes sea fecho agravio<\/em>\u00bb, ya que \u00e9sa era su \u00ab<em>intencion e voluntad determinada<\/em>\u00bb<sup>226<\/sup>.<\/p>\n<p>Y se dirigi\u00f3 al sumo pont\u00edfice para suplicarle que \u00ab<em>en la causa y differencia que en essa corte piende entre las cibdades e Yglesias de Murcia y Orihuela, se faga breve y expedita justicia sin agravio de las partes<\/em>\u00bb, y anunciarle que su embajador May le participar\u00eda dicho ruego<sup>227<\/sup>.<\/p>\n<p>Unos d\u00edas despu\u00e9s, el 8 de agosto, Perot P\u00e9rez y Vicente Mart\u00ed volvieron a Orihuela e informaron a las autoridades civiles y eclesi\u00e1sticas de la buena nueva del despacho de las cartas<sup>228<\/sup>.<\/p>\n<p>Desde ese mismo momento, los referidos mandatarios comprendieron que, para aprovechar la disposici\u00f3n real, era absolutamente necesario enviar a un s\u00edndico a Roma, para que se hiciese cargo de la negociaci\u00f3n y no hubiese r\u00e9moras ni contradicciones. Llegaron a la conclusi\u00f3n de que dicho procurador habr\u00eda de ser una persona de especial \u00ab<em>calitat<\/em>\u00bb por ser la causa \u00ab<em>tan ardua y de tanta importancia<\/em>\u00bb. Y decidieron que dicha persona tendr\u00eda que cumplir tres condiciones: \u00ab<em>que sia fidelisima<\/em>\u00bb, \u00ab<em>que sapia y tingua noticia de tota la neguociacio, perque ell a de instruyr en Roma als advocats y procuradors<\/em>\u00bb, y \u00ab<em>que tingua abilitat per a negociar, y que sia molt bon neguociant<\/em>\u00bb.<\/p>\n<p>Los mun\u00edcipes estuvieron un tiempo \u00ab<em>esvellats, pensant a qui porien nomenar<\/em>\u00bb. Y despu\u00e9s de reflexionar concienzudamente, de forma un\u00e1nime decidieron rogar al can\u00f3nigo Vicente Mart\u00ed que se hiciese cargo del caso, puesto que, seg\u00fan su parecer, aunque en Orihuela hab\u00eda personas fidel\u00edsimas y con habilidad para negociar, no hab\u00eda nadie que conociese mejor que \u00e9l la cuesti\u00f3n del obispado.<\/p>\n<p>Por ello, le rogaron que aceptase la designaci\u00f3n, pero se neg\u00f3 tajantemente a embarcarse en tama\u00f1o empe\u00f1o. El 21 de agosto, los ediles se quedaron sin argumentos con los que poder convencer directamente al cl\u00e9rigo, y como \u00faltimo recurso escribieron al gobernador Maza \u00ab<em>molt afectadament<\/em>\u00bb, rog\u00e1ndole para le pidiese a Mart\u00ed que aceptase encargarse de la crucial embajada<sup>229<\/sup>. Maza trat\u00f3, asimismo, de convencerle, pero sus solicitudes fueron, igualmente, vanas.<\/p>\n<p>Por ello, las autoridades oriolanas decidieron aplazar la elecci\u00f3n del procurador, al menos, hasta la llegada a Orihuela de las cartas reales, y en dicho cometido se centraron. Se determinaron a enviar a Madrid a un correo para que pagase los escritos y se los llevase a la ciudad del Bajo Segura. Y deliberaron escoger a \u00ab<em>algun home de fiar y de bon recapte, perque la despesa sera poc mes y lo profit sera molt<\/em>\u00bb. El \u00ab<em>esperimentat<\/em>\u00bb notario Andr\u00e9s Arnal cumpl\u00eda ambos requisitos, era persona \u00ab<em>de bon recapte y apasionat<\/em>\u00bb por la causa del obispado, por lo que los mun\u00edcipes le pidieron que se encargase de la delicada misi\u00f3n. Arnal les contest\u00f3 que ir\u00eda siempre y cuando el gobernador Maza, a cuyo servicio estaba, le concediese su permiso. De esa manera, los ediles tuvieron que volver a escribir a D. Pedro para pedirle que dejase a Arnal ir a la corte, e intentaron convencerle asegur\u00e1ndole que, al ser el asunto de tanta importancia, no quer\u00edan que \u00ab<em>altra persona anas sino ell<\/em>\u00bb<sup>230<\/sup>. Maza les contest\u00f3 negativamente, y los oficiales municipales tuvieron que buscar a otro correo fiable.<\/p>\n<p>Por fin, el 6 de septiembre encomendaron la tarea a Jaime Franch, y le entregaron 30 ducados, 12 como pago por el viaje, y los restantes 18 para pagar las cartas<sup>231<\/sup>.<\/p>\n<p>Tras la designaci\u00f3n del correo, los mun\u00edcipes pasaron los dos d\u00edas siguientes redactando diferentes cartas de agradecimiento para sus aliados en la corte (el doctor Juan Ram, el escribano de registro Jimeno S\u00e1nchez del Vilar, el gran canciller Gattinara, Bartolom\u00e9 de Gattinara, el escribano de mandamiento Juan Vaguer, el secretario Hugo de Urries, y el doctor Soriano)<sup>232<\/sup>. El 9 de septiembre le escribieron una carta a D. Jaime Cabrero, obispo electo de Huesca, para felicitarle por su nombramiento<sup>233<\/sup>. Y despu\u00e9s, con todas las misivas, Jaime Franch parti\u00f3 en direcci\u00f3n a la villa del oso y el madro\u00f1o<sup>234<\/sup>.<\/p>\n<p>Una vez en Madrid, el correo reparti\u00f3 las cartas, y consigui\u00f3 que Juan Vaguer le entregase, previo pago, las dos misivas reales. Terminada su labor, Franch retorn\u00f3 a Orihuela, ciudad a la que arrib\u00f3 el 3 de octubre<sup>235<\/sup>.<\/p>\n<p>A su llegada, el correo entreg\u00f3 a los mandatarios los anhelados escritos, y les refiri\u00f3 de palabra que el escribano Vaguer le hab\u00eda dicho que ser\u00eda muy \u00fatil para la empresa que consiguiesen algunas cartas de recomendaci\u00f3n para el embajador May de los duques de Segorbe y de Calabria, de D\u00aa. Germana de Foix, y del gobernador Maza, que ten\u00edan cierto ascendiente sobre \u00e9l.<\/p>\n<p>Las autoridades oriolanas consideraron muy acertada la recomendaci\u00f3n, y el 6 de octubre escribieron a los citados nobles solicit\u00e1ndoles la concesi\u00f3n de la gracia<sup>236<\/sup>. Y le encargaron a Perot P\u00e9rez -que segu\u00eda el transcurso de las Cortes ante D. Fernando de Arag\u00f3n- que, con la ayuda del doctor Ros, les pidiera personalmente que escribiesen las referidas misivas, y que cuando las tuviese en su poder, las mandase con toda celeridad a Orihuela<sup>237<\/sup>.<\/p>\n<p>Por otra parte, tres d\u00edas despu\u00e9s -el 9 de octubre-, el cap\u00edtulo del Salvador y el <em>Consell<\/em> decidieron revocar, sin nota de infamia, el sindicato del abogado Jer\u00f3nimo Soriano, puesto que el Pleito del Obispado hab\u00eda sido remitido a la Santa Sede y no ten\u00edan ninguna necesidad de mantener a ning\u00fan procurador en la corte<sup>238<\/sup>. Y le encargaron a Vicente Mart\u00ed que le notificase la revocaci\u00f3n<sup>239<\/sup>. Sin embargo, el can\u00f3nigo se neg\u00f3 de nuevo a ir a la corte, que se hallaba en Toledo, y la presentaci\u00f3n de la anulaci\u00f3n del sindicato qued\u00f3 en suspenso durante unos d\u00edas.<\/p>\n<p>El 21 de octubre, las autoridades de la ciudad decidieron que fuese Jaime Franch quien se encargase de tal misi\u00f3n. Y aprovecharon su inminente partida para la corte para escribir un par de cartas, dirigidas al escribano Juan Vaguer, y al aludido Jer\u00f3nimo Soriano. Al primero le agradecieron sus servicios y consejos<sup>240<\/sup>. Y al segundo, le explicaron el porqu\u00e9 de su cese, le agradecieron todos los favores que hab\u00eda prestado a la causa episcopal, y le aclararon que cuando tuviesen que preparar alguna escritura o hubiesen de hacer cualquier diligencia en la corte, acudir\u00edan a \u00e9l, y le pagar\u00edan tan \u00ab<em>magnificament<\/em>\u00bb que quedar\u00eda \u00ab<em>molt satisfet<\/em>\u00bb<sup>241<\/sup>.<\/p>\n<p>Y ocho d\u00edas despu\u00e9s, el 29 de octubre, Jaime Franch volvi\u00f3 a partir de Orihuela en direcci\u00f3n a la corte real<sup>242<\/sup>. Lleg\u00f3 a Toledo a principios de noviembre, realiz\u00f3 con correcci\u00f3n la labor que le hab\u00edan encomendado, y regres\u00f3 a la ciudad del Bajo Segura.<\/p>\n<ol start=\"12\">\n<li><strong> Los preparativos de la embajada de Juan Mir\u00f3 a Roma.<\/strong><\/li>\n<\/ol>\n<p>Tras la llegada a Orihuela de las cartas reales para Clemente VII y el embajador May, las autoridades civiles y eclesi\u00e1sticas de la ciudad se dedicaron a preparar la embajada a la Santa Sede. Dicha labor les ocup\u00f3 los meses de noviembre y diciembre.<\/p>\n<p>No obstante, durante la segunda mitad del \u00faltimo mes del a\u00f1o tuvieron que preocuparse por otra cuesti\u00f3n, que estaba haci\u00e9ndose bastante pesada. Hubieron de hacer frente a las pertinaces reclamaciones monetarias del can\u00f3nigo Jaime G\u00f3mez, quien no desist\u00eda de su intenci\u00f3n de cobrar la cantidad que le adeudaban por sus pret\u00e9ritas \u00abactividades\u00bb en la Curia romana.<\/p>\n<p>Si hacemos un poco de memoria, recordaremos que G\u00f3mez les requiri\u00f3 varias veces que le dejasen presentar las cuentas de su embajada. Pues bien, ante las reiteradas negativas de los mandatarios, le refiri\u00f3 el problema a D. Pedro Maza, pero el gobernador tampoco solucion\u00f3 su situaci\u00f3n. Por ello, decidi\u00f3 recurrir ante los virreyes, quienes por una provisi\u00f3n dada en Valencia el 7 de septiembre de ese mismo 1528 le mandaron al lugarteniente del gobernador, D. Luis Togores, bajo pena de 1.000 florines de oro, que con celeridad propusiese el remedio m\u00e1s oportuno para el caso. La orden tampoco signific\u00f3 que el can\u00f3nigo G\u00f3mez consiguiese su objetivo, por lo que volvi\u00f3 a suplicar en repetidas ocasiones a los virreyes que se encargasen personalmente de dar soluci\u00f3n a su problema. Y, por fin, a mediados de diciembre, el duque y su esposa abocaron la causa al doctor Bartolom\u00e9 Ramos, del <em>Real Consell<\/em>, para su resoluci\u00f3n.<\/p>\n<p>El d\u00eda 16 de dicho mes, el can\u00f3nigo G\u00f3mez envi\u00f3 a su procurador, un notario apellidado L\u00f3pez, al domicilio particular del doctor Bartolom\u00e9 Ramos, para presentarle la comisi\u00f3n. \u00c9ste se ofreci\u00f3 a solventar la cuesti\u00f3n sin mayores dilaciones. Y para ello, despach\u00f3 letras citatorias convocando a ambas partes para que le prestasen declaraci\u00f3n<sup>243<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, tras muchas cavilaciones y debates, los <em>Electos<\/em> aceptaron una propuesta de Lope Ferr\u00e1ndez de Mesa y cometieron a Juan Mir\u00f3 -cu\u00f1ado del m\u00e1s conocido e insigne Jaime Despuig- la delicad\u00edsima misi\u00f3n de llevar las misivas reales a Roma y de representar a Orihuela en los actos judiciales.<\/p>\n<p>Y poco despu\u00e9s, el 27 de diciembre, dieron un nuevo paso al respecto, encomendando a Juan Masquefa y Juan de Loazes la tarea de cargar algunos censales con el prop\u00f3sito de obtener dinero con el que sufragar los gastos iniciales de la embajada de Mir\u00f3<sup>244<\/sup>.<\/p>\n<p>Antes de que acabase 1528, el procurador del can\u00f3nigo G\u00f3mez les present\u00f3 a los mandatarios de la ciudad los despachos citatorios expedidos por el doctor Ramos. De inmediato, las autoridades le respondieron que sus procuradores acudir\u00edan al emplazamiento dentro del plazo asignado.<\/p>\n<p>Una vez realizada la notificaci\u00f3n, los ediles reflexionaron sobre el tema y decidieron aprovechar que Perot P\u00e9rez y Lope Ferr\u00e1ndez de Mesa estaban en Valencia, participando en las Cortes, para cometerles su representaci\u00f3n en la causa. Por ello, el 2 de enero de 1529 les hicieron una procura, concedi\u00e9ndoles facultad para intervenir en la lite, y les enviaron algunas cartas explicativas y de recomendaci\u00f3n para los doctores Figuerola, Ros, Bas, Ubach, y Filibert, para el notario Lluch Joan Riudaura, y para el propio juez Bartolom\u00e9 Ramos<sup>245<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s, les encargaron a P\u00e9rez y Ferr\u00e1ndez una nueva labor, que le pidiesen a D. Ram\u00f3n Lladr\u00f3, se\u00f1or de Castalla y Onil, que en nombre de la ciudad negociase con alguna compa\u00f1\u00eda mercantil la apertura en Roma de una l\u00ednea de cr\u00e9dito para Juan Mir\u00f3 de hasta 1.000 ducados<sup>246<\/sup>.<\/p>\n<p>El 11 de enero Lope Ferr\u00e1ndez de Mesa hizo acto de comparecencia ante Bartolom\u00e9 Ramos como procurador del cap\u00edtulo y la ciudad de Orihuela y comenz\u00f3 la vista del litigio. Paralelamente, las partes se sentaron a negociar extrajudicialmente, y el 15 de enero acordaron que la \u00ab<em>causa de comptes<\/em>\u00bb fuese solucionada por los \u00ab<em>jutges comptadors<\/em>\u00bb designados por las autoridades oriolanas (Juan Jim\u00e9nez, Bartolom\u00e9 Cascant, Jaime Ruiz y Juan Mart\u00ed). Por ello, Jaime G\u00f3mez le comunic\u00f3 a Ramos la retirada de la denuncia y, seguidamente, volvi\u00f3 a la ciudad del Bajo Segura. All\u00ed inici\u00f3 la revisi\u00f3n de sus cuentas pero, tal como hab\u00eda sucedido con anterioridad, no logr\u00f3 entenderse con los contadores, y el d\u00eda 27 de dicho primer mes del a\u00f1o tom\u00f3 la decisi\u00f3n de renunciar a su arbitraje y de confiarse a la equidad de los <em>Electos<\/em>. De esta manera, el chantre Jaime de Soler, los can\u00f3nigos Juan de Vilafranca y Vicente Mart\u00ed, el justicia Bartolom\u00e9 Cascant, Jaime Masquefa -se\u00f1or de la Daya- y Jaime Despuig estudiaron el caso y reconocieron, finalmente, que la deuda ascend\u00eda a poco m\u00e1s de 110 libras. Y le prometieron que las cobrar\u00eda de modo fraccionado, en tres pagas anuales que saldr\u00edan de la \u00ab<em>renda del diner de la carn<\/em>\u00bb<sup>247<\/sup>.<\/p>\n<p>Por otra parte, las autoridades de Orihuela comenzaron el mes de febrero recibiendo una carta del inquisidor Sancho V\u00e9lez, fechada el 30 de enero, en la que les anunciaba su intenci\u00f3n de presentarse en breve en la ciudad para ejercer el santo oficio, y les ped\u00eda que preparasen posadas tanto para \u00e9l como para sus oficiales y ministros<sup>248<\/sup>.<\/p>\n<p>Ello, sin embargo, no distrajo la atenci\u00f3n de los mandatarios que por entonces se hallaban ultimando los preparativos de la embajada de Juan Mir\u00f3 a Roma. El 3 de febrero enviaron dos cartas a Valencia. Una para D. Jer\u00f3nimo de Vic, en la que le informaban del pr\u00f3ximo viaje del s\u00edndico y le rogaban que enviase a sus conocidos en la Ciudad Eterna algunas cartas en recomendaci\u00f3n de la causa episcopal<sup>249<\/sup>. Y otra de D. Ram\u00f3n de Rocafull, dirigida a D. Ram\u00f3n Lladr\u00f3, en la que el se\u00f1or de Albatera le ped\u00eda al de Castalla, como un favor personal, que se diese prisa en conseguir las p\u00f3lizas habilitadoras del cr\u00e9dito romano<sup>250<\/sup>.<\/p>\n<p>Dicho d\u00eda redactaron tambi\u00e9n una primera carta de creencia para el cardenal Salviatis, solicit\u00e1ndole que ayudase al procurador oriolano en la medida de sus posibilidades, y que le informase al santo padre de \u00ab<em>las pasiones de Castilla<\/em>\u00bb para que \u00ab<em>mande tornar al estamento que estava facta erectione<\/em>\u00bb<sup>251<\/sup>.<\/p>\n<p>Durante los d\u00edas siguientes, las autoridades continuaron la tarea de prepararle a Mir\u00f3 la documentaci\u00f3n que hab\u00eda de llevarse a la capital del Orbe Cat\u00f3lico. El d\u00eda 8 de febrero firmaron otras cinco cartas de creencia para el s\u00edndico, dirigidas al doctor Saganta, al penitenciario y auditor de la Rota Luis G\u00f3mez -familiar del cardenal Santiquatro<sup>252<\/sup>-, al embajador Miguel May, al caballero Gaspar Marrades -pros\u00e9lito de May- y a Mart\u00edn Ferr\u00e1ndez de Mesa -mayordomo del cardenal Fernes-.<\/p>\n<p>Al doctor Saganta le pidieron que fuese planificando las gestiones que habr\u00eda que realizar para que la causa fuese introducida en el consistorio pontificio con la mayor brevedad<sup>253<\/sup>.<\/p>\n<p>Al doctor Luis G\u00f3mez, cuyo paradero desconoc\u00edan puesto que a ra\u00edz del Saco de Roma hab\u00eda tenido que huir a N\u00e1poles, le rogaron que en el caso de que estuviese en la capital de los Estados Pontificios, como \u00ab<em>fill de la terra<\/em>\u00bb, auxiliase a Mir\u00f3, y que, si, por el contrario, estaba fuera de dicha ciudad, escribiese cartas en recomendaci\u00f3n de la causa oriolana a las personas que supiese que podr\u00edan favorecerla<sup>254<\/sup>.<\/p>\n<p>Al embajador May le recordaron \u00ab<em>les vexations, treballs e despeses que aquesta ciutat e capitol han sostengut en lo pleyt de la sglesia catredal, causant-ho les favores e impurtunatio dels castellans<\/em>\u00bb. Le dijeron que lo ten\u00edan por \u00ab<em>persona molt justificada<\/em>\u00bb, y que sab\u00edan que buscar\u00eda \u00ab<em>la raho e justicia<\/em>\u00bb. Apelaron a su nacionalidad para pedirle que con su intervenci\u00f3n les librase \u00ab<em>de la submissio castellana, tant enemiga y contraria a la gent catalana e valenciana<\/em>\u00bb. Y, por \u00faltimo, le rogaron que ayudase a Mir\u00f3 en sus trabajos<sup>255<\/sup>.<\/p>\n<p>Al caballero Marrades le indicaron que sab\u00edan que era \u00ab<em>natural de la ciutat de Valencia, a la qual Oriola te per mare<\/em>\u00bb, y le solicitaron que ayudase al s\u00edndico oriolano cuando se presentase ante May<sup>256<\/sup>.<\/p>\n<p>Y, por \u00faltimo, a Mart\u00edn Ferr\u00e1ndez de Mesa -que era hermano de Lope- le pidieron que junto a Juan Mir\u00f3 se encargase de realizar las diligencias que fuesen oportunas, siguiendo los consejos de Saganta y del abogado Juan Luis Aragona, y que tratase de conseguir el favor del cardenal Fernes<sup>257<\/sup>.<\/p>\n<p>Asimismo, el 8 de febrero las autoridades oriolanas enviaron a Valencia otros tres escritos de contenido muy similar. En ellos, les rogaron a D. Pedro Maza de Lizana, a los jurados de dicha ciudad, y al cap\u00edtulo de la iglesia Metropolitana que escribiesen al embajador May y al caballero Marrades en recomendaci\u00f3n de la causa episcopal<sup>258<\/sup>.<\/p>\n<p>El d\u00eda siguiente, los <em>Electos<\/em> concluyeron la redacci\u00f3n del extens\u00edsimo instrumento que recog\u00eda las instrucciones que Mir\u00f3 hab\u00eda de seguir a su llegada a Roma.<\/p>\n<p>En primer lugar, nada m\u00e1s arribar a la Ciudad Eterna, el s\u00edndico ten\u00eda que ordenar la celebraci\u00f3n de una misa a fin de lograr el favor divino para la causa. A continuaci\u00f3n, hab\u00eda de entablar contacto con los diferentes aliados de Orihuela: Mart\u00edn Ferr\u00e1ndez de Mesa, el doctor Saganta, Luis G\u00f3mez y el caballero Marrades. Despu\u00e9s, con la ayuda de este \u00faltimo, ten\u00eda que presentarse ante el embajador May, entregarle las dos cartas reales, y pedirle que le llevase al papa la suya y que le suplicase de parte de Carlos I que decretase la revisi\u00f3n judicial del Pleito del Obispado. Mir\u00f3 deb\u00eda, asimismo, impedir las posibles contradicciones que pudiese efectuar los murcianos.<\/p>\n<p>Una vez que el papa hubiese aceptado la voluntad real, el procurador hab\u00eda de conseguir que la causa fuese remitida al tribunal de la Sacra Rota. All\u00ed, deb\u00eda lograr que el auditor diputado decretase la suspensi\u00f3n cautelar de los breves revocatorios y la absoluci\u00f3n de las censuras eclesi\u00e1sticas lanzadas contra el clero y el pueblo de Orihuela por el incumplimiento de los citados rescriptos. Acto seguido, ten\u00eda que conseguir que el papa aceptase nombrar a los obispos de Segorbe y Barcelona como \u00ab<em>conservadores<\/em>\u00bb de la Catedral del Salvador, de modo que pudiesen defender sus honores y preeminencias en el caso de que sufriesen alg\u00fan ataque o perjuicio por parte de los murcianos. Adem\u00e1s, en este sentido, para lograr la autosuficiencia espiritual, al menos temporalmente, hab\u00eda de suplicarle al pont\u00edfice que mandase a Orihuela a alg\u00fan \u00ab<em>antistite<\/em>\u00bb, a alg\u00fan eclesi\u00e1stico facultado para \u00ab<em>poder donar corones e altres ordens<\/em>\u00bb, y para impartir \u00ab<em>lo sagrament de confirmacio<\/em>\u00bb.<\/p>\n<p>El instrumento recog\u00eda, asimismo, la posibilidad de que el papa, bien por influencia de los murcianos-castellanos, bien por un cambio de opini\u00f3n del rey Carlos, se negase a modificar la situaci\u00f3n episcopal. En tal caso, el procurador tendr\u00eda que recurrir contra dicha decisi\u00f3n ante el mismo pont\u00edfice, y si Su Santidad le denegase la apelaci\u00f3n, habr\u00eda de interponer una protesta <em>a futuro gravamine<\/em>, en espera de tiempos mejores, ante varios cl\u00e9rigos honrados y probos.<\/p>\n<p>Por otra parte, Mir\u00f3 ten\u00eda tambi\u00e9n la misi\u00f3n de conseguir la absoluci\u00f3n de todas las penas de excomuni\u00f3n, suspensi\u00f3n o entredicho que los inquisidores del obispado de Cartagena hab\u00edan lanzado sobre la ciudad del Bajo Segura en los \u00faltimos a\u00f1os. No pod\u00eda, en cambio, negociar ning\u00fan tipo de asuntos de particulares. Y sobre el dinero de la l\u00ednea de cr\u00e9dito, especificaba muy claramente que s\u00f3lo podr\u00eda utilizarlo para pagar los gastos derivados de la expedici\u00f3n de bulas o breves, y que para conseguirlo habr\u00eda de solicitarlo con el permiso y bajo la supervisi\u00f3n de Mart\u00edn Ferr\u00e1ndez de Mesa<sup>259<\/sup>.<\/p>\n<p>Ese mismo d\u00eda 9 de febrero, los <em>Electos<\/em> terminaron tambi\u00e9n la redacci\u00f3n de un \u00ab<em>memorial del estament de la causa<\/em>\u00bb que inclu\u00eda una pormenorizada relaci\u00f3n de los hechos m\u00e1s destacados de la historia reciente del obispado de Orihuela, desde su creaci\u00f3n a instancias de Fernando el <em>Cat\u00f3lico<\/em>. Gracias a \u00e9l, el embajador oriolano podr\u00eda tener en todo momento una idea muy precisa de todos los acontecimientos e incidencias que pudiesen guardar alguna relaci\u00f3n con la problem\u00e1tica episcopal<sup>260<\/sup>.<\/p>\n<p>El d\u00eda siguiente -10 de febrero-, redactaron una \u00faltima carta, dirigida a D. Ram\u00f3n Lladr\u00f3, en la que le pidieron que le entregase a Juan Mir\u00f3 las letras del cr\u00e9dito a su paso por Valencia<sup>261<\/sup>.<\/p>\n<p>Y a continuaci\u00f3n le entregaron al s\u00edndico la documentaci\u00f3n preparada, y Juan Mir\u00f3 inici\u00f3 su largo viaje<sup>262<\/sup>.<\/p>\n<ol start=\"13\">\n<li><strong> La definitiva absoluci\u00f3n de las censuras inquisitoriales.<\/strong><\/li>\n<\/ol>\n<p>El d\u00eda 12 de febrero, el cabildo de Cartagena y las autoridades civiles de la ciudad de Murcia consiguieron, por fin, la expedici\u00f3n del ejecutorial real tantas veces demandado. Tras escuchar las continuadas argumentaciones de sus procuradores, fundamentadas en el hecho de que \u00ab<em>desde que las dichas \u00e7ibdades son de christianos siempre la yglesia de la \u00e7ibdad de Origuela fue collegial e subjeta a la dicha yglesia e obispado de Cartagena<\/em>\u00bb, Carlos I opt\u00f3 por concederles el auxilio del brazo secular. As\u00ed, mand\u00f3 al corregidor de Murcia, Jorge Ruiz de Alarc\u00f3n, que cuando el cabildo de Cartagena le pidiese ayuda para ejecutar los rescriptos apost\u00f3licos revocatorios, se la proporcionase sin consultas ni dilaciones. Y lo mismo les orden\u00f3 a todos los \u00ab<em>grandes y cavalleros del nuestro Reyno de Mur\u00e7ia, y a los Con\u00e7ejos, justi\u00e7ias, regidores, cavalleros, escuderos, ofi\u00e7iales y honbres buenos de todas las \u00e7ibdades, villas y lugares, asi del dicho nuestro Reyno de Mur\u00e7ia y de su comarca, commo del nuestro Marquesado de Villena<\/em>\u00bb, bajo pena de la merced real, la p\u00e9rdida de los oficios que detentasen, y la confiscaci\u00f3n de la mitad de sus bienes<sup>263<\/sup>.<\/p>\n<p>El despacho del ejecutorial real no result\u00f3, finalmente, ning\u00fan problema insoslayable para los oriolanos. Las autoridades civiles citadas en el instrumento \u00fanicamente ten\u00edan jurisdicci\u00f3n dentro de los l\u00edmites de la Corona de Castilla, y si los habitantes de Orihuela no cruzaban la frontera -cosa que, desde luego, no ten\u00edan ninguna intenci\u00f3n de hacer-, no corr\u00edan ning\u00fan peligro de que los mandatarios murcianos pudiesen obligarles a aceptar los referidos breves y, consecuentemente, la anulaci\u00f3n del obispado y la vuelta a la obediencia cartaginense. En nuestra opini\u00f3n, los oriolanos debieron respirar aliviados al conocer que el ejecutorial hab\u00eda sido dirigido a las autoridades seculares de Murcia, y no al duque de Calabria o al gobernador Maza.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el 16 de febrero, el licenciado Sancho V\u00e9lez se present\u00f3 en la ciudad del Bajo Segura. Y como era casi su obligaci\u00f3n, por ser tambi\u00e9n provisor del obispado de Cartagena, trat\u00f3 de perjudicar los intereses oriolanos en el Pleito comenzando sus intervenciones en calidad de \u00ab<em>inquisidor del bisbat de Cartagena y del partido de Orihuela<\/em>\u00bb, tal como lo hab\u00eda hecho ya en marzo de 1527.<\/p>\n<p>La reacci\u00f3n de las autoridades civiles de la ciudad fue inmediata. Ese mismo d\u00eda, por medio del procurador Andr\u00e9s Arnal, le interpusieron una protesta contra su intitulaci\u00f3n, le suplicaron que no se entrometiese en cuestiones que pudiesen perjudicar <em>modo aliquo<\/em> sus derechos en la lite del obispado, y le comunicaron que si decid\u00eda proseguir su labor sin modificar el citado t\u00edtulo, apelar\u00edan contra cada uno de los actos que llevase a cabo. El inquisidor, viendo frustradas sus intenciones, les contest\u00f3 que no pretend\u00eda perjudicarles y s\u00ed ejercer el Santo Oficio, y si tenemos en cuenta los indicios documentales, podemos afirmar -no sin cierto riesgo- que se avino a efectuar dicha tarea como inquisidor del Reino de Murcia y de la gobernaci\u00f3n de Orihuela<sup>264<\/sup>.<\/p>\n<p>Poco antes de que Juan Mir\u00f3 llegase a Roma, el 14 de marzo de ese mismo a\u00f1o 1529, el <em>Consell<\/em> de la ciudad se reuni\u00f3 para aprobar el despacho de un instrumento de \u00ab<em>guardament de dan<\/em>\u00bb para D. Ram\u00f3n Lladr\u00f3, quien, finalmente, consigui\u00f3 que los mercaderes Urban de Novara y Francesco Passabonello le concediesen al aludido procurador la l\u00ednea de cr\u00e9dito de 1.000 ducados. Dos d\u00edas despu\u00e9s, el documento fue expedido, y por \u00e9l las autoridades civiles oriolanas se comprometieron a pagar a los financieros, en lugar de Lladr\u00f3, las cantidades que Mir\u00f3 tomase en la Ciudad Eterna, as\u00ed como los cambios, recambios e intereses pactados<sup>265<\/sup>.<\/p>\n<p>No hemos podido conocer la fecha exacta de la llegada del mencionado s\u00edndico a la capital del Orbe Cat\u00f3lico. Sin embargo, con casi total seguridad, \u00e9sta debi\u00f3 producirse en la segunda quincena de marzo. Lo que s\u00ed podemos afirmar es que, tras su arribada, Mir\u00f3 sigui\u00f3 al pie de la letra sus instrucciones. Sufrag\u00f3 la celebraci\u00f3n de la misa en favor de la causa. Contact\u00f3 con Mart\u00edn Ferr\u00e1ndez de Mesa y con el doctor Saganta. Los tres buscaron al caballero Gaspar Marrades y, gracias su intercesi\u00f3n, pudieron comparecer ante el embajador y entregarle los escritos reales. May recibi\u00f3 con reverencia las \u00f3rdenes de Carlos I y les respondi\u00f3 que las cumplir\u00eda. Despu\u00e9s, fueron a entrevistarse con el curial Luis G\u00f3mez, quien les prometi\u00f3 su apoyo. Todo parec\u00eda desarrollarse seg\u00fan los planes previstos.<\/p>\n<p>Una vez realizadas estas diligencias iniciales, el 2 de abril Juan Mir\u00f3 escribi\u00f3 una primera carta a las autoridades de Orihuela. En ella, les comunic\u00f3 que hab\u00eda llegado con salud a Roma; les coment\u00f3 las gestiones que hab\u00eda efectuado; les inform\u00f3 que Mart\u00edn Ferr\u00e1ndez de Mesa se hab\u00eda enfadado porque no le hab\u00edan enviado ninguna carta; y, por \u00faltimo, les refiri\u00f3 que su siguiente objetivo radicar\u00eda en tratar de conseguir el breve absolutorio de las censuras inquisitoriales<sup>266<\/sup>.<\/p>\n<p>Durante todo el mes de abril, Mir\u00f3, Ferr\u00e1ndez, Saganta y el abogado Aragona trabajaron en la Curia en pos de dicho logro. La intervenci\u00f3n del penitenciario Luis G\u00f3mez result\u00f3 esencial. El d\u00eda 19 de dicho mes el despacho del rescripto deb\u00eda estar ya apalabrado, puesto que Mir\u00f3, ante la presencia de Ferr\u00e1ndez, tom\u00f3 a pr\u00e9stamo 100 libras, a fin de sufragar los costes y otros gastos derivados de su expedici\u00f3n<sup>267<\/sup>. \u00c9sta se produjo el \u00faltimo d\u00eda de abril. Firm\u00f3 el breve el propio Luis G\u00f3mez, y fue dirigido a tres eclesi\u00e1sticos del Reino de Valencia: el obispo de Segorbe, el vicario general del arzobispado valentino -D. Guillem Desprats-, y el prior del monasterio de Santo Domingo -de la orden de Predicadores-, tambi\u00e9n en la ciudad del Turia. El documento decretaba la absoluci\u00f3n de todas las censuras y penas eclesi\u00e1sticas que hubiesen impuesto los inquisidores del obispado de Cartagena -principalmente, Salvatierra, Ugarte y Y\u00e1\u00f1ez- sobre el clero y el pueblo de Orihuela<sup>268<\/sup>. Una vez lo tuvo Mir\u00f3 en sus manos, lo que acaeci\u00f3 el 5 de mayo, lo remiti\u00f3 a la ciudad del Bajo Segura<sup>269<\/sup>.<\/p>\n<p>Tres d\u00edas despu\u00e9s -el 8 de mayo-, el duque de Calabria dio por clausuradas las Cortes iniciadas el a\u00f1o anterior, tras superar algunos problemas relacionados con la guarda de la costa<sup>270<\/sup>.<\/p>\n<p>A principios de junio lleg\u00f3 a Orihuela, con bastante retraso, la misiva que envi\u00f3 Juan Mir\u00f3 el 2 de abril. Las autoridades civiles y eclesi\u00e1sticas de la ciudad recibieron esperanzadas las nuevas romanas. El d\u00eda 5 de ese mismo mes escribieron cuatro cartas, dirigidas a Juan Mir\u00f3, Mart\u00edn Ferr\u00e1ndez de Mesa, Luis G\u00f3mez y Gaspar Marrades.<\/p>\n<p>Al procurador, que estaba residiendo junto a Ferr\u00e1ndez, en la posada del cardenal Fernes, le dieron aviso de la llegada del escrito anteriormente citado. Le recomendaron -premonitoriamente- que buscase el apoyo de Luis G\u00f3mez, pues podr\u00eda resultar fundamental a todos los efectos. Sobre el enfado de su compa\u00f1ero de residencia, le pidieron que le mostrase el instrumento de las instrucciones para que viese que contaban con \u00e9l para todo, y que le dijese que su carta se hab\u00eda extraviado de camino a Roma y que se la volv\u00edan a remitir. Tambi\u00e9n le solicitaron a Mir\u00f3 que pusiese la m\u00e1xima diligencia en el negocio de la absoluci\u00f3n de las censuras inquisitoriales (a\u00fan no sab\u00edan que ya hab\u00eda obtenido el breve). Asimismo, le ordenaron que vigilase la posada de May, por si aparec\u00eda alg\u00fan procurador murciano o el embajador recib\u00eda cartas contrarias del rey. Le indicaron que, de su parte, prometiese suculentas recompensas a Marrades y a G\u00f3mez si ayudaban a la causa. Y, por \u00faltimo, le rogaron que enviase sus escritos a buen recaudo y pagando portes elevados, con el fin de que no se perdiesen por el camino o cayesen en manos extra\u00f1as. Tal era la desconfianza que sent\u00edan hacia los murcianos y sus manejos<sup>271<\/sup>.<\/p>\n<p>Al mayordomo del cardenal Fernes le indicaron que no deb\u00eda estar resentido contra ellos. Le explicaron que el asunto de la carta no hab\u00eda sido fruto ni de un olvido ni de un descuido por su parte, y que el causante del malentendido hab\u00eda sido el propio Juan Mir\u00f3. Le aseguraron que el escrito exist\u00eda, y para que pudiese comprobarlo, le remitieron adjunta una copia aut\u00e9ntica de la letra original. Adem\u00e1s, le dijeron que quer\u00edan que aconsejase y acompa\u00f1ase a Mir\u00f3 siempre que pretendiese realizar alguna gesti\u00f3n, y que incluso hab\u00edan dispuesto que \u00e9ste, cuando desease tomar dinero prestado de su l\u00ednea de cr\u00e9dito, ineludiblemente tuviese que pedirle su consentimiento. Dejando aparte este espinoso tema, le manifestaron que se hab\u00edan enojado mucho al conocer que durante el Saco de Roma, los soldados imperiales se hab\u00edan cebado en el expolio y la destrucci\u00f3n de la casa del monse\u00f1or de Fernes porque en ella guardaba los autos y documentos relativos al Pleito del Obispado que hab\u00eda dejado en su poder el can\u00f3nigo Jaime G\u00f3mez antes de regresar a Espa\u00f1a. En este sentido, le pidieron que le presentase las excusas de la ciudad al cardenal. Y, por \u00faltimo, le rogaron que siguiese encarg\u00e1ndose de los asuntos oriolanos con la pasi\u00f3n que siempre le hab\u00eda caracterizado<sup>272<\/sup>.<\/p>\n<p>Al auditor G\u00f3mez le agradecieron las muestras de favor que hab\u00eda mostrado hacia la causa. Apelaron a su condici\u00f3n de \u00ab<em>natural de la patria<\/em>\u00bb para pedirle que continuase prestando su inestimable ayuda a los representantes oriolanos. Para que fuese a\u00fan m\u00e1s consciente de la trascendencia del asunto, le explicaron que la revocaci\u00f3n del obispado supondr\u00eda \u00ab<em>destroyr aquesta terra per les favors dels castellans<\/em>\u00bb, y le manifestaron que confiaban en que su mediaci\u00f3n sirviese para que el cap\u00edtulo del Salvador y los habitantes de la ciudad se viesen libres \u00ab<em>de la captivitat en que nostres pasats estigueren<\/em>\u00bb. Y, por \u00faltimo, le ofrecieron sus servicios de un modo incondicional<sup>273<\/sup>.<\/p>\n<p>Y en cuarto lugar, al caballero Marrades le agradecieron el apoyo que hab\u00eda prestado a Mir\u00f3 y sus compa\u00f1eros ante el embajador real, le pidieron que siguiese favoreci\u00e9ndolos desde su privilegiada posici\u00f3n, y le comunicaron que no ser\u00edan ingratos con \u00e9l<sup>274<\/sup>.<\/p>\n<p>Ese mismo d\u00eda 5 redactaron otras dos misivas. Una para D. Pedro Maza, suplic\u00e1ndole que le escribiese a su servidor Marrades, pidi\u00e9ndole que ayudase a los oriolanos<sup>275<\/sup>. Y otra para D. Guillem Desprats, vicario general del arzobispado de Valencia y abad de San Marcial, rog\u00e1ndole que enviase el pliego de cartas a Roma<sup>276<\/sup>.<\/p>\n<p>El 13 de junio lleg\u00f3 a la ciudad del Bajo Segura el breve absolutorio. R\u00e1pidamente, el <em>Consell<\/em> se reuni\u00f3 y nombr\u00f3 procurador al can\u00f3nigo Juan de Vilafranca, que tambi\u00e9n hab\u00eda sido distinguido con tal cargo por el cap\u00edtulo del Salvador. Ambas instituciones le asignaron la misi\u00f3n de ir a Valencia a presentar el rescripto a sus ejecutores<sup>277<\/sup>.<\/p>\n<p>Tres d\u00edas m\u00e1s tarde, le entregaron a Vilafranca cartas de creencia para el vicario general, el obispo de Segorbe y el prior del monasterio de Santo Domingo; un documento que inclu\u00eda las instrucciones que hab\u00eda de seguir para lograr la ejecuci\u00f3n del breve; una misiva para D. Pedro Maza, en la que le ped\u00edan que volviese a escribir a Marrades para agradecerle sus servicios; otra para D. Jer\u00f3nimo Vic, rog\u00e1ndole que escribiese a su criado Julio Corvino, que estaba en Roma, para que le recomendase la causa al cardenal Santiquatro; y una tercera para el influyente doctor Rubio, a fin de que ayudase a Vilafranca en su cometido<sup>278<\/sup>.<\/p>\n<p>Y el d\u00eda siguiente -17 de junio-, las autoridades le dieron otro pliego de cartas, para que se lo entregase a Guillem Desprats, y \u00e9ste lo hiciese llegar a manos de Juan Mir\u00f3. El paquete postal inclu\u00eda amplias misivas para el propio s\u00edndico, para Mart\u00edn Ferr\u00e1ndez, para Luis G\u00f3mez, para Gaspar Marrades y para el embajador May.<\/p>\n<p>Resumiendo sus contenidos, diremos que a Mir\u00f3 le escribieron que ten\u00edan esperanzas en que sus gestiones desembocaran en breve en la comisi\u00f3n de la causa a la Rota. Le felicitaron por su buena labor, compar\u00e1ndola con la desastrosa de Jaime G\u00f3mez. Le pidieron que negociase con el m\u00e1ximo sigilo para que el s\u00edndico cartaginense cerca de la Santa Sede, Sebasti\u00e1n Clavijo, siguiese sin descubrirle. Le comentaron que estaban de acuerdo con que diese propinas, <em>manchas<\/em>, a los benefactores de la causa. Y, por \u00faltimo, le indicaron que sondease las posibilidades que exist\u00edan de obtener una licencia pontificia que permitiese al cap\u00edtulo del Salvador, en ausencia del obispo -que estaba en Flandes-, proceder al nombramiento de un vicario general que rigiese la Iglesia oriolana hasta el final del Pleito<sup>279<\/sup>.<\/p>\n<p>A Mart\u00edn Ferr\u00e1ndez de Mesa le rogaron que procurase con \u00ab<em>molta ansia<\/em>\u00bb el \u00e9xito de la causa episcopal, y que les escribiese alguna carta para demostrarles que ya no estaba enfadado con ellos<sup>280<\/sup>.<\/p>\n<p>Al penitenciario G\u00f3mez -que tambi\u00e9n era abad de Villabeltr\u00e1n-, le agradecieron la firma del breve absolutorio, le suplicaron que siguiese favoreci\u00e9ndoles, y le indicaron que aceptar\u00edan con sumo gozo que fuese nombrado obispo de Orihuela, as\u00ed como que le concediesen el capelo cardenalicio<sup>281<\/sup>.<\/p>\n<p>A Marrades le volvieron a agradecer su intercesi\u00f3n cabe el embajador, y le dijeron que pidiese que lo quisiese a los caballeros de Orihuela, y que la clerec\u00eda de la ciudad no dejaba cotidianamente \u00ab<em>de pregar per la vida y casa sua<\/em>\u00bb<sup>282<\/sup>.<\/p>\n<p>Y, por \u00faltimo, a Miguel May, le rogaron que los siguiese teniendo \u00ab<em>per comendats en cosa tant justa e a raho conforme<\/em>\u00bb, que los librase \u00ab<em>de tantes fatigues e tribulacions e despeses<\/em>\u00bb, y que, de acuerdo con la voluntad real, con su mediaci\u00f3n, los liberase de \u00ab<em>la submissio de aquesta gent a nostra natio tanto contraria<\/em>\u00bb<sup>283<\/sup>.<\/p>\n<p>El d\u00eda siguiente -18 de junio- le entregaron a Vilafranca el dinero que ten\u00eda que darle a D. Ram\u00f3n Lladr\u00f3 para que pagase a los mercaderes Novara y Passabonello por la cantidad tomada por Juan Mir\u00f3 en Roma el 19 de abril<sup>284<\/sup>. Y, por fin, parti\u00f3 en direcci\u00f3n hacia la capital del Reino.<\/p>\n<p>Una vez en Valencia, el can\u00f3nigo se entrevist\u00f3 con Guillem Desprats, le entreg\u00f3 la carta que llevaba para \u00e9l y el pliego que ten\u00eda que enviar a la capital del Orbe Cat\u00f3lico. Despu\u00e9s, le mostr\u00f3 el breve absolutorio, y le pidi\u00f3 que lo ejecutase. El vicario general le respondi\u00f3 que se lo pidiese al prior de Santo Domingo. Y eso es lo que hizo Vilafranca.<\/p>\n<p>Por fin, el 25 de junio, el se\u00f1alado dominico expidi\u00f3 el ejecutorial absolutorio, quedando pendiente de su puesta en vigor<sup>285<\/sup>.<\/p>\n<p>Y el 14 de julio siguiente, el prior se person\u00f3 en la \u00abCatedral\u00bb del Salvador, y ante los can\u00f3nigos, el justicia, los jurados, el lugarteniente del gobernador y el pueblo de Orihuela, puso en ejecuci\u00f3n el rescripto haciendo efectiva de esa manera la absoluci\u00f3n general de las enquistadas censuras inquisitoriales. A continuaci\u00f3n, con la participaci\u00f3n de los frailes de la Merced, del propio cap\u00edtulo catedralicio, y de la gente que hab\u00eda asistido al acto, se organiz\u00f3 una procesi\u00f3n \u00ab<em>ab les creus de la dita sglesia, y ab molta reverencia<\/em>\u00bb al monasterio del Socorro, en cuya iglesia se dijo una misa \u00ab<em>ab molta devocio, y en la qual y ague sermo<\/em>\u00bb. Acabada la eucarist\u00eda, la solemne comitiva volvi\u00f3 a la Catedral. Y la celebraci\u00f3n concluy\u00f3 en la capilla de \u00ab<em>la Verge Maria del Roser<\/em>\u00bb con el rezo de una \u00ab<em>Salve Regina<\/em>\u00bb<sup>286<\/sup>.<\/p>\n<ol start=\"14\">\n<li><strong> La comisi\u00f3n de la causa episcopal a la Sacra Rota.<\/strong><\/li>\n<\/ol>\n<p>En julio de 1529, Carlos I y Clemente VII se reconciliaron oficialmente por el Tratado de Barcelona. La situaci\u00f3n desde el Saco de Roma -mayo de 1527- hab\u00eda cambiado sustancialmente, y el pont\u00edfice accedi\u00f3 a recibir al Rey de Romanos en Italia, y a coronarlo Emperador.<\/p>\n<p>Ante las nuevas perspectivas, el rey decidi\u00f3 marchar al encuentro del papa y, en su ausencia, nombr\u00f3 \u00ab<em>lugarteniente y procuradriz general<\/em>\u00bb a \u00ab<em>la Serenissima emperatriz e Reyna, nuestra muy cara y muy amada muger<\/em>\u00bb, Isabel de Portugal, para que se encargase del \u00ab<em>govierno y administracion de nuestros Reynos de Aragon y Valencia, y deste nuestro Prin\u00e7ipado de Catalunya, y de Mallorcas, Cerdenya y condados de Rossellon y Cerdanya, e islas a ellas annexas<\/em>\u00bb. Y desde la Ciudad Condal remiti\u00f3 diferentes cartas a sus s\u00fabditos de las distintas ciudades y villas de los citados reinos a fin de que obedeciesen, asistiesen y sirviesen a su \u00ab<em>representante en todo y por todo<\/em>\u00bb<sup>287<\/sup>.<\/p>\n<p>A finales del citado mes de julio o a principios del de agosto, las autoridades de Orihuela se enteraron de que el cabildo de Cartagena y la ciudad de Murcia hab\u00edan enviado como procurador a la corte real a un gentilhombre llamado Pedro Sambrana -que era yerno de Juan V\u00e1zquez-, con la misi\u00f3n de conseguir que el emperador escribiese al papa solicit\u00e1ndole que obviase las cartas expedidas en Monz\u00f3n el 15 de julio del a\u00f1o anterior, y que resolviese el Pleito del Obispado en favor de los intereses murcianos, sin escuchar las argumentaciones oriolanas.<\/p>\n<p>Sin embargo, quiz\u00e1 influidos por la penuria econ\u00f3mica, o porque no supieron valorar de un modo correcto el riesgo que conllevaba la embajada de Sambrana, los mandatarios de la Iglesia y la ciudad del Bajo Segura no estimaron necesario enviar a un s\u00edndico a Barcelona con el \u00fanico cometido de contrarrestar y contradecir personalmente las importunaciones murcianas. En nuestra opini\u00f3n, confiaron en la fuerza de la \u00faltima disposici\u00f3n real, decretada en virtud de un <em>acte de cort<\/em>, y en su justicia, y se equivocaron&#8230;<\/p>\n<p>Tras desechar la posibilidad del env\u00edo del s\u00edndico a la corte, el cap\u00edtulo del Salvador, el justicia y los jurados, de modo conjunto, trataron de evitar a distancia que la misi\u00f3n de Pedro Sambrana tuviese \u00e9xito. El 4 de agosto escribieron a D. Juan Cabrero -obispo de Huesca- y a D. Fernando de Loazes -dos personajes destacad\u00edsimos por su afecci\u00f3n a la causa episcopal- para que informasen al gran canciller Gattinara, y a los doctores del Consejo de Arag\u00f3n de las intenciones murcianas, y les pidiesen de su parte que intentasen impedir que Carlos I escribiese al papa cartas contrarias a las despachadas en Monz\u00f3n. Y tambi\u00e9n remitieron cuatro cartas explicativas del asunto al propio Gattinara, a Juan Ram, a Juan Jacobo de Bonomia y a Felip de Ferreres, solicit\u00e1ndoles directamente que no permitiesen que Sambrana pudiese convencer al monarca para que mandase \u00ab<em>escrevir en contrario del que tan justamente esta scrito, porque seria destroyr esta ciudat<\/em>\u00bb, y \u00ab<em>donar causa que aquestes diferencies may prenguen fi<\/em>\u00bb<sup>288<\/sup>.<\/p>\n<p>Sin embargo, todas estas misivas se convirtieron, al poco de su llegada, en papel mojado puesto que Sambrana, eficazmente, consigui\u00f3 que Carlos I accediese a sus s\u00faplicas y que, antes de embarcarse para Italia, aprobase la expedici\u00f3n una carta contradiciendo las dadas en Monz\u00f3n en favor de Orihuela. El escrito fue preparado en el seno del Consejo de Castilla por D. Juan Garc\u00eda de Padilla, y fue firmado por el secretario Cobos; y, en \u00e9l, Su Majestad le orden\u00f3 al embajador May \u00ab<em>que no entienda en que la causa se determine por justicia, y que procure que sobre ello no se aga novedat alguna<\/em>\u00bb. Ni el Consejo de Arag\u00f3n, ni el gran canciller Gattinara tuvieron noticia alguna del despacho, y puesto que el procurador murciano viaj\u00f3 junto al monarca para encargarse personalmente de evitar que las antiguas provisiones tuviesen efecto, las autoridades de Orihuela creyeron durante alg\u00fan tiempo que no hab\u00eda podido llevar a cabo su misi\u00f3n<sup>289<\/sup>.<\/p>\n<p>Entretanto, en Roma, tras la obtenci\u00f3n del breve absolutorio de las censuras inquisitoriales, Mir\u00f3 y su equipo de colaboradores se centr\u00f3 en la cuesti\u00f3n de la revisi\u00f3n judicial del Pleito del Obispado. Sin embargo, de inmediato, se toparon contra un problema de muy dif\u00edcil soluci\u00f3n. Pese a que, gracias a la valiosa intercesi\u00f3n del caballero Marrades, le suplicaron muchas veces al embajador que le mostrase a Clemente VII la carta real obtenida en las Cortes Generales del a\u00f1o anterior, May, siguiendo instrucciones del propio Carlos I, hizo o\u00eddos sordos a todas y cada una de las demandas oriolanas, y se dedic\u00f3 a poner \u00ab<em>dilacions e llongueries<\/em>\u00bb, y a retrasar la presentaci\u00f3n esperando la llegada de provisiones contrarias a la se\u00f1alada<sup>290<\/sup>.<\/p>\n<p>Pese a la oposici\u00f3n del representante real, durante los meses de junio, julio y agosto, Mir\u00f3 y Ferr\u00e1ndez intentaron conseguir extraoficialmente la revisi\u00f3n de la causa episcopal. De hecho, en cinco ocasiones, los d\u00edas 20 de junio, 22 de julio, y 6, 14 y 21 de agosto, enviaron al abogado Aragona y al procurador Saganta a la Signatura para solicitar la comisi\u00f3n de la lite a la Sacra Rota. Pero sus intentos fueron infructuosos<sup>291<\/sup>.<\/p>\n<p>Los continuados fracasos les hicieron cobrar consciencia de que mientras el papa no tuviese conocimiento de las intenciones reales, no lograr\u00edan nada.<\/p>\n<p>Por ello, por una parte, Mart\u00edn Ferr\u00e1ndez de Mesa decidi\u00f3 aprovechar su viaje a la corte real -pues hab\u00eda de acompa\u00f1ar al cardenal Fernes, que hab\u00eda sido nombrado legado pontificio- para solicitarle a Carlos I que volviese a escribir a Clemente VII para que resolviese el litigio del Obispado por la v\u00eda judicial.<\/p>\n<p>Y por otra, Juan Mir\u00f3, que se qued\u00f3 en Roma al frente de las negociaciones, decidi\u00f3 recuperar la carta de Monz\u00f3n y hac\u00e9rsela llegar al papa por otra v\u00eda. Con esa idea, tras la \u00faltima de las proposiciones citadas -la del 21 de agosto-, Mir\u00f3, acompa\u00f1ado por el abogado Aragona, fue a buscar a Gaspar Marrades, y los tres comparecieron ante May y le pidieron el escrito. El embajador, que acababa de recibir la provisi\u00f3n conseguida por Sambrana, les entreg\u00f3 el desfasado documento real, sin poner ninguna traba ni comentarles una palabra sobre la nueva disposici\u00f3n.<\/p>\n<p>Entonces, Mir\u00f3 y Aragona fueron a hablar con el auditor Luis G\u00f3mez y le pidieron que le rogase al cardenal Santiquatro que le entregase el instrumento a Clemente VII<sup>292<\/sup>. Al penitenciario le pareci\u00f3 buena idea, y el 25 de agosto Mir\u00f3, Aragona y G\u00f3mez se entrevistaron con el purpurado. Santiquatro no s\u00f3lo se ofreci\u00f3 para hacerle llegar la carta al pont\u00edfice, sino que les coment\u00f3 que, seg\u00fan su parecer, \u00ab<em>seria molt millor separar lo bisbat de Horiola del de Cartagena per apartar aquestos pleyts, despeses y males voluntats<\/em>\u00bb. Y les dijo que hablar\u00eda con el santo padre para tratar de convencerle de que decretase la dismembraci\u00f3n de los dos obispados<sup>293<\/sup>.<\/p>\n<p>Poco tiempo despu\u00e9s, el de los Cuatro Santos Coronados platic\u00f3 con el papa. De parte de la ciudad, le ofreci\u00f3 700 ducados de oro de la C\u00e1mara Apost\u00f3lica por dar validez a las bulas de la creaci\u00f3n del obispado de Orihuela, despachadas por Julio II. Y a\u00fan m\u00e1s, consigui\u00f3 que aceptase el proyecto de la segregaci\u00f3n con una \u00fanica condici\u00f3n: que Carlos I diese su consentimiento a la operaci\u00f3n. La gesti\u00f3n del cardenal fue tan satisfactoria que, <em>ex una<\/em>, logr\u00f3 que Clemente VII se aviniese a nombrar como obispo de la sede <em>oriolensis<\/em> al auditor Luis G\u00f3mez, previo pago de una determinada cantidad de dinero, y, <em>ex alia<\/em>, que se mostrase dispuesto a asignar a la Iglesia oriolana tantas rentas del Reino de Castilla como la cartaginense ten\u00eda en la di\u00f3cesis de Orihuela.<\/p>\n<p>Nada m\u00e1s conocer la respuesta pontificia, el 1 de septiembre, Juan Mir\u00f3 escribi\u00f3 una misiva urgente a las autoridades oriolanas. Les dio cuenta del proyecto auspiciado por el cardenal, y les rog\u00f3 que, con la mayor celeridad, tratasen de conseguir cartas de recomendaci\u00f3n del duque de Calabria y de la Iglesia y la ciudad de Valencia, y que se las enviasen a Roma, ya que la llegada de Carlos I era inminente, y con tan firmes apoyos y la ayuda del gran canciller Gattinara -que era amigo del aludido purpurado- podr\u00edan tratar de conseguir del rey la precisada licencia. Les recomend\u00f3 que escribiesen a Santiquatro ofreci\u00e9ndole 300 \u00f3 400 ducados como premio por sus esfuerzos y sus trabajos en el caso de que la divisi\u00f3n episcopal prosperase. Les pidi\u00f3 que comenzasen las diligencias para renovar la l\u00ednea de cr\u00e9dito, pues el t\u00e9rmino fijado en las p\u00f3lizas para poder tomar dinero prestado conclu\u00eda en Navidad. Resalt\u00f3 los servicios que estaba prestando a la causa Luis G\u00f3mez, que le hac\u00edan merecedor de la mitra. Y, por \u00faltimo, les suplic\u00f3 que mantuviesen el m\u00e1ximo sigilo pues la situaci\u00f3n requer\u00eda la m\u00e1xima discreci\u00f3n<sup>294<\/sup>.<\/p>\n<p>Sin embargo, llegados a este punto, ocurri\u00f3 lo que hab\u00eda de ocurrir. Justo cuando Clemente VII estaba a punto de aceptar las ofertas oriolanas, May le comunic\u00f3 las \u00faltimas \u00f3rdenes \u00ab<em>contraries<\/em>\u00bb del emperador, y el pont\u00edfice se ech\u00f3 atr\u00e1s.<\/p>\n<p>El 4 de septiembre, estando ya pactada la revisi\u00f3n del Pleito del Obispado en la Sacra Rota, Juan Luis Aragona y Jacobo de Saganta se presentaron en la Signatura para proponer la aceptaci\u00f3n de la comisi\u00f3n, pero \u00e9sta no fue decretada de la forma que hab\u00eda sido acordada. Se aprob\u00f3 la revisi\u00f3n del litigio pero no en la Rota, y se deneg\u00f3 la expedici\u00f3n del rescripto absolutorio de las censuras cartaginenses impuestas a ra\u00edz de los diferentes intentos vanos de ejecuci\u00f3n de los breves revocatorios.<\/p>\n<p>Tras este rev\u00e9s, Mir\u00f3 persever\u00f3 en sus intenciones. Orden\u00f3 a Aragona y a Saganta que volviesen a plantear la cuesti\u00f3n en la Signatura, y gracias a la influencia de Santiquatro, la petici\u00f3n oriolana fue aceptada casi por completo. \u00danicamente fue rechazada la solicitud del nombramiento del vicario general interino.<\/p>\n<p>Una vez fue aprobada la comisi\u00f3n a la Rota, \u00e9sta pas\u00f3 a poder del datario quien le dijo a Mir\u00f3 que no se la entregar\u00eda a menos que le diese los 700 ducados prometidos al papa. Siguiendo los consejos del auditor G\u00f3mez, Mir\u00f3, Saganta y Aragona se esforzaron por hacerle comprender que se hab\u00edan comprometido a abonar dicha cantidad s\u00f3lo en el caso de que Su Santidad decretase la dismembraci\u00f3n del obispado de Orihuela del de Cartagena o, en su defecto, la validaci\u00f3n de las bulas de Julio II. Estuvieron discutiendo con \u00e9l diez o doce d\u00edas pero no lograron hacerle cambiar de opini\u00f3n.<\/p>\n<p>Entonces, Mir\u00f3 volvi\u00f3 a acudir al cardenal Santiquatro. \u00c9ste le recomend\u00f3, asimismo, que no le hiciese llegar el dinero al papa por la mera comisi\u00f3n de la causa, pues eso no era lo que hab\u00eda negociado con el sucesor de San Pedro. Adem\u00e1s, le coment\u00f3 la existencia de la carta de Carlos I en la que le indicaba al embajador May que le suplicase al papa que no aceptase la revisi\u00f3n del caso. Acuciado por el repentino c\u00famulo de circunstancias adversas, el procurador oriolano le pidi\u00f3 al purpurado que le dijese al datario que le entregase la comisi\u00f3n, pero Santiquatro, conocedor de la voluntad del emperador y de que Clemente VII hab\u00eda de satisfacerle, prefiri\u00f3 ser prudente y le contest\u00f3 que nada pod\u00eda hacer puesto que el negocio era \u00ab<em>cosa que tocava al papa<\/em>\u00bb<sup>295<\/sup>.<\/p>\n<p>El 13 de septiembre, Juan Mir\u00f3 se vio abrumado por las dudas, y temiendo perder la comisi\u00f3n, se decidi\u00f3 a escribir a sus representados para consultarles si deb\u00eda entregarle al datario los 700 ducados. En la carta, les hizo un sucinto informe de las \u00faltimas incidencias y, adem\u00e1s, les coment\u00f3 que ten\u00eda en su poder toda la documentaci\u00f3n que le dej\u00f3 Jaime G\u00f3mez a Mart\u00edn Ferr\u00e1ndez de Mesa al partir para Espa\u00f1a<sup>296<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s -el 15-, el abogado Aragona fue a la Signatura y trat\u00f3 de convencer de nuevo al datario para que le diese la comisi\u00f3n. Pero no consigui\u00f3 que mudase de parecer<sup>297<\/sup>.<\/p>\n<p>No obstante, varios d\u00edas m\u00e1s tarde, Mir\u00f3 decidi\u00f3 probar por una v\u00eda alternativa -muy frecuente en tal tipo de situaciones-. Pens\u00f3 en sobornar al datario, sin m\u00e1s. Y con ese fin, envi\u00f3 al procurador y al abogado a ofrecerle al citado curial un cuantioso regalo a cambio del instrumento. Sin embargo, de un modo sorprendente, aunque tambi\u00e9n algo sospechoso, el datario les entreg\u00f3 el documento sin pedir nada a cambio y, adem\u00e1s, les avis\u00f3 de que el procurador murciano, Sebasti\u00e1n Clavijo, le hab\u00eda solicitado al papa que anulase la comisi\u00f3n y que mandase que la causa volviese a ser tratada en la Signatura.<\/p>\n<p>Unos d\u00edas despu\u00e9s, Mir\u00f3 comprendi\u00f3 la contradictoria actitud del datario, pues la comisi\u00f3n a la Rota fue revocada, y el tema fue revisado en el aludido organismo de la Curia. Y el 22 de septiembre, el datario, que estaba claramente de parte de los intereses murcianos, hizo que se cambiasen los t\u00e9rminos de la comisi\u00f3n, quedando \u00e9sta de un modo muy perjudicial para las aspiraciones oriolanas<sup>298<\/sup>.<\/p>\n<p>Entonces, Mir\u00f3 tom\u00f3 la m\u00e1s h\u00e1bil de las decisiones. Habl\u00f3 con el anciano cardenal de Ancona, que era el purpurado con mayor peso espec\u00edfico tanto en la Signatura como en el Consistorio pontificio. Le coment\u00f3 lo ocurrido como consecuencia de la intervenci\u00f3n del datario, y le prometi\u00f3 100 ducados si favorec\u00eda a Aragona y Saganta en la Signatura. El cardenal acept\u00f3 la oferta y el 27 de septiembre propuso que la causa episcopal fuese revisada de nuevo en el citado organismo. Y en la sesi\u00f3n del domingo 3 de octubre, a instancias de Ancona y Santiquatro, la comisi\u00f3n propuesta por el obispo de Como, en calidad de referendario, fue aprobada definitivamente<sup>299<\/sup>.<\/p>\n<p>Sin embargo, Mir\u00f3 y sus colaboradores a\u00fan tuvieron que superar un \u00faltimo escollo. El documento ten\u00eda que pasar por las manos del datario, y \u00e9ste no se lo quiso entregar a los representantes de Orihuela sin citar a Clavijo y escuchar sus alegaciones.<\/p>\n<p>El cl\u00e9rigo cartaginense compareci\u00f3 ante el curial ese mismo d\u00eda, y le solicit\u00f3 la anulaci\u00f3n de la comisi\u00f3n aduciendo que antes de ser revisada la causa, los oriolanos hab\u00edan de prestar obediencia al obispo y el cabildo de Cartagena en virtud del breve de 1526, y que hasta entonces, no pod\u00edan siquiera defender sus derechos porque estaban excomulgados.<\/p>\n<p>Mir\u00f3 le replic\u00f3 que la comisi\u00f3n hab\u00eda sido aprobada por Clemente VII en la Signatura, y que ineludiblemente hab\u00eda de ponerse en ejecuci\u00f3n. Y le volvi\u00f3 a requerir al datario que se la entregase, advirti\u00e9ndole que en caso contrario ir\u00eda a hablar directamente con el papa.<\/p>\n<p>Ante la posibilidad de que el pont\u00edfice se enterase de que estaba impidiendo la ejecuci\u00f3n de sus \u00f3rdenes, el datario no pudo seguir neg\u00e1ndose y le hizo entrega del documento. Y a continuaci\u00f3n, Mir\u00f3, Saganta y Aragona se lo llevaron al regente de la Canciller\u00eda Apost\u00f3lica, y \u00e9ste cometi\u00f3 la causa al auditor Jacobo Simoneta, obispo electo de Pisauro<sup>300<\/sup>.<\/p>\n<p>La habilidad diplom\u00e1tica de Juan Mir\u00f3, puesta de manifiesto en el logro del favor del cardenal Santiquatro y, sobre todo, del de Ancona, hab\u00eda servido para ganarle la batalla a Miguel May, a Sebasti\u00e1n Clavijo y al datario apost\u00f3lico. Pero el triunfo corr\u00eda el riesgo de convertirse en un logro ef\u00edmero. Carlos I quer\u00eda que la Iglesia de Orihuela siguiese perteneciendo al obispado de Cartagena, y a\u00fan no hab\u00eda dicho la \u00faltima palabra.<\/p>\n<ol start=\"15\">\n<li><strong> La revisi\u00f3n judicial y la expedici\u00f3n de las letras compulsorias.<\/strong><\/li>\n<\/ol>\n<p>Tres d\u00edas despu\u00e9s de conseguir la orden de la revisi\u00f3n judicial del Pleito del Obispado en la Rota, el 6 de octubre, Juan Mir\u00f3 escribi\u00f3 a las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura refiri\u00e9ndoles la buena nueva.<\/p>\n<p>En la carta, que era muy amplia, adem\u00e1s de darles cuenta de las negociaciones que hab\u00edan llevado a la consecuci\u00f3n del anhelado mandato, el eficiente procurador les comunic\u00f3 que m\u00e1s adelante tendr\u00edan que confeccionar un compendio documental que probase que todos los rescriptos revocatorios obtenidos por los murcianos hab\u00edan sido subrepticios y falsos, y que la instituci\u00f3n del obispado de Orihuela hab\u00eda sido absolutamente leg\u00edtima. Adem\u00e1s, les indic\u00f3 que, con el fin de facilitarles tal tarea, les remitir\u00eda una serie de instrucciones para que pudiesen preparar el informe de modo que tuviese plena validez jur\u00eddica, y que tambi\u00e9n les enviar\u00eda un listado de puntos o \u00edtemes en los que habr\u00edan de incidir para fundamentar las argumentaciones episcopales.<\/p>\n<p>Por otra parte, en relaci\u00f3n con el venerable cardenal de Ancona, Mir\u00f3 les coment\u00f3 que hab\u00eda sido la clave para el \u00e9xito del negocio (pues era \u00ab<em>lo mes principal de la Signatura y tanbe del Consistori, que quant ell diu la cosa no y a qui la gose contradir<\/em>\u00bb), y que su labor hab\u00eda sido tan crucial que de no haber sido por \u00e9l, \u00ab<em>may agueren obtes neguna cosa<\/em>\u00bb. Y les escribi\u00f3 que era muy conveniente que ordenaran el pago de los 100 ducados que le hab\u00eda prometido, para que no se ofuscase con ellos, pues la causa a\u00fan deb\u00eda volver a pasar por el Consistorio para su resoluci\u00f3n definitiva, y tambi\u00e9n ten\u00eda que solventar la cuesti\u00f3n del nombramiento del vicario general provisional. No obstante, a sugerencia del sibilino auditor G\u00f3mez, les se\u00f1al\u00f3 que como el papa ten\u00eda la intenci\u00f3n de partir para Bolonia el 14 de octubre, \u00ab<em>a coronar lo Emperador<\/em>\u00bb, y el cardenal de Ancona hab\u00eda de acompa\u00f1arle, \u00ab<em>poria eser que en lo cami, o stant <\/em>[a]<em>lla, es moris, per eser molt vell<\/em>\u00bb, por lo que les dijo que aguardar\u00eda a su vuelta para darle el dinero, por si de esa escabrosa manera pod\u00edan ahorr\u00e1rselo. Asimismo, les pidi\u00f3 que le enviasen al citado cardenal una sentida carta de agradecimiento, dici\u00e9ndole que lo consideraban \u00ab<em>protector de la siutat, perque sert aprofitara molt<\/em>\u00bb.<\/p>\n<p>Tocando ya otros aspectos, Mir\u00f3 coment\u00f3 que ser\u00eda muy \u00fatil que le mandasen que le hiciese un regalo al datario, para ganarse su voluntad, pues por su cargo participaba en la expedici\u00f3n de cualquier documento apost\u00f3lico.<\/p>\n<p>Y, por \u00faltimo, concluy\u00f3 el escrito indic\u00e1ndoles a sus representados que ten\u00eda la intenci\u00f3n de conseguir por la v\u00eda de la Penitenciar\u00eda -que regentaba Luis G\u00f3mez- una dispensa para que un obispo de anillo fuese a Orihuela a \u00ab<em>dar ordens y corones, y confermar, lite pendente<\/em>\u00bb<sup>301<\/sup>.<\/p>\n<p>Mientras tanto, en la ciudad del Bajo Segura, ni el cap\u00edtulo del Salvador ni los mun\u00edcipes ten\u00edan la m\u00e1s ligera idea del ajetreado discurrir de los acontecimientos en Roma. Pocos d\u00edas antes de la aprobaci\u00f3n de la comisi\u00f3n a Jacobo Simoneta, el 25 de septiembre lleg\u00f3 a sus o\u00eddos la noticia de la consecuci\u00f3n por el s\u00edndico Sambrana a principios de agosto de la carta real favorable a los intereses cartaginenses.<\/p>\n<p>El asombro no les impidi\u00f3 actuar de un modo inmediato. Ese mismo d\u00eda redactaron cinco cartas y las enviaron a Valencia, a manos de Guillem Desprats, para que el vicario general las enviase a la Ciudad Eterna. Sumariamente, diremos que al gran canciller Mercurino Gattinara le rogaron que instara a Carlos I a que mandase cumplir lo pactado en las \u00faltimas Cortes de la Corona de Arag\u00f3n. Al caballero Gaspar Marrades le solicitaron que tratase de convencer al embajador May para que prestase su favor a la causa oriolana. Al auditor Luis G\u00f3mez le agradecieron sus servicios, y le pidieron que consiguiese el apoyo del cardenal Santiquatro. A Mart\u00edn Ferr\u00e1ndez de Mesa le demandaron que siguiese supervisando la labor de Juan Mir\u00f3. Y a este \u00faltimo le ordenaron que le presentase una suplicaci\u00f3n escrita al emperador, record\u00e1ndole el contenido de las cartas de Monz\u00f3n, y que buscase el auxilio de Gattinara, May y Santiquatro para influir en la voluntad del monarca y tratar de modificarla<sup>302<\/sup>.<\/p>\n<p>En Roma, el panorama era mucho mejor para la causa episcopal. Los d\u00edas 20, 25 y 27 de octubre, y 4 y 7 de noviembre, el abogado Aragona y el procurador Saganta, enviados por Juan Mir\u00f3, comparecieron en la Rota a fin de negociar los diferentes aspectos relacionados con la obtenci\u00f3n de las letras compulsoriales y la presentaci\u00f3n de pruebas documentales<sup>303<\/sup>.<\/p>\n<p>Antes de proseguir la narraci\u00f3n de las gestiones en la Rota, hemos de hacer un breve inciso para decir que a ra\u00edz del fallecimiento del pavorde de la iglesia del Salvador, Pedro P\u00e9rez, que era tambi\u00e9n de\u00e1n de la Catedral de Cartagena, Clemente VII, ya en Bolonia, decidi\u00f3 asignar la primera dignidad oriolana -y la canonj\u00eda que llevaba anexa- al cl\u00e9rigo sevillano Fernando Rodr\u00edguez, teniendo en cuenta sus estudios, su honestidad y otras virtudes loables<sup>304<\/sup>. Destacamos el dato de esta provisi\u00f3n por dos motivos: porque el prep\u00f3sito o pavorde era el presidente del cap\u00edtulo del Salvador, y porque el propio Rodr\u00edguez tendr\u00eda una curiosa participaci\u00f3n en el Pleito del Obispado.<\/p>\n<p>El 8 de noviembre, las diligencias de Aragona y Saganta, coordinadas por Mir\u00f3, obtuvieron nuevos resultados. Siguiendo los t\u00e9rminos de la comisi\u00f3n a la Rota, Camilo Ballion, lugarteniente del auditor Jacobo Simoneta -que hab\u00eda tenido que ausentarse de la Curia para encargarse de ciertos negocios eclesi\u00e1sticos-, expidi\u00f3 un mandato citatorio dirigido al de\u00e1n y el cabildo de Cartagena. En \u00e9l, les orden\u00f3 a los citados capitulares que compareciesen ante \u00e9l, ante Simoneta, o ante el auditor que fuese diputado para el caso, por medio de procuradores leg\u00edtimos, para defender sus derechos en la lite. Mand\u00f3 que el edicto p\u00fablico fuese le\u00eddo en la Audiencia Pontificia -donde sol\u00edan hacerse efectivas las citaciones de este tipo-, y que fuese fijado en las puertas de la Bas\u00edlica de San Pedro y del Palacio Apost\u00f3lico de las Causas (la Rota), y fuera de la Curia romana, en las puertas de la Metropolitana de Valencia y en las de las parroquiales de Elche. Y les advirti\u00f3 que habr\u00edan de comparecer en los 60 d\u00edas siguientes a la ejecuci\u00f3n de la provisi\u00f3n<sup>305<\/sup>.<\/p>\n<p>Cinco d\u00edas despu\u00e9s, Ballion cit\u00f3 a los procuradores murcianos para comunicarles el inminente despacho de sendas letras compulsorias para las dos partes, con la intenci\u00f3n de que oriolanos y cartaginenses pudiesen preparar los compendios documentales que habr\u00edan de utilizar para fundamentar sus argumentaciones en los careos del juicio. El 14 de noviembre, Aragona y Saganta le suplicaron al auditor subrogado que expidiese sin demora los instrumentos<sup>306<\/sup>. Y el d\u00eda siguiente, 15 de noviembre, Ballion los despach\u00f3.<\/p>\n<p>Como hemos avanzado, las letras compulsorias iban dirigidas al cabildo de Cartagena, <em>ex una<\/em>, y al cap\u00edtulo del Salvador y la ciudad de Orihuela, <em>ex alia<\/em>. En ellas, se facultaba a los procuradores de ambas partes para designar a un juez compulsor que supervisase todo el proceso de presentaci\u00f3n de documentos. Dichos jueces hab\u00edan de citar a todos los cl\u00e9rigos y notarios de la di\u00f3cesis que tuviesen en su poder las escrituras o instrumentos que los procuradores de las partes les requiriesen. Y una vez presentados dichos autos, ten\u00edan que proceder a la comprobaci\u00f3n de su veracidad y legitimidad.<\/p>\n<p>Por otra parte, Ballion estipul\u00f3 que los s\u00edndicos nombrados por los litigantes ten\u00edan que asistir al proceso de colaci\u00f3n y compulsa de las pruebas adversarias. Y demostr\u00f3 conocer bien la situaci\u00f3n existente en la di\u00f3cesis al incluir en el edicto una cl\u00e1usula en la que advert\u00eda a los habitantes de Orihuela y Murcia que no perturbasen, molestasen ni vejasen a los notarios y procuradores de las respectivas partes adversas cuando se desplazasen a las ciudades contrarias para comparecer ante los jueces compulsores. Asimismo, para asegurarse de que los compendios fuesen preparados sin que se produjese ning\u00fan tipo de incidentes, amenaz\u00f3 a los eclesi\u00e1sticos que contraviniesen de cualquier forma sus mandatos con la imposici\u00f3n de la pena de excomuni\u00f3n, con la suspensi\u00f3n <em>a divinis<\/em> para los cap\u00edtulos y colegios a los que perteneciesen, y con la fulminaci\u00f3n de entredicho para las iglesias y los monasterios en los que oficiasen o residiesen.<\/p>\n<p>Por \u00faltimo, hemos de destacar que el lugarteniente de Simoneta, en virtud del documento aludido, absolvi\u00f3 al clero y el pueblo de Orihuela de todas las censuras en las que hab\u00edan incurrido por impedir la ejecuci\u00f3n de los breves revocatorios, pero no anul\u00f3 la validez de estos rescriptos, ni restituy\u00f3 la causa a la situaci\u00f3n episcopal creada tras la expedici\u00f3n de las bulas de Julio II<sup>307<\/sup>.<\/p>\n<p>Cuatro d\u00edas despu\u00e9s, Juan Mir\u00f3 decidi\u00f3 reforzar su equipo de colaboradores contratando a otro \u00ab<em>solicitador e procurador<\/em>\u00bb, micer Berenguer Gombau, con la misi\u00f3n de que, junto con Jacobo de Saganta, se encargase de presentar en la Curia las s\u00faplicas oriolanas<sup>308<\/sup>.<\/p>\n<p>El 24 de noviembre, por orden de Ballion, el notario Alexander Fuscherius de Urbino public\u00f3 el edicto citatorio <em>in partibus<\/em>. Fuscherius present\u00f3 el mandato en la Audiencia Pontificia -donde sol\u00edan ser notificadas las citaciones-, y despu\u00e9s lo fij\u00f3 en las puertas de la Bas\u00edlica de San Pedro y en las del Palacio de la Rota<sup>309<\/sup>.<\/p>\n<p>Tres d\u00edas m\u00e1s tarde, las autoridades de Orihuela recibieron la carta que Juan Mir\u00f3 les envi\u00f3 el 6 de octubre, notific\u00e1ndoles la comisi\u00f3n de la causa a la Rota, y quedaron a la espera de novedades<sup>310<\/sup>. El segundo domingo de Adviento -5 de diciembre- les llegaron de Valencia nuevos escritos del procurador. Sin embargo, se llevaron una peque\u00f1a desilusi\u00f3n al comprobar que se trataba de dos misivas escritas el 29 de agosto y el 1 de septiembre, que hab\u00edan quedado completamente desfasadas por el curso de los acontecimientos<sup>311<\/sup>. Esperaron algunos d\u00edas, y el 23 de diciembre decidieron enviar un pliego de cartas a Roma. Dicho paquete inclu\u00eda cinco escritos dirigidos al procurador Mir\u00f3, al gran canciller Gattinara, al auditor G\u00f3mez y los cardenales Santiquatro y Ancona.<\/p>\n<p>A Juan Mir\u00f3 le remitieron una largu\u00edsima misiva, que a continuaci\u00f3n resumimos.<\/p>\n<p>En primer lugar, le comunicaron que estaban esperando que llegasen las letras compulsorias y sus instrucciones para comenzar a confeccionar el compendio defensivo.<\/p>\n<p>En relaci\u00f3n con la comisi\u00f3n a la Rota, le comentaron que tem\u00edan que los cartaginenses obtuviesen una sentencia favorable pues contaban con un solid\u00edsimo entramado de influencias dentro de la Curia y, adem\u00e1s, Carlos I iba a tener un contacto directo con Clemente VII, y era m\u00e1s que probable que le suplicase que revocara la revisi\u00f3n de la lite, y que volviese a decretar la anulaci\u00f3n de la creaci\u00f3n del obispado de Orihuela. Por ello, le pidieron que consultase al auditor G\u00f3mez, al abogado Aragona y al resto de aliados de la causa si ser\u00eda mejor \u00ab<em>disimular la fahena y no instar<\/em>\u00bb hasta que el emperador saliese de Italia, o si ser\u00eda m\u00e1s conveniente \u00ab<em>fer instancia y portar la causa a sentencia<\/em>\u00bb con la mayor brevedad.<\/p>\n<p>Por otra parte, sobre las cantidades de dinero que hab\u00eda prometido, las autoridades le indicaron que le hiciese llegar al cardenal de Ancona los 100 ducados pactados -cuando lo estimase oportuno-, y que, por el contrario, no le diese nada al papa.<\/p>\n<p>En cuanto a la cuesti\u00f3n del proyecto de dismembraci\u00f3n auspiciado por el cardenal Santiquatro, le escribieron que intentase hacerlo prosperar \u00ab<em>per qualsevol via o manera<\/em>\u00bb, llegando a ofrecer las cantidades que fuesen convenientes (\u00ab<em>no diem trescents ni quatrecents ducats, mas tot quant costara<\/em>\u00bb), y tambi\u00e9n que hiciese las gestiones necesarias a fin de que el auditor Luis G\u00f3mez fuese nombrado obispo.<\/p>\n<p>La \u00faltima cuesti\u00f3n que las autoridades tocaron fue la del regimiento espiritual de la Iglesia de Orihuela y su t\u00e9rmino. Le indicaron que efectuase todas las diligencias posibles y que ofreciese hasta 200 ducados para lograr que Clemente VII le diese licencia al cap\u00edtulo del Salvador para que nombrase a un vicario general provisional, y que le concediese poder suficiente para \u00ab<em>col.lar beneficis, y conexer de les causes de sacrilegis, matrimonis e altres que los vicaris y provisors acostumen de conexer<\/em>\u00bb. Y en el caso de que no consiguiese tal gracia, le mandaron que trabajase por la v\u00eda de la Penitenciar\u00eda para impetrar un breve en el que el pont\u00edfice enviase a Orihuela a un obispo de anillo con la misi\u00f3n de \u00ab<em>donar corones y ordens, y confirmar<\/em>\u00bb<sup>312<\/sup>.<\/p>\n<p>Al gran canciller Gattinara le felicitaron por la obtenci\u00f3n del capelo cardenalicio, le contaron que las cartas que firm\u00f3 en Monz\u00f3n no hab\u00edan tenido efecto por la actitud del embajador May, y le suplicaron que tomase las medidas oportunas para que la causa episcopal fuese sentenciada por la v\u00eda judicial, sin injerencias ni parcialidades<sup>313<\/sup>.<\/p>\n<p>A Luis G\u00f3mez, las autoridades oriolanas le agradecieron su intercesi\u00f3n ante el cardenal Santiquatro y ante otros curiales y le comentaron que se sentir\u00edan muy honrados si llegase a ce\u00f1ir la mitra oriolana en el caso de que el proyecto de segregaci\u00f3n fraguase. Le pidieron que guiase con sus consejos a Mir\u00f3 a la hora de realizar las diferentes gestiones en la Rota. Y, por \u00faltimo, le comentaron la necesidad que ten\u00edan de disponer de un vicario general<sup>314<\/sup>.<\/p>\n<p>Y, por \u00faltimo, a los cardenales de Ancona y Santiquatro les escribieron para agradecerles su intervenci\u00f3n en la consecuci\u00f3n de la comisi\u00f3n de la causa, y pedirles que siguiesen amparando y protegiendo los intereses oriolanos<sup>315<\/sup>.<\/p>\n<ol start=\"16\">\n<li><strong> Los compendios documentales y el nuevo breve revocatorio de Clemente VII.<\/strong><\/li>\n<\/ol>\n<p>Las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura festejaron la entrada del a\u00f1o 1530 con la recepci\u00f3n de los instrumentos citatorios y compulsorios de Camilo Ballion, y de las instrucciones de Juan Mir\u00f3. Y con mucha parsimonia decidieron ponerlos en ejecuci\u00f3n.<\/p>\n<p>En primer lugar, el cap\u00edtulo del Salvador y los oficiales municipales acordaron nombrar a Vicente Mart\u00ed procurador de la Iglesia y la ciudad de Orihuela, y le encomendaron su representaci\u00f3n en todos los actos que tuviesen alguna conexi\u00f3n con el Pleito del Obispado y, en especial, en los que se derivasen de los decretos expedidos en la Rota. As\u00ed, el justicia y los jurados le entregaron su sindicato el 2 de enero<sup>316<\/sup>. Y el d\u00eda siguiente lo hicieron los capitulares<sup>317<\/sup>.<\/p>\n<p>El cuarto d\u00eda del a\u00f1o los mandatarios le ordenaron al nuevo procurador que se preparase para ir a Valencia. Le encargaron una doble misi\u00f3n. <em>Ex una<\/em>, fijar el mandato citatorio del 8 de noviembre del a\u00f1o anterior en las puertas de la Metropolitana, seg\u00fan ordenaba Camilo Ballion en su tenor. Y <em>ex alia<\/em>, hablar con D. Ram\u00f3n Lladr\u00f3 para que negociase con los prestamistas Novara y Passabonello nuevas p\u00f3lizas de cr\u00e9dito para Juan Mir\u00f3 -pues las anteriores hab\u00edan terminado en Navidad-. Y dos d\u00edas despu\u00e9s -el 6 de enero-, le entregaron 20 ducados y algunas cartas de recomendaci\u00f3n y creencia, dirigidas al vicario general Desprats, a D. Pedro Maza, al baile general del Reino de Valencia D. Luis Carroz, al doctor Filibert y al referido se\u00f1or de Castalla, con el fin de facilitarle su labor, y Mart\u00ed parti\u00f3 en direcci\u00f3n a la ciudad del Turia<sup>318<\/sup>.<\/p>\n<p>Primero se ocup\u00f3 de zanjar la cuesti\u00f3n del cr\u00e9dito, y una vez tuvo en sus manos las nuevas letras, el 15 de enero pag\u00f3 a un notario llamado Miguel Beneyto para que fijase la citatoria de Ballion en el acceso principal de la Metropolitana y le entregase un auto p\u00fablico que diese fe de tal acto<sup>319<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el 26 de ese mismo mes, Mart\u00ed repiti\u00f3 dicha operaci\u00f3n en las puertas de la iglesia de Santa Mar\u00eda la Mayor de Elche, ante la supervisi\u00f3n del notario Andr\u00e9s Arnal<sup>320<\/sup>.<\/p>\n<p>Por esas fechas, las letras compulsoriales ya hab\u00edan llegado a Murcia. El 28 de enero el de\u00e1n y el cabildo de Cartagena procedieron al nombramiento del can\u00f3nigo Juan de Orozco y del beneficiado Francisco Delgado como procuradores diputados para la ejecuci\u00f3n de los mandatos de Ballion, y les dieron poder suficiente para que designasen al juez que tendr\u00eda que supervisar la redacci\u00f3n del compendio<sup>321<\/sup>.<\/p>\n<p>El d\u00eda siguiente, Orozco se dirigi\u00f3 al monasterio de la Merced, que estaba ubicado fuera de las murallas de la ciudad de Murcia. Una vez all\u00ed, compareci\u00f3 ante su comendador, fr. Cosme de Guzm\u00e1n, le present\u00f3 su sindicato y las letras apost\u00f3licas, y le pidi\u00f3 que se aviniese a ser el juez ejecutor del proceso compulsorio. Tras asegurarse de la legitimidad de la documentaci\u00f3n, el mercedario acept\u00f3 la judicatura con la reverencia debida. Y, acto seguido, se\u00f1al\u00f3 que las audiencias tendr\u00edan lugar en el monasterio que regentaba todos los d\u00edas no feriados \u00ab<em>a la ora de tercia, a la manyana, y a la ora de las bisperas, a la tarde<\/em>\u00bb. Nombr\u00f3 como notario a Rodrigo de M\u00e9rida, y como \u00ab<em>nuncio y cursor<\/em>\u00bb a Francisco Jufr\u00e9, y les hizo jurar que desempe\u00f1ar\u00edan honrada y eficientemente sus respectivas funciones. Y a continuaci\u00f3n dio por concluida la primera sesi\u00f3n del proceso<sup>322<\/sup>.<\/p>\n<p>Posteriormente, ese mismo d\u00eda 29 de enero, Orozco escribi\u00f3 al cap\u00edtulo del Salvador y al justicia y los jurados de Orihuela para notificarles su nombramiento, informarles del inminente inicio de las compulsas, y pedirles que le remitiesen una \u00ab<em>caucio<\/em>\u00bb, un documento en el que asegurasen que no causar\u00edan ning\u00fan perjuicio ni pondr\u00edan ning\u00fan impedimento a los notarios y eclesi\u00e1sticos que fuesen llamados por Guzm\u00e1n para presentar ante \u00e9l cualquier tipo de \u00ab<em>scriptures e instruments<\/em>\u00bb<sup>323<\/sup>.<\/p>\n<p>Tras recibir la misiva, el d\u00eda siguiente las autoridades oriolanas le ordenaron a Vicente Mart\u00ed que fuese a Murcia con el prop\u00f3sito de que asistiese desde el principio a la confecci\u00f3n del compendio cartaginense. Y le encargaron que all\u00ed tratase con Orozco la cuesti\u00f3n de los salvoconductos<sup>324<\/sup>.<\/p>\n<p>Mientras tanto, en la ciudad vecina y rival, el otro s\u00edndico, Francisco Delgado, compareci\u00f3 ante fr. Cosme de Guzm\u00e1n y le pidi\u00f3 que comenzase el proceso compulsorio con la inserci\u00f3n de la apelaci\u00f3n presentada por D. Mart\u00edn Ferr\u00e1ndez de Angulo el 31 de octubre de 1510. En nuestra opini\u00f3n, la intenci\u00f3n de sus representados era muy clara. Dado que en dicha protesta Angulo aseguraba que Fernando el <em>Cat\u00f3lico<\/em> le hab\u00eda forzado a dar su consentimiento a la creaci\u00f3n del obispado de Orihuela, quer\u00edan probar que tal instituci\u00f3n episcopal era completamente ileg\u00edtima, y que por ello no pod\u00eda ser permitida.<\/p>\n<p>Guzm\u00e1n atendi\u00f3 la solicitud del procurador, y teniendo en consideraci\u00f3n que dicho instrumento se hallaba en el Archivo de la Catedral de Cartagena, expidi\u00f3 un mandato dirigido al propio Juan de Orozco y al racionero Alonso Petit, en cuyo poder estaban las llaves del citado dep\u00f3sito, orden\u00e1ndoles que se lo presentasen la tarde del d\u00eda siguiente. Seg\u00fan nuestro parecer, el juez comprendi\u00f3 perfectamente la importancia de la presentaci\u00f3n del auto de disentimiento de Angulo, que, como hemos puesto antes de manifiesto, era la piedra angular de las argumentaciones cartaginenses. Por ello, decret\u00f3 que su inserci\u00f3n en el proceso se realizase con tan inusitada premura con el fin de evitar que los oriolanos pudiesen poner objeciones. No obstante, para no incurrir en irregularidades, cumpli\u00f3 -relativamente- con su obligaci\u00f3n de citar al cap\u00edtulo del Salvador y a las autoridades municipales de Orihuela despachando una letra citatoria, y ordenando que fuese fijada en las puertas de la referida iglesia murciana con la excusa de que no hab\u00eda tiempo para llevarla a la ciudad del Bajo Segura<sup>325<\/sup>. Por lo que podemos deducir, ni Guzm\u00e1n ni el cabildo de Cartagena deseaban que Vicente Mart\u00ed estuviese presente cuando Orozco y Petit presentasen el mencionado documento.<\/p>\n<p>Y ciertamente tuvieron suerte porque los dos prebendados, seg\u00fan estaba previsto, le llevaron al juez la escritura demandada la tarde del 31 de enero. Y estando ausente la parte oriolana, fue examinada y reconocida por dos notarios, y Guzm\u00e1n aprob\u00f3 su inclusi\u00f3n en el proceso justo cuando Vicente Mart\u00ed y su notario Francisco Olzina hac\u00edan entrada en la sala del monasterio que hab\u00eda sido habilitada para las audiencias<sup>326<\/sup>.<\/p>\n<p>Acto seguido, Delgado intervino para solicitarle al juez que les ordenase a Orozco y a Petit que presentasen una serie de documentos que hac\u00edan referencia a las rentas que el cabildo de Cartagena pose\u00eda en la ciudad de Orihuela y su t\u00e9rmino -incluidas las Pilas-, as\u00ed como todos los rescriptos apost\u00f3licos en los que los sucesivos pont\u00edfices (Eugenio IV, Nicol\u00e1s V, Le\u00f3n X y Clemente VII) hab\u00edan decretado la revocaci\u00f3n de las dos erecciones del obispado de Orihuela. Guzm\u00e1n acept\u00f3 el requerimiento del s\u00edndico y promulg\u00f3 un edicto conminando a los conservadores del Archivo Catedralicio, bajo pena de excomuni\u00f3n mayor, a que le llevasen la documentaci\u00f3n reclamada en un plazo de nueve d\u00edas que comenzar\u00edan a contabilizarse a partir del momento en el que se les fuese presentado su mandato<sup>327<\/sup>.<\/p>\n<p>Durante los d\u00edas siguientes, mientras la parte cartaginense preparaba la documentaci\u00f3n que iba a presentar ante fr. Cosme de Guzm\u00e1n, Vicente Mart\u00ed y Juan de Orozco negociaron el asunto de los salvoconductos y llegaron a un acuerdo. Y el 5 de febrero, el Concejo de Murcia le entreg\u00f3 a Mart\u00ed una \u00ab<em>patente de salvaguarda<\/em>\u00bb por la que promet\u00eda, aseguraba y daba su \u00ab<em>fee y palabra<\/em>\u00bb de que los procuradores y notarios oriolanos \u00ab<em>seran bien tratados y mirados, y no les sera fecho enojo ni danyo ninguno en sus personas, ni en sus bienes, ni en sus criados<\/em>\u00bb<sup>328<\/sup>. Y qued\u00f3 a la espera de que el <em>Consell<\/em> de la ciudad del Bajo Segura remitiese la suya.<\/p>\n<p>Cuatro d\u00edas despu\u00e9s, los eclesi\u00e1sticos murcianos terminaron la b\u00fasqueda de las escrituras que hab\u00edan de presentarle al juez compulsor. Por ello, el notario Rodrigo de M\u00e9rida les notific\u00f3 a Orozco y Petit el mandato expedido el 31 de enero. Y el d\u00eda siguiente, 10 de febrero, comparecieron ante Guzm\u00e1n cargados de documentos<sup>329<\/sup>.<\/p>\n<p>Le hicieron que reconociese el <em>Fundamentum Ecclesiae Cartaginensis<\/em> del obispo Diego de Comontes, ya que quer\u00edan que en el proceso compulsorio fuese incluido el cap\u00edtulo relativo a la distribuci\u00f3n de las rentas del obispado, para que quedasen especificados los frutos que el cabildo de Cartagena pose\u00eda en la ciudad de Orihuela y su t\u00e9rmino. Tambi\u00e9n tuvo que examinar algunas ordenaciones del \u00ab<em>Libro antiguo de las Constituciones synodales de la dicha yglesia<\/em>\u00bb, que hac\u00edan alusi\u00f3n a la concesi\u00f3n apost\u00f3lica de las <em>Pilas<\/em> a la f\u00e1brica de la Catedral murciana.<\/p>\n<p>Compuls\u00f3, asimismo, los diferentes breves en los que los sucesivos papas revocaron las dos fundaciones del obispado de Orihuela: el de Eugenio IV del 11 de octubre de 1443, el de Nicol\u00e1s V del 14 de julio de 1451, el de Le\u00f3n X del 17 de marzo de 1518 -y el ejecutorial que expidi\u00f3 Jer\u00f3nimo de Thinutiis dos d\u00edas despu\u00e9s-, y el de Clemente VII del 14 de octubre de 1524 -junto con el ejecutorial despachado por Thinutiis el 6 de diciembre de ese mismo a\u00f1o, y el promulgado por el propio pont\u00edfice el 5 de agosto de 1525-. Y, por \u00faltimo, colacion\u00f3 otros documentos que la parte cartaginense consider\u00f3 de inter\u00e9s como la revocaci\u00f3n del vicariato general de Orihuela decretada por Eugenio IV el 9 de mayo de 1436, o las anulaciones de las dos comisiones que los oriolanos consiguieron que Le\u00f3n X le hiciese al cardenal Jacobacis para que revisase el Pleito del Obispado, despu\u00e9s de haber revocado las bulas de instituci\u00f3n episcopal de Julio II.<\/p>\n<p>Vicente Mart\u00ed dio su visto bueno a las compulsas, y Guzm\u00e1n orden\u00f3 que todos los referidos documentos fuesen copiados en el compendio<sup>330<\/sup>.<\/p>\n<p>Una vez terminada esta primera fase del proceso cartaginense, Mart\u00ed y Olzina retornaron a Orihuela, y dieron buena cuenta de lo sucedido a las autoridades civiles y eclesi\u00e1sticas de la ciudad. De esa manera, los mandatarios se dieron cuenta de que las argumentaciones murcianas radicar\u00edan sobre dos l\u00edneas maestras: la ilegitimidad de las dos creaciones del obispado de Orihuela y sus consiguientes derogaciones, y los perjuicios que les causaba la erecci\u00f3n episcopal en relaci\u00f3n con la percepci\u00f3n de sus rentas.<\/p>\n<p>Por otra parte, el can\u00f3nigo Mart\u00ed les entreg\u00f3 a los oficiales municipales el salvoconducto que le hab\u00eda proporcionado el Concejo de Murcia, y el 14 de febrero el <em>Consell<\/em> le remiti\u00f3 a dicha corporaci\u00f3n su propia patente de salvaguarda<sup>331<\/sup>, y ratific\u00f3 a Mart\u00ed en su cargo de procurador de la universidad de habitantes de Orihuela. Adem\u00e1s, en dicha reuni\u00f3n, los ediles decidieron enviarle a D. Ram\u00f3n Lladr\u00f3 la correspondiente c\u00e9dula de \u00ab<em>guardament de dan<\/em>\u00bb, comprometi\u00e9ndose a pagar en su lugar a los mercaderes Novara y Passabonello las cantidades que tomase prestadas Juan Mir\u00f3 en Roma, as\u00ed como los cambios de moneda y los intereses<sup>332<\/sup>.<\/p>\n<p>Tras la comparecencia ante los mandatarios civiles, Vicente Mart\u00ed se dirigi\u00f3 al monasterio de San Agust\u00edn con la intenci\u00f3n de nombrar a fr. Luis Matarredona como juez compulsor del cap\u00edtulo del Salvador y la ciudad de Orihuela. Una vez estuvo ante \u00e9l, se present\u00f3 como procurador de ambas instituciones, le mostr\u00f3 el rescripto de Camilo Ballion y le solicit\u00f3 que aceptase la nominaci\u00f3n. Matarredona no s\u00f3lo no puso ning\u00fan inconveniente, sino que de inmediato design\u00f3 el citado establecimiento mon\u00e1stico como sede de las audiencias, especific\u00f3 que \u00e9stas tendr\u00edan lugar todos los d\u00edas no feriados \u00ab<em>a la hora de tertia<\/em>\u00bb por la ma\u00f1ana y a las 2 despu\u00e9s del \u00ab<em>mig jorn<\/em>\u00bb por la tarde<sup>333<\/sup>, y nombr\u00f3 a Francisco Olzina y a Antonio Llorens notario y \u00ab<em>corredor<\/em>\u00bb del proceso, respectivamente<sup>334<\/sup>.<\/p>\n<p>El d\u00eda siguiente -15 de febrero-, las autoridades civiles y eclesi\u00e1sticas de Orihuela escribieron tres cartas para Juan Mir\u00f3, Luis G\u00f3mez y Berenguer Gombau, y las enviaron a Roma, por mediaci\u00f3n de Guillem Desprats.<\/p>\n<p>A Juan Mir\u00f3 le anunciaron que Vicente Mart\u00ed hab\u00eda publicado las citatorias de Ballion en la <em>Seu<\/em> de Valencia y en Santa Mar\u00eda de Elche, y le remitieron los autos que daban fe de ambos actos. Tambi\u00e9n le enviaron las nuevas p\u00f3lizas crediticias gestionadas por el se\u00f1or de Castalla. Le encargaron que, con el m\u00e1ximo secreto, tratase de hacer prosperar el negocio de la dismembraci\u00f3n. Le pidieron que les hiciese nuevos regalos al auditor G\u00f3mez y a los cardenales Santiquatro y Ancona. Y teniendo en consideraci\u00f3n las informaciones que les hab\u00eda proporcionado el aludido Mart\u00ed sobre las futuras alegaciones cartaginenses, le recomendaron que en sus intervenciones en la Rota hiciese especial incidencia en dos puntos:<\/p>\n<p>+<em>Ex una<\/em>, que explicase que la instituci\u00f3n del obispado de Orihuela no le supon\u00eda ning\u00fan perjuicio al cabildo de Cartagena a nivel de rentas, puesto que no iban a obstaculizar de forma alguna la tarea recaudadora de sus arrendadores y mayordomos.<\/p>\n<p>+Y <em>ex alia<\/em>, que defendiese la legitimidad de la fundaci\u00f3n episcopal decretada por Julio II utilizando los siguientes argumentos. Que el pont\u00edfice la hab\u00eda promulgado a suplicaci\u00f3n de Fernando el <em>Cat\u00f3lico<\/em>, con una finalidad tan justificada como era poner fin a la causa propiciatoria de las discordias que cotidianamente acontec\u00edan entre el clero y el pueblo de Orihuela y los obispos y el cabildo cartaginenses, esto es, los abusos de poder de \u00e9stos, encarnados en la particular figura del obispo Juan Daza. Que la prestaci\u00f3n forzada de obediencia dada durante el Saco de Orihuela, en 1521, no pod\u00eda ser considerada v\u00e1lida. Y que, no habiendo sido efectuada l\u00edcitamente su revocaci\u00f3n, la creaci\u00f3n del obispado hab\u00eda de ser respetada y ratificada<sup>335<\/sup>.<\/p>\n<p>Al auditor G\u00f3mez le rogaron que le insistiese al cardenal Santiquatro en el tema de la dismembraci\u00f3n, aclar\u00e1ndole que estaban dispuestos a pagar cuanto hiciese falta por lograrla. Sobre el consentimiento real, le indicaron que a ellos les resultaba imposible conseguirlo, ya que Carlos I estaba en Italia y, sobre todo, porque los castellanos ten\u00edan ganado su favor. Y precisamente por este motivo, previendo que la cuesti\u00f3n episcopal diese un giro negativo, le comentaron que estaban dispuestos a llegar a una concordia con los murcianos, y que la \u00fanica soluci\u00f3n que pod\u00edan aceptar al respecto era que la iglesia del Salvador quedase como Catedral, manteniendo todas los honores y las preeminencias propias de las iglesias de esta categor\u00eda, y que el gobierno espiritual de todos los territorios del Reino de Valencia que pertenec\u00edan al obispado de Cartagena fuese cometido a un vicario general que residiese en Orihuela<sup>336<\/sup>.<\/p>\n<p>Y en tercer lugar, a Berenguer Gombau le escribieron para pedirle que, en atenci\u00f3n a su naturalidad valenciana, siguiese trabajando en favor de la causa episcopal<sup>337<\/sup>.<\/p>\n<p>La segunda mitad del mes de febrero y la primera del de marzo transcurrieron en la ciudad del Bajo Segura sin que se produjesen novedades realmente destacables en relaci\u00f3n con el Pleito del Obispado.<\/p>\n<p>La buena predisposici\u00f3n inicial del juez Matarredona se vio pronto truncada porque el agustino tuvo que encargarse de un sinf\u00edn de negocios particulares, que retrasaron <em>sine die<\/em> el comienzo del proceso compulsorio<sup>338<\/sup>. Ante la situaci\u00f3n, las autoridades oriolanas decidieron aguardar a que el fraile quedase libre de sus ocupaciones para iniciar la confecci\u00f3n del compendio. En nuestra opini\u00f3n, ello se debi\u00f3 a que estaban esperando que Carlos I se fuese de Italia para reanudar las gestiones encaminadas a la resoluci\u00f3n judicial del litigio en los tribunales de la Rota.<\/p>\n<p>Tambi\u00e9n hemos de destacar que durante este per\u00edodo, el cabildo de Cartagena envi\u00f3 al can\u00f3nigo Orozco a Orihuela \u00ab<em>fingint que volien promoure concordia<\/em>\u00bb. El cap\u00edtulo del Salvador acept\u00f3 la oferta y encomend\u00f3 las negociaciones a Vicente Mart\u00ed. Sin embargo, las entrevistas -que tuvieron lugar en Campillo- no se tradujeron en ning\u00fan acuerdo por la intransigencia del representante murciano a realizar concesiones, y porque en el fondo, lo que realmente pretend\u00edan los cl\u00e9rigos cartaginenses era ocupar a las autoridades oriolanas en la preparaci\u00f3n de las pl\u00e1ticas, y evitar que investigasen en Murcia y que pudiesen descubrir el avanzad\u00edsimo estado de sus tratos con el Consejo de Castilla y con el propio monarca<sup>339<\/sup>.<\/p>\n<p>Mientras los cartaginenses negociaban en la corte real, en Roma, el s\u00edndico Juan Mir\u00f3, completamente ajeno a tales actividades, contrat\u00f3 a otro abogado, el doctor Segismundo D\u00e1ndalo, aunque de bien poco le sirvi\u00f3<sup>340<\/sup>.<\/p>\n<p>Por aquellas fechas, el centro de todas las atenciones europeas se hallaba en otra ciudad no muy lejana, Bolonia, donde Clemente VII coron\u00f3 emperador a Carlos I el 24 de febrero. Ambos soberanos mantuvieron largas conversaciones y en ellas trataron la cuesti\u00f3n del Pleito del Obispado. Ello signific\u00f3 el final de las opciones oriolanas.<\/p>\n<p>El s\u00edndico murciano Pedro Sambrana consigui\u00f3 convencer al Consejo de Castilla de la justicia de sus representados<sup>341<\/sup>. Y este organismo y las importunaciones del referido procurador movieron al rey a suplicarle al pont\u00edfice que volviese a confirmar la revocaci\u00f3n del obispado de Orihuela aduciendo que \u00e9sa era la \u00fanica v\u00eda para lograr la paz y la quietud de sus s\u00fabditos.<\/p>\n<p>El papa quiso satisfacer al emperador y el 15 de marzo expidi\u00f3 un breve por el que decret\u00f3, <em>motu proprio<\/em>, la anulaci\u00f3n de la comisi\u00f3n hecha a Jacobo Simoneta y la derogaci\u00f3n de todos los rescriptos apost\u00f3licos institutorios del referido \u00ab<em>Episcopatus Oriolensis<\/em>\u00bb. Orden\u00f3 al clero y al pueblo de la ciudad del Bajo Segura que les prestasen el juramento de obediencia al obispo y al cabildo de Cartagena, reconociendo de esa manera su autoridad espiritual, y que les reintegrasen todas sus rentas. Promulg\u00f3, asimismo, que hasta que dichos actos tuviesen lugar, volver\u00edan a tener vigor todas las censuras en las que hab\u00edan incurrido por oponerse a los mandatos pontificios. Y, finalmente, se\u00f1al\u00f3 como ejecutores de sus disposiciones al arzobispo de Granada, al preceptor del monasterio de la Merced de Murcia, y al ministro del monasterio de la Sant\u00edsima Trinidad de dicha ciudad.<\/p>\n<p>Antes de concluir el an\u00e1lisis de este breve, hemos de a\u00f1adir que la suplicaci\u00f3n de Carlos I no fue la \u00fanica causa que movi\u00f3 a Clemente VII a expedirlo. Tambi\u00e9n influyeron en su decisi\u00f3n otros dos factores. El pont\u00edfice aprob\u00f3 su despacho, <em>ex una<\/em>, con la intenci\u00f3n de que, en adelante, nadie pudiese arg\u00fcir que las discordias entre murcianos y oriolanos estuviesen motivadas por cuestiones espirituales, y, <em>ex alia<\/em>, con otro prop\u00f3sito m\u00e1s personal: poner fin a las importunaciones de los s\u00edndicos de ambas partes, ya que con sus sofisticadas argumentaciones y sus simuladas quejas lo ten\u00edan bastante cansado<sup>342<\/sup>.<\/p>\n<p>Una vez Sambrana tuvo el rescripto en sus manos, le rog\u00f3 al emperador que le expidiese dos provisiones en las que instase a su mujer y al duque de Calabria a propiciar la ejecuci\u00f3n del breve. Carlos I atendi\u00f3 la suplicaci\u00f3n del procurador cartaginense y le hizo entregar ambos instrumentos<sup>343<\/sup>. Y, acto seguido, el s\u00edndico emprendi\u00f3 a toda prisa el camino de vuelta a Murcia.<\/p>\n<p>Entretanto, en Orihuela, fr. Luis Matarredona se vio forzado finalmente a renunciar a la judicatura compulsorial por sus m\u00faltiples ocupaciones. Por ello, el 26 de marzo Vicente Mart\u00ed le propuso el cargo a fr. Pedro Ferr\u00e1ndez, vicario provincial del monasterio de San Agust\u00edn de dicha ciudad. Ferr\u00e1ndez acept\u00f3 la ejecuci\u00f3n del proceso y, acto seguido, confirm\u00f3 los nombramientos del notario Francisco Olzina y del nuncio Antonio Llorens, y asign\u00f3 el establecimiento mon\u00e1stico que regentaba como sede para las audiencias<sup>344<\/sup>.<\/p>\n<p>A continuaci\u00f3n, Mart\u00ed le comunic\u00f3 al nuevo juez todos los documentos que sus representados deseaban incluir en el compendio, y el nombre de todos y cada uno de sus custodios. Y le pidi\u00f3 que les expidiese un mandato orden\u00e1ndoles que se los presentasen, para que pudiese procederse a su reconocimiento y a su inserci\u00f3n en el libro compulsorio. Ferr\u00e1ndez acept\u00f3 la demanda del s\u00edndico y expidi\u00f3 dos moniciones citatorias. Una dirigida al de\u00e1n del cabildo de Cartagena, D. Jer\u00f3nimo de Araque, y al notario Rodrigo de M\u00e9rida. Y otra destinada a un buen n\u00famero de eclesi\u00e1sticos y notarios oriolanos: Luis y Jaime de Soler, el propio Vicente Mart\u00ed, Francisco Vilanova, Francisco Olzina, Salvador de Loazes, Andr\u00e9s Arnal, Juan L\u00f3pez de Tuesta, Juan Portogu\u00e9s y Luis Traver. Y les inst\u00f3 a todos ellos, bajo pena de excomuni\u00f3n mayor, a que le hiciesen llegar los instrumentos reclamados. Despu\u00e9s, Mart\u00ed le solicit\u00f3 a Ferr\u00e1ndez que le despachase otra orden de comparecencia al can\u00f3nigo Juan de Orozco y al notario que el cabildo cartaginense quisiese asignar para realizar de su parte los cotejos, a fin de que se personasen en la sala habilitada para las audiencias entre los d\u00edas 26 y 30 de abril. El fraile agustino no puso ning\u00fan inconveniente, orden\u00f3 al notario Olzina que expidiese dicho mandato, y dio por concluida la sesi\u00f3n<sup>345<\/sup>.<\/p>\n<p>Cinco d\u00edas despu\u00e9s, el 31 de marzo, un sumamente desilusionado Juan Mir\u00f3 consigui\u00f3 hacerse con una copia del breve bolo\u00f1\u00e9s, y la envi\u00f3 con toda urgencia a Orihuela<sup>346<\/sup>.<\/p>\n<p>Ese mismo d\u00eda, Vicente Mart\u00ed volvi\u00f3 a desplazarse a Murcia para asistir a la segunda y \u00faltima presentaci\u00f3n cartaginense de pruebas. Tras dar comienzo la audiencia vespertina, Orozco le requiri\u00f3 a fr. Cosme de Guzm\u00e1n que ordenase el reconocimiento y la compulsa de la documentaci\u00f3n que sus representados deseaban que fuese incluida en su compendio. As\u00ed, present\u00f3 una serie de cartas de Fernando el <em>Cat\u00f3lico<\/em> en las que el monarca reconoc\u00eda el perjuicio que les hab\u00eda causado la erecci\u00f3n del obispado de Orihuela, les instaba a apelar contra ella ante la Santa Sede y les manifestaba claramente su apoyo incondicional<sup>347<\/sup>. Otro bloque de provisiones reales de Carlos I, en las que conced\u00eda el auxilio del brazo secular para la ejecuci\u00f3n de los rescriptos revocatorios de la referida fundaci\u00f3n episcopal<sup>348<\/sup>. Y otros tres valiosos instrumentos: un auto en el que la autoridades municipales de la ciudad del Bajo Segura le ordenaban a Jaime de Sant\u00e1ngel el secuestro de las rentas del cabildo de Cartagena y de la f\u00e1brica de la Catedral de Murcia (3 de junio de 1518); la revocaci\u00f3n del vicario general Luis de Soler (30 de junio de 1518); y, finalmente, unas letras del cardenal Jacobacis reimponiendo sobre el clero y el pueblo de Orihuela las censuras en que hab\u00edan incurrido por desobedecer los mandatos apost\u00f3licos (16 de noviembre de 1518). Guzm\u00e1n revis\u00f3 todas las escrituras, confirm\u00f3 su legitimidad y mand\u00f3 que fuesen copiadas en el compendio. Y una vez el notario M\u00e9rida termin\u00f3 tan minuciosa labor, Orozco le rog\u00f3 al juez que diese por concluido el proceso compulsorio. Guzm\u00e1n acept\u00f3 la solicitud del procurador cartaginense, le pregunt\u00f3 a Mart\u00ed si estaba conforme, y ante su respuesta afirmativa, les mand\u00f3 a los notarios de ambas partes que signasen, sellasen y cerrasen el libro. Y cuando \u00e9stos lo hicieron, el mercedario se lo entreg\u00f3 a Orozco y dio por acabada su misi\u00f3n<sup>349<\/sup>.<\/p>\n<p>Entonces, siguiendo las instrucciones de sus representados, Vicente Mart\u00ed se acerc\u00f3 al notario M\u00e9rida y le encargo una copia del compendio. Y para que aceptase su proposici\u00f3n le ofreci\u00f3 como pago una generos\u00edsima cantidad, 6 ducados. Tras conocer la cuant\u00eda del estipendio, M\u00e9rida no pudo negarse y se comprometi\u00f3 a entreg\u00e1rsela en unos diez d\u00edas.<\/p>\n<p>Tras dicha conversaci\u00f3n, Mart\u00ed y Olzina se retiraron e hicieron noche en Murcia. Y la ma\u00f1ana del d\u00eda siguiente, 1 de abril, le comunicaron al procurador Orozco la orden de comparecencia expedida por fr. Pedro Ferr\u00e1ndez<sup>350<\/sup>.<\/p>\n<p>El mes de abril comenz\u00f3 de una manera muy tranquila para las autoridades oriolanas. \u00danicamente podemos rese\u00f1ar dos acontecimientos. Por un lado, que el d\u00eda 8 Olzina y Mart\u00ed les notificaron a Luis y a Jaime de Soler el mandato citatorio del juez, y les indicaron que comenzasen a buscar en el Archivo de la Catedral del Salvador los documentos necesarios para probar la legitimidad de la fundaci\u00f3n episcopal<sup>351<\/sup>. El sacrist\u00e1n y el chantre comenzaron tal tarea, y con mucha dificultad consiguieron encontrar las escrituras demandadas pues \u00ab<em>hi estaven les coses baregades del temps del Saco de Oriola<\/em>\u00bb<sup>352<\/sup>. Y por otro, que d\u00eda 13, con algo de retraso, Rodrigo de M\u00e9rida envi\u00f3 el traslado del libro compulsorio cartaginense<sup>353<\/sup>.<\/p>\n<p>Sin embargo, la calma termin\u00f3 hacia el 20 de abril cuando los mandatarios se enteraron -no sabemos c\u00f3mo- de que los murcianos estaban esperando la inminente llegada de \u00ab<em>unes bulles en les quals lo papa mana que lo provisor aja de exercir jurisdictio en Oriola, en virtut de la posesio quels donam forcivolment e metu quant a la Rota<\/em>\u00bb. La gravedad de la situaci\u00f3n les hizo escribir a Juan Mir\u00f3 para comentarle el rumor y rogarle que tratase de conseguir a cualquier precio \u00ab<em>un vicari apostolich, litte pendente<\/em>\u00bb, \u00ab<em>ab lo poder que altres vicaris generals tenen en les sglesies catredals<\/em>\u00bb, y con \u00ab<em>jurisdictio en tota la diocesis de Oriola<\/em>\u00bb<sup>354<\/sup>. Por esta petici\u00f3n podemos deducir que la informaci\u00f3n de que dispon\u00edan las autoridades no era del todo correcta puesto que, como ya hemos indicado, el nuevo breve derogaba la comisi\u00f3n hecha al auditor Simoneta y pon\u00eda fin al litigio. De esa manera, de bien poco les iba a servir contar con un vicario general \u00ab<em>litte pendente<\/em>\u00bb.<\/p>\n<p>Pese a su trascendencia, la nueva no vari\u00f3 los planes del cap\u00edtulo del Salvador y los oficiales municipales, y las diligencias encaminadas a la confecci\u00f3n del proceso compulsorio prosiguieron. El d\u00eda 21 de abril Mart\u00ed y Olzina notificaron la orden de comparecencia de Ferr\u00e1ndez a los notarios Vilanova, Arnal, L\u00f3pez de Tuesta, Portogu\u00e9s y Traver. Y el 26 hicieron lo propio con Salvador de Loazes. Y una vez efectuaron esta \u00faltima citaci\u00f3n, Mart\u00ed se present\u00f3 ante el juez compulsor con la intenci\u00f3n de comenzar el cotejo de escrituras y la inserci\u00f3n de pruebas en el compendio. No obstante, ni Juan de Orozco ni su notario se personaron en el monasterio de San Agust\u00edn, y el procurador oriolano no pudo hacer m\u00e1s que acusarlos de contumacia, y esperar al d\u00eda siguiente para ver si aparec\u00edan, y pod\u00edan iniciarse los tr\u00e1mites<sup>355<\/sup>.<\/p>\n<p>Aunque la representaci\u00f3n murciana no estaba obligada a presentarse ante Ferr\u00e1ndez ese preciso d\u00eda, pues ten\u00eda de plazo para hacerlo hasta el 30 de abril, entre las autoridades oriolanas cundi\u00f3 la sospecha de que la incomparecencia pudiese deberse a que, efectivamente, el cabildo de Cartagena hubiese obtenido el rescripto apost\u00f3lico.<\/p>\n<p>Dicha suspicacia vino a confirmarse de inmediato ya que ese mismo d\u00eda 26, probablemente a \u00faltima hora de la tarde, lleg\u00f3 a la ciudad del Bajo Segura un correo que portaba una carta del Concejo de Murcia, en la que sus regidores expon\u00edan que el \u00ab<em>sancto padre, sabyda la voluntad de Su Magestad de su propria boca<\/em>\u00bb, hab\u00eda aprobado la expedici\u00f3n de un breve. A\u00f1ad\u00edan los ediles de un modo premeditadamente vago que en \u00e9l, el pont\u00edfice mandaba \u00ab<em>lo que le ha pares\u00e7ido que satisfaze al servicio de Dios y suyo, y de Su Magestad, y a la pa\u00e7ifica\u00e7ion y quietud destas \u00e7ibdades y destos Reynos<\/em>\u00bb. Seg\u00fan nuestro parecer, explicaron de ese modo tan impreciso el contenido del rescripto para tratar de aprovechar la ignorancia de los oriolanos y hacerles creer que constitu\u00eda una suerte de concordia, a fin de que no les embarazasen su ejecuci\u00f3n. El tenor subsiguiente de la misiva confirma este planteamiento ya que los aludidos mun\u00edcipes aseguraban querer \u00ab<em>hazer sabydora a esa \u00e7ibdad de lo que Su Sanctidad ha mandado<\/em>\u00bb tanto por la \u00ab<em>buena crian\u00e7a y cortesya<\/em>\u00bb de la que siempre hac\u00edan gala, como por \u00ab<em>el amor y deudo que general y particularmente<\/em>\u00bb dec\u00edan sentir hacia sus vecinos oriolanos; y les rogaban que les notificasen el d\u00eda que estaban dispuestos a que los representantes del cabildo de Cartagena les mostrasen el breve. Y culminando el enga\u00f1o, conclu\u00edan afirmando que esperaban que les respondiesen afirmativamente puesto que ellos har\u00edan lo mismo \u00ab<em>en semejante caso y en otro cualquiera<\/em>\u00bb que su ciudad fuese \u00ab<em>exortada por vuestras mer\u00e7edes<\/em>\u00bb<sup>356<\/sup>.<\/p>\n<p>La sibilina treta murciana no tuvo ning\u00fan \u00e9xito. Poco despu\u00e9s de la llegada del mencionado correo concejil a la ciudad del Bajo Segura, arribaron noticias fidedignas de que el breve impetrado por el procurador Pedro Sambrana derogaba la comisi\u00f3n hecha a Simoneta, y ordenaba la revocaci\u00f3n del obispado de Orihuela y el retorno a la sumisi\u00f3n cartaginense.<\/p>\n<p>Esta \u00faltima informaci\u00f3n propici\u00f3 que el cap\u00edtulo del Salvador y los oficiales municipales se reunieran para trazar un plan inmediato de actuaciones. De entrada, todos estuvieron de acuerdo en no permitir la ejecuci\u00f3n directa del rescripto por los cl\u00e9rigos murcianos. Y previendo que les solicitasen a Isabel de Portugal o al duque de Calabria el auxilio del brazo secular, decidieron enviar sendas embajadas a las respectivas cortes de la emperatriz y del virrey. Cometieron la primera al experimentado Luis Mart\u00ednez, y la segunda a Juan de Vilafranca, otro can\u00f3nigo del Salvador que tambi\u00e9n hab\u00eda representado los intereses oriolanos en alguna ocasi\u00f3n. Y a\u00fan tuvieron tiempo esa misma noche para redactar la carta de creencia de Vilafranca para D. Fernando de Arag\u00f3n, y tres escritos de recomendaci\u00f3n para tres caballeros residentes en la ciudad del Turia: D. Ram\u00f3n Boh\u00edl -se\u00f1or de B\u00e9tera-, D. Ram\u00f3n Lladr\u00f3 -se\u00f1or de Castalla y Onil-, y D. Juan Ferr\u00e1ndez de Heredia<sup>357<\/sup>.<\/p>\n<p>El d\u00eda siguiente -27 de abril-, las referidas autoridades consideraron oportuno liberar a Vicente Mart\u00ed de sus obligaciones en el proceso compulsorio, para que pudiese centrarse plenamente en la organizaci\u00f3n de la defensa contra el nuevo breve de Clemente VII. En su lugar, nombraron procurador a Pedro L\u00f3pez, quien acudi\u00f3 a la audiencia matutina de Ferr\u00e1ndez, le present\u00f3 sus sindicatos, y se mostr\u00f3 dispuesto a comenzar la revisi\u00f3n de los documentos. Sin embargo, la parte cartaginense no acudi\u00f3 ni a dicha sesi\u00f3n ni a la vespertina, y el inicio de las compulsas hubo de aplazarse, al menos, hasta el d\u00eda siguiente<sup>358<\/sup>. Por entonces, en nuestra opini\u00f3n, los oriolanos ya supon\u00edan que el cabildo rival no enviar\u00eda, finalmente, a nadie a supervisar la confecci\u00f3n del compendio puesto que el aludido rescripto apost\u00f3lico anulaba la comisi\u00f3n de Simoneta y, por consiguiente, el proceso compulsorio ser\u00eda absolutamente in\u00fatil.<\/p>\n<p>El mismo d\u00eda 27 de abril, los mandatarios le entregaron a Luis Mart\u00ednez algunas cartas.<\/p>\n<p>Una credencial para la emperatriz, en la que le explicaban que el breve bolo\u00f1\u00e9s hab\u00eda sido despachado sin que les fuese permitido el derecho de defensa, que iba en contra del <em>acte de cort<\/em> aprobado por su marido en las \u00faltimas Cortes de Monz\u00f3n, y que podr\u00eda suponer el inicio de truculentos enfrentamientos entre las poblaciones de Orihuela y Murcia; y en atenci\u00f3n a tales justificados motivos, le suplicaban que cuando el cabildo de Cartagena le rogase la expedici\u00f3n del ejecutorial, antes de despacharlo, le consultase a Carlos I si realmente deseaba que se procediese a la ejecuci\u00f3n del rescripto<sup>359<\/sup>.<\/p>\n<p>Y dos misivas dirigidas a los doctores Artes y Ram, del Consejo de Arag\u00f3n, en las que les informaban que los murcianos, viendo que no ten\u00edan posibilidades de ganar el litigio, hab\u00edan conseguido el documento apost\u00f3lico de modo extrajudicial, \u00ab<em>ab sinistres informacions<\/em>\u00bb y \u00ab<em>ab les favors de Castella<\/em>\u00bb, y \u00ab<em>sens oyr al nostre sindich<\/em>\u00bb, y les rogaban que apoyasen a Mart\u00ednez ante la emperatriz para que \u00e9sta le consultase a su esposo antes de tomar ninguna decisi\u00f3n puesto que de no hacerlo, con casi total seguridad, volver\u00edan a reproducirse \u00ab<em>les diferencies pasades<\/em>\u00bb<sup>360<\/sup>.<\/p>\n<p>Y el d\u00eda siguiente -28 de abril- le entregaron a Luis Mart\u00ednez un \u00faltimo escrito, dirigido a Juan Vaguer, que ten\u00eda un contenido muy similar al de las misivas redactadas para los consejeros supraescritos. Le ped\u00edan al \u00ab<em>scriva de manament<\/em>\u00bb que tratase de ayudar al procurador en su delicada misi\u00f3n<sup>361<\/sup>.<\/p>\n<p>Tambi\u00e9n le proporcionaron cuatro cartas m\u00e1s a Juan de Vilafranca, para que se las entregase en Valencia al gobernador del Reino <em>citra Sexonam<\/em>, al cap\u00edtulo de la Metropolitana valentina, y a los doctores Ros y Figuerola. Merece especial comentario esta \u00faltima ya que, en ella, le comentaron al vicecanciller que Orihuela estaba \u00ab<em>molt alterada y ab grandissima fatigua<\/em>\u00bb porque el emperador la hab\u00eda perjudicado \u00ab<em>apres de haver provehit en les Corts, y avernos causat grandissimes despeses en trametre a Roma sindichs e procuradors<\/em>\u00bb, sobre todo, \u00ab<em>essent aquesta ciutat tant fidelissima a la real Corona de Arago<\/em>\u00bb. Asimismo, le advirtieron que tem\u00edan que se produjesen \u00ab<em>alguns escandols entre estes ciutats si los de Murcia trameten al provisor a exercir jurisdiccio<\/em>\u00bb. Le comunicaron su opini\u00f3n de que el monarca le hab\u00eda recomendado al papa la expedici\u00f3n del breve sin recordar su provisi\u00f3n real dada en Monz\u00f3n. Y, finalmente, le suplicaron que le recomendase al duque que no diese lugar al \u00e9xito de \u00ab<em>les pasions de Castella<\/em>\u00bb en perjuicio de Orihuela, y que antes de adoptar cualquier resoluci\u00f3n, le consultase a Su Majestad sobre \u00ab<em>la veritat y estament de la causa<\/em>\u00bb<sup>362<\/sup>.<\/p>\n<p>Y, por \u00faltimo, ese mismo 28 de abril, las autoridades oriolanas le remitieron su respuesta al Concejo de Murcia. Como comprobaremos a continuaci\u00f3n, decidieron claramente seguirles el juego. Les escribieron que cre\u00edan que el breve que deseaban mostrarles deb\u00eda tratar \u00ab<em>sobre lo proces ques fulmina davant los jutges compulsors<\/em>\u00bb. Y para ganar tiempo y no se\u00f1alar el d\u00eda de la presentaci\u00f3n, se inventaron la excusa de que algunos de los <em>Electos<\/em> que se encargaban de dicho asunto se hallaban fuera de la ciudad y que, por ello, no sab\u00edan \u00ab<em>en quin estament<\/em>\u00bb estaba la cuesti\u00f3n. Y les informaron que en cuanto llegasen, les volver\u00edan a escribir para anunciarles la fecha en la que estar\u00edan dispuestos a recibir la notificaci\u00f3n<sup>363<\/sup>.<\/p>\n<p>El \u00faltimo d\u00eda de abril termin\u00f3 el plazo otorgado a la parte cartaginense para presentarse ante fr. Pedro Ferr\u00e1ndez. Por ello, en su ausencia, Pedro L\u00f3pez le pidi\u00f3 al juez que diese inicio a las compulsas. El agustino acept\u00f3 la petici\u00f3n del procurador y para agilizar los tr\u00e1mites nombr\u00f3 conotario del proceso al escribano del <em>Consell<\/em>, Francisco Vilanova. Despu\u00e9s, declar\u00f3 contumaces y rebeldes a los murcianos, nombr\u00f3 compulsores a Pedro de la Mata, Gin\u00e9s Zaplana, Mart\u00edn Ruiz de Mendoza, Jaime Segarra y Andr\u00e9s Arnal, y orden\u00f3 que comenzase la presentaci\u00f3n de documentos<sup>364<\/sup>.<\/p>\n<p>En primer lugar, comparecieron Luis y Jaime de Soler, y Vicente Mart\u00ed, custodios de las llaves del Archivo Catedralicio, y le entregaron a Ferr\u00e1ndez las bulas de la creaci\u00f3n del obispado de Julio II (13 de mayo de 1510); la de aplicaci\u00f3n de las <em>Pilas<\/em> a la f\u00e1brica del Salvador (6 de febrero de 1511); las bulas del nombramiento de Mateo Lang como obispo de Cartagena y Orihuela (1 de noviembre de 1512); el breve confirmatorio del obispado de Le\u00f3n X (27 de junio de 1515); y un instrumento absolutorio de censuras del cardenal Jacobacis (15 de julio de 1520)<sup>365<\/sup>.<\/p>\n<p>Tras el reconocimiento y la inserci\u00f3n de los citados documentos en el compendio, el conotario Vilanova, como responsable del Archivo del <em>Consell<\/em>, le present\u00f3 al juez una serie de privilegios reales concedidos a la ciudad: un repartimiento decretado por Alfonso X el <em>Sabio<\/em> (15 de julio de 1266); el juramento de sumisi\u00f3n de Orihuela a Jaime II y su inclusi\u00f3n en la Corona de Arag\u00f3n (11 de mayo de 1296); la creaci\u00f3n de la Gobernaci\u00f3n de Orihuela y el decreto de inseparabilidad de Pedro IV el <em>Ceremonioso<\/em> (10 de septiembre de 1366); el privilegio llamado del <em>Morabat\u00edn<\/em> del mismo Pedro IV (18 de julio de 1380); el veto beneficial a los castellanos de Mart\u00edn I el <em>Humano<\/em> (20 y 22 de junio de 1405); la erecci\u00f3n en ciudad de Orihuela y la promesa del obispado de Alfonso V el <em>Magn\u00e1nimo<\/em> (11 de septiembre de 1437); la confirmaci\u00f3n de los privilegios de la ciudad de Fernando el <em>Cat\u00f3lico<\/em> (30 de julio de 1510); y la confirmaci\u00f3n de privilegios de Carlos I y Juana la <em>Loca<\/em> (30 de noviembre de 1522)<sup>366<\/sup>.<\/p>\n<p>Tambi\u00e9n present\u00f3 un buen n\u00famero de cartas y c\u00e9dulas reales favorables: una provisi\u00f3n de Alfonso el <em>Magn\u00e1nimo<\/em> prohibiendo cualquier comunicaci\u00f3n con la clerec\u00eda cartaginense (23 de septiembre de 1451); dos cartas de Fernando el <em>Cat\u00f3lico<\/em> dirigidas al obispo Mateo, y al embajador D. Jer\u00f3nimo de Vic y al doctor Loaysa (junio de 1514); otras dos misivas de Carlos I para Le\u00f3n X, y para D. Jer\u00f3nimo de Vic y D. Pedro de Urrea (4 de agosto de 1517); dos escritos del citado rey cuyos destinatarios eran Clemente VII, <em>ex una<\/em>, y el duque de Sessa y D. Juan Bartolom\u00e9 de Gattinara, <em>ex alia<\/em> (3 y 10 de marzo de 1525); una carta del mismo monarca a las autoridades oriolanas en respuesta a la embajada de Mart\u00edn Ruiz de Mendoza (22 de diciembre de 1525); y, por \u00faltimo, las dos provisiones expedidas en las Cortes de Monz\u00f3n a Clemente VII y al embajador Miguel May (15 de julio de 1528)<sup>367<\/sup>.<\/p>\n<p>Despu\u00e9s de Francisco Vilanova compareci\u00f3 Andr\u00e9s Arnal, que ten\u00eda en su poder los registros del notario Alfonso Crist\u00f2fol, y present\u00f3 los siguientes documentos: el auto de presentaci\u00f3n de las bulas de Julio II al cap\u00edtulo del Salvador y a las autoridades civiles de la ciudad (22 de octubre de 1510); una copia de dichos rescriptos apost\u00f3licos; el ejecutorial de las bulas despachado por Fernando el <em>Cat\u00f3lico<\/em> (30 de septiembre de 1510); la presentaci\u00f3n de dichos instrumentos pontificios en las diferentes poblaciones del obispado (del 17 al 23 de noviembre de 1510); y, por \u00faltimo, la toma de posesi\u00f3n del obispado por Jer\u00f3nimo de Carasso, en sustituci\u00f3n del procurador episcopal, Maximiliano Transilvano (23 de noviembre de 1517)<sup>368<\/sup>. Tras Vilanova, Salvador de Loazes le present\u00f3 a fr. Pedro Ferr\u00e1ndez la procura hecha por Transilvano a Carasso (12 de noviembre de 1517)<sup>369<\/sup>.<\/p>\n<p>A continuaci\u00f3n fue Francisco Olzina quien puso en manos del juez compulsor una buena cantidad de documentos expedidos por los vicarios generales de Orihuela (Luis y Jaime de Soler) y toda una serie de apelaciones y protestas interpuestas por el cap\u00edtulo del Salvador y las autoridades municipales contra los rescriptos obtenidos por los cartaginenses y contra sus intentos de ejecuci\u00f3n (ordenadas cronol\u00f3gicamente: 27 de abril, 12 de mayo y 30 de junio de 1518; 14 de enero y 7 de septiembre de 1519; 16 de febrero y 9 de noviembre de 1524; 18 de febrero, 3 de abril, 6 de octubre, 9 y 25 de noviembre y 15 de diciembre de 1525; y 3 de abril de 1527)<sup>370<\/sup>.<\/p>\n<p>Despu\u00e9s de Olzina, hizo acto de comparecencia Juan Portogu\u00e9s, quien present\u00f3 otra apelaci\u00f3n interpuesta contra un proceso monitorio fulminado por fr. Fernando de Rojas, y fechada el 30 de junio de 1518<sup>371<\/sup>. Y tras \u00e9l, fue Juan L\u00f3pez de Tuesta el notario que entreg\u00f3 la documentaci\u00f3n que le hab\u00eda sido requerida: una provisi\u00f3n del 20 de febrero de 1520 dirigida al licenciado Juan Ruiz de Salvatierra en la que el cardenal Adriano de Utrecht le conminaba a actuar como inquisidor del Reino de Murcia y la gobernaci\u00f3n de Orihuela<sup>372<\/sup>. Acto seguido, Luis Traver present\u00f3 dos autos de disentimiento que hab\u00eda extra\u00eddo de los registros del difunto Bernardo Manresa, fechados el 22 de agosto de 1523 y el 9 de noviembre de 1525<sup>373<\/sup>. Luego, volvi\u00f3 a intervenir Francisco Vilanova para presentar la documentaci\u00f3n relativa al intento cartaginense de ejecuci\u00f3n de la revocaci\u00f3n del obispado que D. Pedro Maza de Lizana abort\u00f3 en 1525<sup>374<\/sup>. Y por \u00faltimo, el propio s\u00edndico Pedro L\u00f3pez complet\u00f3 el proceso a\u00f1adiendo dos \u00faltimos instrumentos: la bula de nombramiento de Fernando Rodr\u00edguez como pavorde de la Catedral de Orihuela (31 de octubre de 1529) y el auto de fijaci\u00f3n de las citatorias de Camilo Ballion en la iglesia de Santa Mar\u00eda de Elche (26 de enero de 1530)<sup>375<\/sup>.<\/p>\n<p>Los compulsores dieron su visto bueno a la inserci\u00f3n de toda la documentaci\u00f3n se\u00f1alada en el compendio. El juez Ferr\u00e1ndez otorg\u00f3, asimismo, su consentimiento. Y los notarios Olzina y Vilanova la copiaron en el libro. Y ese mismo d\u00eda 30 de abril, lo signaron y sellaron y se lo entregaron a Pedro L\u00f3pez para que lo pudiese enviar a la Curia romana<sup>376<\/sup>.<\/p>\n<p>El compendio constaba, como hemos podido comprobar, de un gran volumen de documentos de variada tipolog\u00eda:<\/p>\n<p>-Privilegios reales entre los que cabe destacar el archicitado de Alfonso el <em>Magn\u00e1nimo<\/em> prometiendo el obispado y la confirmaci\u00f3n de Carlos I, por la que se compromet\u00eda impl\u00edcitamente a auspiciar la fundaci\u00f3n episcopal.<\/p>\n<p>-Cartas reales dirigidas a los embajadores espa\u00f1oles cerca de la Santa Sede y a los pont\u00edfices Le\u00f3n X y Clemente VII, con la intenci\u00f3n de conseguir que el Pleito del Obispado fuese resuelto imparcialmente por la v\u00eda judicial.<\/p>\n<p>-Provisiones inquisitoriales encaminadas a la soluci\u00f3n pac\u00edfica de los roces surgidos entre los inquisidores murcianos y el clero y el pueblo de Orihuela, con el trasfondo de la cuesti\u00f3n episcopal.<\/p>\n<p>-Apelaciones, protestas y disentimientos interpuestos conjuntamente por el cap\u00edtulo del Salvador y las autoridades municipales contra breves apost\u00f3licos perjudiciales o contra los procesos promulgados por los jueces ejecutores y subejecutores de dichos rescriptos.<\/p>\n<p>-Y, por \u00faltimo, toda una serie de \u00f3rdenes y resoluciones expedidas por los vicarios generales de Orihuela en el ejercicio de sus funciones.<\/p>\n<p>La extensi\u00f3n del compendio, 287 folios, y su ampl\u00edsima selecci\u00f3n documental nos hace deducir que los oriolanos eran plenamente conscientes de la trascendencia del proceso compulsorio para el futuro de sus aspiraciones episcopales. Una vez hecha p\u00fablica la noticia de la obtenci\u00f3n cartaginense del breve de Bolonia, los referidos mandatarios no pensaron en abandonar su confecci\u00f3n, sino en todo lo contrario. Pretendieron preparar un complet\u00edsimo alegato defensivo de sus derechos de modo que, de confirmarse la anulaci\u00f3n de la comisi\u00f3n a Simoneta, pudiese servir de base para la fundamentaci\u00f3n de las apelaciones que fuese necesario interponer contra la nueva situaci\u00f3n tanto ante Carlos I como ante la Santa Sede<sup>377<\/sup>.<\/p>\n<ol start=\"17\">\n<li><strong> La consulta de la emperatriz Isabel a Carlos I.<\/strong><\/li>\n<\/ol>\n<p>Terminados todos los preparativos, el lunes 1 de mayo los can\u00f3nigos Juan de Vilafranca y Luis Mart\u00ednez partieron de Orihuela en direcci\u00f3n a sus respectivos destinos: las cortes del virrey y de la emperatriz<sup>378<\/sup>.<\/p>\n<p>Cuatro d\u00edas despu\u00e9s, las autoridades municipales decidieron volver a escribir a sus colegas murcianos, con la doble intenci\u00f3n de darles nuevas largas en relaci\u00f3n con el asunto de la presentaci\u00f3n del breve, y de hacerles creer que no conoc\u00edan todav\u00eda el contenido del rescripto. Conectando con su anterior misiva, les comentaron que Vicente Mart\u00ed les hab\u00eda dicho que cre\u00eda que la \u00ab<em>venguda<\/em>\u00bb de los murcianos no pod\u00eda tener \u00ab<em>altre efecte<\/em>\u00bb sino \u00ab<em>veure lo proces ques fa davant lo jutge compulsor<\/em>\u00bb; que no ten\u00eda sentido pensar que la causa hab\u00eda sido derogada porque Carlos I la hab\u00eda remitido al sumo pont\u00edfice \u00ab<em>ab acte de Corts Generals, que no pot esser revocat segons los furs e privilegis de aquest Regne sino ab acte contrari celebrat en altres Corts Generals<\/em>\u00bb; y que a\u00fan era m\u00e1s incomprensible que, estando la lite pendiente y habiendo sido expedidas y ejecutadas unas letras compulsorias, Su Santidad pudiese tomar una resoluci\u00f3n al margen de la v\u00eda judicial, con el equivocado fin de lograr el \u00ab<em>repos e tranquilitat de les parts<\/em>\u00bb. Despu\u00e9s, en atenci\u00f3n al prop\u00f3sito que ambas partes hab\u00edan de compartir, de lograr \u00ab<em>la pau e concordia destes ciutats<\/em>\u00bb, les se\u00f1alaron que no pod\u00edan creer que hubiesen \u00ab<em>procurat que la causa sia treta del cami de la justicia<\/em>\u00bb y que la hubiesen hecho resolver por una v\u00eda por la cual era \u00ab<em>imposible pendre lo terme que satisfa al servey de Nostre Senyor<\/em>\u00bb. Tras dichos comentarios introductorios, les comunicaron que si quer\u00edan personarse en Orihuela para tratar cualquier cuesti\u00f3n relativa a las compulsorias, lo hicieran sin temor y en paz. Y se despidieron recalcando que Orihuela \u00fanicamente ped\u00eda que \u00ab<em>la causa sia determenada per justicia<\/em>\u00bb<sup>379<\/sup>.<\/p>\n<p>Tras recibir la carta, los murcianos sospecharon que finalmente no podr\u00edan pillar por sorpresa a sus adversarios. No obstante, antes de hacer proceder contra ellos a alguno de los jueces ejecutores del rescripto, decidieron aguardar algunos d\u00edas por si a\u00fan ca\u00edan en la trampa que hab\u00edan urdido.<\/p>\n<p>El 9 de mayo, el cap\u00edtulo del Salvador y los oficiales municipales volvieron a escribirle a Juan Mir\u00f3 para darle noticia de los \u00faltimos acontecimientos. En primer lugar, le avisaron de que los murcianos se jactaban continuamente de que el cardenal Santiquatro estaba de su parte y de que todas las bulas y los breves que hab\u00edan obtenido, los hab\u00edan logrado \u00ab<em>per ses mans<\/em>\u00bb. Le indicaron que tambi\u00e9n aseguraban que hab\u00edan ganado el favor del monse\u00f1or de Ancona. Sobre el breve, le comentaron que era tan favorable a los cartaginenses \u00ab<em>com si ells lo aguesen ordenat<\/em>\u00bb. Le anunciaron que, para entorpecer su ejecuci\u00f3n, hab\u00edan enviado sendas embajadas a las cortes de Isabel de Portugal y del duque de Calabria. Le manifestaron su malestar y su hast\u00edo por el hecho de que, sin ser tenida en cuenta para nada su justicia, los murcianos hubiesen conseguido tan favorable provisi\u00f3n \u00ab<em>ab maldats hi supreptions<\/em>\u00bb. Y, por \u00faltimo, le comunicaron que, pese al rescripto, hab\u00edan decidido proseguir los tr\u00e1mites de las compulsorias y que, tan pronto como acabasen de copiar el compendio -para quedarse con un ejemplar-, se lo enviar\u00edan, junto con el murciano, \u00ab<em>ab persona propria<\/em>\u00bb, para que le llegase con una mayor seguridad<sup>380<\/sup>.<\/p>\n<p>Por otra parte, en Valencia, Juan de Vilafranca compareci\u00f3 ante el lugarteniente general del Reino y le suplic\u00f3 que le consultase al emperador su voluntad antes de tomar ninguna decisi\u00f3n al respecto de la cuesti\u00f3n episcopal. Despu\u00e9s, recab\u00f3 los consejos de diferentes doctores para saber c\u00f3mo deb\u00edan actuar sus representados en el caso de que los cartaginenses pretendiesen ejecutar el breve. Una vez realizadas estas dos tareas, el can\u00f3nigo, en lugar de quedarse en la ciudad del Turia -como ten\u00eda ordenado- a la espera de la llegada de los murcianos, retorn\u00f3 a la poblaci\u00f3n del Bajo Segura<sup>381<\/sup>. No hemos podido conocer el motivo de tal vuelta. Sin embargo, s\u00ed sabemos que las autoridades oriolanas, preocupadas por el hecho de que los adversarios fueran a rogarle al duque la concesi\u00f3n del auxilio del brazo secular, decidieron enviar a la capital del Reino a un nuevo procurador, Francisco P\u00e9rez Felipe. Y el 25 de mayo le entregaron su sindicato y un instrumento de instrucciones, que repet\u00eda pr\u00e1cticamente las que le hab\u00edan dado a su predecesor en el cargo<sup>382<\/sup>.<\/p>\n<p>El 26 de mayo, los murcianos se cansaron de esperar que los oriolanos les diesen el permiso para presentar el breve y decidieron pedirle al ministro del monasterio de San Blas, de la orden de la Sant\u00edsima Trinidad, fr. Pedro Porcel, que, como \u00ab<em>jutge delegat del Summo Pontifice<\/em>\u00bb, publicase un monitorio instando al clero y al pueblo a obedecer los mandatos apost\u00f3licos. El trinitario atendi\u00f3 la suplicaci\u00f3n y dicho d\u00eda orden\u00f3 que fuesen fijados en las puertas de la Catedral de Murcia y de las iglesias de Abanilla y Elche sendos \u00ab<em>cartells<\/em>\u00bb, en los que les conced\u00eda a los habitantes laicos y eclesi\u00e1sticos de la ciudad del Bajo Segura un plazo de tres d\u00edas para que compareciesen ante \u00e9l, y le mostrasen estar dispuestos a obedecer el breve bolo\u00f1\u00e9s y a prestar el pertinente juramento de obediencia al obispo, al provisor y al cabildo de Cartagena.<\/p>\n<p>Dos d\u00edas despu\u00e9s llegaron a Orihuela vagas noticias sobre el proceso fulminado por Porcel. Por ello, el cap\u00edtulo del Salvador y los oficiales municipales se reunieron y prepararon dos escrituras: una apelaci\u00f3n contra dicho monitorio y una consulta para la Santa Sede, dos documentos formalmente diferentes pero de igual enfoque y contenido.<\/p>\n<p>En ambos, las autoridades oriolanas aduc\u00edan que Clemente VII hab\u00eda aprobado el breve \u00ab<em>per conplaure als castellans<\/em>\u00bb, que no dejaban de importunarle con falsas informaciones, \u00ab<em>tacita veritate<\/em>\u00bb; que el rescripto hab\u00eda sido despachado \u00ab<em>sine causa cognicione<\/em>\u00bb, y sin permitir a los procuradores de Orihuela que presentasen sus alegaciones antes de la expedici\u00f3n, algo que atentaba \u00ab<em>contra ley divina y humana, scrita y evangelica<\/em>\u00bb; y que si el pont\u00edfice hubiese sabido que la ejecuci\u00f3n del breve iba a dar pie al surgimiento de nuevos \u00ab<em>scandols e morts e revolucions entre estes dos ciutats y en estos Regnes<\/em>\u00bb no habr\u00eda permitido su impetraci\u00f3n. Y teniendo en cuenta tan l\u00edcitos y justificados motivos, los mandatarios afirmaban que no estaban obligados a acatar ni las \u00f3rdenes apost\u00f3licas contenidas en dicho documento, ni los mandatos del juez ejecutor, y que tampoco hab\u00edan de aceptar como v\u00e1lidas las censuras y penas que les impusiesen por desobedecerlas, al menos, hasta que el papa resolviese el recurso.<\/p>\n<p>No obstante, como no conoc\u00edan la identidad del referido juez y no pod\u00edan acceder a Murcia con total seguridad, le pidieron a Vicente Mart\u00ed que les presentase la apelaci\u00f3n a fr. Pedro Rocamora y fr. Juan Carmenso, y les solicitase la concesi\u00f3n de los ap\u00f3stolos reverenciales o testimoniales necesarios para remitirla a la Santa Sede. Los dos regulares admitieron de inmediato la protesta y le concedieron \u00ab<em>los appostols reverentials o aquells los quals de dret poden donar<\/em>\u00bb<sup>383<\/sup>.<\/p>\n<p>Despu\u00e9s, ese mismo d\u00eda 26 de mayo, el cap\u00edtulo del Salvador y los oficiales municipales consideraron conveniente notificar la existencia de ambos documentos al cabildo de Cartagena y al desconocido juez ejecutor, y le encargaron tal tarea al notario Jaime Segarra<sup>384<\/sup>.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, el 3 de junio, los mandatarios oriolanos tuvieron plena noticia del proceso monitorio y se enteraron de que su autor hab\u00eda sido fr. Pedro Porcel, por lo que redactaron dos nuevas escrituras -una consulta y una apelaci\u00f3n-, perseverando en las anteriores, y se las entregaron al s\u00edndico Segarra para que las llevase a Murcia.<\/p>\n<p>En ellas, le indicaron al trinitario que no pod\u00eda proceder contra ellos por cinco \u00ab<em>rahones e causes<\/em>\u00bb. 1. Porque lo consideraban \u00ab<em>molt sospitos<\/em>\u00bb y \u00ab<em>enemich capital<\/em>\u00bb, por ser \u00ab<em>conventual de la ciutat de Murcia y de la nacio castellana<\/em>\u00bb. 2. Por ser muy breve el plazo que les hab\u00eda dado para comparecer ante \u00e9l, pues era \u00ab<em>imposible<\/em>\u00bb conocer el contenido del \u00ab<em>nulle cartell<\/em>\u00bb y tener tiempo para \u00ab<em>anar a la ciutat de Murcia a presentarse<\/em>\u00bb. 3. Por no haber \u00ab<em>tutus accessus<\/em>\u00bb, acceso sin riesgo, para los de Orihuela, por tener que ir \u00ab<em>a la terra de sos enemichs capitals<\/em>\u00bb. 4. Porque no ten\u00eda poder para proveer \u00ab<em>contra tota justicia<\/em>\u00bb, como lo hab\u00eda hecho. Y 5, porque el cap\u00edtulo del Salvador y las autoridades municipales hab\u00edan consultado al papa \u00ab<em>per informarlo de les morts ques seguiran si lo dit breu se executa, e de la veritat de la causa et pendente consulta<\/em>\u00bb, y entretanto no pod\u00eda haber innovaci\u00f3n alguna en la causa.<\/p>\n<p>Sobre el breve, le comentaron que no pod\u00eda tener ning\u00fan valor porque los murcianos lo hab\u00edan conseguido utilizando medios tan poco l\u00edcitos como el recurso a \u00ab<em>les grans favors dels castellans<\/em>\u00bb, y a los \u00ab<em>prechs e sobornacions<\/em>\u00bb efectuados por sus procuradores. Y le presentaron una serie de argumentos que hac\u00edan leg\u00edtima la existencia del obispado de Orihuela: los end\u00e9micos enfrentamientos entre los habitantes de la ciudad del Bajo Segura y los obispos y provisores cartaginenses, la suplicaci\u00f3n de Fernando el <em>Cat\u00f3lico<\/em>, el consentimiento del obispo Angulo, la ejecuci\u00f3n de las bulas de Julio II en la Catedral del Salvador, la toma de posesi\u00f3n del obispado por el obispo Mateo, y el nombramiento y las actuaciones del vicario general Luis de Soler. E incidieron en el hecho de que la erecci\u00f3n episcopal no causaba detrimento alguno \u00ab<em>en les rendes nec alia<\/em>\u00bb ni a la ciudad de Murcia, ni al cap\u00edtulo de Cartagena, ni a la f\u00e1brica de su Catedral.<\/p>\n<p>Tambi\u00e9n le explicaron que no iban a presentarle personalmente los instrumentos porque tem\u00edan que Jaime Segarra sufriese \u00ab<em>algun mal tractament per les inimicicies e males voluntats que son, ab antiquo, entre les dos ciutats, a causa del dit Pleyt<\/em>\u00bb, y que las iban a colocar \u00ab<em>de nocte, ab temor, a les portes de la vostra casa<\/em>\u00bb. Y, por \u00faltimo, le solicitaron que les admitiese el recurso, y le advirtieron que en el caso de que lo denegase, apelar\u00edan de la denegaci\u00f3n, y ser\u00edan siempre \u00ab<em>ultimus in appellando<\/em>\u00bb, someti\u00e9ndose \u00ab<em>sub protectione domini nostri Pape et Sedis Apostolice<\/em>\u00bb para no sufrir mayores y agravados perjuicios<sup>385<\/sup>.<\/p>\n<p>La noche del citado 3 de junio, Jaime Segarra y el tambi\u00e9n notario Nicol\u00e1s Morrelles partieron de Orihuela, de inc\u00f3gnito, en direcci\u00f3n hacia la ciudad rival. Llegaron al monasterio de la Trinidad, que afortunadamente estaba extramuros, poco despu\u00e9s de o\u00edr c\u00f3mo las campanas de las iglesias murcianas anunciaban la entrada del nuevo d\u00eda. Una vez all\u00ed, Segarra le pidi\u00f3 a Morrelles que procediese a la lectura de los cuatro escritos. El notario no puso ning\u00fan reparo a protagonizar tan curioso acto. Y cuando termin\u00f3 de notificar los instrumentos, a petici\u00f3n del s\u00edndico, los fij\u00f3 en las puertas del referido establecimiento mon\u00e1stico.<\/p>\n<p>La reacci\u00f3n cartaginense \u00fanicamente tard\u00f3 en producirse unos d\u00edas. El 7 de junio fr. Pedro Porcel despach\u00f3 un nuevo \u00ab<em>monitori<\/em>\u00bb, en el que volvi\u00f3 a ordenar al clero y el pueblo de Orihuela, \u00ab<em>ab certes cominacions<\/em>\u00bb, que compareciesen ante \u00e9l para manifestarle su disposici\u00f3n a obedecer los mandatos apost\u00f3licos. Las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura se enteraron de la expedici\u00f3n del nuevo mandato y de su lesivo contenido gracias al \u00ab<em>cartell<\/em>\u00bb que el juez trinitario hizo fijar en las puertas de la iglesia de Santa Mar\u00eda de Elche. Y de inmediato comenzaron a preparar una escritura de protesta contra \u00e9l \u00ab<em>a futuro gravamine et a tempore fatali et a quacumque denegacione per dictum asertum judicem facta vel fienda<\/em>\u00bb porque, seg\u00fan su criterio, no pod\u00eda despachar provisi\u00f3n alguna hasta que el papa determinase la consulta que le hab\u00edan tramitado hac\u00eda unos d\u00edas<sup>386<\/sup>.<\/p>\n<p>Cuatro d\u00edas despu\u00e9s, conocieron que Luis de Fontes, fraile del monasterio del Socorro y uno de los caballeros principales de la ciudad, ten\u00eda la intenci\u00f3n de ir a Roma para tratar ciertos negocios. Por ello, le pidieron que le llevase a Juan Mir\u00f3 los procesos compulsorios. Fontes les contest\u00f3 afirmativamente, y ese mismo d\u00eda 11 le escribieron al procurador oriolano cerca de la Santa Sede para anunciarle el env\u00edo de los compendios<sup>387<\/sup>.<\/p>\n<p>Sin embargo, antes de remitir la carta a Roma, les llegaron algunas informaciones procedentes de dicha ciudad que indicaban que Mir\u00f3 hab\u00eda iniciado su viaje de retorno a Espa\u00f1a, v\u00eda N\u00e1poles, el Lunes de Pascua -18 de abril-<sup>388<\/sup>, y tuvieron que cambiar de planes. Para evitar la posibilidad de que la Iglesia y la ciudad de Orihuela se quedasen sin un representante directo en la capital del Orbe Cat\u00f3lico, le solicitaron al propio Fontes que aceptase ser el sustituto de Mir\u00f3. \u00c9ste supedit\u00f3 su consentimiento al del vicario del monasterio en el que resid\u00eda. Por ello, los referidos mandatarios le elevaron la s\u00faplica al citado superior regular, y sin dificultad consiguieron que le diese la licencia oportuna al destacado fraile.<\/p>\n<p>Antes de iniciar los preparativos de la nueva embajada, el 15 de junio las autoridades oriolanas terminaron de redactar la escritura de apelaci\u00f3n contra el proceso de fr. Pedro Porcel, y le encargaron su interposici\u00f3n al s\u00edndico Vicente Mart\u00ed. El can\u00f3nigo les solicit\u00f3 su admisi\u00f3n y los ap\u00f3stolos reverenciales a los eclesi\u00e1sticos probos y honestos habituales, fr. Pedro Rocamora y fr. Juan Carmenso, quienes le concedieron su permiso para que el recurso fuese introducido en la Curia Apost\u00f3lica<sup>389<\/sup>.<\/p>\n<p>Durante los d\u00edas siguientes, los mandatarios se dedicaron por completo a la organizaci\u00f3n de la aludida embajada. Y tras unos d\u00edas de duro trabajo, el 21 de junio le entregaron a fr. Luis de Fontes la documentaci\u00f3n que ten\u00eda que llevarse a Roma. El volumen de instrumentos era tan considerable que los <em>Electos<\/em> decidieron prepararle un memorial en el que ven\u00edan especificados todos los autos que le hab\u00edan confiado: su sindicato firmado por el cap\u00edtulo del Salvador y los oficiales municipales, la licencia del vicario del Socorro, los dos compendios compulsorios -el oriolano y el murciano-, un par de copias del breve de Bolonia, las apelaciones presentadas contra el citado rescripto y contra el ejecutor Porcel, la consulta que hab\u00eda que presentarle a Clemente VII, una c\u00e9dula de cambio, un traslado de los autos de presentaci\u00f3n de las citatorias de Ballion en Valencia y Elche, tres cartas para el auditor G\u00f3mez, dos para Berenguer Gombau, una para el cardenal Salviatis, y otra para el caballero Marrades -las siete solicitando consejo y apoyo para la causa-, una misiva y una c\u00e9dula de cambio para Juan Mir\u00f3 -por si las noticias eran falsas y segu\u00eda en la Ciudad Eterna-, y un par de cartas de Vicente Mart\u00ed dirigidas al propio Mir\u00f3 y a Luis G\u00f3mez<sup>390<\/sup>.<\/p>\n<p>Tambi\u00e9n le proporcionaron un instrumento que conten\u00eda las instrucciones que hab\u00eda de seguir a su llegada a Roma. Los planes oriolanos eran claros. El procurador que se encargase de las negociaciones -ya fuera Fontes, ya fuera Mir\u00f3- habr\u00eda de presentarle a Clemente VII la consulta, y tendr\u00eda que conseguir que aceptase revisar la cuesti\u00f3n episcopal. Una vez logrado este primer objetivo, el s\u00edndico tendr\u00eda que efectuar con el m\u00e1ximo sigilo las diligencias convenientes para que el pont\u00edfice revocase el breve bolo\u00f1\u00e9s y para que restituyese la causa a la Rota, de modo que \u00e9sta fuese retomada por Simoneta y Ballion en el punto en el que la dejaron, y el complet\u00edsimo proceso compulsorio pudiese desequilibrar la balanza judicial del lado oriolano.<\/p>\n<p>Los mandatarios tambi\u00e9n previeron el m\u00e1s posible caso de que el papa se negase a admitir la interposici\u00f3n de la consulta. Si se produc\u00eda tal indeseada situaci\u00f3n, el s\u00edndico hab\u00eda de presentar apelaciones <em>a futuro gravamine<\/em>, esto es, para evitar futuros perjuicios, ante algunos eclesi\u00e1sticos respetables que residiesen en la Ciudad Eterna -obispos, abades o priores-, en espera de tiempos m\u00e1s afortunados y menos fatales.<\/p>\n<p>Asimismo, tambi\u00e9n plantearon algunas metas secundarias que Mir\u00f3 o Fontes hab\u00edan de conseguir con la ayuda de Berenguer Gombau y, sobre todo, del auditor y penitenciario Luis G\u00f3mez.<\/p>\n<p>En primer lugar, ten\u00edan que lograr que Clemente VII despachase un rescripto nombrando conservador de la iglesia y el cap\u00edtulo del Salvador, y de sus rentas y privilegios, al vicario general valentino, Guillem Desprats, o al prior del monasterio de San Agust\u00edn, Juan Carmenso. Pretend\u00edan con ello que cuando los cartaginenses se presentasen en Orihuela con la intenci\u00f3n de ejecutar el breve revocatorio, el conservador se opusiese a su puesta en vigor, y excomulgase y lanzase el entredicho contra la Iglesia murciana.<\/p>\n<p>Tambi\u00e9n hab\u00edan de realizar las gestiones oportunas para conseguir un breve en el que fuese designado un vicario general de Orihuela, que pudiese encargarse del regimiento espiritual de la ciudad y su t\u00e9rmino mientras estuviese pendiente la lite. A este respecto, Mir\u00f3 o Fontes estaban facultados para ofrecer dinero a cualquier cardenal que estuviese dispuesto a interceder ante el pont\u00edfice para lograr la expedici\u00f3n del rescripto. Y si consegu\u00edan la merced gracias a la intervenci\u00f3n del auditor G\u00f3mez, hab\u00edan de entregarle una recompensa de 50 libras.<\/p>\n<p>Por \u00faltimo, si no pod\u00edan conseguir dicho breve institutorio del vicario general, los procuradores hab\u00edan de tratar de impetrar una gracia de alcance m\u00e1s moderado que permitiese el habilitamiento de un juez que tuviese poder para \u00ab<em>fer executar los testaments e fer complir los lexats e coses pies<\/em>\u00bb<sup>391<\/sup>.<\/p>\n<p>Por otra parte, hemos de se\u00f1alar que a ra\u00edz de la expedici\u00f3n del breve de Bolonia, las autoridades de la ciudad del Bajo Segura abandonaron por completo el proyecto de la dismembraci\u00f3n, dada la imposibilidad de obtener la aprobaci\u00f3n de Carlos I. Por aquellas fechas, ya era un hecho conocido y probado que el emperador hab\u00eda sido el promotor del rescripto y que, bien por la influencia castellana o bien por sus propias convicciones -lo que no quer\u00edan creer-, estaba decididamente en contra de las aspiraciones episcopales oriolanas. Por ello, los mandatarios optaron por tratar de salvar la posibilidad de lograr que el Pleito fuese solucionado finalmente por la v\u00eda judicial, antes de procurar medidas secesionistas cuyo planteamiento podr\u00eda predisponer al monarca a\u00fan m\u00e1s en contra de Orihuela<sup>392<\/sup>.<\/p>\n<p>Pese a que los <em>Electos<\/em> le entregaron a fr. Luis de Fontes toda la documentaci\u00f3n que hab\u00eda de llevarse a Roma, el cl\u00e9rigo regular aplaz\u00f3 temporalmente su partida. Desconocemos los motivos de su demora. Quiz\u00e1 la explicaci\u00f3n se halle en el hecho de que las autoridades decidiesen aguardar por alg\u00fan tiempo la llegada de Juan Mir\u00f3, para conocer cu\u00e1l era el estado de la cuesti\u00f3n en la Curia, y c\u00f3mo habr\u00edan de enfocarse las negociaciones.<\/p>\n<p>Entretanto, en Madrid el eficiente Luis Mart\u00ednez, con la valiosa ayuda de la condesa de Faro, segu\u00eda realizando diligencias ante el Consejo de Arag\u00f3n y ante Isabel de Portugal<sup>393<\/sup>. Tras muchos esfuerzos e importunaciones consigui\u00f3 convencer a los doctores del citado organismo de la legitimidad de las reclamaciones oriolanas. Entonces, \u00e9stos hicieron comprender a la emperatriz que la expedici\u00f3n del breve revocatorio no hab\u00eda sido del todo correcta desde el punto de vista legal, porque no hab\u00eda tenido en consideraci\u00f3n el derecho oriolano de defensa. Tambi\u00e9n le comentaron que su marido no hab\u00eda respetado el \u00ab<em>acte de cort<\/em>\u00bb aprobado en las Cortes de 1528, y que con sus actos siempre deb\u00eda buscar la justicia, pues era el m\u00e1s \u00ab<em>solido fundamento de los Reynos<\/em>\u00bb. Y por ambos motivos, le aconsejaron que antes de ordenar la ejecuci\u00f3n del rescripto, le consultase a Carlos I qu\u00e9 era lo que hab\u00eda de proveer para procurar el \u00ab<em>servicio, paz y sosiego<\/em>\u00bb de sus s\u00fabditos. Isabel atendi\u00f3 las recomendaciones del Consejo y las repetidas s\u00faplicas del can\u00f3nigo Mart\u00ednez, y el 9 de julio decidi\u00f3 remitirle la cuesti\u00f3n del obispado a su esposo<sup>394<\/sup>.<\/p>\n<ol start=\"18\">\n<li><strong> La embajada de Luis Mart\u00ednez y la respuesta contraria del emperador.<\/strong><\/li>\n<\/ol>\n<p>Inmediatamente despu\u00e9s de conocer la decisi\u00f3n de la emperatriz Isabel, el can\u00f3nigo Luis Mart\u00ednez escribi\u00f3 a las autoridades civiles y eclesi\u00e1sticas de Orihuela para comunicarles la buena nueva de la suspensi\u00f3n temporal de la ejecuci\u00f3n del breve revocatorio.<\/p>\n<p>La noticia fue acogida con gran satisfacci\u00f3n en la ciudad del Bajo Segura. Los mandatarios la interpretaron como un primer paso en el tortuoso camino que hab\u00eda de conducir hacia la ansiada revisi\u00f3n apost\u00f3lica del Pleito, y hacia la a\u00fan m\u00e1s deseada confirmaci\u00f3n del obispado. Por ello, el 17 de julio decidieron hacer un esfuerzo econ\u00f3mico extraordinario para enviar a dos s\u00edndicos a las cortes imperial y pontificia. Y con el fin de conseguir efectivo para sufragar los gastos de ambas embajadas, el <em>Consell<\/em> le encomend\u00f3 a Juan Palomares la tarea de cargar censales por valor de 400 ducados de oro, obviando la alta tasa de endeudamiento municipal<sup>395<\/sup>.<\/p>\n<p>Unos d\u00edas despu\u00e9s, el justicia y los <em>Electos<\/em> decidieron que hab\u00eda llegado la hora de la partida de fr. Luis de Fontes para Roma. Por ello, el d\u00eda 26 de ese mismo mes de julio le escribieron una carta de creencia para el auditor Luis G\u00f3mez, a quien le pidieron, adem\u00e1s de que ayudase al nuevo s\u00edndico, que les enviase informaci\u00f3n sobre Juan Mir\u00f3, puesto que extra\u00f1amente a\u00fan no ten\u00edan de \u00e9l noticia alguna<sup>396<\/sup>. Y poco tiempo despu\u00e9s, Fontes emprendi\u00f3 el camino hacia la Ciudad Eterna.<\/p>\n<p>Tras la marcha del procurador a la capital del Orbe Cat\u00f3lico, las autoridades oriolanas se centraron en la organizaci\u00f3n de la embajada a la corte imperial. Deliberaron sobre la persona que mejor podr\u00eda encargarse de tal misi\u00f3n, y optaron por cometerle el viaje a Alemania a Luis Mart\u00ednez. Asimismo, para suplirle en la corte de la emperatriz, le encomendaron la representaci\u00f3n de la ciudad a otro h\u00e1bil solicitador, Vicente Mart\u00ed.<\/p>\n<p>El 12 de agosto arrib\u00f3, por fin, a Orihuela Juan Mir\u00f3<sup>397<\/sup>. Desgraciadamente, la documentaci\u00f3n no nos permite conocer la causa de su enorme retraso, ni tampoco qu\u00e9 fue lo que les cont\u00f3 a los miembros del cap\u00edtulo del Salvador y del <em>Consell<\/em> sobre el curso de las negociaciones en Roma. Lo que s\u00ed podemos afirmar es que los planes generales de las referidas autoridades no sufrieron modificaci\u00f3n alguna.<\/p>\n<p>A lo largo del mes de agosto, los <em>Electos<\/em> se dedicaron a preparar la documentaci\u00f3n que Mart\u00ednez hab\u00eda de llevarse a Alemania, para present\u00e1rsela a Carlos I. Prestaron un particular inter\u00e9s por conseguir unos determinados documentos; esto es, los autos que se realizaron en 1525, cuando se produjo el \u00faltimo intento cartaginense de ejecuci\u00f3n de la anulaci\u00f3n del obispado. El 20 de agosto enviaron a Vicente Mart\u00ed a la corte de la Gobernaci\u00f3n con el prop\u00f3sito de que D. Luis Togores, lugarteniente de D. Pedro Maza, les proporcionase un traslado de dichos instrumentos<sup>398<\/sup>. Pretend\u00edan con ellos recordarle al emperador un valioso precedente: que ya en otra ocasi\u00f3n anterior hab\u00eda suspendido la puesta en vigor de los rescriptos revocatorios, encomendando la resoluci\u00f3n imparcial del litigio murciano-oriolano a sus Consejos de Castilla y Arag\u00f3n.<\/p>\n<p>Cinco d\u00edas m\u00e1s tarde, Mart\u00ed parti\u00f3 en direcci\u00f3n a Madrid, portando sendas cartas de creencia para los doctores Ram y Artes, as\u00ed como la documentaci\u00f3n que Mart\u00ednez hab\u00eda de llevarse a Alemania. Tambi\u00e9n recibi\u00f3 de las autoridades de la ciudad del Bajo Segura 250 libras que habr\u00eda de entregarle al citado can\u00f3nigo, como adelanto de su salario, para que pudiese emprender el trayecto<sup>399<\/sup>.<\/p>\n<p>A su llegada a la corte de la emperatriz, Vicente Mart\u00ed le particip\u00f3 a Luis Mart\u00ednez la decisi\u00f3n de sus representados de que se encargase de las negociaciones de la causa episcopal ante Carlos I. Mart\u00ednez acept\u00f3 la proposici\u00f3n de los mandatarios oriolanos, y el 7 de septiembre les escribi\u00f3 una carta para comunicarles que cuando se lo ordenaran, partir\u00eda para Alemania.<\/p>\n<p>El escrito lleg\u00f3 a la ciudad del Bajo Segura el 16 de septiembre, y ese mismo d\u00eda, los <em>Electos<\/em> le escribieron una misiva de respuesta, en la que le pidieron que iniciase el viaje cuanto antes, puesto que de Murcia ya hab\u00eda salido una importante delegaci\u00f3n del cabildo de Cartagena en direcci\u00f3n hacia la corte imperial. Para que estuviese m\u00e1s tranquilo, le comunicaron que hab\u00edan conseguido que, durante su ausencia, el cap\u00edtulo del Salvador le mantuviese las distribuciones que le tocaban por su canonj\u00eda, a excepci\u00f3n de las percepciones derivadas de la asistencia a los oficios divinos de rito doble y a los de los aniversarios. Asimismo, le rogaron que aprovechase su estancia en Alemania para entrevistarse con el lejano obispo, el cardenal Mateo, y que apelase a su condici\u00f3n -casi ir\u00f3nica- de \u00ab<em>bon pastor e prelat<\/em>\u00bb para suplicarle por todos los medios que estuviesen a su alcance que nombrase a un vicario general de la di\u00f3cesis de Orihuela, explic\u00e1ndole que hab\u00eda muerto mucha gente sin recibir el sacramento de la confirmaci\u00f3n, y que no hab\u00eda en dicha demarcaci\u00f3n territorial nadie que se encargase del regimiento espiritual de los fieles. Asimismo, le indicaron que tras terminar las diligencias ante Carlos I, se dirigiese a Roma, donde tendr\u00eda que realizar algunas gestiones. Por un lado, habr\u00eda de rogarle al papa la expedici\u00f3n de un breve en el que facultase al cap\u00edtulo del Salvador a proveer las vacantes que se produjesen, \u00ab<em>lite pendente<\/em>\u00bb, en el diaconato, el subdiaconato y los cuatro beneficios curados de la citada Catedral. Y por otro, en el caso de que D. Mateo Lang se negase a proveer al vicario general, tendr\u00eda que suplicarle al pont\u00edfice que procediese al nombramiento del referido primer oficial del obispado de Orihuela. Tambi\u00e9n le se\u00f1alaron que en el caso de que el cardenal de Sant\u00e1ngel se mostrase complaciente, le solicitase que le remitiese un escrito a Clemente VII pidi\u00e9ndole que hiciese justicia en el Pleito, y d\u00e1ndole a entender los da\u00f1os que hab\u00eda causado con el despacho del breve revocatorio. Y, por \u00faltimo, le informaron que le facultaban para tomar prestados hasta 100 ducados de oro, con el fin de que pudiese hacer frente a los gastos relacionados con la consecuci\u00f3n de los objetivos mencionados<sup>400<\/sup>.<\/p>\n<p>La partida de Luis Mart\u00ednez se demor\u00f3 durante algo m\u00e1s de un mes por motivos personales. Por fin, el 22 de octubre el can\u00f3nigo les escribi\u00f3 a las autoridades oriolanas para comunicarles que ese mismo d\u00eda iba a iniciar el viaje. Adem\u00e1s, les inform\u00f3 que la emperatriz le hab\u00eda ordenado que le llevase al emperador su provisi\u00f3n del 9 de julio. Les refiri\u00f3 que llevaba cartas de recomendaci\u00f3n de la condesa de Faro, del duque de Gand\u00eda, de los marqueses de Lombay, del duque de Alba y del marqu\u00e9s de Vilafranca para el secretario Cobos y para el propio Carlos I. Les coment\u00f3 que Vicente Mart\u00ed estaba preparado, asimismo, para volver a Orihuela, ya que su presencia en Madrid carec\u00eda de sentido y s\u00f3lo serv\u00eda para generar gastos in\u00fatiles. Les avis\u00f3 de que D. \u00c1ngel de Pr\u00f3xita se quedaba en la corte de la emperatriz como responsable de la correspondencia oriolana, y que le hab\u00edan encargado, asimismo, que les avisase si ocurr\u00eda alg\u00fan acontecimiento relacionado con la causa episcopal. Y, por \u00faltimo, les pidi\u00f3 que escribiesen a Roma para que le proporcionasen dinero cuando arribase a la Ciudad Eterna<sup>401<\/sup>.<\/p>\n<p>Dicho d\u00eda 22 de octubre, el intr\u00e9pido embajador sali\u00f3 de Alcal\u00e1 de Henares rumbo a Zaragoza. Cuando lleg\u00f3 a la capital ma\u00f1a, se dirigi\u00f3 a Jaca. Atraves\u00f3 despu\u00e9s las tierras del Bearn y de Gascu\u00f1a para llegar a Toulouse. Desde all\u00ed march\u00f3 a Lyon, donde se enter\u00f3 de que el emperador se dirig\u00eda por aquellas fechas a Colonia. Por ello, puso rumbo a Ginebra, cruzando las monta\u00f1as de Saboya. De all\u00ed pas\u00f3 a Basilea, donde supo que Carlos I estaba a punto de llegar a Maguncia. Y tras un breve trayecto terrestre, el d\u00eda de Navidad opt\u00f3 por viajar hasta la ciudad alemana en barca, por las movidas aguas del Rhin. Arrib\u00f3 a Maguncia a finales de a\u00f1o, y sano y salvo, pese a haber pasado multitud de penalidades, motivadas fundamentalmente por el fr\u00edo<sup>402<\/sup>.<\/p>\n<p>Entretanto, en Espa\u00f1a, a fines de noviembre el cabildo de Cartagena intent\u00f3 conseguir de la emperatriz, a instancias del Consejo de Estado, los ejecutoriales del breve pontificio. Nada m\u00e1s conocer los manejos murcianos, D. \u00c1ngel de Pr\u00f3xita alert\u00f3 a las autoridades de Orihuela.<\/p>\n<p>En atenci\u00f3n al aviso, el 9 de diciembre los mandatarios de la poblaci\u00f3n del Bajo Segura decidieron enviar a un correo urgente con la doble intenci\u00f3n de averiguar las intenciones de sus adversarios y de pedir a sus aliados en la corte que, en nombre de la ciudad, realizasen las gestiones oportunas para evitar la concesi\u00f3n real del auxilio del brazo secular. Asimismo, les escribieron algunas cartas a los referidos afectos a la causa oriolana. A D. \u00c1ngel de Pr\u00f3xita y al escribano de mandamiento Juan Talayero les solicitaron que se enterasen de los prop\u00f3sitos murcianos. Al doctor Coscollar le pidieron que aconsejase las medidas que habr\u00eda que tomar para impedir el \u00e9xito del plan cartaginense. Y al doctor Ram le rogaron que, desde su privilegiada posici\u00f3n en el Consejo de Arag\u00f3n, tratase de frustrar el ileg\u00edtimo intento murciano. Tambi\u00e9n le enviaron una misiva a la propia emperatriz, suplic\u00e1ndole que no tomase ninguna decisi\u00f3n relacionada con el Pleito del Obispado hasta que su marido le hiciese llegar una respuesta a la consulta que los oriolanos le hab\u00edan realizado<sup>403<\/sup>.<\/p>\n<p>Poco tiempo despu\u00e9s llegaron a las manos de Isabel dos cartas de Carlos I, dadas en Spira y Colonia, en las que comet\u00eda la resoluci\u00f3n de la cuesti\u00f3n episcopal a los doctores de los Consejos de Castilla y de Arag\u00f3n.<\/p>\n<p>Por otra parte, al llegar a Maguncia, Luis Mart\u00ednez se enter\u00f3 de que el emperador hab\u00eda partido para Colonia ya que su hermano Fernando, el rey de Hungr\u00eda, iba a ser elegido &#8216;rey de romanos&#8217; en dicha ciudad y, despu\u00e9s, hab\u00eda de ser coronado en Aquisgr\u00e1n. Por ello, el embajador oriolano volvi\u00f3 a embarcarse, y por las aguas del Rhin lleg\u00f3 a Colonia el 4 de enero de 1531. All\u00ed alcanz\u00f3, por fin, a Carlos I.<\/p>\n<p>De inmediato, Mart\u00ednez busc\u00f3 la ayuda de D. Hugo de Urries y el se\u00f1or de Ayerve se ofreci\u00f3 amablemente a hablarle del negocio al comendador mayor de Le\u00f3n, Francisco de los Cobos, pues, seg\u00fan su opini\u00f3n, era el ministro real que m\u00e1s pod\u00eda influir sobre el emperador acerca del tema. Y le recomend\u00f3 que no le comentase nada a Carlos I hasta que llegase a Flandes y estuviese algo m\u00e1s desocupado. El can\u00f3nigo consider\u00f3 pertinente el consejo de Urries, y decidi\u00f3 no hacer ninguna diligencia ante el monarca.<\/p>\n<p>El d\u00eda siguiente -5 de enero-, D. Fernando fue electo rey de romanos pese a la oposici\u00f3n del hijo del duque de Sajonia. Dos d\u00edas despu\u00e9s, el emperador, el rey de Hungr\u00eda y toda la corte se desplazaron a Aquisgr\u00e1n para proceder a la coronaci\u00f3n. Llegaron a las cercan\u00edas de la villa el 9 de enero, y el martes 10 la comitiva entr\u00f3 en la hist\u00f3rica poblaci\u00f3n, en un desfile lleno de fastuosidad.<\/p>\n<p>La noche de ese mismo d\u00eda 10, Mart\u00ednez fue a la posada de D. Fernando, del que hab\u00eda sido servidor durante 7 u 8 a\u00f1os, para avisarle de su presencia y pedirle su favor e intercesi\u00f3n. Sin embargo, no pudo hablar con \u00e9l ya que, cansado del ajetreo y del viaje, el monarca decidi\u00f3 cenar retirado en sus aposentos.<\/p>\n<p>El d\u00eda siguiente tuvo lugar su coronaci\u00f3n como rey de romanos. Y el 12 de enero, cuando los \u00e1nimos estaban ya algo m\u00e1s tranquilos, el can\u00f3nigo fue a la posada del reci\u00e9n designado heredero del Imperio y pudo platicar con su antiguo se\u00f1or. D. Fernando lo recibi\u00f3 con honores y le pregunt\u00f3 qu\u00e9 estaba haciendo tan lejos de su patria. Mart\u00ednez le coment\u00f3 que lo hab\u00edan enviado el cap\u00edtulo del Salvador y la ciudad de Orihuela a tratar ciertos asuntos con Carlos I. Y sin que hiciesen falta m\u00e1s palabras, el monarca de Hungr\u00eda le pregunt\u00f3 si dichos negocios ten\u00edan que ver con el Pleito del Obispado. Asombrado por el hecho de que el hermano del emperador tuviese noticia de la causa episcopal, apenas pudo responderle que s\u00ed. Y D. Fernando le replic\u00f3 que, aunque era poco favor para un criado tan antiguo y tan fiel, hablar\u00eda con Cobos y le pedir\u00eda que tomase las medidas oportunas para que el obispado de Orihuela no fuese revocado.<\/p>\n<p>Y la ma\u00f1ana siguiente, como hab\u00eda aseverado, el rey de romanos cit\u00f3 en su posada a Mart\u00ednez y a Cobos, y le pidi\u00f3 al comendador mayor de Le\u00f3n como un favor muy personal que favoreciese los intereses oriolanos en el Pleito. El secretario real le respondi\u00f3 de un modo rotundo: -\u00ab<em>Yo hare lo que Vuestra Merced me manda<\/em>\u00bb, y se despidi\u00f3 del monarca. Y lo mismo hizo Luis Mart\u00ednez tras agradecerle sentidamente sus impagables atenciones.<\/p>\n<p>Poco despu\u00e9s, ese mismo d\u00eda 13, Carlos I y Fernando de Hungr\u00eda, con sus respectivos s\u00e9quitos, partieron en direcci\u00f3n a Flandes y a Bohemia, respectivamente. Y Mart\u00ednez emprendi\u00f3 el viaje a los Pa\u00edses Bajos sin perder de vista al emperador<sup>404<\/sup>.<\/p>\n<p>Ya en Bruselas, el procurador comenz\u00f3 a hacer gestiones con la ayuda y la supervisi\u00f3n de D. Hugo de Urries. \u00c9ste le indic\u00f3 que fuese a hablar con un criado de Cobos, quien a su vez le coment\u00f3, muy en secreto, que intentase convencer al comendador mayor de Calatrava de la justicia oriolana porque \u00e9sa era la mejor manera de hacer prosperar el negocio. Mart\u00ednez se entrevist\u00f3 con el de Calatrava, y el comendador le dijo muy a las claras que all\u00ed, en Flandes, poco se pod\u00eda decidir porque no hab\u00eda letrados, y que tomar una decisi\u00f3n al respecto de la cuesti\u00f3n episcopal supondr\u00eda una afrenta para los doctores de los Consejos de Arag\u00f3n y de Castilla. Asimismo, le comunic\u00f3 que el emperador hab\u00eda escrito dos veces a la emperatriz por v\u00eda del Consejo de Castilla, desde Spira y desde Colonia, dejando el estudio del caso a los miembros de los referidos organismos.<\/p>\n<p>Unos d\u00edas m\u00e1s tarde, Mart\u00ednez se entrevist\u00f3 con el poderoso Cobos. Le entreg\u00f3 las cartas de recomendaci\u00f3n que llevaba del duque de Alba, de la condesa de Faro y de la marquesa de Lombay. Y le relat\u00f3 las diferentes circunstancias del negocio, poniendo especial \u00e9nfasis en la ilegitimidad del breve de Bolonia. El secretario andaluz le explic\u00f3 que \u00e9l no hab\u00eda tenido nada que ver con su despacho, y que el emperador hab\u00eda suplicado su expedici\u00f3n movido por la influencia del Consejo de Castilla. Le pidi\u00f3 un memorial y le dio su palabra de apoyar la causa oriolana.<\/p>\n<p>Tambi\u00e9n parlament\u00f3 el incansable Mart\u00ednez con el borgo\u00f1\u00f3n Nicholas Perrenot, se\u00f1or de Granvelle, que ten\u00eda a su cargo los asuntos de la Corona de Arag\u00f3n. Le inform\u00f3 de los agravios causados por los cartaginenses y de las conexiones de los murcianos. Granvelle le pidi\u00f3 que le entregase al Consejo de Arag\u00f3n un informe que relatase todo el negocio y, al igual que su colega Cobos, se comprometi\u00f3 a auspiciar los intereses episcopales de la Iglesia y la ciudad del Bajo Segura.<\/p>\n<p>Sin embargo, las buenas palabras de los ministros reales no se tradujeron en hechos. Pese a que durante los meses de enero y febrero Luis Mart\u00ednez importun\u00f3 a Carlos I con multitud de instancias y le implor\u00f3 en repetidas ocasiones que aceptase dar una respuesta p\u00fablica a la consulta interpuesta por sus representados, el emperador no despach\u00f3 por la v\u00eda del Consejo de Arag\u00f3n ninguna provisi\u00f3n relacionada con el Pleito del Obispado.<\/p>\n<p>A comienzos de marzo, el procurador se enter\u00f3 de que Carlos I iba a iniciar en breve un recorrido por las principales poblaciones de los Pa\u00edses Bajos, y comprendi\u00f3 que la resoluci\u00f3n del recurso oriolano a\u00fan se demorar\u00eda por alg\u00fan tiempo. Por ello, el d\u00eda 9 del referido mes decidi\u00f3 escribir a las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura a fin de informarles del desesperante estado del negocio. En la carta, les explic\u00f3 a sus superiores que ni el monarca ni sus consejeros hab\u00edan tratado en firme la cuesti\u00f3n episcopal ante el considerable volumen de asuntos que hab\u00edan de proveer, y ante la lentitud de los tr\u00e1mites previos a la adopci\u00f3n gubernativa de decisiones. Mart\u00ednez describ\u00eda dicha situaci\u00f3n con palabras ciertamente significativas: \u00ab<em>tienen tantas cosas que hazer y despachan tan pocas que es lastima ver los negociantes que andan por aca perdidos<\/em>\u00bb. Asimismo, les coment\u00f3 que para evitar mayores gastos, a partir del primero de abril, pasar\u00eda a cobrar 15 sueldos diarios en lugar del ducado que le hab\u00edan fijado como dieta. Y, por \u00faltimo, les comunic\u00f3 que por diversas fuentes hab\u00eda conocido que Carlos I hab\u00eda remitido la resoluci\u00f3n del conflicto a los Consejos de Castilla y de Arag\u00f3n<sup>405<\/sup>.<\/p>\n<p>A los ojos de Luis Mart\u00ednez, \u00e9sta era la situaci\u00f3n en la que se hallaba por aquellas fechas el Pleito del Obispado. Pues bien, como veremos a continuaci\u00f3n, distaba bastante de ser acertada. Todos los indicios apuntan a que durante la segunda mitad de enero, el emperador le envi\u00f3 a su esposa, por la v\u00eda del Consejo de Castilla y con sumo secreto, la respuesta a la consulta oriolana. Carlos I quer\u00eda que el breve bolo\u00f1\u00e9s fuese ejecutado, y en la citada provisi\u00f3n le indic\u00f3 a Isabel de Portugal que le ordenase al duque de Calabria que pusiese a disposici\u00f3n del cabildo de Cartagena todos los medios seculares que fuesen necesarios para la puesta en vigor del aludido rescripto apost\u00f3lico<sup>406<\/sup>.<\/p>\n<ol start=\"19\">\n<li><strong> La nueva consulta oriolana y el ejecutorial definitivo de la emperatriz Isabel.<\/strong><\/li>\n<\/ol>\n<p>Mientras Luis Mart\u00ednez recorr\u00eda las fr\u00edas tierras de Europa, en Madrid, el nuevo pavorde del Salvador, Fernando Rodr\u00edguez, se decidi\u00f3 a intervenir en el Pleito del Obispado con el fin de hallar una soluci\u00f3n pac\u00edfica a las discordias. Conocedor de los perjuicios que hab\u00eda de comportar una futura ejecuci\u00f3n del breve de Bolonia para el cap\u00edtulo de su iglesia, se ofreci\u00f3 al Consejo de Arag\u00f3n como medianero entre las partes. Al no haber en la corte de la emperatriz ning\u00fan procurador de Orihuela, los doctores del citado organismo le mandaron al s\u00edndico de la ciudad de Valencia, Luis Cifr\u00e9, que escribiese una carta al cap\u00edtulo del Salvador y a las autoridades municipales de la ciudad del Bajo Segura, pregunt\u00e1ndoles si estar\u00edan dispuestos a aceptar el arbitraje del pavorde. Cifr\u00e9 acat\u00f3 la orden de los consejeros y el 7 de enero inform\u00f3 a los mandatarios oriolanos de la posibilidad concordataria<sup>407<\/sup>.<\/p>\n<p>La oferta agrad\u00f3 a las mencionadas autoridades, de modo que el d\u00eda 26 del citado primer mes de 1531 le escribieron al procurador valenciano pidi\u00e9ndole, <em>ex una<\/em>, que le comunicase al Consejo su aprobaci\u00f3n y, <em>ex alia<\/em>, que hiciese todo lo posible para que la emperatriz le encomendase a Rodr\u00edguez de manera oficial la mediaci\u00f3n pacificadora<sup>408<\/sup>.<\/p>\n<p>Tras conocer la voluntad oriolana, Cifr\u00e9 y el pavorde volvieron a comparecer ante los doctores del citado organismo, y \u00e9stos le presentaron el proyecto a Isabel de Portugal. Sin embargo, entonces, Juan V\u00e1zquez, s\u00edndico del cabildo de Cartagena y de la ciudad de Murcia, se person\u00f3 ante el Consejo de Castilla. Aleg\u00f3 que, con anterioridad, ambas partes ya hab\u00edan tratado de solucionar el Pleito por la v\u00eda del pacto en algunas ocasiones, y que todos los intentos hab\u00edan sido vanos. Y les suplic\u00f3 a sus miembros que se opusiesen al despacho de la comisi\u00f3n, y que le rogasen a la emperatriz que proveyese la ejecuci\u00f3n del \u00faltimo breve de Clemente VII. El presidente del Consejo castellano se neg\u00f3 a aprobar el \u00ab<em>acordio<\/em>\u00bb, y el plan del pavorde se vino abajo. No obstante, Fernando Rodr\u00edguez no se dio por vencido, y decidi\u00f3 viajar a Murcia con el prop\u00f3sito de convencer al cabildo de Cartagena de que aceptase su arbitraje<sup>409<\/sup>.<\/p>\n<p>Poco tiempo despu\u00e9s de su marcha, probablemente a mediados de febrero lleg\u00f3 a la corte la provisi\u00f3n de Carlos I. De inmediato, Juan V\u00e1zquez le suplic\u00f3 a Isabel de Portugal que le remitiese el ejecutorial del breve bolo\u00f1\u00e9s al duque de Calabria, para que pudiese ser puesto en vigor definitivamente. La emperatriz atendi\u00f3 los ruegos del procurador cartaginense, despach\u00f3 el mandato y orden\u00f3 a un letrado llamado licenciado Vald\u00e9s que, tras pasar por Murcia, fuese a Valencia a present\u00e1rselo a D. Fernando de Arag\u00f3n.<\/p>\n<p>Mientras tanto, en la primera de las dos ciudades supraescritas, Rodr\u00edguez se dedic\u00f3 a importunar a los eclesi\u00e1sticos cartaginenses con persistentes ruegos. Su insistencia ofusc\u00f3 a los cl\u00e9rigos de tal manera que el 22 de febrero le advirtieron que si no persist\u00eda de sus in\u00fatiles y pesados empe\u00f1os, lo excomulgar\u00edan y no le permitir\u00edan percibir las rentas de su prebenda. Y adem\u00e1s, le prohibieron que fuese a Orihuela a unirse a las filas del cap\u00edtulo del Salvador.<\/p>\n<p>Poco despu\u00e9s de pronunciar este ultim\u00e1tum, ese mismo d\u00eda, arrib\u00f3 el licenciado Vald\u00e9s con el mandato de la emperatriz. Al enterarse de la existencia de la provisi\u00f3n, aun sin conocer su contenido exacto, el pavorde avis\u00f3 a las autoridades oriolanas para que enviasen a alg\u00fan procurador a la corte virreinal, si lo estimaban oportuno<sup>410<\/sup>.<\/p>\n<p>Los mandatarios de la ciudad del Bajo Segura no acabaron de creer que el documento de la emperatriz fuese un ejecutorial del breve clementino. Por ello, el d\u00eda siguiente -23 de febrero- le enviaron una carta de respuesta a Fernando Rodr\u00edguez recomend\u00e1ndole que no tuviese ning\u00fan temor a las moniciones que le hab\u00edan hecho los componentes del cabildo de Cartagena ya que no ten\u00edan ning\u00fan poder para hacerlas efectivas. No le comentaron nada, en cambio, sobre la orden de la emperatriz<sup>411<\/sup>.<\/p>\n<p>Sin embargo, durante los d\u00edas siguientes reflexionaron sobre esa misma cuesti\u00f3n, y trataron de convencerse a s\u00ed mismos de que no pod\u00eda tratarse de ninguna disposici\u00f3n contraria a sus reivindicaciones episcopales, dado que, seg\u00fan las \u00faltimas informaciones de que dispon\u00edan, Carlos I no s\u00f3lo no hab\u00eda pronunciado su respuesta a la consulta, sino que, al parecer, ni siquiera se hab\u00eda planteado su resoluci\u00f3n. Y el 26 de febrero le comentaron al pavorde dicha conclusi\u00f3n, le dijeron que, seg\u00fan su opini\u00f3n, los murcianos estaban tratando de difundir falsos rumores para \u00ab<em>mover los animos de la gente que de ello tienen poca noticia<\/em>\u00bb, le pidieron que les escribiese si consegu\u00eda nuevos datos acerca del controvertido instrumento real, y, finalmente, le reiteraron que no hiciese ning\u00fan caso a las advertencias del cabildo cartaginense pues \u00e9stas no pod\u00edan afectar a alguien que \u00fanicamente buscaba la paz<sup>412<\/sup>.<\/p>\n<p>Tras confirmar que el mandato de la emperatriz era un ejecutorial del breve revocatorio de la creaci\u00f3n del obispado de Orihuela, Fernando Rodr\u00edguez no tuvo en consideraci\u00f3n estas palabras de las citadas autoridades, y s\u00ed decidi\u00f3 hacer caso al ultim\u00e1tum murciano. Comprendi\u00f3 el porqu\u00e9 del tajante trato que le hab\u00edan dispensado los capitulares cartaginenses, abandon\u00f3 sus prop\u00f3sitos conciliadores y opt\u00f3 marchar a Valencia, sin entrar en Orihuela. No obstante, el d\u00eda siguiente, 27 de febrero, antes de salir de Murcia, les escribi\u00f3 a los referidos mandatarios una \u00faltima carta. En ella, les asegur\u00f3 que el contenido de la orden de Isabel era el que les hab\u00eda anunciado desde un principio, y les comunic\u00f3 que aunque no pasar\u00eda por Orihuela e ir\u00eda directamente a la ciudad del Turia, no dejar\u00eda en ning\u00fan momento de defender los intereses episcopales oriolanos ante el gobernador Maza, el duque de Calabria o la propia emperatriz.<\/p>\n<p>Aunque el pavorde lo dej\u00f3 muy claro en su misiva, el cap\u00edtulo del Salvador y los oficiales municipales no acabaron de creerse la noticia. Por ello, tras un par de d\u00edas de deliberaciones, el 2 de marzo decidieron enviar tres cartas a la corte de la emperatriz, dirigidas al s\u00edndico valenciano Luis Cifr\u00e9, al doctor Coscollar y a Juan Talayero -escribano de mandamiento del Consejo de Arag\u00f3n-. Les pidieron que investigaran tres puntos: si el emperador hab\u00eda enviado alguna respuesta a la consulta efectuada sobre la cuesti\u00f3n del Obispado; si su esposa Isabel o los Consejos de Castilla o Arag\u00f3n hab\u00edan expedido alguna provisi\u00f3n relacionada con dicha causa; y, en tercer lugar, si al licenciado Vald\u00e9s le hab\u00edan encomendado la misi\u00f3n de conseguir el auxilio del brazo secular para la ejecuci\u00f3n del breve bolo\u00f1\u00e9s. Y les demandaron su opini\u00f3n sobre la conveniencia de enviar a la corte a alg\u00fan procurador de la Iglesia y la ciudad de Orihuela<sup>413<\/sup>.<\/p>\n<p>Sin embargo, no tuvieron que esperar la respuesta de los aliados en la corte de la emperatriz para llegar a la conclusi\u00f3n de que no pod\u00edan negar por m\u00e1s tiempo la evidencia. El d\u00eda siguiente, 3 de marzo, se enteraron de que ya hac\u00eda algunos d\u00edas que hab\u00edan salido de Murcia el licenciado Vald\u00e9s y el secretario del cabildo de Cartagena, Rodrigo de M\u00e9rida, en direcci\u00f3n a Valencia. Entonces, decidieron actuar. Nombraron procurador a Vicente Mart\u00ed y le encargaron que fuese, asimismo, a la capital del Reino, y que, una vez all\u00ed, avisase a D. Pedro de Rocafull y a Lluch Joan Riudaura de las funestas intenciones de los emisarios cartaginenses, a fin de que impidiesen por todos los medios que consiguiesen una provisi\u00f3n favorable del duque de Calabria<sup>414<\/sup>.<\/p>\n<p>Sin embargo, mientras le preparaban a Mart\u00ed la procura y la documentaci\u00f3n, ese mismo d\u00eda 3, recibieron un escrito de Riudaura en el que les comunicaba que los mensajeros murcianos le hab\u00edan presentado el breve y la orden real al lugarteniente general, y que le hab\u00edan solicitado el auxilio del brazo secular para la ejecuci\u00f3n del rescripto. La nueva noticia les hizo actuar con mayor urgencia, de modo que, haciendo un alarde de organizaci\u00f3n, le entregaron a Mart\u00ed una carta de creencia para el duque; algunas letras de recomendaci\u00f3n para el vicario general Guillem Desprats, para el confesor del virrey fr. Joseu, y para los doctores Ros, Bas, Ubach, Artes, Figuerola y Filibert; y sendas cartas para Rocafull y Riudaura, en las que les ped\u00edan que convenciesen a D. Fernando de Arag\u00f3n de que no les concediese la mencionada ayuda del poder civil. Y le mandaron que partiese a toda prisa para la ciudad del Turia<sup>415<\/sup>.<\/p>\n<p>Mientras tanto, en la corte del virrey, M\u00e9rida y Vald\u00e9s no desaprovecharon la ocasi\u00f3n. Nada m\u00e1s iniciar las gestiones, se dieron cuenta de que los representantes de la ciudad del Bajo Segura ten\u00edan \u00ab<em>poca noticia de la causa<\/em>\u00bb y, comprando favores, intentaron ganar la voluntad del duque. Sin embargo, Mart\u00ed lleg\u00f3 en el momento clave. Prepar\u00f3 la oposici\u00f3n en un tiempo r\u00e9cord, gracias a la ayuda de Riudaura, Rocafull, Ros y Artes, y a la colaboraci\u00f3n del escribano de mandamiento Luis Dom\u00ednguez. Y tras varias semanas de pugna con los cartaginenses, consigui\u00f3 que el duque de Calabria aceptase aplazar la concesi\u00f3n del auxilio del brazo secular, y que permitiese la interposici\u00f3n de dos nuevas consultas ante la emperatriz Isabel y ante el propio Carlos I. La habilidad negociadora de Mart\u00ed y sus influencias cabe el virrey fueron los factores que propiciaron el \u00e9xito oriolano. De poco les sirvieron a Vald\u00e9s y a M\u00e9rida sus \u00ab<em>grans armes<\/em>\u00bb argumentales o sus espl\u00e9ndidas propinas puesto que, seg\u00fan afirmaba Vicente Mart\u00ed, \u00ab<em>Nostre Senyor es de nostra part<\/em>\u00bb. La cuesti\u00f3n episcopal volv\u00eda as\u00ed a Isabel de Portugal y a Carlos I. Y a finales de marzo, el mismo Mart\u00ed se dirigi\u00f3 a la corte de la emperatriz para presentar los nuevos recursos y defender los derechos de su patria<sup>416<\/sup>.<\/p>\n<p>Por otra parte, ya en abril, el can\u00f3nigo Luis Mart\u00ednez, que desconoc\u00eda los sucesos acontecidos a ra\u00edz de la respuesta del monarca y del mandato de la reina, aburrido por la falta de actividad, escribi\u00f3 a las autoridades oriolanas para pedirles que le permitiesen volver a Orihuela. Los <em>Electos<\/em> le explicaron que su misi\u00f3n no hab\u00eda terminado, y le recordaron que una vez quedase solucionado el tema de la consulta al emperador, a\u00fan hab\u00eda de ir a hablar con el obispo Lang, y que despu\u00e9s todav\u00eda ten\u00eda que desplazarse a Roma. Pese a su evidente cansancio, Mart\u00ednez obedeci\u00f3 las \u00f3rdenes al pie de la letra y decidi\u00f3 permanecer en Bruselas a la espera de nuevos acontecimientos<sup>417<\/sup>.<\/p>\n<p>Tras frenar la primera intentona cartaginense de conseguir el auxilio del brazo secular, durante los meses siguientes, el cap\u00edtulo del Salvador y las autoridades municipales de Orihuela, por medio de Vicente Mart\u00ed y de Luis Mart\u00ednez, intentaron hacer cambiar de opini\u00f3n tanto a Isabel como a Carlos I. No obstante, lo \u00fanico que consiguieron fue retrasar la ejecuci\u00f3n del breve de Bolonia.<\/p>\n<p>Finalmente, el emperador impuso su criterio y le mand\u00f3 a su mujer que ordenase al Consejo de Arag\u00f3n la expedici\u00f3n del ejecutorial. Isabel sigui\u00f3 los dictados de su esposo, y el documento fue despachado en \u00c1vila el 12 de agosto de ese mismo a\u00f1o 1531, con el <em>vidit<\/em> del doctor Ram.<\/p>\n<p>El ejecutorial iba dirigido a las autoridades civiles y eclesi\u00e1sticas del Reino de Valencia: el duque de Calabria y su mujer D\u00aa. Germana de Foix -lugartenientes generales-, los gobernadores <em>citra<\/em> y <em>ultra Sexonam<\/em>, los bailes generales, y los justicias y oficiales de las poblaciones de dicho Reino, por una parte; y el arzobispo de Valencia, su vicario general y sus oficiales, y el resto de cl\u00e9rigos seculares y regulares, por otra. En \u00e9l, la emperatriz les exhortaba que, bajo pena de incurrir en la indignaci\u00f3n y la ira regias y en el pago de 10.000 florines de oro de Arag\u00f3n -que ir\u00edan a parar a las arcas reales-, cuando el obispo o su provisor, y el de\u00e1n y el cabildo de Cartagena, por s\u00ed mismos o por medio de sus procuradores leg\u00edtimos, les pidiesen que diesen ejecuci\u00f3n al breve de Clemente VII, lo hiciesen efectivo tanto en la Colegiata del Salvador de Orihuela como en las iglesias de las poblaciones que fuese necesario, para que tuviese pleno cumplimiento, de modo que nadie pudiese impedir su puesta en vigor, ni molestar a los cartaginenses en la posesi\u00f3n de sus derechos, preeminencias, jurisdicciones y rentas<sup>418<\/sup>.<\/p>\n<ol start=\"20\">\n<li><strong> La revocaci\u00f3n del Obispado de Orihuela.<\/strong><\/li>\n<\/ol>\n<p>La expedici\u00f3n del ejecutorial por la reina Isabel no supuso tampoco la inmediata puesta en vigor del breve revocatorio de Bolonia. Gracias a la permisividad del duque de Calabria y, sobre todo, al apoyo del gobernador D. Pedro Maza, las autoridades oriolanas consiguieron que la ejecuci\u00f3n de los mandatos apost\u00f3licos y reales se demorase hasta el a\u00f1o siguiente, 1532.<\/p>\n<p>Ante el considerable retraso, el 28 de febrero del citado a\u00f1o 1532, la emperatriz Isabel, movida por las continuadas quejas murcianas, decidi\u00f3 despachar una nueva provisi\u00f3n confirmando el mandato del 12 de agosto de 1531, y ordenando a los lugartenientes generales del Reino de Valencia que auspiciasen la ejecuci\u00f3n inmediata de la revocaci\u00f3n del obispado de Orihuela, sin m\u00e1s consultas ni dilaciones.<\/p>\n<p>El s\u00edndico cartaginense Alfonso Pacheco -uno de los regidores de Murcia- le llev\u00f3 el mandato real a D. Fernando de Arag\u00f3n y D\u00aa. Germana de Foix. Y tras algunas suplicaciones consigui\u00f3 que los virreyes ordenasen, bajo pena de 3.000 florines, el inmediato cumplimiento del breve pontificio y del ejecutorial de la emperatriz, por medio de una orden dada en Valencia el 18 de abril<sup>419<\/sup>.<\/p>\n<p>No obstante, recordando tiempos pasados y, en especial, el intento de ejecuci\u00f3n de 1525 abortado por D. Pedro Maza, los murcianos quisieron asegurarse de que la prestaci\u00f3n oriolana de obediencia al obispo, el provisor y el cabildo de Cartagena transcurriese de un modo correcto. Por ello, el regidor Pacheco le rog\u00f3 al duque de Calabria que suspendiese a Maza de sus funciones hasta que el clero y el pueblo de la ciudad del Bajo Segura reconociesen bajo juramento la autoridad espiritual cartaginense. El lugarteniente general atendi\u00f3 la suplicaci\u00f3n murciana, y el 22 de abril decret\u00f3 la destituci\u00f3n temporal de D. Pedro Maza de Lizana y el nombramiento como gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona de D. Luis Ferrer. Adem\u00e1s, le encomend\u00f3 a Ferrer la inmediata tarea de ir a Orihuela a auxiliar a los cl\u00e9rigos cartaginenses en la ejecuci\u00f3n de los mandatos reales y apost\u00f3licos. Y para ello, le asign\u00f3 como asesor al doctor en ambos Derechos Jer\u00f3nimo Centelles -que era, a su vez, asesor del baile general del Reino-, como alguacil a Jer\u00f3nimo Ram\u00f3n, y como escribano de mandamiento, al notario Juan Guaxart. Y, por \u00faltimo, fij\u00f3 una pena de 1.000 florines de oro que ser\u00eda aplicada contra todos los que contraviniesen sus \u00f3rdenes en relaci\u00f3n con el nombramiento del nuevo gobernador temporal o con la ejecuci\u00f3n de la revocaci\u00f3n del obispado de Orihuela<sup>420<\/sup>.<\/p>\n<p>Ocho d\u00edas m\u00e1s tarde, el \u00faltimo de abril, D. Luis Ferrer, acompa\u00f1ado por su asesor, el alguacil y el notario, se person\u00f3 en la poblaci\u00f3n del Bajo Segura. Y comenz\u00f3 su delicada misi\u00f3n en el Archivo Municipal, ante un buen n\u00famero de vecinos de Orihuela, notificando a los mandatarios civiles de la ciudad su nombramiento como gobernador temporal <em>ultra Sexonam<\/em>. El justicia Garci Ferr\u00e1ndez de Tuesta y los jurados Juan Mons\u00ed de Casta\u00f1eda, Juan de Alcaraz y Juan Sans reconocieron la legitimidad de la provisi\u00f3n del virrey, le felicitaron por su promoci\u00f3n y, en relaci\u00f3n con la ejecuci\u00f3n de los mandatos apost\u00f3licos y reales, le indicaron que ten\u00edan la intenci\u00f3n de presentarle algunas protestas. Ferrer les replic\u00f3 que \u00fanicamente las admitir\u00eda en el caso de que fuesen justas, y dio por concluido el acto de presentaci\u00f3n. Y a continuaci\u00f3n, se dirigi\u00f3 a la Catedral del Salvador, donde, arrodill\u00e1ndose frente al altar mayor y colocando las manos sobre un libro misal y un crucifijo, jur\u00f3 ejercer su cargo con honor. Y tras \u00e9l, prest\u00f3 juramento su asesor<sup>421<\/sup>.<\/p>\n<p>El lunes 2 de mayo, Ferrer, que estaba hospedado en la casa de Juan de Loazes, hizo llamar al justicia, a los jurados, al s\u00edndico D. Pedro de Rocafull y a otros miembros del <em>Consell<\/em>. Y all\u00ed mismo, les present\u00f3 la provisi\u00f3n expedida por los lugartenientes generales del Reino el 18 de abril, y les orden\u00f3 que la obedeciesen y, por lo tanto, que se resignasen a aceptar la superioridad espiritual cartaginense. D. Pedro de Rocafull, en nombre de los referidos mandatarios, le respondi\u00f3 que sus representados ten\u00edan la intenci\u00f3n de acatar las voluntades real, virreinal y apost\u00f3lica con la m\u00e1s humilde reverencia. No obstante, acto seguido, le entreg\u00f3 un escrito de protesta en el que eran enumerados los diferentes factores que legitimaban la instituci\u00f3n del obispado y la erecci\u00f3n catedralicia de la iglesia del Salvador, y con el que quer\u00edan recordarle al emperador que no deb\u00eda perjudicarles mientras siguiesen pendientes de resoluci\u00f3n los apelaciones que hab\u00edan interpuesto tanto en su corte como en la Curia romana, con motivo de la expedici\u00f3n del breve de Bolonia. El gobernador le pas\u00f3 la escritura a su asesor y Centelles, argumentando que Ferrer \u00fanicamente era un mero ejecutor de \u00f3rdenes, les devolvi\u00f3 la protesta, y le aconsej\u00f3 a su superior que procediese a la inmediata ejecuci\u00f3n de los mencionados mandatos<sup>422<\/sup>.<\/p>\n<p>El d\u00eda siguiente -3 de mayo-, Vicente Mart\u00ed compareci\u00f3 ante D. Luis Ferrer y le present\u00f3 una nueva escritura de disentimiento. En ella, las autoridades oriolanas le comunicaron al gobernador que, a ra\u00edz de las Cortes de Monz\u00f3n de 1528, Carlos I le pidi\u00f3 a Clemente VII que solucionase el Pleito del Obispado por la v\u00eda judicial, que el papa cometi\u00f3 la causa al auditor de la Rota, Jacobo Simoneta, y que la lite a\u00fan se hallaba pendiente de resoluci\u00f3n. Le comentaron que mientras el litigio no fuese determinado, la iglesia del Salvador no pod\u00eda ni deb\u00eda ser privada de su condici\u00f3n catedralicia por ning\u00fan escrito pontificio. Y le pidieron directamente a Ferrer que le denegase a los cartaginenses el auxilio del brazo secular porque lo que pretend\u00edan era contrario a la justicia. Entonces, volvi\u00f3 a intervenir el asesor Centelles, y tras repetir que el gobernador no era m\u00e1s que un mero ejecutor, le devolvi\u00f3 la escritura a Mart\u00ed<sup>423<\/sup>.<\/p>\n<p>Dos d\u00edas despu\u00e9s, el 5 de mayo, D. Luis Ferrer les requiri\u00f3 a D. Pedro de Rocafull y a Vicente Mart\u00ed que les hiciesen saber a los miembros del cap\u00edtulo del Salvador que deseaba participarles las \u00f3rdenes de Su Majestad. Los s\u00edndicos le contestaron que procurar\u00edan que los cl\u00e9rigos estuviesen reunidos ese mismo d\u00eda, por la tarde. Y efectivamente, a las 15 horas, en la Catedral, el sacrist\u00e1n Luis de Soler, el chantre Jaime de Soler, el arcediano Pedro Catherino y los can\u00f3nigos Juan de Vilafranca, Pedro Mart\u00ednez, Miguel Monto, Jaime G\u00f3mez Daroca, Francisco Alcaraz, Andr\u00e9s L\u00f3pez, Luis Torres y el propio Vicente Mart\u00ed comparecieron ante el gobernador. \u00c9ste les indic\u00f3 que como todos los cap\u00edtulos de las iglesias colegiales, hab\u00edan de prestar obediencia a sus superiores, esto es, al obispo y al cabildo de Cartagena. Despu\u00e9s, les reproch\u00f3 que se negaran tan obstinadamente, por medio de las intervenciones orales o escritas de sus dos s\u00edndicos, a aceptar un hecho tan claro. Y tras comentar que no pod\u00eda dejar de cumplir las \u00f3rdenes reales, les mand\u00f3 que juraran la referida sumisi\u00f3n. Y culmin\u00f3 su intervenci\u00f3n mostr\u00e1ndoles sus credenciales, el breve de Bolonia y las provisiones reales.<\/p>\n<p>Los s\u00edndicos oriolanos recibieron los documentos con gran desagrado, pero no sin respeto, y le contestaron que no entend\u00edan por qu\u00e9 Carlos I y Clemente VII pretend\u00edan menoscabar los derechos de la Catedral del Salvador, cuando antes siempre hab\u00edan querido que permaneciesen ilesos y salvos. Y le pidieron un traslado de los referidos escritos pontificios y reales.<\/p>\n<p>Entonces, el gobernador, teniendo en consideraci\u00f3n que dichos documentos ya hab\u00edan sido le\u00eddos y que los capitulares ten\u00edan de ellos plena y expl\u00edcita noticia, les inst\u00f3 a que los obedecieran, d\u00e1ndoles de plazo para hacerlo hasta el d\u00eda siguiente a las dos de la tarde. Los s\u00edndicos le rogaron que les concediese algo m\u00e1s de tiempo para que sus representados tuviesen ocasi\u00f3n de deliberar sin tanta urgencia. Pero el gobernador se mostr\u00f3 inflexible y mantuvo su \u00faltima oferta. Y Mart\u00ed y Rocafull, perseverando en sus intenciones, le presentaron una nueva escritura de protesta, mejor fundamentada que las anteriores, en la que explicaban el proceso de la erecci\u00f3n del obispado y rese\u00f1aban un sinf\u00edn de causas que demostraban la ilegalidad de la situaci\u00f3n creada tras la aprobaci\u00f3n del breve bolo\u00f1\u00e9s y de los ejecutoriales de la reina. Y tras la lectura del disentimiento, volvieron a pedirle a Ferrer que les denegase su auxilio a los cartaginenses, que aparcara la sentencia de la cual era ejecutor, y que consultase al rey y la reina, exponi\u00e9ndoles los justificados y razonables motivos que asist\u00edan a la parte oriolana.<\/p>\n<p>No obstante, la protesta no sirvi\u00f3 para nada. Al igual que hab\u00eda hecho en anteriores ocasiones, el gobernador les devolvi\u00f3 el escrito a los procuradores. Y, acto seguido, les repiti\u00f3 que su \u00fanico cometido era proceder al cumplimiento de los mandatos de la emperatriz y de los lugartenientes generales del Reino de Valencia, y concluy\u00f3 dici\u00e9ndoles que no deseaba que el asunto se prolongara por m\u00e1s tiempo.<\/p>\n<p>Posteriormente, ese mismo 5 de mayo, Ferrer le mand\u00f3 personalmente al justicia que el d\u00eda siguiente, a las 8 horas, reuniese el <em>Consell<\/em> para que pudiese comunicarles las \u00f3rdenes reales a sus componentes. Y Garci Ferr\u00e1ndez de Tuesta le mostr\u00f3 al gobernador su intenci\u00f3n de facilitarle las cosas contest\u00e1ndole que procurar\u00eda con todas sus fuerzas que la citada asamblea municipal estuviese reunida seg\u00fan hab\u00eda dispuesto<sup>424<\/sup>.<\/p>\n<p>Y efectivamente, el viernes 6 de mayo, a las 8 de la ma\u00f1ana, en la Sala del <em>Consell<\/em>, comparecieron ante D. Luis Ferrer, el referido justicia, los jurados Juan Mons\u00ed de Casta\u00f1eda, Francisco Monyor, Juan de Alcaraz y Juan Sans, y 21 <em>consellers<\/em>. Iniciada la sesi\u00f3n, el gobernador tom\u00f3 la palabra y se dirigi\u00f3 a la concurrencia para recordar que algunos d\u00edas atr\u00e1s, el 2 de mayo, el justicia y los jurados de la ciudad le manifestaron su disposici\u00f3n a obedecer los mandatos reales y apost\u00f3licos, como leales s\u00fabditos de la Corona de Arag\u00f3n y cristianos fieles a la Santa Madre Iglesia. Y en atenci\u00f3n a tales palabras, les pidi\u00f3 a los asistentes que cumpliesen con su oferta, sin ponerse de parte de la clerec\u00eda oriolana ni obstaculizar su misi\u00f3n con nuevas protestas y dilaciones. La respuesta municipal no pudo agradarle m\u00e1s al gobernador: el justicia, los jurados y los <em>consellers<\/em> ratificaron su anunciada predisposici\u00f3n a obtemperar los dictados del emperador y del pont\u00edfice, y se comprometieron a asistirle cumplidamente en lo que le fuese necesario<sup>425<\/sup>.<\/p>\n<p>Poco despu\u00e9s, los s\u00edndicos del cap\u00edtulo del Salvador, Rocafull y Mart\u00ed, se personaron ante Ferrer, y por escrito le comunicaron que, habiendo sido entregados los trasuntos del breve pontificio y del ejecutorial real esa misma ma\u00f1ana, y requiriendo tan ardua causa muchas ponderaciones, sus representados se ve\u00edan incapaces de responder o de alegar cosa alguna en defensa de sus derechos a las dos de la tarde, m\u00e1xime cuando no hab\u00eda disponible ning\u00fan abogado que les pudiese aconsejar ya que Francisco Alavanya y Jaime Terr\u00e9s eran los asesores del cesado gobernador Maza, y Mart\u00edn Ruiz de Mendoza era el abogado fiscal, y por sus oficios respectivos no pod\u00edan defenderles, y no conoc\u00edan a m\u00e1s doctores en Derecho que viviesen en la gobernaci\u00f3n <em>ultra Sexonam<\/em> y que no fuesen fieles a la obediencia de Cartagena. Y como consideraban imprescindible para la protecci\u00f3n de sus intereses que dichos traslados fueran examinados por letrados, le solicitaron al gobernador una ampliaci\u00f3n del plazo para dar la respuesta, advirti\u00e9ndole que en el caso de que les fuese negada, apelar\u00edan al emperador y al papa.<\/p>\n<p>Ferrer, importunado por la nueva solicitud y el retraso que conllevaba, volvi\u00f3 a responder que no era m\u00e1s que un mero ejecutor de las \u00f3rdenes reales, y que no estaba facultado para conocer la causa ni para consultar al rey. Acto seguido, incidi\u00f3 en que la confecci\u00f3n y entrega de los trasuntos citados ya hab\u00eda constituido una iniciativa propia y gratuita, y que se sal\u00eda de sus facultades. A continuaci\u00f3n, les deneg\u00f3 la demanda y se\u00f1al\u00f3 que no retrasar\u00eda por m\u00e1s tiempo la ejecuci\u00f3n de ambos escritos. Y, finalmente, tras devolverles la escritura para que ellos mismos la remitiesen a Su Majestad o a quien quisiesen, les comunic\u00f3 que si persist\u00edan en su voluntad de negarse a aceptar la superioridad espiritual de los cartaginenses, estar\u00edan desobedeciendo al emperador y sufrir\u00edan los temibles efectos de su indignaci\u00f3n e ira regias<sup>426<\/sup>.<\/p>\n<p>Mart\u00ed y Rocafull volvieron a la iglesia del Salvador y les dieron cuenta a los capitulares de la posici\u00f3n del gobernador. Los cl\u00e9rigos analizaron la situaci\u00f3n y, pese a las amenazas proferidas por Ferrer, decidieron aguardar hasta el d\u00eda siguiente para responder a sus lesivos requerimientos. De esa manera, cuando el mero ejecutor se present\u00f3 en la Catedral a las dos del mediod\u00eda no hall\u00f3 a nadie en sus silenciosas naves.<\/p>\n<p>El 7 de mayo, los mensajeros murcianos le indicaron al gobernador que el provisor del obispado y los representantes del cabildo de Cartagena llegar\u00edan a Orihuela en tres d\u00edas. Por ello, Ferrer moder\u00f3 un \u00e1pice su actitud, y cuando los miembros del cap\u00edtulo del Salvador comparecieron ante \u00e9l, se limit\u00f3 a presentarles una carta del duque de Calabria en la que les instaba a obedecer los mandatos reales y apost\u00f3licos, y a anunciarles que el martes 10, antes del mediod\u00eda, el provisor y vicario general Sancho V\u00e9lez, acompa\u00f1ado por otras personas eclesi\u00e1sticas de Murcia, se presentar\u00edan en la iglesia del Salvador para recibir el juramento de obediencia<sup>427<\/sup>.<\/p>\n<p>Durante los dos d\u00edas siguientes, 8 y 9 de mayo, el gobernador se encarg\u00f3 de asegurarse del apoyo de las autoridades seculares, y volvi\u00f3 a reunirse con el justicia, los jurados y el <em>Consell<\/em>. \u00c9stos le ratificaron su apoyo<sup>428<\/sup>.<\/p>\n<p>El d\u00eda 10, de buena ma\u00f1ana, el cap\u00edtulo del Salvador intent\u00f3 por \u00faltima vez lograr que D. Luis Ferrer desistiese de su prop\u00f3sito de prestarle su auxilio a los cartaginenses. El notario Gaspar Juan Rovira, en nombre de la referida instituci\u00f3n colegial, le present\u00f3 un escrito en el que los can\u00f3nigos arg\u00fc\u00edan que, seg\u00fan las Sagradas Escrituras, el hecho de que un juez laico ayudase a un juez eclesi\u00e1stico iba en contra no s\u00f3lo del derecho natural, sino tambi\u00e9n del derecho divino. Y explicaban que la situaci\u00f3n que estaban viviendo a\u00fan era m\u00e1s ileg\u00edtima porque el breve que los cartaginenses pretend\u00edan poner en ejecuci\u00f3n con la asistencia del brazo secular hab\u00eda sido obtenido de Clemente VII faltando a la verdad y sin pleno conocimiento del asunto por parte del sumo pont\u00edfice<sup>429<\/sup>.<\/p>\n<p>De poco sirvi\u00f3 la protesta pues, de inmediato, el gobernador, acompa\u00f1ado por su asesor Centelles y por el notario Guaxart, march\u00f3 al monasterio franciscano de Santa Ana, que estaba situado fuera de los muros de la ciudad, al \u00ab<em>notable espay de dos tirs de ballesta, poch mes o menys<\/em>\u00bb. All\u00ed, se encontr\u00f3 con la expedici\u00f3n murciana, que estaba integrada por el licenciado Sancho V\u00e9lez, a la cabeza, y por eclesi\u00e1sticos tan destacados como fr. Juan Amela -ministro del monasterio de la Trinidad y subejecutor apost\u00f3lico-, el tesorero Pedro de Medina, el maestrescuela Antonio Tamar\u00f3n, el arcediano Mart\u00edn de Selva, y los dos procuradores del obispo y el cabildo de Cartagena, el racionero Lorenzo Caravaca y el beneficiado Francisco Delgado. Y les coment\u00f3 que estaba dispuesto a auxiliarles para que pudiesen poner en ejecuci\u00f3n el breve de Clemente VII. Tambi\u00e9n les manifest\u00f3 que cre\u00eda que las autoridades civiles de Orihuela, pese a estar disconformes con el perjuicio que iban a sufrir, les apoyar\u00edan en tan dificultosa empresa por no desobedecer y contrariar al emperador.<\/p>\n<p>Lejos de alegrarse por la rectitud del gobernador, el provisor V\u00e9lez, sumamente receloso, le contest\u00f3 que si no le daba fe escrita de su oferta auxiliatoria, tanto \u00e9l como el resto de los cl\u00e9rigos cartaginenses se volver\u00edan a Murcia e informar\u00edan de su negligencia al emperador. Ferrer le repiti\u00f3 que lo que a \u00e9l realmente le conven\u00eda era prestarles ayuda, y le orden\u00f3 al notario Guaxart que hiciese un auto p\u00fablico de su respuesta y se lo entregase al citado vicario general<sup>430<\/sup>.<\/p>\n<p>A\u00fan entonces, empero, los murcianos mostraron alg\u00fan temor, de modo que \u00fanicamente el subejecutor Amela, el tesorero Medina y los dos procuradores se atrevieron a entrar en la ciudad, y lo hicieron cabalgando junto al gobernador, su asesor y otros ministros y asociados.<\/p>\n<p>Una vez llegaron a la iglesia del Salvador, entraron en la capilla mayor, donde les estaban esperando Pedro Masquefa -lugarteniente del baile general de Orihuela-, Luis Togores -lugarteniente del gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona-, micer Ruiz, Juan Guasch \u00ab<em>alias lo capita<\/em>\u00bb, y muchas otras insignes personas. Tras ellos, ingresaron el justicia, su lugarteniente, los jurados, y un buen n\u00famero vecinos de la ciudad, hasta que se llen\u00f3 el aforo del citado recinto.<\/p>\n<p>Entonces, Caravaca y Delgado le mostraron a D. Luis Ferrer el breve de Clemente VII, el proceso fulminado por fr. Pedro Porcel contra los desobedientes de la autoridad apost\u00f3lica, los ejecutoriales reales de la emperatriz Isabel y, por \u00faltimo, la comisi\u00f3n auxiliatoria que el duque de Calabria le hab\u00eda despachado al propio gobernador. Y a continuaci\u00f3n le pidieron que ordenase la inmediata ejecuci\u00f3n de los mandatos pontificios y reales, instando al cap\u00edtulo del Salvador y a los oficiales municipales a prestar el juramento de obediencia al obispo y el cabildo de Cartagena, en nombre del clero y el pueblo de Orihuela.<\/p>\n<p>Antes de que Ferrer pudiese pronunciar una sola palabra, intervino el s\u00edndico Gaspar Juan Rovira. Trat\u00f3 de entorpecer la puesta en vigor de los rescriptos demand\u00e1ndole al gobernador que le ordenase a alg\u00fan notario que le proporcionase una copia de todos los documentos que los procuradores cartaginenses acababan de presentar. Tambi\u00e9n le solicit\u00f3 que le concediese a sus representados un tiempo prudencial para poder alegar contra dichos instrumentos lo que fuere m\u00e1s conveniente a sus intereses.<\/p>\n<p>Ni que decir tiene que Ferrer, aconsejado por Centelles, contest\u00f3 secamente que no entend\u00eda tal reacci\u00f3n; le dijo no le quer\u00eda dar ni copia ni tiempo, y que, adem\u00e1s, no lo pod\u00eda hacer, siendo como era un mero ejecutor de las \u00f3rdenes reales. Y zanj\u00f3 la cuesti\u00f3n indic\u00e1ndole que si quer\u00eda apelar, que enviase la petici\u00f3n al rey o a quien le pareciese oportuno.<\/p>\n<p>Apel\u00f3 despu\u00e9s Rovira a Su Santidad sobre la invalidez del breve. Y obtuvo la misma respuesta del gobernador.<\/p>\n<p>Luego, coment\u00f3 el procurador oriolano que estaban pendientes de sentencia en la Curia romana diferentes apelaciones que sus representados hab\u00edan interpuesto a ra\u00edz de la expedici\u00f3n del rescripto en Bolonia, y como consecuencia del proceso fulminado por el juez ejecutor Porcel. Y le pidi\u00f3 a Ferrer que aplazase la ejecuci\u00f3n del decreto apost\u00f3lico hasta que fuesen resueltos los aludidos recursos. El gobernador sigui\u00f3 haciendo o\u00eddos sordos a los requerimientos de Rovira.<\/p>\n<p>Sin embargo, un \u00faltimo obst\u00e1culo, m\u00e1s bien inesperado, colm\u00f3 su paciencia. El justicia y los jurados de la ciudad se opusieron a prestar el juramento de obediencia en nombre de la universidad de vecinos de Orihuela, aduciendo que el tenor del breve no les obligaba a ello. No obstante, el gobernador los amenaz\u00f3 con la inmediata aplicaci\u00f3n de las penas contenidas en el rescripto apost\u00f3lico y en los ejecutoriales reales, y no pudieron negarse a participar en el acto<sup>431<\/sup>.<\/p>\n<p>Allanado el anfractuoso terreno de la voluntad oriolana, el ministro Amela y el alguacil Jer\u00f3nimo Ram\u00f3n emprendieron el m\u00e1s sencillo camino hacia el monasterio de Santa Ana. Una vez all\u00ed, les comentaron al provisor V\u00e9lez y a los dem\u00e1s cl\u00e9rigos cartaginenses que todo estaba preparado para la prestaci\u00f3n de obediencia, y retornaron con ellos a la iglesia del Salvador, que estaba a punto de volver degradada a la categor\u00eda colegial.<\/p>\n<p>Tras personarse en la capilla mayor, D. Luis Ferrer les orden\u00f3 a las autoridades seglares de la poblaci\u00f3n que juraran sumisi\u00f3n al provisor -en nombre del obispo- y al cabildo de Cartagena. Entonces, solemnemente, el justicia Garci Ferr\u00e1ndez de Tuesta, y los jurados Juan Mons\u00ed de Casta\u00f1eda, Pedro Molins, Juan Sans, Francisco Juan Mu\u00f1oz y Juan de Alcaraz contestaron que estaban dispuestos a prestar la referida obediencia en su propio nombre y en el de todo el pueblo de la ciudad del Bajo Segura, por no ser desobedientes a Su Majestad, y para no incurrir en ninguna de las penas se\u00f1aladas en los diferentes documentos apost\u00f3licos y reales. Y tras hacer manifiesta su oposici\u00f3n al acto que iban a perpetrar en contra de sus propios intereses y derechos, prestaron el juramento de obediencia ante Sancho V\u00e9lez<sup>432<\/sup>.<\/p>\n<p>A continuaci\u00f3n, el gobernador le pregunt\u00f3 a los eclesi\u00e1sticos cartaginenses si estaban satisfechos con el reconocimiento de su superioridad espiritual. Le contestaron afirmativamente. Despu\u00e9s, se dirigi\u00f3 a los s\u00edndicos Caravaca y Delgado, y les pregunt\u00f3 si necesitaban de su auxilio en cualquier otra cosa. Le respondieron que tambi\u00e9n hab\u00edan de prestar juramento ante el provisor los miembros del cap\u00edtulo del Salvador, y le dijeron que no se hallaban en la capilla.<\/p>\n<p>Entonces, Ferrer orden\u00f3 que los buscaran por la Colegiata pero, dado el reducido tama\u00f1o del recinto sagrado -era una iglesia \u00ab<em>chica<\/em>\u00bb-, los asistentes se dieron cuenta casi de inmediato de que ninguno de los capitulares se encontraba all\u00ed. Ante tan extra\u00f1a y curiosa situaci\u00f3n, el gobernador le mand\u00f3 a su alguacil Jer\u00f3nimo Ram\u00f3n que fuese a buscarlos a sus respectivas casas, y que les ordenase de su parte que en el plazo m\u00e1ximo de una hora se presentasen en la Colegiata para prestar el juramento de obediencia a la iglesia y obispado de Cartagena, en nombre del clero de Orihuela.<\/p>\n<p>Nada m\u00e1s recibir las instrucciones de su superior, el alguacil sali\u00f3 de la iglesia del Salvador e inici\u00f3 su recorrido. No obstante, \u00ab<em>apres de notable spay<\/em>\u00bb de b\u00fasqueda infructuosa, retorn\u00f3 a la colegial y le comunic\u00f3 al gobernador que aunque no hab\u00eda encontrado a ninguno de los can\u00f3nigos, les hab\u00eda le\u00eddo el mandato de comparecencia a las personas que hab\u00eda hallado en sus respectivos domicilios particulares.<\/p>\n<p>Ofuscado, el gobernador le orden\u00f3 a Ram\u00f3n que buscara a los capitulares por toda la ciudad. El alguacil volvi\u00f3 a salir de la iglesia y dio una batida por las calles m\u00e1s rec\u00f3nditas de la poblaci\u00f3n. No obstante, sus esfuerzos fueron in\u00fatiles. No hall\u00f3 a ninguno de los can\u00f3nigos. Y tras patrullar durante una media hora, Ram\u00f3n volvi\u00f3 a presentarse ante su superior sin haber conseguido resultado positivo alguno<sup>433<\/sup>.<\/p>\n<p>Ante el vergonzante cariz de la situaci\u00f3n, el provisor V\u00e9lez le solicit\u00f3 a Ferrer que declarase contumaces a los capitulares. El gobernador admiti\u00f3 la petici\u00f3n, y despu\u00e9s les coment\u00f3 a los cartaginenses que, en nombre del emperador, estaba a su entera disposici\u00f3n para llevar a cabo una exhaustiva b\u00fasqueda de los huidos. Y a continuaci\u00f3n, les pidi\u00f3 ayuda al justicia y a los jurados de Orihuela. \u00c9stos le contestaron diligentemente que obedecer\u00edan cualquier mandato suyo.<\/p>\n<p>Entonces, como las campanas del Salvador ya hac\u00eda un buen rato que hab\u00edan tocado la una del mediod\u00eda, y los murcianos se quer\u00edan ir a comer, por medio del procurador Delgado le requirieron a Ferrer que le mandase al s\u00edndico oriolano Rovira que le dijese a sus representados -si es que conoc\u00eda su paradero- que hab\u00edan de comparecer en dicha iglesia a las tres de la tarde. El gobernador convirti\u00f3 en orden dicha petici\u00f3n, y Rovira le contest\u00f3 que \u00ab<em>treballaria en fer-los venir<\/em>\u00bb. Despu\u00e9s, Ferrer les pregunt\u00f3 a los murcianos si deseaban algo m\u00e1s. Le respondieron que no, y, acto seguido, se levantaron, salieron del referido recinto sagrado, y volvieron al monasterio de Santa Ana<sup>434<\/sup>.<\/p>\n<p>El gobernador comi\u00f3 intranquilo en la casa de Juan de Loazes. Hacia las dos y media decidi\u00f3 enviar a su portero, Juan de Mallent, a la iglesia del Salvador para ver si se hab\u00edan presentado los can\u00f3nigos. Mallent no hall\u00f3 a nadie en la Catedral y se volvi\u00f3 a la posada de su superior, a la que lleg\u00f3 pasadas las tres.<\/p>\n<p>Al conocer que los capitulares segu\u00edan sin aparecer, D. Luis Ferrer cabalg\u00f3 hasta Santa Ana, acompa\u00f1ado por Centelles, Guaxart y otros ministros. Una vez all\u00ed, les inform\u00f3 a los murcianos de la nueva incomparecencia de los can\u00f3nigos, les pregunt\u00f3 si deseaban volver a la iglesia mayor para hacer alg\u00fan acto m\u00e1s, y les comunic\u00f3 que tanto \u00e9l como los oficiales municipales estaban dispuestos a auxiliarles. Los cartaginenses le contestaron que en breve iban a partir para Murcia, y volvieron a solicitarle que declarase contumaces a los ausentes miembros del cap\u00edtulo del Salvador. El gobernador no puso ning\u00fan inconveniente y admiti\u00f3 la acusaci\u00f3n. Acto seguido, le requirieron que decretase el secuestro de todos los frutos y rentas del citado organismo colegiado hasta que sus componentes jurasen la obediencia. Ferrer acept\u00f3 la petici\u00f3n y formaliz\u00f3 el correspondiente edicto de incautaci\u00f3n. Y despu\u00e9s, se despidi\u00f3 de los eclesi\u00e1sticos murcianos y, con su s\u00e9quito y los s\u00edndicos Delgado y Caravaca, volvi\u00f3 a entrar en Orihuela.<\/p>\n<p>Descabalg\u00f3 en la casa de Juan de Loazes, y desde all\u00ed anduvo hasta la iglesia del Salvador. Al entrar en ella, comprob\u00f3 que los can\u00f3nigos segu\u00edan sin aparecer. Y estando entre el coro y la capilla mayor, Delgado le dirigi\u00f3 la palabra para pedirle de nuevo que reconociese la contumacia. El gobernador admiti\u00f3 la acusaci\u00f3n y le mand\u00f3 a Jer\u00f3nimo Ram\u00f3n que reiniciase la b\u00fasqueda de los fugados. A media tarde, pasadas las seis, el alguacil retorn\u00f3 al Salvador, y le comunic\u00f3 a su superior que no s\u00f3lo no hab\u00eda hallado a ninguno de los huidos, sino que ni siquiera hab\u00eda podido conseguir informaci\u00f3n sobre su paradero.<\/p>\n<p>Pese a las dificultades, Ferrer no desisti\u00f3 de su intenci\u00f3n de encontrar a los capitulares. De hecho, el d\u00eda siguiente -11 de mayo- le encomend\u00f3 la b\u00fasqueda a Juan de Mallent, pero \u00e9ste tampoco logr\u00f3 localizar a ninguno de los can\u00f3nigos. Y finalmente, D. Luis Ferrer opt\u00f3 por volver a Valencia e informar de la rebeld\u00eda oriolana al duque de Calabria<sup>435<\/sup>.<\/p>\n<p>El cabildo de Cartagena y las autoridades civiles de Murcia tambi\u00e9n enviaron a la ciudad del Turia a dos procuradores, el maestro en Sagrada Teolog\u00eda Juan de Arrieta y el ya conocido Pedro Sambrana, con la misi\u00f3n de que le presentasen al lugarteniente general del Reino sus quejas sobre la desobediencia del cap\u00edtulo del Salvador a los mandatos apost\u00f3licos, reales y virreinales, y sobre la blandura y negligencia de D. Luis Ferrer.<\/p>\n<p>La intervenci\u00f3n de Arrieta y Sambrana, la relaci\u00f3n del gobernador temporal, y la consciencia de que Carlos I deseaba que se procediese de una vez a la revocaci\u00f3n del obispado de Orihuela fueron los tres factores que movieron fundamentalmente a D. Fernando de Arag\u00f3n a expedir una nueva comisi\u00f3n ejecutora en favor de D. Luis \u00c7ayd\u00eda, alguacil real del Reino de Valencia, el 4 de junio de ese mismo a\u00f1o 1532<sup>436<\/sup>.<\/p>\n<p>En esta ocasi\u00f3n, el duque quiso asegurarse de que el breve de Bolonia fuese inexcusablemente puesto en pleno vigor. Por ello, en el instrumento le orden\u00f3 a \u00c7ayd\u00eda que marchase a Orihuela, acompa\u00f1ado por el notario real y apost\u00f3lico Galcer\u00e1n P\u00e9rez y por todos los ministros que considerase necesarios, y que presentase en la iglesia del Salvador la provisi\u00f3n real del 28 de febrero de modo que a los capitulares no les quedase la menor duda de que la \u00fanica e inconmutable voluntad del emperador radicaba en el hecho de que, en nombre del clero de la ciudad, prestasen al obispo -en este caso, el provisor- y el cabildo de Cartagena el pertinente juramento de obediencia, seg\u00fan hab\u00eda dispuesto Clemente VII.<\/p>\n<p>Adem\u00e1s, en la comisi\u00f3n, D. Fernando previ\u00f3 con detalle cualquier contrariedad que pudiese afectar a la ejecuci\u00f3n inmediata de los mandatos apost\u00f3licos y reales. Por ejemplo, en el caso de que los s\u00edndicos del cap\u00edtulo del Salvador tratasen de demorar el reconocimiento de la supremac\u00eda espiritual cartaginense mediante la interposici\u00f3n de alegaciones y protestas, le indic\u00f3 al alguacil que le ordenase a cualquier notario de la ciudad que recibiese tales autos, sin preocuparse por admitirlos o denegarlos.<\/p>\n<p>Asimismo, advirti\u00f3 que impondr\u00eda severas penas a cuantos se opusiesen a la labor del \u00c7ayd\u00eda. En este sentido, le concedi\u00f3 al alguacil poder suficiente para proceder a la detenci\u00f3n de todas las personas que le obstaculizasen en su cometido, independientemente de su rango o condici\u00f3n. Y, paralelamente, amenaz\u00f3 con multar con 1.000 florines de oro al gobernador Maza, a su lugarteniente Togores, al justicia, a los jurados, a los <em>consellers<\/em> y, en general, a todos los vecinos de Orihuela, en el caso de que osasen estorbar la ejecuci\u00f3n de los mandatos reales y pontificios, se atreviesen a desobedecer a \u00c7ayd\u00eda, o le negasen su ayuda. Y con asignar una m\u00e1s onerosa sanci\u00f3n de 3.000 florines a todos cuantos molestasen o no tratasen con cortes\u00eda a los murcianos que hubiesen de asistir a la prestaci\u00f3n del juramento de obediencia<sup>437<\/sup>.<\/p>\n<p>La comisi\u00f3n conclu\u00eda se\u00f1alando que el dinero que hab\u00edan de percibir en concepto de dietas D. Luis \u00c7ayd\u00eda, Galcer\u00e1n P\u00e9rez y los dem\u00e1s ministros, habr\u00eda de salir de los bienes y frutos confiscados al cap\u00edtulo del Salvador.<\/p>\n<p>Por fin, el 15 de junio, \u00c7ayd\u00eda se person\u00f3 en la iglesia del Salvador, acompa\u00f1ado por el notario Galcer\u00e1n P\u00e9rez y sus ayudantes; por uno de los jueces ejecutores designados en el breve bolo\u00f1\u00e9s, el comendador del monasterio de la Merced de Murcia, fr. Alonso de San Vicente; por el provisor del obispado, Sancho V\u00e9lez, en representaci\u00f3n del obispo Mateo; y por el tesorero Pedro de Medina y el arcediano Mart\u00edn de Selva, como delegados del cabildo de Cartagena. Los recibieron en el coro el sacrist\u00e1n y protonotario apost\u00f3lico Luis de Soler, el chantre Jaime de Soler, el arcediano Pedro Catherino, los can\u00f3nigos Pedro Mart\u00ednez, Miguel Monto, Juan de Vilafranca, Jaime G\u00f3mez Daroca, Andr\u00e9s L\u00f3pez, Francisco Alcaraz y Vicente Mart\u00ed, y los domeros Gin\u00e9s Ferr\u00e1ndez, Jaime Colmelles, Pedro de la Mata y Gin\u00e9s Zaplana.<\/p>\n<p>\u00c7ayd\u00eda comenz\u00f3 su intervenci\u00f3n pidi\u00e9ndole a Galcer\u00e1n P\u00e9rez que procediese a la lectura de la comisi\u00f3n del 4 de junio. El notario hizo lo que el alguacil le demand\u00f3 y, a continuaci\u00f3n, le pas\u00f3 el escrito a Vicente Mart\u00ed, s\u00edndico del cap\u00edtulo, para que reconociese su autenticidad. Mart\u00ed comprob\u00f3 que el documento estaba en regla<sup>438<\/sup>. Y, acto seguido, le present\u00f3 a \u00c7ayd\u00eda un extenso escrito.<\/p>\n<p>En \u00e9l, los capitulares se quejaban de que D. Luis Ferrer le hab\u00eda relatado al duque de Calabria una versi\u00f3n distorsionada de los acontecimientos ocurridos durante su estancia en Orihuela, y de que dicha equ\u00edvoca y parcial relaci\u00f3n hab\u00eda movido el \u00e1nimo del lugarteniente general contra ellos y le hab\u00eda hecho expedir una provisi\u00f3n tan severa. Despu\u00e9s, trataron de explicarle a \u00c7ayd\u00eda que su incomparecencia ante Ferrer ten\u00eda una doble justificaci\u00f3n legal. <em>Ex una<\/em>, le comentaron que el gobernador no pod\u00eda forzarles a prestar el juramento de obediencia al obispo y el cabildo de Cartagena mientras estuviesen pendientes de resoluci\u00f3n diversas apelaciones que hab\u00edan interpuesto en la Curia romana sobre la ilegitimidad de la revocaci\u00f3n del obispado de Orihuela. Y, <em>ex alia<\/em>, le argumentaron que Ferrer no les hab\u00eda dado tiempo suficiente para preparar las alegaciones que ten\u00edan derecho a presentar antes de la ejecuci\u00f3n del rescripto de Clemente VII. Y por ambos motivos le comunicaron a \u00c7ayd\u00eda que de ninguna manera pod\u00edan ser considerados desobedientes de los mandatos reales y apost\u00f3licos, que era absolutamente il\u00edcito el secuestro de sus rentas y bienes, y que no pod\u00edan permitir la ejecuci\u00f3n del breve revocatorio porque les supon\u00eda un evidente perjuicio a sus derechos<sup>439<\/sup>.<\/p>\n<p>Siguiendo las instrucciones de D. Fernando de Arag\u00f3n, el comisario \u00c7ayd\u00eda le contest\u00f3 a Mart\u00ed que no era m\u00e1s que un mero ejecutor de \u00f3rdenes superiores, e hizo caso omiso a la protesta. Y acto seguido, se puso a disposici\u00f3n del ejecutor apost\u00f3lico, fr. Alonso de San Vicente. \u00c9ste, sin m\u00e1s pre\u00e1mbulos, le pidi\u00f3 que les ordenase a los componentes del cap\u00edtulo del Salvador que, en nombre del clero de Orihuela, le prestasen el juramento de obediencia al representante del obispo, el provisor V\u00e9lez. El alguacil atendi\u00f3 la solicitud del mercedario, y la convirti\u00f3 en una orden de cumplimiento ineludible e inmediato<sup>440<\/sup>.<\/p>\n<p>Sin embargo, Vicente Mart\u00ed volvi\u00f3 a intervenir para alegar de palabra que sus representados no pod\u00edan ser obligados a jurar obediencia al obispo y el cabildo de Cartagena porque ya lo hicieron en 1521, forzados por el marqu\u00e9s de los V\u00e9lez, y porque sobre dicha actuaci\u00f3n hab\u00edan interpuesto una apelaci\u00f3n en la Santa Sede, que estaba a\u00fan pendiente de resoluci\u00f3n. Mart\u00ed adujo que el cap\u00edtulo del Salvador no aceptar\u00eda someterse a los dictados espirituales cartaginenses hasta que dicho recurso fuese determinado. Y despu\u00e9s le entreg\u00f3 a \u00c7ayd\u00eda un nuevo instrumento de protesta, en el que los capitulares argumentaban que concurr\u00edan diferentes circunstancias para que no fuesen puestos en ejecuci\u00f3n ni el breve de Clemente VII ni los ejecutoriales de la emperatriz Isabel: las apelaciones indecisas contra el citado rescripto y contra el proceso del ejecutor Porcel, y el parecer de los doctores del Consejo de Arag\u00f3n de que no deb\u00eda tomarse ninguna medida que pudiese afectar al Pleito del Obispado hasta que el pont\u00edfice y su consistorio cardenalicio resolviesen los aludidos recursos<sup>441<\/sup>.<\/p>\n<p>El alguacil le repiti\u00f3 al s\u00edndico que no estaba facultado ni para admitir ni para denegar sus protestas, e insisti\u00f3 en que su \u00fanica misi\u00f3n era lograr que el cap\u00edtulo reconociese su obediencia al provisor episcopal<sup>442<\/sup>.<\/p>\n<p>Pese a tan claras palabras, Mart\u00ed quiso agotar sus posibilidades y le present\u00f3 al comisario dos nuevas escrituras:<\/p>\n<p>-Una petici\u00f3n de sobreseimiento de la ejecuci\u00f3n del breve a fr. Alonso de San Vicente, fundamentada en el car\u00e1cter subrepticio y perjudicial del rescripto -por su obtenci\u00f3n gracias a enga\u00f1os y favores-, y en las funestas consecuencias que su puesta en vigor iba, sin duda, a desatar -esto es, el resurgimiento de las discordias y los enfrentamientos entre los habitantes de Orihuela y Murcia-<sup>443<\/sup>.<\/p>\n<p>-Y una apelaci\u00f3n para la Santa Sede contra la parcialidad manifiesta de los jueces ejecutores designados por el breve de Bolonia, quienes, seg\u00fan afirmaban los capitulares del Salvador, siempre hab\u00edan actuado siguiendo las directrices del cabildo cartaginense<sup>444<\/sup>.<\/p>\n<p>Y tras presentar ambos instrumentos, Mart\u00ed culmin\u00f3 su intervenci\u00f3n anunciando el prop\u00f3sito de sus representados de apelar contra todos los actos que pretendiesen hacer tanto fr. Alonso de San Vicente como fr. Francisco de M\u00e1laga -ministro del monasterio de la Sant\u00edsima Trinidad de Murcia-, en virtud de su designaci\u00f3n como jueces ejecutores apost\u00f3licos, mientras estuviese pendiente de sentencia la aludida apelaci\u00f3n en la Curia romana.<\/p>\n<p>Las amenazas y acusaciones oriolanas no arredraron a fr. Alonso de San Vicente, sino que, muy al contrario, el mercedario incit\u00f3 a \u00c7ayd\u00eda a que cumpliese de una vez con su real misi\u00f3n y obligase al cap\u00edtulo del Salvador a prestar la susodicha obediencia. Adem\u00e1s, le pidi\u00f3 que en el caso de que alguno o algunos de sus miembros, o todos ellos, se negasen a aceptar la autoridad cartaginense, procediese rigurosamente a su detenci\u00f3n y encarcelamiento.<\/p>\n<p>El firme parlamento de San Vicente acab\u00f3 de azuzar al alguacil, quien orden\u00f3 a los capitulares que, sin m\u00e1s demoras ni dilaciones, hiciesen el juramento<sup>445<\/sup>.<\/p>\n<p>Y viendo perdida la situaci\u00f3n, Vicente Mart\u00ed le present\u00f3 dos \u00faltimos escritos. Uno en el que sus representados manifestaban que se avendr\u00edan a realizar finalmente la salva a fin de que nadie pudiese acusarlos de desobedecer los mandatos de sus soberanos temporal y espiritual, pese a no aprobarla en absoluto y a sentir gravemente menospreciados sus m\u00e1s fundamentales derechos. Y otro de contenido muy similar, en el que afirmaban que \u00fanicamente acced\u00edan a las pretensiones cartaginenses para no incurrir en las penas fijadas por los citados rescriptos reales y pontificios<sup>446<\/sup>.<\/p>\n<p>Y a continuaci\u00f3n, ese mismo d\u00eda 15 de junio de 1532, ante el notario Galcer\u00e1n P\u00e9rez, el cap\u00edtulo del Salvador prest\u00f3 el siguiente juramento de obediencia ante el provisor Sancho V\u00e9lez<sup>447<\/sup>:<\/p>\n<p>\u00ab<em>Nosaltres, Don Luys de Soler, prothonotari appostholich e sacrista de la Seu de Oriola, Don Jaume Soler, chantre, Mossen Pere Catherino, Artraca, Mossen Pere Martinez, Canonge, Mossen Miquel Monto, Canonge, Mossen Joan de Vilafranca, Canonge, Mossen Jaume Gomez, Canonge, Mossen Francesch Alcaraz, Canonge, Mossen Vicent Marti, Canonge, Mossen Gines Ferrandez, Mossen Pere de la Mata, Mossen Jaume Colmelles, Mossen Gines Saplana, preveres domers de la dita Seu de Oriola, capitularment convocats e congregatis cum sono campanae et more solito in similibus convocari et cogregari, in choro principali dictae ecclesiae propter comoditatem loci asserentes esse totum Capitulum ac Clerum dicte Ecclesiae, obtemperants als manaments del magnifich mossen Luis \u00c7aydia, alguazil de la Cessarea e Real Magestat, per virtut de la comissio per ell a nosaltres presentada, instant e requirent lo reverent frare Alonso de Sant Vicent, comanador del monestir de Nostra Senyora de la Mer\u00e7e, extramuros de la Ciutat de Murcia construhit, subexecutor de les dites Butles appostholiques, e en presencia e asisten\u00e7ia del reverent licenciat Sancho Velez, Canonge e provisor del bisbat y esglesia de Carthagena, e de Don Marti de Selva, arcediano de la dita esglesia de Cartagena, e de Don Pedro de Medina, tresorer, e procuradors de la dita esglesia de Carthagena, precehint los protests e escriptures per part del dit Capitol e Clero de la dita Ciutat de Oriola possades, e en res no apartantse de aquells dits protests, juren en ma e poder del notari deius escrit, tenint comissio del dit reverent provissor per a rebre dit jurament antem Senyor Deu e als Sancts Evangelis de aquells, de les sues mans dretes particularment e corporalment tocats, prestar axi com de present presten la obediencia al Reverendissimo bisbe y esglesia de Cartagena, y prometten en virtut del dit jurament de obehir sos manaments, y de aquells james se apartaran ni menys faran cosa alguna contra lo dit bisbat y esglesia de Carthagena juxta forma de les dites Butles apostoliques y executorials Reals, e a\u00e7o sots pena de perjurs e de altres penes e censures contengudes en les dites Butles appostoliques e altres manaments de Sa Majestat, e per \u00e7o se obliguen en ma e poder del dit provissor, representant lo dit bisbat e esglesia de Carthagena, de tenir per ferma e agradable la dita obediencia, ab les protestacions e escriptures per aquells fetes e possades, e contra aquella dita obediencia no vendran ni venir faran sots les penes dessus dites per les quals obliguen tots los bens del dit Clero e Capitol, mobles e inmobles, hauts e per aver, hon se vol que sien o seran, lo qual acte en la forma desus dita fonch rebut per mi dit notari de manament del dit Magnifich alguazil e comissari, lo qual estava e perseverava en no admettre ni repellir les dites protestacions, lo dit dia de quinze de juny, any de la Nativitat de Nostre Senyor Deu Jesu Christ Mil cinch cents trenta y dos. Se<\/em>(signo)<em>nyals de nosaltres, Don Luys Soler, Mossen Jaume Soler, Mossen Pere Catherino, Mossen Pere Martinez, Mossen Miquel Monto, Mossen Joan Vilafranca, Mossen Jaume Gomez, Mossen Andreu Lopez, Mossen Francesch Alcaraz, Mossen Vicent Marti, Mossen Gines Ferrandez, Mossen Pere de la Mata, Mossen Jaume Colmelles e Mossen Gines \u00c7aplana, sobredits, e lo dit Capitol e Clero de la dita Seu de Oriola representants que, ab les protestacions e escriptures per part del dit Capitol e Clero possades, loen e approven la dita obediencia<\/em>\u00bb.<\/p>\n<p>A partir de este preciso momento, la creaci\u00f3n del obispado de Orihuela decretada por Julio II pas\u00f3 a la Historia. Oficialmente, la iglesia del Salvador volvi\u00f3 a ser Colegiata, y su cap\u00edtulo qued\u00f3 de nuevo subordinado a las \u00f3rdenes del provisor del obispado de Cartagena.<\/p>\n<p>Sin embargo, ni los capitulares ni las autoridades civiles de la ciudad del Bajo Segura desistieron de sus prop\u00f3sitos. Y como veremos a continuaci\u00f3n, de inmediato prosiguieron la lucha.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>NOTAS<\/strong><\/p>\n<p>1GARC\u00cdA C\u00c1RCEL, R.: <em>Las German\u00edas de Valencia&#8230;<\/em>, p. 125.<\/p>\n<p>2CHIARRI MART\u00cdN, M.L., <em>op. cit.<\/em>, p. 95.<\/p>\n<p>3<em>Ibidem<\/em>, pp. 105-106.<\/p>\n<p>4<em>Ibidem<\/em>, pp. 112-113.<\/p>\n<p>5CAPPELLI, A., <em>op. cit.<\/em>, p. 274.<\/p>\n<p>6<em>Ibidem<\/em>. Adriano VI fue sucedido por Julio de M\u00e9dicis, que fue electo el 15 de noviembre y fue consagrado con el nombre de Clemente VII ocho d\u00edas despu\u00e9s.<\/p>\n<p>7El p\u00e9simo estado de conservaci\u00f3n del libro n\u00ba 42, <em>Contestador<\/em> de 1522, del A.M.O. no nos ha permitido extraer m\u00e1s informaci\u00f3n sobre este a\u00f1o.<\/p>\n<p>8A.M.O. Libro n\u00ba 43, <em>Contestador<\/em> de 1523, ff. 9-10, 13-14.<\/p>\n<p>9A.C.O. Armario I, libro n\u00ba 1, ff. 81v.-82, y libro n\u00ba 2, ff. 20-22v. Armario IX, Legajo XX, parte 1\u00aa, documento n\u00ba 16. Y armario X, libro n\u00ba 1094, ff. 82-84v. Tambi\u00e9n en A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, ff. 25-26.<\/p>\n<p>10A.M.O. Libro n\u00ba 43, <em>Contestador<\/em> de 1523, f. 40.<\/p>\n<p>11<em>Ibidem<\/em>, ff. 27-27v.<\/p>\n<p>12<em>Ibidem<\/em>, f. 93.<\/p>\n<p>13<em>Ibidem<\/em>, ff. 70-70v.<\/p>\n<p>14<em>Ibidem<\/em>, ff. 79, 88.<\/p>\n<p>15<em>Ibidem<\/em>, f. 427.<\/p>\n<p>16<em>Ibidem<\/em>, f. 385.<\/p>\n<p>17A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 15-18v.<\/p>\n<p>18A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 23-65.<\/p>\n<p>19<em>Ibidem<\/em>, ff. 66v., 69-69v., 121.<\/p>\n<p>20A.C.O. Armario I, libro n\u00ba 1, ff. 205-205v. Armario IX, Legajo XX, documento n\u00ba 20. Y armario X, libro n\u00ba 1094, ff. 12-13v.<\/p>\n<p>21A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 84-84v., 118-119, 164A, 183v. Los embajadores oriolanos fueron, entre otros, Vicente Mart\u00ed, Ger\u00f3nimo Rosell, Andr\u00e9s Soler, Juan Mart\u00ed y los doctores Mart\u00edn Ruiz de Mendoza y Luch Joan Riudaura.<\/p>\n<p>22A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 321-322.<\/p>\n<p>23<em>Ibidem<\/em>, ff. 390-390v.<\/p>\n<p>24<em>Ibidem<\/em>, ff. 392-392v.<\/p>\n<p>25<em>Ibidem<\/em>, f. 391.<\/p>\n<p>26<em>Ibidem<\/em>, ff. 395-396.<\/p>\n<p>27<em>Ibidem<\/em>, ff. 406-408v.<\/p>\n<p>28<em>Ibidem<\/em>, f. 417.<\/p>\n<p>29A.C.O. Armario X, libro n\u00ba 1096, ff. 79-86v.<\/p>\n<p>30A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 460-462. Hecha la distribuci\u00f3n, el cap\u00edtulo del Salvador ten\u00eda que contribuir con la \u00ab<em>ter\u00e7a part<\/em>\u00bb de los gastos de la embajada.<\/p>\n<p>31A.C.O. Armario I, libro n\u00ba 1, ff. 206-207v.<\/p>\n<p>32A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 466-467.<\/p>\n<p>33<em>Ibidem<\/em>, ff. 488-490.<\/p>\n<p>34A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, f. 475.<\/p>\n<p>35<em>Ibidem<\/em>, f. 478.<\/p>\n<p>36A.C.O. Armario X, libro n\u00ba 1096, ff. 86v.-99v.<\/p>\n<p>37A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 487-487v.<\/p>\n<p>38<em>Ibidem<\/em>, ff. 502-502v.<\/p>\n<p>39Estas complet\u00edsimas instrucciones se hallan en <em>ibidem<\/em>, ff. 488-490, 494.<\/p>\n<p>40<em>Ibidem<\/em>, f. 491.<\/p>\n<p>41Las instrucciones pueden localizarse en <em>ibidem<\/em>, ff. 492-493v., 505.<\/p>\n<p>42<em>Ibidem<\/em>, ff. 496-503v.<\/p>\n<p>43<em>Ibidem<\/em>, f. 504.<\/p>\n<p>44A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 475-476.<\/p>\n<p>45A.M.O. Libro n\u00ba 44, <em>Contestador<\/em> de 1524, ff. 513-514.<\/p>\n<p>46A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, ff. 52-52v.<\/p>\n<p>47<em>Ibidem<\/em>.<\/p>\n<p>48A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 108-110.<\/p>\n<p>49<em>Ibidem<\/em>, ff. 72-72v.<\/p>\n<p>50<em>Ibidem<\/em>, f. 81v.<\/p>\n<p>51<em>Ibidem<\/em>, ff. 126-126v., 130.<\/p>\n<p>52A.C.O. Armario I, libro n\u00ba 1, ff. 216v.-219v. Y armario X, libro n\u00ba 1094, ff. 24-27v.; y libro n\u00ba 1095, ff. 118-122v. Y tambi\u00e9n en el A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, ff. 83-86v. El clero oriolano estuvo representado por algunos cl\u00e9rigos de las tres iglesias de la ciudad: la Colegiata del Salvador, y las parroquiales de Santiago y de las Santas Justa y Rufina. Por la del Salvador, asistieron el sacrist\u00e1n Luis de Soler, el chantre y vicario general Jaime de Soler, los can\u00f3nigos Pedro Mart\u00ednez, Miguel Monto, Jaime G\u00f3mez Daroca, Juan de Vilafranca y Andr\u00e9s Soler; los hebdomadarios Pedro de la Mata, Gin\u00e9s Ferr\u00e1ndez, Jaime Colmelles y Gin\u00e9s Zaplana; y los presb\u00edteros Fernando Garc\u00eda, Pedro L\u00f3pez, Gin\u00e9s Crietes, Jaime Despuig, Juan Ruiz, Luis Viudes, Juan Gallego, Juan Grau, Sebasti\u00e1n Pedr\u00f3s, Jaime Ferriol y el sacrist\u00e1n mayor Pedro Santander. Por la parroquial de las Santas Justa y Rufina, los curas Bartolom\u00e9 Manresa y Gin\u00e9s Villena. Y por la de Santiago, los cl\u00e9rigos Juan Ferrer y Mart\u00edn S\u00e1nchez. Y el pueblo de la ciudad del Bajo Segura estuvo representado por el justicia Pedro Morrelles y por los jurados Jer\u00f3nimo Rossell, Pedro Silvestre Claramunt y Pedro Sanz.<\/p>\n<p>53A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, ff. 53-55.<\/p>\n<p>54A.C.O. Armario I, libro n\u00ba 1, f. 90. A.M.O. Libro n\u00ba 56, <em>Contestador<\/em> de 1538, ff. 88, 93, 97, 103.<\/p>\n<p>55A.C.O. Armario I, libro n\u00ba 1, ff. 90-90v. A.M.O. Libro n\u00ba 56, <em>Contestador<\/em> de 1538, ff. 89, 94, 100.<\/p>\n<p>56A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 123-125, ff. 133-134.<\/p>\n<p>57<em>Ibidem<\/em>, f. 135.<\/p>\n<p>58<em>Ibidem<\/em>, ff. 136-137v., ff. 138-140.<\/p>\n<p>59<em>Ibidem<\/em>, ff. 140v.-141v.<\/p>\n<p>60<em>Ibidem<\/em>, f. 142.<\/p>\n<p>61<em>Ibidem<\/em>, ff. 144-144v.<\/p>\n<p>62<em>Ibidem<\/em>, ff. 145-146v.<\/p>\n<p>63<em>Ibidem<\/em>, ff. 149-150.<\/p>\n<p>64<em>Ibidem<\/em>, f. 95.<\/p>\n<p>65<em>Ibidem<\/em>, f. 147.<\/p>\n<p>66<em>Ibidem<\/em>, f. 147v.<\/p>\n<p>67<em>Ibidem<\/em>, ff. 148, 151-151v., 161-161v.<\/p>\n<p>68<em>Ibidem<\/em>, f. 152.<\/p>\n<p>69<em>Ibidem<\/em>, f. 153.<\/p>\n<p>70A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, ff. 97v-102v.<\/p>\n<p>71A.M.O. Libro n\u00ba 2208, <em>Libro de procedimientos. 1434-1525<\/em>, ff. 196-196v.<\/p>\n<p>72A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, ff. 56-56v.<\/p>\n<p>73A.C.O. Armario I, libro n\u00ba 1, ff. 219v.-222. Y armario X, libro n\u00ba 1095, ff. 112-115. Los cl\u00e9rigos estuvieron representados por el sacrist\u00e1n Luis de Soler, el chantre y vicario general Jaime de Soler, los can\u00f3nigos Pedro Mart\u00ednez, Miguel Monto, Jaime G\u00f3mez Daroca, Juan de Vilafranca y Andr\u00e9s Soler, el di\u00e1cono Bartolom\u00e9 Dur\u00e1, el subdi\u00e1cono Francisco Alc\u00e1zar, y los hebdomadarios Pedro de la Mata, Gin\u00e9s Ferr\u00e1ndez, Jaime Colmelles y Gin\u00e9s Zaplana. Y las autoridades municipales por el justicia Pedro Morrelles y los jurados Jer\u00f3nimo Rossell, Pedro Silvestre Claramunt y Pedro Sanz.<\/p>\n<p>74A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 232-233v.<\/p>\n<p>75Hemos localizado dos copias de dicho expediente. Una en el A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, ff. 88-169. Y otra en el A.C.O. Armario X, libro n\u00ba 1094, ff. 133-222.<\/p>\n<p>76A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 190-191.<\/p>\n<p>77<em>Ibidem<\/em>, ff. 253, 260-260v.<\/p>\n<p>78<em>Ibidem<\/em>, f. 234.<\/p>\n<p>79<em>Ibidem<\/em>, f. 236.<\/p>\n<p>80<em>Ibidem<\/em>, ff. 270, 271.<\/p>\n<p>81<em>Ibidem<\/em>, ff. 272, 273.<\/p>\n<p>82<em>Ibidem<\/em>, ff. 262-263.<\/p>\n<p>83<em>Ibidem<\/em>, ff. 274-276v., 291-292v.<\/p>\n<p>84<em>Ibidem<\/em>, ff. 301-302, 303-304.<\/p>\n<p>85<em>Ibidem<\/em>, ff. 286-290v., 293-293v., 306-308v.<\/p>\n<p>86<em>Ibidem<\/em>, f. 318.<\/p>\n<p>87<em>Ibidem<\/em>, ff. 383-384.<\/p>\n<p>88<em>Ibidem<\/em>, f. 373v.<\/p>\n<p>89<em>Ibidem<\/em>, f. 377.<\/p>\n<p>90<em>Ibidem<\/em>, ff. 379-379v., 381-382v.<\/p>\n<p>91GARC\u00cdA C\u00c1RCEL, R.: <em>Cortes del reinado de Carlos I&#8230;<\/em>, p. VIII.<\/p>\n<p>92A.C.O. Armario X, libro n\u00ba 1094, ff. 54-56v.<\/p>\n<p>93El breve original se halla en el A.C.O. Armario IX, Legajo III, siglo XVI, pergamino n\u00ba 80. Tambi\u00e9n hemos hallado dos copias en el mismo A.C.O. Armario X, libro n\u00ba 1094, ff. 259-260v.; y libro n\u00ba 1096, ff. 99v.-101v.<\/p>\n<p>94Hemos localizado algunos traslados de la provisi\u00f3n en el A.C.O. Armario I, libro n\u00ba 1, ff. 258-258v. Y armario X, libro n\u00ba 1094, ff. 61-62, y libro n\u00ba 1096, ff. 123-124. Tambi\u00e9n hay una copia de la real c\u00e9dula en el A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, ff. 7-7v.<\/p>\n<p>95A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 475-476. Teniendo en cuenta el decidido apoyo de Carlos I a los murcianos-castellanos, Luis Mart\u00ednez ejerci\u00f3 su labor de embajador de Orihuela con \u00e9xito. En el mes de marzo, logr\u00f3 que el rey escribiese a sus embajadores cabe la Santa Sede y al propio Clemente VII, solicitando que el Pleito del Obispado tuviese una resoluci\u00f3n judicial. Y consigui\u00f3, asimismo, que el monarca ordenase a los murcianos que no volviesen a provocar inundaciones en el t\u00e9rmino de Orihuela. El 19 de mayo consigui\u00f3 que Carlos I reinstaurase el privilegio del regimiento de la ciudad, \u00ab<em>no haviendo causas legitimas y razonables que lo impidan<\/em>\u00bb (A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 387). Y a lo largo del transcurso de su embajada tuvo que mediar para que el conflicto con la Inquisici\u00f3n no se agravase, ni perjudicase al Pleito del Obispado.<\/p>\n<p>96A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 441-441v. Los mandatarios oriolanos le entregaron en efectivo 40 ducados de oro. Y le proporcionaron nueve letras de cambio valoradas en 1.000 ducados, y otras tres \u00ab<em>cedules de canbi<\/em>\u00bb por valor de 100 ducados, para cubrir los gastos que se derivaran de la embajada.<\/p>\n<p>97A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, f. 25.<\/p>\n<p>98La diligencia y la eficacia mostradas por el s\u00edndico nos inducen a pensar que muy bien pudo tratarse de Vicente Mart\u00ed o de Perot P\u00e9rez.<\/p>\n<p>99Hemos hallado copias de dicha c\u00e9dula en el A.C.O. Armario I, libro n\u00ba 1, ff. 264v.-265; y libro n\u00ba 2, ff. 3-3v. En el Armario X, libro n\u00ba 1094, ff. 69v.-70. Y tambi\u00e9n en el A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, f. 13.<\/p>\n<p>100A.C.O. Armario I, libro n\u00ba 1, ff. 259v.-260v. Y armario X, libro n\u00ba 1094, ff. 64-65v. En representaci\u00f3n del cabildo cartaginense, firmaron la procura el arcediano Mart\u00edn de Selva, el chantre Pedro Hurtado, el tesorero Pedro de Medina, y los can\u00f3nigos Juan Soriano, Gin\u00e9s de Mergelina, Juan de Orozco, Alonso de Sandoval y Juan de Arrieta.<\/p>\n<p>101A.C.O. Armario I, libro n\u00ba 1, ff. 259, 261.<\/p>\n<p>102Seg\u00fan sindicato firmado el d\u00eda anterior -4 de octubre de 1525-. <em>Ibidem<\/em>, ff. 262-262v.<\/p>\n<p>103<em>Ibidem<\/em>, f. 261v. El ejecutorial real iba en contra de los privilegios de la ciudad y, en general, del Reino de Valencia, porque atentaba contra el archicitado privilegio dado por Alfonso el <em>Magn\u00e1nimo<\/em> el 11 de septiembre de 1437, y que Carlos I hab\u00eda jurado respetar el 30 de noviembre de 1522.<\/p>\n<p>104<em>Ibidem<\/em>, f. 262v.<\/p>\n<p>105<em>Ibidem<\/em>, f. 263.<\/p>\n<p>106<em>Ibidem<\/em>, ff. 263-263v.<\/p>\n<p>107<em>Ibidem<\/em>, f. 263v.<\/p>\n<p>108<em>Ibidem<\/em>, ff. 263v.-264.<\/p>\n<p>109<em>Ibidem<\/em>, f. 264.<\/p>\n<p>110<em>Ibidem<\/em>, ff. 265-265v.<\/p>\n<p>111<em>Ibidem<\/em>, ff. 265v.-269v.<\/p>\n<p>112Este argumento era err\u00f3neo, puesto que los pont\u00edfices pod\u00edan reservarse las causas que quisiesen y determinarlas seg\u00fan su voluntad siempre que mediasen motivos de consideraci\u00f3n, como una suplicaci\u00f3n real o el deseo de promover la paz entre los fieles.<\/p>\n<p>113Los oriolanos sol\u00edan ser maltratados, vejados y robados por los propios guardas y \u00ab<em>desmeros<\/em>\u00bb de la ciudad de Murcia. \u00c9stos no ten\u00edan ning\u00fan miramiento, y su falta de respeto llegaba hasta tal extremo que a algunas de las mujeres que iban a la citada ciudad para tratar causas matrimoniales, les robaron la ropa, y tambi\u00e9n \u00ab<em>les manilles d&#8217;or que porten en los bra\u00e7os<\/em>\u00bb. Adem\u00e1s, en los juzgados los oriolanos no pod\u00edan hablar en valenciano, porque los notarios no les comprend\u00edan. Y durante el viaje de ida o de vuelta, sus vidas corr\u00edan un gran peligro ante la posibilidad de sufrir ataques de ladrones de caminos, de moros, o de los propios murcianos.<\/p>\n<p>114A.C.O. Armario I, libro n\u00ba 1, f. 270.<\/p>\n<p>115<em>Ibidem<\/em>, f. 270v.<\/p>\n<p>116<em>Ibidem<\/em>, ff. 271v.-272v.<\/p>\n<p>117<em>Ibidem<\/em>, ff. 273v.-274.<\/p>\n<p>118Recordemos que en la provisi\u00f3n del 23 de septiembre, el emperador le hab\u00eda ordenado que ayudase a los procuradores murcianos a presentar los escritos apost\u00f3licos a los oriolanos, y que, tras ello, si las alegaciones interpuestas por \u00e9stos le convenc\u00edan, remitiese a la corte real a ambas partes sin permitir la ejecuci\u00f3n de dichos breves.<\/p>\n<p>119A.C.O. Armario I, libro n\u00ba 1, ff. 274v.-275v.<\/p>\n<p>120<em>Ibidem<\/em>, ff. 275v.-276.<\/p>\n<p>121A.C.O. Armario I, libro n\u00ba 1, f. 277v. Y armario X, libro n\u00ba 1094, f. 235.<\/p>\n<p>122A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 471-472. Hemos de aclarar que las autoridades municipales se encargaban de procurar el abastecimiento de carne para la ciudad.<\/p>\n<p>123<em>Ibidem<\/em>, ff. 475-476.<\/p>\n<p>124A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, f. 25.<\/p>\n<p>125A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, f. 475v.<\/p>\n<p>126<em>Ibidem<\/em>, ff. 478-479v., 485-486. Ese mismo d\u00eda, el <em>Consell<\/em> confirm\u00f3 la composici\u00f3n de la comisi\u00f3n de los <em>Electos<\/em>. \u00c9sta qued\u00f3 conformada por el justicia, D. Ram\u00f3n de Rocafull, Jaime Masquefa, Perot P\u00e9rez y Vicente Mart\u00ed. Y al mismo tiempo, les renov\u00f3 el poder que ten\u00edan para nombrar procuradores que pudiesen comparecer ante cualquier juez, del tipo que fuere, y para redactar instrucciones, cartas y otros instrumentos necesarios para la prosecuci\u00f3n del Pleito del Obispado.<\/p>\n<p>127A.C.O. Armario I, libro n\u00ba 1, ff. 250-251v. Y armario X, libro n\u00ba 1094, ff. 33-35, 36-37v.; y libro n\u00ba 1095, ff. 29-31, 46-49v., 50-51v.<\/p>\n<p>128A.C.O. Armario I, libro n\u00ba 1, ff. 210-211v. Y armario X, libro n\u00ba 1094, ff. 20-22v.; y libro n\u00ba 1095, ff. 25-27v., 39-41v.<\/p>\n<p>129A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 482, 483.<\/p>\n<p>130A.C.O. Armario X, libro n\u00ba 1094, f. 232v.<\/p>\n<p>131A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, f. 512.<\/p>\n<p>132A.C.O. Armario I, libro n\u00ba 1, ff. 210-211v. Y armario X, libro n\u00ba 1094, ff. 20-22v.; y libro n\u00ba 1095, ff. 25-27v., 39-41v.<\/p>\n<p>133A.C.O. Armario I, libro n\u00ba 1, ff. 212-214. Y armario X, libro n\u00ba 1094, ff. 16-18v.; y libro n\u00ba 1095, ff. 1-3v., 19-21.<\/p>\n<p>134Curiosa comparaci\u00f3n entre cartaginenses y cartagineses.<\/p>\n<p>135A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 488-491.<\/p>\n<p>136A.C.O. Armario I, libro n\u00ba 1, ff. 212-214. Y armario X, libro n\u00ba 1094, ff. 16-18v.; y libro n\u00ba 1095, ff. 1-3v., 19-21.<\/p>\n<p>137A.C.O. Armario I, libro n\u00ba 1, ff. 252-253v. Y armario X, libro n\u00ba 1094, ff. 38-39v.; y libro n\u00ba 1095, ff. 32-33v.<\/p>\n<p>138A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 491v.-493.<\/p>\n<p>139El malec\u00f3n estaba situado sobre la ciudad de Murcia, y su ruptura no s\u00f3lo hubiese evitado que llegasen las avenidas a los campos oriolanos, sino que habr\u00eda supuesto la destrucci\u00f3n de la ciudad de Murcia.<\/p>\n<p>140A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 512-513v.<\/p>\n<p>141<em>Ibidem<\/em>, f. 476.<\/p>\n<p>142A.C.O. Armario I, libro n\u00ba 1, ff. 214-216. Y armario X, libro n\u00ba 1095, ff. 23-24v.<\/p>\n<p>143A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 493v.-494v. Y tambi\u00e9n en el libro n\u00ba 46, <em>Contestador<\/em> de 1527, ff. 251-251v.<\/p>\n<p>144A.M.O. Libro n\u00ba 45, <em>Contestador<\/em> de 1525, ff. 497, 498.<\/p>\n<p>145A.C.O. Armario I, libro n\u00ba 1, ff. 90v.-91; y libro n\u00ba 2, f. 177v. Y tambi\u00e9n en el A.M.O. Libro n\u00ba 56, <em>Contestador<\/em> de 1538, ff. 90, 95, 96.<\/p>\n<p>146No parece, empero, que Carlos I adoptase ninguna medida definitiva al respecto de esta cuesti\u00f3n ya que una de las suplicaciones que la ciudad de Orihuela le present\u00f3 al emperador en las Cortes Generales de Monz\u00f3n de 1528 fue que ordenase el cierre del \u00ab<em>riacho<\/em>\u00bb o cauce artificial del Segura. A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 175-176v.<\/p>\n<p>147A.C.O. Armario I, libro n\u00ba 1, ff. 222-224v. A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 7-8.<\/p>\n<p>148A.M.O. Libro n\u00ba 46, <em>Contestador<\/em> de 1527, f. 114. Y Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 33-33v., 34v.<\/p>\n<p>149A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 110, 182-182v. En estos dos documentos, el cardenal Salviatis es considerado -un tanto curiosamente- protector de la ciudad de Orihuela.<\/p>\n<p>150Hemos podido localizar dos copias de este rescripto, y en ambas falta la dataci\u00f3n. A.C.O. Armario I, libro n\u00ba 2, ff. 170-176. Y armario X, libro n\u00ba 1094, ff. 262-265v.<\/p>\n<p>151Hay referencias a este proyecto de concierto en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 10-12v.<\/p>\n<p>152Desconocemos m\u00e1s detalles sobre la labor de G\u00f3mez, aunque si hacemos caso a la informaci\u00f3n que nos aporta A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 90v.-91, \u00e9sta debi\u00f3 ser casi inexistente.<\/p>\n<p>153Todos estos incidentes son relatados en A.M.O. Libro n\u00ba 46, <em>Contestador<\/em> de 1527, ff. 36-38v., 44-45.<\/p>\n<p>154<em>Ibidem<\/em>, ff. 38-38v., 44-45.<\/p>\n<p>155<em>Ibidem<\/em>, ff. 49-50.<\/p>\n<p>156<em>Ibidem<\/em>, ff. 37-37v.<\/p>\n<p>157<em>Ibidem<\/em>, f. 39.<\/p>\n<p>158<em>Ibidem<\/em>, ff. 38-38v.<\/p>\n<p>159<em>Ibidem<\/em>, ff. 44-45.<\/p>\n<p>160<em>Ibidem<\/em>, ff. 36-36v., 40-43. Adem\u00e1s de la cuesti\u00f3n del Beato Mart\u00ed, Arnal ten\u00eda que encargarse de hacer diferentes gestiones relacionadas con la composici\u00f3n de los populares, el regimiento de la ciudad, o con cuestiones de protocolo. Y Mart\u00ednez ten\u00eda que proseguir las negociaciones ante los Consejos.<\/p>\n<p>161A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 40. Luis Mart\u00ednez parti\u00f3 de la ciudad del Bajo Segura el 16 de enero.<\/p>\n<p>162A.M.O. Libro n\u00ba 46, <em>Contestador<\/em> de 1527, ff. 49-50.<\/p>\n<p>163<em>Ibidem<\/em>, ff. 54-56, 57-58.<\/p>\n<p>164<em>Ibidem<\/em>, ff. 51-52v.<\/p>\n<p>165<em>Ibidem<\/em>, ff. 100, 100v., 102-103v., 105, 106-107v.<\/p>\n<p>166<em>Ibidem<\/em>, f. 110.<\/p>\n<p>167<em>Ibidem<\/em>, f. 115.<\/p>\n<p>168A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 1.<\/p>\n<p>169<em>Ibidem<\/em>, f. 2.<\/p>\n<p>170<em>Ibidem<\/em>, f. 3.<\/p>\n<p>171<em>Ibidem<\/em>, ff. 4-4v.<\/p>\n<p>172<em>Ibidem<\/em>, ff. 4v.-5.<\/p>\n<p>173<em>Ibidem<\/em>, ff. 6-6v.<\/p>\n<p>174Precisamente, porque no hemos hallado ninguna apelaci\u00f3n interpuesta contra las actividades de Sancho V\u00e9lez, ni ninguna noticia sobre la imposici\u00f3n por \u00e9ste de censuras contra los rebeldes.<\/p>\n<p>175Hemos hallado dos copias de dicha apelaci\u00f3n. En A.C.O. Armario I, libro n\u00ba 1, ff. 222-224v. Y en A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 7-8.<\/p>\n<p>176A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 10-12v.<\/p>\n<p>177<em>Ibidem<\/em>.<\/p>\n<p>178<em>Ibidem<\/em>, f. 9.<\/p>\n<p>179<em>Ibidem<\/em>, ff. 14-19.<\/p>\n<p>180En A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 27-28v., las autoridades oriolanas afirmaban que el doctor Ros prepar\u00f3 dos argumentaciones. Sin embargo, \u00fanicamente hemos podido encontrar una de ellas. Est\u00e1 en el A.C.O. Armario X, libro n\u00ba 1094. ff. 270-276v.<\/p>\n<p>181Los dos memoriales se hallan en el A.C.O. Armario I, libro n\u00ba 2, ff. 258v.-270, y ff. 270v.-307.<\/p>\n<p>182A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 21, 25. Y libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 20-20v.<\/p>\n<p>183<em>Ibidem<\/em>, ff. 21, 90v.-91.<\/p>\n<p>184A.M.O. Libro n\u00ba 46, <em>Contestador<\/em> de 1527, f. 192.<\/p>\n<p>185<em>Ibidem<\/em>, f. 193.<\/p>\n<p>186A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 27-28v.<\/p>\n<p>187A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 26.<\/p>\n<p>188<em>Ibidem<\/em>, ff. 22-25.<\/p>\n<p>189<em>Ibidem<\/em>, ff. 27-28v.<\/p>\n<p>190<em>Ibidem<\/em>, f. 26v.<\/p>\n<p>191<em>Ibidem<\/em>, f. 30.<\/p>\n<p>192<em>Ibidem<\/em>, f. 40.<\/p>\n<p>193A.M.O. Libro n\u00ba 46, <em>Contestador<\/em> de 1527, f. 366.<\/p>\n<p>194A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 31-32.<\/p>\n<p>195<em>Ibidem<\/em>, ff. 33-33v., 34v. El acuerdo con Soriano, a efectos del pago anual, comenzaba a tener vigor el 15 de noviembre de 1527, y establec\u00eda que el s\u00edndico habr\u00eda de cobrar sus 50 ducados en dos pagas: la primera a lo largo del citado mes de noviembre, y la segunda el d\u00eda de San Juan.<\/p>\n<p>196<em>Ibidem<\/em>, f. 34v.<\/p>\n<p>197A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 20-20v.<\/p>\n<p>198La biograf\u00eda m\u00e1s destacada sobre este insigne andaluz es la que escribi\u00f3 KENISTON, H.: <em>Francisco de los Cobos, Secretary of the Emperor Charles V<\/em>, Pittsburg, 1960.<\/p>\n<p>199A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 39.<\/p>\n<p>200<em>Ibidem<\/em>, f. 39v.<\/p>\n<p>201A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 47v. Y libro n\u00ba 48, Contestador de 1528, ff. 129-132, 186-188v.<\/p>\n<p>202A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 45. Y libro n\u00ba 48, <em>Contestador<\/em> de 1528, f. 183.<\/p>\n<p>203A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 47. Y libro n\u00ba 48, <em>Contestador<\/em> de 1528, f. 184.<\/p>\n<p>204A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 45-45v.<\/p>\n<p>205<em>Ibidem<\/em>, ff. 45v.-46, 48v., 50-50v.<\/p>\n<p>206<em>Ibidem<\/em>, ff. 45v., 48, 49-49v.<\/p>\n<p>207A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 51-51v.<\/p>\n<p>208A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 151, 152.<\/p>\n<p>209<em>Ibidem<\/em>, ff. 148-148v.<\/p>\n<p>210<em>Ibidem<\/em>, ff. 146-146v., 154-154v.<\/p>\n<p>211<em>Ibidem<\/em>, ff. 156-156v.<\/p>\n<p>212<em>Ibidem<\/em>, ff. 168-169v., 170-173v., 175-176v. El <em>Consell<\/em> le dio a Perot P\u00e9rez poder suficiente para prestar el juramento de fidelidad, asistir a las Cortes, votar la habilitaci\u00f3n del virrey y poner agravios relacionados con el Pleito del Obispado, la inhibici\u00f3n de sacar trigo de Orihuela, la escriban\u00eda del <em>Consell<\/em> y las inundaciones provocadas por los murcianos.<\/p>\n<p>213<em>Ibidem<\/em>, f. 174.<\/p>\n<p>214<em>Ibidem<\/em>, f. 174v.<\/p>\n<p>215<em>Ibidem<\/em>, f. 182.<\/p>\n<p>216<em>Ibidem<\/em>, ff. 177-181v.<\/p>\n<p>217<em>Ibidem<\/em>, ff. 292-293v.<\/p>\n<p>218GARC\u00cdA C\u00c1RCEL, R.: <em>Cortes del reinado de Carlos I&#8230;<\/em>, p. VIII.<\/p>\n<p>219A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 65-65v. Y libro n\u00ba 48, <em>Contestador<\/em> de 1528, f. 246.<\/p>\n<p>220A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 68-69v.<\/p>\n<p>221<em>Ibidem<\/em>.<\/p>\n<p>222A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 66-69v.<\/p>\n<p>223<em>Ibidem<\/em>, ff. 66-67v.<\/p>\n<p>224A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 71. Y A.C.O. Armario I, libro n\u00ba 2, ff. 162v.-163.<\/p>\n<p>225A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 77, 142-143. Y libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 293-293v.<\/p>\n<p>226A.C.O. Armario I, libro n\u00ba 1, f. 91; y libro n\u00ba 2, f. 178v. Y armario X, libro n\u00ba 1094, f. 247. Tambi\u00e9n en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 79; y libro n\u00ba 56, <em>Contestador<\/em> de 1538, f. 91.<\/p>\n<p>227A.C.O. Armario I, libro n\u00ba 1, f. 91v.; y libro n\u00ba 2, f. 178. Y armario X, libro n\u00ba 1094, f. 248. Tambi\u00e9n en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 79v. Y libro n\u00ba 56, <em>Contestador<\/em> de 1538, f. 92.<\/p>\n<p>228A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 292-293v. Mart\u00ed volvi\u00f3 apurado de la corte porque el provisor de Cartagena estaba tratando de arrebatarle una canonj\u00eda de la iglesia del Salvador que hac\u00eda poco que hab\u00eda conseguido gracias a una concesi\u00f3n del legado pontificio en Espa\u00f1a. Hay abundante informaci\u00f3n sobre este caso en el mismo A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 70-70v., 72-73.<\/p>\n<p>229A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, f. 322.<\/p>\n<p>230A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 74.<\/p>\n<p>231A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, ff. 305-305v. Franch hab\u00eda de pagar, el registro, el sellado y otros derechos.<\/p>\n<p>232A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 75v.-78v.<\/p>\n<p>233<em>Ibidem<\/em>, f. 75. Las autoridades oriolanas le dijeron a Cabrero que les hubiese encantado que le hubiesen nombrado obispo de Cartagena y Orihuela, aunque m\u00e1s bien merec\u00eda el capelo cardenalicio y el arzobispado de Toledo.<\/p>\n<p>234A.M.O. Libro n\u00ba 48, <em>Contestador<\/em> de 1528, f. 306.<\/p>\n<p>235<em>Ibidem<\/em>.<\/p>\n<p>236A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 80v.<\/p>\n<p>237<em>Ibidem<\/em>, ff. 80-81.<\/p>\n<p>238<em>Ibidem<\/em>, ff. 82, 85-85v., 86-87.<\/p>\n<p>239<em>Ibidem<\/em>, ff. 82v., 87.<\/p>\n<p>240<em>Ibidem<\/em>, ff. 83-83v.<\/p>\n<p>241<em>Ibidem<\/em>, ff. 84-84v.<\/p>\n<p>242<em>Ibidem<\/em>, f. 88.<\/p>\n<p>243A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529, ff. 56-67v.<\/p>\n<p>244<em>Ibidem<\/em>, ff. 23-23v. Tambi\u00e9n pretend\u00edan utilizar ese dinero para sufragar los gastos de los s\u00edndicos enviados a las Cortes, pues \u00e9stas hab\u00edan sido prorrogadas y estaban desarroll\u00e1ndose en Valencia, bajo la direcci\u00f3n del duque de Calabria.<\/p>\n<p>245A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 89-91v.<\/p>\n<p>246<em>Ibidem<\/em>, ff. 109, 109v., 113v.<\/p>\n<p>247A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529, ff. 56-67v.<\/p>\n<p>248<em>Ibidem<\/em>, f. 85.<\/p>\n<p>249A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 108.<\/p>\n<p>250<em>Ibidem<\/em>, f. 113.<\/p>\n<p>251<em>Ibidem<\/em>, f. 110.<\/p>\n<p>252Lorenzo Puci, cardenal de los Cuatro Santos Coronados, era un venal. En 1517 y 1518 hab\u00eda mostrado una especial afecci\u00f3n por los intereses murcianos-castellanos. No obstante, durante los a\u00f1os 1528, 1529 y 1530, la cercan\u00eda de Luis G\u00f3mez y la posibilidad de conseguir dinero de manos de los representantes de la ciudad del Bajo Segura le hicieron inclinarse hacia las posiciones oriolanas.<\/p>\n<p>253A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 92-92v.<\/p>\n<p>254<em>Ibidem<\/em>, ff. 93-93v.<\/p>\n<p>255<em>Ibidem<\/em>, ff. 94-94v.<\/p>\n<p>256<em>Ibidem<\/em>, ff. 94v.-95.<\/p>\n<p>257<em>Ibidem<\/em>, ff. 95-95v. Como veremos m\u00e1s adelante, esta carta se perdi\u00f3 y el descuido molest\u00f3 much\u00edsimo a su destinatario.<\/p>\n<p>258<em>Ibidem<\/em>, ff. 96, 96v., 97.<\/p>\n<p>259A.C.O. Armario IX, Legajo XX, parte 1\u00aa, documento n\u00ba 32. A.M.O., libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades, 1527-1531<\/em>, ff. 97v.-102v.<\/p>\n<p>260A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 103-106v.<\/p>\n<p>261<em>Ibidem<\/em>, f. 107.<\/p>\n<p>262<em>Ibidem<\/em>, f. 112v.<\/p>\n<p>263A.C.O. Armario X, libro n\u00ba 1096, ff. 125-127.<\/p>\n<p>264A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 114-114v.<\/p>\n<p>265A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529, ff. 142, 143, 144-145.<\/p>\n<p>266No nos ha llegado este escrito de Juan Mir\u00f3. Conocemos su contenido gracias a las referencias a \u00e9l que el cap\u00edtulo del Salvador y el <em>Consell<\/em> de Orihuela incluyeron en la carta que le remitieron al procurador el 5 de junio de 1529. \u00c9sta se halla en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 116-117.<\/p>\n<p>267<em>Ibidem<\/em>, f. 124v. De las 100 libras, \u00fanicamente 60 ducados fueron empleados en el pago del breve. <em>Ibidem<\/em>, f. 209. El resto del dinero sirvi\u00f3 para abonar tasas, dar propinas y hacer algunos presentes.<\/p>\n<p>268A.C.O. Armario IX, Legajo III, siglo XVI, pergamino n\u00ba 84.<\/p>\n<p>269A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 132.<\/p>\n<p>270GARC\u00cdA C\u00c1RCEL, R.: <em>Cortes del reinado de Carlos I&#8230;<\/em>, p. IX. Hay abundantes referencias a la cuesti\u00f3n de la defensa de la costa en el A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529.<\/p>\n<p>271A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 116-117.<\/p>\n<p>272<em>Ibidem<\/em>, ff. 115-115v.<\/p>\n<p>273<em>Ibidem<\/em>, ff. 118-118v.<\/p>\n<p>274<em>Ibidem<\/em>, ff. 118v.-119.<\/p>\n<p>275<em>Ibidem<\/em>, ff. 119v.-120.<\/p>\n<p>276<em>Ibidem<\/em>, ff. 119-119v.<\/p>\n<p>277A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529, ff. 305-308v.<\/p>\n<p>278A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 121v.-124.<\/p>\n<p>279<em>Ibidem<\/em>, ff. 132-133v.<\/p>\n<p>280<em>Ibidem<\/em>, f. 131v.<\/p>\n<p>281<em>Ibidem<\/em>, ff. 130v.-131v. Al parecer, aunque no hemos podido constatar el siguiente dato en ninguna otra fuente documental, D. Alfonso G\u00f3mez, abuelo del auditor, fue nombrado procurador de la ciudad de Orihuela durante el reinado de Alfonso V el <em>Magn\u00e1nimo<\/em>, y estuvo en N\u00e1poles negociando la cuesti\u00f3n del obispado. A continuaci\u00f3n, reproducimos un curioso fragmento de la carta, que muestra que las autoridades oriolanas utilizaban todo tipo de argumentos para predisponer a sus aliados y protectores: \u00ab<em>&#8230; los osos del senyor Alfonso Gomes, en gloria sia, senten alegria de veure que aquesta causa per ell principiada com a embaxador de aquesta ciutat en Napols, en vida del rey don Alfonso, de inmortal recort, contra lo tunc bisbe de Cartagena, aja de pendre terme en mans de son net, y per esser digne de tanta comendatio, la sua patria y sglesia sien sublimades y delliures de la submissio de nostres capitals enemichs<\/em>\u00bb.<\/p>\n<p>282<em>Ibidem<\/em>, f. 130.<\/p>\n<p>283<em>Ibidem<\/em>, f. 135v.<\/p>\n<p>284<em>Ibidem<\/em>, f. 124v.<\/p>\n<p>285A.C.O. Armario IX, Legajo XX, parte 1\u00aa, documento n\u00ba 22.<\/p>\n<p>286A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 137, 139v.<\/p>\n<p>287La dirigida a los oriolanos se halla en el A.M.O. Libro n\u00ba 49, <em>Contestador<\/em> de 1529, f. 597.<\/p>\n<p>288A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 138-141.<\/p>\n<p>289<em>Ibidem<\/em>, ff. 142-147.<\/p>\n<p>290<em>Ibidem<\/em>, ff. 199-200.<\/p>\n<p>291<em>Ibidem<\/em>, ff. 209v.-210. La aprobaci\u00f3n de cualquier cuesti\u00f3n en la Signatura era necesaria para que el consistorio pontificio pudiese promulgar cualquier decreto o adoptar cualquier disposici\u00f3n.<\/p>\n<p>292<em>Ibidem<\/em>, ff. 199-200.<\/p>\n<p>293<em>Ibidem<\/em>, ff. 196-197v.<\/p>\n<p>294<em>Ibidem<\/em>, ff. 196-197v.<\/p>\n<p>295<em>Ibidem<\/em>, ff. 195-195v.<\/p>\n<p>296<em>Ibidem<\/em>, ff. 199-200.<\/p>\n<p>297<em>Ibidem<\/em>, f. 210v.<\/p>\n<p>298<em>Ibidem<\/em>, f. 210v.<\/p>\n<p>299<em>Ibidem<\/em>, f. 211.<\/p>\n<p>300<em>Ibidem<\/em>, ff. 175, 195-195v., 211. Hay que hacer constar que por estas fechas el cardenal Jacobacis ya hab\u00eda muerto, y que, de haber estado vivo, con casi total seguridad habr\u00eda sido el encargado de revisar la cuesti\u00f3n episcopal.<\/p>\n<p>301A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 195-195v., 198-198v.<\/p>\n<p>302<em>Ibidem<\/em>, ff. 142-148v.<\/p>\n<p>303<em>Ibidem<\/em>, ff. 211-212.<\/p>\n<p>304A.C.O. Armario I, libro n\u00ba 1, ff. 283-284v.<\/p>\n<p>305A.C.O. Armario I, libro n\u00ba 2, ff. 182-192v. Camilo Ballion era doctor en ambos Derechos y capell\u00e1n del papa.<\/p>\n<p>306A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 212.<\/p>\n<p>307A.C.O. Armario I, libro n\u00ba 1, ff. 4-9v., ff. 14-19v.; y libro n\u00ba 2, ff. 218-230. Y armario X, libro n\u00ba 1096, ff. 5-10v.<\/p>\n<p>308A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 212v.<\/p>\n<p>309A.C.O. Armario I, libro n\u00ba 2, ff. 192v.-193v.<\/p>\n<p>310A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 153-154v.<\/p>\n<p>311<em>Ibidem<\/em>, ff. 151-154v.<\/p>\n<p>312<em>Ibidem<\/em>, ff. 153-154v.<\/p>\n<p>313<em>Ibidem<\/em>, ff. 149v.-150.<\/p>\n<p>314<em>Ibidem<\/em>, ff. 151-152v.<\/p>\n<p>315<em>Ibidem<\/em>, f. 149.<\/p>\n<p>316A.C.O. Armario I, libro n\u00ba 1, ff. 11-13, 19v.-22. Y armario X, Libro n\u00ba 1096, ff. 27-29.<\/p>\n<p>317A.C.O. Armario I, libro n\u00ba 1, ff. 9v.-11, ff. 22-23v. Y armario X, libro n\u00ba 1096, ff. 24v.-27.<\/p>\n<p>318A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 158-159v.<\/p>\n<p>319A.C.O. Armario IX, Legajo XX, parte 1\u00aa, documento n\u00ba 24.<\/p>\n<p>320A.C.O. Armario I, libro n\u00ba 1, ff. 282-282v.<\/p>\n<p>321A.C.O. Armario X, libro n\u00ba 1096, ff. 3-4v. El sindicato nos permite conocer a la mayor\u00eda de los componentes del cabildo de Cartagena. Conformaban dicho organismo colegiado el de\u00e1n Jer\u00f3nimo de Araque, el chantre Pedro Hurtado, el tesorero Pedro de Medina y el maestrescuela Antonio Tamar\u00f3n -como dignidades-; los can\u00f3nigos Juan Soriano, Mat\u00edas Coque, Juan Arrieta y Diego Vald\u00e9s; y los beneficiados Alonso Petit, Jaime Villatorta, Francisco Guerao, Lorenzo Caravaca, Juan Tom\u00e1s, Luis Soriano, Juan Miralles, Juan Fern\u00e1ndez Pantoja, Diego Romo, Francisco Ortega, Juan Camargo y Pedro de Torres.<\/p>\n<p>322<em>Ibidem<\/em>, ff. 3-11v.<\/p>\n<p>323Conocemos la existencia de esta carta gracias a dos referencias indirectas, que se hallan en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 160 y 161-161v.<\/p>\n<p>324<em>Ibidem<\/em>.<\/p>\n<p>325A.C.O. Armario X, libro n\u00ba 1096, ff. 11v.-15.<\/p>\n<p>326<em>Ibidem<\/em>, ff. 15v.-21.<\/p>\n<p>327<em>Ibidem<\/em>, ff. 15-23v.<\/p>\n<p>328A.C.O. Armario I, libro n\u00ba 2, ff. 216v.-217. Y A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, f. 41v.<\/p>\n<p>329A.C.O. Armario X, libro n\u00ba 1096, ff. 23-23v.<\/p>\n<p>330Toda esta documentaci\u00f3n se halla en <em>ibidem<\/em>, ff. 30v.-101v.<\/p>\n<p>331A.C.O. Armario I, libro n\u00ba 2, ff. 215-216. Y armario X, libro n\u00ba 1096, ff. 30-30v. Tambi\u00e9n hay una copia en el A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, f. 45.<\/p>\n<p>332A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, ff. 45v.-48.<\/p>\n<p>333La hora tercia corresponde a las 9 la ma\u00f1ana. Nos permitimos la licencia de escribir en esta nota el libro que, con gusto, nos permiti\u00f3 aprender la equivalencia de las horas can\u00f3nicas. ECO, U.: <em>El nombre de la rosa<\/em>, Barcelona, 1992, p. 10.<\/p>\n<p>334A.C.O. Armario I, libro n\u00ba 1, ff. 4-14. Fray Luis Matarredona era maestro en Sacra Teolog\u00eda y vicario provincial del monasterio de San Agust\u00edn de la villa de Alcoi.<\/p>\n<p>335A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 162-164.<\/p>\n<p>336<em>Ibidem<\/em>, ff. 164v.-165.<\/p>\n<p>337<em>Ibidem<\/em>, ff. 164-164v.<\/p>\n<p>338A.C.O. Armario I, libro n\u00ba 1, ff. 14-23v.<\/p>\n<p>339A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 234-235v., 248-250v. El can\u00f3nigo Orozco y D. Carlos y D. Luis D\u00e1valos le ofrecieron a Vicente Mart\u00ed el siguiente pacto. Las iglesia del Salvador mantendr\u00eda su rango catedralicio y Orihuela su obispado unido. Y como compensaci\u00f3n, el vicario general de Orihuela s\u00f3lo tendr\u00eda jurisdicci\u00f3n sobre la propia ciudad del Bajo Segura y sus \u00ab<em>ravals<\/em>\u00bb, y los obispos de Cartagena y Orihuela tendr\u00edan que tomar posesi\u00f3n de los dos obispados \u00fanicamente en la Catedral de Murcia. Las autoridades oriolanas se negaron a aceptar la oferta cartaginense porque iba claramente en contra de la Concordia de Logro\u00f1o, ya que el vicario general perd\u00eda la jurisdicci\u00f3n sobre las villas y los lugares de la huerta de Orihuela, y tambi\u00e9n sobre las dem\u00e1s poblaciones del Reino de Valencia que estaban adscritas a la di\u00f3cesis. Y porque no ten\u00eda sentido que siendo Catedral la iglesia del Salvador, los obispos no tomasen posesi\u00f3n del obispado de Orihuela en ella.<\/p>\n<p>340<em>Ibidem<\/em>, f. 214.<\/p>\n<p>341<em>Ibidem<\/em>, ff. 260-261v.<\/p>\n<p>342Hemos hallado diferentes traslados de dicho breve. A.C.O. Armario I, libro n\u00ba 2, ff. 133v.-140. Armario IX, Legajo XX, parte 1\u00aa, documento n\u00ba 25. Y armario X, libro n\u00ba 1094, ff. 266-268.<\/p>\n<p>343Conocemos la existencia de ambas provisiones gracias a una referencia hallada en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 175.<\/p>\n<p>344A.C.O. Armario I, libro n\u00ba 1, ff. 14-24v.<\/p>\n<p>345<em>Ibidem<\/em>, 24v.-32.<\/p>\n<p>346A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 215.<\/p>\n<p>347Las cartas del 26 de octubre de 1510, del 5 y el 9 de enero de 1514, y del 20 de agosto de ese mismo a\u00f1o.<\/p>\n<p>348Los ejecutoriales fechados el 15 de mayo de 1519, el 7 y el 10 de abril de 1520, el 25 de agosto de 1525 -y el instrumento de presentaci\u00f3n a D. Pedro Maza-, y el 12 de febrero de 1529.<\/p>\n<p>349A.C.O. Armario X, libro n\u00ba 1096, ff. 101v.-128.<\/p>\n<p>350A.C.O. Armario I, libro n\u00ba 1, ff. 32-33.<\/p>\n<p>351<em>Ibidem<\/em>, ff. 33-33v.<\/p>\n<p>352A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 248-250v.<\/p>\n<p>353A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 170-170v. Por otra parte, en el A.C.O. a\u00fan se conserva la copia enviada por Rodrigo de M\u00e9rida. Se trata del libro n\u00ba 1096, titulado \u00ab<em>Proceso Compulsorio sobre cosas tocantes a la ereccion y govierno de las rentas desta Sancta Yglesia<\/em>\u00bb, que se halla en el Armario X.<\/p>\n<p>354A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 248-250v. La carta no va fechada, pero por su contenido suponemos que fue escrita hacia el 20 de abril.<\/p>\n<p>355A.C.O. Armario I, libro n\u00ba 1, ff. 33v.-34v.<\/p>\n<p>356A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, f. 109v.<\/p>\n<p>357A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 174-174v.<\/p>\n<p>358A.C.O. Armario I, libro n\u00ba 1, ff. 34v.-36v.<\/p>\n<p>359A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 172v.<\/p>\n<p>360<em>Ibidem<\/em>, ff. 171-172.<\/p>\n<p>361<em>Ibidem<\/em>, f. 173.<\/p>\n<p>362<em>Ibidem<\/em>, ff. 175-177.<\/p>\n<p>363A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, f. 110.<\/p>\n<p>364A.C.O. Armario I, libro n\u00ba 1, ff. 39v.-41v.<\/p>\n<p>365<em>Ibidem<\/em>, ff. 41v.-67v.<\/p>\n<p>366<em>Ibidem<\/em>, ff. 69-86.<\/p>\n<p>367<em>Ibidem<\/em>, ff. 86-91v.<\/p>\n<p>368<em>Ibidem<\/em>, ff. 91v.-100v.<\/p>\n<p>369<em>Ibidem<\/em>, ff. 101-105v.<\/p>\n<p>370<em>Ibidem<\/em>, ff. 105v.-228v.<\/p>\n<p>371<em>Ibidem<\/em>, ff. 229-232.<\/p>\n<p>372<em>Ibidem<\/em>, ff. 232v.-246v.<\/p>\n<p>373<em>Ibidem<\/em>, ff. 247-256v.<\/p>\n<p>374<em>Ibidem<\/em>, ff. 257-281.<\/p>\n<p>375<em>Ibidem<\/em>, ff. 281-285v.<\/p>\n<p>376<em>Ibidem<\/em>, f. 287v.<\/p>\n<p>377Murcianos y oriolanos no le otorgaban igual importancia a sus respectivos procesos compulsorios. Claro exponente de ello es su desigual extensi\u00f3n. Mientras que el oriolano ten\u00eda, como ya hemos se\u00f1alado, 287 folios, el cartaginense \u00fanicamente ocupaba 128. En el Armario I del A.C.O. hay localizada una copia del compendio oriolano, titulada \u00ab<em>Papeles y bulas conducentes a la Catedral\u00eda<\/em>\u00bb.<\/p>\n<p>378A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 226.<\/p>\n<p>379A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, ff. 111-111v.<\/p>\n<p>380A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 248-250v.<\/p>\n<p>381<em>Ibidem<\/em>, f. 246.<\/p>\n<p>382A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, f. 169v.-170v.<\/p>\n<p>383A.C.O. Armario X, libro n\u00ba 1095, ff. 127-130v., 131-133v.<\/p>\n<p>384<em>Ibidem<\/em>, ff. 137-139.<\/p>\n<p>385<em>Ibidem<\/em>, ff. 134-135, 137-139.<\/p>\n<p>386<em>Ibidem<\/em>, ff. 140-140v.<\/p>\n<p>387A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 178-180v. Las autoridades oriolanas tardaron tanto tiempo en enviar los procesos compulsorios porque quer\u00edan que los llevase una persona de total confianza. Dicha actitud ten\u00eda una clara y justificad\u00edsima explicaci\u00f3n. Durante los a\u00f1os 1529 y 1530, muchos de los correos enviados por la v\u00eda del vicario valentino Guillem Desprats no llegaron a su destino romano porque, al parecer, fueron interceptados en Italia por los murcianos. Y en esta ocasi\u00f3n no quer\u00edan arriesgarse a que los compendios no llegasen a manos de Juan Mir\u00f3.<\/p>\n<p>388<em>Ibidem<\/em>, f. 192.<\/p>\n<p>389A.C.O. Armario X, libro n\u00ba 1095, ff. 140-140v.<\/p>\n<p>390Toda la documentaci\u00f3n se\u00f1alada se encuentra en el A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 178-191v.<\/p>\n<p>391Las instrucciones para Mir\u00f3 o Fontes se hallan en <em>ibidem<\/em>, ff. 178-180v., 185-186v.<\/p>\n<p>392<em>Ibidem<\/em>, ff. 178-180v.<\/p>\n<p>393<em>Ibidem<\/em>, ff. 188-188v.<\/p>\n<p>394A.C.O. Armario I, libro n\u00ba 2, ff. 153-154v.<\/p>\n<p>395A.M.O. Libro n\u00ba 50, <em>Contestador<\/em> de 1530, ff. 239-241v.<\/p>\n<p>396A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, f. 192.<\/p>\n<p>397<em>Ibidem<\/em>, f. 218v.<\/p>\n<p>398A.C.O. Armario I, libro n\u00ba 2, ff. 1-2. A.M.O. Libro n\u00ba 2208, <em>Libro de Procedimientos<\/em>, 1434-1525, ff. 202-202v.<\/p>\n<p>399A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 203-203v., 205. Las autoridades oriolanas le asignaron a Mart\u00ednez un salario de un ducado diario.<\/p>\n<p>400<em>Ibidem<\/em>, ff. 221-224v.<\/p>\n<p>401<em>Ibidem<\/em>, ff. 226-227v.<\/p>\n<p>402<em>Ibidem<\/em>, ff. 253v.-259.<\/p>\n<p>403<em>Ibidem<\/em>, ff. 228-232v.<\/p>\n<p>404<em>Ibidem<\/em>, ff. 253v.-259.<\/p>\n<p>405<em>Ibidem<\/em>, ff. 260-261v.<\/p>\n<p>406No hemos hallado esta provisi\u00f3n real. No obstante s\u00ed hemos encontrado algunas referencias a ella en la documentaci\u00f3n inmediatamente posterior. <em>Ibidem<\/em>, ff. ff. 240-240v.<\/p>\n<p>407A.M.O. Libro n\u00ba 47, <em>Cartas a diferentes personas y autoridades. 1527-1531<\/em>, ff. 239-239v.<\/p>\n<p>408<em>Ibidem<\/em>, ff. 234-235v.<\/p>\n<p>409<em>Ibidem<\/em>, ff. 237-238v.<\/p>\n<p>410<em>Ibidem<\/em>, ff. 240-240v.<\/p>\n<p>411<em>Ibidem<\/em>, f. 241.<\/p>\n<p>412<em>Ibidem<\/em>, ff. 243-245.<\/p>\n<p>413<em>Ibidem<\/em>, ff. 263-263v, 268-268v.<\/p>\n<p>414<em>Ibidem<\/em>, ff. 264-264v.<\/p>\n<p>415<em>Ibidem<\/em>, ff. 264-267v.<\/p>\n<p>416<em>Ibidem<\/em>, ff. 269-272v.<\/p>\n<p>417A.M.O. Libro n\u00ba 2213, <em>Contestador<\/em> de 1533, ff. 225-226v.<\/p>\n<p>418A.C.O. Armario I, libro n\u00ba 2, ff. 133-142v.<\/p>\n<p>419A.C.O. Armario I, libro n\u00ba 2, ff. 92-93v.<\/p>\n<p>420<em>Ibidem<\/em>, ff. 87v.-89v.<\/p>\n<p>421<em>Ibidem<\/em>, ff. 87-87v., 89v.-91v.<\/p>\n<p>422<em>Ibidem<\/em>, ff. 91v.-92, 94-96v.<\/p>\n<p>423<em>Ibidem<\/em>, ff. 97-98v.<\/p>\n<p>424<em>Ibidem<\/em>, ff. 98v.-108v.<\/p>\n<p>425<em>Ibidem<\/em>, ff. 108v.-110v.<\/p>\n<p>426<em>Ibidem<\/em>, ff. 111-112v.<\/p>\n<p>427<em>Ibidem<\/em>, ff. 113-113v.<\/p>\n<p>428<em>Ibidem<\/em>, ff. 113v.-114v.<\/p>\n<p>429<em>Ibidem<\/em>, ff. 114v.-116.<\/p>\n<p>430<em>Ibidem<\/em>, ff. 116-118.<\/p>\n<p>431<em>Ibidem<\/em>, ff. 118-120v.<\/p>\n<p>432<em>Ibidem<\/em>, ff. 121-121v.<\/p>\n<p>433<em>Ibidem<\/em>, ff. 121v.-123.<\/p>\n<p>434<em>Ibidem<\/em>, ff. 123-124.<\/p>\n<p>435<em>Ibidem<\/em>, ff. 124v.-126.<\/p>\n<p>436<em>Ibidem<\/em>, ff. 127v.-129v.<\/p>\n<p>437En la comisi\u00f3n, el duque especificaba incluso que los oriolanos habr\u00edan de vender a los cl\u00e9rigos cartaginenses las vituallas que requiriesen sin ponerles precios m\u00e1s altos que los habituales.<\/p>\n<p>438A.C.O. Armario I, libro n\u00ba 2, ff. 126v.-127.<\/p>\n<p>439<em>Ibidem<\/em>, ff. 130-131v.<\/p>\n<p>440<em>Ibidem<\/em>, ff. 131v.-132v., 142v.<\/p>\n<p>441<em>Ibidem<\/em>, ff. 143-144.<\/p>\n<p>442<em>Ibidem<\/em>, ff. 145-145v.<\/p>\n<p>443<em>Ibidem<\/em>, ff. 145v.-146v.<\/p>\n<p>444<em>Ibidem<\/em>, ff. 146v.-148.<\/p>\n<p>445<em>Ibidem<\/em>, f. 148.<\/p>\n<p>446<em>Ibidem<\/em>, ff. 148v.-149v.<\/p>\n<p>447<em>Ibidem<\/em>, ff. 149v.-151v.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El inicio de la recuperaci\u00f3n oriolana despu\u00e9s de la German\u00eda. El 29 de septiembre de 1521, el marqu\u00e9s de los V\u00e9lez decidi\u00f3 dar por concluidas las rapi\u00f1as. Las tropel\u00edas cometidas por los hombres de D. Pedro Fajardo fueron de tal gravedad que han llevado a D. Ricardo Garc\u00eda C\u00e1rcel a afirmar que el Saco de [&hellip;]<\/p>\n","protected":false},"author":936,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/users\/936"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":36,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/22\/revisions\/36"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}