{"id":39,"date":"2021-09-29T04:40:30","date_gmt":"2021-09-29T04:40:30","guid":{"rendered":"https:\/\/blogs.ua.es\/obispadoorihuela\/?page_id=39"},"modified":"2021-09-29T04:40:30","modified_gmt":"2021-09-29T04:40:30","slug":"12-conclusiones","status":"publish","type":"page","link":"https:\/\/blogs.ua.es\/obispadoorihuela\/12-conclusiones\/","title":{"rendered":"12. Conclusiones"},"content":{"rendered":"<p align=\"JUSTIFY\">En el cap\u00edtulo dedicado a las conclusiones del presente trabajo de investigaci\u00f3n, realizaremos una interpretaci\u00f3n en torno a los siguientes puntos de reflexi\u00f3n:<\/p>\n<p align=\"JUSTIFY\">7.1. El origen del Pleito del Obispado: la falta de coincidencia entre los l\u00edmites eclesi\u00e1sticos y pol\u00edticos.<\/p>\n<p align=\"JUSTIFY\">7.2. Las causas de las reivindicaciones episcopales oriolanas.<\/p>\n<p align=\"JUSTIFY\">7.3. La oposici\u00f3n murciana a la escisi\u00f3n de la di\u00f3cesis de Cartagena.<\/p>\n<p align=\"JUSTIFY\">7.4. El apoyo real a las aspiraciones episcopales y la creaci\u00f3n del obispado de Orihuela.<\/p>\n<p align=\"JUSTIFY\"><strong>7.1. El origen del Pleito del Obispado: la falta de coincidencia entre los l\u00edmites eclesi\u00e1sticos y pol\u00edticos.<\/strong><\/p>\n<p align=\"JUSTIFY\">Tras la Reconquista de las tierras del sudeste de la Pen\u00ednsula Ib\u00e9rica a los musulmanes, a mediados del siglo XIII, el infante Alfonso (el futuro Alfonso X) decidi\u00f3 fomentar la reimplantaci\u00f3n del Cristianismo en ellas, restaurando el obispado hist\u00f3rico de Cartagena. El monarca asign\u00f3 a la nueva di\u00f3cesis los territorios que acababa de conquistar, de modo que \u00e9sta qued\u00f3 conformada por todo lo que hoy es la actual provincia de Murcia, parte de la de Albacete, una porci\u00f3n de la de Almer\u00eda, un estrecho margen de la de Valencia y aproximadamente la mitad sur de la provincia de Alicante.<\/p>\n<p align=\"JUSTIFY\">Sin embargo, a principios del siglo XIV, como consecuencia de la firma de los tratados de Torrellas y Elche, el l\u00edmite meridional entre las coronas de Arag\u00f3n y Castilla fue ligeramente modificado, quedando definitivamente establecido m\u00e1s al sur, entre las localidades de El Pilar de la Horadada y San Pedro del Pinatar. De esa manera, el sur de la actual provincia de Alicante, a cuya cabeza se hallaba la entonces villa de Orihuela, pas\u00f3 a pertenecer pol\u00edticamente al Reino de Valencia y la Corona de Arag\u00f3n, aunque sigui\u00f3 dependiendo a nivel espiritual de los obispos castellanos de Cartagena.<\/p>\n<p align=\"JUSTIFY\">Con el tiempo, esta an\u00f3mala situaci\u00f3n, la falta de coincidencia entre los l\u00edmites pol\u00edticos y eclesi\u00e1sticos, fue la causa de graves problemas para los habitantes de Orihuela y su t\u00e9rmino, e hizo surgir en ellos una necesidad de independencia espiritual que en la segunda mitad del Trescientos se desarroll\u00f3 para plasmarse en el inicio de las reivindicaciones en pos de la consecuci\u00f3n de un obispado propio, independiente del de Cartagena, con sede en la iglesia oriolana del Salvador y con una di\u00f3cesis formada por los territorios del Reino de Valencia que pertenec\u00edan al obispado \u00abmurciano\u00bb.<\/p>\n<p align=\"JUSTIFY\"><strong>7.2. Las causas de las reivindicaciones episcopales oriolanas.<\/strong><\/p>\n<p align=\"JUSTIFY\">Si bien la no coincidencia entre los l\u00edmites pol\u00edticos y eclesi\u00e1sticos fue la premisa que propici\u00f3 el Pleito del Obispado, la necesidad segregacionista fue fortaleci\u00e9ndose progresivamente en la conciencia oriolana por otros variados motivos. Podemos agruparlos en cuatro categor\u00edas generales:<\/p>\n<ul>\n<li>7.2.1. Los frecuentes roces entre las poblaciones de Orihuela y Murcia, de marcado car\u00e1cter nacionalista.<\/li>\n<li>7.2.2. Los conflictos relacionados con el ejercicio del poder espiritual por el obispo y el cabildo de Cartagena, y sus respectivos oficiales.<\/li>\n<li>7.2.3. La falta de atenci\u00f3n pastoral a los diocesanos del Reino de Valencia por parte de los prelados cartaginenses.<\/li>\n<li>7.2.4. La percepci\u00f3n por el obispo y el cabildo de Cartagena de rentas procedentes de la parte de la di\u00f3cesis perteneciente al Reino de Valencia.<\/li>\n<li>7.2.1. Los frecuentes roces entre las poblaciones de Orihuela y Murcia, de marcado car\u00e1cter nacionalista.<\/li>\n<\/ul>\n<p align=\"JUSTIFY\">Desde la misma fundaci\u00f3n de Murcia por Abderram\u00e1n II, en el siglo IX, la proximidad espacial de \u00e9sta a Orihuela, la posici\u00f3n destacada de ambas al frente de sus respectivas zonas de influencia econ\u00f3mica y su rivalidad como centros de poder, promovieron la existencia de m\u00faltiples conflictos entre los habitantes de las dos poblaciones.<\/p>\n<p align=\"JUSTIFY\">Dichos roces se hicieron m\u00e1s frecuentes a partir de principios del siglo XIV cuando, en virtud de los aludidos tratados de Torrellas y Elche, Orihuela y su t\u00e9rmino pasaron al Reino de Valencia. Desde ese momento, la pertenencia de las dos poblaciones a monarqu\u00edas distintas propici\u00f3 que ambas tuviesen leyes diferentes, sistemas de gobierno y administraci\u00f3n distintos, e incluso, que sus respectivos habitantes hablasen distintas lenguas. Y tuvo, asimismo, como consecuencia que murcianos y oriolanos se enfrentasen en las guerras de sus soberanos; en grandes contiendas que, como en el caso de la Guerra de los Dos Pedros, tuvieron como escenario de las batallas el propio Levante peninsular.<\/p>\n<p align=\"JUSTIFY\">No obstante, si bien las relaciones entre murcianos y oriolanos se agriaron a ra\u00edz de su participaci\u00f3n en enfrentamientos a gran escala -recordemos la existencia de episodios violentos y sa\u00f1udos como la toma de Orihuela en la citada guerra bajomedieval o el Saco de 1521 en el contexto doble de la German\u00eda y el Pleito del Obispado-, no empeoraron menos por la larga serie de roces que se hicieron habituales entre los habitantes de ambas localidades. Nos estamos refiriendo a las discordias entre nobles, a los robos de ganado, a los asaltos en los caminos, a la tala y quema de \u00e1rboles, a la destrucci\u00f3n de los campos de cultivo e, incluso, a las inundaciones provocadas por desbordamientos artificiales del r\u00edo Segura. La rivalidad lleg\u00f3 hasta tal punto que se hizo com\u00fan que los oriolanos que tuviesen que desplazarse a Murcia por cualquier motivo fuesen all\u00ed maltratados o vejados; y viceversa. Tanto los habitantes de Orihuela como los de Murcia ten\u00edan a sus vecinos como enemigos capitales, y en atenci\u00f3n a tal consideraci\u00f3n, sol\u00edan comportarse.<\/p>\n<p align=\"JUSTIFY\">Pese a que las autoridades civiles de ambas poblaciones mantuvieron regularmente relaciones m\u00e1s o menos cordiales, la rivalidad popular y el elemento nacionalista se alimentaron rec\u00edprocamente, y hallaron un nuevo y poderoso motor de crecimiento en la cuesti\u00f3n del obispado.<\/p>\n<p align=\"JUSTIFY\">En este sentido, tanto la rivalidad secular como la conciencia nacionalista tuvieron una clara incidencia en el \u00e1mbito de las relaciones espirituales. En el caso oriolano fomentaron la apuntada necesidad de lograr la independencia de la tutela eclesi\u00e1stica y el deseo paralelo de encabezar un obispado que tuviese como di\u00f3cesis las referidas tierras del sur del Reino de Valencia. Y en el caso murciano se manifestaron en la prohibici\u00f3n de que \u00abextranjeros\u00bb (entre los que se hallaban, por supuesto, los cl\u00e9rigos del otro lado de la frontera) pudiesen detentar beneficios en las iglesias de la parte castellana del obispado; disposici\u00f3n que, de manera opuesta, tambi\u00e9n fue decretada posteriormente por Mart\u00edn el Humano para evitar que los murcianos-castellanos pudiesen disfrutar de prebendas en los templos sitos dentro del Reino de Valencia.<\/p>\n<p align=\"JUSTIFY\">Por \u00faltimo, hemos de se\u00f1alar que tras la uni\u00f3n de las Coronas de Castilla y Arag\u00f3n, las discordias entre murcianos y oriolanos no perdieron su componente nacionalista. Al contrario, la conciencia de pertenecer a naciones distintas sigui\u00f3 siendo uno de los principales sustentos de la voluntad oriolana por lograr la independencia espiritual.<\/p>\n<p align=\"JUSTIFY\">7.2.2. Los conflictos relacionados con el ejercicio del poder espiritual por el obispo y el cabildo de Cartagena, y sus respectivos oficiales.<\/p>\n<p align=\"JUSTIFY\">A pesar de la influencia que la Iglesia ten\u00eda sobre la sociedad bajomedieval y moderna, los mandatarios civiles y eclesi\u00e1sticos y la poblaci\u00f3n de Orihuela no mostraron recelo alguno a la hora de obedecer a la soberan\u00eda temporal de los reyes de la Corona de Arag\u00f3n, o, simplemente, a los dictados de sus propios intereses antes que a la autoridad espiritual cartaginense. Ello provoc\u00f3 que, a lo largo de los siglos que dur\u00f3 el Pleito del Obispado, los oriolanos sufriesen la imposici\u00f3n de una variada gama de censuras eclesi\u00e1sticas. Las excomuniones y los entredichos se sucedieron de una manera tan inmediata y cotidiana que podemos arriesgarnos a afirmar que los oriolanos se acostumbraron a vivir en situaciones de irregularidad espiritual, pese a las incomodidades morales que ello conllevaba. Asimismo, tambi\u00e9n podemos decir que la ingente cantidad de negociaciones que los oriolanos tuvieron que afrontar, en aras al alzamiento de las penas, les proporcion\u00f3 una larga experiencia que les sirvi\u00f3 para formar a verdaderos peritos en las actividades diplom\u00e1ticas (como Miguel Mols\u00f3s, Perot P\u00e9rez Terol, Vicente Mart\u00ed, Luis Mart\u00ednez, Gin\u00e9s de Vilafranca o el propio Diego Ferr\u00e1ndez de Mesa, por citar algunos ejemplos).<\/p>\n<p align=\"JUSTIFY\">La imposibilidad de obedecer al mismo tiempo \u00f3rdenes de las autoridades pol\u00edticas (monarcas, lugartenientes generales del Reino de Valencia o gobernadores ultra Sexonam) y de las eclesi\u00e1sticas (obispos, provisores y cabildo cartaginenses, o ejecutores de comisiones apost\u00f3licas) llev\u00f3 en no pocas ocasiones a los oriolanos -tanto cl\u00e9rigos como laicos- a sufrir excomuniones e interdictos. Los cartaginenses tendieron, por norma, a defender sus intereses eclesi\u00e1sticos materiales y espirituales, y tambi\u00e9n las directrices pol\u00edticas de los monarcas castellanos, y ello les llev\u00f3 a chocar con las decisiones de los soberanos de la Corona de Arag\u00f3n, que acostumbraron a ser diferentes, si no contrarias. La mayor parte de estos conflictos se dieron durante los reinados de Pedro IV el Ceremonioso, Mart\u00edn I el Humano y Alfonso V el Magn\u00e1nimo. Y finalizaron en la \u00e9poca de los Reyes Cat\u00f3licos, como consecuencia de la uni\u00f3n de las dos coronas.<\/p>\n<p align=\"JUSTIFY\">Las autoridades cartaginenses tambi\u00e9n toparon con relativa frecuencia con el Consell de Orihuela. Los conflictos tuvieron principalmente dos \u00e1mbitos de discordia: el jurisdiccional y el econ\u00f3mico.<\/p>\n<p align=\"JUSTIFY\">Para comprender los roces jurisdiccionales, hemos de tener presente que en la sociedad bajomedieval y moderna, los cl\u00e9rigos gozaban del privilegio de contar con una jurisdicci\u00f3n particular, de modo que no pod\u00edan ser juzgados por ning\u00fan juez laico. En el obispado de Cartagena, la m\u00e1xima autoridad judicial a nivel eclesi\u00e1stico era el obispo, y tras \u00e9l, su primer ayudante, el provisor y vicario general.<\/p>\n<p align=\"JUSTIFY\">Los prelados cartaginenses -y sus delegados- se mostraron especialmente atentos a la hora de defender el r\u00e9gimen jurisdiccional separado de los tonsurados de toda la di\u00f3cesis, incluidos los del arciprestazgo de Orihuela y los vicariatos de Elche, Ayora y Alicante. Por ello, actuaron en\u00e9rgicamente siempre que los mun\u00edcipes oriolanos procedieron contra eclesi\u00e1sticos, y no dudaron un \u00e1pice en utilizar las censuras espirituales con la intenci\u00f3n de amedrentar a los citados mandatarios y hacerles desistir de su prop\u00f3sito de juzgar o penar a los cl\u00e9rigos encausados. Y se comportaron de id\u00e9ntica manera en los momentos en que tuvieron que defender otros privilegios eclesi\u00e1sticos, como el derecho de asilo, que tambi\u00e9n fue violado con cierta frecuencia.<\/p>\n<p align=\"JUSTIFY\">Otro tipo de conflictos de car\u00e1cter jurisdiccional tuvo su origen en los abusos de poder que las autoridades cartaginenses cometieron sobre los oriolanos que citaban para dirimir sus causas eclesi\u00e1sticas en los tribunales episcopales, sitos en Murcia.<\/p>\n<p align=\"JUSTIFY\">Tras la inclusi\u00f3n de Orihuela en la Corona de Arag\u00f3n, los monarcas prohibieron con fueros que sus habitantes saliesen del Reino de Valencia a resolver sus pleitos. Y el Consell de la poblaci\u00f3n del Bajo Segura defendi\u00f3 dichas leyes siempre que las consider\u00f3 atacadas. Ello choc\u00f3 en repetidas ocasiones con la intenci\u00f3n de los mandatarios espirituales de que los diocesanos acudiesen a los juzgados murcianos, y supuso un buen n\u00famero de rompimientos.<\/p>\n<p align=\"JUSTIFY\">La actitud municipal no impidi\u00f3, no obstante, que muchos oriolanos se personasen en los citados tribunales. Y all\u00ed sufrieron m\u00faltiples contratiempos. Dado que los oficiales episcopales no sol\u00edan conocer el valenciano, los oriolanos ten\u00edan que defenderse en castellano, lengua que muy pocos hablaban con fluidez. Adem\u00e1s, cuando se ten\u00edan que enfrentar con murcianos, \u00e9stos gozaban de un trato de favor, y con una frecuencia extra\u00f1amente habitual eran beneficiados con sentencias favorables. Ello significaba que los oriolanos ten\u00edan que pagar las costas judiciales, y las tasas que hab\u00edan de abonar eran cuatro o cinco veces superiores a las que ten\u00edan que satisfacer los pobladores de Murcia.<\/p>\n<p align=\"JUSTIFY\">Las autoridades de Orihuela quisieron solucionar estos abusos de poder de dos maneras. En un primer momento, trataron de conseguir una relativa independencia jurisdiccional y, por ello, suplicaron a diversos reyes y papas que les permitiesen disponer de un vicario general particular, que tuviese la facultad de tratar en la misma capital del Bajo Segura todos los pleitos eclesi\u00e1sticos que se suscitasen en la parte de la di\u00f3cesis perteneciente al Reino de Valencia. No obstante, posteriormente se dieron cuenta de que la soluci\u00f3n m\u00e1s efectiva para evitar los desmanes y las injerencias de los obispos y los oficiales cartaginenses era la independencia total y, a partir de ese momento, mostraron un mayor inter\u00e9s por lograr la creaci\u00f3n del obispado de Orihuela.<\/p>\n<p align=\"JUSTIFY\">Por otra parte, los mun\u00edcipes oriolanos tambi\u00e9n tuvieron conflictos con las autoridades cartaginenses por cuestiones econ\u00f3micas. Los prelados y sus oficiales defendieron las exenciones fiscales del clero y sancionaron con censuras los sucesivos intentos municipales de conseguir que los cl\u00e9rigos de la poblaci\u00f3n contribuyesen mediante el pago de impuestos -como la sisa- en los gastos de defensa y de obras p\u00fablicas (reparaci\u00f3n de muros, valles, fuentes, puentes y caminos).<\/p>\n<p align=\"JUSTIFY\">Asimismo, los citados mandatarios espirituales trataron de acceder a la percepci\u00f3n o, al menos, la administraci\u00f3n de las rentas de las f\u00e1bricas de las iglesias de Orihuela y su t\u00e9rmino. Dichos apetecibles frutos -tambi\u00e9n llamados tercios diezmos- pertenec\u00edan en origen a la Corona y, en virtud de diferentes privilegios, fueron concedidos a la corporaci\u00f3n municipal, con el prop\u00f3sito de que fuesen aplicados a la construcci\u00f3n y reparaci\u00f3n de los citados templos. Los prelados, influidos por el cabildo de Cartagena, trataron de hacerse con ellos o con su gesti\u00f3n de diferentes maneras: prohibiendo que los fabriqueros fuesen laicos, acusando a los mun\u00edcipes de negligencia o malversaci\u00f3n de fondos ante los lugartenientes generales del Reino de Valencia, o, incluso, amenazando con censuras a cuantos se opusiesen a su percepci\u00f3n.<\/p>\n<p align=\"JUSTIFY\">7.2.3. La falta de atenci\u00f3n pastoral a los diocesanos del Reino de Valencia por parte de los prelados cartaginenses.<\/p>\n<p align=\"JUSTIFY\">La situaci\u00f3n de abandono espiritual que sufrieron end\u00e9micamente los diocesanos de Orihuela y su t\u00e9rmino por parte de los mitrados cartaginenses y sus vicarios generales tuvo diferentes manifestaciones y fue motivada por un conjunto de factores interrelacionados, que podemos agrupar en varias categor\u00edas:<\/p>\n<ul>\n<li>7.2.3.1. Las consecuencias de la propia configuraci\u00f3n interna de la di\u00f3cesis.<\/li>\n<li>7.2.3.2. Los problemas derivados de decisiones de la Sede Apost\u00f3lica.<\/li>\n<li>7.2.3.3. La influencia del propio Pleito del Obispado.<\/li>\n<\/ul>\n<p align=\"JUSTIFY\">7.2.3.1. Las consecuencias de la propia configuraci\u00f3n interna de la di\u00f3cesis.<\/p>\n<p align=\"JUSTIFY\">Tras la restauraci\u00f3n del obispado de Cartagena, su di\u00f3cesis qued\u00f3 conformada por vastos territorios que, seg\u00fan la exposici\u00f3n de D. Diego de Comontes, fueron articulados en diferentes unidades espirituales: los oficialatos de Murcia, Cartagena y Lorca, los arciprestazgos de Orihuela, Villena, Chinchilla y Hu\u00e9scar, y los vicariatos de Alicante, Elche, Ayora, Hell\u00edn, Segura, Jorquera y Albacete. Adem\u00e1s, tambi\u00e9n quedaron dentro de los l\u00edmites diocesanos diferentes localidades de encomienda de varias \u00f3rdenes militares. Diversos testimonios de la \u00e9poca hac\u00edan alusi\u00f3n al gran tama\u00f1o de la di\u00f3cesis, que abarcaba tierras comprendidas en una l\u00ednea de 78 leguas, de las cuales 22 correspond\u00edan a los territorios sitos dentro de los l\u00edmites del Reino de Valencia.<\/p>\n<p align=\"JUSTIFY\">La magnitud del obispado, conjugada con otro decisivo factor, la dificultad de las comunicaciones intradiocesanas, que hac\u00eda bastante inc\u00f3modos y arriesgados los desplazamientos (tanto por la naturaleza del terreno como por el riesgo de sufrir asaltos o, incluso, secuestros), impidi\u00f3 a los mitrados proporcionar la adecuada atenci\u00f3n espiritual a todos sus diocesanos, desde los mismos tiempos fundacionales.<\/p>\n<p align=\"JUSTIFY\">Adem\u00e1s, junto a dichas contrariedades, el elevado y creciente n\u00famero de habitantes que viv\u00edan en las diferentes localidades de la di\u00f3cesis, contribuy\u00f3 al citado abandono pastoral. Y a\u00fan m\u00e1s, sirvi\u00f3 a los oriolanos como doble pretexto reivindicativo en sus suplicaciones episcopales ante los diferentes papas y reyes: ex una, porque la poblaci\u00f3n residente en la Gobernaci\u00f3n ultra Sexonam y la zona de Ayora era superior a la de otros obispados, como Jaca o Barbastro, y, por tanto, suficiente para tener un obispado propio; y ex alia, porque m\u00e1s de la tercera parte de dichos pobladores eran moriscos, y la falta de vigilancia espiritual supon\u00eda, adem\u00e1s de una mancha para la Iglesia, la p\u00e9rdida de un resorte de control sobre dicha poblaci\u00f3n.<\/p>\n<p align=\"JUSTIFY\">7.2.3.2. Los problemas derivados de decisiones de la Sede Apost\u00f3lica.<\/p>\n<p align=\"JUSTIFY\">Algunas decisiones de los romanos pont\u00edfices tambi\u00e9n contribuyeron de una manera m\u00e1s o menos directa o consciente al abandono pastoral que sufrieron los diocesanos de Orihuela y su \u00e1rea de influencia.<\/p>\n<p align=\"JUSTIFY\">El nombramiento de prelados que raramente pisaron las tierras de la di\u00f3cesis, como D. Juan Mart\u00ednez Sil\u00edceo, o de otros que jam\u00e1s residieron, como Rodrigo de Borja o Mateo Lang, provoc\u00f3 generalmente esta desatenci\u00f3n de las necesidades espirituales.<\/p>\n<p align=\"JUSTIFY\">Asimismo, la decisi\u00f3n de Inocencio IV de erigir el obispado cartaginense declar\u00e1ndolo exento, esto es, directamente dependiente de la Santa Sede influy\u00f3 tambi\u00e9n negativamente sobre las necesidades espirituales los diocesanos del Reino de Valencia. El hecho de no poder recurrir a ninguna autoridad eclesi\u00e1stica superior al obispo, que no fuese el pont\u00edfice, acentu\u00f3 el abandono pastoral e impidi\u00f3 a los oriolanos, en la mayor\u00eda de las ocasiones, que dispusiesen de una v\u00eda jur\u00eddica inmediata para reclamar contra los frecuentes abusos de poder espiritual murcianos. Dicha circunstancia cambi\u00f3 en beneficio de la Iglesia de Orihuela en 1492, cuando Inocencio VIII dictamin\u00f3 que las di\u00f3cesis de Cartagena y Mallorca, que hasta esa fecha hab\u00edan sido exentas, pasasen a ser sufrag\u00e1neas de la nueva metr\u00f3poli valentina. La novedad constituy\u00f3 todo un alivio para las autoridades de la poblaci\u00f3n del Bajo Segura puesto que, adem\u00e1s de reducir considerablemente los gastos y la duraci\u00f3n de las embajadas, les ofreci\u00f3 la posibilidad de solicitar ayuda a un superior \u00abregn\u00edcola\u00bb, que, en teor\u00eda, hab\u00eda de ser m\u00e1s sensible a sus problemas y reivindicaciones espirituales que el sumo pont\u00edfice.<\/p>\n<p align=\"JUSTIFY\">7.2.3.3. La influencia del propio Pleito del Obispado.<\/p>\n<p align=\"JUSTIFY\">Las continuas tensiones motivadas por las reclamaciones episcopales oriolanas fueron otro factor que contribuy\u00f3 a distanciar progresivamente las relaciones de los habitantes de la Gobernaci\u00f3n con los obispos y sus oficiales.<\/p>\n<p align=\"JUSTIFY\">Por otra parte, como hemos apuntado, la falta de atenci\u00f3n a las necesidades espirituales de la poblaci\u00f3n de Orihuela y su distrito se hizo evidente en diferentes manifestaciones:<\/p>\n<p align=\"JUSTIFY\">-En el reducido n\u00famero de actuaciones del Santo Oficio cartaginense.<\/p>\n<p align=\"JUSTIFY\">-En la persistente falta de un vicario general espec\u00edfico, que hiciese m\u00e1s efectiva la autoridad espiritual en dicha zona.<\/p>\n<p align=\"JUSTIFY\">-En la pr\u00e1ctica inexistencia de visitas pastorales de los obispos.<\/p>\n<p align=\"JUSTIFY\">-En la pasividad que mostraron generalmente los prelados para tomar posesi\u00f3n en las iglesias principales de las ciudades, villas y lugares de la parte del Reino de Valencia -valgan los ejemplos de Juan Daza, Mateo Lang o Esteban de Almeyda-.<\/p>\n<p align=\"JUSTIFY\">-En el escaso inter\u00e9s que demostraron tener los mitrados, salvo honrosas excepciones, por fomentar las devociones en las tierras situadas al este de la frontera castellano-aragonesa; algo que se puso claramente de manifiesto en su casi nula participaci\u00f3n en los actos de culto o en las manifestaciones p\u00fablicas de piedad que ten\u00edan lugar en ellas, pues muy pocas veces asistieron a las misas del gallo o las celebraciones de la Semana Santa que tanto auge ten\u00edan en la capital de la Gobernaci\u00f3n ultra Sexonam.<\/p>\n<p align=\"JUSTIFY\">-En la escasa vigilancia de la educaci\u00f3n y de las pr\u00e1cticas espirituales de los fieles que, en muchas ocasiones, rayaban la superstici\u00f3n y la herej\u00eda a causa de la ignorancia.<\/p>\n<p align=\"JUSTIFY\">-Y, por \u00faltimo, en el inexistente control sobre las ense\u00f1anzas y los sermones de los curas.<\/p>\n<p align=\"JUSTIFY\">7.2.4. La percepci\u00f3n por el obispo y el cabildo de Cartagena de rentas procedentes de la parte de la di\u00f3cesis perteneciente al Reino de Valencia.<\/p>\n<p align=\"JUSTIFY\">El \u00faltimo fundamento en que sustentaron la Iglesia y la ciudad de Orihuela sus reivindicaciones episcopales fue la salida anual de una considerable cantidad de dinero y de productos del campo de las tierras de la Gobernaci\u00f3n del Reino de Valencia m\u00e1s all\u00e1 de Jijona, en direcci\u00f3n hacia Murcia, en beneficio de las mensas episcopal y capitular cartaginenses.<\/p>\n<p align=\"JUSTIFY\">De los diezmos recaudados anualmente en el campo de Orihuela y en las tierras de su Gobernaci\u00f3n, una cantidad oscilante entre el 33% y la totalidad de las rentas iba a parar a las arcas de los obispos cartaginenses y de los can\u00f3nigos de la catedral murciana. En muchas ocasiones, cuando los enfrentamientos con las autoridades eclesi\u00e1sticas del obispado se recrudec\u00edan, y los entredichos ca\u00edan sobre la ciudad del Bajo Segura, era pr\u00e1ctica frecuente de los mun\u00edcipes, bien por iniciativa propia, o bien siguiendo \u00f3rdenes reales, responder a dichas censuras con la confiscaci\u00f3n de tales frutos, lo que enfurec\u00eda a\u00fan m\u00e1s a los murcianos. Con la creaci\u00f3n del obispado, el Consell pretend\u00eda evitar que todo ese dinero, y todo ese trigo -que tan necesario era para el consumo de los habitantes de Orihuela-, no fuesen a enriquecer y a alimentar las ambiciones del obispo y los can\u00f3nigos murcianos.<\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\"><strong>7.3. La oposici\u00f3n murciana a la escisi\u00f3n de la di\u00f3cesis de Cartagena.<\/strong><\/p>\n<p align=\"JUSTIFY\">Desde el mismo inicio de las reivindicaciones oriolanas, el cabildo de Cartagena y, por influencia suya, los obispos se opusieron de plano a la segregaci\u00f3n de la di\u00f3cesis y al proyecto de creaci\u00f3n del obispado. \u00c9ste les supon\u00eda intolerables perjuicios desde m\u00faltiples perspectivas. A nivel jurisdiccional, la dismembraci\u00f3n les causaba una notabil\u00edsima p\u00e9rdida de poder. En el plano honor\u00edfico, un inmediato y notorio descenso del gran prestigio hist\u00f3rico de la sede cartaginense seguir\u00eda inevitablemente a la mengua de un buen n\u00famero de territorios, de una cantidad considerable de fieles y de una veintena de iglesias. Y, por \u00faltimo, desde el punto de vista econ\u00f3mico, que seg\u00fan nuestra opini\u00f3n , y pese a la importancia de todos los dem\u00e1s condicionantes, era el que m\u00e1s les afectaba a los prelados, la fundaci\u00f3n del obispado oriolano les hab\u00eda de suponer una disminuci\u00f3n aproximada del 30% de sus ingresos anuales.<\/p>\n<p align=\"JUSTIFY\">Por ello, ni el cabildo ni los mitrados mostraron jam\u00e1s la m\u00e1s m\u00ednima dejadez a la hora de defender sus intereses. Durante los siglos XIV y XV fundamentaron su oposici\u00f3n en el apoyo de los reyes de Castilla, que tradicionalmente contaron con una mayor influencia que los de Arag\u00f3n sobre los sucesivos papas. \u00bfPor qu\u00e9? Entre otras razones m\u00e1s coyunturales, porque los monarcas de la Corona aragonesa ten\u00edan amplias posesiones en el sur de Italia, el reino de N\u00e1poles, y uno de los objetivos b\u00e1sicos de su pol\u00edtica exterior era extenderlas hacia el norte, en direcci\u00f3n a los territorios de los Estados Pontificios. Los papas romanos ve\u00edan, por tanto, a los monarcas de la Corona de Arag\u00f3n como potenciales enemigos o, al menos, como inquietantes vecinos, y por ello, prefer\u00edan beneficiar con sus favores a los reyes castellanos. Teniendo en cuenta esta tendencia general, cada vez que los oriolanos trataron de conseguir la fundaci\u00f3n del obispado, los murcianos recurrieron a los monarcas de Castilla y, con su intervenci\u00f3n, lograron evitar la divisi\u00f3n de la di\u00f3cesis de Cartagena.<\/p>\n<p align=\"JUSTIFY\">Los autoridades oriolanas \u00fanicamente lograron \u00e9xitos ef\u00edmeros en coyunturas muy favorables o poco estables:<\/p>\n<p align=\"JUSTIFY\">-En primer lugar, consiguieron la promoci\u00f3n a Colegial de la iglesia del Salvador (1413) aprovech\u00e1ndose del inter\u00e9s que el monarca entronizado tras el Compromiso de Caspe, el castellano Fernando I, mostr\u00f3 por congraciarse con sus nuevos s\u00fabditos.<\/p>\n<p align=\"JUSTIFY\">-Unos a\u00f1os m\u00e1s tarde, en 1430, lograron la instituci\u00f3n del primer vicariato general gracias al apoyo de los estamentos de los reinos de la Corona de Arag\u00f3n en las Cortes de Traiguera, a la intervenci\u00f3n de Alfonso V el Magn\u00e1nimo, y al favor de un influyente eclesi\u00e1stico, D. Alfonso de Borja, que con el tiempo llegar\u00eda a ocupar el solio pontificio con el nombre de Calixto III.<\/p>\n<p align=\"JUSTIFY\">-Posteriormente, en 1442, consiguieron que los padres del Concilio de Basilea y el antipapa F\u00e9lix V decretasen la primera creaci\u00f3n del obispado, sin el consentimiento del romano pont\u00edfice, Eugenio IV. Ello marc\u00f3 su perentoria existencia ya que, acabado el per\u00edodo de irregularidad, las disposiciones conciliares fueron anuladas y Alfonso V, que hab\u00eda apoyado abiertamente a los rebeldes, busc\u00f3 la reconciliaci\u00f3n con Eugenio IV. Y aunque le solicit\u00f3 la confirmaci\u00f3n del obispado, el papa prefiri\u00f3 premiar la fidelidad de Juan II de Castilla y decret\u00f3 su revocaci\u00f3n.<\/p>\n<p align=\"JUSTIFY\">-La consecuci\u00f3n del segundo vicariato general (en 1461) fue el hito m\u00e1s sorprendente pues se gest\u00f3 como consecuencia de la pol\u00edtica pacifista del rey castellano, Enrique IV el Impotente, y de la disposici\u00f3n del obispo Lope de Rivas y del propio cabildo de Cartagena a buscar una soluci\u00f3n concordada al Pleito. De cualquier forma, el logro tambi\u00e9n fue pasajero, pues la voluntad cartaginense cambi\u00f3 tras la muerte del segundo vicario, Francisco Desprats, y el nombramiento del nuevo oficial se retras\u00f3 durante varios episcopados.<\/p>\n<p align=\"JUSTIFY\">Tras la uni\u00f3n de las Coronas y, sobre todo, despu\u00e9s del retorno de Fernando el Cat\u00f3lico al gobierno de Castilla, las circunstancias del Pleito del Obispado cambiaron considerablemente. A partir de este momento, oriolanos y murcianos tuvieron que acudir a los mismos monarcas para defender sus respectivas posiciones en torno a la cuesti\u00f3n del obispado. Entonces, el \u00e9xito de unos u otros pas\u00f3 a depender, am\u00e9n de la voluntad de los soberanos, de las influencias con las que contasen, y tambi\u00e9n del dinero que pudiesen gastar en el env\u00edo de embajadas a la cortes real y pontificia, y en sobornos y propinas a los funcionarios y personajes influyentes de ambas administraciones. En todo momento, los murcianos llevaron ventaja en los dos puntos -apoyos y liquidez-. Se aprovecharon del mayor peso espec\u00edfico de Castilla en la Monarqu\u00eda Hisp\u00e1nica y no tuvieron que sufrir una crisis econ\u00f3mica tan aguda como la que sobrevino a Orihuela a ra\u00edz de la represi\u00f3n de la German\u00eda. Y ambos factores les ayudaron durante los reinados del propio Fernando el Cat\u00f3lico y de Carlos I a bloquear el progreso del proyecto episcopal de sus vecinos y rivales.<\/p>\n<p align=\"JUSTIFY\">No obstante, no fueron estos dos medios, la consecuci\u00f3n del favor de los monarcas y las derramas monetarias, los \u00fanicos que utilizaron para refrenar las ansias independentistas de sus contrincantes. Tambi\u00e9n trataron de hacerles desistir de sus prop\u00f3sitos, como ya hemos apuntado, imponi\u00e9ndoles todo tipo de censuras eclesi\u00e1sticas. Los momentos en que los oriolanos se acercaron m\u00e1s a su objetivo de lograr y afianzar su independencia espiritual coincidieron con los de mayor actividad punitiva cartaginense. No obstante, la voluntad oriolana fue tan inconmovible que los habitantes de la ciudad -tanto laicos como cl\u00e9rigos- soportaron en varias ocasiones entredichos que se mantuvieron vigentes duraron a\u00f1os o incluso lustros.<\/p>\n<p align=\"JUSTIFY\">La tenacidad oriolana lleg\u00f3, en ocasiones, a colmar la paciencia de los murcianos. Y \u00e9stos debieron llegar a tal grado de desquiciamiento que optaron -de una manera tan poco inteligente como carente de escr\u00fapulos- por recurrir al uso de la violencia con la intenci\u00f3n de forzarles a claudicar. Estas pr\u00e1cticas fueron muy frecuentes a principios del Quinientos, tras la segunda creaci\u00f3n del obispado. Pongamos algunos ejemplos.<\/p>\n<p align=\"JUSTIFY\">Tras la toma de posesi\u00f3n por poderes de Mateo Lang, las autoridades civiles y eclesi\u00e1sticas de Murcia realizaron dos acciones que les hicieron perder todos los apoyos y favores que hab\u00edan logrado ganar poco a poco, gracias a su efectivo esfuerzo diplom\u00e1tico ante Fernando el Cat\u00f3lico y Le\u00f3n X. Por una parte, mandaron cavar un \u00abriacho\u00bb, una especie de cauce alternativo para el r\u00edo, y consiguieron desviar su curso e inundar los campos y las heredades de los vecinos de la parte m\u00e1s meridional del Reino de Valencia, causando algunas muertes y la ruina de la pr\u00e1ctica totalidad de los cultivos. Y por otra, y a\u00fan m\u00e1s grave, provocaron un enfrentamiento armado que pudo hacer peligrar la unidad de la Monarqu\u00eda. M\u00e1s de un millar de murcianos armados efectuaron varias incursiones por las tierras de la Gobernaci\u00f3n ultra Sexonam, e intentaron invadir tanto la ciudad de Orihuela como su t\u00e9rmino, provocando que todo el Reino de Valencia se levantara en armas contra ellos, y causando nuevos da\u00f1os a sus maltrechos habitantes.<\/p>\n<p align=\"JUSTIFY\">Posteriormente, el marqu\u00e9s de los V\u00e9lez tambi\u00e9n protagoniz\u00f3 un par de incidentes, de inmerecido recuerdo. Satisfaciendo los deseos de los referidos mandatarios murcianos, en 1518 reuni\u00f3 una considerable milicia y cay\u00f3 sobre la capital del Bajo Segura y su huerta, causando incontables destrozos. La r\u00e1pida respuesta oriolana le oblig\u00f3 a retirarse. Pero el d\u00eda de Navidad de dicho a\u00f1o, volvi\u00f3 a atacar la ciudad mientras se celebraban los oficios divinos en la iglesia del Salvador, y perpetr\u00f3 una nueva razia, robando y quemando casas y heredades, cortando cientos de \u00e1rboles, y terminando de arruinar los campos de cultivo de la huerta. Y m\u00e1s tarde, en 1521, encabez\u00f3 las tropas reales-nobiliarias que vencieron a las agermanadas y saquearon Orihuela, y forz\u00f3 a sus autoridades laicas y eclesi\u00e1sticas a jurar la obediencia al obispo y el cabildo cartaginenses, reconociendo as\u00ed la revocaci\u00f3n del obispado.<\/p>\n<p align=\"JUSTIFY\">La violencia estuvo presente en las relaciones entre los mandatarios espirituales y los oriolanos. En la d\u00e9cada de los &#8217;50 del XVI los abusos de poder de los fiscales episcopales causaron grandes alborotos en la poblaci\u00f3n del Bajo Segura. Y en sentido contrario, los habitantes de la ciudad del Bajo Segura tambi\u00e9n tuvieron reacciones vehementes cuando los murcianos trataron de poner en vigor los diferentes breves revocatorios de la erecci\u00f3n episcopal de Julio II -recordemos el suceso que concluy\u00f3 con el destierro de D. Luis de Soler en 1520-; o en los diferentes momentos en que trataron de perjudicar los intereses oriolanos en la lite -como cuando enviaron a los inquisidores del obispado de Cartagena a ejercer el santo oficio como tales, o cuando procedieron al nombramiento del citado D. Luis de Soler como administrador y visitador del obispado-.<\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\"><strong>7.4. El apoyo real a las aspiraciones episcopales y la creaci\u00f3n del obispado de Orihuela.<\/strong><\/p>\n<p align=\"JUSTIFY\">La oposici\u00f3n cartaginense al proyecto episcopal oriolano puso de manifiesto, desde el mismo momento de su gestaci\u00f3n, que el apoyo real ante la Santa Sede hab\u00eda de convertirse en el factor m\u00e1s determinante de su \u00e9xito.<\/p>\n<p align=\"JUSTIFY\">Dicha circunstancia nos lleva a plantearnos una serie de cuestiones. \u00bfApoyaron todos los monarcas de la Corona de Arag\u00f3n las reivindicaciones oriolanas?\u00bfPusieron todos el mismo inter\u00e9s? \u00bfC\u00f3mo reaccionaron los reyes de la Monarqu\u00eda Hisp\u00e1nica ante el proyecto? \u00bfSe opuso alguno de ellos? Y, por \u00faltimo, \u00bfpor qu\u00e9 tardaron los tenaces oriolanos casi dos siglos en conseguir la creaci\u00f3n del obispado?<\/p>\n<p align=\"JUSTIFY\">Al contrario de lo que escribieron Gisbert y sus seguidores, el sentimiento independentista no naci\u00f3 a mediados del Trescientos, como consecuencia de los primeros roces entre el Consell de Orihuela y las autoridades cartaginenses.<\/p>\n<p align=\"JUSTIFY\">Tras la Guerra de los Dos Pedros, la imagen de la entonces villa del Bajo Segura sali\u00f3 enormemente fortalecida por la heroica resistencia de sus habitantes al empuje castellano. Su comportamiento valeroso y fiel les granje\u00f3 el favor de Pedro IV el Ceremonioso, y el de sus inmediatos sucesores; una disposici\u00f3n que trataron de aprovechar siempre que tuvieron que hacer llegar sus demandas a los soberanos. Pues bien, pese a dicha favorabil\u00edsima circunstancia, las autoridades oriolanas no llegaron a pedirle a Pedro IV que intercediese ante la Santa Sede en aras a la creaci\u00f3n del obispado. El Ceremonioso instituy\u00f3 la Gobernaci\u00f3n del Reino de Valencia m\u00e1s all\u00e1 de Jijona y fij\u00f3 su capital en Orihuela, y les prometi\u00f3 que la villa no ser\u00eda jam\u00e1s separada de la Corona de Arag\u00f3n. Por ello, consideramos que el sentimiento independentista a\u00fan no hab\u00eda fraguado en la conciencia oriolana. De otra manera, sus mandatarios le habr\u00edan hecho llegar al monarca sus reivindicaciones.<\/p>\n<p align=\"JUSTIFY\">El proyecto episcopal se hizo realidad unos a\u00f1os despu\u00e9s, como consecuencia, por una parte, de las continuas censuras eclesi\u00e1sticas con que castigaron los obispos Vargas y Gimiel a los habitantes de Orihuela y, por otra, del sentimiento nacionalista surgido tras la contienda de los Dos Pedros. La primera suplicaci\u00f3n real que hemos logrado constatar tuvo lugar en 1383, seg\u00fan acert\u00f3 a se\u00f1alar Gea. En dicha fecha, las autoridades de la poblaci\u00f3n del Bajo Segura le elevaron a Pedro IV una primera suplicaci\u00f3n, poco argumentada, que no tuvo ninguna repercusi\u00f3n ante la Santa Sede. El proyecto estaba a\u00fan en mantillas.<\/p>\n<p align=\"JUSTIFY\">Dicha situaci\u00f3n, no obstante, vari\u00f3 r\u00e1pidamente. Con el paso de los a\u00f1os, el creciente inter\u00e9s por la independencia espiritual acuci\u00f3 a las autoridades oriolanas a madurar el plan. Y en el reinado de Mart\u00edn I el Humano experiment\u00f3 un desarrollo tal que logr\u00f3 atraer la atenci\u00f3n del soberano. El citado monarca lleg\u00f3 a conocer bien las dificultades que entra\u00f1aban cotidianamente las relaciones eclesi\u00e1sticas entre oriolanos y murcianos, y se mostr\u00f3 especialmente celoso de los intereses de sus s\u00fabditos y del predominio de su poder temporal sobre el espiritual de los obispos de Cartagena. En este sentido, despach\u00f3 diferentes provisiones contrarias a la jurisdicci\u00f3n eclesi\u00e1stica ordinaria y, lo que es m\u00e1s importante, solicit\u00f3 a la Santa Sede la erecci\u00f3n del obispado. No obstante, el destino jug\u00f3 en contra de los presupuestos secesionistas puesto que cuando el rey aragon\u00e9s ya ten\u00eda apalabrada la instituci\u00f3n episcopal con Gregorio XII, el sumo pont\u00edfice falleci\u00f3 y el proyecto qued\u00f3 paralizado.<\/p>\n<p align=\"JUSTIFY\">Las aspiraciones independentistas volvieron a hallar una coyuntura favorable tras el acceso al trono de la Corona del castellano Fernando I de Antequera, tras el Compromiso de Caspe. La voluntad del monarca por congraciarse con sus s\u00fabditos le llev\u00f3 a apoyar las tesis segregacionistas. Su favor, la buena disposici\u00f3n del Papa Luna, Benedicto XIII -aragon\u00e9s de nacimiento-, y la habilidad diplom\u00e1tica de Miguel Mols\u00f3s fueron los factores que permitieron la promoci\u00f3n a colegial de la arciprestal del Salvador de Orihuela. El logro no colm\u00f3 las expectativas oriolanas, por lo que siguieron trabajando para lograr la creaci\u00f3n del obispado.<\/p>\n<p align=\"JUSTIFY\">No obstante, tras la muerte de Fernando I en 1416, su sucesor, Alfonso V el Magn\u00e1nimo, se plante\u00f3 favorecer la conclusi\u00f3n del Cisma de Occidente. Por ello, le neg\u00f3 la obediencia a Benedicto XIII y ah\u00ed terminaron las esperanzas oriolanas de conseguir del antipapa el objetivo episcopal. De todas maneras, el Magn\u00e1nimo fue uno de los reyes aragoneses que m\u00e1s favoreci\u00f3 la causa segregacionista.<\/p>\n<p align=\"JUSTIFY\">Tras la entronizaci\u00f3n del nuevo monarca, las autoridades oriolanas se afanaron por ponerle al corriente de los desmanes de los cl\u00e9rigos murcianos. Y desde entonces, Alfonso V se mostr\u00f3 siempre atento y dispuesto a defender los intereses de sus s\u00fabditos frente a los abusos cartaginenses -muy frecuentes a lo largo de los a\u00f1os de gobierno del obispo Bed\u00e1n-. Despach\u00f3 mandatos para blindar las rentas de las f\u00e1bricas o para censurar el ileg\u00edtimo trat\u00f3 jur\u00eddico que les dispensaban a los oriolanos los oficiales de los tribunales episcopales, y respondi\u00f3 a las censuras espirituales con sucesivas confiscaciones de rentas.<\/p>\n<p align=\"JUSTIFY\">No obstante, el Magn\u00e1nimo no tom\u00f3 conciencia real de la necesidad de la creaci\u00f3n del obispado independiente hasta que las autoridades oriolanas le solicitaron la erecci\u00f3n catedralicia de la Colegial del Salvador, o, en su defecto, la designaci\u00f3n de un vicario general for\u00e1neo, con poder espiritual sobre los fieles de la Gobernaci\u00f3n, en un nuevo marco, un \u00e1mbito muy concreto que se iba convertir en trascendental para la evoluci\u00f3n del Pleito del Obispado: las Cortes de la Corona de Arag\u00f3n, que en esta ocasi\u00f3n tuvieron lugar en Traiguera, entre 1429 y 1430.<\/p>\n<p align=\"JUSTIFY\">Abundando en esta cuesti\u00f3n, hemos de destacar que los mandatarios oriolanos trataron casi siempre de aprovechar la convocatoria de Cortes para reclamar la satisfacci\u00f3n de sus reivindicaciones espirituales. Las reuniones estamentarias se convirtieron en coyunturas especialmente favorables, pues les proporcionaron la posibilidad de presentar sus s\u00faplicas con el apoyo de los brazos de las naciones componentes de la Monarqu\u00eda, de manera que los reyes no pudiesen sino aceptar tales demandas si es que quer\u00edan conseguir sus subsidios.<\/p>\n<p align=\"JUSTIFY\">Por otra parte, tambi\u00e9n hemos de apostillar que el recurso a la suplicaci\u00f3n en las Cortes cobr\u00f3 una mayor trascendencia a partir del reinado de los Reyes Cat\u00f3licos, a ra\u00edz de la unificaci\u00f3n de las coronas de Castilla y Arag\u00f3n, pues Fernando el Cat\u00f3lico, Carlos I y Felipe II habr\u00edan a atender las importunaciones tanto del obispo y el cabildo de Cartagena, y la ciudad de Murcia, como de la Iglesia y la ciudad de Orihuela, y los ruegos elevados en las sesiones parlamentarias tendr\u00edan una mayor fuerza que las rutinarias representaciones en la corte, habitualmente localizada en territorio castellano.<\/p>\n<p align=\"JUSTIFY\">La suplicaci\u00f3n en las Cortes de Traiguera, conjugada con la intervenci\u00f3n de D. Alfonso de Borja y la suplicaci\u00f3n real, como ya indicamos, se tradujo en 1430 en la instituci\u00f3n pontificia de un vicariato general de Orihuela, que vino a aliviar los problemas que los oriolanos ven\u00edan end\u00e9micamente sufriendo en el plano de la jurisdicci\u00f3n eclesi\u00e1stica. La reacci\u00f3n murciana fue inmediata: las presiones castellanas a Eugenio IV no s\u00f3lo hicieron in\u00fatiles las ansias de Alfonso V de lograr la fundaci\u00f3n episcopal, sino que propiciaron la expedici\u00f3n de varios instrumentos revocatorios del vicariato; unos rescriptos que, por diversas circunstancias, no llegaron a tener efecto alguno.<\/p>\n<p align=\"JUSTIFY\">Poco despu\u00e9s, en 1437, Alfonso V hizo p\u00fablico su deseo de satisfacer los deseos de sus s\u00fabditos y, adem\u00e1s de erigir la villa de Orihuela en ciudad, prometi\u00f3 a sus habitantes que har\u00eda todo lo posible por lograr la creaci\u00f3n del obispado. Sin embargo, la cercan\u00eda de Eugenio IV al rey de Castilla y, consecuentemente, a las posturas murcianas, impidi\u00f3 entonces el progreso l\u00edcito del proyecto. De cualquier forma, ello no detuvo al Magn\u00e1nimo, ni mucho menos a los constantes oriolanos. El alineamiento del monarca con el rebelde Concilio de Basilea abri\u00f3 de nuevo las puertas a la erecci\u00f3n episcopal, y, efectivamente, \u00e9sta se convirti\u00f3 en una realidad a principios de 1542.<\/p>\n<p align=\"JUSTIFY\">La falta de legitimidad de las disposiciones conciliares marc\u00f3 su ef\u00edmera existencia. Acabado el per\u00edodo de irregularidad, Alfonso V decidi\u00f3 reconciliarse con el romano pont\u00edfice y aunque le solicit\u00f3 la confirmaci\u00f3n del obispado, el papa prefiri\u00f3 premiar la fidelidad de Juan II de Castilla y decret\u00f3 su revocaci\u00f3n.<\/p>\n<p align=\"JUSTIFY\">Esta adversidad no desanim\u00f3, empero, ni a los oriolanos ni al propio rey. Unos a\u00f1os m\u00e1s tarde, la insistencia de los segregacionistas movi\u00f3 de nuevo a Alfonso V a solicitar al pont\u00edfice la revisi\u00f3n del caso. Eugenio IV dio p\u00e1bulo a las s\u00faplicas reales y encarg\u00f3 a una comisi\u00f3n formada por varios curiales el estudio del expediente. No obstante, la muerte del sucesor de San Pedro paraliz\u00f3 sus planes y la derogaci\u00f3n sigui\u00f3 vigente.<\/p>\n<p align=\"JUSTIFY\">Tras el nombramiento del nuevo pont\u00edfice, Nicol\u00e1s V, Alfonso el Magn\u00e1nimo volvi\u00f3 a suplicar la revisi\u00f3n de la causa, pero de nuevo la influencia de Juan II de Castilla pudo m\u00e1s que los ruegos del monarca aragon\u00e9s, y en 1451, el papa confirm\u00f3 la anulaci\u00f3n del obispado.<\/p>\n<p align=\"JUSTIFY\">Dicha situaci\u00f3n se mantuvo hasta la muertes consecutivas de Juan II y Nicol\u00e1s V. Entonces advino una fant\u00e1stica coyuntura puesto que el rey de Castilla, Enrique IV el Impotente, opt\u00f3 por seguir una l\u00ednea pol\u00edtica pacifista y el solio pontificio pas\u00f3 a ser ocupado por un viejo aliado de la causa episcopal, D. Alfonso de Borja, Calixto III. Sin embargo, las esperanzas oriolanas se vinieron repentinamente abajo en 1458 al sorprenderles otros dos \u00f3bitos casi inmediatos, los de sus m\u00e1ximos valedores: Alfonso V y Calixto III.<\/p>\n<p align=\"JUSTIFY\">Recapitulando, podemos afirmar que el Magn\u00e1nimo trat\u00f3 por todos los medios factibles de conseguir para Orihuela la creaci\u00f3n del obispado. Y si no lo logr\u00f3 fue porque tanto Eugenio IV como Nicol\u00e1s V fueron m\u00e1s sensibles a las propuestas de Juan II de Castilla que a las suyas, y porque, tras conceder su apoyo a los rebeldes de Basilea, hubo de ceder a la voluntad de ambos pont\u00edfices, sin oponer obst\u00e1culo alguno, para no ver comprometidas sus relaciones con la Santa Sede. Por otra parte, tambi\u00e9n creemos que la muerte del monarca aragon\u00e9s y del papa Borja impidi\u00f3 la segunda erecci\u00f3n del obispado de Orihuela; una fundaci\u00f3n que, con toda probabilidad, podr\u00eda haber sido duradera.<\/p>\n<p align=\"JUSTIFY\">Durante el reinado de Juan II de Arag\u00f3n, la voluntad pacifista de Enrique IV el Impotente llev\u00f3 a oriolanos y murcianos a tratar de encontrar una soluci\u00f3n pactada al Pleito del Obispado. Siguiendo las directrices de los monarcas, las dos partes fueron cediendo en sus pretensiones hasta acordar la instituci\u00f3n del segundo vicariato general for\u00e1neo. La concordia de Logro\u00f1o propici\u00f3 un per\u00edodo de tranquilidad espiritual sin precedentes en el obispado de Cartagena.<\/p>\n<p align=\"JUSTIFY\">Durante casi tres d\u00e9cadas, las aspiraciones episcopales quedaron m\u00e1s o menos soterradas. No obstante, en 1490, reinando ya Fernando el Cat\u00f3lico, el fallecimiento del vicario Francisco Desprats resucit\u00f3 las discordias y, con ello, el inter\u00e9s independentista. El cabildo de Cartagena decidi\u00f3 incumplir las estipulaciones del acuerdo logro\u00f1\u00e9s y, contando con el apoyo de sucesivos mitrados -D. Rodrigo de Borja (futuro Alejandro VI), D. Bernardino de Carvajal y D. Juan de Medina- y, sobre todo, de sus provisores, logr\u00f3 aplazar el nombramiento de su sucesor. Los oriolanos denunciaron la situaci\u00f3n ante el monarca Cat\u00f3lico, el metropolitano valentino y la Sede Apost\u00f3lica y, por fin, en 1498, consiguieron que los murcianos se plegasen a las disposiciones de la concordia y aceptasen el nombramiento de Pedro Argensola.<\/p>\n<p align=\"JUSTIFY\">Fernando II de Arag\u00f3n sigui\u00f3 con atenci\u00f3n los enfrentamientos espirituales entre murcianos y oriolanos pues pronto se dio cuenta de que pod\u00edan convertirse en un elemento desestabilizador del proyecto de uni\u00f3n de las coronas. Por ello, en todo momento trat\u00f3 de conseguir que los cartaginenses se aviniesen a cumplir la Concordia de Logro\u00f1o. Y si tuvieron que pasar m\u00e1s de ocho a\u00f1os para que claudicaran fue por la tenacidad que en todo momento mostraron, por el car\u00e1cter absentista y fugaz de los prelados que ci\u00f1eron la mitra y por el car\u00e1cter parcial de sus provisores.<\/p>\n<p align=\"JUSTIFY\">La soluci\u00f3n de la cuesti\u00f3n vicarial no signific\u00f3, empero, el fin de las discordias. La elecci\u00f3n de D. Juan Daza como obispo de Cartagena, en 1502, supuso un nuevo punto de inflexi\u00f3n en los enfrentamientos. La actitud del nuevo prelado y sus oficiales origin\u00f3 nuevas y grav\u00edsimas discordias, que no pudo pasar por alto Fernando el Cat\u00f3lico. En connivencia con el cabildo cartaginense, Daza se neg\u00f3 a tomar posesi\u00f3n de su cargo en las localidades diocesanas sitas al otro lado de la frontera por consideraciones nacionalistas, se neg\u00f3 a aceptar la autoridad del vicario general de Orihuela, y se dedic\u00f3 a encarcelar a cuantos emisarios le enviaron los mandatarios civiles y eclesi\u00e1sticos de la ciudad del Bajo Segura. Su intolerable comportamiento movi\u00f3 a las citadas autoridades a suplicarle al monarca la creaci\u00f3n del obispado en 1503. Fernando reflexion\u00f3 sobre la situaci\u00f3n, evalu\u00f3 las consecuencias pol\u00edticas que conllevar\u00eda la escisi\u00f3n de la di\u00f3cesis cartaginense y para no ofuscar a los castellanos o a su propia esposa, intent\u00f3 solucionar el problema de una manera coyuntural y no estructural. Evit\u00f3 la segregaci\u00f3n, promovi\u00f3 la traslaci\u00f3n del problem\u00e1tico Juan Daza al obispado de C\u00f3rdoba y lo sustituy\u00f3 por un prelado de talante m\u00e1s diplom\u00e1tico y conciliador, D. Juan Fern\u00e1ndez de Velasco.<\/p>\n<p align=\"JUSTIFY\">El episcopado del nuevo mitrado fue extra\u00f1amente pac\u00edfico, sobre todo, si tenemos en cuenta los repentinos giros que dio la Monarqu\u00eda Hisp\u00e1nica tras las muertes de Isabel I de Castilla y Felipe el Hermoso. La labor de Velasco al frente de la di\u00f3cesis calm\u00f3 las discordias, pero, por supuesto, no las hizo desaparecer. Las autoridades oriolanas siguieron insisti\u00e9ndole al Fernando el Cat\u00f3lico que la soluci\u00f3n a los end\u00e9micos enfrentamientos no pod\u00eda ser otra que la creaci\u00f3n del obispado. Y, por fin, en 1509, sus s\u00faplicas hallaron la complicidad del soberano \u00fanico de las dos coronas.<\/p>\n<p align=\"JUSTIFY\">Fernando V valor\u00f3 las complejas circunstancias de la cuesti\u00f3n y, pese a saber que la decisi\u00f3n no caer\u00eda muy bien en Castilla, opt\u00f3 por auspiciar la erecci\u00f3n episcopal ante la Sede Apost\u00f3lica, por una parte, con la intenci\u00f3n de castigar los abusos murcianos, y, por otra, para probar si de tal manera lograba hacer desaparecer esas inoportunas discordias, que durante dos d\u00e9cadas hab\u00edan afectado de una manera m\u00e1s o menos desestabilizadora a su proyecto de configuraci\u00f3n de la Monarqu\u00eda Hisp\u00e1nica. Fernando estudi\u00f3 detenidamente el caso y trat\u00f3 de plantear la fundaci\u00f3n de modo que perjudicase lo menos posible al obispo y el cabildo cartaginenses, esto es, teniendo en cuenta aspectos honor\u00edficos, jurisdiccionales y econ\u00f3micos.<\/p>\n<p align=\"JUSTIFY\">As\u00ed, siguiendo las directrices del monarca, el 13 de mayo de 1510, Julio II decret\u00f3 la segunda creaci\u00f3n del obispado de Orihuela. La decisi\u00f3n del Cat\u00f3lico provoc\u00f3 de inmediato la reacci\u00f3n cartaginense. Y las presiones castellanas le obligaron a retractarse y a recomendar a las autoridades civiles y eclesi\u00e1sticas de Murcia que recurriesen contra la segregaci\u00f3n en la Curia romana.<\/p>\n<p align=\"JUSTIFY\">Los recursos murcianos propiciaron el inicio de una larga sucesi\u00f3n de embajadas a las cortes real y pontificia. A partir de este momento, Fernando tuvo que hacer gala de su habilidad diplom\u00e1tica ante los insistentes representantes de una y otra ciudad, para no granjearse ninguna enemistad. Sus decisiones se vieron influidas por una conjunci\u00f3n de factores. Su origen aragon\u00e9s le llev\u00f3 a tratar de beneficiar a los oriolanos. Sin embargo, el peso de la tradici\u00f3n hist\u00f3rica de la di\u00f3cesis cartaginense y, sobre todo, las presiones castellanas equilibraron la balanza. No obstante, la belicosa actitud de los murcianos le inclin\u00f3, en los momentos finales de su reinado, a favorecer la erecci\u00f3n episcopal, consiguiendo que Le\u00f3n X confirmase las bulas institutorias de Julio II. Fernando muri\u00f3 en 1516. Y en relaci\u00f3n con el Pleito del Obispado hemos de afirmar que cumpli\u00f3 plenamente su objetivo: con sus aparentemente ambiguas o duales decisiones, consigui\u00f3 evitar que la problem\u00e1tica murciano-oriolana pudiese poner en peligro la tarea unificadora iniciada junto a Isabel la Cat\u00f3lica.<\/p>\n<p align=\"JUSTIFY\">El acceso al trono de Carlos I conllev\u00f3 importantes cambios para el desarrollo del Pleito del Obispado. En principio, el nuevo monarca hab\u00eda de ser absolutamente neutral e imparcial; una circunstancia completamente novedosa pues hasta ese momento, los oriolanos siempre hab\u00edan podido hacer llegar sus s\u00faplicas a reyes de la Corona de Arag\u00f3n, que en la mayor\u00eda de las ocasiones hab\u00edan prestado gustosos su apoyo a la causa independentista. La entronizaci\u00f3n de Carlos de Gante modific\u00f3 las \u00abreglas del juego\u00bb del Pleito, cuyos logros pasaron a depender de factores muy diversos.<\/p>\n<p align=\"JUSTIFY\">En primer lugar, hemos de se\u00f1alar que la mayor parte de su tiempo, Carlos dirigi\u00f3 su atenci\u00f3n hacia las cuestiones de la pol\u00edtica exterior, interes\u00e1ndose de una manera poco comprometida por los problemas de orden interno de sus s\u00fabditos hisp\u00e1nicos. Ello nos lleva a concluir que el Pleito del Obispado no le import\u00f3, desde luego, tanto como a su abuelo. Sus preocupaciones se dirigieron, m\u00e1s que hacia la unidad de la Monarqu\u00eda, hacia la integridad de la Cristiandad. Sus luchas fueron contra el franc\u00e9s, el turco o la herej\u00eda&#8230;<\/p>\n<p align=\"JUSTIFY\">Durante los primeros a\u00f1os de su reinado, su posici\u00f3n respecto a la controversia fue muy variable. Dado el escaso inter\u00e9s que le suscitaba y la poca importancia que le atribu\u00eda, y su casi nulo conocimiento del tema, se limit\u00f3 pr\u00e1cticamente a quitarse de encima a los procuradores de ambas partes que le visitaron, satisfaciendo sus respectivas y sucesivas peticiones. De esta manera, hasta 1518, el Pleito sufri\u00f3 una serie de vaivenes que pusieron de manifiesto la inexistencia de una voluntad real definida en relaci\u00f3n con la lite.<\/p>\n<p align=\"JUSTIFY\">En dicha fecha, la cuesti\u00f3n comenz\u00f3 a desnivelarse en favor de los intereses murcianos. El monarca se molest\u00f3 por el hecho de que D. Mateo Lang, obispo de Cartagena y Orihuela, de acuerdo con las autoridades civiles y eclesi\u00e1sticas de esta \u00faltima ciudad, tomase posesi\u00f3n del obispado sin informarle de ello previamente. Dicha circunstancia, unida a las protestas murcianas y a las presiones castellanas, le movieron a conseguir que Le\u00f3n X revocase la creaci\u00f3n del obispado de Orihuela.<\/p>\n<p align=\"JUSTIFY\">Desde este hito de la evoluci\u00f3n del Pleito, las relaciones entre Orihuela y Carlos I comenzaron a hacerse distantes. Y llegaron a su peor momento a ra\u00edz de la participaci\u00f3n de la ciudad del Bajo Segura en la German\u00eda. Su alineamiento con los rebeldes le supuso nefastas consecuencias a todos los niveles. Orihuela fue saqueada durante un mes por las tropas murcianas del marqu\u00e9s de los V\u00e9lez, que sacaron a relucir con sus acciones todo el rencor que hab\u00edan acumulado durante siglos contra sus vecinos y rivales. Al desorden demogr\u00e1fico y administrativo, se uni\u00f3 la crisis econ\u00f3mica que sobrevino con la represi\u00f3n de los agermanados. Y a nivel religioso, la revocaci\u00f3n del obispado se hizo efectiva, si bien de una manera irregular, pues el referido marqu\u00e9s forz\u00f3 a los habitantes de la ciudad, cl\u00e9rigos y laicos, a admitir la superioridad espiritual cartaginense.<\/p>\n<p align=\"JUSTIFY\">Pero no todos los efectos negativos de la participaci\u00f3n de Orihuela en la German\u00eda fueron tan inmediatos. Durante unos cuantos a\u00f1os, Carlos I tuvo en cuenta dicha circunstancia a la hora de rechazar con dilaciones las suplicaciones oriolanas de justicia en el Pleito del Obispado. En l\u00edneas generales, el ya electo emperador quiso favorecer a los fieles murcianos y, en este sentido, les apoy\u00f3 cabe la Santa Sede cuando la irregularidad del juramento de obediencia oriolano les oblig\u00f3 a volver a solicitar la revocaci\u00f3n de las bulas fundacionales de Julio II.<\/p>\n<p align=\"JUSTIFY\">Adem\u00e1s, los conflictos de las autoridades de Orihuela con la Inquisici\u00f3n cartaginense hicieron empeorar a\u00fan m\u00e1s la imagen de la ciudad del Bajo Segura a los ojos del emperador. Y ni siquiera las tensas relaciones que mantuvo con Clemente VII le hicieron dejar de apoyar los intereses murcianos. El pont\u00edfice revoc\u00f3 la creaci\u00f3n de Julio II por medio de tres rescriptos (1524, 1526 y 1530). No obstante, los oriolanos aprovecharon bien sus posibilidades y lograron retrasar su ejecuci\u00f3n. Su habilidad diplom\u00e1tica ante el emperador, el favor incondicional del gobernador del Reino de Valencia m\u00e1s all\u00e1 de Jijona, D. Pedro Maza, y el recurso al apoyo de los estamentos en las Cortes generales de la Corona de Arag\u00f3n, celebradas en Monz\u00f3n, en 1528, impidieron que la derogaci\u00f3n del obispado se hiciese efectiva hasta 1532, fecha en que Carlos I mand\u00f3 severamente a su lugarteniente general en el citado Reino de Valencia, el duque de Calabria, que auxiliase a los murcianos en su af\u00e1n por recuperar la integridad del obispado cartaginense y por restaurar su autoridad espiritual en toda la di\u00f3cesis.<\/p>\n<p align=\"JUSTIFY\">Los oriolanos, por supuesto, no se resignaron a aceptar esa superioridad, y de inmediato apelaron contra la derogaci\u00f3n del obispado. Y consiguieron atraer la atenci\u00f3n del emperador aprovech\u00e1ndose de un factor que realmente le preocupaba: la necesidad de liquidez. Aunque este comentario parezca extra\u00f1o, creemos que los oriolanos supieron jugar muy bien sus bazas ante Carlos I. Los ingentes gastos derivados de su ambiciosa pol\u00edtica exterior le obligaron a tratar de conseguir fondos de sus s\u00fabditos de Castilla y la Corona de Arag\u00f3n. Y para ello utiliz\u00f3 la v\u00eda de la celebraci\u00f3n de Cortes generales de ambas unidades pol\u00edticas en diferentes a\u00f1os (1533, 1537, 1542, 1547, 1552). Las autoridades de la ciudad del Bajo Segura, con el apoyo de los estamentos de los tres reinos, consiguieron que el monarca se comprometiese formalmente a revisar el Pleito del Obispado. No obstante, no lograron plenamente sus objetivos pues, dado que desconfiaban del emperador, le suplicaron que remitiese la causa a la justicia apost\u00f3lica, y Carlos I prefiri\u00f3 encargarse personalmente de resolver la controversia, al considerar que dicha opci\u00f3n ser\u00eda, sobre todo, menos gravosa para las econom\u00edas oriolana y murciana. En su pensamiento, desde luego, no cab\u00eda la posibilidad de que sus s\u00fabditos dilapidaran sus ingresos en embajadas a la Santa Sede, en tr\u00e1mites y en propinas para los interesados curiales.<\/p>\n<p align=\"JUSTIFY\">De esta manera, el monarca dio origen a una nueva etapa, un segundo tiempo del Pleito en su reinado. Carlos I cit\u00f3 a los litigantes en diversas ocasiones con la intenci\u00f3n de proceder a la revisi\u00f3n de la causa. En 1533, en Monz\u00f3n. En 1534, en Toledo. En 1535, en Madrid. En 1537, de nuevo en Monz\u00f3n. En 1538, en Barcelona y Toledo. En 1539, en Madrid. En 1542, otra vez en Monz\u00f3n. Y en 1543, en Madrid y Barcelona. No obstante, pese a ello, creemos que en el fondo no quiso cambiar el \u00aborden\u00bb establecido en la di\u00f3cesis cartaginense tras la revocaci\u00f3n de 1532. Nos resistimos a pensar que otros factores como las incomparecencias murcianas, las estratagemas y presiones del Consejo de Castilla, las dilaciones provocadas por las autoridades oriolanas en coyunturas desfavorables o sus continuos viajes fueran causas suficientes para que el emperador no pudiese poner fin a la cuesti\u00f3n. En el fondo, creemos que la cuesti\u00f3n episcopal no le importaba realmente y que, acomodado tras la citada derogaci\u00f3n de Clemente VII, no quiso realizar cambio alguno. Toler\u00f3 las importunaciones oriolanas, escuch\u00f3 m\u00e1s o menos correctamente sus sufridas reivindicaciones, pero sin alejar un \u00e1pice su atenci\u00f3n de cuanto estaba sucediendo en \u00abEuropa\u00bb.<\/p>\n<p align=\"JUSTIFY\">Asimismo, los elecciones reales de D. Juan Mart\u00ednez Sil\u00edceo (en 1541) y de D. Esteban de Almeyda (en 1546) como obispos de Cartagena vienen a confirmar dicha interpretaci\u00f3n. Carlos I eligi\u00f3 sucesivamente a ambos candidatos con una clara intenci\u00f3n: apaciguar los \u00e1nimos en la di\u00f3cesis y apagar las manifestaciones independentistas. Por las buenas, en el caso del persuasivo maestro del pr\u00edncipe Felipe. Y por las malas, en el del autoritario portugu\u00e9s. Y consigui\u00f3, finalmente, durante el gobierno espiritual de este \u00faltimo, que la desesperanza cundiese entre las autoridades civiles y eclesi\u00e1sticas de Orihuela y que sus reclamaciones episcopales dejasen de distraerle.<\/p>\n<p align=\"JUSTIFY\">La abdicaci\u00f3n del emperador y el acceso al trono de su primog\u00e9nito, Felipe II, supusieron la entrada en juego de nuevos condicionantes para el curso del Pleito del Obispado. Dichas variables se hicieron a\u00fan m\u00e1s favorables a los intereses episcopales oriolanos tras el fallecimiento de Carlos en Yuste.<\/p>\n<p align=\"JUSTIFY\">Las autoridades civiles y eclesi\u00e1sticas de la ciudad del Bajo Segura se apercibieron pronto de que el nuevo monarca iba a regirse por criterios diferentes a la hora de abordar la resoluci\u00f3n del litigio. De entrada, Felipe II no ten\u00eda los motivos de su padre para castigar a los pobladores de la ciudad del Bajo Segura, o para ceder a las influencias castellanas. Ni tampoco la necesidad de dedicar su atenci\u00f3n a las urgencias europeas, ya que la corona imperial hab\u00eda pasado a su t\u00edo Fernando. Al contrario, el heredero de la Corona Hisp\u00e1nica hab\u00eda de ocuparse de las cuestiones de orden interno de su Monarqu\u00eda y la del obispado era una de ellas. Por todos estos factores, los oriolanos debieron pensar que la entronizaci\u00f3n de Felipe II abr\u00eda nuevas posibilidades para conseguir el objetivo episcopal y quedaron a la espera de que se presentase una coyuntura proclive al reinicio de las reivindicaciones.<\/p>\n<p align=\"JUSTIFY\">Los primeros a\u00f1os del reinado de Felipe II pusieron claramente de manifiesto las enunciadas l\u00edneas gubernativas. En un contexto hist\u00f3rico profundamente marcado por el Concilio de Trento, el rey espa\u00f1ol se present\u00f3 ante la Cristiandad como el palad\u00edn defensor de la fe cat\u00f3lica. Y en consecuencia, centr\u00f3 su pol\u00edtica religiosa en la erradicaci\u00f3n de la herej\u00eda y en una escrupulosa vigilancia de la pureza del Catolicismo practicado en sus dominios. Tras acabar con dos focos luterizantes surgidos en Valladolid y Sevilla, se ocup\u00f3 del segundo principio anunciado y en 1563 comenz\u00f3 a prestar atenci\u00f3n a una l\u00ednea de actuaciones que cre\u00eda que podr\u00eda coadyuvar al fortalecimiento de la fe: la reorganizaci\u00f3n de la geograf\u00eda eclesi\u00e1stica de sus reinos. El monarca hall\u00f3 en la creaci\u00f3n de nuevos obispados una soluci\u00f3n eficaz para reafirmar e, incluso, incrementar el control que pretend\u00eda tener sobre el rigor del Catolicismo profesado por sus s\u00fabditos y, en especial, por los que consideraba m\u00e1s peligrosos, los moriscos. Y quiz\u00e1 descubri\u00f3 la utilidad de este m\u00e9todo gracias a las suplicaciones episcopales oriolanas.<\/p>\n<p align=\"JUSTIFY\">Tal como indicamos, las autoridades de la ciudad del Bajo Segura esperaron la llegada de una coyuntura favorable para reiniciar sus suplicaciones secesionistas. Y \u00e9sta lleg\u00f3 a principios de 1563 cuando, ante la cercan\u00eda de la muerte del obispo Almeyda, le suplicaron al monarca la erecci\u00f3n del obispado, poniendo especial \u00e9nfasis en el hecho de que dicha soluci\u00f3n ser\u00eda la m\u00e1s adecuada para mejorar la atenci\u00f3n pastoral de los habitantes de la Gobernaci\u00f3n, y que tambi\u00e9n servir\u00eda para vigilar de cerca las sospechosas pr\u00e1cticas religiosas de los abundantes moros convertidos al Cristianismo que constitu\u00edan la principal mano de obra en los campos de cultivo.<\/p>\n<p align=\"JUSTIFY\">El Rey Prudente, que ten\u00eda la costumbre gubernamental de entremezclar los intereses pol\u00edticos y los religiosos, se apercibi\u00f3 en seguida de que la aplicaci\u00f3n del plan oriolano le permitir\u00eda obtener beneficios muy notorios en ambos planos, y decidi\u00f3 comenzar a auspiciarlo en secreto, a fin de evitar las protestas murciano-castellanas.<\/p>\n<p align=\"JUSTIFY\">Felipe II hizo suyo el proyecto oriolano y se lo present\u00f3 a P\u00edo IV. El pont\u00edfice, que al igual que el monarca sent\u00eda una especial preocupaci\u00f3n por los temas pastorales, acogi\u00f3 favorablemente la iniciativa y le encarg\u00f3 un estudio sobre la viabilidad de la erecci\u00f3n episcopal.<\/p>\n<p align=\"JUSTIFY\">El rey accedi\u00f3 de inmediato al requerimiento pontificio y a finales de 1563 orden\u00f3 la realizaci\u00f3n de las pesquisas en las dos partes de la di\u00f3cesis cartaginense. Convencido por los resultados de la investigaci\u00f3n, en mayo del a\u00f1o siguiente, la envi\u00f3 a la Santa Sede, junto con la suplicaci\u00f3n del obispado y la carta de presentaci\u00f3n del que habr\u00eda de ser el primer obispo, el catedr\u00e1tico y te\u00f3logo salmantino, D. Gregorio Gallo de Andrade; y le encarg\u00f3 al pavorde de la iglesia del Salvador de Orihuela, D. Diego Ferr\u00e1ndez de Mesa, la realizaci\u00f3n de los tr\u00e1mites oportunos para la obtenci\u00f3n de las bulas.<\/p>\n<p align=\"JUSTIFY\">Los rescriptos fueron aprobados por P\u00edo IV en su consistorio del 14 de julio de 1564, y expedidos dos meses despu\u00e9s. Con ellos, el mencionado pavorde retorn\u00f3 a Espa\u00f1a y los llev\u00f3 a la corte, donde Felipe II les concedi\u00f3 su exequ\u00e1tur.<\/p>\n<p align=\"JUSTIFY\">La oposici\u00f3n murciana fue in\u00fatil, pues la voluntad de Felipe II se mostr\u00f3 siempre muy firme. El primero de mayo de1565, las bulas de P\u00edo IV fueron publicadas en la Catedral del Salvador, haci\u00e9ndose realidad la creaci\u00f3n del obispado.<\/p>\n<p align=\"JUSTIFY\">Poco despu\u00e9s, el 22 de agosto de dicho a\u00f1o, D. Gregorio Gallo consigui\u00f3, por fin, sus rescriptos provisorios. Y tras recibir el pase regio, el 23 de marzo de 1566, tom\u00f3 posesi\u00f3n del obispado de Orihuela.<\/p>\n<p align=\"JUSTIFY\">La divisi\u00f3n del obispado de Cartagena y la creaci\u00f3n del de Orihuela se hicieron definitivas como consecuencia de dicho acto solemne. No obstante, las discordias entre oriolanos y murcianos no finalizaron en ese momento. Los damnificados se negaron a aceptar la escisi\u00f3n de su di\u00f3cesis, oponi\u00e9ndose a la nueva distribuci\u00f3n de las rentas. No obstante, Felipe II impidi\u00f3 cualquier involuci\u00f3n y el 4 de abril de 1576 el papa Gregorio XIII puso fin a las reclamaciones cartaginenses.<\/p>\n<p align=\"JUSTIFY\">Hasta ese d\u00eda, los murcianos se negaron a aceptar la realidad, manteniendo viva la esperanza de que la segregaci\u00f3n de la di\u00f3cesis de Cartagena fuese revocada. Pero la tenaz voluntad de Felipe II pudo m\u00e1s y, por fin, el obispado de Orihuela se convirti\u00f3 en una realidad perpetua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el cap\u00edtulo dedicado a las conclusiones del presente trabajo de investigaci\u00f3n, realizaremos una interpretaci\u00f3n en torno a los siguientes puntos de reflexi\u00f3n: 7.1. El origen del Pleito del Obispado: la falta de coincidencia entre los l\u00edmites eclesi\u00e1sticos y pol\u00edticos. 7.2. Las causas de las reivindicaciones episcopales oriolanas. 7.3. La oposici\u00f3n murciana a la escisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":936,"featured_media":0,"parent":0,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-39","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/users\/936"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":40,"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/pages\/39\/revisions\/40"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/obispadoorihuela\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}