{"id":89,"date":"2009-07-16T12:03:10","date_gmt":"2009-07-16T10:03:10","guid":{"rendered":"https:\/\/blogs.ua.es\/opencourseware\/?p=89"},"modified":"2009-07-16T12:03:10","modified_gmt":"2009-07-16T10:03:10","slug":"ayudas-2009-a-la-publicacion-de-cursos-en-opencourseware","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/opencourseware\/2009\/07\/16\/ayudas-2009-a-la-publicacion-de-cursos-en-opencourseware\/","title":{"rendered":"Ayudas 2009 a la publicaci\u00f3n de cursos en OpenCourseWare"},"content":{"rendered":"<p><span style=\"color: #666666\">En breve se comunicar\u00e1 a l@s docentes la aprobaci\u00f3n de las ayudas a la publicaci\u00f3n en OpenCourseWare, aunque ya se puede el <a href=\"http:\/\/ocw.ua.es\/procedimiento\">procedimiento<\/a> de edici\u00f3n y publicaci\u00f3n de los cursos en OCW 2009 solo para l@s docentes cuyas solicitudes de publicaci\u00f3n se aprueben.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En breve se comunicar\u00e1 a l@s docentes la aprobaci\u00f3n de las ayudas a la publicaci\u00f3n en OpenCourseWare, aunque ya se puede el procedimiento de edici\u00f3n y publicaci\u00f3n de los cursos en OCW 2009 solo para l@s docentes cuyas solicitudes de publicaci\u00f3n se aprueben.<\/p>\n","protected":false},"author":832,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/users\/832"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":91,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/posts\/89\/revisions\/91"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/opencourseware\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}