{"id":68,"date":"2014-05-12T18:28:20","date_gmt":"2014-05-12T18:28:20","guid":{"rendered":"https:\/\/blogs.ua.es\/orihuela\/?p=68"},"modified":"2014-06-01T14:13:13","modified_gmt":"2014-06-01T14:13:13","slug":"acta-28-de-febrero-de-1939","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/orihuela\/2014\/05\/12\/acta-28-de-febrero-de-1939\/","title":{"rendered":"Acta 28 de febrero de 1939"},"content":{"rendered":"<ul>\n<li><strong>Municipio<\/strong>: Orihuela.<\/li>\n<li><strong>Sesi\u00f3n<\/strong>: Ordinaria.<\/li>\n<li><strong>Fecha<\/strong>: 28 de febrero de 1939.<\/li>\n<li><strong>Nombre del Alcalde<\/strong>: Pascual Soriano Hell\u00edn.<\/li>\n<li><strong>Asistentes<\/strong>: Jos\u00e9 Soriano Gim\u00e9nez, David Calindo Mart\u00ednez, Ram\u00f3n Rogel Mu\u00f1oz, Cruz Andreu Rubio, Gregorio Cecilia Tor\u00e1, Olegario L\u00f3pez Eugenio, Antonio Leonis Ru\u00edz, Jos\u00e9 Bas L\u00f3pez, Antonio Tejuelo Cabrera, Manuel Barrachuina Vall, Manuel Vicente Leonis.<\/li>\n<li><strong>Secretario<\/strong>: Jos\u00e9 Escudero Bernicola.<\/li>\n<\/ul>\n<p style=\"text-align: center\"><strong>Acuerdos<\/strong>:<\/p>\n<p style=\"text-align: justify\">Se acuerda pasar a la Comisi\u00f3n de Empleados un escrito del\u00a0Presidente comunicando el nombramiento de Roberto Vel\u00e1zquez S\u00e1nchez como guardia de almac\u00e9n de lonja interino adem\u00e1s de dotarle de una ratificaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Se da cuenta de un oficio de Inspector Municipal.<\/p>\n<p style=\"text-align: justify\">Se acuerda \u00a0vender una mula propiedad del Consejo que no re\u00fane las condiciones necesarias para el trabajo y destinar lo obtenido a fines ben\u00e9ficos.<\/p>\n<p style=\"text-align: justify\">Se acuerda conceder el socorro de lactancia a Dionisia Garc\u00eda.<\/p>\n<p style=\"text-align: center\"><strong>Ruegos y preguntas:<\/strong><\/p>\n<p style=\"text-align: justify\">El se\u00f1or Anierote denuncia el estado ruinoso de algunas galer\u00edas del cementerio y anuncia una moci\u00f3n sobre la construcci\u00f3n de nuevos nichos para la pr\u00f3xima sesi\u00f3n.<\/p>\n<p style=\"text-align: justify\">El se\u00f1or Hern\u00e1ndez se da por satisfecho con las explicaciones, sobre la denuncia hecha por el se\u00f1or Soriano Gim\u00e9nez, acerca de haberse encontrado abierta la puerta del refugio de Santa Justa, en el que est\u00e1n depositados los g\u00e9neros de abastos.<\/p>\n<p style=\"text-align: justify\">El se\u00f1or Hern\u00e1ndez ruega a la presidencia que encarezca a todos los consejeros la puntual asistencia a las sesiones a fin de evitar las supletorias, y pregunta si se puede ampliar el n\u00famero de miembros del Comit\u00e9 Agr\u00edcola por excesivas labor que desarrollan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Municipio: Orihuela. Sesi\u00f3n: Ordinaria. Fecha: 28 de febrero de 1939. Nombre del Alcalde: Pascual Soriano Hell\u00edn. Asistentes: Jos\u00e9 Soriano Gim\u00e9nez, David Calindo Mart\u00ednez, Ram\u00f3n Rogel Mu\u00f1oz, Cruz Andreu Rubio, Gregorio Cecilia Tor\u00e1, Olegario L\u00f3pez Eugenio, Antonio Leonis Ru\u00edz, Jos\u00e9 Bas &hellip; <a href=\"https:\/\/blogs.ua.es\/orihuela\/2014\/05\/12\/acta-28-de-febrero-de-1939\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2907,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1269749],"tags":[1459033,1460795,106706,1459912],"class_list":["post-68","post","type-post","status-publish","format-standard","hentry","category-sesion-ordinaria","tag-comision-de-empleados","tag-comite-agricola","tag-consejo","tag-pascual-soriano-hellin"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/posts\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/users\/2907"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/posts\/68\/revisions"}],"predecessor-version":[{"id":218,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/posts\/68\/revisions\/218"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/media?parent=68"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/categories?post=68"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/orihuela\/wp-json\/wp\/v2\/tags?post=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}