{"id":376,"date":"2012-01-01T11:21:45","date_gmt":"2012-01-01T11:21:45","guid":{"rendered":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/?p=376"},"modified":"2012-01-04T15:27:13","modified_gmt":"2012-01-04T15:27:13","slug":"debate-sobre-el-estado-del-patrimonio-alicantino","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/2012\/01\/01\/debate-sobre-el-estado-del-patrimonio-alicantino\/","title":{"rendered":"Debate sobre el estado del patrimonio alicantino"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"color: #000000\"><strong>Resumen:<\/strong><\/span><\/p>\n<p style=\"text-align: justify\">Rese\u00f1a period\u00edstica que anuncia el inicio de las mesas\u00a0redondas\u00a0de debate sobre el estado del patrimonio alicantino en sus diversas variantes, incluyendo el monumental, a ra\u00edz de la iniciativa surgida por la tienda de libros 80 Mundos y la PIC (Plataforma de Iniciativas Ciudadanas).<\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\"><strong>Referencia:<\/strong><\/span><\/p>\n<p style=\"text-align: justify\">A.V. Debate sobre el estado del patrimonio alicantino. <em>Diario Informaci\u00f3n. <\/em>Noticias Cultura.\u00a0Alicante: 30 de marzo de 2011. [01\/01\/2012]. Disponible en:\u00a0<a href=\"http:\/\/www.diarioinformacion.com\/cultura\/2011\/03\/30\/debate-patrimonio-alicantino\/1110220.html\">http:\/\/www.diarioinformacion.com\/cultura\/2011\/03\/30\/debate-patrimonio-alicantino\/1110220.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumen: Rese\u00f1a period\u00edstica que anuncia el inicio de las mesas\u00a0redondas\u00a0de debate sobre el estado del patrimonio alicantino en sus diversas variantes, incluyendo el monumental, a ra\u00edz de la iniciativa surgida por la tienda de libros 80 Mundos y la PIC (Plataforma de Iniciativas Ciudadanas). Referencia: A.V. Debate sobre el estado del patrimonio alicantino. Diario Informaci\u00f3n. [&hellip;]<\/p>\n","protected":false},"author":2481,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6674],"tags":[105797],"class_list":["post-376","post","type-post","status-publish","format-standard","hentry","category-recursos-electronicos","tag-patrimonio-monumental"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/posts\/376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/users\/2481"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/posts\/376\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/posts\/376\/revisions\/478"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/categories?post=376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/patrimoniomonumentalalicante\/wp-json\/wp\/v2\/tags?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}