{"id":110,"date":"2012-01-16T18:16:58","date_gmt":"2012-01-16T18:16:58","guid":{"rendered":"https:\/\/blogs.ua.es\/peliculasmedievo\/?p=110"},"modified":"2012-01-17T17:30:55","modified_gmt":"2012-01-17T17:30:55","slug":"la-batalla-de-hastings","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/peliculasmedievo\/2012\/01\/16\/la-batalla-de-hastings\/","title":{"rendered":"La batalla de Hastings"},"content":{"rendered":"<p>Decisiones de mando: La batalla de Hastings. Canal de Historia Espa\u00f1a, 2004<\/p>\n<p>&nbsp;<\/p>\n<p>Este documental nos narra la batalla de Hastings que tuvo lugar en oto\u00f1o 1066 y enfrento al duque Guillermo de Normand\u00eda con el rey anglosaj\u00f3n Harold II por el trono de Inglaterra. Esta batalla seria decisiva para la historia medieval inglesa y cambiaria el rumbo del pa\u00eds para siempre. El documental empieza poni\u00e9ndonos en situaci\u00f3n, explic\u00e1ndonos la situaci\u00f3n de Inglaterra despu\u00e9s de morir el rey Eduardo el Confesor. Nos explica el contexto hist\u00f3rico de una manera r\u00e1pida y concisa. Adem\u00e1s nos hace un peque\u00f1o an\u00e1lisis psicol\u00f3gico de Guillermo de Normand\u00eda. Este documental es interactivo, ofreciendo al espectador la oportunidad de contestar diferentes preguntas con tres posibles respuestas. Estas preguntas tratan sobre cuestiones estrat\u00e9gicas importantes que tuvo que tomar Guillermo para conseguir la victoria en la batalla. Algunas de estas preguntas son dif\u00edciles, casi imposibles que el espectador pueda adivinar la respuesta correcta.<\/p>\n<p>Despu\u00e9s\u00a0de explicarnos el contexto previo a la batalla y como desemboco esta, el documental nos explica los pasos y las estrategias que sucedieron en dicho acontecimiento. Se explican elementos tan importantes como los soldados de cada ej\u00e9rcito, sus armas o sus estrategias. Adem\u00e1s se sigue el anterior esquema de preguntas y tres respuestas. Durante todo el documental se utiliza a actores reales para recrear la batalla y las luchas, lo que ayuda al espectador a entender y facilitar la comprensi\u00f3n de lo sucedido. Esto se apoya mostrando mapas y miniaturas. Adem\u00e1s el documental hace espor\u00e1dicamente res\u00famenes espont\u00e1neos para que los espectadores recuerden conceptos claves y poner en situaci\u00f3n a los nuevos espectadores. Esto m\u00e1s que una herramienta de apoyo es un truco publicitario para hacer una pausa publicitaria y luego volver al documental sin cortes. Finalmente, despu\u00e9s de que termine la batalla explica las consecuencias que dicha batalla tuvo para el pa\u00eds en cuesti\u00f3n y la suerte que tuvo despu\u00e9s el general victorioso<\/p>\n<p>Este documental tiene elementos novedosos como la\u00a0inclusi\u00f3n\u00a0de las preguntas. Para m\u00ed este es un elemento bastante positivo del documental, ya que deja en vilo al espectador y le da un aliciente para seguir viendo el documental. Adem\u00e1s las explicaciones militares, junto a las aclarativas sobre armas y estrategias resultan muy interesantes e importantes para poder seguir el documental. Este documental es claro,\u00a0r\u00e1pido\u00a0y divertido mostrando en 30 minutos aproximadamente una de las batallas m\u00e1s importantes de la Edad Media en Inglaterra. Es un documental muy recomendable como todos los de su serie, ya que este documental es parte de una serie llamada Decisiones de Mando que recomiendo\u00a0encarecidamente\u00a0a los lectores de este blog.<\/p>\n<p>Finalmente os dejo las tres partes del documental para que las\u00a0pod\u00e1is\u00a0ver:<\/p>\n<p>Parte 1:<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/9Bm_eT8N7eU\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>Parte 2:<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/aZ_9DbwwIwk\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>Parte 3:<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/_xSkPgVTTIY\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decisiones de mando: La batalla de Hastings. Canal de Historia Espa\u00f1a, 2004 &nbsp; Este documental nos narra la batalla de Hastings que tuvo lugar en oto\u00f1o 1066 y enfrento al duque Guillermo de Normand\u00eda con el rey anglosaj\u00f3n Harold II por el trono de Inglaterra. Esta batalla seria decisiva para la historia medieval inglesa y [&hellip;]<\/p>\n","protected":false},"author":2329,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86622,6037,6674],"tags":[3277,122144,122143,2466,122145],"class_list":["post-110","post","type-post","status-publish","format-standard","hentry","category-audiovisuales","category-documental","category-recursos-electronicos","tag-batallas","tag-guillermo-el-conquistador","tag-hastings","tag-inglaterra","tag-normandia"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/users\/2329"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":113,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/posts\/110\/revisions\/113"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/peliculasmedievo\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}