{"id":64,"date":"2026-03-24T07:00:00","date_gmt":"2026-03-24T07:00:00","guid":{"rendered":"https:\/\/blogs.ua.es\/piedraseca\/?p=64"},"modified":"2026-03-26T15:12:22","modified_gmt":"2026-03-26T15:12:22","slug":"arquitecturas-de-piedra-en-seco","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/piedraseca\/2026\/03\/24\/arquitecturas-de-piedra-en-seco\/","title":{"rendered":"Arquitecturas de piedra en seco"},"content":{"rendered":"\n<p>Actas del VII Congreso Internacional de Arquitectura de Piedra en Seco. Pe\u00f1\u00edscola (2000)<\/p>\n\n\n\n<p>Vicente Meseguer Folch, Arturo Zaragoz\u00e1 Catal\u00e1n (eds.)<\/p>\n\n\n\n<p>Centro de Estudios del Maestrazgo, Benicarl\u00f3 (2004)<br>ISBN: 84-932784-3-2<\/p>\n\n\n\n<p>\u00abEl reconocimiento de la misteriosa presencia de la arquitectura, o del monumento, en un amontonamiento de piedras es un fen\u00f3meno del mundo contempor\u00e1neo. El asombro ante los muros de piedra en seco, ante las barracas, o ante los paisajes construidos, ha surgido en los \u00faltimos a\u00f1os, de forma simult\u00e1nea, en diferentes pa\u00edses, entre investigadores sin comunicaci\u00f3n entre s\u00ed.<\/p>\n\n\n\n<p>Los congresos internacionales de Piedra en Seco han permitido intercambiar experiencias, aglutinar intereses y dar a conocer paisajes y arquitecturas olvidadas.<\/p>\n\n\n\n<p>Bari, Italia (1988); Barcelona, Espa\u00f1a (1990); Anogia, Creta, Grecia (1992); Mallorca, Espa\u00f1a (1994); Pontedassio-Coldinava, Imperia, Italia (1996) y Carc\u00e9s-le Val, Var, Francia (1998), han sido otros hitos que han permitido el intercambio de conocimientos de investigadores llegados de un amplio abanico geogr\u00e1fico que va desde Israel hasta EE.UU. y desde Argelia hasta Alemania.\u00bb<\/p>\n\n\n\n<p><a href=\"https:\/\/pedraseca.gva.es\/documents\/168838666\/168851325\/Arquitecturas+de+piedra+en+seco.pdf\/c49aca10-4e14-45cb-b193-b5a96f7a0f97\">https:\/\/pedraseca.gva.es\/documents\/168838666\/168851325\/Arquitecturas+de+piedra+en+seco.pdf\/c49aca10-4e14-45cb-b193-b5a96f7a0f97<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"719\" src=\"https:\/\/blogs.ua.es\/piedraseca\/files\/2026\/03\/Arquitecturas-de-piedra-en-seco.png\" alt=\"Arquitecturas de piedra en seco\" class=\"wp-image-65\" style=\"width:524px;height:auto\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Actas del VII Congreso Internacional de Arquitectura de Piedra en Seco. Pe\u00f1\u00edscola (2000) Vicente Meseguer Folch, Arturo Zaragoz\u00e1 Catal\u00e1n (eds.) Centro de Estudios del Maestrazgo, Benicarl\u00f3 (2004)ISBN: 84-932784-3-2 \u00abEl reconocimiento de la misteriosa presencia de la arquitectura, o del monumento, en un amontonamiento de piedras es un fen\u00f3meno del mundo contempor\u00e1neo. El asombro ante los [&hellip;]<\/p>\n","protected":false},"author":797,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-actas"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/users\/797"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":66,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/posts\/64\/revisions\/66"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/piedraseca\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}