{"id":3324,"date":"2012-04-24T15:48:31","date_gmt":"2012-04-24T13:48:31","guid":{"rendered":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/?p=3324"},"modified":"2012-04-24T15:48:31","modified_gmt":"2012-04-24T13:48:31","slug":"despues-pfc%c2%b7viajes-iii","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/2012\/04\/24\/despues-pfc%c2%b7viajes-iii\/","title":{"rendered":"Despu\u00e9s PFC\u00b7viajes III"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/2012\/03\/27\/3263\/cartel-despua%c2%a9spfcq2b\/\" rel=\"attachment wp-att-3279\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3279\" src=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/afterpfc2.jpg\" alt=\"\" width=\"800\" height=\"190\" srcset=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/afterpfc2.jpg 800w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/afterpfc2-300x71.jpg 300w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/afterpfc2-150x35.jpg 150w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/afterpfc2-400x95.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>El pr\u00f3ximo<strong> Jueves 26 de Abril<\/strong> tendr\u00e1 lugar la tercera y \u00faltima sesi\u00f3n de conferencias del curso CECLEC <em>Despu\u00e9s PFC, \u00bfsabes qu\u00e9 arquitecto quieres ser?<\/em> dedicada a <em>Viajes<\/em>. En esta ocasi\u00f3n contaremos con la presencia de <strong>Ethel Baraona<\/strong> y <strong>Paco Gonz\u00e1lez<\/strong>.<\/p>\n<p>La asistencia es libre y tendr\u00e1 lugar en el Sal\u00f3n de Actos de la Polit\u00e9cinca IV de la UA a las 13h00.<\/p>\n<p><!--more--><a href=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/2012\/03\/14\/despues-pfc\/cartel-despua%c2%a9spfcq2b-2\/\" rel=\"attachment wp-att-3274\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3274\" src=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email.jpg\" alt=\"\" width=\"800\" height=\"1131\" srcset=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email.jpg 800w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email-212x300.jpg 212w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email-724x1024.jpg 724w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email-106x150.jpg 106w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2012\/03\/120306_Cartel-Despu\u00e9sPFCQ2_email-400x565.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo Jueves 26 de Abril tendr\u00e1 lugar la tercera y \u00faltima sesi\u00f3n de conferencias del curso CECLEC Despu\u00e9s PFC, \u00bfsabes qu\u00e9 arquitecto quieres ser? dedicada a Viajes. En esta ocasi\u00f3n contaremos con la presencia de Ethel Baraona y Paco Gonz\u00e1lez. La asistencia es libre y tendr\u00e1 lugar en el Sal\u00f3n de Actos de la [&hellip;]<\/p>\n","protected":false},"author":2564,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6606],"tags":[1375650,3838],"class_list":["post-3324","post","type-post","status-publish","format-standard","hentry","category-generallll","tag-ceclec","tag-conferencia"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/3324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/users\/2564"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/comments?post=3324"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/3324\/revisions"}],"predecessor-version":[{"id":3326,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/3324\/revisions\/3326"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/media?parent=3324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/categories?post=3324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/tags?post=3324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}