{"id":5880,"date":"2016-05-25T15:34:43","date_gmt":"2016-05-25T13:34:43","guid":{"rendered":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/?p=5880"},"modified":"2016-09-01T14:01:46","modified_gmt":"2016-09-01T12:01:46","slug":"online-archivo-proyectos-arquitectonicos","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/2016\/05\/25\/online-archivo-proyectos-arquitectonicos\/","title":{"rendered":"ONLINE: Archivo Proyectos Arquitect\u00f3nicos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5881\" src=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home.jpg\" alt=\"archivo_proyectos_arquitectonicos_universidad_alicante_home\" width=\"1020\" height=\"654\" srcset=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home.jpg 1020w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home-300x192.jpg 300w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home-768x492.jpg 768w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home-150x96.jpg 150w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2016\/05\/archivo_proyectos_arquitectonicos_universidad_alicante_home-400x256.jpg 400w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>\u00a1POR FIN TENEMOS LA WEB DEL ARCHIVO DE PROYECTOS ARQUITECT\u00d3NICOS!<\/p>\n<p><!--more--><\/p>\n<p>Despu\u00e9s de varios a\u00f1os recopilando proyectos y dise\u00f1ando la web, por fin hoy podemos anunciar que nuestro Archivo est\u00e1 en funcionamiento. Empezaremos mostrando los Proyectos Fin de Carrera. Semana tras semana iremos subiendo m\u00e1s siendo nuestra idea ir completando los a\u00f1os m\u00e1s recientes para despu\u00e9s pasar a los posteriores hasta llegar al a\u00f1o de la primera promoci\u00f3n en presentar el PFC (2003).<\/p>\n<p>Seguir\u00e1n los proyectos de cursos por niveles, m\u00e1ster, etc. Por otro lado, adem\u00e1s de Proyectos nuestra idea es incluir en el Archivo:\u00a0Talleres, Textos, Publicaciones, Profesores, Eventos, Tesis y Blogs. Es, sin duda, un proyecto ambicioso y a largo plazo. Hoy damos el primer paso poni\u00e9ndolo en funcionamiento.<\/p>\n<p>Si quer\u00e9is que colguemos vuestro proyecto\u00a0o ten\u00e9is fotos de talleres, eventos, juries, momentos de clase, viajes, etc. que quer\u00e1is que aparezcan en un futuro pr\u00f3ximo en la web os agradecer\u00edamos que nos enviarais un enlace de descarga al siguiente email:<\/p>\n<p>archivo.proyectos.arquitectonicos@ua.es<\/p>\n<p>De todos modos, os iremos contactando a tod@s en breve.<\/p>\n<p>\u00a1Seguimos!<\/p>\n<p>web:\u00a0<a href=\"https:\/\/archivoproyectosarquitectonicos.ua.es\/\" target=\"_blank\">https:\/\/archivoproyectosarquitectonicos.ua.es\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1POR FIN TENEMOS LA WEB DEL ARCHIVO DE PROYECTOS ARQUITECT\u00d3NICOS!<\/p>\n","protected":false},"author":2744,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[],"class_list":["post-5880","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/5880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/users\/2744"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/comments?post=5880"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/5880\/revisions"}],"predecessor-version":[{"id":5883,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/5880\/revisions\/5883"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/media?parent=5880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/categories?post=5880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/tags?post=5880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}