{"id":6229,"date":"2017-03-20T13:20:14","date_gmt":"2017-03-20T12:20:14","guid":{"rendered":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/?p=6229"},"modified":"2017-03-20T13:23:40","modified_gmt":"2017-03-20T12:23:40","slug":"curso-post-arcadia-en-el-cendeac-murcia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/2017\/03\/20\/curso-post-arcadia-en-el-cendeac-murcia\/","title":{"rendered":"Curso Post-Arcadia en el CENDEAC (Murcia)"},"content":{"rendered":"<p class=\"gmail_default\">Los profesores Enrique Nieto y Miguel Mesa del Castillo dirigen este curso en el <a href=\"http:\/\/www.cendeac.net\/es\/\">CENDEAC<\/a> de Murcia .<\/p>\n<p class=\"gmail_default\">Las conferencias son todas en jueves salvo la de Mar\u00eda Jerez (que es lunes 10 la performance y martes 11 la conferencia) y la de Yayo Herrero (el martes 30\/05). Las fechas est\u00e1n en la web.<\/p>\n<p class=\"gmail_default\">Arquitectura: Adem\u00e1s de nuestro catedr\u00e1tico Jos\u00e9 Mar\u00eda Torres Nadal, participan: Andr\u00e9s Jaque, Izaskun Chinchilla, Uriel Fogu\u00e9, todos ellos han sido profesores\u00a0de Alicante.<\/p>\n<p class=\"gmail_default\">Arte: Joan Fontcuberta, Mar\u00eda Jerez, Thomas Thwaites, B\u00e1rbara Flux\u00e1 y Lorena Amor\u00f3s.<\/p>\n<p class=\"gmail_default\">Teor\u00eda\/Pensamiento: Jorge Riechmann, Remedios Zafra, Yayo Herrero e Iv\u00e1n L\u00f3pez Munuera.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.cendeac.net\/es\/curso-de-introduccion-al-arte-contemporaneo\/\" target=\"_blank\"><span style=\"font-family: 'times new roman', serif\">http:\/\/www.cendeac.net\/es\/curso-de-introduccion-al-arte-contemporaneo\/<\/span><br \/>\n<\/a><\/li>\n<li>Hora: 20:00<\/li>\n<li>Lugar: Cendeac\/Centro P\u00e1rraga\u00a0<a href=\"https:\/\/www.google.es\/maps\/place\/Cendeac\/@37.9790908,-1.1361331,17z\/data=!3m1!4b1!4m5!3m4!1s0xd638203b64f81c9:0x9d5fc07490e44a7c!8m2!3d37.9790908!4d-1.1339444\" target=\"_blank\">https:\/\/www.google.es\/maps\/place\/Cendeac\/@37.9790908,-1.1361331,17z\/data=!3m1!4b1!4m5!3m4!1s0xd638203b64f81c9:0x9d5fc07490e44a7c!8m2!3d37.9790908!4d-1.1339444<\/a><\/li>\n<li>Entrada libre hasta completar aforo.<\/li>\n<li>No es necesaria inscripci\u00f3n previa. En la sala habr\u00e1\u00a0una hoja de firmas para que los estudiantes que lo deseen acrediten su asistencia en cada sesi\u00f3n. Al final del curso se entregar\u00e1 un certificado a quienes hayan asistido al menos al 80% de las sesiones.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6230\" src=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2017\/03\/PostArcadia_FINAL_web_02_blog.png\" alt=\"\" width=\"560\" height=\"792\" srcset=\"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2017\/03\/PostArcadia_FINAL_web_02_blog.png 560w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2017\/03\/PostArcadia_FINAL_web_02_blog-212x300.png 212w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2017\/03\/PostArcadia_FINAL_web_02_blog-106x150.png 106w, https:\/\/blogs.ua.es\/proyectosarquitectonicos\/files\/2017\/03\/PostArcadia_FINAL_web_02_blog-400x566.png 400w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los profesores Enrique Nieto y Miguel Mesa del Castillo dirigen este curso en el CENDEAC de Murcia . Las conferencias son todas en jueves salvo la de Mar\u00eda Jerez (que es lunes 10 la performance y martes 11 la conferencia) y la de Yayo Herrero (el martes 30\/05). Las fechas est\u00e1n en la web. Arquitectura: [&hellip;]<\/p>\n","protected":false},"author":503,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6606],"tags":[],"class_list":["post-6229","post","type-post","status-publish","format-standard","hentry","category-generallll"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/6229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/users\/503"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/comments?post=6229"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/6229\/revisions"}],"predecessor-version":[{"id":6235,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/posts\/6229\/revisions\/6235"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/media?parent=6229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/categories?post=6229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/proyectosarquitectonicos\/wp-json\/wp\/v2\/tags?post=6229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}