{"id":210,"date":"2013-12-31T14:39:14","date_gmt":"2013-12-31T14:39:14","guid":{"rendered":"https:\/\/blogs.ua.es\/santapola2\/?p=210"},"modified":"2013-12-31T14:39:14","modified_gmt":"2013-12-31T14:39:14","slug":"grafiti-zombi","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/santapola2\/2013\/12\/31\/grafiti-zombi\/","title":{"rendered":"Grafiti zombi"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/santapola2\/files\/2013\/12\/CAM00229.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-211\" alt=\"CAM00229\" src=\"https:\/\/blogs.ua.es\/santapola2\/files\/2013\/12\/CAM00229-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/santapola2\/files\/2013\/12\/CAM00229-300x225.jpg 300w, https:\/\/blogs.ua.es\/santapola2\/files\/2013\/12\/CAM00229.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En cuanto a este grafiti es distinto a la majoria de los dem\u00e1s, ya que como he comentado la mayor parte de ellos \u00a0son mujeres, aunque los que no son de mujeres son de zombis .<\/p>\n<p>Cabe destacar que la cabeza del zombi parece estar saliendo del coche, lo que resulta a\u00fan m\u00e1s graciosa la imagen.<\/p>\n<p><em>Calle Hern\u00e1n Cort\u00e9s (se trata de un conquistador espa\u00f1ol que se hizo con el imperio azteca, actual centro de m\u00e9xico), Santa Pola.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cuanto a este grafiti es distinto a la majoria de los dem\u00e1s, ya que como he comentado la mayor parte de ellos \u00a0son mujeres, aunque los que no son de mujeres son de zombis . Cabe destacar que la cabeza del zombi parece estar saliendo del coche, lo que resulta a\u00fan m\u00e1s graciosa la [&hellip;]<\/p>\n","protected":false},"author":3293,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275995],"tags":[293065,119013,720700],"class_list":["post-210","post","type-post","status-publish","format-standard","hentry","category-grafitis-iconograficos","tag-grafiti","tag-santa-pola","tag-zombi"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/posts\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/users\/3293"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/comments?post=210"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/posts\/210\/revisions"}],"predecessor-version":[{"id":212,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/posts\/210\/revisions\/212"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/media?parent=210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/categories?post=210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/santapola2\/wp-json\/wp\/v2\/tags?post=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}