{"id":1340,"date":"2011-10-12T17:58:30","date_gmt":"2011-10-12T15:58:30","guid":{"rendered":"https:\/\/blogs.ua.es\/santiago\/?p=1340"},"modified":"2011-10-12T17:59:35","modified_gmt":"2011-10-12T15:59:35","slug":"palabras-desde-atenas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/santiago\/2011\/10\/12\/palabras-desde-atenas\/","title":{"rendered":"Palabras desde Atenas"},"content":{"rendered":"<p style=\"text-align: justify\">Este es un blog fundamentalmente sobre lengua y cultura griegas. En alguna ocasi\u00f3n lo he utilizado para tratar cuestiones de tipo pol\u00edtico o social que no guardan relaci\u00f3n directa con mi pr\u00e1ctica docente y mis intereses en materia de metodolog\u00eda.  Hoy, en esta sobremesa del desfasado d\u00eda de la Hispanidad, quiero dedicar una entrada a un asunto de actualidad que me preocupa: la cr\u00edtica situaci\u00f3n econ\u00f3mica de Grecia. Y lo hago dejando un espacio a las emocionantes palabras y el llamamiento urgente que el helenista <a href=\"http:\/\/www.pedroolalla.com\/index.html\">Pedro Olalla<\/a> envia desde la herida Atenas en un video que conozco a trav\u00e9s de <a href=\"http:\/\/lapasiongriega.blogspot.com\/\">la Pasi\u00f3n griega<\/a>. Su an\u00e1lisis no puede ser m\u00e1s claro. Seguro que no os deja indiferentes.<\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p><code> <\/code><code><\/code><code><\/code><code><\/code><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/jX7Kqb21b44\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este es un blog fundamentalmente sobre lengua y cultura griegas. En alguna ocasi\u00f3n lo he utilizado para tratar cuestiones de tipo pol\u00edtico o social que no guardan relaci\u00f3n directa con mi pr\u00e1ctica docente y mis intereses en materia de metodolog\u00eda. Hoy, en esta sobremesa del desfasado d\u00eda de la Hispanidad, quiero dedicar una entrada a [&hellip;]<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[568],"class_list":["post-1340","post","type-post","status-publish","format-standard","hentry","category-general","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/posts\/1340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/comments?post=1340"}],"version-history":[{"count":13,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/posts\/1340\/revisions"}],"predecessor-version":[{"id":1353,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/posts\/1340\/revisions\/1353"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/media?parent=1340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/categories?post=1340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/santiago\/wp-json\/wp\/v2\/tags?post=1340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}