{"id":1796,"date":"2011-09-07T09:51:23","date_gmt":"2011-09-07T07:51:23","guid":{"rendered":"https:\/\/blogs.ua.es\/si\/?p=1796"},"modified":"2011-09-07T09:51:23","modified_gmt":"2011-09-07T07:51:23","slug":"el-buscador-de-videos-de-vertice","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/si\/2011\/09\/07\/el-buscador-de-videos-de-vertice\/","title":{"rendered":"El buscador de v\u00eddeos de V\u00e9rtice"},"content":{"rendered":"<p>La aplicaci\u00f3n de gesti\u00f3n de contenidos multimedia de la Universidad de  Alicante sigue creciendo. Desde hace unos d\u00edas, tenemos a nuestra  disposici\u00f3n un buscador <strong>p\u00fablico<\/strong> que nos facilitar\u00e1 la tarea de  encontrar cualquier v\u00eddeo de V\u00e9rtice. Podemos acceder a \u00e9l a trav\u00e9s del  enlace disponible en la web de la aplicaci\u00f3n (<a title=\"V\u00e9rtice\" href=\"http:\/\/si.ua.es\/vertice\" target=\"_blank\">http:\/\/si.ua.es\/vertice<\/a>).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/vertice.cpd.ua.es\/buscador\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1797\" src=\"https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image001.png\" alt=\"Buscador de v\u00eddeos de V\u00e9rtice\" width=\"258\" height=\"81\" \/><\/a><\/p>\n<p style=\"text-align: center\">&nbsp;<\/p>\n<p>Disponemos de<strong> 6 criterios de b\u00fasqueda<\/strong> que se pueden combinar entre s\u00ed, con el fin de obtener unos resultados  m\u00e1s precisos. Es posible realizar b\u00fasquedas por t\u00edtulo, autor, palabras  clave, actores, palabras del resumen y ramas de conocimiento.\u00a0 Eso s\u00ed,  los resultados de una b\u00fasqueda s\u00f3lo mostrar\u00e1n v\u00eddeos de car\u00e1cter  p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/vertice.cpd.ua.es\/buscador\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1798\" src=\"https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image002.png\" alt=\"Ejemplo de resultados obtenidos al realizar una b\u00fasqueda\" width=\"285\" height=\"561\" srcset=\"https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image002.png 285w, https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image002-152x300.png 152w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El buscador tambi\u00e9n es accesible desde cualquier v\u00eddeo de V\u00e9rtice: desde  la pantalla de visualizaci\u00f3n del v\u00eddeo, si desplegamos la pesta\u00f1a \u201c<strong>Acciones<\/strong>\u201d podremos encontrar el enlace \u201c<strong>Buscar<\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/vertice.cpd.ua.es\/buscador\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1799\" src=\"https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image003.png\" alt=\"Acceso a la b\u00fasqueda desde un v\u00eddeo\" width=\"349\" height=\"302\" srcset=\"https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image003.png 349w, https:\/\/blogs.ua.es\/si\/files\/2011\/09\/image003-300x259.png 300w\" sizes=\"auto, (max-width: 349px) 100vw, 349px\" \/><\/a><\/p>\n<p style=\"text-align: center\">&nbsp;<\/p>\n<p style=\"text-align: left\">Para\u00a0 m\u00e1s informaci\u00f3n sobre esta opci\u00f3n, visite el Tutorial de V\u00e9rtice en: <a title=\"Tutorial sobre el buscador de v\u00eddeos de V\u00e9rtice\" href=\"http:\/\/si.ua.es\/es\/vertice\/guia-de-uso\/buscador-de-contenidos.html\" target=\"_blank\">http:\/\/si.ua.es\/es\/vertice\/guia-de-uso\/buscador-de-contenidos.html<\/a><\/p>\n<p style=\"text-align: left\">&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n de gesti\u00f3n de contenidos multimedia de la Universidad de Alicante sigue creciendo. Desde hace unos d\u00edas, tenemos a nuestra disposici\u00f3n un buscador p\u00fablico que nos facilitar\u00e1 la tarea de encontrar cualquier v\u00eddeo de V\u00e9rtice. Podemos acceder a \u00e9l a trav\u00e9s del enlace disponible en la web de la aplicaci\u00f3n (http:\/\/si.ua.es\/vertice). &nbsp; &nbsp; Disponemos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.ua.es\/si\/2011\/09\/07\/el-buscador-de-videos-de-vertice\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;El buscador de v\u00eddeos de V\u00e9rtice&#8221;<\/span><\/a><\/p>\n","protected":false},"author":797,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2644],"tags":[1660,9771,411],"class_list":["post-1796","post","type-post","status-publish","format-standard","hentry","category-noticias-del-si","tag-desarrollos-propios","tag-vertice","tag-video"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/users\/797"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/1796\/revisions"}],"predecessor-version":[{"id":1803,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/1796\/revisions\/1803"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/categories?post=1796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/tags?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}