{"id":2405,"date":"2012-03-06T13:50:55","date_gmt":"2012-03-06T11:50:55","guid":{"rendered":"https:\/\/blogs.ua.es\/si\/?p=2405"},"modified":"2012-03-06T13:56:11","modified_gmt":"2012-03-06T11:56:11","slug":"los-discos-de-arranque-como-antivirus-de-emergencia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/si\/2012\/03\/06\/los-discos-de-arranque-como-antivirus-de-emergencia\/","title":{"rendered":"Los discos de arranque como antivirus de emergencia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>En muchas ocasiones nuestro ordenador se ha infectado de alg\u00fan tipo de malware y nuestro antivirus no consigue eliminarlo. \u00bfQu\u00e9 hacer? Nuestro primer recurso consiste en llamar al Servicio de Inform\u00e1tica y pedir que nos resuelvan el problema pero&#8230; \u00bfy si tuvi\u00e9ramos una herramienta para intentar eliminarlo nosotros mismos y de una manera sencilla? Esta herramienta existe y <strong>se trata de los discos de arranque<\/strong>. Si reiniciamos nuestro ordenador con un disco de arranque se ejecutar\u00e1 un antivirus con el que podremos limpiar nuestro equipo.<!--more--> \u00bfPor qu\u00e9 este antivirus s\u00ed puede solucionar nuestro problema y no el que tenemos instalado? La raz\u00f3n estriba en que, en muchas ocasiones, cuando el virus est\u00e1 instalado, una de sus estrategias consiste en impedir que pueda ser eliminado. En ocasiones se oculta y en otras, se protege para evitar su eliminaci\u00f3n.<\/p>\n<p>Ahora bien, si arrancamos con un <strong>live-CD,<\/strong> es decir, con un <strong>CD de arranque<\/strong>, conseguiremos que el antivirus se cargue mientras el virus no, por lo que el virus no habr\u00e1 podido &#8220;blindarse&#8221; y ser\u00e1 much\u00edsimo m\u00e1s f\u00e1cil su eliminaci\u00f3n.<\/p>\n<p>Existen varias empresas de seguridad que crean este tipo de CD&#8217;s de arranque. Nosotros hemos escogido algunos de ellos y cuyo uso es gratuito. La grabaci\u00f3n del disco es muy sencilla ya que al ser im\u00e1genes iso, tan s\u00f3lo tenemos que grabar la imagen con cualquier programa de grabaci\u00f3n de cd\/dvd que tengamos instalado y en muy breve plazo <strong>tendremos nuestro antivirus &#8220;de emergencia&#8221; preparado.<\/strong><\/p>\n<p>Hay que tener claro que este tipo de antivirus NO se instala en nuestro ordenador, es decir, si quisi\u00e9ramos volver a pasar el antivirus tendr\u00edamos que volver a arrancar con \u00e9l dentro de nuestra unidad de cd\/dvd. Si ha transcurrido un cierto tiempo ser\u00eda conveniente generar un nuevo disco con el fin de tenerlo actualizado.<\/p>\n<p>Hemos probado tres de ellos, cada uno con sus ventajas y sus inconvenientes. <strong>Todas las im\u00e1genes que se adjuntan est\u00e1n actualizadas a febrero de 2012.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dr.Web LiveCD<\/strong><\/p>\n<p>Descarga:\u00a0 <a title=\"Dr.Web LiveCD\" href=\"http:\/\/download.geo.drweb.com\/pub\/drweb\/livecd\/drweb-livecd-600.iso\" target=\"_blank\">http:\/\/download.geo.drweb.com\/pub\/drweb\/livecd\/drweb-livecd-600.iso<\/a><\/p>\n<p>Se trata del m\u00e1s sencillo de todos. R\u00e1pido en arrancar. Aparece un men\u00fa de Dr.Web en el cual ejecutaremos la opci\u00f3n de analizar si nuestro disco duro tiene virus. La b\u00fasqueda es r\u00e1pida y no tiene muchas complicaciones, por lo que lo recomendamos para quien no quiera muchas complicaciones. Tal vez la \u00fanica pega es que solamente est\u00e1 en ingl\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/www.freedrweb.com\/livecd\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2407\" src=\"https:\/\/blogs.ua.es\/si\/files\/2012\/03\/logo_es.jpg\" alt=\"Dr.Web LiveCD\" width=\"154\" height=\"83\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Kaspersky Rescue Disk<\/strong><\/p>\n<p>Descarga:\u00a0 <a title=\"Kaspersky Rescue Disk\" href=\"http:\/\/rescuedisk.kaspersky-labs.com\/rescuedisk\/updatable\/kav_rescue_10.iso\">http:\/\/rescuedisk.kaspersky-labs.com\/rescuedisk\/updatable\/kav_rescue_10.iso<\/a><\/p>\n<p>A mi modesto entender,\u00a0 es el m\u00e1s completo aunque tal vez el m\u00e1s complicado. Nos aparece un men\u00fa para la elecci\u00f3n de idioma, pero\u00a0 no han considerado poner el castellano. Tenemos varias opciones y entre ellas, la que nos interesa, que es analizar nuestro disco. Es el que recomiendo, porque su motor de b\u00fasqueda es el mejor de los tres que vamos a ver. Tarda un poco m\u00e1s en\u00a0 inicializarse que el Dr.Web pero tambi\u00e9n es cierto que carga m\u00e1s opciones.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/support.kaspersky.com\/viruses\/rescuedisk\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2408\" src=\"https:\/\/blogs.ua.es\/si\/files\/2012\/03\/logo_01.gif\" alt=\"Kaspersky Rescue Disk\" width=\"260\" height=\"79\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bitdefender live CD<\/strong><\/p>\n<p>Descarga: <a title=\"Bitdefender live CD\" href=\"http:\/\/download.bitdefender.com\/rescue_cd\/bitdefender-rescue-cd.iso\">http:\/\/download.bitdefender.com\/rescue_cd\/bitdefender-rescue-cd.iso<\/a><\/p>\n<p>Esta versi\u00f3n tiene una cosa en su contra y es que tarda mucho m\u00e1s que los anteriores en cargar y adem\u00e1s, en ocasiones parece que se ha quedado bloqueado. No se bloquea, pero podr\u00edan indicar que est\u00e1 cargando en memoria la aplicaci\u00f3n, para evitar sustos. A favor tiene dos cosas muy interesantes: La primera, que s\u00ed permite el castellano como lengua, y eso facilita\u00a0 mucho el trabajo, y dos y principal, que intenta actualizarse si nuestro ordenador est\u00e1 conectado a la red, por lo que siempre pasar\u00e1 la \u00faltima versi\u00f3n del antivirus. Esto es muy importante y debe tenerse en cuenta, porque mientras los otros dos necesitamos ir descarg\u00e1ndonos versiones, \u00e9ste se actualiza. Ahora bien, se actualiza en l\u00ednea, por lo que cada vez tardar\u00e1 algo m\u00e1s en descargarse las nuevas actualizaciones.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.bitdefender.com\/freetools\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2409\" src=\"https:\/\/blogs.ua.es\/si\/files\/2012\/03\/bitdefender.jpg\" alt=\"Bitdefender\" width=\"429\" height=\"124\" srcset=\"https:\/\/blogs.ua.es\/si\/files\/2012\/03\/bitdefender.jpg 429w, https:\/\/blogs.ua.es\/si\/files\/2012\/03\/bitdefender-300x86.jpg 300w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En definitiva, son tres sencillas aplicaciones que tan s\u00f3lo nos obligan a grabar un CD y arrancar con \u00e9l nuestro equipo, para\u00a0 limpiar el malware que pueda haberse instalado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Miguel \u00c1ngel Alcaraz, <\/strong>T\u00e9cnico de soporte y asistencia a usuarios.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; En muchas ocasiones nuestro ordenador se ha infectado de alg\u00fan tipo de malware y nuestro antivirus no consigue eliminarlo. \u00bfQu\u00e9 hacer? Nuestro primer recurso consiste en llamar al Servicio de Inform\u00e1tica y pedir que nos resuelvan el problema pero&#8230; \u00bfy si tuvi\u00e9ramos una herramienta para intentar eliminarlo nosotros mismos y de una manera sencilla? &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.ua.es\/si\/2012\/03\/06\/los-discos-de-arranque-como-antivirus-de-emergencia\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Los discos de arranque como antivirus de emergencia&#8221;<\/span><\/a><\/p>\n","protected":false},"author":797,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2644,5464],"tags":[5329,488,2201],"class_list":["post-2405","post","type-post","status-publish","format-standard","hentry","category-noticias-del-si","category-recomendaciones-y-guias","tag-antivirus","tag-seguridad","tag-virus"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/users\/797"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/comments?post=2405"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2405\/revisions"}],"predecessor-version":[{"id":2411,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2405\/revisions\/2411"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/media?parent=2405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/categories?post=2405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/tags?post=2405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}