{"id":2534,"date":"2012-03-21T13:52:52","date_gmt":"2012-03-21T11:52:52","guid":{"rendered":"https:\/\/blogs.ua.es\/si\/?p=2534"},"modified":"2012-03-21T13:52:52","modified_gmt":"2012-03-21T11:52:52","slug":"renovacion-de-software-para-la-docencia-en-aulas-de-uso-general","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/si\/2012\/03\/21\/renovacion-de-software-para-la-docencia-en-aulas-de-uso-general\/","title":{"rendered":"Renovaci\u00f3n de software para la docencia en aulas de uso general"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Hasta el 3 de abril<\/strong> se pueden presentar solicitudes para la renovaci\u00f3n centralizada de licencias de programas.<\/p>\n<p><strong>Las solicitudes deben ser canalizadas a trav\u00e9s de los Centros<\/strong>, que podr\u00e1n priorizar las propuestas.<\/p>\n<p>Las razones que justificar\u00edan una adquisici\u00f3n centralizada de licencias de programas son:<br \/>\n-Aplicaciones inform\u00e1ticas de uso generalizado (sistemas operativos,navegadores, ofim\u00e1tica) con disponibilidad de licencias campus.<br \/>\n-Aplicaciones inform\u00e1ticas compartidas por varios departamentos, lo que permite compartir costes.<br \/>\n-Aplicaciones inform\u00e1ticas de elevado coste pero de alto inter\u00e9s, que dif\u00edcilmente ser\u00edan asumibles por una asignatura\/departamento.<\/p>\n<p>En esta p\u00e1gina <a title=\"Relaci\u00f3n de software disponible\" href=\"http:\/\/si.ua.es\/es\/programas\/programas-para-docencia-en-aulas-de-informatica.html\" target=\"_blank\">http:\/\/si.ua.es\/es\/programas\/programas-para-docencia-en-aulas-de-informatica.html<\/a> se detalla el\u00a0 software docente del que la UA tiene actualizadas las licencias y, por tanto, puede ser instalado en las aulas de inform\u00e1tica para su uso docente.<\/p>\n<p>\u2013<\/p>\n<p>Convocatoria: <a title=\"Convocatoria\" href=\"http:\/\/www.boua.ua.es\/pdf.asp?pdf=1987.pdf\" target=\"_blank\">BOUA, 16 de marzo de 2011<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hasta el 3 de abril se pueden presentar solicitudes para la renovaci\u00f3n centralizada de licencias de programas. Las solicitudes deben ser canalizadas a trav\u00e9s de los Centros, que podr\u00e1n priorizar las propuestas. Las razones que justificar\u00edan una adquisici\u00f3n centralizada de licencias de programas son: -Aplicaciones inform\u00e1ticas de uso generalizado (sistemas operativos,navegadores, ofim\u00e1tica) con disponibilidad &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.ua.es\/si\/2012\/03\/21\/renovacion-de-software-para-la-docencia-en-aulas-de-uso-general\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Renovaci\u00f3n de software para la docencia en aulas de uso general&#8221;<\/span><\/a><\/p>\n","protected":false},"author":797,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2644],"tags":[1584,356],"class_list":["post-2534","post","type-post","status-publish","format-standard","hentry","category-noticias-del-si","tag-aulas","tag-software"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/users\/797"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/comments?post=2534"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2534\/revisions"}],"predecessor-version":[{"id":2536,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/posts\/2534\/revisions\/2536"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/media?parent=2534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/categories?post=2534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/si\/wp-json\/wp\/v2\/tags?post=2534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}