{"id":150,"date":"2011-04-12T19:01:33","date_gmt":"2011-04-12T18:01:33","guid":{"rendered":"https:\/\/blogs.ua.es\/teleco\/?p=150"},"modified":"2011-04-12T19:34:34","modified_gmt":"2011-04-12T18:34:34","slug":"concursos-dividendo-digital-y-lte","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/teleco\/2011\/04\/12\/concursos-dividendo-digital-y-lte\/","title":{"rendered":"Concursos, dividendo digital y LTE"},"content":{"rendered":"<p>Hoy 11 de abril se han publicado en el Bolet\u00edn Oficial del Estado,\u00a0los pliegos del concurso para las bandas de 900MHz <a rel=\"nofollow\" href=\"http:\/\/bit.ly\/gscbT7\" target=\"_blank\">http:\/\/bit.ly\/gscbT7<\/a> y 1800MHz <a rel=\"nofollow\" href=\"http:\/\/bit.ly\/ewnP2Q\" target=\"_blank\">http:\/\/bit.ly\/ewnP2Q<\/a>\u00a0donde\u00a0se <span style=\"font-size: x-small\"><span style=\"font-size: x-small\">establece que las bandas de frecuencias de 880-915 MHz y 925-960 MHz (banda de 900 MHz) y de 1.710-1.785MHz y 1.805MHz\u20131.880MHz (banda de 1.800MHz) se ponen a disposici\u00f3n de los sistemas GSM y los sistemas UMTS as\u00ed como de otros sistemas terrestres capaces de prestar servicios de comunicaciones electr\u00f3nicas que puedan coexistir con los sistemas GSM. Y esto adem\u00e1s sucede a nivel europeo, viene a partir de una directiva europea\u00a0relativa a las bandas de frecuencia a reservar para las comunicaciones de telefon\u00eda m\u00f3vil en toda la Comunidad europea.<\/span><\/span><\/p>\n<p>Por primera vez, habr\u00e1 unas bandas de frecuencia en las cuales los operadores podr\u00e1n escoger si ofrecer su servicios de telefon\u00eda m\u00f3vil con GSM, UMTS o incluso con cualquier otro sistema siempre y cuando no machaque al GSM original destinado en esas bandas. Antes s\u00f3lo pod\u00edan ser utilizadas con el sistema GSM.<\/p>\n<p>Estas bandas no son las del famoso <a title=\"TDT y Dividendo Digital\" href=\"http:\/\/es.wikipedia.org\/wiki\/Televisi%C3%B3n_terrestre_en_Espa%C3%B1a#Reasignaci.C3.B3n_de_frecuencias_y_el_.22dividendo_digital.22\" target=\"_blank\">dividendo digital<\/a> ocupadas actualmente por las cadenas de TDT que est\u00e1n en los canales altos a partir del C60 de UHF (vamos, en Alicante\u00a0toda la TDT de emisi\u00f3n nacional) y que se est\u00e1n migrando progresivamente a sus canales finales. Estas bandas son las <a href=\"http:\/\/blogcmt.com\/2010\/05\/21\/conceptos-basicos-del-telecos-evolucion-de-las-comunicaciones-moviles-del-gsm-al-lte\/\" target=\"_blank\">actuales bandas de GSM<\/a> tal y como hemos visto en:<\/p>\n<p><a href=\"http:\/\/blogcmt.com\/wp-content\/uploads\/2010\/05\/distribuciondefrecuencias2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/blogcmt.com\/wp-content\/uploads\/2010\/05\/distribuciondefrecuencias2.png\" alt=\"GSM y UMTS en Espa\u00f1a hasta 2011\" width=\"911\" height=\"488\" \/><\/a><\/p>\n<p>LTE ser\u00e1 el siguiente sistema que se utilizar\u00e1 en esas bandas y como pod\u00e9is ver en el siguiente anuncio de la operadora Verizon en los EEUU sobre su red LTE en la banda de 700MHz, es significativamente diferente a los sistemas actuales:<\/p>\n<p>[kml_flashembed movie=&#8221;http:\/\/www.youtube.com\/v\/w-CtuXbgp58&#8243; width=&#8221;425&#8243; height=&#8221;350&#8243; wmode=&#8221;transparent&#8221; \/]<\/p>\n<p>Lo cierto es que algunos nos identificamos m\u00e1s con el otro anuncio (18 minutos son 18 minutos oiga):<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/OhNFE6V8QRQ\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>Seguramente pensar\u00e9is que no es oro todo lo que reluce y es verdad. Hay que tener mucho cuidado y saber de lo que se est\u00e1 hablando porque es necesario hacer <a href=\"http:\/\/bandaancha.eu\/articulo\/7556\/telefonica-desplegara-1500-estaciones-base-lte-banda-dividendo-digital-alemana\" target=\"_blank\">grandes inversiones<\/a>\u00a0 y no es admisible que <a href=\"http:\/\/www.lacofa.es\/lang\/en\/index.php\/tecnologias\/lo-que-no-puede-ser-no-puede-ser-y-ademas-es-imposible-incluso-en-4g\" target=\"_blank\">concursos como el de hoy (si esto nos pasara en Espa\u00f1a sal\u00edamos en todas partes) tengan &#8220;pegas&#8221;<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy 11 de abril se han publicado en el Bolet\u00edn Oficial del Estado,\u00a0los pliegos del concurso para las bandas de 900MHz http:\/\/bit.ly\/gscbT7 y 1800MHz http:\/\/bit.ly\/ewnP2Q\u00a0donde\u00a0se establece que las bandas de frecuencias de 880-915 MHz y 925-960 MHz (banda de 900 MHz) y de 1.710-1.785MHz y 1.805MHz\u20131.880MHz (banda de 1.800MHz) se ponen a disposici\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[830,828,425],"tags":[940,1294,1293],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-telecomunicaciones","category-telefonia","category-television","tag-dividendo-digital","tag-lte","tag-redes-4g"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":12,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"predecessor-version":[{"id":161,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts\/150\/revisions\/161"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}