{"id":16,"date":"2008-03-11T12:58:20","date_gmt":"2008-03-11T11:58:20","guid":{"rendered":"https:\/\/blogs.ua.es\/teleco\/2008\/03\/11\/plan-avanza-y-red-social-universitaria\/"},"modified":"2008-03-11T12:58:20","modified_gmt":"2008-03-11T11:58:20","slug":"plan-avanza-y-red-social-universitaria","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/teleco\/2008\/03\/11\/plan-avanza-y-red-social-universitaria\/","title":{"rendered":"Plan Avanza y red social universitaria"},"content":{"rendered":"<p>Dentro de muy poco, la Universidad espa\u00f1ola contar\u00e1 con una red social nacional patrocinada por el Plan Avanza del Ministerio de Industria, Comercio y Turismo. Este novedoso proyecto del Plan Avanza ha sido concedido a un grupo de investigaci\u00f3n de la Universidad de Alicante: el Grupo de Tecnolog\u00eda de la Imagen (GTI). Actualmente, se encuentra en fase de desarrollo y se prevee su lanzamiento para noviembre &#8211; diciembre de 2008, aunque en mayo pr\u00f3ximo ya aparecer\u00e1 una primera versi\u00f3n que va a dar mucho que hablar.<\/p>\n<p>Por cuestiones de seguridad no os podemos contar mucho m\u00e1s sobre el sistema, aunque como pista os adelantamos que va a cambiar la forma de que el universitario interactue con su entorno de ocio, trabajo y cultura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" border=\"0\" width=\"214\" src=\"http:\/\/www.canaltec.com\/pub\/banners\/banners_gobierno_espana3_3e2bc63c.gif\" alt=\"Ministerio de Industria\" height=\"50\" \/><img loading=\"lazy\" decoding=\"async\" border=\"0\" width=\"142\" src=\"http:\/\/www.canaltec.com\/pub\/banners\/_logo_avanza_74dc9735.gif\" alt=\"Plan avanza\" height=\"50\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentro de muy poco, la Universidad espa\u00f1ola contar\u00e1 con una red social nacional patrocinada por el Plan Avanza del Ministerio de Industria, Comercio y Turismo. Este novedoso proyecto del Plan Avanza ha sido concedido a un grupo de investigaci\u00f3n de la Universidad de Alicante: el Grupo de Tecnolog\u00eda de la Imagen (GTI). Actualmente, se encuentra [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829],"tags":[1134],"class_list":["post-16","post","type-post","status-publish","format-standard","hentry","category-redes-de-datos","tag-plan-avanza"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/teleco\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}