{"id":65,"date":"2013-12-15T19:36:10","date_gmt":"2013-12-15T19:36:10","guid":{"rendered":"https:\/\/blogs.ua.es\/torrevieja1\/?p=65"},"modified":"2014-01-11T07:58:18","modified_gmt":"2014-01-11T07:58:18","slug":"ramon-gallud-torregrosa","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/torrevieja1\/2013\/12\/15\/ramon-gallud-torregrosa\/","title":{"rendered":"Ram\u00f3n Gallud Torregrosa"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-66\" alt=\"RAM\u00d3N GALLUD TORREGROSA\" src=\"https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA.jpg\" width=\"450\" height=\"361\" srcset=\"https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA.jpg 450w, https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA-300x240.jpg 300w, https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA-186x150.jpg 186w, https:\/\/blogs.ua.es\/torrevieja1\/files\/2013\/12\/RAM\u00d3N-GALLUD-TORREGROSA-150x120.jpg 150w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Esta es la placa de Ram\u00f3n Gallud Torregrosa, hijo de Ram\u00f3n Gallud M\u00ednguez, alcalde de Torrevieja desde 1944 hasta 1948, naci\u00f3 en y muri\u00f3 en 1936, con s\u00f3lo 19 a\u00f1os. En la placa vemos que\u00a0 muri\u00f3 en 1936, en plena Guerra Civil (1936-1939), fue fusilado por sentencia del Tribunal Popular de Alicante el mismo d\u00eda que otros torrevejenses como Gabriel Aracil. Ram\u00f3n Gallud era estudiante de medicina en la Universidad de Valencia, y decidi\u00f3 afiliarse a Falange Espa\u00f1ola, una decisi\u00f3n que le oblig\u00f3 a huir del lugar donde resid\u00eda y escapar hacia Barcelona, como cuenta Francisco Rebollo en su Historia de Torrevieja. Esta hu\u00edda fue realizada con el barco de pesca de su abuelo, Ram\u00f3n Sala M\u00ednguez, y pudo llegar a casa de un amigo con la intenci\u00f3n de esconderse all\u00ed, pero fue localizado por las fuerzas de la Rep\u00fablica. Se vio obligado a volver a Alicante y despu\u00e9s de un tiempo en prisi\u00f3n fue fusilado, junto a otro compa\u00f1ero falangista, por dichas fuerzas republicanas en el contexto de la Guerra Civil, que tantas v\u00edctimas dej\u00f3 en Espa\u00f1a. Una vez acabada la guerra, el ayuntamiento decidi\u00f3 dar su nombre a una calle que anteriormente se denominaba Quiroga, combatiente de los franceses en la Guerra de la Independencia (1808-1812). Su pertenencia a la Falange Espa\u00f1ola justifica que en su placa aparezca que \u201cdio su vida por dios y por la patria\u201d, pues con la victoria del bando nacional, muertes como la suya fueron consideradas por Franco como la de hombres que hab\u00edan muerto para salvar Espa\u00f1a del peligro republicano, y por tanto honores como el de dar su nombre a una calle vienen dados por esta consideraci\u00f3n.<\/p>\n<p>Esta fotograf\u00eda fue realizada en el Cementerio Municipal de Torrevieja,\u00a0V\u00eda Pa Cementerio, 03181 Torrevieja, Alicante,\u00a0\u00a0el d\u00eda 26 de noviembre de 2013.<\/p>\n<p>Bibliograf\u00eda y referencias web:\u00a0<em>Historia de Torrevieja.<\/em>\u00a0[En l\u00ednea]<em>.\u00a0<\/em>Francisco Rebollo, 2013 [consulta: 3 de diciembre de 2013]. Disponible en:\u00a0franciscorebollo.blogspot.com<\/p>\n<p>Seminario Vista Alegre de Torrevieja.<em>\u00a0Un siglo de Torrevieja (1901-2000).\u00a0<\/em>Torrevieja: Exmo. Ayuntamiento de Torrevieja. 2001. 338 p.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esta es la placa de Ram\u00f3n Gallud Torregrosa, hijo de Ram\u00f3n Gallud M\u00ednguez, alcalde de Torrevieja desde 1944 hasta 1948, naci\u00f3 en y muri\u00f3 en 1936, con s\u00f3lo 19 a\u00f1os. En la placa vemos que\u00a0 muri\u00f3 en 1936, en plena Guerra Civil (1936-1939), fue fusilado por sentencia del Tribunal Popular de Alicante el mismo [&hellip;]<\/p>\n","protected":false},"author":3324,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274049],"tags":[421,445610],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-inscripciones-y-placas-en-cementerios","tag-guerra-civil","tag-torrevieja-cementerio-municipal"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/users\/3324"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":207,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/posts\/65\/revisions\/207"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/torrevieja1\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}